{"id":73334,"date":"2012-08-22T06:24:01","date_gmt":"2012-08-22T06:24:01","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/08\/22\/subrepticement-la-crise-syrienne-devient-haute\/"},"modified":"2012-08-22T06:24:01","modified_gmt":"2012-08-22T06:24:01","slug":"subrepticement-la-crise-syrienne-devient-haute","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/08\/22\/subrepticement-la-crise-syrienne-devient-haute\/","title":{"rendered":"Subrepticement, la crise syrienne devient haute"},"content":{"rendered":"<p><h2 class=\"common-article\">Subrepticement, la crise syrienne devient haute<\/h2>\n<\/p>\n<p><p>\t22 ao\u00fbt 2012  C&rsquo;est le 4 f\u00e9vrier 2012 que la crise syrienne a pris son envol, avec le veto russe et le veto chinois \u00e0 une r\u00e9solution propos\u00e9e \u00e0 l&rsquo;ONU par le bloc BAO, qui e\u00fbt constitu\u00e9 une r\u00e9plique du coup libyen d&rsquo;\u00e0 peu pr\u00e8s une ann\u00e9e auparavant. Dans ce cas, nous voyions la crise syrienne prendre <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_voie_de_la_syrie_a_la_crise_haute__08_02_2012.html\" class=\"gen\">sa place<\/a> dans la <a href=\"http:\/\/www.dedefensa.org\/article-la_crise_haute_03_02_2012.html\" class=\"gen\">crise haute<\/a> faite d&rsquo;une n\u00e9buleuse de crise, dans le golfe Persique et la Mer d&rsquo;Oman, en Iran, etc. Ce n&rsquo;\u00e9tait que l&rsquo;envol et, dans la crise haute, la crise syrienne ne tenait certainement pas la premi\u00e8re place,  pas encore.<\/p>\n<\/p>\n<p><p>\tLes semaines et les mois ont pass\u00e9, la crise s&rsquo;est d\u00e9velopp\u00e9e, dans le sens qu&rsquo;on sait, c&rsquo;est-\u00e0-dire dans des conditions de communication extr\u00eames, o\u00f9 les montages et la <em>narrative<\/em> du bloc BAO enfermaient celui-ci dans une position maximaliste (\u00e9limination d&rsquo;Assad comme condition <em>sine qua non<\/em> <strong>\u00e0 n&rsquo;importe quoi<\/strong>), alors que s&rsquo;effa\u00e7ait peu \u00e0 peu la probabilit\u00e9 d&rsquo;une victoire rapide des rebelles qui, seule, assurait cette position maximaliste. D&rsquo;un autre c\u00f4t\u00e9, la Russie (avec le soutien sans faille de la Chine) tenait une position d&rsquo;extr\u00eame fermet\u00e9 fond\u00e9e sur l&rsquo;affirmation du droit international (respect de la souverainet\u00e9) et la pr\u00e9sence de toutes les parties en pr\u00e9sence, dont Assad \u00e9videmment, \u00e0 tout processus de n\u00e9gociation\/de paix.<\/p>\n<\/p>\n<p><p>\tLa Russie a peu \u00e0 peu \u00e9largi sa r\u00e9flexion, ou, plut\u00f4t, elle l&rsquo;a hauss\u00e9e. Nous avons tent\u00e9 de signaler cette \u00e9volution, \u00e0 mesure que nous croyions la distinguer. Nous rappellerons principalement deux \u00e9volutions (plut\u00f4t que deux \u00e9tapes, comme nous \u00e9tions d&rsquo;abord tent\u00e9s d&rsquo;\u00e9crire), d&rsquo;ailleurs assez rapproch\u00e9es dans la publication des textes qui les marquent. La chronologie dans cette sorte de sp\u00e9culation importe assez peu puisqu&rsquo;on voit \u00e9voluer ses divers domaines d&rsquo;une fa\u00e7on parall\u00e8le et dans tous les cas autonome plus que d&rsquo;une fa\u00e7on logiquement li\u00e9e.<\/p>\n<\/p>\n<p><p>\t Le <a href=\"http:\/\/www.dedefensa.org\/article-avertissement_nucl_aire_de_la_russie_au_g8_18_05_2012.html\" class=\"gen\">18 mai 2012<\/a>, nous commentions un avertissement de Medvedev, alors encore nominalement pr\u00e9sident de la F\u00e9d\u00e9ration russe pour quelque jours, sur les d\u00e9sormais possibles incontr\u00f4labilit\u00e9 et aggravation des conflits r\u00e9gionaux. Medvedev \u00e9voquait sans ambages le risque qu&rsquo;un de ces conflits \u00e9volu\u00e2t en affrontement nucl\u00e9aire.<\/p>\n<\/p>\n<p><p>\t Le <a href=\"http:\/\/www.dedefensa.org\/article-m_ditations_de_poutine_04_06_2012.html\" class=\"gen\">4 juin 2012<\/a>, nous \u00e9voquions la possibilit\u00e9, pas loin d&rsquo;une probabilit\u00e9 que la Russie modifi\u00e2t son attitude dans la crise syrienne. Le facteur d\u00e9clenchant de cette sp\u00e9culation de notre part fut l&rsquo;extraordinaire l\u00e9g\u00e8ret\u00e9, pour ne pas parler d&rsquo;irresponsabilit\u00e9 compl\u00e8te plong\u00e9e dans une interpr\u00e9tation hallucin\u00e9e de la chose, avec lesquelles les signataires du bloc BAO de l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_une_conf_rence_perdue_corps_et_biens_03_07_2012.html\" class=\"gen\">accord de Gen\u00e8ve<\/a> du 30 juin montr\u00e8rent aussit\u00f4t qu&rsquo;ils entendaient n&rsquo;en tenir aucun compte. Les m\u00e9ditations auxquelles il est fait allusion dans le texte r\u00e9f\u00e9renc\u00e9 concernent le choix qui \u00e9tait d\u00e9sormais possible de la Russie de passer d&rsquo;une position de quasi-m\u00e9diateur\/n\u00e9gociateur en Syrie, \u00e0 celle d&rsquo;un retrait de ce domaine pour envisager une position de repli agressif, voire de durcissement contre l&rsquo;action du bloc BAO.<\/p>\n<\/p>\n<p><p>\tCes deux id\u00e9es (la premi\u00e8re implicitement, avec le point d&rsquo;interrogation nucl\u00e9aire et l&rsquo;expression de guerre froide peut-\u00eatre inappropri\u00e9e) \u00e9taient contenues dans le texte de Fran\u00e7ois Fillon du <a href=\"http:\/\/www.lefigaro.fr\/international\/2012\/08\/12\/01003-20120812ARTFIG00173-un-peu-de-courage-monsieur-le-president.php\" class=\"gen\">13 ao\u00fbt 2012<\/a>. On sait (voir le <a href=\"http:\/\/www.dedefensa.org\/article-fillon_la_syrie_et_la_russie_boire_et_manger_15_08_2012.html\" class=\"gen\">15 ao\u00fbt 2012<\/a>) que nous tenons ce texte comme singuli\u00e8rement schizophr\u00e9nique, d&rsquo;un homme capable de penser fort juste et pourtant contraint, par son pass\u00e9 imm\u00e9diat et ses engagements partisans, de saupoudrer le produit de cette pens\u00e9e fort juste de grossi\u00e8res inexactitudes et d&rsquo;hallucinations de <em>narrative<\/em> renvoyant \u00e0 la doctrine Sarko-BHL. Le passage le plus int\u00e9ressant parce que d\u00e9pourvu de ces sornettes contraintes de l&rsquo;article de Fillon, pour le sujet qui nous concerne, est celui-ci, avec partie soulign\u00e9 de gras par nous, concernant les moyens militaires des Russes en Syrie, mani\u00e9s directement par les Russes et impliquant un engagement des Russes,  cela venant d&rsquo;un homme qui \u00e9tait Premier ministre jusqu&rsquo;au 10 mai et qui \u00e9tait \u00e9videmment bien inform\u00e9 en la mati\u00e8re, y compris par des entretiens avec Poutine. (Fillon parle de l&rsquo;hypoth\u00e8se d&rsquo;une intervention militaire, c&rsquo;est-\u00e0-dire l&rsquo;hypoth\u00e8se plus large d&rsquo;une internationalisation <strong>ouverte<\/strong> de la crise.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>J&rsquo;ai toujours pens\u00e9 qu&rsquo;une telle intervention militaire serait une tr\u00e8s grave erreur strat\u00e9gique. Faire de la Syrie un nouvel Irak, th\u00e9\u00e2tre des pires affrontements entre chiites et sunnites manipul\u00e9s en sous-main par un Iran qui reste la menace num\u00e9ro un pour la paix dans le monde, n&rsquo;est pas une option. Sans compter que la Russie n&rsquo;apportera jamais son soutien \u00e0 une telle initiative; pire, elle la combattra sur le plan diplomatique,<\/em> <strong><em>mais aussi avec d&rsquo;autres moyens dont elle a gard\u00e9 la ma\u00eetrise<\/em><\/strong><em>. Si l&rsquo;on veut vraiment allumer la m\u00e8che d&rsquo;un conflit g\u00e9n\u00e9ralis\u00e9 au Proche et au Moyen-Orient et recr\u00e9er les conditions d&rsquo;une nouvelle guerre froide, il ne faudrait pas s&rsquo;y prendre autrement.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tMaintenant, nous citons deux observations du ministre russe des affaires \u00e9trang\u00e8res Lavrov, lors d&rsquo;une conf\u00e9rence de presse en Finlande, o\u00f9 il avait rencontr\u00e9 (le 20 ao\u00fbt) son homologue finnois \u00e0 Helsinki. (Selon <em>Russia Today<\/em>, le <a href=\"http:\/\/rt.com\/news\/lavrov-syria-future-conflicts-162\/\" class=\"gen\">21 ao\u00fbt 2012<\/a>.)<\/p>\n<\/p>\n<p><p>\t Parlant du comportement des pays du bloc BAO, sp\u00e9cifiquement de la France, du Royaume-Uni et des USA, notamment en ce qui concerne les accords de Gen\u00e8ve du 30 juin qui impliquait selon lui des engagements s\u00e9rieux, Lavrov fait cette remarque,  l&rsquo;id\u00e9e n&rsquo;est pas neuve mais les termes sont particuli\u00e8rement durs et n&rsquo;ont plus rien de diplomatique : \u00ab<em>We have managed to get support for the Geneva communiqu\u00e9 from the Syrian government. But our partners haven&rsquo;t<\/em> <strong><em>even<\/em><\/strong> <em>tried to do something like that; moreover, the main opposition groups publicly rejected the document. Nobody<\/em> <strong><em>even<\/em><\/strong> <em>tried to work with them<\/em>\u00bb (Ces remarques viennent alors que les Russes ont <a href=\"http:\/\/news.antiwar.com\/2012\/08\/20\/russia-syrian-rebels-getting-lots-of-western-made-arms\/\" class=\"gen\">annonc\u00e9<\/a> publiquement que ces m\u00eames pays du bloc, sp\u00e9cifiquement les USA, font des livraisons d&rsquo;armes massives aux rebelles. L\u00e0 non plus, la chose n&rsquo;est pas nouvelle, mais l&rsquo;aspect public et affirm\u00e9 de la d\u00e9claration est remarquable.)<\/p>\n<\/p>\n<p><p>\t Il y a surtout cette remarque d&rsquo;ordre g\u00e9n\u00e9ral, qui offre une d\u00e9finition de l&rsquo;importance de la crise syrienne, de l&rsquo;enjeu qui la domine dans la fa\u00e7on dont elle \u00e9voluera et dont elle se terminera. Cette remarque n&rsquo;est pas th\u00e9orique mais bien concr\u00e8te, avec des termes violents \u00e0 l&rsquo;adresse du bloc BAO (la doctrine du bombardement d\u00e9mocratique, ou bombardement pour la d\u00e9mocratie), concernant des intentions op\u00e9rationnelles affich\u00e9es Il s&rsquo;agit clairement d&rsquo;un avertissement d\u00e9finissant un enjeu irr\u00e9m\u00e9diable pour l&rsquo;issue de la crise syrienne : \u00ab<em>We believe this issue attracts so much attention not only because of the scale of the bloodshed, which worries all of us, but also because the outcome of the crisis will significantly influence the patterns for conflict settlement   either everything will fall in accordance with laws, that is according to the UN Charter, or bomb democracy&rsquo; will prevail<\/em>\u00bb <\/p>\n<\/p>\n<p><p>\tPendant ce temps, et pour clore le dossier des \u00e9v\u00e8nements courants, mentionnons un aper\u00e7u de la position US, qui comprend l&rsquo;annonce r\u00e9cente du pr\u00e9sident Obama de la possibilit\u00e9 et des coonditions d&rsquo;une intervention US, et l&rsquo;annonce encore plus exotique sous forme d&rsquo;accusation, de la porte-parole du d\u00e9partement d&rsquo;\u00c9tat Virginia Noland, selon laquelle les Russes veulent contourner l&rsquo;ONU. La force de la d\u00e9claration d&rsquo;Obama est largement contest\u00e9e par divers commentateurs selon divers arguments (voir <em>The Moon of Alabama<\/em>, le <a href=\"http:\/\/www.moonofalabama.org\/2012\/08\/obama-to-assad-do-whatever-you-need-to-do.html\" class=\"gen\">21 ao\u00fbt 2012<\/a> et le vice-Premier ministre syrien le <a href=\"http:\/\/en.rian.ru\/world\/20120821\/175349139.html\" class=\"gen\">21 ao\u00fbt 2012<\/a>), mais le fond de cette d\u00e9claration demeure pour ce qu&rsquo;il est,  une menace d&rsquo;intervention, Conseil de S\u00e9curit\u00e9 ou pas.<\/p>\n<\/p>\n<p><p>\t La logique de Noland est assez n\u00e9buleuse, affirmant que c&rsquo;est contourner l&rsquo;ONU que de ne pas faire pression sur Assad selon les termes que les USA pr\u00e9conisent (c&rsquo;est-\u00e0-dire le d\u00e9part d&rsquo;Assad, imm\u00e9diat et sans condition), et d&rsquo;autres choses du m\u00eame tonneau. L&rsquo;affirmation vient en riposte de l&rsquo;accusation russe de livraison d&rsquo;armes aux rebelles par les USA. L&rsquo;intervention, \u00e9videmment compl\u00e8tement \u00e9trang\u00e8re \u00e0 la v\u00e9rit\u00e9 de la situation, n&rsquo;a d&rsquo;int\u00e9r\u00eat, comme la d\u00e9claration d&rsquo;Obama, que de montrer combien les positions du bloc BAO sont, dans leur esprit dans tous les cas, compl\u00e8tement \u00e0 l&rsquo;oppos\u00e9 de celle des Russes. Elles sont soutenues par une logique de confrontation et, pour l&rsquo;accusation de Noland, toujours appuy\u00e9es sur un d\u00e9ni grossier de la r\u00e9alit\u00e9 conduisant \u00e0 des accusations antirusses qui ne peuvent que conforter les Russes dans leur d\u00e9termination&#8230; (D&rsquo;apr\u00e8s Novosti, le <a href=\"http:\/\/fr.rian.ru\/world\/20120821\/195738514.html\" class=\"gen\">21 ao\u00fbt 2012<\/a>.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>J&rsquo;estime que la Russie d\u00e9tourne l&rsquo;attention du fait qu&rsquo;elle ne veut pas se servir de m\u00e9canismes du Conseil de s\u00e9curit\u00e9 de l&rsquo;Onu pour faire pression sur Bachar el-Assad afin que ce dernier respecte le plan de Kofi Annan visant \u00e0 faire cesser la violence et \u00e0 assurer les changements politiques. La Russie n&rsquo;a pas non plus voulu rendre plus efficace la strat\u00e9gie dont nous avons convenue \u00e0 Gen\u00e8ve. Vous savez, il y a des choses tr\u00e8s importantes que la Russie aurait pu faire<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCes \u00e9tranges d\u00e9clarations rel\u00e8vent-elles de l&rsquo;habituelle op\u00e9ra-bouffe washingtonien sur la <em>narrative<\/em> en cours, ou bien y a-t-il quelque chose de plus int\u00e9ressant ? Les deux, sans doute. Tony Cartalucci, du site <em>Land Destroyed<\/em>, ennemi jur\u00e9 de Washington mais avec l&rsquo;habitude de peindre les choses en noir en parant Washington d&rsquo;une puissance et d&rsquo;une capacit\u00e9 nuisibles qui nous semblent en g\u00e9n\u00e9ral bien g\u00e9n\u00e9reuses,  Cartalucci, donc, conclurait cette fois plut\u00f4t au d\u00e9sespoir profond de Washington, qui ne voit aucune de ses manigances r\u00e9compens\u00e9e par quelque impression de succ\u00e8s,  en Syrie, face \u00e0 l&rsquo;Iran, etc. Cartalucci \u00e9crit, le <a href=\"http:\/\/landdestroyer.blogspot.co.uk\/2012\/08\/us-desperation-surfaces-in-syria.html\" class=\"gen\">21 ao\u00fbt 2012<\/a>, dans son texte \u00ab<em>US Desperation Surfaces in Syria<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t\u00ab<em>To say that the US is overstretched is an understatement. It is overstretched politically, economically, and tactically. It risks a historically unprecedented collapse that would destroy all shareholders invested in its increasingly unhinged and transparently illegitimate ambitions. Nations, in particular GCC members, are beginning to realize with acute alarm that their support of Washington&rsquo;s agenda is now threatening their very self-preservation. A victory even at this point would still likely be Pyrrhic<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tWashington d\u00e9sesp\u00e9r\u00e9 ? Alors, Washington va se rendre \u00e0 la raison, faire des concessions, etc. ? Non, parce que ce serait capituler, et que Washington n&rsquo;est pas \u00e9quip\u00e9 psychologiquement, par les temps qui courent, c&rsquo;est-\u00e0-dire encore plus qu&rsquo;\u00e0 l&rsquo;habitude, pour imaginer quoi que ce soit sinon encore et toujours une radicalisation de sa position, parce que l&rsquo;id\u00e9e de se rendre \u00e0 la raison, de faire des concessions, signifierait capituler dans son grossissement des choses, et que ce concept n&rsquo;a pas cours dans les esprits de ces gens par refus pur et simple de leur psychologie de le substantiver. La psychologie de l&rsquo;am\u00e9ricanisme interdit d&rsquo;envisager selon cette vision grossie des choses, simplement comme impensable et inconcevable, le concept d&rsquo;une capitulation m\u00eame am\u00e9nag\u00e9e de la nation indispensable. (Voir l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-l_inculpabilite_comme_fondement_de_la_psychologie_americaniste_06_05_2006.html\" class=\"gen\">inculpabilit\u00e9<\/a> et l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-a_cote_de_l_inculpabilite_l_indefectibilite_de_la_psychologie_us_23_11_2006.html\" class=\"gen\">ind\u00e9fectibilit\u00e9<\/a>, soit l&rsquo;incapacit\u00e9 de se percevoir coupable et l&rsquo;incapacit\u00e9 de se percevoir vaincu.)<\/p>\n<h3>Il semble que le rouge est mis<\/h3>\n<\/p>\n<p><p>\tOn dispose ainsi de l&rsquo;\u00e9tat de l&rsquo;esprit du c\u00f4t\u00e9 US, et c&rsquo;est le plus dangereux qu&rsquo;on puisse imaginer : accul\u00e9 aux \u00e9checs \u00e0 r\u00e9p\u00e9tition, et de plus en plus incapable d&rsquo;accepter, et d&rsquo;ailleurs de concevoir l&rsquo;\u00e9chec ; ainsi pense, juge et r\u00e9agit l&#8217;empire aux abois Mais, <strong>surtout<\/strong>, du c\u00f4t\u00e9 russe, le fond de la pens\u00e9e a chang\u00e9. Il nous semble que la remarque de Lavrov commence \u00e0 atteindre le cur du sujet, non plus seulement en th\u00e9orie mais bien du point de vue op\u00e9rationnel tant de la communication que des potentialit\u00e9s de la situation sur le terrain. <\/p>\n<\/p>\n<p><p>\tCe que Lavrov nous dit, c&rsquo;est que la Syrie devient un test final, fondamental, et que, par cons\u00e9quent, pour la Russie il est politiquement inacceptable que triomphe la doctrine du bombardement d\u00e9mocratique ; ce que Lavrov nous dit,  allons un pas plus loin mais un pas \u00e9vident selon la logique du propos,  c&rsquo;est que la Russie fera tout ce qui est en son pouvoir pour faire en sorte que cela, le triomphe de cette th\u00e9orie, ne se fasse pas. Ce que disent les Russes, enfin, c&rsquo;est qu&rsquo;ils ne peuvent accepter le triomphe de la doctrine du bombardement d\u00e9mocratique, parce qu&rsquo;on se trouverait dans ce cas devant un d\u00e9cha\u00eenement potentiel qui ne serait plus born\u00e9 par rien, que plus rien n&rsquo;arr\u00eaterait, qui toucherait m\u00eame, qui sait, la Russie elle-m\u00eame. <\/p>\n<\/p>\n<p><p>\tD\u00e9sormais, la crise syrienne, c&rsquo;est bien plus que la crise syrienne. Nous avons vu son envol, cette fois-ci nous voyons la crise syrienne <strong>qui s&rsquo;envole<\/strong>, pour devenir le moteur central de crise haute, ce par quoi les d\u00e9veloppements majeurs,  explosion ou autre chose,  peuvent d\u00e9sormais survenir. La d\u00e9claration de Lavrov (\u00ab<em>We believe this issue attracts so much attention not only because of the scale of the bloodshed, which worries all of us, but also because the outcome of the crisis will significantly influence the patterns for conflict settlement<\/em>\u00bb) montre parfaitement que les Russes appr\u00e9cient d\u00e9sormais cette crise comme un \u00e9v\u00e8nement central, dont l&rsquo;issue d\u00e9passe largement le cadre du pays, de la r\u00e9gion, voire de toute situation g\u00e9opolitique, pour devenir un \u00e9v\u00e8nement fondateur ou un \u00e9v\u00e9nement f\u00e9d\u00e9rateur de la situation g\u00e9n\u00e9rale de relations internationales. Cette analyse semblerait effectivement que la Russie est en train de faire son choix, si elle ne l&rsquo;a fait d\u00e9j\u00e0 : s&rsquo;il s&rsquo;av\u00e8re, ou m\u00eame puisqu&rsquo;il s&rsquo;av\u00e8re que l&rsquo;entente sur une issue acceptable par rapport aux lois internationales s&rsquo;av\u00e8re impossible, alors les choses se r\u00e9gleront sur le terrain de la crise devenue guerre civile, et qui menacerait alors de devenir un conflit international Il est d\u00e9cid\u00e9ment extr\u00eamement difficile de ne pas voir dans l&rsquo;observation de Lavrov suivant celle d&rsquo;Obama selon laquelle les USA pourraient intervenir en Syrie, le simple constat que les Russes, dans ce cas, interviendraient contre une aventure am\u00e9ricaniste.<\/p>\n<\/p>\n<p><p>\tLa psychologie, et avec elle la communication, joue un r\u00f4le fondamental dans un conflit qui est encore une crise et n&rsquo;est pas encore une guerre, tout en en ayant tous les attributs au niveau de la perception ; qui ne m\u00e9nage pas d&rsquo;enjeu op\u00e9rationnel fondamental, encore moins maintenant que la dynamique rebelle des mois de mai-juillet, largement renforc\u00e9e, sinon emmen\u00e9e par les op\u00e9rations de communication (montage, <em>narrative<\/em>,massacres-<em>marketing<\/em>, etc.), se trouve bloqu\u00e9e et n&rsquo;\u00e9volue plus gu\u00e8re. (La diplomatie, elle continue \u00e0 \u00eatre enlis\u00e9e dans le marigot de l&rsquo;impossibilit\u00e9 de l&rsquo;entente, et les Russes semblent d\u00e9sormais consid\u00e9rer cette activit\u00e9 comme une possibilit\u00e9 d&rsquo;action parmi d&rsquo;autres et non plus comme la possibilit\u00e9 centrale, \u00e0 favoriser \u00e0 tout prix.) C&rsquo;est parce que la guerre semble fig\u00e9e que, soudain, la crise menace d&rsquo;atteindre un niveau sup\u00e9rieur. L&rsquo;on doit bien comprendre que la psychologie du bloc BAO ne peut accepter la v\u00e9rit\u00e9 de la situation actuelle, celle o\u00f9 Assad est toujours en place et les rebelles de plus en plus \u00e9clat\u00e9s en groupes extr\u00e9mistes et bandes ressortant du crime organis\u00e9, parce qu&rsquo;elle est engag\u00e9e sur une course vitale, une fuite en avant qui, par sa seule dynamique, devrait \u00e9touffer les r\u00e9alit\u00e9s de cette d\u00e9b\u00e2cle et l&rsquo;insupportable v\u00e9rit\u00e9 de la situation. C&rsquo;est \u00e9videmment en cela que la psychologie accompagne l&rsquo;\u00e9volution et la transformation des dynamiques de surpuissance en dynamique d&rsquo;autodestruction.<\/p>\n<\/p>\n<p><p>\tEn un sens, c&rsquo;est un pas suppl\u00e9mentaire \u00e0 celui qu&rsquo;on constatait au d\u00e9but du mois, apr\u00e8s la d\u00e9mission de Kofi Annan, et un pas suppl\u00e9mentaire dans la logique m\u00eame des \u00e9v\u00e8nements tels que la communication les interpr\u00e8te d\u00e9sormais (voir le <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_deuxi_me_cha_ne_crisique__06_08_2012.html\" class=\"gen\">6 ao\u00fbt 2012<\/a> et la deuxi\u00e8me cha\u00eene crisique, et aussi le <a href=\"http:\/\/www.dedefensa.org\/article-d_une_narrative_l_autre_10_08_2012.html\" class=\"gen\">10 ao\u00fbt 2012<\/a> et le changement de <em>narrative<\/em>). La d\u00e9mission de Kofi Annan a vu un basculement et une mise \u00e0 nue de la v\u00e9ritable situation, avec les engagements pleins de risque de la Turquie et de l&rsquo;Arabie. Aujourd&rsquo;hui, ce sont les USA eux-m\u00eames qui sont conduits \u00e0 envisager une impasse pour leur entreprise (\u00ab<em>US Desperation Surfaces in Syria<\/em>\u00bb), impasse que leur psychologie leur impose pourtant de ne concevoir en aucune fa\u00e7on possible ; et ce sont les Russes qui d\u00e9cident d&rsquo;identifier toutes les cartes du jeu de la crise syrienne pos\u00e9es sur la table et d&rsquo;identifier l&rsquo;enjeu de cette crise tel qu&rsquo;il est devenu. Au-del\u00e0 de la lecture qu&rsquo;en font les Russes, cet enjeu est n\u00e9cessairement colossal puisque, par le biais des sas de blocage psychologiques qu&rsquo;on a rappel\u00e9s et qui peuvent conduire \u00e0 des initiatives sans la moindre mesure des risques qu&rsquo;elles portent, il concerne le sort m\u00eame de l&#8217;empire flageolant que sont devenus les USA et le bloc BAO <em>as a whole<\/em>, et le sort du Syst\u00e8me enfin&#8230;<\/p>\n<\/p>\n<p><p>\tAinsi la crise syrienne a-t-elle atteint une dimension elle-m\u00eame colossale, alors que rien ne la d\u00e9signait au d\u00e9part pour cette destin\u00e9e. Tout cela se fait, \u00e9trangement, sans que rien d&rsquo;irr\u00e9m\u00e9diable n&rsquo;ait \u00e9t\u00e9 engag\u00e9 aux niveaux qu&rsquo;on \u00e9voque, sans que rien ne se soit fait, si l&rsquo;on veut, comme si la repr\u00e9sentation int\u00e9rieure \u00e0 chacun des possibilit\u00e9s suffisait \u00e0 figurer l&rsquo;acte. Ainsi vont les crises aujourd&rsquo;hui, \u00e9ventuellement jusqu&rsquo;\u00e0 l&rsquo;effondrement de l&#8217;empire, <em>dito<\/em> du Syst\u00e8me,  sans que, vraiment, personne n&rsquo;ait rien con\u00e7u qui puisse faire qu&rsquo;on en vienne \u00e0 cette intensit\u00e9, simplement sous la pouss\u00e9e de psychologies <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_terrorisation_de_la_psychologie_ddecrisis_18_06_2012.html\" class=\"gen\">terroris\u00e9es<\/a>, emport\u00e9s dans un vertige manipul\u00e9 de <a href=\"http:\/\/www.dedefensa.org\/article-de_la_guerre_qui_n_a_pas_eu_lieu_en_syrie_02_04_2012.html\" class=\"gen\">communication<\/a>, sur un territoire min\u00e9e par leurs propres <a href=\"http:\/\/www.dedefensa.org\/article-le_syst_me_et_ses_termites_21_08_2012.html\" class=\"gen\">termites<\/a> Il se pourrait que la fin de leur monde ressemble \u00e0 une rocambolesque caricature d&rsquo;apocalypse, l&rsquo;immense et terrible ambition qui caract\u00e9rise le Syst\u00e8me d\u00e9chain\u00e9 et n\u00e9 du <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_source_de_tous_les_maux_ddecrisis_10_09_2010.html\" class=\"gen\">d\u00e9cha\u00eenement pur<\/a> qu&rsquo;on conna\u00eet, se terminant dans le rien d&rsquo;une implosion jusqu&rsquo;\u00e0 la r\u00e9duction dans son propre trou noir.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Subrepticement, la crise syrienne devient haute 22 ao\u00fbt 2012 C&rsquo;est le 4 f\u00e9vrier 2012 que la crise syrienne a pris son envol, avec le veto russe et le veto chinois \u00e0 une r\u00e9solution propos\u00e9e \u00e0 l&rsquo;ONU par le bloc BAO, qui e\u00fbt constitu\u00e9 une r\u00e9plique du coup libyen d&rsquo;\u00e0 peu pr\u00e8s une ann\u00e9e auparavant. Dans&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4270,3910,10859,3228,8294,2764,5714,3634,4735,2830,3387,3099,9656],"class_list":["post-73334","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-autodestruction","tag-bombardement","tag-chaine","tag-crise","tag-crisique","tag-democratique","tag-haute","tag-inculpabilite","tag-indefectibilite","tag-lavrov","tag-noir","tag-psychologie","tag-trou"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73334"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73334\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}