{"id":73338,"date":"2012-08-24T11:35:42","date_gmt":"2012-08-24T11:35:42","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/08\/24\/lamerican-dream-contemple-le-trou-noir-ou-il-se-disloque\/"},"modified":"2012-08-24T11:35:42","modified_gmt":"2012-08-24T11:35:42","slug":"lamerican-dream-contemple-le-trou-noir-ou-il-se-disloque","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/08\/24\/lamerican-dream-contemple-le-trou-noir-ou-il-se-disloque\/","title":{"rendered":"L&rsquo;<em>American Dream<\/em> contemple le trou noir o\u00f9 il se disloque"},"content":{"rendered":"<p><h3 class=\"titrebloc\">L&rsquo;<em>American Dream<\/em> contemple le trou noir o\u00f9 il se disloque<\/h3>\n<\/p>\n<p><p>\tMercredi, le Congressional Budget Office (CBO) a publi\u00e9 un rapport qui pr\u00e9voit pour 2013 des conditions tr\u00e8s graves de r\u00e9cession aux USA, avec perte de deux millions d&#8217;emploi, si le Congr\u00e8s ne parvient pas \u00e0 prendre en mains le probl\u00e8me du d\u00e9ficit titanesque des finances publiques. C&rsquo;est en fait \u00e0 une direction politique paralys\u00e9e que le CBO s&rsquo;adresse, avec un rapport qui constitue un choc politique et psychologique fondamental pour les USA.<\/p>\n<\/p>\n<p><p>\tQuelques mots du <em>National Post<\/em>, reprenant Reuters, ce <a href=\"http:\/\/news.nationalpost.com\/2012\/08\/22\/u-s-facing-its-worst-decade-heading-toward-fiscal-cliff-congressional-budget-office\/\" class=\"gen\">23 ao\u00fbt 2012<\/a>, pour nous donner quelques impressions de l&rsquo;esprit qui se d\u00e9gage de ce rapport,  un esprit absolument catastrophiste, qui se retrouve dans d&rsquo;autres \u00e9tudes dont celle du <em>PEW Research Center<\/em> donnant une image effrayante de l&rsquo;\u00e9tat mat\u00e9riel et psychologique de la population, particuli\u00e8rement la classe moyenne d\u00e9vast\u00e9e par la crise. (Nous employons ce terme de catastrophiste, dans un sens objectivement approbateur bien plus que critique. Ce n&rsquo;est pas un esprit alarmiste mais un esprit constatant objectivement une tendance g\u00e9n\u00e9rale et in\u00e9luctable vers la catastrophe comme condition g\u00e9n\u00e9rale de la situation bien plus que l&rsquo;annonce d&rsquo;une catastrophe bien sp\u00e9cifique, m\u00eame s&rsquo;il la contient.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>As the U.S. middle class faces its worst decade in modern history, a new report says an impending fiscal cliff is worse than previously thought and could plunge the country into recession.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Massive U.S. government spending cuts and tax hikes due next year will cause dire economic damage if Washington fails to come up with a solution, the Congressional Budget Office (CBO) warned on Wednesday. Without action by Congress to avoid the fiscal cliff, Americans should expect a significant recession and the loss of some two million jobs, CBO director Doug Elmendorf said in his gloomiest assessment yet.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The forecast comes as a Pew Research Center study says 85% of middle-class Americans feel it is more difficult now than a decade ago to maintain their standard of living. The report describes them as losing faith in the future. The study says the U.S. middle class is facing its worst decade in modern history, with its share of the nation&rsquo;s income falling for the first time since the Second World War<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDans un article d&rsquo;opinion publi\u00e9 sur le m\u00eame <em>National Post<\/em>, le <a href=\"http:\/\/opinion.financialpost.com\/2012\/08\/21\/u-s-worse-than-europe\/\" class=\"gen\">22 ao\u00fbt 2012<\/a>, l&rsquo;universitaire et \u00e9conomiste Jack M. Mintz dresse un r\u00e9quisitoire contre l&rsquo;attitude de la direction politique des USA. Il la compare \u00e0 celle de l&rsquo;Europe, constatant que les Europ\u00e9ens tentent de faire quelque chose tandis que Washington ne fait rien, semblant paralys\u00e9 Il n&rsquo;est pas question ici de souscrire \u00e0 la comparaison de l&rsquo;experts, de comparer l&rsquo;Europe et les USA en tirant des conclusions de cette seule comparaison, ce qui serait faire le jeu du Syst\u00e8me ; l&rsquo;Europe fait quelque chose, mais ce quelque chose est \u00e9galement catastrophique puisque l&rsquo;on reste dans le <em>diktat<\/em> du Syst\u00e8me qui encha\u00eene catastrophe sur catastrophe. Ce qui nous int\u00e9resse est l&rsquo;aspect psychologique,  ici l&rsquo;on tente quelque chose, l\u00e0 on ne fait rien,  et, pr\u00e9cis\u00e9ment, de mettre en \u00e9vidence l&rsquo;esp\u00e8ce d&rsquo;atonie paradoxalement furieuse qui caract\u00e9rise les \u00e9lites am\u00e9ricanistes, avec quelque chose d&rsquo;une pathologie qu&rsquo;on identifierait comme une asth\u00e9nie de la psychologie<\/p>\n<\/p>\n<p><p>\t\u00ab<em>At a European conference on the sovereign-debt crises that I \u00adattended this week, my overwhelming conclusion, after listening to many experts, is that the U.S. is in far more trouble than Europe. This was brought home by calculations presented by Larry Kotlikoff of Boston University at a lecture held at the International Institute of Public Finance, the biggest gathering of public-finance experts in the world. Greece may be bankrupt, but the U.S. looks like a giant Ponzi scheme.<\/em> [] <em>The U.S. reflects the most extreme case of intergenerational inequality. Generation after generation has participated in a Ponzi game, leaving younger taxpayers to pick up the tab for money effectively borrowed by older generations to spend on unfunded benefits. Kotlikoff labelled such practices as child fiscal abuse, a rather strong term but not far from the truth<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>The European are dealing with their severe fiscal problem, even if clumsily. But where are U.S. politicians and the public, who still don&rsquo;t understand the extent of their potential fiscal bankruptcy? The U.S. has the political structure to get the job done, but seems too paralyzed to address a looming fiscal crisis<\/em> [] <em>The United States should be ashamed. While many experts criticize the Europeans for not pulling together politically, U.S. indebtedness is far greater and more dangerous to the world economy.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tOn ajoute un autre facteur, \u00e9conomique lui aussi, mais qui rappelle les v\u00e9ritables dimensions absolument, fondamentalement <strong>eschatologiques<\/strong> de la crise g\u00e9n\u00e9rale du Syst\u00e8me, en ajoutant l&rsquo;\u00e9l\u00e9ment de la catastrophe naturelle. Nous ne sommes pas neutres non plus dans cette affaire (nous, l&rsquo;esp\u00e8ce humaine en g\u00e9n\u00e9ral), nous qui avons entrepris et semblons sur la voie de l&rsquo;accomplissement, <strong>\u00e9galement<\/strong>, de la destruction du monde avec notre <a href=\" http:\/\/www.dedefensa.org\/article-notes_sur_la_source_de_tous_les_maux_ddecrisis_10_09_2010.html\" class=\"gen\">d\u00e9cha\u00eenement de la Mati\u00e8re<\/a>. On choisit ici de mettre en \u00e9vidence, dans un texte du site <em>The Economic Collapse<\/em> sur les huit menaces \u00e9conomiques dont ne parlions m\u00eame pas au d\u00e9but de l&rsquo;\u00e9t\u00e9 (le <a href=\"http:\/\/theeconomiccollapseblog.com\/archives\/8-economic-threats-that-we-were-not-even-talking-about-at-the-beginning-of-the-summer\" class=\"gen\">22 ao\u00fbt 2012<\/a>), cette menace sp\u00e9cifique de l&rsquo;\u00e9tat du fleuve Mississipi, en voie d&rsquo;ass\u00e9chement \u00e0 cause de l&rsquo;immense s\u00e9cheresse qui d\u00e9vaste les \u00c9tats-Unis. Ce cas est singuli\u00e8rement path\u00e9tique et symbolique, tant le puissant Mississipi est un objet fondamental de la psychologie et de la culture humaine aux USA, un symbole \u00e0 la fois de puissance de la nature, de sa sublime beaut\u00e9, de l&rsquo;\u00e9quilibre du monde lorsque nous croyions qu&rsquo;il s&rsquo;agissait du Nouveau Monde et ainsi de suite. La description est dans les effets \u00e9conomiques de la chose, mais imaginez la d\u00e9vastation que ce ph\u00e9nom\u00e8ne ajoute \u00e0 une psychologie am\u00e9ricaine (plus qu&rsquo;am\u00e9ricaniste, dans ce cas) d&rsquo;ores et d\u00e9j\u00e0 d\u00e9vast\u00e9e (Comme d&rsquo;habitude avec <em>The Economic Collapse<\/em>, les textes sont farcis de r\u00e9f\u00e9rences qui permettent de disposer, si on le veut, de toutes les pr\u00e9cisions n\u00e9cessaires.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Thanks to this drought, rivers and lakes all over the United States are drying up.  In fact, there have been reports that millions of fish have been dying because water levels have gotten so low in many areas. Even the mighty Mississippi River has dropped to dangerously low levels.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>At this point, the Mississippi is lower than most people living along the river can ever remember.  If it drops much lower, it could potentially have an absolutely devastating impact on the U.S. economy. A recent NBC News report described what is at stake&#8230; About $180 billion worth of goods move up and down the river on barges, 500 million tons of the basic ingredients for much of the U.S. economy, according to the American Waterways Operators, a trade group. It carries 60 percent of the nation&rsquo;s grain, 22 percent of the oil and gas and 20 percent of the coal, according to American Waterways Operators. It would take 60 trailer trucks to carry the cargo in just one barge, 144 18-wheeler tankers to carry the oil and gas in one petroleum barge.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>If all traffic along the Mississippi was forced to stop, it is estimated that it would cost the U.S. economy about 300 million dollars a day. And already there have been stoppages along one 11 mile stretch of the river&#8230; Nearly 100 boats and barges were waiting for passage Monday along an 11-mile stretch of the Mississippi River that has been closed because of low water levels, the U.S. Coast Guard said. New Orleans-based Coast Guard spokesman Ryan Tippets said the stretch of river near Greenville, Miss., has been closed intermittently since Aug. 11, when a vessel ran aground.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>So what happens if the Mississippi gets even lower?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tVous avez enfin, comme un effet de miroir qui a la vertu de vous faire oublier la froide impulsion des statistiques \u00e9conomiques, l&rsquo;\u00e9tat difficilement embrass\u00e9 m\u00eame par les pires qualificatifs, de la population US. Ce n&rsquo;est pas la documentation qui manque, au contraire elle nous submerge, nous asphyxie Il faut donc choisir, au moment ad\u00e9quat. (Voir le <LIEN=http:\/\/www.dedefensa.org\/article-chronique_du_19_courant_bilan_19_08_2012.html>19 ao\u00fbt 2012  et notre id\u00e9e de l&rsquo;\u00ab<em>opportunit\u00e9 de s\u00e9lection de ces informations.<\/em>\u00bb) Aujourd&rsquo;hui est un moment ad\u00e9quat, pour \u00e9largir le propos, dans le sens de la catastrophe \u00e9conomique renforc\u00e9e et confort\u00e9e par la catastrophe humaine, les deux li\u00e9es par un effondrement psychologique de la soci\u00e9t\u00e9 et des \u00eatres qui la composent. Cet effondrement vaut aussi bien, sous des formes diff\u00e9rentes, pour les 1% qui semblent accueillir presque avec <strong>innocence<\/strong> les pires influences mal\u00e9fiques en chevauchant avec une arrogance nihiliste et presque joyeuse la course vers l&rsquo;effondrement, que pour les 99% qui sont emport\u00e9s par elle. Il faut donc lire (sur <em>TomDispatch.com<\/em>, le <a href=\"http:\/\/www.tomdispatch.com\/blog\/175585\/\" class=\"gen\">21 ao\u00fbt 2012<\/a>) le texte de Chris Hedges, co-auteur d&rsquo;un livre qui va para\u00eetre, <em>Days of Destruction, Days of Revolt<\/em>, r\u00e9sultat d&rsquo;une enqu\u00eate de deux ans sur la destruction de la population des USA,  o\u00f9 tout se passe comme si quelque force gigantesque,  le Syst\u00e8me auquel toutes ces directions et \u00e9lites sont soumises est au moins dans notre esprit,  poursuivait avec m\u00e9thode et la plus grande efficacit\u00e9 un programme absolument g\u00e9nocidaire qui ne r\u00e9pond qu&rsquo;\u00e0 une pulsion nihiliste d&rsquo;entropisation g\u00e9n\u00e9rale d&rsquo;une puissance colossale. (Il faut lire aussi, pour les statistiques path\u00e9tiques de l&rsquo;\u00e9volution de cette m\u00eame population, le texte \u00ab<em>Forsaken And Forgotten<\/em>\u00bb, \u00e9galement de <em>The Economic Collapse<\/em>, le <a href=\"http:\/\/theeconomiccollapseblog.com\/archives\/forsaken-and-forgotten\" class=\"gen\">23 ao\u00fbt 2012<\/a>.)<\/p>\n<\/p>\n<p><p>\tOn voit le Syst\u00e8me touch\u00e9 dans ses axes fondamentaux, dans son domaine US dont la sup\u00e9riorit\u00e9 dans le domaine catastrophique est d\u00e9sormais un fait av\u00e9r\u00e9, emport\u00e9 dans une crise qui suit inexorablement sa course d&rsquo;aggravation et d&rsquo;eschatologisation. L&rsquo;<em>American Dream<\/em> continue \u00e0 \u00eatre d\u00e9chiquet\u00e9 dans une \u00e9volution cauchemardesque, qui restitue l&rsquo;inversion de tous les crit\u00e8res fondamentaux de ce mythe. Il y a d&rsquo;abord la paralysie extraordinaire d&rsquo;un syst\u00e8me politique qui semblait prodigieusement bien organis\u00e9 pour contr\u00f4ler et administrer selon ses propres int\u00e9r\u00eats une masse humaine d&rsquo;une consid\u00e9rable importance. D\u00e9sormais, ce syst\u00e8me, organis\u00e9 pour \u00eatre centriste, consensuel, etc., se d\u00e9couvre extr\u00e9miste et fractur\u00e9 d&rsquo;antagonismes sans issue, produisant par ses vertus m\u00eame une situation de blocage que rien ne permet de briser. Il s&rsquo;ensuit que le syst\u00e8me \u00e9conomique et financier est incapable de reprendre son souffle, de retrouver les artifices qui lui permettraient de durer (dans quel but ? Question indiscr\u00e8te). Le deuxi\u00e8me axe fondamental est la d\u00e9vastation extraordinaire de la classe moyenne, orgueil et s\u00e9curit\u00e9 \u00e0 la fois du syst\u00e8me de l&rsquo;am\u00e9ricanisme, r\u00e9duite en charpie dans un processus qui d\u00e9couvre avec une violence extraordinaire la logique totalitaire de destruction de l&rsquo;\u00eatre humain. Enfin, l&rsquo;intervention de la catastrophe \u00e9cologique et climatique, o\u00f9 l&rsquo;Am\u00e9rique occupe la premi\u00e8re place dans sa manufacture par rapport au syst\u00e8me de production et de consommation d&rsquo;\u00e9nergie qui caract\u00e9rise le Syst\u00e8me depuis deux si\u00e8cles, semble avoir un aspect presque symbolique : avec l&rsquo;\u00e9tablissement de plus en plus av\u00e9r\u00e9, qu&rsquo;on croirait presque <strong>organis\u00e9e<\/strong>, d&rsquo;un syst\u00e8me climatique monstrueux, d\u00e9sormais hostile \u00e0 l&rsquo;organisation \u00e9conomique et sociale du Syst\u00e8me, on a l&rsquo;impression d&rsquo;une esp\u00e8ce de revanche de la nature,  certainement, ce symbole-l\u00e0 va finir par peser d&rsquo;un poids de plus en plus lourd dans nos jugements. <\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit des USA mais il ne s&rsquo;agit plus des USA (ce pourquoi, plus haut, la comparaison entre USA et Europe nous paraissait n&rsquo;avoir aucun sens pertinent). C&rsquo;est une civilisation, un monde, une conception d&rsquo;\u00eatre qui sont en cours d&rsquo;effondrement. Les USA m\u00e8nent la course malgr\u00e9 tous les montages et autres <em>narrative<\/em> parce qu&rsquo;ils sont le cur grondant de cette chose qui nous d\u00e9vore, le cur \u00e0 la fois grondant et d&rsquo;une infinie fragilit\u00e9 ; la fragilit\u00e9 US est \u00e0 l&rsquo;exacte mesure de son apparente puissance, comme la dynamique d&rsquo;autodestruction du Syst\u00e8me accompagne et remplace peu \u00e0 peu sa dynamique de surpuissance. M\u00eame si elles aident encore un peu, les explications \u00e9conomiques, sociales, politiques et historiques sont notablement insuffisantes pour l&#8217;embrassement et la compr\u00e9hension du ph\u00e9nom\u00e8ne.<\/p>\n<\/p>\n<p><p>\tIl se passe aujourd&rsquo;hui quelque chose de cosmique, qui d\u00e9passe nos conceptions et explications habituelles. Il est plus que temps que nos capacit\u00e9s de r\u00e9flexion, et principalement notre raison si elle parvient \u00e0 se d\u00e9gager du <em>diktat<\/em> du Syst\u00e8me, envisage la situation en cours selon des r\u00e9f\u00e9rences et des inspirations plus audacieuses, beaucoup plus audacieuses que celles que nous autorise le Syst\u00e8me. C&rsquo;est ce que nous essayons de faire autant que nous le pouvons, en sugg\u00e9rant constamment l&rsquo;intervention de forces m\u00e9tahistoriques, de ph\u00e9nom\u00e8nes qui d\u00e9passent l&rsquo;organisation humaine Il est tout simplement inacceptable et scandaleux que notre raison, toujours sous le <em>diktat<\/em> du Syst\u00e8me, soit limit\u00e9e dans ses enqu\u00eates, ses r\u00e9flexions et ses hypoth\u00e8ses, aux seules capacit\u00e9s humaines et aux seules explications humaines. Quand on observe le r\u00e9sultat final de ces capacit\u00e9s humaines et la pauvret\u00e9 des explications de la catastrophe, on est conduit \u00e0 se demander \u00e0 quoi sert la raison si elle se trouve limit\u00e9e \u00e0 ces r\u00e9f\u00e9rences Il est extr\u00eamement urgent de lib\u00e9rer notre raison de l&rsquo;insupportable r\u00e9f\u00e9rence humaine, sans quoi toute recherche de compr\u00e9hension du ph\u00e9nom\u00e8ne et de ses cons\u00e9quences suivra le m\u00eame chemin que le Syst\u00e8me qui propose comme solution de la crise de poursuivre la m\u00eame d\u00e9marche, en l&rsquo;accentuant encore, qui a conduit \u00e0 la crise.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 24 ao\u00fbt 2012 \u00e0 11H32<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;American Dream contemple le trou noir o\u00f9 il se disloque Mercredi, le Congressional Budget Office (CBO) a publi\u00e9 un rapport qui pr\u00e9voit pour 2013 des conditions tr\u00e8s graves de r\u00e9cession aux USA, avec perte de deux millions d&#8217;emploi, si le Congr\u00e8s ne parvient pas \u00e0 prendre en mains le probl\u00e8me du d\u00e9ficit titanesque des finances&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4270,7168,9721,14961,4152,15048,5535,3725,8122],"class_list":["post-73338","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-autodestruction","tag-cbo","tag-collapse","tag-economic","tag-hedges","tag-mississipi","tag-raison","tag-recession","tag-secheresse"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73338"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73338\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}