{"id":73359,"date":"2012-09-03T05:47:56","date_gmt":"2012-09-03T05:47:56","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/09\/03\/grace-a-la-crise-syrienne-la-turquie-risque-le-pire\/"},"modified":"2012-09-03T05:47:56","modified_gmt":"2012-09-03T05:47:56","slug":"grace-a-la-crise-syrienne-la-turquie-risque-le-pire","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/09\/03\/grace-a-la-crise-syrienne-la-turquie-risque-le-pire\/","title":{"rendered":"Gr\u00e2ce \u00e0 la crise syrienne, la Turquie risque le pire"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Gr\u00e2ce \u00e0 la crise syrienne, la Turquie risque le pire<\/h3>\n<\/p>\n<p><p>\tOn voit par ailleurs (sur <em>Ouverture libre<\/em>, ce <a href=\"http:\/\/www.dedefensa.org\/article-sc_nes_quotidiennes_du_d_sastre-erdogan_la_fronti_re_syrienne_03_09_2012.html\" class=\"gen\"> 3 septembre 2012<\/a>), la situation \u00e0 la fronti\u00e8re turque, dans les clamps de r\u00e9fugi\u00e9s syriens, ou plut\u00f4t autour d&rsquo;eux puisqu&rsquo;il s&rsquo;av\u00e8re difficile sinon impossible d&rsquo;y p\u00e9n\u00e9trer. Ces camps s&rsquo;av\u00e8rent \u00eatre plus des enclaves d&rsquo;une sorte d&rsquo;agglom\u00e9r\u00e9 comprenant des fractions des rebelles syriens, avec une bonne dose d&rsquo;islamistes, des rassemblements de d\u00e9serteurs de l&rsquo;arm\u00e9e syrienne r\u00e9guli\u00e8re, et, bien s\u00fbr, un pullulement de d\u00e9tachements ou de forces sp\u00e9ciales accoint\u00e9es \u00e0 divers services habitu\u00e9s des coups fourr\u00e9s, surtout dans cette occurrence,  CIA, <em>Mossad<\/em>, MI6, DGSE On \u00e9voque \u00e9galement, bien entendu, le PKK et les divers Kurdes, s&rsquo;infiltrant ici et l\u00e0. Les r\u00e9fugi\u00e9s ont des comportements plut\u00f4t inattendus,  ou bien, le contraire, qui ne surprendront pas ceux qui sont avertis,  vis-\u00e0-vis des populations turques. Les officiels turcs, l&rsquo;arm\u00e9e turque contr\u00f4lent-ils encore quelque chose dans ces zones ?<\/p>\n<\/p>\n<p><p>\t\u00bb<em>In the meantime, unease is increasing in Turkey, and particularly in Hatay province, where people are unhappy not just about the number of refugees, but also over the question of whether PKK elements, or Jihadist militants, are also coming into Turkey in the guise of refugees, as many media reports suggest they are. Locals in daily contact with the Syrians also complain increasingly about unruly behavior. For example, there are reports about Syrians eating at restaurants and buying from shops and leaving without paying, telling the proprietors to send the bill to [Prime Minister Recep Tayyip] Erdogan. What compounds the dilemma for Erdogan and Davutoglu is that they are faced with responsibilities now that will also turn international attention on Turkey. First there is the welfare of the refugees, especially given the fact the both Erdogan and Davutogl have consistently said those fleeing Bashar al-Assad can come to Turkey.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>There are many indications that Hatay province has in fact become something of a gathering spot not just for radical Islamic fighters, but also for the secret services of all those countries in the West, and Israel of course, that are concerned about Islamic terrorism. These are not things the Turkish public is prepared to stomach. The upshot is that Turkey faces a potential debacle such as it has not had before due to Syria. The question is how much of this is the result of the government&rsquo;s hasty and overambitious Syrian policy, and how much of it is the product of an inevitable chain of events..&#8232;&#8232;..<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEn d&rsquo;autres termes, qui a envahi qui ? On (Turquie comprise) \u00e9tait cens\u00e9 envahir la Syrie, dans la certitude de la chute annonc\u00e9e du r\u00e9gime Assad pour apr\u00e8s-demain, cela depuis 6 mois, par tous les dirigeants des pays du bloc BAO ; on (Turquie comprise) est cens\u00e9 travailler \u00e0 une <em>no-fly zone<\/em> en Syrie, dont le g\u00e9n\u00e9ral Dempsey <a href=\"http:\/\/www.dedefensa.org\/article-le_g_n_ral_dempsey_en_a_assez_plus_qu_assez_31_08_2012.html\" class=\"gen\">nous dit<\/a> qu&rsquo;il ne vaut mieux pas y penser, que c&rsquo;est un projet militairement intenable. (A ce propos, que disent les g\u00e9n\u00e9raux fran\u00e7ais au pr\u00e9sident Hollande puisque ce pr\u00e9sident annonce tout de go qu&rsquo;on y travaille ?) Pour l&rsquo;instant, c&rsquo;est plut\u00f4t une dr\u00f4le d&rsquo;invasion syrienne de la Turquie, et certainement pas des \u00e9l\u00e9ments les plus s\u00fbrs et les plus contr\u00f4lables. Qu&rsquo;est-ce que le Premier ministre Erdogan nous dit de la souverainet\u00e9 nationale turque, de l&rsquo;\u00e9volution de la coh\u00e9sion de la Turquie avec des rebelles qui se baladent dans les villages turcs autour de leur camp dans la province de Hatay, en disant aux habitants que ce sera bient\u00f4t leur tour ?<\/p>\n<\/p>\n<p><p>\tL&rsquo;aventure est exemplaire. Il y a un an, Erdogan triomphait, partout dans les pays arabes il \u00e9tait le h\u00e9ros populaire, presque un nouveau Nasser, acclam\u00e9 dans <a href=\"http:\/\/www.dedefensa.org\/article-la_turquie_et_l_hypothese_gaullienne_22_09_2011.html\" class=\"gen\">les rues du Caire<\/a>. Sa politique \u00e9tait bas\u00e9e sur un principe affirm\u00e9 de souverainet\u00e9 nationale, sur une dynamique d&rsquo;ind\u00e9pendance, dans le but d&rsquo;\u00e9tablir une situation g\u00e9n\u00e9rale d&rsquo;autonomie souveraine des pays musulmans dans cette zone jusqu&rsquo;ici sous la coupe des puissances \u00e9trang\u00e8res. Par sa nature m\u00eame, absolument structurante et fortement per\u00e7ue comme telle, cette politique le portait irr\u00e9sistiblement. Puis il y eut cette erreur strat\u00e9gique, pire encore, une erreur de conception m\u00eame, montrant que la dirigeants turcs ignoraient finalement, ou bien ont perdu de vue ce qui fait une politique invincible en trop sacrifier \u00e0 l&rsquo;apparence ou \u00e0 l&rsquo;illusion de la puissance comme moteur de la politique. A s&rsquo;allier avec des forces notoirement d\u00e9structurantes, conduites \u00e0 s&rsquo;appuyer in\u00e9luctablement sur des groupes incontr\u00f4l\u00e9s, extr\u00e9mistes, ou bien simplement de groupes de mercenaires, de groupes de criminels et de droits communs, on se trouve entrain\u00e9 dans la voie de la dissolution de ses propres principes, de ses structures fondamentales. La Turquie a exp\u00e9riment\u00e9 d&rsquo;une fa\u00e7on d\u00e9monstrative et incroyablement convaincante ce qu&rsquo;il en co\u00fbte d\u00e9sormais de s&rsquo;allier avec le Syst\u00e8me qui se trouve lui-m\u00eame encalmin\u00e9 dans des crises profondes.<\/p>\n<\/p>\n<p><p>\tNous disons le Syst\u00e8me avec intention, car nous ne croyons certainement pas \u00e0 la sempiternelle version d&rsquo;une Turquie retomb\u00e9e sous la coupe des USA, ou qui pr\u00e9tendument ne l&rsquo;aurait jamais quitt\u00e9e. Comme nous l&rsquo;avons d\u00e9fini r\u00e9cemment en donnant une analyse de ce que nous nommons le bloc BAO (voir le <a href=\"http:\/\/www.dedefensa.org\/article-g_n_alogie_et_v_rit_du_bloc_bao__23_06_2012.html\" class=\"gen\">23 juin 2012<\/a>), il n&rsquo;est plus tant question d&rsquo;h\u00e9g\u00e9monie de l&rsquo;un (les USA, bien entendu) sur les autres. D&rsquo;une fa\u00e7on tr\u00e8s diff\u00e9rente, il s&rsquo;agit d&rsquo;un ensemble de directions politiques compl\u00e8tement gangren\u00e9es par l&rsquo;homog\u00e9nisation, en apparence pour une raison conjoncturelle ou pour une autre inscrite dans une <em>narrative<\/em>,  pour certaines ambitions, \u00e0 cause de certains choix politiques,  et finalement amalgam\u00e9s structurellement dans la grande dynamique-Syst\u00e8me \u00e0 finalit\u00e9 dissolvante et compl\u00e8tement hostile au <a href=\"http:\/\/www.dedefensa.org\/article-la_haine_du_principe_du_principe__31_05_2012.html\" class=\"gen\">principe du Principe<\/a>. Il en r\u00e9sulte que ceux qui entrent dans cette mouvance perdent eux-m\u00eames toute possibilit\u00e9 et toute pr\u00e9tention \u00e0 pouvoir conserver des r\u00e9f\u00e9rences principielles. Il en r\u00e9sulte qu&rsquo;ils perdent rapidement, notamment, leur souverainet\u00e9 dissoute dans la dynamique-Syst\u00e8me, et que cela se sent Il y a un an, telle ou telle bande, d&rsquo;islamistes ou de criminels organis\u00e9s, venus d&rsquo;une Syrie quelconque, n&rsquo;auraient certainement pas os\u00e9 s&rsquo;installer en ma\u00eetre chez soi en plein territoire turc. Aujourd&rsquo;hui, cela se fait parce que cela se peut faire, parce qu&rsquo;il n&rsquo;existe plus la barri\u00e8re invisible mais infranchissable de l&rsquo;affirmation de la souverainet\u00e9, de la colonne vert\u00e9brale du Principe Le r\u00e9sultat est qu&rsquo;il y a six mois d&rsquo;ici, on enterrait d\u00e9j\u00e0 la Syrie, avec la Turquie porteuse principale du cercueil, et qu&rsquo;aujourd&rsquo;hui l&rsquo;on constate que c&rsquo;est la Turquie qui est en grand p\u00e9ril de d\u00e9structuration et qui a tout \u00e0 craindre de l&rsquo;avenir tr\u00e8s proche, qui est d\u00e9j\u00e0 entr\u00e9e dans une crise politique int\u00e9rieure grave.<\/p>\n<\/p>\n<p><p>\tOn veut bien croire que d&rsquo;immenses menaces planent sur toutes les proies que d\u00e9signent les commentateurs-Syst\u00e8me, les experts appoint\u00e9s, les analystes qui pensent selon le cat\u00e9chisme du Syst\u00e8me. Ils sont d&rsquo;ailleurs puissamment aid\u00e9s par une cat\u00e9gorie fournie de commentateurs qui s&rsquo;intitulent antiSyst\u00e8me (ou anti-USA, blanc bonne-bonnet blanc), qui ne cessent de pr\u00eater au Syst\u00e8me des plans universels d&rsquo;investissement et des capacit\u00e9s surnaturelles de les conduire \u00e0 bien. La question n&rsquo;est certainement pas de nier la dangerosit\u00e9 de l&rsquo;\u00e9poque mais bien de d\u00e9terminer de quelle dangerosit\u00e9 il s&rsquo;agit. Chaque nouvelle intervention du Syst\u00e8me dans des territoires qui lui sont pourtant d\u00e9j\u00e0 soumis et o\u00f9 il installe le d\u00e9sordre comme pour s&rsquo;imposer une \u00e9preuve suppl\u00e9mentaire, est salu\u00e9e comme une ruse suppl\u00e9mentaire, pour faire croire \u00e0 une habilet\u00e9 tactique passag\u00e8re dissimulant une puissance strat\u00e9gique conceptuelle plus grande encore. En attendant, les \u00e9v\u00e8nements qui se d\u00e9roulent avant m\u00eame qu&rsquo;on ait envisag\u00e9 de pouvoir les exploiter selon le plan pr\u00e9vu, pour affirmer aussit\u00f4t qu&rsquo;on savait bien qu&rsquo;ils allaient se produire, ne nous montrent que deux choses : la premi\u00e8re est que la surpuissance du Syst\u00e8me, maniant des objectifs d\u00e9structurants et dissolvants, en est elle-m\u00eame victime et se transforme en force d&rsquo;autodestruction, entra\u00eenant ceux qui se rangent sous cette banni\u00e8re dans le d\u00e9sordre et la confusion ; la seconde est que la seule force efficace qu&rsquo;on puisse lui opposer quasiment comme un exorcisme,  non pour le vaincre mais pour accentuer son d\u00e9sordre int\u00e9rieur et autodestructeur, est le principe structurant qui agit sur le Syst\u00e8me comme la croix qu&rsquo;on agite devant le vampire. La Turquie paye et elle n&rsquo;a pas fini de payer pour avoir ignor\u00e9 ou abandonn\u00e9 ces r\u00e8gles fondamentales d&rsquo;une \u00e9poque o\u00f9 il est devenu absurde, vain et contre-productif de raisonner en termes d&rsquo;h\u00e9g\u00e9monies, de forces (forces id\u00e9ologiques, religieuses, etc.) et de conclusions \u00e0 mesure (victoires et d\u00e9faites de ces forces, etc.).<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 3 septembre 2012 \u00e0 05H48<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gr\u00e2ce \u00e0 la crise syrienne, la Turquie risque le pire On voit par ailleurs (sur Ouverture libre, ce 3 septembre 2012), la situation \u00e0 la fronti\u00e8re turque, dans les clamps de r\u00e9fugi\u00e9s syriens, ou plut\u00f4t autour d&rsquo;eux puisqu&rsquo;il s&rsquo;av\u00e8re difficile sinon impossible d&rsquo;y p\u00e9n\u00e9trer. Ces camps s&rsquo;av\u00e8rent \u00eatre plus des enclaves d&rsquo;une sorte d&rsquo;agglom\u00e9r\u00e9 comprenant&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4270,3737,5217,11648,2746,11131,14843,2613],"class_list":["post-73359","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-autodestruction","tag-erdogan","tag-frontiere","tag-principe","tag-souverainete","tag-surpuissance","tag-syrienne","tag-turquie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73359"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73359\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}