{"id":73394,"date":"2012-09-18T13:05:13","date_gmt":"2012-09-18T13:05:13","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/09\/18\/record-pour-le-dow-jones-de-la-fin-des-temps-185-le-17-septembre-2012\/"},"modified":"2012-09-18T13:05:13","modified_gmt":"2012-09-18T13:05:13","slug":"record-pour-le-dow-jones-de-la-fin-des-temps-185-le-17-septembre-2012","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/09\/18\/record-pour-le-dow-jones-de-la-fin-des-temps-185-le-17-septembre-2012\/","title":{"rendered":"Record pour le <em>Dow Jones<\/em> de la Fin des Temps : 185 le 17 septembre 2012"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Record pour le <em>Dow Jones<\/em> de la Fin des Temps : 185 le 17 septembre 2012<\/h3>\n<\/p>\n<p><p>\tLa rubrique <em>Rapture Index<\/em> du <a href=\"http:\/\/www.raptureready.com\/rap2.html\" class=\"gen\">site<\/a> <em>Rapture Ready<\/em> a battu son record, avec un index de 185, effectif hier 17 septembre 2012. Au fait, de quoi s&rsquo;agit-il ?<\/p>\n<\/p>\n<p><p>\tLe mot <em>Rapture<\/em> a une grande vari\u00e9t\u00e9 de traduction, notamment en r\u00e9f\u00e9rence au langage biblique, et souvent en rapport avec les id\u00e9es d&rsquo;Apocalypse et de Fin des Temps Il peut ainsi signifier Extase ou Enl\u00e8vement dans l&rsquo;id\u00e9e de l&rsquo;Enl\u00e8vement des saints, tout cela avant l&rsquo;Apocalypse ou la Fin des Temps (les saints devant \u00eatre conduits au paradis). Le <em>Rapture Index<\/em> est donc un index indicatif de l&rsquo;intensit\u00e9 des activit\u00e9s qui pourraient intervenir comme pr\u00e9curtrices de la Fin des Temps, selon l&rsquo;explication que donne le site lui-m\u00eame sur son travail. Nombre des 40 indicateurs de r\u00e9f\u00e9rence, qui sont expliqu\u00e9s en d\u00e9tails, renvoient \u00e0 la Bible et autres livres saints. Le site compare son index \u00e0 une sorte de <em>Dow Jones Industrial Average<\/em> de la Fin des Temps, avant de c\u00e9der tout de m\u00eame \u00e0 l&rsquo;interpr\u00e9tation d&rsquo;une mesure proph\u00e9tique de l&rsquo;acc\u00e9l\u00e9ration vers la Fin des Temps,  id\u00e9e qui, d&rsquo;ailleurs, se marie avec les lois de la thermodynamique sur l&rsquo;acc\u00e9l\u00e9ration de l&rsquo;entropie et de l&rsquo;effondrement des syst\u00e8mes,  sans contredire en rien, par ailleurs, la loi de la dynamique de l&rsquo;autodestruction, \u00e0 laquelle <em>dedefensa.org<\/em> souscrit comme un des parrains et promoteurs principaux&#8230; Bref, tout le monde semble d&rsquo;accord. <\/p>\n<\/p>\n<p><p>\t\u00ab<em>The Rapture Index has two functions: one is to factor together a number of related end time components into a cohesive indicator, and the other is to standardize those components to eliminate the wide variance that currently exists with prophecy reporting. The Rapture Index is by no means meant to predict the rapture, however, the index is designed to measure the type of activity that could act as a precursor to the rapture. You could say the Rapture index is a Dow Jones Industrial Average of end time activity, but I think it would be better if you viewed it as<\/em> <strong><em>prophetic speedometer. The higher the number, the faster we&rsquo;re moving towards the occurrence of pre-tribulation rapture.<\/em><\/strong>\u00bb<\/p>\n<\/p>\n<p><p>\tNous avions fait allusion en d\u00e9tails au <em>Rapture Index<\/em> le <a href=\"http:\/\/www.dedefensa.org\/article-comme_un_torrent_17_10_2011.html\" class=\"gen\">17 octobre 2011<\/a>, en connexion avec un article de <em>The Independent<\/em> qui signalait l&rsquo;\u00e9volution de la r\u00e9f\u00e9rence de ce m\u00eame index ; nous-m\u00eames rappelant \u00e0 propos du <em>Rapture Index<\/em> ceci, \u00e0 quoi il faudra rajouter l&rsquo;ann\u00e9e 2012 qui bat \u00e9videmment tous les records avec les chiffres de r\u00e9f\u00e9rence de 185 (le plus haut,  record depuis le 17 septembre 2012) et 176 (le plus bas), et confirmant ainsi la tendance ainsi d\u00e9crite. <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Le site du Rapture Index nous indique d&rsquo;ailleurs, toujours dans sa forme statistico-apocalyptique, combien l&rsquo;ann\u00e9e 2011 est exceptionnelle, mais en cela poursuivant une tendance extr\u00eamement r\u00e9guli\u00e8re d&rsquo;exceptionnalit\u00e9 depuis 2008 Respectivement, les index les plus hauts et les plus bas, pour chaque ann\u00e9e depuis 2008 : 2008 (170 et 155), 2009 (169 et 157), 2010 (174 et 168) 2011 jusqu&rsquo;au 10 octobre (184 et 172,  l&rsquo;index au 10 octobre 2011 est de 180) ; on appr\u00e9ciera la r\u00e9gularit\u00e9 de la hausse, aussi bien pour les hauts que pour les bas, et que l&rsquo;index le plus bas pour 2011 est pour l&rsquo;instant quasiment \u00e9quivalent, \u00e0 deux points pr\u00e8s, \u00e0 l&rsquo;index le plus haut de 2010, et sup\u00e9rieur \u00e0 tous les autres,  les plus hauts et les plus bas,  de 2008 et 2009.<\/em>\u00bb (A cette derni\u00e8re <\/p>\n<\/p>\n<p><p>\tA signaler dans la m\u00eame rubrique de la proximit\u00e9 empress\u00e9e de la Fin de Temps un article du site r\u00e9put\u00e9 <em>ZeroHedge.com<\/em>, de ce m\u00eame <a href=\"http:\/\/www.zerohedge.com\/news\/world-verge-war\" class=\"gen\">17 septembre 2012<\/a>. Le th\u00e8me se comprend de lui-m\u00eame, directement \u00e0 partir du titre : \u00ab<em>A World On The Verge Of War?<\/em>\u00bb Le d\u00e9ferlement de la troisi\u00e8me vague du printemps arabe depuis le 11 septembre alimente \u00e9videmment les sp\u00e9culations, par ailleurs renforc\u00e9es par le constat r\u00e9gulier depuis 9\/11 et surtout depuis l&rsquo;automne 2008 que les crises s&rsquo;encha\u00eenent sans qu&rsquo;aucune ne soit r\u00e9solue, \u00e9tablissant et d\u00e9veloppant une <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_chaine_crisique_ddecrisis_02_04_2011.html\" class=\"gen\">cha\u00eene<\/a> <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_deuxi_me_cha_ne_crisique__06_08_2012.html\" class=\"gen\">crisique<\/a> dont on pourrait comparer la structure et le fonctionnement \u00e0 une cha\u00eene volcanique en activit\u00e9 constante.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 18 septembre 2012 \u00e0 13H06<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Record pour le Dow Jones de la Fin des Temps : 185 le 17 septembre 2012 La rubrique Rapture Index du site Rapture Ready a battu son record, avec un index de 185, effectif hier 17 septembre 2012. Au fait, de quoi s&rsquo;agit-il ? Le mot Rapture a une grande vari\u00e9t\u00e9 de traduction, notamment en&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4012,2631,2604,3497,15090,2985,7368,583,2622,11586,6750],"class_list":["post-73394","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-apocalypse","tag-de","tag-des","tag-dow","tag-eschatiologie","tag-fin","tag-index","tag-jones","tag-la","tag-rapture","tag-temps"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73394"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73394\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}