{"id":73399,"date":"2012-09-20T11:18:49","date_gmt":"2012-09-20T11:18:49","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/09\/20\/pentagone-au-bord-de-la-crise-de-nerfs\/"},"modified":"2012-09-20T11:18:49","modified_gmt":"2012-09-20T11:18:49","slug":"pentagone-au-bord-de-la-crise-de-nerfs","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/09\/20\/pentagone-au-bord-de-la-crise-de-nerfs\/","title":{"rendered":"Pentagone au bord de la crise de nerfs"},"content":{"rendered":"<p><h2 class=\"common-article\">Pentagone au bord de la crise de nerfs<\/h2>\n<\/p>\n<p><p>\t20 septembre 2012  Il y a un certain temps que nous n&rsquo;avons plus parl\u00e9 du JSF ; tout va mal, merci&#8230; Le programme fondamental de l&rsquo;avenir du Pentagone poursuit effectivement son chemin catastrophique, mais selon une voie tout \u00e0 fait inhabituelle qui montre que nous nous trouvons dans un monde tr\u00e8s diff\u00e9rent. Le JSF est quelque chose qui est tr\u00e8s inhabituel.<\/p>\n<\/p>\n<p><p>\tEn une semaine, par diverses voix et dans le cadre de processus diff\u00e9rents, le Pentagone a montr\u00e9 qu&rsquo;il se trouvait litt\u00e9ralement \u00e0 bout de nerfs par rapport \u00e0 ce programme et, pr\u00e9cis\u00e9ment, par rapport \u00e0 son constructeur, Lockheed-Martin (LM). Les critiques concernent des points particuliers d&rsquo;ordre technique, certes, mais aussi une appr\u00e9ciation g\u00e9n\u00e9rale, une perception du Pentagone selon laquelle ce programme semble devenir une chose impossible \u00e0 r\u00e9aliser. Les d\u00e9clarations montrent une sorte d&rsquo;affirmation implicite assez  \u00e9trange, comme si le Pentagone semblait estimer de plus en plus que LM vit sur une plan\u00e8te diff\u00e9rente, et qu&rsquo;il y a d&rsquo;abord un gigantesque probl\u00e8me de communication et de compr\u00e9hension.<\/p>\n<\/p>\n<p><p>\t Le <a href=\"http:\/\/www.aviationweek.com\/Article.aspx?id=\/article-xml\/awx_09_11_2012_p0-494098.xml#\" class=\"gen\">11 septembre 2011<\/a> (dans <em>Aviation Week &#038; Space Technology<\/em>), une revue de l&rsquo;\u00e9tat du programme par les principaux officiels du Pentagone concern\u00e9s, d\u00e9bouchait sur un constat d&rsquo;insatisfaction, \u00e0 la fois sur la fa\u00e7on don les essais sont conduits (par LM) et \u00e0 la fois sur un nouveau probl\u00e8me sp\u00e9cifique, celui du casque du pilote du JSF qui int\u00e8gre un ensemble consid\u00e9rable de technologies de contr\u00f4le de l&rsquo;avion lors des missions qu&rsquo;il aura \u00e0 conduire. (Comme sur un scooter, on ne peut pas piloter et contr\u00f4ler fondamentalement le JSF sans son casque hyper-sophistiqu\u00e9.) Le compte-rendu rendait compte effectivement d&rsquo;attitudes g\u00e9n\u00e9rales qui sont de l&rsquo;ordre de la psychologie, au-del\u00e0 et au-dessus des seuls probl\u00e8mes techniques sp\u00e9cifiques. Quelques lignes cit\u00e9es suffisent \u00e0 rendre compte de cette atmosph\u00e8re<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Senior Pentagon officials<\/em> <strong><em>voiced frustration<\/em><\/strong> <em>about the pace of Lockheed Martin Corp&rsquo;s development of the $396 billion F-35 Joint Strike Fighter program at a high-level review on Friday, according to several sources familiar with the program. Officials did not approve a comprehensive plan for operational testing of the F-35 program as had been expected.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The Pentagon&rsquo;s Defense Acquisition Board huddled for more than four hours on Friday evening in a meeting described by one participant as <\/em><strong><em>very painful<\/em><\/strong><em> given ongoing challenges facing the high-tech F-35 helmet that is integral to the craft&rsquo;s weapons systems, and other aspects of the huge program<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Une autre intervention a fait grand bruit, celle du g\u00e9n\u00e9ral de l&rsquo;USAF Christopher Bogdan au s\u00e9minaire annuel de l&rsquo;Air Force Association (AFA), le 17 septembre. (Bogdan est le nouveau chef d\u00e9sign\u00e9 du JSF Program Office [JPO], qui supervise le programme pour le Pentagone. Il doit prochainement succ\u00e9der \u00e0 l&rsquo;amiral Venlet, qui dirige le JPO depuis avril 2010.) Divers comptes-rendus en rendent compte, celui d&rsquo;<em>Aviation Week<\/em> \u00e0 nouveau, le <a href=\"http:\/\/www.aviationweek.com\/Article.aspx?id=\/article-xml\/awx_09_17_2012_p0-496707.xml#\" class=\"gen\">17 septembre 2012<\/a>, celui de <em>AOL Defense<\/em>, le <a href=\"http:\/\/defense.aol.com\/2012\/09\/17\/f-35-programs-relationship-with-lockheed-worst-ive-ever-seen\/\" class=\"gen\">17 septembre 2012<\/a> \u00e9galement, celui de <em>Russia Today<\/em> le <a href=\"http:\/\/rt.com\/usa\/news\/pentagon-f-35-program-bogdan-439\/\" class=\"gen\">19 septembre 2012<\/a>. La phrase qui a domin\u00e9 l&rsquo;intervention de Bogdan, reprise par tous les comptes-rendus, concerne les relations entre le Pentagone et le constructeur Lockheed-Martin dans le cadre du programme JSF,  relations qualifi\u00e9es de pires que j&rsquo;ai jamais connues entre le Pentagone et un de ses contractants. C&rsquo;est Amy Butler, de <em>Aviation Week<\/em>, qui caract\u00e9rise le mieux l&rsquo;esprit de l&rsquo;intervention de Bogdan, qui est extr\u00eamement marqu\u00e9e par l&rsquo;humeur, une sorte de sensation d&rsquo;impuissance, encore plus que des points techniques pr\u00e9cis<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The incoming director of the F-35 program says that a poor relationship between the Joint Program Office, customers and prime contractor Lockheed Martin is the biggest threat to the success of the stealthy, single-engine fighter. It is the worst I have ever seen in a career of managing complex Pentagon programs, including the contentious KC-46A downselect between Boeing and EADS last year, says U.S. Air Force Maj. Gen. Christopher Bogdan. The notoriously forthright general officer spoke Sept. 17 at the Air Force Assn. conference outside Washington, in a small room overflowing with onlookers.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Bogdan says he plans to break down the barriers among the partners immediately upon taking over the program office. For the time being he is the deputy until the Senate approves his nomination for the leadership position. We have got to shed our baggage, he says of program staffers who are unwilling to move forward more productively.<\/em><\/p>\n<\/p>\n<p><p>\t Dans un autre texte, le jour suivant, le <a href=\"http:\/\/www.aviationweek.com\/Article.aspx?id=\/article-xml\/asd_09_18_2012_p04-02-496804.xml\" class=\"gen\">18 septembre 2012<\/a>, la m\u00eame Amy Butler met \u00e0 nouveau le doigt sur <strong>l&rsquo;esprit<\/strong> de cette sorte de crise de nerfs des dirigeants du programme JSF au Pentagone, qui semble d\u00e9sormais plus qu&rsquo;un \u00e9pisode paroxystique mais un \u00e9tat g\u00e9n\u00e9ral durable de d\u00e9pression profonde entrecoup\u00e9 effectivement d&rsquo;\u00e9pisodes \u00e9chevel\u00e9s. Bien que le texte soit compl\u00e8tement centr\u00e9 sur la question technique du casque du pilote, il se termine par des citations de Bogdan particuli\u00e8rement significatives Il y est fait mention de la panique de Bogdan devant la perspective de la chronologie de d\u00e9veloppement (encodage) du programme informatique de l&rsquo;avion,  op\u00e9ration qui devrait atteindre son rythme maximum dans deux ans et qui est d\u00e9j\u00e0 per\u00e7ue comme gigantesque sinon apocalyptique (le volume d&rsquo;encodage du JSF est estim\u00e9 \u00e0 autour de trois fois celui du F-22,  et l&rsquo;on conna\u00eet les probl\u00e8mes insolubles du F-22 \u00e0 cet \u00e9gard,  au point que le JSF est d\u00e9sormais d\u00e9crit par des officiels comme un ordinateur volant). D&rsquo;autre part, il y a une appr\u00e9ciation assez \u00e9nigmatique : Nous faisons des progr\u00e8s Je ne suis pas s\u00fbr que nous cr\u00e9ions les bons progr\u00e8s (les phrases, en anglais, soulign\u00e9es de gras par nous, nous paraissent extr\u00eamement significatives, quoi qu&rsquo;en ait voulu l&rsquo;orateur).<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Bogdan says that some features may not be ready for that 2015 date, but emphasizes that the helmet must be able to perform at night, in weather and allow for weapons operations for the Marine Corps to declare IOC.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Though he sees some glimmers of hope that production processes are improving, Bogdan notes that F-35 software is up to four months behind schedule. There is an awful lot of software on this program.<\/em> <strong><em>It scares the heck out of me<\/em><\/strong><em>, Bogdan says. The flight test program is ahead of schedule in terms of planned flights and test points, he says. From my perspective with the test programs.<\/em> <strong><em>We are making progress . I&rsquo;m not sure we are creating the right progress<\/em><\/strong><em>, Bogdan says.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLorsque l&rsquo;amiral Venlet \u00e9tait arriv\u00e9 \u00e0 la t\u00eate du JSF Program Office, en avril 2010, on consid\u00e9rait qu&rsquo;une p\u00e9riode nouvelle commen\u00e7ait dans les relations entre le Pentagone et LM dans le programme JSF. Venlet se tint coi pendant des mois, au contraire de ses pr\u00e9d\u00e9cesseurs qui avaient constamment men\u00e9 une campagne de relations publiques fond\u00e9e sur un virtualisme total, et diverses <em>narrative<\/em> flatteuses pour le JSF, s&rsquo;encha\u00eenant les unes apr\u00e8s les autres et sans aucune consid\u00e9ration pour la r\u00e9alit\u00e9. Le <a href=\"http:\/\/www.dedefensa.org\/article-le_jsf_le_pentagone_versus_lm_et_la_crise_ultime_29_01_2011.html\" class=\"gen\">29 janvier 2011<\/a>, nous rendions compte de l&rsquo;intention de l&rsquo;amiral Venlet de lancer une offensive fondamentale pour forcer \u00e0 modifier le comportement de Lockheed-Martin, pour que LM ma\u00eetrise enfin son programme. C&rsquo;\u00e9tait, par ailleurs, le constat, d\u00e9j\u00e0 apparent en <a href=\"http:\/\/www.dedefensa.org\/article-le_jsf_et_l_effet_fratricide__04_10_2010.html\" class=\"gen\">ao\u00fbt 2010<\/a>, que les relations entre le Pentagone et LM \u00e9taient devenues, par anticipation du mot du g\u00e9n\u00e9ral Bogdan, les pires que j&rsquo;ai jamais connues<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Dans le Tr\u00e8s Grand D\u00e9sordre qu&rsquo;est devenu le programme JSF, cette \u00e9volution souterraine mais fondamentale qui est en train d&rsquo;\u00e9merger et de s&rsquo;imposer constitue un facteur d&rsquo;une tr\u00e8s grande importance, sans doute un tournant dans le destin du programme JSF. En ao\u00fbt 2009 encore, la complicit\u00e9 JPO-LM \u00e9tait manifeste, suivant en cela, d&rsquo;ailleurs, les illusions qu&rsquo;entretenait le secr\u00e9taire \u00e0 la d\u00e9fense Gates \u00e0 propos du programme JSF. Un an plus tard, en ao\u00fbt 2010, on pouvait sentir qu&rsquo;un froid polaire \u00e9tait en train de s&rsquo;installer entre les deux partenaires, cela encore en parall\u00e8le avec l&rsquo;\u00e9volution de l&rsquo;attitude de Robert Gates. Le changement de climat semble se confirmer et s&rsquo;institutionnaliser, essentiellement \u00e0 la suite des d\u00e9cisions successives du secr\u00e9taire \u00e0 la d\u00e9fense qui repousse le JSF d&rsquo;au moins deux \u00e0 trois ann\u00e9es, dans le meilleur des cas (pas de probl\u00e8mes techniques, pas de surco\u00fbts, etc.), et repousse d&rsquo;autant les b\u00e9n\u00e9fices que Lockheed Martin attend du programme sur la vente de l&rsquo;avion.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;annonce qui avait \u00e9t\u00e9 faite de l&rsquo;arriv\u00e9e en avril 2010 de Venlet \u00e0 la t\u00eate du JPO, et notamment en fonction de sa personnalit\u00e9, avait \u00e9t\u00e9 tonitruante. Pendant neuf mois, le silence de Venlet semblait indiquer que l&rsquo;amiral faisait le m\u00e9nage, nettoyait les \u00e9curies d&rsquo;Augias bureaucratiques qu&rsquo;avait \u00e9t\u00e9 pendant plus de dix ans un JPO compl\u00e8tement complice de LM dans l&rsquo;\u00e9dification d&rsquo;une r\u00e9alis\u00e9 faussaire, compl\u00e8tement acquise \u00e0 la philosophie du virtualisme,  laquelle englobait \u00e9galement le F-22, et avec les r\u00e9sultats qu&rsquo;on a vus depuis. (Voir notamment le <a href=\"http:\/\/www.dedefensa.org\/article-le_monde_virtualiste_des_avions_de_combat_us_f-22_jsf_24_02_2004.html\" class=\"gen\">24 f\u00e9vrier 2004<\/a>,  le <a href=\"http:\/\/www.dedefensa.org\/article-le_roi-jsf_est_nu_05_02_2009.html\" class=\"gen\">5 f\u00e9vrier 2009<\/a>, le <a href=\"http:\/\/www.dedefensa.org\/article-et_voici_le_jsf-bullshit_21_02_2009.html\" class=\"gen\">21 f\u00e9vrier 2009<\/a>.) En janvier 2011, Venlet semblait donc pr\u00eat \u00e0 affronter le monstre, \u00e0 chevaucher le tigre (le tigre-LM et\/ou le tigre-JSF) et \u00e0 le dompter. La pr\u00e9sentation que faisait alors la m\u00eame Butler de l&rsquo;amiral Venlet, portrait unanimement partag\u00e9 par les commentateurs, \u00e9tait celle d&rsquo;un homme solide, comp\u00e9tent, ennemi des compromissions et des arrangements virtualistes de relations publiques, impitoyable dans ses relations avec ses partenaires ou ses adversaires : \u00ab[Venlet&rsquo;s] <em>task will be challenging; but as a noted MiG killer, he is well equipped to navigate what is ahead. He must serve as both a tough government customer  protecting the U.S. interest in this behemoth of a program at a time of growing national debt and increased financial scrutiny  but must also instill confidence in the public (including eight international partners) that this program is worth the expenditure.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tVingt mois plus tard, la b\u00eate semble toujours aussi indompt\u00e9e, au point qu&rsquo;on pourrait le croire indomptable Venlet s&rsquo;en va, sans avoir d\u00e9m\u00e9rit\u00e9, sans que personne n&rsquo;\u00e9mette un mot de r\u00e9serve et encore moins de critique, et son successeur s&rsquo;\u00e9crie que les choses sont pires que jamais. Mais le ton a chang\u00e9 ; il est tonitruant, furieux, annon\u00e7ant que les choses, elles aussi et une fois encore, vont changer ; d&rsquo;autre part, il y a des mots indiquant qu&rsquo;\u00e0 c\u00f4t\u00e9 de cette fureur se sont install\u00e9es l&rsquo;angoisse, voire la panique, t\u00e9moignant d&rsquo;un \u00e9tat de d\u00e9pression profonde. La B\u00eate, le Pentagone que le secr\u00e9taire \u00e0 la d\u00e9fense Cohen baptisait en 1998 du surnom de <em>Moby Dick<\/em>, semblerait avoir trouv\u00e9 B\u00eate plus monstrueuse que lui<\/p>\n<\/p>\n<p><p>\tCes mots (du g\u00e9n\u00e9ral Bogdan) raisonnent \u00e9trangement et rel\u00e8vent effectivement \u00e0 la fois de la psychiatrie, d&rsquo;un psychologie terriblement perturb\u00e9e, et d&rsquo;une sorte de schizophr\u00e9nie qu&rsquo;on qualifierait d&rsquo;<strong>objective<\/strong>, comme si l&rsquo;on ne savait plus, face \u00e0 une r\u00e9alit\u00e9 de plus en plus insaisissable, quel est le vrai monde, et m\u00eame si cela existe encore, le vrai monde : \u00ab<strong><em>It scares the heck out of me<\/em><\/strong> [] <strong><em>We are making progress . I&rsquo;m not sure we are creating the right progress.<\/em><\/strong>\u00bb Qu&rsquo;est-ce qu&rsquo;un bon progr\u00e8s ou un progr\u00e8s juste, cela semblant indiquer qu&rsquo;il y a de faux progr\u00e8s ou des progr\u00e8s mauvais ? Par nature, un progr\u00e8s est une am\u00e9lioration, quelque chose de meilleur,  ou bien non, et alors le g\u00e9n\u00e9ral-philosophe serait-il en train de nous faire le proc\u00e8s de la modernit\u00e9, et du syst\u00e8me du technologisme qui est un des piliers de l&rsquo;entit\u00e9 (le Syst\u00e8me) qui substantive la modernit\u00e9 ?<\/p>\n<h3>Le JSF les emporte tous<\/h3>\n<\/p>\n<p><p>\tBien, nous avons toujours pens\u00e9 que le JSF, c&rsquo;est bien plus que le JSF ; bien plus qu&rsquo;un programme d&rsquo;avion de combat, bien plus m\u00eame que le plus grand programme d&rsquo;avion de combat de tous les temps. Le JSF est une chose en soi, quelque chose de sp\u00e9cifique, avec sa substance sp\u00e9cifique, voire son essence, qui est alors une essence faussaire, trompeuse. La taille colossale du programme, son manich\u00e9isme inh\u00e9rent (le seul avion de combat pour l&rsquo;avenir du Pentagone, c&rsquo;est lui ou rien), son hyper-technologisme impliquant une constante restructuration emp\u00eachant l&rsquo;ach\u00e8vement de ce syst\u00e8me de syst\u00e8mes qu&rsquo;il est en r\u00e9alit\u00e9, son histoire m\u00eame qui le d\u00e9signait d\u00e8s 1995-1996 comme l&rsquo;accomplissement pour au moins un si\u00e8cle de la quintessence de l&rsquo;a\u00e9ronautique de combat selon les r\u00e8gles de l&rsquo;hyperpuissance d&rsquo;alors (les USA au sommet de leur ivresse), tout d\u00e9signait le JSF comme quelque chose de <strong>diff\u00e9rent<\/strong>. Les promesses ont \u00e9t\u00e9 tenues. Le JSF ne ressemble \u00e0 rien de ce qui a pr\u00e9c\u00e9d\u00e9, il est \u00e0 lui seul tout l&rsquo;avenir de la force de combat a\u00e9rienne des USA (et du bloc BAO, sauf l&rsquo;un ou l&rsquo;autre larron en souvenir de ce que fut la France [le <em>Rafale<\/em>, certes]) ; le JSF est \u00e0 lui seul l&rsquo;avenir de l&rsquo;industrie a\u00e9rospatiale dans ce qu&rsquo;elle a de plus avanc\u00e9e en tant que fer de lance du syst\u00e8me du technologisme, du Syst\u00e8me tout court, de la modernit\u00e9. Ainsi sommes-nous \u00e9difi\u00e9s sur l&rsquo;\u00e9tat du technologisme, du Syst\u00e8me tout court, de la modernit\u00e9.<\/p>\n<\/p>\n<p><p>\tMais dire que le JSF, c&rsquo;est bien plus que le JSF et qu&rsquo;il est chose en soi, cela va beaucoup plus loin. Et le constat est confirm\u00e9 par ce que nous disent la fureur et le d\u00e9sarroi \u00e0 la fois de Bogdan, <em>sapiens<\/em> \u00e9toil\u00e9 au service du Syst\u00e8me et croyant du Syst\u00e8me, et d\u00e9couvrant que son idole lui a jou\u00e9 un bien \u00e9trange tour. Le programme JSF est devenu effectivement quelque chose de <strong>vivant<\/strong> en ce sens qu&rsquo;il est totalement incontr\u00f4lable, anim\u00e9 de sa propre logique, de son propre objectif.<\/p>\n<\/p>\n<p><p>\tLe paradoxe de la situation actuelle est que les essais se poursuivent \u00e0 un bon rythme, que la production continue, que les JSF (ou F-35 pour faire plus s\u00e9rieux et nous rassurer) s&#8217;empilent sur les divers pistes de diverses bases et qu&rsquo;ils volent. Bref, le programme progresse mais il s&rsquo;av\u00e8re \u00e9trangement que ce n&rsquo;est pas le bon programme, le progr\u00e8s juste, ou bien le progr\u00e8s gentil si vous voulez. Tout marche et, pourtant, rien ne marche, et le g\u00e9n\u00e9ral Bogdan reste paniqu\u00e9, est de plus en plus paniqu\u00e9, et m\u00eame il panique comme un fou (<em>It scares the heck out of me<\/em>) \u00e0 la pens\u00e9e des progr\u00e8s qui vont \u00eatre faits effectivement Lorsque le g\u00e9n\u00e9ral Bogdan dit \u00ab<em>We are making progress . I&rsquo;m not sure we are creating the right progress<\/em>\u00bb, ne nous dit-il pas (inconsciemment, certes, il ne faut pas lui en demander trop) que le programme JSF fait les progr\u00e8s qu&rsquo;il veut faire, lui, selon sa propre logique de chose autonome ? Et comme le JSF est n\u00e9cessairement enfant du syst\u00e8me du technologisme et donc du Syst\u00e8me tout court, les progr\u00e8s de sa propre logique qui est la logique du Syst\u00e8me sont n\u00e9cessairement les produits d&rsquo;une logique de l&rsquo;autodestruction, selon la dynamique d&rsquo;autodestruction S&rsquo;il y pense, Bogdan, effectivement, <em>It scares the heck out of me<\/em>.<\/p>\n<\/p>\n<p><p>\tEt il n&rsquo;est pas question de tuer la B\u00eate. Il y a deux ou trois ans, quand nous \u00e9tions encore optimiste, on pouvait envisager d&rsquo;abandonner le programme, ce qui \u00e9tait la <strong>seule<\/strong> solution pour sauver les quelques meubles progressistes encore en place. (On pouvait envisager des versions avanc\u00e9es des chasseurs actuellement en service,  un F-16 <em>block<\/em>-60 encore un peu am\u00e9lior\u00e9e, un F-15 SE, pour <em>Silent Eagle<\/em>, propos\u00e9e dans sa version furtive, qui feraient bien l&rsquo;affaire pour remplacer le JSF.) Mais cette option semble de plus en plus improbable \u00e0 mesure que le Pentagone s&rsquo;enfonce de plus en plus dans la nasse qu&rsquo;est le JSF, sort des paquets de $milliards de ses poches perc\u00e9es, continue \u00e0 produire du JSF improbable et dont nul ne sait que faire, se trouve de plus en plus prisonnier de l&rsquo;image de progr\u00e8s que v\u00e9hicule le JSF et qui sied n\u00e9cessairement aux USA, etc. L&#8217;emprisonnement ne cesse de progresser, et le JSF de prendre dans ses rets le Pentagone lui-m\u00eame.<\/p>\n<\/p>\n<p><p>\tLa fureur des gens du Pentagone contre Lockheed-Martin est \u00e0 la fois comique, injuste et path\u00e9tique,  car qui t&rsquo;a fait roi ? Depuis bient\u00f4t vingt ans dans cette affaire,  comme dans bien d&rsquo;autres mais celle-l\u00e0 est l&rsquo;ultime chose,  le Pentagone a \u00e9t\u00e9 complice, formateur, \u00e9ducateur de LM dans l&rsquo;art de la dissimulation, du montage virtualiste, d&rsquo;ailleurs avec un LM excellent \u00e9l\u00e8ve<D>; il l&rsquo;a \u00e9t\u00e9 sans intention de nuire ni de tromper, comme la plupart des complots du jour qu&rsquo;on nous pr\u00e9sente chaque jour,  type plat du jour pour expliquer rationnellement et comme une machination de convenance ce monde m\u00e9tahistorique qui \u00e9chappe totalement \u00e0 l&rsquo;entendement d&rsquo;une raison subvertie. Le Pentagone a \u00e9t\u00e9 ce qu&rsquo;il a \u00e9t\u00e9 dans la perversion de LM et du programme JSF parce qu&rsquo;il y croyait, et LM, bien entendu d\u00e9j\u00e0 perverti lui-m\u00eame, s&rsquo;est laiss\u00e9 entra\u00eener dans cette perversion qu&rsquo;il planifiait d\u00e9j\u00e0 pour lui-m\u00eame, parce qu&rsquo;il y croyait lui aussi. Tout cela, larrons en foire, et larrons en toute ing\u00e9nuit\u00e9, sans voir \u00e0 mal en v\u00e9rit\u00e9 ; mais voil\u00e0 que les lampions diffusent une \u00e9trange lumi\u00e8re et que la f\u00eate a du mal \u00e0 se poursuivre dans la cacophonie des couacs<\/p>\n<\/p>\n<p><p>\tAinsi le JSF progresse-t-il, c&rsquo;est-\u00e0-dire qu&rsquo;il poursuit sa chute en pleine cadence de production, avec le progr\u00e8s produisant de l&rsquo;autodestruction, exactement comme le sugg\u00e8re la loi thermodynamique de production maximale d&rsquo;entropie (MEP ou MaxEP : <em>Maximum Entropy Production<\/em>). La question est de savoir jusqu&rsquo;o\u00f9 il va entra\u00eener le Pentagone, et Lockheed-Martin, dans cette descente aux enfers, qui se fait effectivement \u00e0 la cadence maximale, selon les vastes plans de production du JSF. On reconna\u00eet l\u00e0 les sch\u00e9mas de la logique de l&rsquo;effondrement de l&rsquo;Am\u00e9rique et de la dynamique d&rsquo;autodestruction du Syst\u00e8me. La psychologie en crise des serviteurs du Syst\u00e8me, une psychologie compl\u00e8tement <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_terrorisation_de_la_psychologie_ddecrisis_18_06_2012.html\" class=\"gen\">terroris\u00e9e<\/a> et qui s&rsquo;enfonce dans la panique et dans la d\u00e9pression devant l&rsquo;\u00e9volution de ce qu&rsquo;ils n&rsquo;osent m\u00eame plus croire qu&rsquo;ils contr\u00f4lent, marquera pour nous la progression (encore du progr\u00e8s) du processus.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pentagone au bord de la crise de nerfs 20 septembre 2012 Il y a un certain temps que nous n&rsquo;avons plus parl\u00e9 du JSF ; tout va mal, merci&#8230; Le programme fondamental de l&rsquo;avenir du Pentagone poursuit effectivement son chemin catastrophique, mais selon une voie tout \u00e0 fait inhabituelle qui montre que nous nous trouvons&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4270,12007,15098,2969,250,3501,3502,10130,610],"class_list":["post-73399","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-autodestruction","tag-bogdan","tag-encodage","tag-f-35","tag-jsf","tag-lockheed","tag-martin","tag-venlet","tag-virtualisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73399"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73399\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}