{"id":73400,"date":"2012-09-21T07:39:51","date_gmt":"2012-09-21T07:39:51","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/09\/21\/le-nouveau-paroxysme-du-printemps-et-la-rue-arabe\/"},"modified":"2012-09-21T07:39:51","modified_gmt":"2012-09-21T07:39:51","slug":"le-nouveau-paroxysme-du-printemps-et-la-rue-arabe","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/09\/21\/le-nouveau-paroxysme-du-printemps-et-la-rue-arabe\/","title":{"rendered":"Le nouveau paroxysme du \u201cprintemps\u201d et \u201cla rue arabe\u201d"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Le nouveau paroxysme du printemps et la rue arabe<\/h3>\n<\/p>\n<p><p>\tDans <em>Yedioth Ahronoth<\/em>, Itamar Eichner  consacre un article \u00e0 la position d&rsquo;Isra\u00ebl face aux initiatives arabes pour une zone d\u00e9nucl\u00e9aris\u00e9e au Moyen-Orient, \u00e0 d\u00e9battre au sein de l&rsquo;AIEA. Bien entendu, Isra\u00ebl est compl\u00e8tement oppos\u00e9 \u00e0 cette initiative Mais l&rsquo;int\u00e9r\u00eat de l&rsquo;article, \u00e0 notre sens, r\u00e9side dans les deux premiers paragraphes, qui concernent un probl\u00e8me tout \u00e0 fait diff\u00e9rent : les r\u00e9actions des pays arabes, essentiellement l&rsquo;\u00c9gypte et la Jordanie, en cas d&rsquo;attaque de l&rsquo;Iran par Isra\u00ebl. Il s&rsquo;agit d&rsquo;une \u00e9valuation des USA transmise \u00e0 Isra\u00ebl \u00e0 partir de la perception qu&rsquo;ont les USA de la situation dans les pays arabes avec la nouvelle vague d&rsquo;agitation depuis le 11 septembre. Eichner cite un officiel isra\u00e9lien, parlant de cette intervention US.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Today the Arab leaders do not control their peoples, the street controls the leaders, said a high-ranking Israeli political official who was privy to the American warnings, an Israeli strike is just what the Iranians need: The entire Arab and Muslim street will take to the streets to demonstrate. The high-ranking official linked the warning to the latest developments in the Muslim world, emphasizing that what happened with the film against Mohammed is just a preview of what will happen in case of an Israeli strike.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The official said that the leaders of Egypt and Jordan would not be able to withstand the pressure of the masses and would have to take drastic measures such as the severing of diplomatic ties and annulling the peace agreements, despite the fact that they are personally opposed to a nuclear Iran and perhaps even hope for an Israeli strike.  In addition to the risk of losing the relations with the neighboring countries, the official warned that the strike would have severe ramifications on the ties between Israel and additional Muslim countries around the world, which currently maintain ties with Israel but would be hard put to remain indifferent&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCes indications sont \u00e0 prendre au s\u00e9rieux. Elles expriment certainement une analyse accept\u00e9e dans des segments importants de la direction am\u00e9ricaniste. Il faut mettre l&rsquo;accent sur le fait que cette analyse implique, dans le chef des analystes US, que les directions jordanienne et \u00e9gyptienne actuelles sont, <strong>en temps normal<\/strong>, acquises \u00e0 une orientation pro-am\u00e9ricaniste, qu&rsquo;elles sont hostiles notamment \u00e0 un Iran nucl\u00e9aire comme sont les USA et Isra\u00ebl. Si cela est une appr\u00e9ciation en partie acceptable pour la Jordanie, c&rsquo;est compl\u00e8tement contestable (et dans le meilleur des cas, tout \u00e0 fait incertain) pour le pr\u00e9sident Morsi. Les arguments de ceux qui pr\u00e9sentent cette th\u00e8se d&rsquo;un alignement de Morsi sur les USA, notamment l&rsquo;argument selon lequel Morsi est redevable aux USA d&rsquo;avoir \u00e9t\u00e9 soutenu par eux (en tant que membre des Fr\u00e8res Musulman) et d&rsquo;avoir pu prendre le pouvoir, par neutralisation des militaires par eux (les USA), font jouer dans ce cas un argument de fid\u00e9lit\u00e9 (en faveur des USA) impliquant une certaine correction dans les rapports qui n&rsquo;existe certainement pas dans toute l&rsquo;op\u00e9ration ainsi d\u00e9crite, marqu\u00e9e par le cynisme, la manipulation, la corruption, etc. (L&rsquo;argument de l&rsquo;aide US pour tenir Morsi \u00e9tant extr\u00eamement discutable en fonction des <a href=\"http:\/\/www.dedefensa.org\/article-l_incertitude_bho-morsi_avec_l_interf_rence_ue_15_09_2012.html\" class=\"gen\">alternatives<\/a> existantes et d&rsquo;ores et d\u00e9j\u00e0 explor\u00e9es.) On retrouve surtout l&rsquo;habituelle et puissante d\u00e9formation psychologique (les caract\u00e8res d&rsquo;inculpabilit\u00e9 et d&rsquo;ind\u00e9fectibilit\u00e9) des dirigeants am\u00e9ricaniste, fond\u00e9e sur la conviction faussaire et subversive pour leurs jugements d&rsquo;une sorte d&rsquo;influence \u00e0 la fois objective et transcendante des USA charg\u00e9s de vertus \u00e0 mesure, aboutissant aux situation d\u00e9crites notamment dans notre <em>F&#038;C<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-_how_could_this_happen__17_09_2012.html\" class=\"gen\">17 septembre 2012<\/a>, dans le chef d&rsquo;Hillary Clinton \u00e0 propos des \u00e9v\u00e9nements \u00e0 Benghazi le 11 septembre (\u00ab<em>How could this happen ?<\/em>\u00bb). A cet \u00e9gard, le jugement de Hillary Leverett, \u00e9galement cit\u00e9 dans cet article r\u00e9f\u00e9renc\u00e9, a toute sa valeur : \u00ab<em>It a fantasy to think that<\/em> [<em>the United States<\/em>] <em>has cards to play, with which it can leverage key local actors. The President of Egypt, before he comes to the United States, his first trips were to China and IranThe train has left the station in these countries, and<\/em> <strong><em>unless<\/em><\/strong> [<strong><em>Washington<\/em><\/strong>] <strong><em>figures out how to adapt,<\/em><\/strong> [<strong><em>its<\/em><\/strong>] <strong><em>strategic position in the Middle East and, therefore, globally will continue to erode.<\/em><\/strong>\u00bb<\/p>\n<\/p>\n<p><p>\tC&rsquo;est dans ce cadre que cette analyse d&rsquo;origine am\u00e9ricaniste ne peut en aucun cas \u00eatre soup\u00e7onn\u00e9e de s&rsquo;appuyer, elle, sur une \u00e9valuation pr\u00eatant \u00e0 Morsi des intentions anti-am\u00e9ricanistes et anti-isra\u00e9liennes ; <strong>pourtant<\/strong>, elle aboutit \u00e0 la conclusion que Morsi, et le roi de Jordanie dans le m\u00eame sens, seraient conduits \u00e0 affirmer des positions fortement anti-US et anti-Isra\u00ebl en  cas d&rsquo;attaque de l&rsquo;Iran ; il y aurait alors l&rsquo;abrogation <em>de facto<\/em> du trait\u00e9 de paix de Camp David (et des liens Isra\u00ebl-Jordanie), dans des conditions d&rsquo;extr\u00eame tension qui constitueraient objectivement un acte de d\u00e9claration d&rsquo;hostilit\u00e9 contre Isra\u00ebl. Au contraire des illusions concernant Morsi qu&rsquo;on a vues plus haut, la premi\u00e8re citation rapport\u00e9e sur la situation des dirigeants arabes apr\u00e8s l&rsquo;affaire du film <em>Innocence of Muslims<\/em> comprend certainement une tr\u00e8s grande part de v\u00e9rit\u00e9 objective : \u00ab<em>Today the Arab leaders do not control their peoples, the street controls the leaders.<\/em>\u00bb Il est manifeste qu&rsquo;il s&rsquo;agit du premier effet et de l&rsquo;effet principal de la vague de protestation qui a touch\u00e9 les pays arabes et musulmans depuis le 11 septembre 2012, qui modifie d&rsquo;une fa\u00e7on importante la situation dans la zone. L&rsquo;appr\u00e9ciation cit\u00e9e ci-dessus sur la puissance de la rue dans les pays arabes et musulmans est largement substantiv\u00e9e par le fait que les pays du bloc BAO (surtout les USA) et le syst\u00e8me de la communication en g\u00e9n\u00e9ral, en r\u00e9agissant avec une extr\u00eame puissance (dans diverses directions, peu importe, c&rsquo;est la puissance de la r\u00e9action qui compte), ont effectivement favoris\u00e9 et ent\u00e9rin\u00e9 \u00e0 la fois cette puissance de la rue et largement contribu\u00e9 \u00e0 installer la situation o\u00f9 les dirigeants arabes sont contr\u00f4l\u00e9s par la rue bien plus qu&rsquo;ils ne contr\u00f4lent la rue.<\/p>\n<\/p>\n<p><p>\tL&rsquo;actuelle s\u00e9quence a install\u00e9 effectivement un ph\u00e9nom\u00e8ne important qui est de faire (re)prendre conscience \u00e0 la rue arabe de sa puissance, et de l&rsquo;usage qu&rsquo;elle peut faire de cette puissance pour orienter la politique des dirigeants. Le cas \u00e9gyptien est exemplaire. Il s&rsquo;agit d&rsquo;une sorte de r\u00e9surrection du ph\u00e9nom\u00e8ne de la place Tahrir en \u00c9gypte au d\u00e9but 2011, premi\u00e8re phase du printemps arabe o\u00f9 la rue avait pu exercer une puissance nouvelle pour elle contre le syst\u00e8me Moubarak. (Peu importe pour le cas actuel que les circonstances soient diff\u00e9rentes, la mobilisation de la rue \u00e9galement diff\u00e9rente, \u00e9ventuellement avec des manipulations qui existent de toutes les fa\u00e7ons dans tous les sens, etc. : seule compte la perception de la puissance de la rue.) Cette puissance de la rue de la p\u00e9riode Tahrir s&rsquo;\u00e9tait peu \u00e0 peu \u00e9rod\u00e9e depuis janvier 2011, d&rsquo;autant que de nouvelles institutions se sont mises en place avec l&rsquo;\u00e9lection de Morsi. A nouveau avec la phase actuelle de d\u00e9sordre, on retrouve, jouant \u00e0 plein, cette situation du d\u00e9but 2011. Morsi s&rsquo;en arrange sans doute beaucoup plus que le roi de Jordanie pour le cas cit\u00e9 (et que Moubarak pour l&rsquo;\u00e9pisode Tahrir, cela va sans dire), si effectivement la situation lui apporte un \u00e9l\u00e9ment tactique pour faire \u00e9voluer sa politique dans le sens qu&rsquo;il voudrait en s&rsquo;appuyant sur cet argument de la puissance de la rue, c&rsquo;est-\u00e0-dire en minimisant les risques de pression et d&rsquo;interf\u00e9rences du bloc BAO.<\/p>\n<\/p>\n<p><p>\tDe ce point de vue, et en \u00e9largissant le cas, on peut admettre que le v\u00e9ritable constat \u00e0 faire, c&rsquo;est que le bloc BAO ne contr\u00f4le plus la rue arabe (par l&rsquo;interm\u00e9diaire suppos\u00e9 des dirigeants arabes), c&rsquo;est la rue arabe qui contr\u00f4le le bloc BAO. Le sens de la d\u00e9marche mentionn\u00e9e dans la citation va d&rsquo;ailleurs exactement dans ce sens,  quelles que soient les arri\u00e8re-pens\u00e9es et les manoeuvres des uns et des autres,  puisqu&rsquo;elle fait d\u00e9pendre la pression de ne pas d\u00e9clencher l&rsquo;attaque contre l&rsquo;Iran du comportement suppos\u00e9 des dirigeants \u00e9gyptiens et jordaniens, lequel comportement est d\u00e9crit comme dict\u00e9 par la puissance de la rue ; ce qui conduit \u00e0 la conclusion que la puissance de la rue arabe constitue un facteur objectif pesant sur les conditions d&rsquo;une position ou d&rsquo;une d\u00e9cision concernant une attaque de l&rsquo;Iran. L\u00e0 aussi, il s&rsquo;agit du facteur essentiel de la perception, telle qu&rsquo;elle semble exister chez de nombreux dirigeants des pays du bloc BAO. D\u00e8s le moment o\u00f9 l&rsquo;argument \u00e0 propos de l&rsquo;attaque contre l&rsquo;Iran est avanc\u00e9 entre USA et Isra\u00ebl et qu&rsquo;il est entendu, on peut effectivement conclure que cet \u00e9tat de contr\u00f4le en partie du bloc BAO par la rue arabe est un fait av\u00e9r\u00e9. Dans cette nouvelle situation, il n&rsquo;y a pas besoin de faits ou d&rsquo;\u00e9v\u00e8nements nouveaux pour substantiver cette analyse, la perception des \u00e9v\u00e8nements de la derni\u00e8re d\u00e9cade suffit. C&rsquo;est bien entendu le syst\u00e8me de la communication, dont le ph\u00e9nom\u00e8ne de la perception est d\u00e9pendant, qui m\u00e8ne le jeu. <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 21 septembre 2012 \u00e0 07H35<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le nouveau paroxysme du printemps et la rue arabe Dans Yedioth Ahronoth, Itamar Eichner consacre un article \u00e0 la position d&rsquo;Isra\u00ebl face aux initiatives arabes pour une zone d\u00e9nucl\u00e9aris\u00e9e au Moyen-Orient, \u00e0 d\u00e9battre au sein de l&rsquo;AIEA. Bien entendu, Isra\u00ebl est compl\u00e8tement oppos\u00e9 \u00e0 cette initiative Mais l&rsquo;int\u00e9r\u00eat de l&rsquo;article, \u00e0 notre sens, r\u00e9side dans&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[6911,2870,4892,4204,2631,2773,2774,7737,2622,11981,6157,5953,3178,7505,4495],"class_list":["post-73400","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-arabe","tag-attaque","tag-camp","tag-david","tag-de","tag-iran","tag-israel","tag-jordanie","tag-la","tag-morsi","tag-paix","tag-perception","tag-printemps","tag-rue","tag-traite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73400"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73400\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}