{"id":73401,"date":"2012-09-21T13:25:14","date_gmt":"2012-09-21T13:25:14","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/09\/21\/signe-des-temps-comment-legiferer-sur-la-fin-des-temps\/"},"modified":"2012-09-21T13:25:14","modified_gmt":"2012-09-21T13:25:14","slug":"signe-des-temps-comment-legiferer-sur-la-fin-des-temps","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/09\/21\/signe-des-temps-comment-legiferer-sur-la-fin-des-temps\/","title":{"rendered":"Signe des temps : comment l\u00e9gif\u00e9rer sur la Fin des Temps?"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Signe des temps : comment l\u00e9gif\u00e9rer sur la Fin des Temps?<\/h3>\n<\/p>\n<p><p>\t<em>Russia Today<\/em> rapporte, le <a href=\"http:\/\/rt.com\/politics\/pete-seeks-apocalyptic-propaganda-493\/\" class=\"gen\">20 septembre 2012<\/a>, les p\u00e9rip\u00e9ties d&rsquo;une demande approuv\u00e9e par la l\u00e9gislature de Saint-Petersbourg, adress\u00e9e au gouverneur de la ville pour qu&rsquo;il limite la propagande de la Fin des Temps, ou propagande apocalyptique. Par ces termes, le d\u00e9put\u00e9 Andrei Gorchechnikov d\u00e9signe la litt\u00e9rature pr\u00e9sentant, accompagnant et commentant les diverses th\u00e8ses sur des pr\u00e9dictions apocalyptiques de fin du monde, Fin des Temps, etc.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The deputy, Andrey Gorshechnikov, writes in the official letter to Governor Aleksandr Poltavchenko that eschatological moods are growing in the community and the mass media, always thirsty for ratings, only add up to general panic. The tendency is especially obvious today, in view of the end of the Mayan calendar, which runs out on December 21 this year. This causes the ordinary citizens to seek consolation in alcohol and illegal drugs, prompts growth in the crime and suicide rates, Gorshechnikov claims. The deputy then asks the governor to take measures against the informational boosting of social hysteria by considering legal limitations on the propaganda about the end of the world.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>The head of the Fair Russia party in the chamber, Aleksey Kovalev (Gorshechnikov was elected from the same leftist-centrist party), supported the initiative saying that the federal TV channels&rsquo; search for tasty&rsquo; plots was effectively debilitating the population. He added that the spreading of mysticism was depriving ordinary people of their coordinate grid. The parliamentarian was especially angry at the mass media for spreading Fomenko&rsquo;s crazy ideas that there were no Middle Ages and that Jesus Christ and Genghis Khan are the same person. Here Kovalev referred to the Alternative History theory, suggested some time ago by Russian mathematician Anatoly Fomenko, which states that known historical documents could be repetitive copies of the same ancient originals and therefore the real human history is several times shorter than the one we are all used to.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The chairman of the legislature, Vyacheslav Makarov, suggested that the author of the request himself sought media attention rather than people&rsquo;s peace of mind. Personally, I am not worried by the end of days, said Makarov who represents the United Russia party. Grigory Yavlinskiy of the pro-democracy liberal party Yabloko said that the people&rsquo;s worries about the apocalypse were a symptom of deeper problems in society. At the same time he opposed the direct limitations on certain reports, saying that valerian tincture is more helpful in such cases. Communist Party Deputy Vladimir Dmitriyev said that for him the end time was a thing of the past, as it happened with the breakup of the Soviet Union. At the same time he tried to calm fellow parliamentarians, claiming that he personally knew of scientific reports proving that the planet Earth would exist in its present form for at least several billion years.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl y a bien entendu deux fa\u00e7ons d&rsquo;appr\u00e9cier cette nouvelle. La premi\u00e8re est de consid\u00e9rer la question des principes, et l&rsquo;on retombe dans le d\u00e9bat autour de la libert\u00e9 de parole contre la responsabilit\u00e9, du type de celui qui est en cours \u00e0 Paris, autour de <em>Charlie Hebdo<\/em> et de ses caricatures du Proph\u00e8te. Bien que l&rsquo;esprit du temps, et m\u00eame l&rsquo;esprit-Syst\u00e8me si cette contradiction est acceptable, affectionne cette sorte de d\u00e9bat, nous dirons que la chose nous para\u00eet un peu vaine, notamment \u00e0 cause des fantastiques d\u00e9formations qu&rsquo;impose le syst\u00e8me de la communication. Une telle d\u00e9marche fait d\u00e9pendre ce d\u00e9bat extr\u00eamement acad\u00e9mique et \u00e9ventuellement tr\u00e8s marqu\u00e9 par des positions id\u00e9ologiques th\u00e9oriques aptes \u00e0 donner une bonne conscience \u00e0 tr\u00e8s bon compte, d&rsquo;un facteur technique (l&rsquo;\u00e9cho m\u00e9diatique qu&rsquo;on obtient ou pas) qui en fausse de toutes les fa\u00e7ons compl\u00e8tement le sens.<\/p>\n<\/p>\n<p><p>\tLa deuxi\u00e8me fa\u00e7on sugg\u00e8re de consid\u00e9rer le contenu de la loi, qui n&rsquo;est pas banal. Si l&rsquo;on \u00e9carte l&rsquo;argument de la recherche de la notori\u00e9t\u00e9 m\u00e9diatique mentionn\u00e9e ici, qui est peut-\u00eatre valable mais qui vaut pour tout homme politique standard dans cette sorte de circonstance et qui renvoie aux concurrences politiciennes habituelles, il reste qu&rsquo;il s&rsquo;agit d&rsquo;une initiative tr\u00e8s inhabituelle et remarquable d&rsquo;originalit\u00e9, sinon in\u00e9dite dans l&rsquo;\u00e9poque moderne, et m\u00eame postmoderne. Elle est, bien s\u00fbr, justifi\u00e9e par les caract\u00e8res g\u00e9n\u00e9raux exceptionnels du temps m\u00e9tahistoriques que nous vivons. Elle est effectivement remarquable pour caract\u00e9riser l&rsquo;esprit du temps dans deux domaines :<\/p>\n<\/p>\n<p><p>\t Le domaine de la perception eschatologique du temps que nous vivons, particuli\u00e8rement d\u00e8s cette ann\u00e9e 2012. Il est manifeste que l&rsquo;argument du calendrier des Mayas (Fin des Temps le 21 d\u00e9cembre 2012) est compl\u00e8tement insuffisant pour justifier l&rsquo;\u00e9tat d&rsquo;esprit g\u00e9n\u00e9ral qui pr\u00e9vaut ; d&rsquo;ailleurs, l&rsquo;un de ceux qui ont soutenu la proposition de l\u00e9gislation critique essentiellement la diffusion qui est faite de la th\u00e8se de l&rsquo;Histoire alternative du math\u00e9maticien Anatoly Fomenko et ne s&rsquo;int\u00e9resse gu\u00e8re aux Mayas. C&rsquo;est donc un climat g\u00e9n\u00e9ral qui est vis\u00e9 ici, d&rsquo;ailleurs au nom d&rsquo;arguments politiques et sociologiques qui peuvent \u00eatre consid\u00e9r\u00e9s (d\u00e9sarroi dans la population, d\u00e9sespoir, d\u00e9stabilisation psychologique, etc.). L&rsquo;int\u00e9r\u00eat du constat est d&rsquo;admettre implicitement, une fois l&rsquo;analyse faite, que ce climat, qui devient ainsi une pr\u00e9occupation officielle, s&rsquo;est d\u00e9velopp\u00e9 \u00e0 cause des \u00e9v\u00e8nements eux-m\u00eames et non des diverses th\u00e9ories et th\u00e8ses incrimin\u00e9es : ces th\u00e9ories et ces th\u00e8ses ont tant d&rsquo;\u00e9chos <strong>\u00e0 cause<\/strong> des \u00e9v\u00e8nements et d&rsquo;un climat g\u00e9n\u00e9ral, et non le contraire (ce ne sont pas elles qui cr\u00e9ent les \u00e9v\u00e8nements et le climat g\u00e9n\u00e9ral). D&rsquo;ailleurs, \u00e0 c\u00f4t\u00e9 du succ\u00e8s des th\u00e8ses et th\u00e9ories de la Fin des temps \u00e0 tendance eschatologique \u00e9chappant \u00e0 la raison (qu&rsquo;on pourrait renvoyer \u00e0 une sorte d&rsquo;eschatologisme), il y a tout autant le succ\u00e8s des diverses th\u00e8ses et th\u00e9ories de complot (complotisme) qui rendent compte au contraire d&rsquo;une tendance \u00e0 la rationalisation extr\u00eame de tous les \u00e9v\u00e8nements, y compris les plus incompr\u00e9hensibles, par l&rsquo;action d&rsquo;individus ou de groupes ainsi dot\u00e9s de moyens et de capacit\u00e9s de contr\u00f4le et de prescience renvoyant \u00e0 une explication rationnelle (m\u00eame si telle ou telle action peut \u00eatre d\u00e9pourvue de tout cr\u00e9dit rationnel, justement, impliquant l&rsquo;intervention d&rsquo;une raison <strong>subvertie<\/strong> pour en juger). L&rsquo;explication fondamentale de cette situation est, \u00e0 notre sens, l&rsquo;ouverture compl\u00e8te de la psychologie puis de l&rsquo;esprit \u00e0 cette sorte de d\u00e9marche, en fonction d&rsquo;\u00e9v\u00e8nements qui ont souvent un caract\u00e8re extraordinaire, arbitraire, effectivement incompr\u00e9hensible au premier chef, comme tout ce qui concerne depuis 9\/11 la guerre contre la Terreur, la crise financi\u00e8re de 2008 et ses cons\u00e9quences, les attitudes des directions politiques poursuivant en l&rsquo;accentuant des conceptions politico-\u00e9conomiques absurdes, l&rsquo;usage intensif des <em>narrative<\/em> et du virtualisme, etc. (En bref, il s&rsquo;agit de tout ce qui concerne l&rsquo;activit\u00e9 du Syst\u00e8me, comme nous l&rsquo;appelons, qui devient effectivement le grand \u00e9v\u00e9nement g\u00e9n\u00e9ral d\u00e9stabilisateur engendrant ces r\u00e9actions psychologiques des populations en g\u00e9n\u00e9ral,  la population russe n&rsquo;\u00e9tant certes pas la seule \u00e0 r\u00e9agir de cette fa\u00e7on.)<\/p>\n<\/p>\n<p><p>\t Le second domaine est, comme toujours dans les \u00e9v\u00e8nements structurels importants de l&rsquo;\u00e9poque, la puissance et la formidable efficacit\u00e9 du syst\u00e8me de la communication accompagnant la perte totale de cr\u00e9dit de r\u00e9f\u00e9rences officielles et soi-disant objectives de l&rsquo;information en g\u00e9n\u00e9ral. Le discr\u00e9dit des sources officielles, venues de nos \u00e9lites en g\u00e9n\u00e9ral et des directions politiques, justement \u00e0 cause de l&rsquo;activit\u00e9 du Syst\u00e8me qui les r\u00e9git d\u00e9sormais directement et enti\u00e8rement, donne par effet de vases communicants un cr\u00e9dit formidable \u00e0 tous les flux v\u00e9hicul\u00e9s puissamment par le syst\u00e8me de la communication. D&rsquo;o\u00f9 un ph\u00e9nom\u00e8ne g\u00e9n\u00e9ral d&rsquo;accr\u00e9ditation touchant toutes les informations transitant par le syst\u00e8me de la communication, sans r\u00e9f\u00e9rences n\u00e9cessaires. <strong>Bien entendu<\/strong>, et <strong>au contraire<\/strong> de ce que voudraient faire croire les serviteurs du Syst\u00e8me (presse-Syst\u00e8me, \u00e9lites-Syst\u00e8me, etc.), cette situation ne discr\u00e9dite absolument pas tout ce qui passe par le syst\u00e8me de la communication, selon un jugement manich\u00e9en condamnant comme faussaire toute accr\u00e9ditation hors-Syst\u00e8me. Cette situation implique plus simplement, mais selon des r\u00e9f\u00e9rences bien plus insaisissables et de fa\u00e7on bien plus diverse, que certaines choses sont vraies (et les autres fausses) parmi l&rsquo;amas de th\u00e8ses et de th\u00e9ories aussi bien venues de l&rsquo;eschatologisme que du complotisme, qui transitent par le syst\u00e8me de la communication. La seule voie pour la tentative de reconnaissance du vrai est une d\u00e9marche de s\u00e9lection appuy\u00e9e sur l&rsquo;exp\u00e9rience et l&rsquo;intuition \u00e0 la fois, et sans aucune possibilit\u00e9 de donner une v\u00e9rification de la chose (Mais comme la v\u00e9rification renvoie n\u00e9cessairement \u00e0 la d\u00e9marche scientifique et \u00e0 la raison, toutes deux subverties par le Syst\u00e8me dans une mesure souvent impressionnante, son absence n&rsquo;est en rien la v\u00e9rification de quoi que ce soit) <\/p>\n<\/p>\n<p><p>\tCette d\u00e9marche l\u00e9gislative de la l\u00e9gislature de Saint-Petersbourg est int\u00e9ressante parce qu&rsquo;elle fait entrer dans la reconnaissance officielle et presque juridique, pour la premi\u00e8re fois d&rsquo;une fa\u00e7on aussi nette et d&rsquo;une fa\u00e7on aussi g\u00e9n\u00e9rale, \u00e0 la fois la situation de chaos qui caract\u00e9rise notre temps m\u00e9tahistorique, \u00e0 la fois la position path\u00e9tique d&rsquo;impuissance des appr\u00e9ciations officielles de cette m\u00eame situation de chaos. <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 21 septembre 2012 \u00e0 13H25<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Signe des temps : comment l\u00e9gif\u00e9rer sur la Fin des Temps? Russia Today rapporte, le 20 septembre 2012, les p\u00e9rip\u00e9ties d&rsquo;une demande approuv\u00e9e par la l\u00e9gislature de Saint-Petersbourg, adress\u00e9e au gouverneur de la ville pour qu&rsquo;il limite la propagande de la Fin des Temps, ou propagande apocalyptique. Par ces termes, le d\u00e9put\u00e9 Andrei Gorchechnikov d\u00e9signe&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[7849,15099,10922,7548,15101,3518,15100,2859],"class_list":["post-73401","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-alternative","tag-clendrier","tag-complotisme","tag-eschatologie","tag-eschatologisme","tag-histoire","tag-maya","tag-saint-petersbourg"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73401"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73401\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}