{"id":73418,"date":"2012-09-29T05:43:28","date_gmt":"2012-09-29T05:43:28","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/09\/29\/dedefensaorg-entre-amis\/"},"modified":"2012-09-29T05:43:28","modified_gmt":"2012-09-29T05:43:28","slug":"dedefensaorg-entre-amis","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/09\/29\/dedefensaorg-entre-amis\/","title":{"rendered":"<em>dedefensa.org<\/em> entre amis"},"content":{"rendered":"<p><h3 class=\"titrebloc\"><em>dedefensa.org<\/em> entre amis<\/h3>\n<\/p>\n<p><p>\tNous avions gliss\u00e9, hier, \u00e0 la fin de ce texte du <a href=\"http:\/\/www.dedefensa.org\/article-l_effondrement_de_la_presse-syst_me_28_09_2012.html\" class=\"gen\">28 septembre 2012<\/a>, une allusion sur notre situation et sur le soutien que nous esp\u00e9rons de nos lecteurs, et dont nous avons besoin en g\u00e9n\u00e9ral et pr\u00e9sentement d&rsquo;une fa\u00e7on pressante comme on le voit sur notre barre de comptage des donations, \u00e0 deux jour de la fin du mois. Un simple paragraphe o\u00f9, pourtant, \u00e9mergeaient des expressions telles que syst\u00e8me de la communication antiSyst\u00e8me et r\u00e9volte g\u00e9n\u00e9rale, dont il nous semble qu&rsquo;elles nous concernent tous, au cur de nous-m\u00eames.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Cette chevauch\u00e9e officielle du<\/em> <strong><em>syst\u00e8me de la communication antiSyst\u00e8me<\/em><\/strong> <em>est un ph\u00e9nom\u00e8ne qui requiert la participation active, par le soutien et la solidarit\u00e9, du public qui soutient cette \u00e9volution. C&rsquo;est un cas formidable, sans doute le plus important et le plus efficace, de la<\/em> <strong><em>r\u00e9volte g\u00e9n\u00e9rale<\/em><\/strong> <em>du public contre le Syst\u00e8me. (La communication est le principal enjeu et le principal champ de la bataille en cours, et le terme de<\/em> <strong><em>r\u00e9volte<\/em><\/strong> <em>est absolument \u00e0 sa place ici.) Il va sans dire que c&rsquo;est notre principal argument aupr\u00e8s de nos lecteurs, pour appeler \u00e0 leur soutien et \u00e0 leur solidarit\u00e9 (par exemple, dans le cas concret des donations que demande dedefensa.org). Nous estimons n&rsquo;avoir certainement pas besoin d&rsquo;en dire plus sur ce cas, tant ce cas nous para\u00eet \u00e9vident ; nullement un r\u00e9flexe de d\u00e9fense et de simple survie mais un acte offensif de mobilisation et de r\u00e9volte.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tD&rsquo;un c\u00f4t\u00e9, nous avons toujours besoin de remercier ceux qui ont d\u00e9j\u00e0 fait acte de soutien, comme ceux qui le font r\u00e9guli\u00e8rement, comme l&rsquo;on a un r\u00e9el besoin d&rsquo;exprimer une reconnaissance ; d&rsquo;un autre c\u00f4t\u00e9, il y a cet \u00e9tonnement que la proposition \u00e9vidente de la n\u00e9cessit\u00e9 de la solidarit\u00e9 entre ceux qui font partie d&rsquo;un m\u00eame mouvement de r\u00e9volte g\u00e9n\u00e9rale ne soit pas aussit\u00f4t rencontr\u00e9e par quelques actes tout aussi \u00e9vidents de n\u00e9cessit\u00e9. Peut-\u00eatre y a-t-il un \u00e9chec de notre part \u00e0 convaincre qui doit l&rsquo;\u00eatre, ou qui ne demande qu&rsquo;\u00e0 l&rsquo;\u00eatre, sur un point qui peut sembler trivial (le soutien financier, \u00e0 mesure des moyens de chacun, renouvel\u00e9 mois apr\u00e8s mois). Certains sugg\u00e8rent (nous les en remercions) des formules pour tenter de rattraper ce qui est sans aucun doute une faiblesse de notre part. Nous avouons avoir bien du mal \u00e0 favoriser et \u00e0 mettre en place un tel m\u00e9canisme, peut-\u00eatre par absence d&rsquo;\u00e9nergie pour d\u00e9velopper une telle initiative qui est d&rsquo;une genre o\u00f9 nous n&rsquo;excellons pas, peut-\u00eatre par lassitude, peut-\u00eatre par une faiblesse qui s&rsquo;apparenterait \u00e0 une sorte de fatigue de la psychologie.<\/p>\n<\/p>\n<p><p>\tDans sa chronique du 19 courant install\u00e9e pour saluer de fa\u00e7on \u00e9galement fort triviale la relance, chaque mois, de notre campagne permanente de donation, Philippe Grasset a \u00e9crit, le <a href=\"http:\/\/www.dedefensa.org\/article-chronique_du_19_courant_l_angoisse-melancholia_19_09_2012.html\" class=\"gen\">19 septembre 2012<\/a>, \u00e0 propos de son angoisse et de ce qu&rsquo;il nomme l&rsquo;angoisse-<em>melancholia<\/em>. Certains lecteurs ont r\u00e9agi avec vigueur en l&rsquo;exhortant \u00e0 ne jamais se laisser emporter par l&rsquo;affreuse et terrible angoisse, en lui rappelant qu&rsquo;ils se trouvent \u00e0 ses c\u00f4t\u00e9s. Sur le fond, ces exhortations n&rsquo;\u00e9taient pas n\u00e9cessaires car PhG, au fond, entendait montrer la <strong>n\u00e9cessit\u00e9<\/strong> pour son compte de l&rsquo;angoisse devenant angoisse-<em>melancholia<\/em> quand on la r\u00e9duit et qu&rsquo;on la transmue, parce qu&rsquo;on la r\u00e9duit et qu&rsquo;on la transmue, et qu&rsquo;ainsi on en fait jaillir une puissance cr\u00e9atrice \u00e0 partir du socle de l&rsquo;interrogation r\u00e9ductrice et angoiss\u00e9e que nul ne devrait \u00e9viter de rencontrer d&rsquo;une fa\u00e7on ou l&rsquo;autre. Sur la forme, ces r\u00e9actions \u00e9taient \u00e9patantes et elles-m\u00eames un \u00e9l\u00e9ment du redressement permanent, en montrant chez ces lecteurs la m\u00eame \u00e9nergie cr\u00e9atrice pour renforcer l&rsquo;auteur dans sa propre r\u00e9action. Cela se d\u00e9finit comme une solidarit\u00e9 dans la bataille g\u00e9n\u00e9rale de la r\u00e9volte qui nous d\u00e9finit tous.<\/p>\n<\/p>\n<p><p>\tBien diff\u00e9rente et bien plus terrible, et bien plus insidieuse, cette autre r\u00e9action psychologique qui nous touche parfois, que nous nommerions fatigue psychologique Une lassitude de soi et de ses actes, qui mine cette \u00e9nergie cr\u00e9atrice dont nous avons tous besoin, qui se rapproche plut\u00f4t de ce <em>taedium vitae<\/em> dont il \u00e9tait question dans l&rsquo;introduction de <em>La gr\u00e2ce de l&rsquo;Histoire<\/em> (voir le <a href=\"http:\/\/www.dedefensa.org\/article-introduction_la_souffrance_du_monde_18_12_2009.html\" class=\"gen\">18 d\u00e9cembre 2009<\/a>,  comme le temps passe). D&rsquo;une fa\u00e7on tr\u00e8s caract\u00e9ristique et \u00e0 premi\u00e8re vue paradoxale par rapport \u00e0 la diff\u00e9rence de qualit\u00e9 et d&rsquo;intensit\u00e9 des traits psychologiques, plus hautes et \u00e9clatantes pour l&rsquo;angoisse, bien plus basses et affreusement insidieuses pour la fatigue psychologique, le premier cas concerne le fil des jours pour mener \u00e0 bien sa t\u00e2che jusqu&rsquo;\u00e0 la fin du jour, ce qui est une besogne quotidienne qui semblerait assez modeste. Au contraire pour la puissance de l&rsquo;enjeu consid\u00e9r\u00e9 comme un tout, le second, pourtant si bas et si insidieux, concerne la pression du temps d\u00e9tourn\u00e9 jusqu&rsquo;\u00e0 une Fin des Temps pervertie, car la fatigue psychologique d\u00e9truit effectivement le cur de nous-m\u00eames, sans que nous nous en avisions et rassemblions notre \u00e9nergie pour nous redresser, comme dans le cas de l&rsquo;angoisse. Mais cette fa\u00e7on tr\u00e8s caract\u00e9ristique de s&rsquo;attaquer aux plus puissants enjeux avec des moyens insidieux et bas est une marque de fabrique : il s&rsquo;agit bien de la d\u00e9marche inf\u00e2me du Syst\u00e8me, du d\u00e9cha\u00eenement de la Mati\u00e8re, qui vous neutralise pour vous conduire, par inversion et par dissolution, \u00e0 une Fin des Temps qui voudrait \u00eatre l&rsquo;entropisation finale infectant \u00e0 jamais le levain de la r\u00e9surrection.<\/p>\n<\/p>\n<p><p>\tCertes, cela ne sera pas puisque cela ne peut pas \u00eatre L&rsquo;exhortation est alors d&rsquo;autant plus fond\u00e9e, celle que nous adressons \u00e0 nos lecteurs aussi bien qu&rsquo;\u00e0 nous-m\u00eames. Puisqu&rsquo;il s&rsquo;agit de continuer la bataille en \u00e9cartant cette terrible fatigue psychologique, ici la chose doit donc \u00eatre exprim\u00e9e d&rsquo;une fa\u00e7on bien concr\u00e8te et sans doute un peu triviale, au jour le jour, jusqu&rsquo;\u00e0 la fin de chaque mois,  continuer \u00e0 animer et \u00e0 soutenir <em>dedefensa.org<\/em><\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 29 septembre 2012 \u00e0 05H43<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>dedefensa.org entre amis Nous avions gliss\u00e9, hier, \u00e0 la fin de ce texte du 28 septembre 2012, une allusion sur notre situation et sur le soutien que nous esp\u00e9rons de nos lecteurs, et dont nous avons besoin en g\u00e9n\u00e9ral et pr\u00e9sentement d&rsquo;une fa\u00e7on pressante comme on le voit sur notre barre de comptage des donations,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[16],"tags":[3834,2631,2981,7099,5452,3969,3125,8386,2622,15094,12065,3997,3741,7925,7926],"class_list":["post-73418","post","type-post","status-publish","format-standard","hentry","category-notre-situation","tag-angoisse","tag-de","tag-dedefensa-org","tag-donations","tag-fatigue","tag-grace","tag-grasset","tag-lhistoire","tag-la","tag-melancholia","tag-phg","tag-philippe","tag-psychologique","tag-taedium","tag-vitae"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73418"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73418\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}