{"id":73459,"date":"2012-10-21T04:59:37","date_gmt":"2012-10-21T04:59:37","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/10\/21\/ce-19-courant-et-son-rythme-languissant\/"},"modified":"2012-10-21T04:59:37","modified_gmt":"2012-10-21T04:59:37","slug":"ce-19-courant-et-son-rythme-languissant","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/10\/21\/ce-19-courant-et-son-rythme-languissant\/","title":{"rendered":"Ce \u201c<em>19 courant\u2026<\/em>\u201d et son rythme languissant"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Ce <em>19 courant<\/em> et son rythme languissant<\/h3>\n<\/p>\n<p><p>\tQuelle id\u00e9e nous est venue de penser que la seule <em>Chronique du 19 courant<\/em> suffirait \u00e0 articuler l&rsquo;argument non-dit, ou plut\u00f4t qui ne serait plus \u00e0 dire, que la <em>Chronique<\/em> rappellerait, par sa seule publication, notre besoin de votre soutien et cette date, du 19 courant, comme un moment clef du mois pour manifester ce besoin, et que c&rsquo;est le moment&#8230; Nous-m\u00eames d&rsquo;ailleurs, et l&rsquo;ineffable PhG en premier, r\u00e9pugnons \u00e0 insister, \u00e0 rappeler cet aspect promotionnel sans gloire ni hauteur, ni n\u00e9cessit\u00e9 autre que la pi\u00e8tre opportunit\u00e9, que pr\u00e9tendrait avoir ce texte. Bref, c&rsquo;est plut\u00f4t rat\u00e9.<\/p>\n<\/p>\n<p><p>\tAlors, nous nous en remettons r\u00e9guli\u00e8rement \u00e0 cette technique message direct, sans trop de fioritures et de fausses habilet\u00e9s. Il est vrai que nous \u00e9tions, le 18 octobre, \u00e0 645 (ce qui \u00e9tait un bon niveau, par rapport \u00e0 l&rsquo;habitude), mais que nous sommes, ce matin du 21 octobre, \u00e0 765 (ce qui est un rythme de progression ex\u00e9crable, par rapport \u00e0 la simple logique arithm\u00e9tique et aux habitudes que nous esp\u00e9rions \u00e9tablies de cette mobilisation du 19 courant). Si nous remercions chaleureusement ceux qui sont d\u00e9j\u00e0 intervenus comme ceux qui vont le faire, et cela en pensant \u00e0 certains messages qui nous touchent, il est vrai aussi qu&rsquo;il nous faut rappeler \u00e0 nos lecteurs que nous avons vraiment besoin de leur soutien.<\/p>\n<\/p>\n<p><p>\tIl est vrai enfin que nous aussi, nous avons tendance \u00e0 consid\u00e9rer que l&rsquo;intendance, c&rsquo;est fait pour suivre, et <em>basta<\/em>. Mais le 19 courant, nous d\u00e9couvrons en g\u00e9n\u00e9ral que l&rsquo;intendance, c&rsquo;est plut\u00f4t r\u00e9tif, et que cela n&rsquo;en fait qu&rsquo;\u00e0 sa t\u00eate. Nous d\u00e9couvrons alors la n\u00e9cessit\u00e9 urgente de nous assurer de votre soutien. Nous y sommes.<\/p>\n<\/p>\n<p><p>\tRappelez-vous que nous avons besoin de 2.000 \u00e0 3.000 chaque mois, entre l&rsquo;intendance limite et l&rsquo;intendance confortable, et que nous sommes bien loin de ces comptes-l\u00e0. Alors, ne nous oubliez pas et rappelez-vous que notre existence a ses imp\u00e9ratifs. Soignez aussi notre intendance, pour qu&rsquo;elle suive, sans rechigner, et au galop. Merci pour elle, d&rsquo;avance.<\/p>\n<\/p>\n<p>\n<p class=\"signature\"><em>dedefensa.org<\/em><\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 21 octobre 2012 \u00e0 04H57<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce 19 courant et son rythme languissant Quelle id\u00e9e nous est venue de penser que la seule Chronique du 19 courant suffirait \u00e0 articuler l&rsquo;argument non-dit, ou plut\u00f4t qui ne serait plus \u00e0 dire, que la Chronique rappellerait, par sa seule publication, notre besoin de votre soutien et cette date, du 19 courant, comme un&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[16],"tags":[2981,4854,15161,15058,4737],"class_list":["post-73459","post","type-post","status-publish","format-standard","hentry","category-notre-situation","tag-dedefensa-org","tag-donation","tag-intendance","tag-mensuel","tag-soutien"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73459"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73459\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}