{"id":73466,"date":"2012-10-25T06:49:11","date_gmt":"2012-10-25T06:49:11","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/10\/25\/syrie-usa-la-guerre-et-lhumeur-furieuse-derdogan\/"},"modified":"2012-10-25T06:49:11","modified_gmt":"2012-10-25T06:49:11","slug":"syrie-usa-la-guerre-et-lhumeur-furieuse-derdogan","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/10\/25\/syrie-usa-la-guerre-et-lhumeur-furieuse-derdogan\/","title":{"rendered":"Syrie, USA, la guerre et l&rsquo;humeur furieuse d&rsquo;Erdogan"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Syrie, USA, la guerre et l&rsquo;humeur furieuse d&rsquo;Erdogan<\/h3>\n<\/p>\n<p><p>\tIl ne manque pas d&rsquo;hypoth\u00e8ses, de supputations, de descriptions m\u00eame sur la marche vers la guerre, notamment de la Turquie vers (contre) la Syrie. C&rsquo;est un sujet r\u00e9current et un th\u00e8me d&rsquo;article redondant depuis plusieurs mois, entrecoup\u00e9s d&rsquo;incidents de fronti\u00e8re, de saisies d&rsquo;avions en plein vol, de provocations, de <em>false flag<\/em> divers et vari\u00e9s, etc. Par ailleurs, la guerre n&rsquo;arrive pas. Cela invite \u00e0 classer le projet, en attendant d&rsquo;hypoth\u00e9tiques prolongements, dans la rubrique du retenez-moi ou je fais un malheur qui semble caract\u00e9riser la politique agressive et belliciste d&rsquo;une pathologie psychologique insistante, de la n\u00e9buleuse form\u00e9e avec le bloc BAO, ou autour du bloc BAO,  dont l&rsquo;un des h\u00e9rauts les plus z\u00e9l\u00e9s est le ministre fran\u00e7ais Fabius. (Dans cette rubrique, on place comme arch\u00e9type l&rsquo;attaque-surprise de l&rsquo;Iran qui est annonc\u00e9e avec pertes et fracas, comme imminente et d\u00e9vastatrice, depuis f\u00e9vrier 2005, depuis que GW Bush, tout frais r\u00e9\u00e9lu, avait d\u00e9clar\u00e9 \u00e0 Bruxelles, le 21 f\u00e9vrier 2005, que toutes les options sont sur la table,  y compris et surtout, l&rsquo;attaque, du fait d&rsquo;Isra\u00ebl et des USA fraternellement confondus. On nous annonce aujourd&rsquo;hui, avec Fabius dans le r\u00f4le-titre et finement <em>in fine<\/em>, que c&rsquo;est pr\u00e9vu, quasiment assur\u00e9, pour 2013. L&rsquo;\u00e9poque est celle de la rapidit\u00e9 fulgurante des situations et du changement brutal \u00e0 mesure.)<\/p>\n<\/p>\n<p><p>\tDeux extraits d&rsquo;articles de journaux turcs nous donnent quelques indications sur la situation au moins <strong>psychologique<\/strong> de la tr\u00e8s-prochaine guerre contre la Syrie. D&rsquo;autres y ajoutent quelques indications compl\u00e9mentaires, dans d&rsquo;autres directions. Il s&rsquo;en d\u00e9duit l&rsquo;observation d&rsquo;une situation de grand d\u00e9sordre qui nous pousse \u00e0 ne nous satisfaire d&rsquo;aucune hypoth\u00e8se de type politique, g\u00e9opolitique et militaire \u00e0 connotation  eschatologique, et \u00e0 nous tourner une fois de plus vers l&rsquo;hypoth\u00e8se de la <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_maniaco-depression_du_monde_ddecrisis_19_01_2012.html\" class=\"gen\">maniaco-d\u00e9pression<\/a> de nos dirigeants politiques. Car il doit bien \u00eatre reconnu, de notre fait, que l&rsquo;hypoth\u00e8se de la maniaco-d\u00e9pression conserve plus que jamais notre faveur dans une \u00e9poque o\u00f9 un \u00e9v\u00e9nement de communication (une d\u00e9claration, une hypoth\u00e8se sugg\u00e9r\u00e9e, un anath\u00e8me bombastique, etc.) semble constituer en soi et d&rsquo;une fa\u00e7on suffisante un acte politique, g\u00e9opolitique et militaire d\u00e9cisif \u00e0 connotation eschatologique \u00e0 lui tout seul. Nous ne nierons certainement pas qu&rsquo;il y a de l&rsquo;eschatologie dans l&rsquo;air, bien au contraire puisque c&rsquo;est une th\u00e8se \u00e0 laquelle nous accordons la plus grande attention, et avec une constance significative. Simplement et d\u00e9cisivement, l&rsquo;eschatologie ne nous semble pas \u00eatre du tout le fait des <em>sapiens<\/em> impliqu\u00e9s, qui sont plut\u00f4t les pi\u00e8tres jouets de la chose. Tout cela est maistrien, c&rsquo;est-\u00e0-dire celle de la sorte d&rsquo;\u00e9v\u00e8nements ordonn\u00e9s par des forces sup\u00e9rieures et subis par les <em>sapiens<\/em> impliqu\u00e9s (nos dirigeants politiques) sans qu&rsquo;ils n&rsquo;y comprennent rien, et ceux-ci s&rsquo;imaginant agir dans un sens d\u00e9cisif (eschatologique) par le simple fait de la parole volubile et avec le moteur de l&rsquo;humeur<\/p>\n<\/p>\n<p><p>\t L&rsquo;humeur, notamment celle d&rsquo;un Erdogan. C&rsquo;est ce qu&rsquo;il ressort de cet article de Mehmet Ali Birand, correspondant du grand quotidien turc <em>Hurriyet<\/em> aux Nations-Unies, ce <a href=\"http:\/\/www.hurriyetdailynews.com\/us-damascus-message-military-intervention-out-of-question.aspx?pageID=449&#038;nID=33001&#038;NewsCatID=405\" class=\"gen\">23 octobre 2012<\/a>. Lui, il \u00e9crit qu&rsquo;il semble y avoir deux mondes diff\u00e9rents, celui de la Turquie o\u00f9 l&rsquo;on parle fi\u00e9vreusement de la guerre qui est imminente, chaque jour davantage, et celui des Nations-Unies, o\u00f9 l&rsquo;id\u00e9e d&rsquo;une guerre avec la Syrie semble venir, justement, d&rsquo;une autre plan\u00e8te. Le journaliste turc recueille notamment les remarques int\u00e9ressantes d&rsquo;un diplomate US qui se plaint des humeurs et des emportements du Premier ministre Erdogan, dont il d\u00e9crit le comportement comme celui d&rsquo;un homme psychologiquement instable qui fait parfois craindre \u00e0 Washington d&rsquo;\u00eatre emport\u00e9 dans une guerre dont personne, vraiment personne ne veut<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Reviewing what happened between us and Syria, and after monitoring our media, you come here and are astounded by what you hear and read. It is as if we are living on another planet and people here are living in a completely different one. According to what is reported in our planet, Turkey is a puppet of the United States and acts according to orders coming from Washington. We can expect an armed clash to erupt along the border at any time. When you look at the situation from here, nobody is mentioning an armed intervention for a solution to the Syrian issue anymore. Solving the issue with arms, more precisely the period of toppling of Bashar al-Assad through an external intervention, ended a long time ago.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Under Washington&rsquo;s close monitoring of Ankara lies a concern that it does not mention very openly: Your prime minister from time to time gets so angry and so excited that even we here are afraid of Turkey&rsquo;s military intervention, said an American diplomat. Actually we know very well that Turkey does not want an armed intervention. You have told this to us very clearly. However, on the other hand, it is again you who is pressuring us the most for al-Assad to leave as soon as possible. We also understand that, but a military intervention will bring disaster not only to you but to the entire region. Our fear is that a maneuver from al-Assad will receive such a reaction from<\/em> [<em>Prime Minister Recep Tayyip<\/em>] <em>Erdogan that we will find ourselves all together in a war.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>What the diplomat I was talking to said was very clear. Forget about Ankara following Washington&rsquo;s orders: Washington is openly trying to calm Ankara down and is afraid that we will enter a war as a result of an accident. The reason for this is obvious: Washington does not, in the least bit,  have any intention of intervening in Syria. When you listen to the American public, you immediately understand the reason<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;article se poursuit par une tirade assez classique commen\u00e7ant par la phrase \u00ab<em>The American public is tired of international interventions<\/em>\u00bb On conna\u00eet la musique et l&rsquo;on sait tr\u00e8s pr\u00e9cis\u00e9ment que ce refrain peut \u00eatre renforc\u00e9 encore par le sentiment des experts et de ceux qui croient d\u00e9finir la politique US alors qu&rsquo;ils ne font finalement qu&rsquo;appliquer ce que le Ciel les conduit \u00e0 faire. (Le Ciel ? Ciel ! Disons plut\u00f4t ces forces impersonnelles identifi\u00e9es par l&rsquo;avis\u00e9 et exp\u00e9riment\u00e9 g\u00e9opoliticien qu&rsquo;est George Friedman,  voir le <a href=\"http:\/\/www.dedefensa.org\/article-joseph_de_maistre_travaille-t-il_pour_stratfor_15_10_2012.html\" class=\"gen\">15 octobre 2012<\/a>.)<\/p>\n<\/p>\n<p><p>\t Autre article int\u00e9ressant de la presse turque, celui de Soli Ozel, du quotidien <em>Haberturk<\/em>, le <a href=\"http:\/\/www.al-monitor.com\/pulse\/politics\/2012\/10\/us-offers-ankara-help-to-take-down-pkk.html\" class=\"gen\">22 octobre 2012<\/a>. Venues d&rsquo;un tout autre horizon (une conf\u00e9rence de presse de l&rsquo;ambassadeur US \u00e0 Ankara), les remarques qu&rsquo;on y lit semblent faites pour renforcer l&rsquo;id\u00e9e que les amis am\u00e9ricanistes en ont un peu assez d&rsquo;entendre Erdogan vitup\u00e9rer contre les amis am\u00e9ricanistes et leurs alli\u00e9s BAO parce que tout le monde laisse la Turquie seule face \u00e0 la Syrie faire le sale boulot, et que, notamment, les USA n&rsquo;offrent absolument rien pour aider la Turquie dans cette occurrence \u00e9pouvantable. Nous n&rsquo;entretenons pas d&rsquo;affection particuli\u00e8re pour les diplomates US en poste \u00e0 l&rsquo;\u00e9tranger, avec toutes leurs manigances, mais il faut reconna\u00eetre que l&rsquo;argument de Ricciardone, fond\u00e9 sur la r\u00e9v\u00e9lation d&rsquo;une proposition US que nul n&rsquo;a d\u00e9mentie, a un certain poids et m\u00eame l&rsquo;accent d&rsquo;une v\u00e9rit\u00e9 r\u00e9v\u00e9latrice ; et l&rsquo;on peut imaginer combien les amis am\u00e9ricanistes doivent \u00eatre exc\u00e9d\u00e9s par les humeurs turques, pour l\u00e2cher ce morceau en public, . (Qu&rsquo;est-ce que vous attendez de plus de nous? Nous vous proposons le plus haut degr\u00e9 de coop\u00e9ration avec les meilleurs moyens techniques dont nous disposons. Plus encore, notre objectif est le commandement supr\u00eame du KK, mais vous n&rsquo;en voulez pas.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>United States Ambassador to Turkey Francis Ricciardone dropped a bomb in his meeting with journalists in Ankara last week. He said the US had proposed a joint operation with Turkey against the leaders of the Kurdistan Workers&rsquo; Party (PKK) at the Kandil Mountain range along the lines of that in which US hunted down and killed Osama Bin Laden. According to Prime Minister Recip Tayyip Erdogan, Turkey refused the offer because of differences in topographical conditions. Obviously, Ricciardone meant the revelation as a firm response to misgivings of Turkish public opinion.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>We remember how the Chief of General Staff Gen. Necdet Ozel complained about not getting sufficient and timely intelligence from the US. Public opinion saw Gen. Ozel&rsquo;s remark as reaffirmation of  their apprehension about the US.  The US ambassador, in a way, tried to erase the Turkish mistrust in his country by saying, What else do you expect us to do? We proposed the highest levels of cooperation with our best technical means. Moreover, our target was the top command of the PKK, but you didn&rsquo;t want it.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Ricciardone also took the opportunity to clear the air on how Washington views Turkey&rsquo;s Syria policy. The message was that although the US cooperates closely with Turkey on the Syrian crisis, it is concerned with any development that could elevate the crisis to a war. The US also feels that the continuation the Syrian crisis is endangering the stability of the region, especially in Jordan, Iraq and Lebanon. Washington doesn&rsquo;t favor a prolonged crisis as some suggest, but wants the clashes to end as soon as possible.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tSuivent quelques remarques pour nous dire que tout le monde semble en avoir soup\u00e9 des bruits de guerre contre la Syrie, et m\u00eame des bruits de guerre en Syrie tout court ; que les envois d&rsquo;armes semblent commencer \u00e0 se rar\u00e9fier, que l&rsquo;on murmure que des plans de paix pourraient bien s&rsquo;esquisser (ni\u00e8me  tentative, mais bon), \u00e0 l&rsquo;image de cette tentative de cessez-le-feu temporaire lanc\u00e9e pour une f\u00eate religieuse musulmane et qui aura sans doute, \u00e9videmment, bien du mal \u00e0 passer l&rsquo;\u00e9preuve du chaos qui a \u00e9t\u00e9 install\u00e9 en Syrie Tout cela ne r\u00e9sout rien des \u00e9v\u00e8nements en Syrie, qui sont d&rsquo;abord <strong>prisonniers<\/strong> du chaos qui a \u00e9t\u00e9 install\u00e9 dans ce pays. Tout cela ne fait que t\u00e9moigner de la fatigue psychologique grandissante des uns et des autres, et notamment des inspirateurs du bloc BAO (sauf Fabius, accordons-lui cela), devant la chose qu&rsquo;ils ont install\u00e9e et qui dure, et qui dure<\/p>\n<\/p>\n<p><p>\t Au reste, n&rsquo;oublions pas l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-les_montagnes_russes_de_la_turquie_20_10_2012.html\" class=\"gen\">initiative<\/a> d&rsquo;Erdogan, un tournant majeur vers la r\u00e9gionalisation de la tentative de r\u00e9solution du conflit, sans la guerre ni les USA, mais avec la Russie et l&rsquo;Iran. Il s&rsquo;agit, nous dit le <a href=\"http:\/\/www.al-monitor.com\/pulse\/politics\/2012\/10\/vision-and-imagination-required-over-syria.html\" class=\"gen\">22 octobre 2012<\/a> le chroniqueur Semih Idiz, de <em>Milliyet<\/em>, d&rsquo;une nouvelle vision (d&rsquo;Erdogan) Comme on le lit avec ces quelques remarques, il semble bien que cette affaire qui \u00e9volue en parall\u00e8le avec d&rsquo;autres affaires qu&rsquo;elle contribue sans la moindre vergogne \u00e0 contredire, porte encore sur des probl\u00e8mes psychologiques r\u00e9currents (l&rsquo;allergie dont parle Idiz \u00e0 propos de la Turquie \u00e9tant manifestement d&rsquo;ordre psychologique).<\/p>\n<\/p>\n<p><p>\t\u00ab<em>In short, Moscow&rsquo;s blocking of United Nations moves and Iran&rsquo;s attitude that affected Turkey&rsquo;s expectations in the region pushed Ankara into a corner and forced it to change its inflexible policy on Syria.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The triple negotiation system Erdogan spoke of after his meeting with Ahmadinejad is an important signal. The triple negotiation system will bring together Turkey, Egypt and Iran; Turkey, Russia and Iran; and Turkey, Egypt and Saudi Arabia to work separately toward a solution in Syria. As one can see from Erdogan&rsquo;s statement, the initiative aims to overcome the obstacle of Saudi unwillingness to the sit at the same table with Iran. Turkey seems to have cured itself of the allergy of discussing Syria with Russia and Iran.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t  D&rsquo;ailleurs et d&rsquo;Ankara, parall\u00e8lement encore, nous apprenons qu&rsquo;Isra\u00ebl, conquis par ce qui \u00e9tait jug\u00e9 comme un tournant pro-BAO d&rsquo;Erdogan et sans doute convaincu que la Turquie \u00e9tait (re)devenue une marionnette de Washington, en avait profit\u00e9 pour tendre la main \u00e0 cette m\u00eame Turquie et lui proposer d&rsquo;enterrer, sinon la hache de guerre, au moins le contentieux qui brouille les relations des deux pays depuis 2009. Cela semblait logique : les marionnettes de mes marionnettes sont mes marionnettes, se disent les finauds strat\u00e8ges isra\u00e9liens Patatras ! Les marionnettes n&rsquo;\u00e9tant plus ce qu&rsquo;elles \u00e9taient, un Erdogan une fois de plus furieux a fait dire \u00e0 Isra\u00ebl qu&rsquo;Isra\u00ebl n&rsquo;avait rien compris \u00e0 la situation. Inutile d&rsquo;esp\u00e9rer qu&rsquo;on parle, m\u00eame sur la Syrie, tant qu&rsquo;Isra\u00ebl n&rsquo;est pas venu faire un tour \u00e0 Canossa pour demander humblement qu&rsquo;on lui pardonne ses \u00e9pouvantables interventions contre les flottilles de la paix de la fin du printemps 2010, qui avaient pouss\u00e9 Erdogan \u00e0 envisager de <a href=\"http:\/\/www.dedefensa.org\/article-demonstration_de_l_absurde_par_l_absurde_07_06_2010.html\" class=\"gen\">prendre lui-m\u00eame<\/a> le commandement d&rsquo;une de ces flottilles Voici comment <em>Zaman<\/em> rapporte, le <a href=\"http:\/\/www.todayszaman.com\/news-296024-.html\" class=\"gen\">22 octobre 2012<\/a>, la tentative de r\u00e9conciliation isra\u00e9lienne et la fin de non-recevoir, indirecte mais cat\u00e9gorique, d&rsquo;un Erdogan \u00e9videmment furieux et fulminant <\/p>\n<\/p>\n<p><p>\t\u00ab<em>The call for dialogue came from Pinhas Avivi, former Israeli ambassador to Turkey, who currently serves as the political director of the Israeli Foreign Ministry. Speaking to a group of Turkish journalists on Monday, Avivi said Israel seeks to hold talks with Turkey regarding the Syrian crisis, noting that the situation in Syria will have an impact on the future of Turkey as well as Israel. We should leave aside the problems between Israel and Turkey and look to the future, he was quoted as saying by NTV television.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>In Ankara, however, Foreign Ministry spokesman Sel\u00e7uk Unal said Israel should speak through deeds rather than messages conveyed through the media.<\/em> [] <em>Ankara demands an official apology and compensation for the families of the victims, as well as the lifting of the Israeli blockade on Gaza, for relations to normalize. Israel has rejected these demands, claiming its soldiers acted in self-defense. In protest of the Israeli refusal to meet Turkish demands, Ankara expelled Israel&rsquo;s ambassador and cut military ties with the country. Unal said Turkey&rsquo;s conditions for the normalization of ties remain in place. There is no change in Turkey&rsquo;s position. Israeli officials should take the steps expected<\/em> [<em>of them<\/em>]<em>, instead of sending messages through statements to the media, he said.<\/em>\u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 25 octobre 2012 \u00e0 06H51<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Syrie, USA, la guerre et l&rsquo;humeur furieuse d&rsquo;Erdogan Il ne manque pas d&rsquo;hypoth\u00e8ses, de supputations, de descriptions m\u00eame sur la marche vers la guerre, notamment de la Turquie vers (contre) la Syrie. C&rsquo;est un sujet r\u00e9current et un th\u00e8me d&rsquo;article redondant depuis plusieurs mois, entrecoup\u00e9s d&rsquo;incidents de fronti\u00e8re, de saisies d&rsquo;avions en plein vol, de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2927,3737,2995,15174,2730,3867,2613],"class_list":["post-73466","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-colere","tag-erdogan","tag-maniaco-depression","tag-regionalisation","tag-russie","tag-syrie","tag-turquie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73466"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73466\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}