{"id":73487,"date":"2012-11-08T06:26:50","date_gmt":"2012-11-08T06:26:50","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/11\/08\/sierra-en-floride\/"},"modified":"2012-11-08T06:26:50","modified_gmt":"2012-11-08T06:26:50","slug":"sierra-en-floride","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/11\/08\/sierra-en-floride\/","title":{"rendered":"<em>Sierra<\/em> en Floride"},"content":{"rendered":"<p><h3 class=\"titrebloc\"><em>Sierra<\/em> en Floride<\/h3>\n<\/p>\n<p><p>\tLes informations qu&rsquo;avait diffus\u00e9es la publication en ligne Washington <em>Free Bacon<\/em> en ao\u00fbt dernier, sous la plume de Bill Gantz, sur l&rsquo;incursion d&rsquo;un sous-marin russe de type <em>Akula<\/em> dans le Golfe du Mexique, devraient bien \u00eatre per\u00e7ues d\u00e9sormais comme tr\u00e8s largement cr\u00e9dibles, avec la pr\u00e9sence de deux navires de guerre russes, dont un sous-marins de classe <em>Sierra<\/em>, au large de la c\u00f4te de Floride, durant l&rsquo;ouragan <em>Frankenstorm<\/em>, plus g\u00e9n\u00e9ralement et officiellement nomm\u00e9 <em>Sandy<\/em>. (Pour l&rsquo;\u00e9quip\u00e9e de l&rsquo;<em>Akula<\/em>, voir notamment le <a href=\"http:\/\/www.dedefensa.org\/article-les_embard_es_d_un_sous-marin_akula_dans_le_golfe_17_08_2012.html\" class=\"gen\">17 ao\u00fbt 2012<\/a> et le <a href=\"http:\/\/www.dedefensa.org\/article-akula_en_balade_l_embarras_grandit__22_08_2012.html\" class=\"gen\">22 ao\u00fbt 2010<\/a>, sur ce site.)<\/p>\n<\/p>\n<p><p>\tBill Gantz d\u00e9taille le cas des deux navires russes le <a href=\"http:\/\/freebeacon.com\/russian-subs-skirt-coast\/\" class=\"gen\">5 novembre 2012<\/a>, \u00e9galement sur le site du Washington <em>Free Bacon<\/em>. On voit que les affirmations de Gantz sont cette fois largement appuy\u00e9es sur des d\u00e9clarations d&rsquo;officiels du Pentagone, avec des pr\u00e9cisions sur l&rsquo;abri fourni \u00e0 l&rsquo;une des deux unit\u00e9s, un navire de surveillance \u00e9lectronique, dans un port de Floride, durant l&rsquo;ouragan.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>One defense official said the submarine was believed to have been conducting anti-submarine warfare efforts against U.S. ballistic and cruise missile submarines based at Kings Bay, Georgia. A second official said the submarine did not sail close to Kings Bay and also did not threaten a U.S. aircraft carrier strike group that was conducting exercises in the eastern Atlantic.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Meanwhile, the officials also said that a Russian electronic intelligence-gathering vessel was granted safe harbor in the commercial port of Jacksonville, Fla., within listening range of Kings Bay. The Russian AGI ship, or Auxiliary-General Intelligence, was allowed to stay in the port to avoid the superstorm that battered the U.S. East Coast last week. A Jacksonville Port Authority spokeswoman had no immediate comment on the Russian AGI at the port.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>A Russian AGI and an SSN in the same geographic area as one of the largest U.S. ballistic missile submarine basesKings Bayis reminiscent of Cold War activities of the Soviet navy tracking the movements of our SSBN&rsquo;s, said a third U.S. official, referring to the designation for ballistic missile submarines, SSBN. While I can&rsquo;t talk about how we detected it, I can tell you that things worked the way they were supposed to, the second official said, stating that the Russian submarine poses no threat whatsoever<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLa nouvelle est reprise par <em>Russia Today<\/em>, qui avait d\u00e9j\u00e0 suivi avec attention les informations sur l&rsquo;<em>Akula<\/em>, en ao\u00fbt dernier. Le <a href=\"http:\/\/rt.com\/usa\/news\/russian-nuclear-sub-gertz-097\/print\/\" class=\"gen\">6 novembre 2012<\/a>, un article de RT reprend les informations de Gantz. (RT semble faire une confusion entre la pr\u00e9sence des deux navires, telle que la rapporte Gantz, et une version selon laquelle le <em>Sierra<\/em> aurait \u00e9t\u00e9 reconverti en navire AGI, et aurait trouv\u00e9 lui-m\u00eame, et lui seulement par cons\u00e9quent, un abri dans un port da la c\u00f4te de Floride. (\u00ab<em>Defense officials say that a nuclear-powered Russian attack submarine sailed to within 200 miles of the United States last week and was granted safe harbor as Superstorm Sandy struck the East Coast.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tLes faits eux-m\u00eames, de m\u00eame que les unit\u00e9s engag\u00e9es telles qu&rsquo;elles sont d\u00e9crites, ne nous semblent en aucune fa\u00e7on pr\u00e9senter un caract\u00e8re strat\u00e9gique fondamental, ni m\u00eame fondamentalement nouveau dans l&rsquo;arrangement g\u00e9n\u00e9ral th\u00e9orique du d\u00e9ploiement des forces. Par cons\u00e9quent, les dispositions strat\u00e9giques prises par les Russes, qui sont illustr\u00e9es par les incidents ainsi d\u00e9crits, ne sont pas elles-m\u00eames d&rsquo;un caract\u00e8re strat\u00e9gique fondamental. C&rsquo;est dans un autre champ, qui est celui du syst\u00e8me de la communication, qu&rsquo;il faut chercher l&rsquo;importance de ces \u00e9v\u00e8nements et leur impact strat\u00e9gique rendu plus imp\u00e9ratif par la divulgation publique de la chose,  bien que cette divulgation soit extr\u00eamement mod\u00e9r\u00e9e, justement du point de vue de la communication,  mais elle existe d\u00e9sormais, d&rsquo;autant qu&rsquo;elle est r\u00e9percut\u00e9e internationalement par RT, et c&rsquo;est l\u00e0 ce qui compte. (On observera une fois de plus combien, \u00e0 cet \u00e9gard, le domaine strat\u00e9gique, et la g\u00e9ostrat\u00e9gie par cons\u00e9quent, sont d\u00e9pendants de la perception que v\u00e9hicule le syst\u00e8me de la communication, donc du domaine de la communication.)<\/p>\n<\/p>\n<p><p>\tLes incidents d\u00e9crits ici rendent publique l&rsquo;existence,  ou plut\u00f4t la r\u00e9surgence, ce qui est plus juste et plus significatif,  d&rsquo;une strat\u00e9gie d&rsquo;affirmation de puissance de la Russie directement destin\u00e9e aux USA. Le sous-marin type <em>Sierra<\/em>, quelle que soit la puissance qu&rsquo;il repr\u00e9sente, \u00e9tait \u00e0 200 miles des c\u00f4tes US, et dans la zone d&rsquo;une manuvre importante de la Flotte (US) de l&rsquo;Atlantique. C&rsquo;est une confirmation <em>in vivo<\/em>, apr\u00e8s l&rsquo;incident de l&rsquo;<em>Akula<\/em>, de la strat\u00e9gie russe pour ler temps pr\u00e9sent. C&rsquo;est un dispositif de guerre froide qui n&rsquo;a aucune sp\u00e9cificit\u00e9 politique particuli\u00e8re ; ce n&rsquo;est pas une r\u00e9surgence de la guerre froide mais simplement l&rsquo;\u00e9vidence que la posture de puissance de la Russie face aux USA qui n&rsquo;ont cess\u00e9 d&rsquo;affirmer leur propre posture strat\u00e9gique agressive rejoint la posture sovi\u00e9tique de la guerre froide selon le constat qu&rsquo;aucun autre d\u00e9ploiement strat\u00e9gique n&rsquo;est possible \u00e0 cet \u00e9gard que celui d&rsquo;une pr\u00e9sence strat\u00e9gique rapproch\u00e9e de la masse continentale US. L&rsquo;important \u00e0 cet \u00e9gard est de voir les causes de cette r\u00e9surgence qui n&rsquo;est que d&rsquo;ordre technique : ces causes sont, elles, politiques, et elles tiennent sans le moindre doute \u00e0 la dynamique agressive et belliciste des USA alimentant une r\u00e9action strat\u00e9gique russe.<\/p>\n<\/p>\n<p><p>\tLes r\u00e9actions officielles du Pentagone, puisqu&rsquo;il y en a cette fois, sont de chercher \u00e0 compl\u00e8tement d\u00e9dramatiser l&rsquo;affaire en la  pr\u00e9sentant comme une circonstance de routine. Cela fait partie de la politique du Pentagone, qui est d&rsquo;\u00e9carter toute dramatisation des situations strat\u00e9giques, <strong>particuli\u00e8rement<\/strong> avec la Russie. Cela n&#8217;emp\u00eache pas les faits d&rsquo;exister, et ces faits de devenir une nouvelle (une confirmation) strat\u00e9gique importante sur l&rsquo;\u00e9volution des relations strat\u00e9giques entre les USA et la Russie, du point de vue russe. Les \u00e9v\u00e9nements de communication qui ont eu lieu ne permettent plus de dissimuler ce facteur nouveau des relations internationales. Ce facteur est moins une volont\u00e9 d&rsquo;affirmation de puissance de la Russie que la concr\u00e9tisation de la pr\u00e9occupation russe de la politique belliciste et agressive des USA, activ\u00e9e et poursuivie par sa direction politique.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 8 novembre 2012 \u00e0 06H26<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sierra en Floride Les informations qu&rsquo;avait diffus\u00e9es la publication en ligne Washington Free Bacon en ao\u00fbt dernier, sous la plume de Bill Gantz, sur l&rsquo;incursion d&rsquo;un sous-marin russe de type Akula dans le Golfe du Mexique, devraient bien \u00eatre per\u00e7ues d\u00e9sormais comme tr\u00e8s largement cr\u00e9dibles, avec la pr\u00e9sence de deux navires de guerre russes, dont&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[15026,15197,6336,15024,3106,14610,2645,13371,2730,3468,3068,3248],"class_list":["post-73487","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-akula","tag-bacon","tag-deploiement","tag-free","tag-froide","tag-gantz","tag-guerre","tag-ouragan","tag-russie","tag-sous-marin","tag-strategique","tag-washington"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73487"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73487\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}