{"id":73508,"date":"2012-11-19T14:44:42","date_gmt":"2012-11-19T14:44:42","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/11\/19\/ron-paul-77-ans-a-la-retraite-le-temps-de-laction-est-arrive\/"},"modified":"2012-11-19T14:44:42","modified_gmt":"2012-11-19T14:44:42","slug":"ron-paul-77-ans-a-la-retraite-le-temps-de-laction-est-arrive","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/11\/19\/ron-paul-77-ans-a-la-retraite-le-temps-de-laction-est-arrive\/","title":{"rendered":"Ron Paul (77 ans) \u00e0 la retraite : le temps de l&rsquo;action est arriv\u00e9"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Ron Paul (77 ans) \u00e0 la retraite : le temps de l&rsquo;action est arriv\u00e9<\/h3>\n<\/p>\n<p><p>\tQu&rsquo;est devenu Ron Paul ? Il vient de donner son discours d&rsquo;adieu \u00e0 la Chambre des Repr\u00e9sentants, au terme de son dernier mandat (il n&rsquo;\u00e9tait pas candidat \u00e0 la r\u00e9\u00e9lection),  voir le <a href=\"http:\/\/www.infowars.com\/ron-pauls-farewell-to-congress-speech-transcript\/\" class=\"gen\">texte<\/a> et la <a href=\"http:\/\/www.youtube.com\/watch?v=Zqi6paX3ong&#038;list=FLJuZoNoE-DBhAFztGqK_X6Q&#038;feature=plcp\" class=\"gen\">vid\u00e9o<\/a> du m\u00eame discours du 15 novembre 2012. L&rsquo;honorable parlementaire est entr\u00e9 dans sa 77\u00e8me ann\u00e9es en ao\u00fbt dernier et l&rsquo;on penserait que le voil\u00e0 parti pour une retraite apais\u00e9e. Il semble que ce n&rsquo;est <strong>pas du tout<\/strong> le cas, puisque d&rsquo;autres r\u00e9torqueront, apr\u00e8s tout, que 77 ans c&rsquo;est le bon \u00e2ge de la maturit\u00e9.<\/p>\n<\/p>\n<p><p>\tLe site <em>DailyPaul.com<\/em> signalait, le <a href=\"http:\/\/www.dailypaul.com\/263422\/lew-rockwell-ron-pauls-secret-plans-for-continued-leadership-for-the-liberty-movement\" class=\"gen\">17 novembre 2012<\/a> une intervention de Lew Rockwell, lors du Alex Jones show (voir un DVD, le <a href=\"http:\/\/youtu.be\/cwMklPa8w_M\" class=\"gen\">17 novembre 2012<\/a>). <em>Leader<\/em> des libertariens US et tr\u00e8s proche ami de Ron Paul, Rockwell annonce, au d\u00e9but de son intervention, que Ron Paul a des plans ambitieux pour le <em>Liberty Party<\/em> (le nom officieux du parti, ou plut\u00f4t du regroupement des partisans de Ron Paul). Voici le texte annon\u00e7ant cette intervention de Rockwell :  <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Via the Liberty Crier: Lew Rockwell appears on the Alex Jones show and discusses what&rsquo;s next for the liberty movements fight against statism. At the beginning of the interview Lew tells us that Ron Paul has big plans for the liberty movement but cannot reveal them until he is out of congress. Lew says that Ron Paul will be more powerful now that he is out of politics.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl faut aussi signaler que, lors d&rsquo;une intervention qu&rsquo;il fit, sur son site et \u00e0 sa radio, \u00e0 propos de l&rsquo;actuel mouvement de p\u00e9titions en faveur de la s\u00e9cession (voir le <a href=\"http:\/\/www.dedefensa.org\/article-aux_armes_et_s_cession_pour_tous__16_11_2012.html\" class=\"gen\">16 novembre 2012<\/a>), Alex Jones fit la suggestion que ce mouvement pourrait \u00eatre f\u00e9d\u00e9r\u00e9 sous l&rsquo;impulsion et l&rsquo;inspiration de Ron Paul. Il y a l&rsquo;id\u00e9e, exprim\u00e9e par Jones \u00e0 la lumi\u00e8re de l&rsquo;actuel mouvement s\u00e9cessionniste, selon laquelle il faut demander et obtenir la s\u00e9cession des \u00c9tats du gouvernement f\u00e9d\u00e9ral, pour que ces \u00c9tats de l&rsquo;Union devenus ind\u00e9pendants se f\u00e9d\u00e8rent \u00e0 nouveau, ou plut\u00f4t se conf\u00e9d\u00e8rent, selon les principes des P\u00e8res Fondateurs trahis par l&rsquo;actuel Syst\u00e8me. Cette id\u00e9e exprimerait le sentiment de Ron Paul et ce qui pourrait devenir un axe fondamental de son action politique.<\/p>\n<\/p>\n<p><p>\tSon action politique ? Le parcours sensationnel de Ron Paul en 2011 et dans les 5-6 premiers mois de 2012 s&rsquo;est achev\u00e9 dans le myst\u00e8re, l&rsquo;ambigu\u00eft\u00e9 et le soup\u00e7on. Au moins deux choses apparaissent probables jusqu&rsquo;\u00e0 devoir \u00eatre envisag\u00e9es avec presque de la certitude, compar\u00e9es aux analyses que nous donnent la presse-Syst\u00e8me et le Syst\u00e8me \u00e0 cet \u00e9gard :<\/p>\n<\/p>\n<p><p>\t L&rsquo;\u00e9tat-major de campagne de Ron Paul \u00e9tait inflitr\u00e9 par des personnalit\u00e9s proches du parti r\u00e9publicain classique ou des n\u00e9o-conservateurs. L&rsquo;argument avait \u00e9t\u00e9 largement document\u00e9 par Justin Raimondo, le <a href=\"http:\/\/original.antiwar.com\/justin\/2012\/02\/02\/can-ron-paul-be-tamed\/\" class=\"gen\">2 f\u00e9vrier 2012<\/a>, sur <em>Antiwar.com<\/em>.<\/p>\n<\/p>\n<p><p>\t Ron Paul a \u00e9t\u00e9 l&rsquo;objet de pressions pour ne pas tenter d&rsquo;imposer sa candidature, comme il aurait pu le faire si l&rsquo;on tient compte de son extr\u00eame popularit\u00e9. (Si Ron Paul avait \u00e9t\u00e9 seul oppos\u00e9 \u00e0 Obama, sa victoire \u00e9tait certainement une tr\u00e8s forte probabilit\u00e9.) Ces pressions auraient pu comporter des menaces physiques, et cela a \u00e9t\u00e9 le cas sans gu\u00e8re de doute \u00e0 notre avis, sans doute contre des membres de sa famille (sa femme).<\/p>\n<\/p>\n<p><p>\tIl est tr\u00e8s caract\u00e9ristique que Rockwell indique la possibilit\u00e9 d&rsquo;une nouvelle carri\u00e8re de Ron Paul (\u00e0 77 ans !) apr\u00e8s qu&rsquo;il ait quitt\u00e9 ses fonctions \u00e0 la Chambre, ce qui implique que ces fonctions sont v\u00e9cues par Ron Paul, dans tous les cas pour cette derni\u00e8re p\u00e9riode qui comprend sa campagne \u00e9lectorale, comme une entrave, voire pire. Il y a l\u00e0 l&rsquo;implication hypoth\u00e9tique qui fait penser que le cadre officiel du Syst\u00e8me est (\u00e9tait) devenu pour Ron Paul un pi\u00e8ge o\u00f9 il ne pouvait plus \u00e9voluer \u00e0 sa guise. Cette appr\u00e9ciation a du sens et rencontre les remarques qui nous sont venues concernant la campagne du candidat r\u00e9publicain-libertarien.<\/p>\n<\/p>\n<p><p>\tQu&rsquo;esp\u00e8re Ron Paul, que va nous annoncer Rockwell ? (On peut supposer que, s&rsquo;il dit ce qu&rsquo;il dit, il y a effectivement quelque chose de s\u00e9rieux qui se pr\u00e9pare.) Il est \u00e9vident que le mouvement <a href=\"http:\/\/www.dedefensa.org\/article-aux_armes_et_s_cession_pour_tous__16_11_2012.html\" class=\"gen\">s\u00e9cessionniste<\/a> va dans le sens d&rsquo;une initiative de Ron Paul. Il est \u00e9vident que cette initiative doit \u00eatre rapide, parce que la situation \u00e9volue tr\u00e8s vite, et alors l&rsquo;\u00e2ge de Ron Paul devient un \u00e9l\u00e9ment moins fondamental : ce qui doit \u00eatre tr\u00e8s rapide implique Ron Paul tel qu&rsquo;il est aujourd&rsquo;hui,  et il va tr\u00e8s bien, merci.<\/p>\n<\/p>\n<p><p>\tDans tous les cas et d&rsquo;une fa\u00e7on plus g\u00e9n\u00e9rale, cette agitation, du c\u00f4t\u00e9 d&rsquo;un homme qu&rsquo;on pensait \u00eatre finalement au bout de sa carri\u00e8re, indique que la situation politique aux USA est singuli\u00e8rement ouverte, qu&rsquo;elle est d\u00e9structur\u00e9e du point de vue du Syst\u00e8me. Nous entendons par l\u00e0 signifier que cette nouveaut\u00e9 indiquerait aussi bien qu&rsquo;il existe des appr\u00e9ciations, voire des projets, dont certaines forces politiques pourraient croire qu&rsquo;on peut les faire \u00e9voluer hors du cadre-Syst\u00e8me. Le climat g\u00e9n\u00e9ral ne leur donne certes pas tort.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 19 novembre 2012 \u00e0 14H44<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ron Paul (77 ans) \u00e0 la retraite : le temps de l&rsquo;action est arriv\u00e9 Qu&rsquo;est devenu Ron Paul ? Il vient de donner son discours d&rsquo;adieu \u00e0 la Chambre des Repr\u00e9sentants, au terme de son dernier mandat (il n&rsquo;\u00e9tait pas candidat \u00e0 la r\u00e9\u00e9lection), voir le texte et la vid\u00e9o du m\u00eame discours du 15&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[9671,583,7856,9607,3140,4337,9608,3310,2949],"class_list":["post-73508","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-alex","tag-jones","tag-justin","tag-lew","tag-paul","tag-raimondo","tag-rockwell","tag-ron","tag-secession"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73508"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73508\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}