{"id":73521,"date":"2012-11-25T09:34:38","date_gmt":"2012-11-25T09:34:38","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/11\/25\/resilience-dune-chronique\/"},"modified":"2012-11-25T09:34:38","modified_gmt":"2012-11-25T09:34:38","slug":"resilience-dune-chronique","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/11\/25\/resilience-dune-chronique\/","title":{"rendered":"R\u00e9silience d&rsquo;une chronique"},"content":{"rendered":"<p><h3 class=\"titrebloc\">R\u00e9silience d&rsquo;une chronique<\/h3>\n<\/p>\n<p><p>\tD\u00e9cid\u00e9ment, c&rsquo;est rat\u00e9 Nous avions jug\u00e9 habile, il y a quelques mois (voir le <a href=\"http:\/\/www.dedefensa.org\/article-chronique_du_19_courant_pr_sentation_19_07_2012.html\" class=\"gen\">19 juillet 2012<\/a>) d&rsquo;\u00e9tablir la <em>Chronique du 19 courant&#8230;<\/em>, pour rappeler chaque mois, par ce biais d&rsquo;une chronique que nous esp\u00e9rions de quelque int\u00e9r\u00eat pour le lecteur, la situation de la donation mensuelle \u00e0 cette date devenue embl\u00e9matique pour nous. La chronique a pris sa place mais le rappel s&rsquo;est peu \u00e0 peu dissous, pour dispara\u00eetre, comme on le constate dans le texte du <a href=\"http:\/\/www.dedefensa.org\/article-chronique_du_19_courant_r_silience_de_verdun_19_11_2012.html\" class=\"gen\">19 novembre 2012<\/a>. R\u00e9silience pour r\u00e9silience, comme <a href=\"http:\/\/www.dedefensa.org\/article-r_silience_pour_r_silience_09_11_2012.html\" class=\"gen\">dirait<\/a> <em>dedefensa.org<\/em>, celle de la chronique a tenu, pas celle du rappel. Nous sommes mauvais vendeurs.<\/p>\n<\/p>\n<p><p>\tLes \u00e9v\u00e9nements, eux, montrent \u00e9galement leur r\u00e9silience. Nous parlons ici des caract\u00e8res si extraordinaires qui les distinguent, de leur puissance, de leur rythme, de leur pression, pour faire d\u00e9filer cette crise ultime sans jamais la voir c\u00e9der, au contraire en la faisant grandir sans cesse. Nous en savons quelque chose, parce que nous sommes chaque jour press\u00e9s par eux, les \u00e9v\u00e9nements, de fa\u00e7on diff\u00e9rente, de fa\u00e7on inattendue, de fa\u00e7on,  comment dirait-on ? R\u00e9siliente ? Le chroniqueur, qui est aussi observateur, vigie, analyste de l&rsquo;instant qu&rsquo;il voudrait aussit\u00f4t interpr\u00e9ter \u00e0 la lumi\u00e8re de la m\u00e9taHistoire, ce chroniqueur n&rsquo;a pas un instant \u00e0 lui ni toute sa t\u00eate. Il en oublie de rappeler les n\u00e9cessit\u00e9s du mois (donation, etc.), et de signaler \u00e0 ses lecteurs que les n\u00e9cessit\u00e9s des \u00e9v\u00e9nements qui p\u00e8sent sur lui de toutes leurs forces lui font souvent oublier de rappeler la n\u00e9cessit\u00e9 de soutenir le site. Nous sommes mauvais batteurs d&rsquo;estrade.<\/p>\n<\/p>\n<p><p>\tEt puis un instant, o\u00f9 l&rsquo;accumulation des \u00e9v\u00e9nements et les exigences de la t\u00e2che atteignent pour un court laps de temps une sorte de zone qu&rsquo;on dirait presque paralys\u00e9e. Comme dit la chanson, l&rsquo;esprit chancelle, la psychologie s&rsquo;affaiblit, les forces semblent se retirer comme la mar\u00e9e descend C&rsquo;est dans cet instant-l\u00e0 que nous nous rappelons, d&rsquo;une fa\u00e7on bien accidentelle en un sens, que nous avons besoin du soutien de nos lecteurs, un besoin psychologique et un besoin de l&rsquo;\u00e2me, et que ce soutien passe aussi par une fa\u00e7on de nous conforter, et que tout cela s&rsquo;exprime notamment par les donations, de la fa\u00e7on la plus triviale du monde. Cela nous d\u00e9sesp\u00e8re de m\u00e9langer toutes ces choses si diff\u00e9rentes et dont nous sommes les premiers \u00e0 reconna\u00eetre l&rsquo;incompatibilit\u00e9 qualitative, voire \u00e0 la d\u00e9noncer. Mais il nous faut tenir et il faut que nos lecteurs nous aident \u00e0 tenir. <\/p>\n<\/p>\n<p><p>\tLes \u00e9v\u00e9nements s&rsquo;accumulent et se pressent d&rsquo;une fa\u00e7on extraordinaire. Plus que jamais, la plus grande bataille se livre au niveau du syst\u00e8me de la communication, vous le savez bien. (*) Vous savez bien, \u00e9galement, qu&rsquo;il y a aujourd&rsquo;hui des forces concurrentes qui s&rsquo;affrontent, et que, face \u00e0 la force d&rsquo;anesth\u00e9sie de la presse-Syst\u00e8me et \u00e0 la puissance aveugle de la politique-Syst\u00e8me,  nous sommes, nous autres dans les r\u00e9seaux alternatifs, la seule force antagoniste qui tiennent et proclament notre et votre volont\u00e9 de conserver libert\u00e9 et ind\u00e9pendance,  la votre et la notre. Vous savez parfaitement que, dans cette bataille, nous avons n\u00e9cessairement besoin de votre soutien.<\/p>\n<\/p>\n<p><p>\t Voyez la barre de comptage. A cinq jours de la fin du mois, nous sommes loin de notre minimum vital (2.000), sans parler de notre moyenne confortable (3.000) pour vivre, fonctionner, faire notre travail. Intervenez au plus vite, soutenez-vous, nous avons besoin de vous.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 25 novembre 2012 \u00e0 09H17<\/p>\n<\/p>\n<p><p>\t(*) Ce message devait \u00eatre mis en ligne \u00e0 04H00 ce matin. Il ne l&rsquo;a pas \u00e9t\u00e9 parce que le site \u00e9tait inaccessible, et l&rsquo;est rest\u00e9 jusque pass\u00e9 09H00 ce matin. Les conditions inhabituelles de cette interruption (sans rapport avec une panne technique courante) font penser \u00e0 une attaque contre <em>dedefensa.org<\/em>. Concluez vous-m\u00eames quant \u00e0 la n\u00e9cessit\u00e9 de votre soutien.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9silience d&rsquo;une chronique D\u00e9cid\u00e9ment, c&rsquo;est rat\u00e9 Nous avions jug\u00e9 habile, il y a quelques mois (voir le 19 juillet 2012) d&rsquo;\u00e9tablir la Chronique du 19 courant&#8230;, pour rappeler chaque mois, par ce biais d&rsquo;une chronique que nous esp\u00e9rions de quelque int\u00e9r\u00eat pour le lecteur, la situation de la donation mensuelle \u00e0 cette date devenue embl\u00e9matique&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[16],"tags":[11598,12981,11007,2981,4854,11979],"class_list":["post-73521","post","type-post","status-publish","format-standard","hentry","category-notre-situation","tag-11598","tag-chronique","tag-courant","tag-dedefensa-org","tag-donation","tag-resilience"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73521"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73521\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}