{"id":73571,"date":"2013-11-29T13:05:00","date_gmt":"2013-11-29T13:05:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/11\/29\/erdogan-locs-et-le-monde-antipolaire\/"},"modified":"2013-11-29T13:05:00","modified_gmt":"2013-11-29T13:05:00","slug":"erdogan-locs-et-le-monde-antipolaire","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/11\/29\/erdogan-locs-et-le-monde-antipolaire\/","title":{"rendered":"Erdogan, l&rsquo;OCS et le monde antipolaire"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Erdogan, l&rsquo;OCS et le monde antipolaire<\/h3>\n<\/p>\n<p><p>\tEn visite en Russie (on s&rsquo;y bouscule actuellement), le Premier ministre turc Erdogan a de nouveau affirm\u00e9 que son pays \u00e9tait candidat pour devenir membre de l&rsquo;Organisation de Coop\u00e9ration de Shanghai. On a d\u00e9j\u00e0 parl\u00e9 de ce projet d&rsquo;Erdogan, qui a d&rsquo;abord \u00e9t\u00e9 pris pour une plaisanterie, puis peu \u00e0 peu consid\u00e9r\u00e9 avec un certain s\u00e9rieux (voir successivement le <a href=\"http:\/\/www.dedefensa.org\/article-erdogan_veut_faire_entrer_la_turquie_dans_l_ocs_30_07_2012.html\" class=\"gen\">30 juiller 2012<\/a>, le <a href=\"http:\/\/www.dedefensa.org\/article-la_turquie_et_l_ocs_sans_plaisanter__02_02_2013.html\" class=\"gen\">2 f\u00e9vrier 2013<\/a>, le <a href=\"http:\/\/www.dedefensa.org\/article-signature_la_turquie_a_un_pied_dans_l_ocs_02_05_2013.html\" class=\"gen\">2 mai 2013<\/a>). Novosti donnait, le <a href=\"http:\/\/fr.ria.ru\/world\/20131122\/199849101.html\" class=\"gen\">22 novembre 2013<\/a>, un sobre compte-rendu de cette question, abord\u00e9e lors d&rsquo;une conf\u00e9rence de presse conjointe Poutine-Erdogan.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>La Turquie souhaite adh\u00e9rer \u00e0 l&rsquo;Organisation de coop\u00e9ration de Shanghai (OSC), a d\u00e9clar\u00e9 vendredi \u00e0 Saint-P\u00e9tersbourg le premier ministre turc Recep Tayyip Erdogan, en visite en Russie. Quant<\/em> [\u00e0 l&rsquo;adh\u00e9sion] <em>\u00e0 l&rsquo;Organisation de coop\u00e9ration de Shanghai, j&rsquo;en ai d\u00e9j\u00e0 parl\u00e9 auparavant au cours de n\u00e9gociations avec Monsieur le Pr\u00e9sident<\/em> [Poutine]<em>. Et je r\u00e9p\u00e8te \u00e0 pr\u00e9sent que nous avons une telle intention, a soulign\u00e9 le chef du gouvernement turc.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>M. Poutine a indiqu\u00e9 \u00e0 son tour que le prestige dont la Turquie b\u00e9n\u00e9ficiait sur la sc\u00e8ne internationale et la politique souveraine ind\u00e9pendante pratiqu\u00e9e par Ankara sous la direction de M. Erdogan permettait \u00e0 ce pays de participer de plus en plus activement aux activit\u00e9s des organisations r\u00e9gionales et internationales. Nous y sommes int\u00e9ress\u00e9s, a conclu le chef de l&rsquo;\u00c9tat russe.<\/em>\u00bb <\/p>\n<\/p>\n<p><p>\tBien. La r\u00e9p\u00e9tition de son intention d&rsquo;adh\u00e9rer \u00e0 l&rsquo;OCS finit par conduire \u00e0 une situation o\u00f9 l&rsquo;on doit envisager de prendre Erdogan au s\u00e9rieux sur ce point. (Ainsi en est-il de cette \u00e9trange \u00e9poque o\u00f9 certaines affirmations se heurtent au <em>diktat<\/em> du Syst\u00e8me [la Turquie, membre de l&rsquo;OTAN et phagocyt\u00e9e par cons\u00e9quent dans le bloc BAO, voulant adh\u00e9rer \u00e0 l&rsquo;OCS ?!], et \u00e9ventuellement au caract\u00e8re fantasque de certains [Erdogan en l&rsquo;occurrence], avant de c\u00e9der aux contraintes presque soup\u00e7onn\u00e9es de totalitarisme de l&rsquo;\u00e9vidence qu&rsquo;implique la r\u00e9p\u00e9tition publique \u00e0 trois reprises d&rsquo;un m\u00eame projet.) Cela a \u00e9t\u00e9 le cas cette fois-ci o\u00f9 l&rsquo;on a donc pris Erdogan sur le fait de devoir \u00eatre pris au s\u00e9rieux, certains commentant la chose comme si, effectivement, il s&rsquo;agissait de la premi\u00e8re intervention d&rsquo;Erdogan dans ce sens. Nous avons choisi deux commentaires, l&rsquo;un favorable \u00e0 la d\u00e9marche d&rsquo;Erdogan, l&rsquo;autre d\u00e9favorable,  les deux additionn\u00e9s nous disant par cons\u00e9quent que la d\u00e9marche est s\u00e9rieuse puisqu&rsquo;on entre dans les eaux agit\u00e9es de la pol\u00e9mique.<\/p>\n<\/p>\n<p><p>\t Le commentateur franco-russe Alexandre Latsa, qui r\u00e9side \u00e0 Moscou et commente r\u00e9guli\u00e8rement l&rsquo;actualit\u00e9 sur Novosti, trace le <a href=\"http:\/\/fr.ria.ru\/blogs\/20131127\/199881303.html\" class=\"gen\">27 novembre 2013<\/a> un portait flatteur mais en grande partie justifi\u00e9 de l&rsquo;ann\u00e9e diplomatique de Vladimir Poutine,  ann\u00e9e triomphale s&rsquo;il en est. Il termine un tableau particuli\u00e8rement \u00e9difiant des performances diplomatiques de la Russie en 2013, par un paragraphe signalant l&rsquo;intention d&rsquo;adh\u00e9sion d&rsquo;Erdogan (de la Turquie) \u00e0 l&rsquo;OCS, qu&rsquo;il place dans un cadre plus large d&rsquo;un rapprochement \u00e9vident de la Turquie avec la Russie,  notamment avec cette nouvelle que la Turquie est int\u00e9ress\u00e9e \u00e9galement par une participation \u00e0 l&rsquo;Union Douani\u00e8re d\u00e9velopp\u00e9e par la Russie pour les anciennes r\u00e9publiques de l&rsquo;URSS devenues ind\u00e9pendantes et quelques autres voisins imm\u00e9diats. (Signalons que cette perspective avait \u00e9t\u00e9 pr\u00e9sent\u00e9e par certains comme une autre plaisanterie possible de la Turquie d&rsquo;Erdogan, mais l\u00e0 aussi peut-\u00eatre pas&#8230;) <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Plus au sud, d&rsquo;\u00e9tranges et inattendus signaux sont venus de Turquie. Le pr\u00e9sident Erdogan, en visite en Russie, a en effet clairement exprim\u00e9 son intention d&rsquo;int\u00e9grer la Turquie \u00e0 l&rsquo;Organisation de Shanghai, souvent qualifi\u00e9e de pendant Eurasiatique de l&rsquo;Otan. Le pr\u00e9sident turc s&rsquo;est \u00e9galement d\u00e9clar\u00e9 int\u00e9ress\u00e9 par une participation de son pays \u00e0 l&rsquo;Union Douani\u00e8re. Dans le m\u00eame temps, Russie et Turquie se sont fix\u00e9 un but: porter leurs \u00e9changes \u00e9conomiques en 2020 \u00e0 un niveau sup\u00e9rieur \u00e0 celui des \u00e9changes Russie-Allemagne actuels, soit 100 milliards de dollars annuels. Pour le moment, la Russie est le deuxi\u00e8me partenaire commercial de la Turquie apr\u00e8s l&rsquo;Allemagne pendant que la Turquie est le deuxi\u00e8me importateur  mondial de gaz naturel russe et que le tron\u00e7on maritime du pipeline South Stream, dont la construction devrait \u00eatre achev\u00e9e en 2015, passera dans la zone \u00e9conomique exclusive de la Turquie&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Le deuxi\u00e8me commentaire vient de Murat Belge, pourtant absolument turc, que <em>Wikip\u00e9dia<\/em> nous pr\u00e9sente  <a href=\"http:\/\/en.wikipedia.org\/wiki\/Murat_Belge\" class=\"gen\">de la sorte<\/a> : \u00ab[A]<em>n outspoken left-liberal Turkish intellectual, academic, translator, literary critic, columnist, civil rights activist, and occasional tour guide.<\/em>\u00bb Son commentaire, traduit du turc pour le site <em>Al-Monitor<\/em> le <a href=\"http:\/\/www.al-monitor.com\/pulse\/politics\/2013\/11\/turkey-stuck-between-europe-and-shanghai.html\" class=\"gen\">27 novembre 2013<\/a>, outre d&rsquo;\u00eatre anti-Erdogan et implicitement antirusse comme l&rsquo;on est anti-Poutine dans les salons, est un \u00e9bouriffant plaidoyer pour l&rsquo;Europe\/UE, type-BHL &#038; consorts, qui ne laisse pas de couper le souffle. L&rsquo;impudence et la na\u00efvet\u00e9 du commentaire \u00e0 la fois, passent tout ce que l&rsquo;on peut entendre et lire dans les salons intellectuels des capitales du bloc BAO,  car l&rsquo;on n&rsquo;ose imaginer qu&rsquo;un partisan stipendi\u00e9 de l&rsquo;UE dirait de telles choses, par simple habilet\u00e9 d&rsquo;influence, aussi accordons-nous \u00e0 Belge le b\u00e9n\u00e9fice de la na\u00efvet\u00e9 et, comme moteur de son propos, celui de la croyance dans la vertu globalisante de l&rsquo;UE.<\/p>\n<\/p>\n<p><p>\tPour Belge, l&rsquo;UE rencontre des difficult\u00e9s \u00e9ventuellement catastrophiques simplement parce que ni les nations, ni les citoyens, ni Dieu lui-m\u00eame sans doute, n&rsquo;ont encore compris que cette UE-l\u00e0, avec sa logique des march\u00e9s et sa sollicitude pour les banques, est le mod\u00e8le de gouvernance parfaite du futur. C&rsquo;est dire dans quel m\u00e9pris furieux il tient la d\u00e9marche d&rsquo;Erdogan ; mais c&rsquo;est dire \u00e9galement,  c&rsquo;est la chose qui compte,  combien nous sommes confirm\u00e9s dans le fait de consid\u00e9rer cette d\u00e9marche d&rsquo;Erdogan comme tr\u00e8s s\u00e9rieuse&#8230; Quant \u00e0 l&rsquo;OCS, c&rsquo;est une organisation du temps pass\u00e9e, qui n&rsquo;est m\u00eame pas capable de s&rsquo;ing\u00e9rer dans les affaires int\u00e9rieures de ses membres, ni d&rsquo;organiser d&rsquo;une fa\u00e7on m\u00e9thodiques les catastrophes financi\u00e8re, culturelle, sociales, humaines,  bref, tout ce qu&rsquo;il y a de structurel,  dans les entit\u00e9s repr\u00e9sent\u00e9es. L&rsquo;on comprend enfin que la critique de la d\u00e9marche d&rsquo;Erdogan se fait au nom de nos plus brillants apports \u00e0 l&rsquo;histoire, du droitdel&rsquo;hommisme ou droit d&rsquo;ing\u00e9rence, certes, et avec les r\u00e9f\u00e9rences qu&rsquo;il faut,  Sarkozy lui-m\u00eame, investi par Belge d&rsquo;une immense popularit\u00e9 et d&rsquo;une fondamentale repr\u00e9sentativit\u00e9 du sentiment du peuple fran\u00e7ais, dont on conna\u00eet l&rsquo;ardente adoration pour la <em>global governance<\/em> venue de Bruxelles.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>During his visit to Russia, Prime Minister Recep Tayyip Erdogan reiterated his desire for Turkey to join the Shanghai Cooperation Organization (SCO). The first time he uttered that desire it was largely played down. But its repetition suggests that the matter is serious and that the prime minister is genuinely yearning to join this particular club.<\/em> [&#8230;] <em>Those who came together in Shanghai make an international alliance typical of the old world. Their limited objectives cannot even compare to those of the EU. The SCO is basically a security organization with no goal of democracy. Hence, noninterference in fellow members&rsquo; internal affairs is an essential principle.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>In Turkey, we have been told for years that the EU is interfering in our internal affairs. But this is exactly the very threat that makes the EU the union model of the future. Being the organization of those who aspire to live in a genuine democracy with full respect for human rights, the EU is entitled to say You can&rsquo;t do that! to those who do not act accordingly. It has used this authority to the extent of stopping Austria&rsquo;s fascist party from ascending to power. In this context, Erdogan&rsquo;s reiteration of his desire to be part of the SCO, coupled with a notion to save us from the trouble of Europe, takes on a larger meaning. It tells us which world Erdogan wants to live in.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>As I mentioned above, the EU often falls behind the potential it represents. One area that clearly illustrates this shortcoming is the opposition of some members to Turkey&rsquo;s membership. The Europeans&rsquo; prejudices and other inhibitions are crystallizing here. Yet, the general trend of evolution remains at work on this issue as well.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>But what if former French President Nicolas Sarkozy came up and said, Didn&rsquo;t I tell you? How could a country accede to the European Union when its prime minister keeps pleading to join the Shanghai group? How could we possibly answer this question? Other people may easily express such views, but the person in question is someone with a record level of electoral support and huge popularity. Then, one would assume he has public support on this issue as well. So how could a nation have a place in the EU when it grumbles about the trouble of Europe while feeling no trouble at all in belonging together with Uzbekistan?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Erdogan may take pride in camaraderie with Uzbekistan and Tajikistan, but this is up to him. He is in no way entitled, however, to deviate Turkey from its historical route just to satisfy his personal tastes.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tAvec ces deux commentaires nous voil\u00e0 fix\u00e9s, outre sur le s\u00e9rieux des intentions d&rsquo;Erdogan, sur les appr\u00e9ciations qui vont commencer \u00e0 accompagner sa d\u00e9marche vers l&rsquo;OCS, et, bien entendu, sur la bataille id\u00e9ologique que vont conduire les intellectuels-Syst\u00e8me contre ces d\u00e9marches. Pour autant, cela ne r\u00e9sout pas ce qu&rsquo;il reste de myst\u00e9rieux dans la d\u00e9marche d&rsquo;Erdogan, depuis longtemps ami de la Russie et ami personnel de Poutine, qui s&rsquo;est retrouv\u00e9 ennemi jur\u00e9 de la Russie de Poutine dans l&rsquo;affaire syrienne, pour se retrouver, ami plus que jamais de la Russie et de Poutine lors de sa visite \u00e0 Moscou, et encha\u00eenant avec insistance sur cette affaire d&rsquo;adh\u00e9sion \u00e0 l&rsquo;OCS, en sens contraire du sens de l&rsquo;histoire repr\u00e9sent\u00e9 par l&rsquo;UE et l&rsquo;OTAN aux c\u00f4t\u00e9s desquelles il se trouvait pourtant lors de l&rsquo;affaire syrienne. <\/p>\n<\/p>\n<p><p>\tCertes, on sait combien, d\u00e9sormais, Erdogan est remarquable par sa personnalit\u00e9 fantasque, on l&rsquo;a vu notamment lors de ses diff\u00e9rentes positions avant et pendant la crise syrienne. Pourtant, nous aimerions offrir une autre explication hypoth\u00e9tique sur cette d\u00e9marche d&rsquo;Erdogan, que le seul caract\u00e8re d&rsquo;Erdogan et de ses \u00e9ventuels changements d&rsquo;humeur. Cette explication hypoth\u00e9tique concerne la conception du monde apolaire ou antipolaire (voir le <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_le_d_sordre_apolaire_du_moyen-orient_10_11_2013.html\" class=\"gen\">10 novembre 2013<\/a> et le <a href=\"http:\/\/www.dedefensa.org\/article-apolaire_ou_antipolaire__16_11_2013.html\" class=\"gen\">16 novembre 2013<\/a>), qui implique le refus des h\u00e9g\u00e9monies et des influences intrusives inh\u00e9rentes aux mod\u00e8les unipolaire et multipolaire. Cette situation antipolaire d\u00e9gage en bonne partie des contraintes diverses, y compris des contraintes institutionnelles \u00e9tablies ; elle \u00e9tablit une nouvelle situation, molle, \u00e9lastique et mouvante, par rapport notamment aux contraintes institutionnelles des \u00e8res pr\u00e9c\u00e9dentes, qu&rsquo;on les qualifie d&rsquo;unipolaires ou de multipolaires. Pour cette raison, nous serions conduits \u00e0 consid\u00e9rer d&rsquo;un il diff\u00e9rent ce qui nous paraissait bien improbable il y a dix-huit mois ou un ans,  savoir, qu&rsquo;un pays membre de l&rsquo;OTAN puisse <strong>\u00e9galement<\/strong> poser sa candidature \u00e0 l&rsquo;OCS. (Bien entendu, l&rsquo;OTAN ne l&rsquo;entendra certainement pas de cette oreille si la candidature de la Turquie devient officielle et formelle, et nous aurons  alors droit \u00e0 des joutes int\u00e9ressantes, car dans ce cas le caract\u00e8re ent\u00eat\u00e9 et furieux d&rsquo;Erdogan jouera son r\u00f4le, contre les exigences de l&rsquo;OTAN certes.)<\/p>\n<\/p>\n<p><p>\tD&rsquo;autre part, cette m\u00eame situation antipolaire d&rsquo;un nouveau genre joue en faveur du rapprochement avec Moscou et avec l&rsquo;OCS. On sait que nous tenons la Russie et sa diplomatie comme parfaitement adapt\u00e9es \u00e0 cette nouvelle situation ; ainsi faisions-nous remarquer (voir le <a href=\"http:\/\/www.dedefensa.org\/article-apolaire_ou_antipolaire__16_11_2013.html\" class=\"gen\">16 novembre 2013<\/a>) que les principaux acteurs \u00e9taient affect\u00e9s par ce basculement vers un monde antipolaire, mais \u00ab[u]<em>n seul pays parmi les principaux acteurs \u00e9chappe \u00e0 ces jugements catastrophiques, et l&rsquo;on se doute que c&rsquo;est la Russie<\/em>\u00bb, parce que (voir le <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_le_d_sordre_apolaire_du_moyen-orient_10_11_2013.html\" class=\"gen\">10 novembre 2013<\/a>) \u00ab<em>les Russes apparaissent<\/em> [ &#8230;] <em>comme une borne de stabilit\u00e9 (plut\u00f4t que l&rsquo;expression trop structur\u00e9e de p\u00f4le de stabilit\u00e9,  voir plus loin), dont la proximit\u00e9 n&rsquo;est pas vraiment dangereuse, au contraire de l&rsquo;instabilit\u00e9 US qui risquerait \u00e0 chaque moment de vous emporter&#8230;<\/em>\u00bb Cela signifie que nul n&rsquo;a vraiment \u00e0 craindre une influence, encore moins une h\u00e9g\u00e9monie des Russes, dont toute la diplomatie s&rsquo;appuie sur la r\u00e9f\u00e9rence principielle de la souverainet\u00e9 qui a toute sa place dans un monde antipolaire. D&rsquo;autre part et contrairement \u00e0 la vision compl\u00e8tement conforme-Syst\u00e8me d&rsquo;un Belge, le mod\u00e8le OCS n&rsquo;est pas un vieux mod\u00e8le, il serait au contraire un mod\u00e8le compl\u00e8tement innovant, pour sa capacit\u00e9 d&rsquo;adaptation au monde antipolaire, justement parce qu&rsquo;il se garde bien d&rsquo;interf\u00e9rer dans la souverainet\u00e9 de ses membres.<\/p>\n<\/p>\n<p><p>\tPar cons\u00e9quent, le champ est ouvert pour les \u00e9volutions inattendues, pleines de contrepieds, d&rsquo;un Erdogan. Mais il est manifeste que l&rsquo;orientation Est et Nord-Est qui passe n\u00e9cessairement par Moscou, dos tourn\u00e9 aux dinosaures et autres usines \u00e0 gaz fig\u00e9es dans les d\u00e9lices de l&rsquo;unipolarit\u00e9 que sont l&rsquo;UE et l&rsquo;OTAN, est beaucoup plus propice \u00e0 cette sorte de parcours tr\u00e8s accord\u00e9 \u00e0 notre temps antipolaire.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 29 novembre 2013 \u00e0 13H04<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erdogan, l&rsquo;OCS et le monde antipolaire En visite en Russie (on s&rsquo;y bouscule actuellement), le Premier ministre turc Erdogan a de nouveau affirm\u00e9 que son pays \u00e9tait candidat pour devenir membre de l&rsquo;Organisation de Coop\u00e9ration de Shanghai. On a d\u00e9j\u00e0 parl\u00e9 de ce projet d&rsquo;Erdogan, qui a d&rsquo;abord \u00e9t\u00e9 pris pour une plaisanterie, puis peu&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[15425,15430,14400,3435,2631,3737,12042,7459,916,5508],"class_list":["post-73571","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-antipolaire","tag-apolaire","tag-belge","tag-cooperation","tag-de","tag-erdogan","tag-latsa","tag-organisation","tag-poutine","tag-shanghai"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73571"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73571\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}