{"id":73575,"date":"2013-12-02T14:01:58","date_gmt":"2013-12-02T14:01:58","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/12\/02\/un-triomphe-crepusculaire\/"},"modified":"2013-12-02T14:01:58","modified_gmt":"2013-12-02T14:01:58","slug":"un-triomphe-crepusculaire","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/12\/02\/un-triomphe-crepusculaire\/","title":{"rendered":"Un triomphe cr\u00e9pusculaire"},"content":{"rendered":"<p><h2 class=\"common-article\">Un triomphe cr\u00e9pusculaire<\/h2>\n<\/p>\n<p><p>\t2 d\u00e9cembre 2013  Le triomphe cr\u00e9pusculaire, c&rsquo;est celui de Vladimir Poutine et de la Russie dans cette ann\u00e9e 2013. Dans notre texte du <a href=\"http:\/\/www.dedefensa.org\/article-de_la_vertu_p_dagogique_de_la_gloire_de_poutine_30_11_2013.html\" class=\"gen\">30 novembre 2013<\/a> sur la gloire de Poutine (et non \u00e0 la gloire de Poutine), nous avions annonc\u00e9 cette suite \u00e9largie du commentaire, notamment et pr\u00e9cis\u00e9ment \u00e0 la lumi\u00e8re d&rsquo;un commentaire de F\u00e9dor Loukianov, qu&rsquo;on retrouve d\u00e9sormais souvent sur ce site parce qu&rsquo;\u00e0 la sagacit\u00e9 du commentaire ce Loukianov (r\u00e9dacteur en chef du magazine <em>Russia in Global Affairs<\/em>) m\u00eale une proximit\u00e9 des cercles du pouvoir \u00e0 Moscou qui lui permet de bien conna\u00eetre les pens\u00e9es fondamentales de la direction russe et de s&rsquo;en faire par cons\u00e9quent l&rsquo;expression.<\/p>\n<\/p>\n<p><p>\tLe commentaire de Loukianov est particuli\u00e8rement \u00e9clairant pour notre propos parce qu&rsquo;il pr\u00e9sente, paradoxalement sans la moindre ambigu\u00eft\u00e9, une situation radicalement ambigu\u00eb pour la Russie de Poutine : une puissance triomphante, un pr\u00e9sident particuli\u00e8rement \u00e0 l&rsquo;aise et droit dans la conduite des affaires, et pourtant la perception fondamentale d&rsquo;une r\u00e9elle impuissance g\u00e9n\u00e9rale, ou strat\u00e9gique, de la Russie devant des d\u00e9veloppements et des \u00e9v\u00e9nements impr\u00e9visibles et qu&rsquo;on ne peut ma\u00eetriser. (Mais cette impuissance, bien entendu, est <strong>encore bien plus celle des autres<\/strong> [le bloc BAO], avec la diff\u00e9rence que les autres ne le r\u00e9alisent m\u00eame pas, ayant perdu toute capacit\u00e9 d&rsquo;y comprendre quelque chose. L&rsquo;impuissance strat\u00e9gique est ici une situation impos\u00e9e aux acteurs, \u00e0 tous les acteurs de la politique du monde.) A cette aune, nous dirions par cons\u00e9quent que la gloire de Poutine, c&rsquo;est sa lucidit\u00e9, ce qui n&rsquo;implique rien de triomphal ni de rassurant pour la bonne marche des affaires du monde en l&rsquo;\u00e9tat. Effectivement, Loukianov montre bien cela, et nous allons diviser son commentaire en trois extraits principaux. (Nous nous basons essentiellement sur la version fran\u00e7aise parue sur Novosti le <a href=\"http:\/\/fr.ria.ru\/tribune\/20131129\/199900002.html\" class=\"gen\">29 novembre 2013<\/a>. Ce texte est une adaptation, avec des tournures in\u00e9dites int\u00e9ressantes et la prise en compte d&rsquo;\u00e9v\u00e9nements nouveaux [l&rsquo;Ukraine], plus qu&rsquo;une traduction du texte en anglais de Loukianov, sur <em>al-Monitor<\/em>, le <a href=\"http:\/\/www.al-monitor.com\/pulse\/originals\/2013\/11\/russia-syria-policy-real-interests.html#ixzz2lSiwc41U\" class=\"gen\">22 novembre 2013<\/a>.)  <\/p>\n<\/p>\n<p><p>\t Loukianov tente de comprendre pourquoi la Russie triomphe sur la sc\u00e8ne internationale, alors que, selon lui, rien de fondamental n&rsquo;a chang\u00e9 sur la sc\u00e8ne internationale&#8230; Certes, rien n&rsquo;a chang\u00e9 <strong>dans le rapport des forces<\/strong>, mais beaucoup a chang\u00e9, selon nous, du point de vue de la communication et de <strong>ses effets sur la psychologie<\/strong>, avec une d\u00e9gradation vertigineuse de ce domaine du c\u00f4t\u00e9 du bloc BAO et de ses suppl\u00e9tifs. La Russie, elle, est rest\u00e9e ferme, simplement parce que sa r\u00e9f\u00e9rence est principielle, comme nous l&rsquo;observons constamment depuis des ann\u00e9es. Cela donne aux dirigeants russes une puissante assise psychologique et une politique \u00e0 mesure, sans pour cela qu&rsquo;ils appr\u00e9hendent mieux ce qui va se passer (mais \u00e0 ce point et sur ce point, nul ne peut rien appr\u00e9hender). Selon cette analyse, Loukianov d\u00e9veloppe sans la moindre h\u00e9sitation cet argument du principe, la poutre-ma\u00eetresse de la politique russe ; simplement sa d\u00e9finition g\u00e9opolitique de la chose ne correspond pas \u00e0 notre propre conception, ou plut\u00f4t elle n&rsquo;en est qu&rsquo;une partie, et une partie produite par l&rsquo;essence du principe bien que faisant partie de cette essence&#8230; (C&rsquo;est d&rsquo;ailleurs le cas g\u00e9n\u00e9ral, sur lequel nous revenons plus bas : Loukianov suit une analyse g\u00e9opolitique. Celle-ci est \u00e0 notre sens, non seulement insuffisante mais de plus en plus marginalis\u00e9e selon la substance des \u00e9v\u00e9nements.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Qu&rsquo;est-ce qui a r\u00e9ellement chang\u00e9<\/em> [qui a transform\u00e9 une position d\u00e9licate de Moscou en triomphe]<em>? Rien. Les circonstances sont les m\u00eames, la disposition g\u00e9n\u00e9rale des forces et le comportement des principaux figurants aussi. Alors pourquoi Moscou, au lieu d&rsquo;\u00eatre devenu le loser de la sc\u00e8ne internationale, est aujourd&rsquo;hui l&rsquo;un de ses acteurs les plus couronn\u00e9s de succ\u00e8s ? Si ce n&rsquo;est pas strat\u00e9giquement, alors tactiquement ? Il s&rsquo;av\u00e8re que dans ce monde o\u00f9 tout est confus, o\u00f9 aucune r\u00e8gle n&rsquo;existe et les anciens fondements s&rsquo;effondrent,  l&rsquo;attachement \u00e0 des principes coh\u00e9rents est un gage de succ\u00e8s. Pourvu qu&rsquo;ils soient solides.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Les principes, ce ne sont pas les valeurs auxquelles se r\u00e9f\u00e8re l&rsquo;Union europ\u00e9enne, l&rsquo;id\u00e9ologie de l&rsquo;URSS ou encore des USA aujourd&rsquo;hui. C&rsquo;est un syst\u00e8me de points de vue sur le fonctionnement du monde. Et il faut se comporter de mani\u00e8re \u00e0 correspondre aux lois empiriques selon lesquelles ce syst\u00e8me fonctionne.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Le r\u00e9sultat de cette politique principielle de la Russie s&rsquo;inscrit dans les succ\u00e8s ou triomphes de l&rsquo;ann\u00e9e 2013 ; pour autant pas de triomphalisme, paradoxalement, et \u00e0 juste raison, parce que les autres (le bloc BAO et les suppl\u00e9tifs), les adversaires selon la vision g\u00e9opolitique, sont non seulement inexistants mais si incoh\u00e9rents qu&rsquo;ils offrent ces succ\u00e8s sur un plateau. Pour autant (suite), ces succ\u00e8s ne d\u00e9gagent rien, ne font rien avancer d&rsquo;un point de vue g\u00e9n\u00e9ral \u00ab<em>dans un contexte de chaos croissant<\/em>\u00bb. L&rsquo;explication g\u00e9n\u00e9rale de la chevauch\u00e9e russe et de la d\u00e9bandade du reste se trouve, bien entendu, dans les r\u00e9f\u00e9rences que nous-m\u00eames distinguons bien entendu (voir le <a href=\"http:\/\/www.dedefensa.org\/article-poutine_la_russie_et_le_sens_de_la_crise_23_09_2013.html\" class=\"gen\">23 septembre 2013<\/a>), entre les principes sur lesquels s&rsquo;appuient les Russes et les valeurs que le bloc BAO suit aveugl\u00e9ment comme autant de bulles inconsistantes issues de la pens\u00e9e du parti des salonards&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab[Poutine] <em>est persuad\u00e9 que dans un contexte de chaos croissant  au niveau mondial, seule la pr\u00e9sence d&rsquo;un appui permettra de survivre. Un appui r\u00e9el si possible, soit fictif si tout se d\u00e9sint\u00e8gre dans la r\u00e9alit\u00e9. Les approches classiques des relations internationales sont pr\u00e9cis\u00e9ment appel\u00e9es \u00e0 remplir cette fonction.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Au vu des r\u00e9sultats actuels, cette m\u00e9thode fonctionne. Son application distingue d&rsquo;ailleurs favorablement la Russie des autres grands acteurs. L&rsquo;Union europ\u00e9enne parle de valeurs en appliquant cet outil \u00e0 diverses situations du Moyen-Orient \u00e0 l&rsquo;Afrique en passant par l&rsquo;Europe de l&rsquo;Est et le Caucase du Sud. Sans approfondir l&rsquo;analyse des causes on ne constate qu&rsquo;une seule chose : une confusion totale, et partout.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>L&rsquo;Europe, qui n&rsquo;a pas d&rsquo;interm\u00e9diaire influent au Moyen-Orient, est compl\u00e8tement absente de la r\u00e9gion, et sa strat\u00e9gie d&rsquo;influence ne fonctionne m\u00eame pas avec les pays de la CEI, bien que l&rsquo;UE semble y avoir un avantage notoire. Les \u00c9tats-Unis pr\u00e9f\u00e8rent une approche id\u00e9ologique ordonn\u00e9e en s\u00e9parant les bellig\u00e9rants entre progressistes et r\u00e9trogrades, mais la r\u00e9alit\u00e9 du Moyen-Orient est capable de pousser au d\u00e9sespoir : plus on avance et moins on arrive \u00e0 inscrire les \u00e9v\u00e9nements dans ce sch\u00e9ma simpliste. D&rsquo;o\u00f9 les agitations,  sans cesse, \u00e0 la recherche du bon c\u00f4t\u00e9 de l&rsquo;histoire.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Ainsi en arrivons-nous au constat fondamental, qui s&rsquo;exprime en une remarque fondamentale : certes, la Russie triomphe partout, mais pourquoi faire, dans quel but &#8230; Elle-m\u00eame l&rsquo;ignore. Loukianov parle d&rsquo;une excellente pratique tactique de la Russie, mais d&rsquo;une strat\u00e9gie absente. Il note que la Russie n&rsquo;a nulle intention h\u00e9g\u00e9monique, surtout pas celle de remplacer les USA,  et c&rsquo;est d&rsquo;ailleurs pour cette raison que sa politique est tant appr\u00e9ci\u00e9e et que nombre de pays jusqu&rsquo;alors hostiles et m\u00e9fiants se tournent vers elle,  par ailleurs, ces pays aussi d\u00e9sorient\u00e9s que les autres, attir\u00e9s par la fermet\u00e9 de la politique principielle russe. C&rsquo;est donc un catalogue paradoxal d&rsquo;une excellente politique qui porte partout ses fruits, et d&rsquo;une r\u00e9elle angoisse diffuse mais pr\u00e9gnante qui fait s&rsquo;interroger sur l&rsquo;avenir de la chose, jusqu&rsquo;\u00e0 ce constat paradoxalement cr\u00e9pusculaire : \u00ab<em>La Russie ne tiendra pas longtemps avec de simples coups tactiques.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Et la politique russe : de quels r\u00e9sultats peut-elle se vanter ? Son autorit\u00e9 est en hausse. Mais elle pourrait se retrouver pi\u00e9g\u00e9e par cette nouvelle situation car les attentes grandissent en m\u00eame temps. Le comportement inintelligible de l&rsquo;Am\u00e9rique au Moyen-Orient, ses tentatives de r\u00e9duire sa pr\u00e9sence et son activit\u00e9 entra\u00eenent l&rsquo;apparition d&rsquo;un vide, qu&rsquo;il est habituellement propos\u00e9 \u00e0 la Russie de remplir. Qui d&rsquo;autre, sinon ? Le souvenir du r\u00f4le syst\u00e9mique jou\u00e9 dans la r\u00e9gion par l&rsquo;URSS demeure, on ne voit pas pour l&rsquo;instant d&rsquo;autres candidats  la Chine semble fuir les responsabilit\u00e9s comme la peste. Mais paradoxalement la Russie n&rsquo;a pas l&rsquo;intention de revenir dans cette r\u00e9gion comme principale force ext\u00e9rieure, et ne l&rsquo;a jamais eu. Ce n&rsquo;\u00e9tait pas l&rsquo;objectif de sa politique syrienne par exemple, qui n&rsquo;avait pas de lien direct avec le Moyen-Orient. Il \u00e9tait primordial pour la Russie de revenir sur son principe de base : l&rsquo;ing\u00e9rence dans un pays pour renverser son r\u00e9gime est inadmissible et m\u00e8ne \u00e0 la destruction totale. Il s&rsquo;av\u00e8re que gr\u00e2ce aux \u00e9checs des autres pays la Russie est quand m\u00eame de retour, mais elle ne voit pas comment capitaliser cette r\u00e9ussite. Autrement dit Moscou \u00e9largirait volontiers son portefeuille de contrats d&rsquo;armements mais on attend de lui quelque chose de plus grande envergure. Or la Russie n&rsquo;est pas pr\u00eate \u00e0 s&rsquo;enliser dans les affaires r\u00e9gionales du Moyen-Orient, qui semblent sans issue.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>A premi\u00e8re vue le dossier ukrainien est diff\u00e9rent  l&rsquo;int\u00e9r\u00eat est compr\u00e9hensible et l&rsquo;excitation est grande. Mais l&rsquo;esprit de comp\u00e9tition va se dissiper et on ignore toujours quoi faire avec ce pays voisin et aussi proche. Apr\u00e8s tout l&rsquo;Ukraine n&rsquo;a fait aucun choix en faveur de Moscou, elle l&rsquo;a une nouvelle fois esquiv\u00e9 en esp\u00e9rant pouvoir continuer \u00e0 mener par le bout du nez les uns et les autres. La Russie peut donc lancer une grande offensive pour attirer Kiev dans ses bras institutionnels avec des promesses et des carottes. Mais ces efforts risqueraient de n&rsquo;avoir aucun effet et on repartirait pour un nouveau tour avec l&rsquo;Ukraine &#8211; car sa d\u00e9rive vers l&rsquo;Occident se poursuit ind\u00e9pendamment des priorit\u00e9s changeantes du gouvernement.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>On se retrouve dans une situation \u00e9trange. Le gouvernement russe ressent mieux que les autres l&rsquo;instabilit\u00e9 de l&rsquo;univers et pour cette raison adopte un comportement plus adapt\u00e9 qui lui apporte des succ\u00e8s. Mais plus on avance et moins on comprend comment les utiliser car la Russie ignore elle-m\u00eame comment elle voudrait \u00eatre dans le futur, quel r\u00f4le jouera-t-elle et quelles priorit\u00e9s fixer. En d&rsquo;autres termes la vision syst\u00e9mique du monde qui permet d&rsquo;\u00e9laborer la bonne tactique est l\u00e0, alors que la vision tout aussi syst\u00e9mique de soi, qui permettrait de d\u00e9finir la strat\u00e9gie du pays, est absente. La Russie ne tiendra pas longtemps avec de simples coups tactiques.<\/em>\u00bb<\/p>\n<h3>Signification et usage de la strat\u00e9gie<\/h3>\n<\/p>\n<p><p>\tPour \u00e9largir notre commentaire au principal, nous faisons un rappel d&rsquo;un texte que nous publiions il y a \u00e0 peu pr\u00e8s un an (le <a href=\"http:\/\/www.dedefensa.org\/article-au_hasard_le_pouvoir_24_12_2012.html\" class=\"gen\">24 d\u00e9cembre 2012<\/a>). L\u00e0 aussi, nous prenions comme base de r\u00e9flexion une analyse de Loukianov, et le th\u00e8me g\u00e9n\u00e9ral \u00e9tait la politique russe avec sa tenue et sa solidit\u00e9 (sans succ\u00e8s notable pour cette p\u00e9riode de l&rsquo;ann\u00e9e 2012) face \u00e0 l&rsquo;inconsistance des autres (l&rsquo;habituelle basse-cour du bloc BAO) ; et le th\u00e8me fondamental \u00e9tait d\u00e9j\u00e0 la paralysie et l&rsquo;impuissance de ces acteurs, y compris les meilleurs (les Russes) face \u00e0 une situation g\u00e9n\u00e9rale qui <strong>ne r\u00e9pond plus<\/strong> aux sollicitations humaines des diverses politiques d\u00e9velopp\u00e9es. Le th\u00e8me conjoncturel \u00e9tait l&rsquo;un des ph\u00e9nom\u00e8nes de l&rsquo;ann\u00e9e 2012, avec le renouvellement (soit par changements, soit par conformations \u00e9lectorales majeures) des directions politiques dans nombre de pays importants (Russie, France, USA, Chine&#8230;)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Le facteur primordial apparu \u00e0 cette occasion, c&rsquo;est bien que le renouvellement des directions politiques, loin de donner un effet, m\u00eame temporaire, de relance de l&rsquo;initiative politique, au contraire acc\u00e9l\u00e8re la situation de paralysie et\/ou d&rsquo;impuissance. C&rsquo;est particuli\u00e8rement \u00e9vident avec le cas fran\u00e7ais et, particuli\u00e8rement aussi, avec le cas US. Hollande, succ\u00e9dant \u00e0 Sarkozy, se d\u00e9couvre encore plus encalmin\u00e9 que son pr\u00e9d\u00e9cesseur dans des engrenages dont personne, dans le personnel politique fran\u00e7ais, n&rsquo;a id\u00e9e de leurs causes, et, certainement pas, de leurs buts et de leurs cons\u00e9quences. Le cas am\u00e9ricaniste est encore plus remarquable. BHO se succ\u00e9dant \u00e0 lui-m\u00eame, avec la promesse de lib\u00e9rer sa politique, et peut-\u00eatre l&rsquo;intention de le faire, ou du moins de le tenter, se trouve d\u00e9j\u00e0 engag\u00e9 dans plusieurs bourbiers parall\u00e8les avant m\u00eame d&rsquo;avoir lanc\u00e9 ses nouvelles initiatives.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Le cas russe est \u00e9videmment diff\u00e9rent, mais repr\u00e9sente une confirmation a contrario. Poutine succ\u00e8de \u00e0 Medvedev pour resserrer les boulons, raffermir la politique russe, la retrancher encore plus sur des principes intangibles, la rendre plus ferme, plus intransigeante sur quelques points essentiels. Cela produit une certaine impuissance dans des domaines et dans un contexte o\u00f9 rien d&rsquo;autre que l&rsquo;immobilit\u00e9 sur la position essentielle (le principe) n&rsquo;est possible, mais cela renforce le choix de la r\u00e9sistance qui est, par d\u00e9finition, plant\u00e9e sur une position de principe. Cette r\u00e9sistance pourrait aller jusqu&rsquo;\u00e0 des situations d&rsquo;affrontements, en cela conforme au r\u00f4le de la Russie qu&rsquo;on a vu plus haut, mais ces affrontements resteraient des affrontements de r\u00e9sistance dont l&rsquo;effet fondamental (pas n\u00e9cessairement recherch\u00e9 par les Russes, ou r\u00e9alis\u00e9 comme tel par eux) serait d&rsquo;acc\u00e9l\u00e9rer la chute g\u00e9n\u00e9rale du Syst\u00e8me.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>En d&rsquo;autres termes, le processus g\u00e9n\u00e9ral int\u00e9gr\u00e9 en 2008 sous la forme de structures de crises, jusqu&rsquo;\u00e0 la g\u00e9n\u00e9ralisation de la crise comme facteur primordial sinon exclusif de la situation du monde, s&rsquo;est largement r\u00e9pandue dans les directions politiques en 2012, notamment \u00e0 l&rsquo;occasion des changements de directions. L&rsquo;une ou l&rsquo;autre crise sert de remarquable exercice pratique du processus, essentiellement la Syrie, apr\u00e8s le coup d&rsquo;essai de la Libye qui marque le d\u00e9but du processus d&rsquo;inversion o\u00f9 l&rsquo;action des directions politiques engendre paralysie et impuissance (transformation de la Libye de Kadhafi, avec laquelle l&rsquo;Ouest s&rsquo;arrangeait en g\u00e9n\u00e9ral, en un foyer d&rsquo;instabilit\u00e9 \u00e9chappant au contr\u00f4le du bloc BAO,  entretemps, l&rsquo;Ouest s&rsquo;\u00e9tant effectivement transform\u00e9 en bloc BAO). Le ph\u00e9nom\u00e8ne g\u00e9n\u00e9ral est donc, maintenant, l&rsquo;\u00e9volution acc\u00e9l\u00e9r\u00e9e de cette situation g\u00e9n\u00e9rale de crise (le monde changeant de Loukianov) alors que l&rsquo;exercice du pouvoir s&rsquo;enfonce dans cette situation encalmin\u00e9e qu&rsquo;il<\/em> [Loukianov] <em>d\u00e9crit (Gouverner pour ne rien changer). Il s&rsquo;agit d&rsquo;une situation m\u00e9tahistorique arriv\u00e9e \u00e0 son point d&rsquo;efficacit\u00e9 maximale. Le sapiens-Syst\u00e8me, l&rsquo;homme de pouvoir id\u00e9alement d\u00e9fini dans le cadre des pays du bloc BAO, est d\u00e9finitivement devenu le figurant au rabais d&rsquo;un affrontement colossal qui se passe bien au-del\u00e0 et bien au-dessus de lui, et qui se passe ais\u00e9ment de lui. C&rsquo;est la phase fondamentale de la crise terminale du Syst\u00e8me et sapiens-Syst\u00e8me, soi-disant homme de pouvoir, n&rsquo;y a aucune utilit\u00e9 particuli\u00e8re sinon celle de s&rsquo;ex\u00e9cuter sans discuter ni rien y comprendre.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLa situation, un an plus tard, est tactiquement toute diff\u00e9rente avec les succ\u00e8s russes, mais strat\u00e9giquement inchang\u00e9e, avec l&rsquo;impuissance g\u00e9n\u00e9rale et l&rsquo;inconnu des choses \u00e0 venir. (Nous employons \u00e0 dessein le langage de g\u00e9opoliticien de Loukianov, dont la remarque pourrait \u00e9galement convenir pour cette comparaison 2012-2013 : \u00ab<em>Qu&rsquo;est-ce qui a r\u00e9ellement chang\u00e9? Rien.<\/em>\u00bb) La situation de fin 2013 est r\u00e9sum\u00e9e par Loukianov dans sa phrase de conclusion, d\u00e9j\u00e0 mise en exergue plus haut, concluant une description des r\u00e9ussites de la politique russe, et de la justesse structurelle de la politique principielle russe : \u00ab<em>La Russie ne tiendra pas longtemps avec de simples coups tactiques.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tA cela, l&rsquo;on pourrait tout de m\u00eame r\u00e9pliquer : qui et quoi feraient en sorte que la Russie ne tiendra pas longtemps ? L&rsquo;absence de strat\u00e9gie dans le chef de la Russie n&rsquo;est pas sp\u00e9cifique \u00e0 la Russie. Elle affecte tout le monde sans exception (pour la raison \u00e9vidente, on le verra plus loin, que la strat\u00e9gie, c&rsquo;est-\u00e0-dire la situation g\u00e9n\u00e9rale, ne d\u00e9pend plus des politiques humaines et, par cons\u00e9quent, n&rsquo;est plus vraiment n\u00e9cessaire \u00e0 ce niveau). Personne ne peut faire chuter la Russie <strong>si la Russie s&rsquo;en tient \u00e0 sa tr\u00e8s-ferme politique principielle<\/strong>, parce que personne n&rsquo;en a ni les moyens, ni la force, ni l&rsquo;imagination tactique pour le faire, ni, encore moins, un concept strat\u00e9gique pour guider l&rsquo;entreprise, qui serait capable d&rsquo;avoir raison de la force du Principe. <em>A contrario<\/em>, et parce que tout le monde est soumis \u00e0 la m\u00eame incertitude, l&rsquo;attirance pour la Russie que Loukianov lui-m\u00eame rel\u00e8ve a toutes les raisons de perdurer. Dire cela, c&rsquo;est temp\u00e9rer la conclusion tr\u00e8s-pessimiste de Loukianov, mais c&rsquo;est pour autant ne d\u00e9mentir en rien l&rsquo;orientation de cette conclusion. L&rsquo;explication de ces constats faits de paradoxes est que nous ne raisonnons pas en g\u00e9opoliticien et en termes g\u00e9opolitique, comme le fait Loukianov.<\/p>\n<\/p>\n<p><p>\tEffectivement,  et il ne s&rsquo;en cache pas car il n&rsquo;y a aucune raison selon lui de s&rsquo;en trouver g\u00ean\u00e9,  Loukianov raisonne en g\u00e9opoliticien, comme sans nul doute la direction russe. Il lui faut des vainqueurs et des vaincus, comme il sied \u00e0 une bonne appr\u00e9ciation g\u00e9opolitique dont l&rsquo;origine est, quoi qu&rsquo;on en veuille, un succ\u00e9dan\u00e9 de l&rsquo;esprit de l&rsquo;id\u00e9al de la puissance. (\u00ab<em>Pour les Russes, les relations internationales sont une lutte permanente pour le pouvoir et le prestige  comme disait Hans Morgenthau, fondateur de l&rsquo;\u00e9cole r\u00e9aliste en science politique  et il ne faut pas croire que dans le monde moderne il n&rsquo;existe pas de gains, m\u00eame dans un jeu \u00e0 somme nulle.<\/em>\u00bb) Le paradoxe russe est que la pens\u00e9e politique est compl\u00e8tement g\u00e9opolitique, alors que l&rsquo;essence de la politique de la Russie est principielle (le Principe), qui est, par essence justement, une r\u00e9f\u00e9rence de l&rsquo;id\u00e9al de perfection contre l&rsquo;id\u00e9al de la puissance. (Voir Guglielmo Ferrero le <a href=\"http:\/\/www.dedefensa.org\/article-notre_11_novembre_11_11_2008.html\" class=\"gen\">11 novembre 2013<\/a> et le <a href=\"http:\/\/www.dedefensa.org\/article-genie_latin_et_germanisme_de_guglielmo_ferrero_1917_08_12_2008.html\" class=\"gen\">8 d\u00e9cembre 2013<\/a>. De ce point de vue, \u00e9galement, nous diff\u00e9rons fortement de Loukianov dans son appr\u00e9ciation du principe, dont nous faisons des r\u00e9f\u00e9rences intangibles hors de la contingence des \u00e9v\u00e9nements et des situations politiques.) Une vraie politique principielle, comme celle d&rsquo;un <a href=\"http:\/\/www.dedefensa.org\/article-eloge_et_necessite_de_la_legitimite_extraits_des_memoires_de_talleyrand_16_08_2007.html\" class=\"gen\">Talleyrand<\/a> ou d&rsquo;un de Gaulle, n&rsquo;est pas une politique de puissance (g\u00e9opolitique), qui n\u00e9cessite une strat\u00e9gie pour accomplir des buts h\u00e9g\u00e9moniques ou de cette sorte contre d&rsquo;autres forces et puissances terrestres ; elle est ce que nous pourrions nommer d&rsquo;une fa\u00e7on symbolique en r\u00e9f\u00e9rence \u00e0 l&rsquo;expression id\u00e9al de perfection, une politique de perfection recherchant un ordre objectif avec la collaboration des uns et des autres, une politique de perfection appliqu\u00e9e au champ terrestre g\u00e9n\u00e9ral (recherche de l&rsquo;\u00e9quilibre, de l&rsquo;harmonie, refus d&rsquo;un vainqueur ou d&rsquo;une h\u00e9g\u00e9monie entra\u00eenant des d\u00e9s\u00e9quilibres d&rsquo;antagonisme, etc.). (La fameuse phrase de De Gaulle, que nous citons souvent car elle r\u00e9sume cette politique de l&rsquo;id\u00e9al de perfection qui propose la rencontre de l&rsquo;int\u00e9r\u00eat commun et de l&rsquo;honneur de chacun : \u00ab<em>Tout peut, un jour arriver, m\u00eame ceci qu&rsquo;un acte conforme \u00e0 l&rsquo;honneur et \u00e0 l&rsquo;honn\u00eatet\u00e9 apparaisse, en fin de compte, comme un bon placement politique.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tMais \u00e0 c\u00f4t\u00e9 de ces consid\u00e9rations des valeurs compar\u00e9es des types de politique, il y a, pour notre \u00e9poque et d&rsquo;une fa\u00e7on \u00e9crasante, un changement fondamental de la forme. Notre point de vue est, on le sait, que nous ne sommes plus dans l&rsquo;\u00e8re g\u00e9opolitique mais dans l&rsquo;\u00e8re psychopolitique (voir notre <em>Glossaire.dde<\/em>, le <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_l_re_psychopolitique_12_10_2013.html\" class=\"gen\">12 octobre 2013<\/a>).  C&rsquo;est une bonne part de l&rsquo;explication de l&rsquo;\u00e9volution de notre appr\u00e9ciation vers l&rsquo;identification de ce que nous avons d\u00e9sign\u00e9 comme un monde antipolaire (voir le <a href=\"http:\/\/www.dedefensa.org\/article-apolaire_ou_antipolaire__16_11_2013.html\" class=\"gen\">16 novembre 2013<\/a>), auquel la Russie est paradoxalement (malgr\u00e9 la forme g\u00e9opolitique de ses conceptions) si bien adapt\u00e9e parce qu&rsquo;elle ne veut pas \u00eatre h\u00e9g\u00e9monique &#8230;  En effet, et effectivement de fa\u00e7on paradoxale, cette volont\u00e9 de ne pas \u00eatre h\u00e9g\u00e9monique de la Russie contredit \u00e9galement la forme g\u00e9opolitique de sa pens\u00e9e, et l\u00e0 d&rsquo;une fa\u00e7on radicale parce qu&rsquo;elle aurait les moyens d&rsquo;\u00eatre h\u00e9g\u00e9monique en raison de la d\u00e9bandade et de l&rsquo;incoh\u00e9rence des autres. Au contraire, tout se passe comme si la Russie s&rsquo;adaptait sans concevoir la chose, et contre sa propre approche g\u00e9opolitique, \u00e0 cette \u00e8re psychopolitique et au monde antipolaire. Par ailleurs, on en comprend la cause profonde, qui n&rsquo;est rien moins que la puissance d&rsquo;entra\u00eenement et d&rsquo;attrait d&rsquo;une politique principielle, \u00e0 mesure de la puissance d&rsquo;inspiration et d&rsquo;attraction du Principe en g\u00e9n\u00e9ral. Dans ce cas, on est \u00e9galement conduit \u00e0 concevoir que l&rsquo;absence de strat\u00e9gie de la Russie que d\u00e9plore Loukianov, la r\u00e9duction de la politique russe \u00e0 des succ\u00e8s tactiques sans parvenir \u00e0 \u00e9tablir une strat\u00e9gie mais en \u00e9tant tenue \u00e0 la r\u00e9f\u00e9rence ferme que sont les principes, n&rsquo;est en rien une faiblesse parce qu&rsquo;un monde antipolaire est par d\u00e9finition un monde priv\u00e9 de strat\u00e9gie du point de vue des politiques humaines, et qui n&rsquo;a pas besoin de strat\u00e9gie de ce point de vue.<\/p>\n<\/p>\n<p><p>\tIci, l&rsquo;on peut prolonger notre raisonnement concernant cette \u00e9volution vers un monde antipolaire qui justifie, dans le chef de la Russie prise comme exemple, de n&rsquo;avoir pas besoin de strat\u00e9gie, en posant la question de savoir pourquoi le monde est devenu antipolaire. Le passage \u00e0 l&rsquo;\u00e8re psychopolitique n&rsquo;est une explication qu&rsquo;en partie puisque ce ph\u00e9nom\u00e8ne n&rsquo;est que l&rsquo;op\u00e9rationnalisation du moyen d&rsquo;une \u00e9volution, et, pour notre compte, l&rsquo;explication d&rsquo;une \u00e9volution de la perception, avec l&rsquo;importance fondamentale reconnue au syst\u00e8me de la communication, permettant l&rsquo;identification et l&rsquo;appr\u00e9ciation du fait que le monde est devenu antipolaire. Il est donc n\u00e9cessaire de se tourner vers des explications extra-conventionnelles, hors des lignes de force humaines dont nous constatons en g\u00e9n\u00e9ral l&rsquo;impuissance et la paralysie, et, au mieux et pour les plus vertueuses, un r\u00f4le r\u00e9duit \u00e0 la r\u00e9sistance aux forces d\u00e9structurantes \u00e0 l&rsquo;aide de r\u00e9f\u00e9rence structurante comme l&rsquo;est une politique principielle. Il est manifeste aujourd&rsquo;hui que les \u00e9v\u00e9nements produisent eux-m\u00eames leur logique et l&rsquo;hypoth\u00e8se d&rsquo;un lien entre eux et des forces extrahumaines qu&rsquo;on mesurera sans difficult\u00e9s comme sup\u00e9rieures ne peut \u00eatre \u00e9cart\u00e9e. Dans ce cas, la strat\u00e9gie organis\u00e9e hors de la ma\u00eetrise humaine va \u00e0 l&rsquo;essentiel, qui est la crise de civilisation op\u00e9rationnalis\u00e9e par la crise du Syst\u00e8me. On retrouve alors, dans le chef de cette sorte d&rsquo;activit\u00e9, les grandes lignes de tension et d&rsquo;affrontement qui s&rsquo;organisent autour du Syst\u00e8me, soit en faveur du Syst\u00e8me, et souvent issus du Syst\u00e8me lui-m\u00eame, soit contre le Syst\u00e8me, selon la r\u00e9f\u00e9rence g\u00e9n\u00e9rale des forces antiSyst\u00e8me.<\/p>\n<\/p>\n<p><p>\tAinsi, l&rsquo;\u00e9volution vers un monde antipolaire, en r\u00e9duisant ou en supprimant des situations classiques d&rsquo;affrontement g\u00e9opolitique o\u00f9 les diff\u00e9rences et antagonismes entre Syst\u00e8me et antiSyst\u00e8me sont perdues dans l&rsquo;interf\u00e9rence de pressions secondaires, op\u00e9rationnalise-t-elle cette accentuation vers l&rsquo;affrontement entre le Syst\u00e8me et les forces antiSyst\u00e8me. La caract\u00e9ristique de la situation g\u00e9n\u00e9rale est que les situations de tension, d&rsquo;antagonisme, d&rsquo;affrontement \u00e9ventuellement, souvent \u00e0 dominante g\u00e9opolitique ou d&rsquo;origine g\u00e9opolitique, tendent constamment \u00e0 \u00eatre modifi\u00e9es, ou r\u00e9duites pour se transformer en situations d&rsquo;affrontement entre le Syst\u00e8me et les forces antiSyst\u00e8me. Bien entendu, on comprend alors que l&rsquo;interrogation de Loukianov, m\u00eame si c&rsquo;est pour des raisons compl\u00e8tement diff\u00e9rentes, a toute sa place : \u00ab[&#8230;L]<em>a vision syst\u00e9mique du monde qui permet d&rsquo;\u00e9laborer la bonne tactique est l\u00e0, alors que la vision tout aussi syst\u00e9mique de soi, qui permettrait de d\u00e9finir la strat\u00e9gie du pays<\/em> [de la Russie]<em>, est absente.<\/em>\u00bb Simplement, il manque \u00e0 cette remarque un troisi\u00e8me \u00e9l\u00e9ment, qui prendrait la place centrale et rendrait les deux autres marginaux ou hors de propos &#8230; La tactique r\u00e9ussie de la Russie souffre moins d&rsquo;une absence de strat\u00e9gie de cette m\u00eame Russie, qu&rsquo;elle ne s&rsquo;accorde, d&rsquo;une fa\u00e7on dissimul\u00e9e mais n\u00e9anmoins tr\u00e8s puissante, \u00e0 la logique propre des \u00e9v\u00e9nements li\u00e9s \u00e0 des forces extrahumaines qui, seules, d\u00e9terminent la strat\u00e9gie, en la concentrant dans l&rsquo;affrontement entre le Syst\u00e8me et l&rsquo;antiSyst\u00e8me. La question m\u00e9tahistorique fondamentale accompagnant cette sorte d&rsquo;hypoth\u00e8ses concernant des activit\u00e9s \u00e9chappant aux normes humaines est de savoir si, \u00e0 l&rsquo;heure d&rsquo;une crise d&rsquo;une importance si grande qu&rsquo;elle d\u00e9termine le sort d&rsquo;une civilisation universelle et du Syst\u00e8me qui la soumet, l&rsquo;Histoire n&rsquo;est pas en train d&rsquo;acqu\u00e9rir un sens, c&rsquo;est-\u00e0-dire une signification plus qu&rsquo;une orientation, qui serait lui-m\u00eame d\u00e9termin\u00e9 par des facteurs compl\u00e8tement \u00e9trangers aux habituelles pol\u00e9miques, id\u00e9ologies, constructions et <em>narrative<\/em> humaines formant depuis au moins plusieurs si\u00e8cles,  mises \u00e0 part certaines s\u00e9quences paroxystiques comme la R\u00e9volution fran\u00e7aise,  l&rsquo;essentiel de la r\u00e9flexion historique. <\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un triomphe cr\u00e9pusculaire 2 d\u00e9cembre 2013 Le triomphe cr\u00e9pusculaire, c&rsquo;est celui de Vladimir Poutine et de la Russie dans cette ann\u00e9e 2013. Dans notre texte du 30 novembre 2013 sur la gloire de Poutine (et non \u00e0 la gloire de Poutine), nous avions annonc\u00e9 cette suite \u00e9largie du commentaire, notamment et pr\u00e9cis\u00e9ment \u00e0 la lumi\u00e8re&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[15425,4646,6054,8516,7746,2878,11648,15433,2730,3440,3014,5210],"class_list":["post-73575","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-antipolaire","tag-antisysteme","tag-ere","tag-geopolitique","tag-loukianov","tag-monde","tag-principe","tag-psychhopolitique","tag-russie","tag-strategie","tag-systeme","tag-valeurs"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73575"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73575\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}