{"id":73585,"date":"2013-12-11T04:32:00","date_gmt":"2013-12-11T04:32:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/12\/11\/le-double-eclairage-du-mensonge-bho-sarin\/"},"modified":"2013-12-11T04:32:00","modified_gmt":"2013-12-11T04:32:00","slug":"le-double-eclairage-du-mensonge-bho-sarin","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/12\/11\/le-double-eclairage-du-mensonge-bho-sarin\/","title":{"rendered":"Le double \u00e9clairage du mensonge BHO-sarin"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Le double \u00e9clairage du mensonge BHO-sarin<\/h3>\n<\/p>\n<p><p>\tLa Syrie c&rsquo;est bien loin, et plus loin encore le formidable fiasco du bloc BAO et de BHO pour forcer \u00e0 une attaque contre Assad. Cela se passait en ao\u00fbt-septembre de l&rsquo;ann\u00e9e 2013&#8230; Soudain, la voix respect\u00e9e et comp\u00e9tente de Seymour Hersh, Prix Pulitzer et ma\u00eetre du journalisme d&rsquo;investigation men\u00e9 en toute ind\u00e9pendance depuis l&rsquo;affaire de My-La\u00ef (1969 dans les ann\u00e9es-Vietnam), nous sort un dossier consid\u00e9rable sur le montage que fut l&rsquo;attaque chimique en Syrie du 21 ao\u00fbt 2013. Pas vraiment de surprise parce qu&rsquo;il semble bien que la surprise n&rsquo;a plus sa place dans les poubelles \u00e9l\u00e9gamment puantes des montages sans fin des USA, et du bloc BAO en g\u00e9n\u00e9ral. On trouve sur l&rsquo;internet, outre le texte de Hersh lui-m\u00eame, nombre d&rsquo;analyses du dossier. Celle de Justin Raimondo, bien document\u00e9e, et \u00e9videmment favorable au travail de Hersh comme la simple d\u00e9cence et l&rsquo;\u00e9puisement de devoir subir leurs mensonges y invitent, est \u00e0 lire, sur <em>Antiwar.com<\/em> le <a href=\"http:\/\/original.antiwar.com\/justin\/2013\/12\/08\/syria-sarin-and-subterfuge-they-made-it-all-up\/\" class=\"gen\">10 d\u00e9cembre 2013<\/a>.<\/p>\n<\/p>\n<p><p>\tIl est tout de m\u00eame \u00e0 noter que Hersh, qui \u00e9tait pr\u00eat \u00e0 publier depuis un nombre respectable de semaines, a d\u00fb faire un saut transatlantique pour publier son dossier dans le <em>London Review of Book<\/em> du <a href=\"http:\/\/www.lrb.co.uk\/2013\/12\/08\/seymour-m-hersh\/whose-sarin\" class=\"gen\">8 d\u00e9cembre 2013<\/a>. Comme il l&rsquo;explique dans <em>Huffington Post<\/em> du <a href=\"http:\/\/www.huffingtonpost.com\/2013\/12\/08\/seymour-hersh-syria-report_n_4409674.html\" class=\"gen\">9 d\u00e9cembre 2013<\/a>, il a essuy\u00e9 deux refus de publication,  du <em>New Yorker<\/em>, le p\u00e9riodique o\u00f9 il publie r\u00e9guli\u00e8rement et qui lui doit une belle popularit\u00e9 et des ventes substantielles,  et du Washington <em>Post<\/em>. On n&rsquo;\u00e9tait pas vraiment int\u00e9ress\u00e9, ou bien l&rsquo;on jugeait ce Hersh pas tr\u00e8s cr\u00e9dible, avec ses sources qui ne sont pas du standard du Washington <em>Post<\/em>&#8230; <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Hersh is a freelancer, but he&rsquo;s best known these days for his work in The New Yorker, where he helped break the Abu Ghraib scandal in 2004. While Hersh is not a New Yorker staff writer, it was notable that his 5,500-word investigative piece landed in the London Review of Books, a London literary and intellectual magazine, rather than the publication with which he&rsquo;s most closely associated. In an email, Hersh wrote that there was little interest for the story at The New Yorker. A New Yorker spokesperson did not immediately respond to a request for comment.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Hersh then took the story to The Washington Post. The Post intended to publish it, as BuzzFeed first reported. Hersh told HuffPost that he went to the Post because of the paper&rsquo;s reporting on documents provided by former NSA contractor Edward Snowden&#8230; <\/em>[&#8230;] <em>It&rsquo;s unclear exactly why the Post decided not to publish the story. Hersh wrote that he was told by email that Executive Editor Marty Baron decided that the sourcing in the article did not meet the Post&rsquo;s standards. Baron and a spokesperson for the Post did not respond to requests for comment on Sunday night.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>A few weeks ago, Hersh sent the Syria story to editors at the London Review of Books, LRB Senior Editor Christian Lorentzen told HuffPost. Lorentzen said the piece was not only edited, but thoroughly fact checked by a former New Yorker fact checker who had worked with Hersh in the past&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEst-il n\u00e9cessaire, vraiment, de s&rsquo;attarder sur la duplicit\u00e9 du Syst\u00e8me et de sa petite main, le bloc BAO ? Sur leur bassesse, leur l\u00e2chet\u00e9, leur indignit\u00e9, leur aveuglement, leur go\u00fbt presque vertueux \u00e0 force de conviction de l&rsquo;inversion et de l&rsquo;imposture ? Il existe d\u00e9j\u00e0 une abondante litt\u00e9rature \u00e0 propos de l&rsquo;attaque chimique du 21 ao\u00fbt et de ce qui \u00e9tait apparu aussit\u00f4t comme l&rsquo;hypoth\u00e8se la plus vraisemblable du montage, ou <em>false flag<\/em> selon l&rsquo;expression en vogue, et l&rsquo;int\u00e9r\u00eat du texte de Hersh repose finalement sur nombre de d\u00e9tails, nombre de points de vue et de t\u00e9moignages, etc., \u00e9clairants \u00e0 plus d&rsquo;un \u00e9gard.<\/p>\n<\/p>\n<p><p>\tL&rsquo;un de ces points int\u00e9ressants concerne la frustration, la fureur, l&rsquo;incompr\u00e9hension de nombre d&rsquo;officiers du renseignement US. Hersh d\u00e9crit les diverses d\u00e9marches, \u00e9valuations, etc., qui ont pr\u00e9c\u00e9d\u00e9 puis accompagn\u00e9 l&rsquo;attaque chimique. Il y a eu la mise en \u00e9vidence de divers \u00e9l\u00e9ments, avant et pendant l&rsquo;attaque, que de telles actions viendraient probablement ou venaient effectivement de groupes terroristes, et particuli\u00e8rement d&rsquo;<em>al-Nusra<\/em>, sorte de groupe d\u00e9pendant de l&rsquo;association g\u00e9n\u00e9rale nomm\u00e9e al Qa\u00efda, dont il a \u00e9t\u00e9 d\u00e9termin\u00e9 qu&rsquo;il ma\u00eetrisait la production de gaz sarin. Nombre de signaux et de constats techniques ont renforc\u00e9 ces diverses \u00e9valuations. \u00ab<em>A former senior intelligence official told me that the Obama administration had altered the available information  in terms of its timing and sequence  to enable the president and his advisers to make intelligence retrieved days after the attack look as if it had been picked up and analysed in real time, as the attack was happening. The distortion, he said, reminded him of the 1964 Gulf of Tonkin incident, when the Johnson administration reversed the sequence of National Security Agency intercepts to justify one of the early bombings of North Vietnam. The same official said there was immense frustration inside the military and intelligence bureaucracy: The guys are throwing their hands in the air and saying, How can we help this guy  Obama  when he and his cronies in the White House make up the intelligence as they go along?&rsquo;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl faudra \u00e9galement noter combien cette affaire pr\u00e9sente d&rsquo;aspects contradictoires, voire d\u00e9routants, qui rendent encore plus remarquable la duplicit\u00e9 comme pratique courante et quasiment automatique, par d\u00e9sint\u00e9r\u00eat de toute rectitude du jugement de comportement et par aveuglement des perspectives, de l&rsquo;administration Obama et du pr\u00e9sident lui-m\u00eame. En effet, il s&rsquo;av\u00e8re que Seymour Hersh fait preuve d&rsquo;un grand courage et d&rsquo;une belle constance en d\u00e9clarant qu&rsquo;il a \u00e9t\u00e9 et qu&rsquo;il reste dans une certaine mesure un fervent partisan d&rsquo;Obama. (Son activisme-journalistique a \u00e9t\u00e9 effectivement nettement plus mesur\u00e9 depuis l&rsquo;arriv\u00e9e d&rsquo;Obama.) Pourtant, l&rsquo;affaire du montage du chimique syrien le conduit tout de m\u00eame \u00e0 d\u00e9noncer cet homme et son administration dont il est partisan. Hersh le montre dans ce passage beaucoup plus personnel (extrait d&rsquo;une interview de Hersh sur <em>Democracy Now !<\/em>, le <a href=\"http:\/\/www.democracynow.org\/2013\/12\/9\/seymour_hersh_obama_cherry_picked_intelligence\" class=\"gen\">9 d\u00e9cembre 2013<\/a>), o\u00f9 il t\u00e9moigne \u00e9galement de l&rsquo;attachement des militaires \u00e0 Obama ; pourtant, le comportement d&rsquo;Obama, dans ce cas, parut \u00e0 nombre de ces personnes, et \u00e0 Hersh lui-m\u00eame, compl\u00e8tement inacceptable. (A noter que, dans ce passage, Hersh \u00e9carte l&rsquo;argument de l&rsquo;opinion publique comme principal frein \u00e0 l&rsquo;attaque de la Syrie, jugeant que l&rsquo;opposition du Pentagone fut d\u00e9terminante. Nous ne partageons nullement cette analyse : sans nier l&rsquo;importance de l&rsquo;opposition des militaires [voir, par exemple, le <a href=\"http:\/\/www.dedefensa.org\/article-une_journ_e_de_dupes_dont_il_n_est_pas_n_cessaire_d_tre_dupe_11_09_2013.html\" class=\"gen\">11 septembre 2013<\/a>], il reste que, pour nous, le climat de l&rsquo;opinion publique, se r\u00e9percutant sur la position du Congr\u00e8s, joua un r\u00f4le primordial m\u00eame si insaisissable dans les faits pr\u00e9cis, dans la volte-face en plusieurs \u00e9tapes d&rsquo;Obama [voir le <a href=\"http:\/\/www.dedefensa.org\/article-hyst_ricisme_syriana_29_08_2013.html\" class=\"gen\">29 ao\u00fbt 2013<\/a> et le <a href=\"http:\/\/www.dedefensa.org\/article-une_am_rique_antiguerre_une_am_rique_en_r_volte__10_09_2013.html\" class=\"gen\">10 septembre 2013<\/a>].) <\/p>\n<\/p>\n<p><p>\t<strong><em>Amy Goodman<\/em><\/strong>: \u00ab<em>And why this is significant today? In the end, President Obama chose not to strike Syria because the American people just overwhelmingly said no. But what this means for what&rsquo;s happening in Syria today? And also, why then did the Syrian&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<strong><em>Seymour Hersh<\/em><\/strong>: \u00ab<em>Let me interrupt you, Amy.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<strong><em>Amy Goodman<\/em><\/strong>: \u00ab<em>Yes.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<strong><em>Seymour Hersh<\/em><\/strong>: \u00ab<em>Amy, let me interrupt you. He didn&rsquo;t&#8230; I&rsquo;m telling you, he didn&rsquo;t do it because the American people said no. He knew it because he didn&rsquo;t have a case. And there was incredible opposition that will be, one of these days, written about, maybe in history books. There was incredible operation from some very, very strong-minded, constitutionally minded people in the Pentagon. That&rsquo;s the real story. I don&rsquo;t have it; I could just tell you I know it.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>And so, it wasn&rsquo;t just a case&#8230; you know, from the military&rsquo;s point of view, this was a president who many respected in many ways. There&rsquo;s many good things about Obama. There&rsquo;s a lot of things&#8230; as I said, I voted for him twice. And he&rsquo;s probably going to be the brightest president we&rsquo;re ever going to have, and maybe the best president we&rsquo;re ever going to have. The system is&#8230; doesn&rsquo;t produce always the very best, our system. But the fact of the matter is that this president was going to go to a war because he felt he had to protect what he said about a red line. That&rsquo;s what it was about, in the military&rsquo;s point of view. And that&rsquo;s not acceptable. You don&rsquo;t go to war, you don&rsquo;t throw missiles at a country, when there&rsquo;s no immediate national security to the United States. And you don&rsquo;t even talk about it in public. That&rsquo;s wrong, and that was a terrible thing to do.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl est tout de m\u00eame bon de noter enfin le grand bruit que l&rsquo;article de Hersh a provoqu\u00e9, malgr\u00e9 les quelques ann\u00e9es-lumi\u00e8re en termes de communication, comprim\u00e9es en quelques mois, qui nous s\u00e9parent des faits et des m\u00e9faits, malgr\u00e9 l&rsquo;absence d&rsquo;intentions sp\u00e9cifiquement antiSyst\u00e8me de Hersh. Il s&rsquo;agit d&rsquo;un aliment de plus pour le discr\u00e9dit du Syst\u00e8me, un renforcement du m\u00e9pris \u00e0 son \u00e9gard, du malaise et du d\u00e9sarroi dans le rang des employ\u00e9s-Syst\u00e8me malgr\u00e9 l&rsquo;impeccable fin de non-recevoir qu&rsquo;ils opposent \u00e0 toutes les v\u00e9rit\u00e9s, il s&rsquo;agit enfin d&rsquo;un renforcement de l&rsquo;attitude syst\u00e9matique, pas n\u00e9cessairement bruyante d&rsquo;ailleurs mais certainement r\u00e9siliente, qu&rsquo;il faut avoir contre toute affirmation, contre tout acte de communication de nos dirigeants, c&rsquo;est-\u00e0-dire du Syst\u00e8me,  bref, pr\u00e9sum\u00e9 menteur et dissimulateur \u00e0 120% avant qu&rsquo;en une circonstance ou l&rsquo;autre, une sorte de preuve soit apport\u00e9e selon laquelle il se r\u00e9v\u00e8le qu&rsquo;il nous a communiqu\u00e9 quelque chose d&rsquo;acceptable &#8230;<\/p>\n<\/p>\n<p><p>\t &#8230; Mais l&rsquo;article de Hersh n&rsquo;est pas seulement int\u00e9ressant par rapport \u00e0 un fait pass\u00e9 et \u00e9ventuellement par rapport \u00e0 ce qu&rsquo;il faut penser de l&rsquo;administration Obama, ou par rapport \u00e0 la confirmation de la pens\u00e9e qu&rsquo;on en a. Il intervient indirectement, comme compl\u00e9ment d&rsquo;une information qui, \u00e0 elle seule, aurait \u00e9t\u00e9 extr\u00eamement incertaine, qui se trouve ainsi renforc\u00e9e, qui peut alors \u00eatre consid\u00e9r\u00e9e en toute hypoth\u00e8se dans ses implications. Il s&rsquo;agit de <em>DEBKAFiles<\/em>, que l&rsquo;on conna\u00eet bien sur ce site.<\/p>\n<\/p>\n<p><p>\tEn ao\u00fbt, <em>DEBKAFiles<\/em> avait relay\u00e9 les versions les plus hyst\u00e9riques portant sur la responsabilit\u00e9 d&rsquo;Assad. Le but, relayant effectivement la tactique des ultras autour de Netanyahou, \u00e9tait de susciter une intervention US en Syrie, avec l&rsquo;espoir d&rsquo;impliquer l&rsquo;Iran et de parvenir \u00e0 une confrontation entre les USA et l&rsquo;Iran. Aujourd&rsquo;hui, <em>DEBKAFiles<\/em> adopte sans la moindre restriction, et par ailleurs sans s&rsquo;encombrer ni de vergogne ni de scrupules excessifs, la th\u00e8se de la responsabilit\u00e9 d&rsquo;al Qa\u00efda dans l&rsquo;attaque chimique, et cite essentiellement comme r\u00e9f\u00e9rence l&rsquo;article de Hersh, qui s&rsquo;av\u00e8re ainsi d&rsquo;une utilit\u00e9 politique inattendue. (<em>DEBKAFiles<\/em> du <a href=\"http:\/\/www.debka.com\/article\/23510\/Al-Qaeda-in-Syria-has-sarin-Russia-ready-to-deal-with-Syrian-Al-Qaeda-plot-against-Sochi-Olympics\" class=\"gen\">8 d\u00e9cembre 2013<\/a>.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>According to some reports, Al Qaeda in Syria has got hold of sarin nerve gas and is ready to use it. This was confirmed by the investigative journalist Seymor Hersh in an article he published in London on Dec. 8. He quoted a large number of American intelligence officials who said that the chemical attack on the eastern Damascus suburb of Ghouta on Aug. 21, in which more than 150 people died, may not have been carried out by Bashar Assad&rsquo;s army but by Jabhat al Nusra [Al Qaeda&rsquo;s Syrian branch].<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>A senior intelligence consultant told the reporter: Already by late May the CIA had briefed the Obama administration on al-Nusra and its work with sarin, and had sent alarming reports that another Sunni fundamentalist group active in Syria, al-Qaida in Iraq (AQI), also understood the science of producing sarin. At the time, al-Nusra was operating in areas close to Damascus, including Eastern Ghouta. DEBKAfile reports that both these organizations have enlisted many Chechen and North Caucasian members to fight in Syria.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The sources quoted by Hersh charged President Barack Obama and Secretary of State John Kerry with deliberate manipulation of intelligence. One high-level intelligence officer called the administration&rsquo;s assurances of Assad&rsquo;s responsibility a ruse. When the attack occurred, al-Nusra should have been a suspect, but the administration cherry-picked intelligence to justify a strike against Assad, according to Seymour Hersh.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<em>DEBKAFiles<\/em> d\u00e9veloppe l&rsquo;id\u00e9e de la possibilit\u00e9 d&rsquo;une coop\u00e9ration entre la Russie et Isra\u00ebl au niveau de la s\u00e9curit\u00e9 et du renseignement, \u00e0 la suite de la rencontre entre Netanyahou et Poutine \u00e0 Moscou, le 20 novembre (rencontre au cours de laquelle on aurait laiss\u00e9 de c\u00f4t\u00e9 la question iranienne, o\u00f9 les deux pays ne s&rsquo;entendent gu\u00e8re). (\u00ab<em>One was possible Russian-Israeli military and intelligence cooperation against al Qaeda elements in Syria.<\/em>\u00bb) La sp\u00e9culation est bas\u00e9e sur la crainte, sinon le constat effectif d&rsquo;un d\u00e9veloppement de l&rsquo;\u00e9quipement chimique d&rsquo;al Qa\u00efda, sur la possibilit\u00e9 d&rsquo;une attaque d&rsquo;une branche du terrorisme tch\u00e9tch\u00e8ne du sysdit al Qa\u00efda lors des JO de Sotchi en Russie, et bien entendu d&rsquo;une menace contre Isra\u00ebl \u00e0 partir de bases syriennes d&rsquo;al Qa\u00efda. (L&rsquo;hypoth\u00e8se avait d\u00e9j\u00e0 \u00e9t\u00e9 \u00e9voqu\u00e9e d&rsquo;une menace du Saoudien Bandar contre la Russie et les JO de Sotchi, d&rsquo;une attaque de groupes tch\u00e9tch\u00e8nes\/al Qa\u00efda que lui, Bandar, aurait contr\u00f4l\u00e9s [voir le <a href=\"http:\/\/www.dedefensa.org\/article-l_arabie_et_bandar_faiseurs_de_d_sordre_aux_abois_23_10_2013.html\" class=\"gen\">23 octobre 2013<\/a>]. Mais les choses ont chang\u00e9 depuis, et aussi la position de Bandar qui se rend souvent en Russie [voir le <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_le_d_sordre_apolaire_du_moyen-orient_10_11_2013.html\" class=\"gen\">10 novembre 2013<\/a>]. Bandar, qui semblait tout ma\u00eetriser en ao\u00fbt, de l&rsquo;attaque-montage chimique du 21 ao\u00fbt en Syrie aux groupes tch\u00e9tch\u00e8nes\/al Qa\u00efda, n&rsquo;est peut-\u00eatre pas, ou plus, dans cette position de ma\u00eetrise qui fait d&rsquo;ailleurs aussi bien partie de son arsenal faussaire de n\u00e9gociations, cela faisant s&rsquo;interroger sur le fondement de ses menaces du mois d&rsquo;ao\u00fbt.)<\/p>\n<\/p>\n<p><p>\tCette interpr\u00e9tation de <em>DEBKAFiles<\/em>, o\u00f9 l&rsquo;attaque chimique du 21 ao\u00fbt prend une allure si diff\u00e9rente que celle favoris\u00e9e jusqu&rsquo;ici par les Isra\u00e9liens, est renforc\u00e9e par une visite assez discr\u00e8te du ministre isra\u00e9lien des affaires \u00e9trang\u00e8res Lieberman \u00e0 Moscou le 9 d\u00e9cembre, pour des entretiens avec Lavrov. Il y a des liens sp\u00e9ciaux entre Lieberman et les Russes, pour la raison \u00e9vidente que Lieberman est un juif de Russie \u00e9migr\u00e9 en Isra\u00ebl. L&rsquo;entretien a \u00e9t\u00e9 cl\u00f4tur\u00e9 par quelques mots rapides de Lavrov, sans gu\u00e8re de d\u00e9tails. <em>PressTV.ir<\/em> donne quelques indications sur la rencontre, ce <a href=\"http:\/\/www.presstv.ir\/detail\/2013\/12\/10\/339151\/russian-israeli-fms-meet-in-moscow\/\" class=\"gen\">10 d\u00e9cembre 2013<\/a>, avec notamment la pr\u00e9cision que les conversations ont port\u00e9 notamment sur la situation en Syrie, <strong>mais aussi en Afrique du Nord<\/strong>. Cela \u00e9tablit clairement une connexion pour conclure que le sujet est bien l&rsquo;activit\u00e9 terroriste de ce qu&rsquo;on nomme al Qa\u00efda,  si le terme terrorisme est d\u00e9sormais suffisant pour la description de l&rsquo;activit\u00e9&#8230; Cette id\u00e9e doit \u00eatre gard\u00e9 \u00e0 l&rsquo;esprit pour tenter de comprendre l&rsquo;\u00e9volution de la situation g\u00e9n\u00e9rale. <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Russian Foreign Minister Sergey Lavrov and his Israeli counterpart Avigdor Lieberman met for talks in Moscow on Monday. Their meeting was held behind closed doors and there wasn&rsquo;t a press conference afterwards. However, the Russian Foreign Ministry says they discussed the situation in the Middle East in detail. Foreign Minister Lavrov and Avigdor Lieberman touched upon key aspects of the situation in the Middle East and North Africa, in particular Syria and Geneva 2 peace conference. They also discussed a number of international topics, including Iranian nuclear program.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Sergey Lavrov reiterated Russian position on solving issues in the region and Moscow&rsquo;s support for a political dialogue without foreign interference. While in Moscow, Lieberman has also taken part in a joint Russian\/ Israeli commission for trade and economic cooperation.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl semble que ces contacts entre Isra\u00e9liens et Russes et les hypoth\u00e8ses \u00e9voqu\u00e9es par <em>DEBKAFiles<\/em> alimentent l&rsquo;hypoth\u00e8se d&rsquo;un contexte nouveau, moins dans le sens g\u00e9opolitique classique de modification et d&rsquo;\u00e9volution des alliance, que dans un contexte beaucoup plus large de l&rsquo;\u00e9volution d&rsquo;une situation g\u00e9n\u00e9rale, notamment de ce qu&rsquo;on nomme terrorisme, avec \u00e9videmment l&rsquo;\u00e9volution du label al Qa\u00efda, les situations et les politiques des \u00c9tats impliqu\u00e9s pouvant \u00e9voluer, elles, selon des orientations inattendues \u00e0 mesure que le terrorisme \u00e9volue vers le d\u00e9sordre pur. Dans ce contexte, il semblerait que des conflits tels que celui de Syrie tendraient \u00e0 perdre les caract\u00e8res id\u00e9ologiques et ethnico-religieux extr\u00eamement pressants qui les ont caract\u00e9ris\u00e9s, pour eux aussi \u00e9voluer vers des situation plus caract\u00e9ris\u00e9es par ce qui se rapproche du d\u00e9sordre pur. D&rsquo;une fa\u00e7on tr\u00e8s symbolique et significative, le texte de Seymour Hersh fait le lien entre ces deux situations, caract\u00e9risant l&rsquo;une (celle qui s&rsquo;effacerait) et pr\u00e9parant l&rsquo;autre (celle qui se dessinerait).<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 11 d\u00e9cembre 2013 \u00e0 02H52<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le double \u00e9clairage du mensonge BHO-sarin La Syrie c&rsquo;est bien loin, et plus loin encore le formidable fiasco du bloc BAO et de BHO pour forcer \u00e0 une attaque contre Assad. Cela se passait en ao\u00fbt-septembre de l&rsquo;ann\u00e9e 2013&#8230; Soudain, la voix respect\u00e9e et comp\u00e9tente de Seymour Hersh, Prix Pulitzer et ma\u00eetre du journalisme d&rsquo;investigation&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3903,11462,4180,2830,4883,4173,2707,13125,4414,3867,1267],"class_list":["post-73585","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-chimique","tag-debkafiles","tag-hersh","tag-lavrov","tag-lieberman","tag-montage","tag-moscou","tag-sarin","tag-seymour","tag-syrie","tag-terrorisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73585"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73585\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}