{"id":73604,"date":"2013-12-24T10:49:29","date_gmt":"2013-12-24T10:49:29","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2013\/12\/24\/notes-sur-les-poupees-russes\/"},"modified":"2013-12-24T10:49:29","modified_gmt":"2013-12-24T10:49:29","slug":"notes-sur-les-poupees-russes","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2013\/12\/24\/notes-sur-les-poupees-russes\/","title":{"rendered":"Notes sur les poup\u00e9es russes"},"content":{"rendered":"<p><h2 class=\"common-article\">Notes sur les poup\u00e9es russes<\/h2>\n<\/p>\n<p><p>\t24 d\u00e9cembre 2013  Nous ne savions pas par quoi commencer cette analyse sur les poup\u00e9es russes (les vraies, hein, pas celles du cin\u00e9ma fran\u00e7ais globalis\u00e9 et mis \u00e0 la sauce-Syst\u00e8me de la pens\u00e9e courte qui va avec). L&rsquo;expression fameuse illustre, dans notre cas, l&#8217;empilement des succ\u00e8s russes et des r\u00e9actions furieuses, impuissantes, vitup\u00e9rantes, ivres d&rsquo;anath\u00e8mes, du bloc BAO devant cette dynamique.<\/p>\n<\/p>\n<p><p>\tFinalement, nous commen\u00e7ons simplement par le rappel de ce qui, \u00e0 notre sens, est la source de tout dans le contexte que nous d\u00e9crivons, qui est l&rsquo;esp\u00e8ce de lib\u00e9ration, par la conceptualisation de la situation Syst\u00e8me <em>versus<\/em> antiSyst\u00e8me, qu&rsquo;a constitu\u00e9 le discours de Poutine devant la <em>Douma<\/em> le 12 d\u00e9cembre. Ce discours a r\u00e9alis\u00e9 une mise en lumi\u00e8re et une identification des v\u00e9ritables adversaires qui \u00e9voluent dans la crise de l&rsquo;effondrement du Syst\u00e8me. Dans ce discours, qu&rsquo;il l&rsquo;ait voulu ou non peu importe, Poutine accepte finalement d&rsquo;assumer pleinement le parti qu&rsquo;il m\u00e8ne depuis quelques ann\u00e9es sans trop oser dire son nom. Il s&rsquo;agit de la mise en uvre symbolique de ce que nous nommons conservatisme antiSyst\u00e8me ou n\u00e9oconservatisme-poutinien par opposition directe et frontale,  v\u00e9rit\u00e9 principielle contre son inversion,  au n\u00e9oconservatisme-<em>neocon<\/em>. (Voir le <a href=\"http:\/\/www.dedefensa.org\/article-un_n_oconservatisme_antisyst_me_18_12_2013.html\" class=\"gen\">18 d\u00e9cembre 2013<\/a>.)<\/p>\n<\/p>\n<p><p>\tCela acquis nous allons observer, d&rsquo;une part 1) quelques cons\u00e9quences op\u00e9rationnelles de plus, du c\u00f4t\u00e9 russe, de cette m\u00eame dynamique initi\u00e9e par la Russie ; et 2) les effets de la prise de conscience tr\u00e8s rapide dans le bloc BAO de cette dynamique initi\u00e9e par la Russie (encore plus que par Poutine car les enjeux engagent les nations, les entit\u00e9s, les conceptions collectives, bien plus que les individus qui ne font que les traduire et les op\u00e9rationnaliser). Dans le premier cas, sur lequel nous encha\u00eenons directement, il s&rsquo;agit de donner quelques exemples les plus divers possibles d&rsquo;actions russes tr\u00e8s r\u00e9centes.<\/p>\n<h3>Poutine et l&rsquo;Ukraine<\/h3>\n<\/p>\n<p><p>\tUn premier point de vue est l&rsquo;affaire ukrainienne. Apr\u00e8s le tohu bohu des trois derni\u00e8res semaines, l&rsquo;essentiel s&rsquo;est donc pass\u00e9 la semaine derni\u00e8re \u00e0 Moscou, entre les deux pr\u00e9sidents russe et ukrainien&#8230; Depuis, la crise ukrainienne et les tentatives type R\u00e9volution orange n\u00b02 semblent avoir perdu de leur attrait pour nos vigilants commentateurs-Syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tLe commentateur indien M.K. Bhadrakumar d\u00e9crit l&rsquo;op\u00e9ration russe (sur <em>Indian PunchLine<\/em>, du <a href=\"http:\/\/blogs.rediff.com\/mkbhadrakumar\/2013\/12\/18\/russia-trumps-us-in-ukraine-poker-game\/\" class=\"gen\">18 d\u00e9cembre 2013<\/a>), en insistant principalement, et avec les meilleures raisons du monde, sur les r\u00e9actions,  ou plut\u00f4t, l&rsquo;absence de r\u00e9action du bloc BAO. En un mot, nous dit Bhadrakumar, le bloc BAO en est rest\u00e9 comme deux ronds de flanc <\/p>\n<\/p>\n<p><p>\tPour Bhadrakumar, Poutine a r\u00e9ussi l\u00e0 l&rsquo;une de ses meilleures op\u00e9rations de politique \u00e9trang\u00e8re de l&rsquo;apr\u00e8s-Guerre froide : \u00ab<em>Russia may have made its most significant foreign-policy gain in the entire post-cold war era when the Kremlin decisively moved in on Tuesday to offer a rescue package for the beleagured Ukrainian economy and may have taken a leap forward in leading that country into the Eurasian Union, which Moscow is planning as the umbrella organization bringing together the former Soviet republics.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>This is undoubtedly one of President Vladimir Putin&rsquo;s finest hours in the Kremlin. The point is, if Ukraine moves into the Western orbit, Russia falls back on its back foot in strategic terms; without Ukraine Eurasian Union remains grossly inadequate; with Ukraine the Eurasian Union all but restores the Soviet Union in politico-economic terms. Unsurprisingly, the West is aghast, and the mood of the cold warriors can&rsquo;t be uglier than this. Russia is beating the West at its own game of cheque book diplomacy. No need for Russian tanks to roll into the streets of Kiev as in 1956 in Budapest.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>The European Union foreign ministers have unceremoniously come down from the high pedestal from where they preached to Ukraine on the virtues of human rights record and western liberal democracy and pleaded it is prepared to sign an Association at a special summit this very week if only President Yanukovich is willing. But it seems a case of too little too late. Washington too is left mumbling for words, not knowing what to say. All that the West is left with now are the protestors from western regions of Ukraine on the Kiev city square. Can the CIA push a color revolution through? This remains the only ray of hope.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The poignancy lies in this that neither the US nor the EU has any money (or the political will to find the money) to help ease Ukraine&rsquo;s staggering debt burden. Whereas, Russia is offering financial support of $15 billion and the slashing of the price of natural gas sold to Ukraine by one-third and adjusting the outstanding debt of $2 billion that Kiev owes to Gazprom for past transactions.<\/em>\u00bb <\/p>\n<h3>La lib\u00e9ration de Mikha\u00efl Khodorkovski<\/h3>\n<\/p>\n<p><p>\tReportons-nous \u00e0 un autre \u00e9pisode, encore plus r\u00e9cent, qui est la lib\u00e9ration de Mikha\u00efl Khodorkovski. L&rsquo;op\u00e9ration, conjointement avec une amnistie accord\u00e9e aux <em>Pussy Riot<\/em> et aux personnes emprisonn\u00e9es dans l&rsquo;op\u00e9ration <em>Greenpeace<\/em> en Artique, s&rsquo;est d\u00e9roul\u00e9e \u00e0 la satisfaction des Russes et selon une tactique de relations publiques habile. (Les Russes apprennent vite des ma\u00eetres en RP du bloc BAO.) Malgr\u00e9 la <em>narrative<\/em> droitdel&rsquo;hommiste grotesque mont\u00e9e autour de lui, Khodorkovski reste un personnage de milliardaire interlope, dont l&rsquo;\u00e9tat r\u00e9el de capitaliste sauvage ayant commis de nombreuses malversations a \u00e9t\u00e9 reconnu par la Cour Europ\u00e9enne des droits de l&rsquo;homme. L&rsquo;\u00e9cho rencontr\u00e9 par cette lib\u00e9ration de Khodorkovski en fonction de ce qu&rsquo;est le personnage r\u00e9duit l&rsquo;\u00e9cho des autres lib\u00e9rations et fragilise \u00e0 mesure l&rsquo;argument classique de la mise en accusation morale du r\u00e9gime,  savoir, que ces lib\u00e9rations constitueraient une preuve de faiblesse et appelleraient d&rsquo;autres lib\u00e9rations, surtout qu&rsquo;elles mettraient en \u00e9vidence son caract\u00e8re oppressif.<\/p>\n<\/p>\n<p><p>\tCette logique invertie,  les actes pos\u00e9s confirment le contraire de ce qu&rsquo;ils signifient,  est g\u00e9n\u00e9rale dans la presse-Syst\u00e8me antirusse, une sorte de classique dans l&rsquo;inversion. (On trouve cette logique exprim\u00e9e dans cet remarque en passant du commentateur Nick Cohen de <em>The Observer<\/em> [voir plus loin, plus en d\u00e9tails] : \u00ab<em>At home, his control over the state and civil society is so complete that he can afford to play the merciful tsar and release dissidents and his former rival Mikhail Khodorkovsky<\/em>\u00bb,  autrement dit, cette mesure lib\u00e9rale est une preuve indubitable que Poutine est un autocrate absolu.) Cette fois, l&#8217;emploi de cet argument n&rsquo;a pas l&rsquo;efficacit\u00e9 habituelle, toujours gr\u00e2ce au personnage de Khodorkovski qui domine la s\u00e9quence.<\/p>\n<h3>Le r\u00f4le de Hans-Dietrich Genscher <\/h3>\n<\/p>\n<p><p>\tLes retomb\u00e9es pol\u00e9miques \u00e9tant minimis\u00e9es contre l&rsquo;avantage du geste pos\u00e9, l&rsquo;essentiel de la d\u00e9marche revient \u00e0 la signification de la lib\u00e9ration de Khodorkovski qui constituerait cet avantage. L&rsquo;\u00e9v\u00e9nement est diversement appr\u00e9ci\u00e9 du point des avantages et des inconv\u00e9nients pour Poutine, mais ses inconv\u00e9nients sont de toutes les fa\u00e7ons limit\u00e9s par la personnalit\u00e9 de Khodorkovski, avec ses diverses casseroles de capitaliste sans foi ni loi.<\/p>\n<\/p>\n<p><p>\tFinalement, l&rsquo;op\u00e9ration s&rsquo;annonce plut\u00f4t avantageuse, d&rsquo;abord parce que Khodorkovski ne semble pas devoir \u00eatre utilis\u00e9 par l&rsquo;opposition \u00e0 Poutine \u00e0 cause de l&rsquo;annonce qu&rsquo;il ne pr\u00e9voit pas de faire de politique. Surtout, l&rsquo;op\u00e9ration s&rsquo;annonce avantageuse pour les relations de la Russie avec l&rsquo;Allemagne, puisque l&rsquo;Allemagne a jou\u00e9 un r\u00f4le central dans cette lib\u00e9ration, essentiellement par l&rsquo;interm\u00e9diaire de l&rsquo;ancien ministre des affaires \u00e9trang\u00e8res Hans-Dietrich Genscher de 1974 \u00e0 1992. <\/p>\n<\/p>\n<p><p>\t&#8230; D&rsquo;o\u00f9 ces observations, dans <em>Russia Today<\/em>, le <a href=\"http:\/\/rt.com\/news\/khodorkovsky-arrive-germany-berlin-560\/\" class=\"gen\">20 d\u00e9cembre 2013<\/a> : \u00ab<em>Germany&rsquo;s government has issued a statement saying that Chancellor Angela Merkel has welcomed Khodorkovsky&rsquo;s release. Former FM Genscher described the move as significant and very encouraging. The statement issued by Genscher&rsquo;s spokesperson revealed the joint efforts of both the former FM and Chancellor Angela Merkel aimed at securing the release of Khodorkovsky. Genscher had met Putin in person twice to talk about Khodorkovsky and Markel has repeatedly lobbied the Russian president for Mr Khodorkovsky&rsquo;s release over the last few years, the official statement said.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEt surtout ce dialogue extrait d&rsquo;une interview d&rsquo;Alexander Rahr, analyste politique qui conseilla Genscher dans cette affaire et servit m\u00eame d&rsquo;interpr\u00e8te entre Genscher et Khodorkovski (le premier \u00e9tant venu accueillir le second apr\u00e8s sa lib\u00e9ration \u00e0 l&rsquo;a\u00e9roport de Berlin). (Voir encore <em>Russia Today<\/em>, le <a href=\"http:\/\/rt.com\/news\/khodorkovsky-alexander-rahr-interview-621\/\" class=\"gen\">21 d\u00e9cembre 2013<\/a>) :<\/p>\n<\/p>\n<p><p>\t<strong><em>Russia Today<\/em><\/strong> : \u00ab<em>Do you think that Genscher&rsquo;s involvement was somehow influential to the resolution of this issue?<\/em>\u00bb <\/p>\n<\/p>\n<p><p>\t<strong><em>Alexander Rahr<\/em><\/strong> : \u00ab<em>I think that Genscher&rsquo;s role was key in the release of Khodorkovsky. Without Genscher playing this role, Khodorkovsky might not have been released. I would go so far and say it because Genscher really worked hard, meeting with Putin, meeting with other Russian officials in a very soft manner. And he was also accepted in this role by Khodorkovsky, who knew him from previous years when Khodorkovsky came to the German Council on Foreign Relations. And also because Genscher has so much trust in Russia and in Germany. He&rsquo;s very close to Angela Merkel. <\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>He was, of course, very close to Westerwelle. He could use the Ministry of Foreign Affairs for his tasks and also other German ministries. And, of course, the Russian elite very well remember his very positive role in the reunification of Germany after the fall of the<\/em> [<em>Berlin<\/em>] <em>Wall, whole support for Russia, which was given to Gorbachev and Yeltsin in the beginning of the 1990s.<\/em>\u00bb [&#8230;]<\/p>\n<\/p>\n<p><p>\t<strong><em>Russia Today<\/em><\/strong> : \u00ab<em>What meaning does the release of Khodorkovsky has for relations between Russia and Germany?<\/em>\u00bb <\/p>\n<\/p>\n<p><p>\t<strong><em>Alexander Rahr<\/em><\/strong> : \u00ab<em>He was a stumbling block in the relations. The Khodorkovsky matter came up at all negotiations all the time between politicians, but also in the civil dialogue, which happened between Germany and Russia.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>The Khodorkovsky release takes away a very problematic point from the agenda. Since the German government said recently that it wants a reset in the relations with Russia or at least an attempt for a reset in the relations with Moscow. Now this gesture, which followed  the release of Khodorkovsky  may have been a positive response to a positive gesture by the Germans, now from the Russians.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tOn d\u00e9couvre donc \u00e0 cette occasion de la mise en \u00e9vidence de  l&rsquo;importance du r\u00f4le de Genscher dans l&rsquo;affaire Khodorkovski, le r\u00f4le jou\u00e9 par Genscher dans la politique allemande, sa proximit\u00e9 de Merkel et l&rsquo;influence qu&rsquo;il exerce sur elle. Genscher \u00e9tant ce qu&rsquo;il est et ce qu&rsquo;il fut (un partisan d&rsquo;une affirmation allemande marqu\u00e9e, y compris avec une r\u00e9affirmation de souverainet\u00e9), on peut admettre que son influence aupr\u00e8s de Merkel qui doit \u00eatre aujourd&rsquo;hui au z\u00e9nith apr\u00e8s la r\u00e9ussite de l&rsquo;affaire va dans le sens d&rsquo;une affirmation allemande passant par un distanciement notable des USA (NSA oblige) et, par voie de cons\u00e9quence politique naturelle dans ce contexte qu&rsquo;on d\u00e9crit, un rapprochement de la Russie. L\u00e0 pourrait se trouver le v\u00e9ritable int\u00e9r\u00eat de l&rsquo;affaire Khodorkovski, qui renforce et compl\u00e8te (en ajoutant l&rsquo;\u00e9l\u00e9ment des relations avec la Russie) l&rsquo;id\u00e9e exprim\u00e9e le <a href=\"http:\/\/www.dedefensa.org\/article-de_l_allemagne-2014_20_12_2013.html\" class=\"gen\">20 d\u00e9cembre 2013<\/a> d&rsquo;une Allemagne-2014. <\/p>\n<h3>Le rire de Poutine<\/h3>\n<\/p>\n<p><p>\tIl faut aussi noter une \u00e9volution dans le comportement des dirigeants russes, qui concerne une psychologie de plus en plus lib\u00e9r\u00e9e des complexes russes vis-\u00e0-vis de l&rsquo;Occident et du bloc BAO, ces complexes russes h\u00e9rit\u00e9s de la Guerre froide et de l&rsquo;imm\u00e9diat apr\u00e8s-Guerre froide. Cela se remarque beaucoup plus dans certains d\u00e9tails, ou certains instants de lib\u00e9ration du langage qu&rsquo;on ne cherche m\u00eame plus \u00e0 dissimuler, au milieu d&rsquo;un discours g\u00e9n\u00e9ral que les Russes continuent \u00e0 contr\u00f4ler dans le sens de la mesure. <\/p>\n<\/p>\n<p><p>\t Voir et \u00e9couter par exemple Poutine r\u00e9pondant \u00e0 une question d&rsquo;un journaliste sur l&rsquo;argument grotesque et otanien \u00e0 la fois des antimissiles (BMDE) d\u00e9ploy\u00e9s en Europe, \u00e0 la fronti\u00e8re de la Russie, pour s&rsquo;opposer aux terribles forces balistiques intercontinentales de l&rsquo;Iran (voir <a href=\"https:\/\/www.youtube.com\/watch?v=4i6nPNpR6PA\" class=\"gen\"> la s\u00e9quence<\/a> sur <em>YouTube<\/em>). La s\u00e9quence dure 1 minute 20, la question prend 5 secondes, la r\u00e9ponse de Poutine le reste, mais elle commence par 15 \u00e0 20 secondes d&rsquo;un rire franc et massif de d\u00e9rision pour l&rsquo;argument expos\u00e9, ponctu\u00e9 par un vous m&rsquo;avez bien fait rire, cela d\u00e9tend apr\u00e8s une journ\u00e9e de travail (devant la mine \u00e9bahie du journaliste). La m\u00eame attitude de Poutine se retrouve dans sa conf\u00e9rence de presse-mammouth devant plus d&rsquo;un millier de journalistes du <a href=\"http:\/\/rt.com\/news\/putin-press-conference-updates-453\/\" class=\"gen\">18 d\u00e9cembre 2013<\/a>. R\u00e9pondant \u00e0 une question sur l&rsquo;espionnage de la NSA,  qu&rsquo;il ne condamne pas par ailleurs, en bon ancien analyste du KGB (il rappelle \u00e0 cette occasion son exp\u00e9rience),  il commence par une remarque assez leste, que l&rsquo;on ne dut gu\u00e8re appr\u00e9cier dans les milieux concern\u00e9s, sur l&rsquo;impunit\u00e9 grossi\u00e8re dont disposent les USA dans toutes leurs activit\u00e9s subversives. (Cette remarque \u00e0 l&#8217;emporte-pi\u00e8ce est bien de la d\u00e9rision pure sur le comportement US, qui concerne effectivement l&rsquo;absence de cons\u00e9quence juridique et personnelle des personnes concern\u00e9es, l&rsquo;observation de l&rsquo;absence de cons\u00e9quences ne portant nullement sur la situation diplomatique,  voir l&rsquo;\u00e9volution de l&rsquo;Allemagne, celle du Br\u00e9sil.) D&rsquo;apr\u00e8s <em>Russia Today<\/em> le <a href=\"http:\/\/rt.com\/news\/putin-snowden-press-conference-487\/\" class=\"gen\">18 d\u00e9cembre 2013<\/a> :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>I envy Obama because he can spy on his allies without any consequences, said Putin when asked about how his relations had changed with the US following Snowden&rsquo;s espionage revelations&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t On notera \u00e9galement une observation de Lavrov, parlant lui aussi des activit\u00e9s de la NSA, et avan\u00e7ant la comparaison du comportement de l&rsquo;agence tel que la crise Snowden\/NSA le met en \u00e9vidence avec les pratiques du NKVD de Staline dans sa p\u00e9riode la plus terrible,  la Grande Terreur, ou <em>I\u00e9jovtchina<\/em> des ann\u00e9es 1937-1939. Cette simple analogie par son poids de r\u00e9f\u00e9rence \u00e0 une p\u00e9riode d&rsquo;une extr\u00eame violence et d&rsquo;une oppression politique extraordinaire, c&rsquo;est l&rsquo;attaque la plus spectaculaire lanc\u00e9e contre la NSA par un haut dirigeant russe, et une attaque agressive, d\u00e9barrass\u00e9e de toute pr\u00e9caution diplomatique, montrant justement cette lib\u00e9ration psychologique des dirigeants russes vis-\u00e0-vis de leurs partenaires et amis du bloc BAO&#8230; (<em>Russia Today<\/em>, le <a href=\"http:\/\/rt.com\/news\/lavrov-nsa-private-life-427\/\" class=\"gen\">18 d\u00e9cembre 2013<\/a>.) <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Russia&rsquo;s Foreign Minister has compared the way NSA obtains permission for its surveillance with the way Soviet people received sentences in Stalin-era courts. Sergey Lavrov said the judicial entities which gave permission for NSA surveillance reminded him of troikas, or extrajudicial bodies that existed in the Soviet Union during the Great Purge of 1937-38. They consisted of only three people who passed sentences very quickly, based on very scanty evidence. \u00ab\u00a0Without any control, they just dropped their signatures on inquiries the NSA representatives brought them, Lavrov said, while speaking Wednesday at Russia&rsquo;s upper house of parliament, the Federation Council, Interfax reported.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Sergey Lavrov has spoken of the NSA activity as of unlimited and uncontrolled intervention into private lives. It is necessary to draw a distinctive borderline between what law enforcement agencies really need for carrying out their work, for protecting citizens, and what appears to be intrusion into private life without any limits and control. And it&rsquo;s exactly the latter, as far as I understand, which took place in the case with the American NSA, Lavrov said.<\/em>\u00bb<\/p>\n<h3>Fureur et \u00e9volution de la psychologie<\/h3>\n<\/p>\n<p><p>\tNous tenions \u00e0 mettre en \u00e9vidence ces instants r\u00e9v\u00e9lateurs, disons ces petits faits psychologique, en nous r\u00e9f\u00e9rant \u00e0 l&rsquo;expression de Stendhal, qui mesurent la r\u00e9alit\u00e9 d&rsquo;une \u00e9volution profonde, psychologique \u00e9galement bien s\u00fbr, cette psychologie de plus en plus lib\u00e9r\u00e9e des complexes russes vis-\u00e0-vis de l&rsquo;Occident et du bloc BAO, ces complexes russes h\u00e9rit\u00e9s de la Guerre froide et de l&rsquo;imm\u00e9diat apr\u00e8s-Guerre froide. C&rsquo;est un facteur r\u00e9v\u00e9lateur d&rsquo;une \u00e9volution importante de la situation de la Russie dans le sens de l&rsquo;affirmation d&rsquo;une ma\u00eetrise nouvelle, et, surtout, d&rsquo;une sorte de l\u00e9gitimit\u00e9 \u00e0 la fois de sa position, de sa politique et de sa critique globale de la politique g\u00e9n\u00e9rale du bloc BAO.<\/p>\n<\/p>\n<p><p>\tPour le reste, qui est une partie essentielle de l&rsquo;analyse, nous avan\u00e7ons l&rsquo;hypoth\u00e8se que le discours de Poutine (voir le <a href=\"http:\/\/www.dedefensa.org\/article-un_n_oconservatisme_antisyst_me_18_12_2013.html\" class=\"gen\">18 d\u00e9cembre 2013<\/a>), qui acte l&rsquo;id\u00e9ologisation de l&rsquo;\u00c9tat selon F\u00e9dor Loukianov, et qui est plut\u00f4t, selon nous, une mis en forme conceptuelle d&rsquo;une perception principielle du monde, constitue un symbole d&rsquo;une puissance extr\u00eame, qui ent\u00e9rine en un moment d&rsquo;une tr\u00e8s grande intensit\u00e9 l&rsquo;\u00e9volution russe de ces trois derni\u00e8res ann\u00e9es, face au d\u00e9cha\u00eenement surpuissance-autodestruction de l&rsquo;Ouest devenue <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_bloc_bao_10_12_2012.html\" class=\"gen\">bloc BAO<\/a>. Ce symbole et le concept qu&rsquo;il recouvre constituent ainsi une \u00e9tape capitale, moins dans l&rsquo;\u00e9volution de la Russie d&rsquo;ailleurs que, par des cons\u00e9quences indirectes, dans l&rsquo;\u00e9volution du Syst\u00e8me. Cela nous conduit \u00e0 encha\u00eener directement sur le deuxi\u00e8me point signal\u00e9 plus haut (les effets et la conscience naissante et tr\u00e8s rapide dans le bloc BAO de cette dynamique initi\u00e9e par la Russie) : il s&rsquo;agit de la fureur apocalyptique du bloc BAO, des \u00e9lites-Syst\u00e8me, bref et puissamment dit,  du Syst\u00e8me lui-m\u00eame.<\/p>\n<h3>La russophobie en frustration-<em>turbo<\/em><\/h3>\n<\/p>\n<p><p>\tAinsi doit-on juger remarquable le texte de Nick Cohen (d\u00e9j\u00e0 cit\u00e9 plus haut), dans <em>The Observer<\/em> (<em>The Guardian<\/em>) du <a href=\"http:\/\/www.theguardian.com\/commentisfree\/2013\/dec\/22\/vladimir-putin-authoritarianism-russia\" class=\"gen\">22 d\u00e9cembre 2013<\/a>. L&rsquo;article n&rsquo;est pas pessimiste, il est en un sens apocalyptique, pr\u00e9sentant l&rsquo;ann\u00e9e 2013 comme celle du triomphe du Diable incarn\u00e9, de ce Poutine qui ne cesse de prendre l&rsquo;Ouest \u00e0 contrepied (\u00ab<em>Vladimir Putin is outflanking the west at every turn<\/em>\u00bb). En ce sens, l&rsquo;article de Cohen exprime aussi bien la rage et la frustration du <em>Guardian<\/em>, symbole m\u00eame pour ce cas de la russophobie \u00e0 la fois visc\u00e9rale et repr\u00e9sentative de la position du Syst\u00e8me des \u00e9lites du bloc BAO. (L&rsquo;ubiquit\u00e9 du <em>Guardian<\/em>, qui a assur\u00e9 un relais puissant et efficace de la crise Snowden\/NSA et qui constitue le meilleur relais antirusse du Syst\u00e8me, illustre d&rsquo;ailleurs assez bien le d\u00e9sordre des options politiques que les \u00e9lites-Syst\u00e8me les plus sophistiqu\u00e9es d\u00e9veloppent simultan\u00e9ment sans en mesurer les effets contradictoires : si le <em>Guardian<\/em> ne nous avait pas servi Snowden sur un plateau, il n&rsquo;aurait pas donn\u00e9 l&rsquo;occasion \u00e0 Poutine-Lavrov d&rsquo;exp\u00e9rimenter une telle lib\u00e9ration psychologique par rapport \u00e0 la pression \u00e9touffante de la vertu occidentale h\u00e9rit\u00e9e de la p\u00e9riode de la Guerre froide et de l&rsquo;imm\u00e9diat apr\u00e8s-Guerre froide.)<\/p>\n<\/p>\n<p><p>\tPlus que tout, Nick Cohen a bien vu l&rsquo;aspect internationaliste qu&rsquo;implique la posture du n\u00e9oconservatisme-poutinien (et il ne manque pas de citer Pat Buchanan [voir le <a href=\"http:\/\/www.dedefensa.org\/article-question_de_fond_is_putin_one_of_us__18_12_2013.html\" class=\"gen\">18 d\u00e9cembre 2013<\/a>], dont le texte r\u00e9f\u00e9renc\u00e9 constitue effectivement un signal de ralliement de type conservateurs\/pal\u00e9oconservateurs de tous les pays, unissez-vous) : \u00ab<em>This has been the year of Vladimir Putin&rsquo;s ascendancy&#8230;<\/em> [&#8230;] <em>Forbes magazine was not making a mistake when it called Putin the world&rsquo;s most powerful person in 2013. However, the Centre for Strategic Communications, a thinktank for the Kremlin&rsquo;s pet intellectuals, assessed his power more precisely last week when it acclaimed him world conservatism&rsquo;s new leader&#8230;<\/em> [&#8230;] <em>Putin is giving every sign that he wants Orthodox Russia to repel the satanic west again&#8230;<\/em> [&#8230;] <em>In his state-of-the-nation address last week, Putin sounded like the most slavophile of patriarchs when he derided the liberal west as genderless and infertile and promised he would fight the western elite&rsquo;s destruction of traditional values from the top.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>If you think that makes him sound like a Christian Coalition or Muslim Brotherhood cleric, well that thought has struck others too. The leathery old American conservative Pat Buchanan, who has been involved in every foul movement on the American right since Richard Nixon&rsquo;s day, knows a potential collaborator when he sees one. Putin could be the leader of conservatives and traditionalists in every country, he said, and lead the fight against the militant secularism of a multicultural and transnational elite&#8230;<\/em><\/p>\n<h3>L&rsquo;Internationale [n\u00e9o]conservatrice<\/h3>\n<\/p>\n<p><p>\tNick Cohen cite dans son texte un collaborateur de <em>Radio Free Europe\/Radio Liberty<\/em>, le Britannique Brian Whitmore, le <a href=\"http:\/\/www.rferl.org\/articleprintview\/25206293.html\" class=\"gen\">19 d\u00e9cembre 2013<\/a>. L\u00e0 aussi, mais en plus accentu\u00e9, sont repris les traits d&rsquo;une description de la r\u00e9surgence d&rsquo;une nouvelle internationale dont tout dans le charabia employ\u00e9 indique qu&rsquo;elle renvoie \u00e0 la p\u00e9riode d\u00e9sormais hyper-diabolis\u00e9e du communisme du XXe si\u00e8cle.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Vladimir Putin is calling on the conservatives of the world to unite  behind him. The Kremlin leader&rsquo;s full-throated defense of Russia&rsquo;s traditional values and his derision of the West&rsquo;s genderless and infertile liberalism in his annual state-of-the-nation address last week was just the latest example of Putin attempting to place himself at the vanguard of a new Conservative International.<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>\t\u00bb<em>And just days before Putin&rsquo;s address, the Center for Strategic Communications, an influential Kremlin-connected think tank, held a press conference in Moscow to announce its latest report. The title: Putin: World Conservatism&rsquo;s New Leader. According to excerpts from the report cited in the media, most people yearn for stability and security, favor traditional family values over feminism and gay rights, and prefer nation-based states rather than multicultural melting pots. Putin, the report says, stands for these values while ideological populism of the left in the West is dividing society. Against the backdrop of a difficult economic situation, people are becoming more prudent,\u00a0\u00bb Dmitry Abzalov of the Center for Strategic Communications said at the news conference. It is important for most people to preserve their way of life, their lifestyle, their traditions. So they tend toward conservatism. This is normal. This, Abzalov added, represented a global trend.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The Kremlin apparently believes it has found the ultimate wedge issue to unite its supporters and divide its opponents, both in Russia and the West, and garner support in the developing world. They seem to believe they have found the ideology that will return Russia to its rightful place as a great power with a messianic mission and the ability to win hearts and minds globally. As the West becomes increasingly multicultural, less patriarchal and traditional, and more open to gay rights, Russia will be a lodestone for the multitudes who oppose this trajectory. Just as the Communist International, or Comintern, and what Soviet ideologists called the correlation of forces sought to unite progressive elements around the globe behind Moscow, the world&rsquo;s traditionalists will now line up behind Putin&#8230;<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>\t\u00bb<em>It is a mistake to believe that Putin wants to lower a new Iron Curtain, build a new Berlin Wall and pursue a policy of isolationism, <\/em> [<em>political analyst Aleksandr<\/em>] <em>Morozov wrote in Colta.ru. On the contrary, Putin is creating a new Comintern. This is not isolationism, but rather the maximum Putinization of the world. The Comintern was a complex system that worked with ideologically sympathetic intellectuals and politicians. What we are seeing now is not an attempt to restore the past, but the creation of an entirely new hegemony.<\/em>\u00bb<\/p>\n<h3>Le r\u00f4le de la Russie<\/h3>\n<\/p>\n<p><p>\tLes attaques contre Poutine et la Russie venant de ces milieux lib\u00e9raux, globalistes, multiculturels, etc., sont \u00e0 la fois \u00e9tranges et logiques, pleins de contradictions historiques et pleins de la juste reconnaissance que Poutine est le dirigeant n\u00e9cessairement le plus antiSyst\u00e8me qui soit. Elles marquent plus le d\u00e9sarroi o\u00f9 l&rsquo;offensive du n\u00e9oconservatisme-poutinien les met, qu&rsquo;elles ne leur inspirent une strat\u00e9gie de d\u00e9fense dans un paysage-Syst\u00e8me d\u00e9vast\u00e9 (il faut lire les appr\u00e9ciations furieuses et m\u00e9prisantes de Cohen \u00e0 l&rsquo;encontre de la passivit\u00e9 et de la faiblesse d&rsquo;un Obama). Elles mesurent l&rsquo;avanc\u00e9e du ph\u00e9nom\u00e8ne surpuissance-autodestruction, car Dieu sait si le Syst\u00e8me a fait \u00e9talage de sa surpuissance notamment antirusse au moins depuis la fin de la Guerre froide, et Dieu sait si les r\u00e9sultats obtenus montrent une d\u00e9structuration et une dissolution acc\u00e9l\u00e9r\u00e9es des positions et des convictions psychologiques asservies au Syst\u00e8me&#8230;<\/p>\n<\/p>\n<p><p>\tC&rsquo;est un facteur r\u00e9v\u00e9lateur d&rsquo;une \u00e9volution importante de la situation de la Russie dans le sens de l&rsquo;affirmation d&rsquo;une ma\u00eetrise nouvelle, et, surtout, d&rsquo;une sorte de l\u00e9gitimit\u00e9 \u00e0 la fois de sa position, de sa politique et de sa critique globale de la politique g\u00e9n\u00e9rale du bloc BAO, \u00e9crivons-nous plus haut \u00e0 propos de ce que nous percevons de l&rsquo;\u00e9volution psychologique des dirigeants russes. En ce sens, la posture et l&rsquo;\u00e9volution actuelle de la Russie est \u00e9videmment absolument antiSyst\u00e8me, et elle est de plus en plus structurellement antiSyst\u00e8me. Pour autant et encore une fois,  nous ne cessons de r\u00e9p\u00e9ter cela \u00e0 chaque occasion,  <strong>cela ne signifie absolument pas<\/strong> que la Russie est une alternative, ni m\u00eame qu&rsquo;elle est en-dehors du Syst\u00e8me. (L&rsquo;\u00e9vidence, selon nous, ne cesse de le proclamer : aujourd&rsquo;hui d&rsquo;une fa\u00e7on voyante et furieuse, comme hier d&rsquo;une fa\u00e7on moins \u00e9vidente dans la p\u00e9riode du dernier demi-si\u00e8cle, nul ne peut \u00eatre en-dehors du Syst\u00e8me et c&rsquo;est pourquoi nous ne cessons d&rsquo;affirmer qu&rsquo;<strong>on ne peut vaincre le Syst\u00e8me si l&rsquo;on n&rsquo;est pas le Syst\u00e8me soi-m\u00eame<\/strong> [voir le <a href=\"http:\/\/www.dedefensa.org\/article-un_n_oconservatisme_antisyst_me_18_12_2013.html\" class=\"gen\">18 d\u00e9cembre 2013<\/a>]. Cela revient effectivement \u00e0 dire que seul le Syst\u00e8me peut se d\u00e9truire [s&rsquo;autod\u00e9truite] ; il s&rsquo;y emploie avec z\u00e8le.)<\/p>\n<\/p>\n<p><p>\tLe r\u00f4le m\u00e9tahistorique de Poutine et de la Russie n&rsquo;est donc \u00e9videmment pas de tenter de d\u00e9truire le Syst\u00e8me (ils ne le peuvent en aucune mani\u00e8re puisque, comme on a vu, ils en font partie et ne peuvent pr\u00e9tendre \u00e0 sa surpuissance), c&rsquo;est de fa\u00e7on tr\u00e8s diff\u00e9rente de susciter sa fureur et son d\u00e9sarroi pour l&rsquo;inciter, le Syst\u00e8me, \u00e0 d\u00e9velopper encore plus sa surpuissance. Il n&rsquo;est pas n\u00e9cessaire que Poutine et la Russie soient conscients de cette strat\u00e9gie puisque cette strat\u00e9gie se d\u00e9veloppe d&rsquo;elle-m\u00eame, qu&rsquo;elle est naturelle \u00e0 la dynamique g\u00e9n\u00e9rale du Syst\u00e8me qui ne r\u00e9pond certainement pas, ni \u00e0 des consignes humaines, ni \u00e0 une volont\u00e9 humaine. Simplement, on observera en jugeant cela comme une occurrence plut\u00f4t logique et vertueuse, du c\u00f4t\u00e9 de notre jugement principiel des choses, que la Russie est, dans ce cas, dans son r\u00f4le historique et m\u00e9tahistorique incontestable. (Ce r\u00f4le que Nick Cohen d\u00e9nonce avec fureur en croyant fournir l&rsquo;argument final de la condamnation de la Russie,  ce qui est juste dans sa logique invertie,  lorsqu&rsquo;il \u00e9crit de sa plume rageuse : \u00ab<em>To true believers, the Third Rome of Christian tsarism defended the divinely ordained old order against the threats of liberalism, socialism, nationalism and modernity.<\/em>\u00bb)<\/p>\n<h3>Le Syst\u00e8me, de plus en plus fort&#8230;<\/h3>\n<\/p>\n<p><p>\tCe que nous montre cette situation, c&rsquo;est la preuve une fois de plus d\u00e9velopp\u00e9e du lien indissoluble que l&rsquo;\u00e9quation surpuissance-autodestruction impose. La surpuissance sans cesse en augmentation du Syst\u00e8me n&rsquo;est pas un gage de puissance selon l&rsquo;entendement humain de la chose mais une op\u00e9rationnalisation de son impuissance selon l&rsquo;effet cosmique de la chose : plus le Syst\u00e8me active sa surpuissance, plus il active le d\u00e9sordre en g\u00e9n\u00e9ral, \u00e0 l&rsquo;ext\u00e9rieur certes,  mais l&rsquo;ext\u00e9rieur de quoi puisque le Syst\u00e8me est notre Tout aujourd&rsquo;hui ? Et ainsi, le d\u00e9sordre s&rsquo;\u00e9tendant, se tordant, revenant sur lui-m\u00eame et vers sa source principale sans rencontrer d&rsquo;obstacles puisque le Syst\u00e8me est partout chez lui ; d\u00e9sordre qui, \u00e0 force de se d\u00e9velopper de la sorte, frappe de plus en plus, en retour, le cur du Syst\u00e8me lui-m\u00eame. (Le cas Snowden, <strong>enfant r\u00e9volt\u00e9 de la surpuissance de la NSA<\/strong>,  peut-on r\u00eaver meilleur <em>blowback<\/em> autodestructeur de la surpuissance ? Mais aussi l&rsquo;\u00e9volution russe : si le bloc BAO avait agi avec raison, respectant ses engagements de non-extension de l&rsquo;OTAN en 1992, s&rsquo;abstenant de ses men\u00e9es subversives de d\u00e9sordre comme les r\u00e9volutions de couleur, s&rsquo;abstenant des aventures libyenne et syrienne, bref tout ce que <strong>produit vainement<\/strong> sa surpuissance pour parvenir \u00e0 son impuissance, o\u00f9 croit-on que serait la Russie sinon en fid\u00e8le compl\u00e9ment-Syst\u00e8me du bloc BAO, sinon int\u00e9gr\u00e9e dans le bloc BAO ?)<\/p>\n<\/p>\n<p><p>\tAinsi, plus le Syst\u00e8me exprime sa surpuissance, plus il active son autodestruction&#8230; Ainsi soit-il,  et qui dit avec d\u00e9couragement voyez, le Syst\u00e8me est de plus en plus fort, celui-l\u00e0 nous dit simplement : Voyez, le Syst\u00e8me alimente de plus en plus son autodestruction.<\/p>\n<\/p>\n<p><p>\tAinsi soit-il, <em>bis repetita placent <\/em>&#8230;<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur les poup\u00e9es russes 24 d\u00e9cembre 2013 Nous ne savions pas par quoi commencer cette analyse sur les poup\u00e9es russes (les vraies, hein, pas celles du cin\u00e9ma fran\u00e7ais globalis\u00e9 et mis \u00e0 la sauce-Syst\u00e8me de la pens\u00e9e courte qui va avec). L&rsquo;expression fameuse illustre, dans notre cas, l&#8217;empilement des succ\u00e8s russes et des r\u00e9actions&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[4646,5474,5264,4314,3089,15484,15485,2830,2691,916,3099,15486,12224,12055,1296],"class_list":["post-73604","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-antisysteme","tag-bhadrakumar","tag-blowback","tag-bmde","tag-cohen","tag-genscher","tag-khodorkovski","tag-lavrov","tag-nick","tag-poutine","tag-psychologie","tag-rahr","tag-snowden","tag-surpuissance-autodestruction","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73604"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73604\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}