{"id":73640,"date":"2014-01-17T07:27:27","date_gmt":"2014-01-17T07:27:27","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/01\/17\/une-nouvelle-rubrique-pour-dedefensaorg\/"},"modified":"2014-01-17T07:27:27","modified_gmt":"2014-01-17T07:27:27","slug":"une-nouvelle-rubrique-pour-dedefensaorg","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/01\/17\/une-nouvelle-rubrique-pour-dedefensaorg\/","title":{"rendered":"Une nouvelle rubrique pour <em>dedefensa.org<\/em>"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Une nouvelle rubrique pour <em>dedefensa.org<\/em><\/h3>\n<\/p>\n<p><p>\tNotre site<em>dedefensa.org<\/em> a subi depuis son origine diverses modifications dans sa structure et dans son contenu, qui constituent \u00e9videmment le processus naturel de maturation d&rsquo;un ensemble recherchant \u00e0 la fois la diversit\u00e9 et la compl\u00e9mentarit\u00e9 de ses rubriques pour enrichir et d\u00e9velopper le th\u00e8me principiel fondamental qui est sa raison d&rsquo;\u00eatre, avec aussi bien ses fondements m\u00e9tahistoriques que ses d\u00e9veloppements op\u00e9rationnels. (Il s&rsquo;agit, comme nous l&rsquo;avons expliqu\u00e9 dans notre dernier <em>Glossaire.dde<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_l_effondrement_du_syst_me_12_01_2014.html\" class=\"gen\">12 janvier 2014<\/a>, du th\u00e8me de la crise de l&rsquo;effondrement du Syst\u00e8me.)<\/p>\n<\/p>\n<p><p>\tComme il est naturel dans un processus de maturation d&rsquo;un ensemble qui entend reprendre une diversit\u00e9 structurelle rendant compte de tous les degr\u00e9s de la communication, de l&rsquo;information pure \u00e0 la r\u00e9flexion la plus \u00e9labor\u00e9e et la plus haute, de l&rsquo;\u00e9v\u00e9nement crisique fondamental de notre \u00e9poque, les rubriques qui en forment la structure d\u00e9marrent \u00e0 partir de certaines donn\u00e9es et conceptions sp\u00e9culatives et \u00e9voluent d&rsquo;elles-m\u00eames selon l&rsquo;\u00e9volution des relations entre leurs contenus, le th\u00e8me principiel qu&rsquo;elles traitent, et la fa\u00e7on dont ce traitement est assur\u00e9e. Bref, elles vivent et se d\u00e9veloppent selon leurs sp\u00e9cificit\u00e9s, et deviennent elles-m\u00eames.<\/p>\n<\/p>\n<p><p>\tIl est instructif de faire un relev\u00e9 et un d\u00e9compte des rubriques g\u00e9n\u00e9ralistes existantes d\u00e9j\u00e0 et d&rsquo;observer leur \u00e9volution depuis l&rsquo;origine du site. Il faut noter, bien entendu, qu&rsquo;\u00e0 cette origine-l\u00e0, autour de 1999-2001, nous \u00e9tions encore loin d&rsquo;instituer comme th\u00e8me principiel du travail du site la crise de l&rsquo;effondrement du Syst\u00e8me. L\u00e0 aussi, l&rsquo;\u00e9volution est consid\u00e9rable et a pes\u00e9 de tout son poids sur l&rsquo;\u00e9volution sp\u00e9cifiques des rubriques. Il faut noter enfin que certaines rubriques pr\u00e9sentes \u00e0 l&rsquo;origine se sont taries d&rsquo;elles-m\u00eames et ne figurent plus que comme archives parfois lointaines,  et de celles-l\u00e0 qui n&rsquo;existent plus <em>de facto<\/em>, certes, il ne sera pas question. Tout cela a cr\u00e9\u00e9 des conditions \u00e9ditoriales qui justifient la mise en place d&rsquo;une nouvelle rubrique (<em>Br\u00e8ves de crise<\/em>).<\/p>\n<\/p>\n<p><p>\t(Il doit \u00eatre bien entendu que nous ne parlons ici que des rubriques g\u00e9n\u00e9ralistes, celles qui figurent en tant que telles [en plus des synth\u00e8ses <em>S\u00e9lection des derni\u00e8res parution<\/em> et <em>A suivre<\/em>] dans le d\u00e9tail de leurs derni\u00e8res parutions sur la page d&rsquo;accueil. Les autres rubriques \u00e0 th\u00e8me [<em>La Gr\u00e2ce de l&rsquo;Histoire<\/em>, <em>Glossaire.dde<\/em>, <em>Notre situation<\/em>, etc.] ne figurent que dans le menu, en t\u00eate de la colonne de gauche de la page d&rsquo;accueil, et ne sont pas concern\u00e9es ici.)<\/p>\n<\/p>\n<p><p>\t La rubrique <em>Analyse<\/em> est l&rsquo;une des deux rubriques originelles qui ont surv\u00e9cu \u00e0 l&rsquo;\u00e9preuve du temps et de la maturation devenue maturit\u00e9. Au d\u00e9part, il s&rsquo;agissait simplement de la rubrique des textes longs, o\u00f9, comme sont nom l&rsquo;indique, nous proposions une analyse d&rsquo;une information, d&rsquo;un probl\u00e8me g\u00e9n\u00e9ral, etc. <em>Analyse<\/em> a \u00e9volu\u00e9 en <em>Notes d&rsquo;analyse<\/em> qui a d\u00e9sormais un sch\u00e9ma bien sp\u00e9cifique. Il s&rsquo;agit d&rsquo;un ensemble d&rsquo;informations rassembl\u00e9es selon un th\u00e8me commun, que nous d\u00e9terminons souvent nous-m\u00eames en fonction d&rsquo;un choix qui n&rsquo;est pas n\u00e9cessairement \u00e9vident de lui-m\u00eame, mais que nous jugeons comme tel selon notre r\u00e9f\u00e9rence principielle. En g\u00e9n\u00e9ral, cette pr\u00e9sentation comment\u00e9e de ces diverses informations et nouvelles est termin\u00e9 par une analyse et une r\u00e9flexion comment\u00e9e g\u00e9n\u00e9rale qui \u00e9tablit effectivement ce lien avec notre r\u00e9f\u00e9rence. La formule du texte comprend de nombreux intertitres, ce qui le fractionne pour rendre compte de la diversit\u00e9 des informations abord\u00e9es, et aussi des citations qui les documentent factuellement, avec souvent un bref commentaire pour chacune .<\/p>\n<\/p>\n<p><p>\t La rubrique <em>Faits &#038; Commentaires<\/em> (<em>F&#038;C<\/em>) \u00e9tait au d\u00e9part la deuxi\u00e8me rubrique, simplement pr\u00e9vue pour les textes courts, avec des \u00e9l\u00e9ments, des citations, etc., sur une information, et quelques commentaires souvent disparates, alors que la ligne du site \u00e9tait encore loin d&rsquo;\u00eatre aussi pr\u00e9cis\u00e9ment d\u00e9finie qu&rsquo;elle l&rsquo;est aujourd&rsquo;hui. <em>F&#038;C<\/em> a terriblement \u00e9volu\u00e9. Les textes se sont consid\u00e9rablement allong\u00e9s, la partie principale devenant le commentaire-r\u00e9flexion souvent annonc\u00e9 par le seul intertitre du texte. L&rsquo;information essentielle qui est trait\u00e9e comme sujet du <em>F&#038;C<\/em> est elle-m\u00eame comment\u00e9e, mais c&rsquo;est la deuxi\u00e8me partie (commentaire-r\u00e9flexion) qui pr\u00e9tend \u00e9largir et hausser consid\u00e9rablement le travail pour l&rsquo;inclure directement dans les th\u00e8ses et conceptions fondamentales qui habillent, sous-tendent et donnent son essence m\u00eame au th\u00e8me principiel du site. Si l&rsquo;on veut, la deuxi\u00e8me partie du <em>F&#038;C<\/em> tente d&rsquo;aborder le domaine de la r\u00e9flexion essentielle de type m\u00e9tahistorique, o\u00f9 peut s&rsquo;inscrire directement la r\u00e9flexion op\u00e9rationnelle suscit\u00e9e par l&rsquo;\u00e9v\u00e9nement consid\u00e9r\u00e9.<\/p>\n<\/p>\n<p><p>\t C&rsquo;est en mai 2005 qu&rsquo;est apparue la rubrique <em>Bloc-Notes<\/em>. Elle s&rsquo;imposait en fonction de l&rsquo;\u00e9volution des rubriques <em>Analyse<\/em> (<em>Notes d&rsquo;analyse<\/em>) et <em>F&#038;C<\/em> dans le sens qu&rsquo;on a dit d&rsquo;un renforcement constant et d&rsquo;une structuration nouvelles, avec allongement des textes \u00e0 mesure. En quelque sorte, <em>Bloc-Notes<\/em> reprenait la fonction attribu\u00e9e \u00e0 l&rsquo;origine \u00e0 <em>F&#038;C<\/em> qui avait alors d\u00e9j\u00e0 largement entam\u00e9 sa transformation. Les textes avaient au d\u00e9part vocation en g\u00e9n\u00e9ral \u00e0 \u00eatre tr\u00e8s court. On peut voir par exemple que l&rsquo;un des deux premiers textes de la rubrique, le <a href=\"http:\/\/www.dedefensa.org\/article-la_permanente_reecriture_de_l_histoire_du_temps_present_31_03_2005.html\" class=\"gen\">31 mars 2005<\/a>, ne comprenait que deux paragraphes et un volume de 1 132 signes. (Pour comparaison, le dernier <em>F&#038;C<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-al-qaeda_marque_d_pos_e_11_01_2014.html\" class=\"gen\">11 janvier 2014<\/a>, qui est d&rsquo;un volume standard, compte 28 856 signes.) Mais la rubrique <em>Bloc-Notes<\/em> a elle aussi \u00e9volu\u00e9 jusqu&rsquo;\u00e0 occuper une fonction de commentaire approfondi sur le probl\u00e8me g\u00e9n\u00e9ral illustr\u00e9 par l&rsquo;information cit\u00e9e, c&rsquo;est-\u00e0-dire une fonction interm\u00e9diaire quantitativement en-dessous de <em>Notes d&rsquo;analyse<\/em> et de <em>F&#038;C<\/em> mais utilisant la m\u00eame m\u00e9thodologie. (Il nous arrive d&rsquo;ailleurs, en cours de r\u00e9daction, devant les d\u00e9veloppements r\u00e9alis\u00e9s, de d\u00e9cider de transformer un <em>Bloc-Notes<\/em> en <em>Notes d&rsquo;analyse<\/em> [le plus souvent] ou en <em>F&#038;C<\/em> [beaucoup moins fr\u00e9quent].) Bref, la rubrique <em>Bloc-Notes<\/em> s&rsquo;est elle-m\u00eame d\u00e9finie et n&rsquo;a plus rien \u00e0 voir avec ce qu&rsquo;elle \u00e9tait originellement, dans la m\u00e9thodologie et dans le volume. (Exemples de l&rsquo;\u00e9volution du volume par rapport au premier texte de la rubrique de mars 2005 : le dernier <em>Bloc-Notes<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-nsa_allemagne_et_usa_dans_un_tunnel_15_01_2014.html\" class=\"gen\">15 janvier 2014<\/a> fait 10 814 signes, ce qui est un volume moyen\/bas, et celui du <a href=\"http:\/\/www.dedefensa.org\/article-la_liquidation_de_majed_et_9_11_07_01_2014.html\" class=\"gen\">7 janvier 2014<\/a> fait 14 849 signes, ce qui est un volume haut pour la rubrique.) Ainsi, peu \u00e0 peu, \u00e0 mesure de l&rsquo;\u00e9volution toujours spontan\u00e9e de la rubrique, il s&rsquo;est av\u00e9r\u00e9 que le probl\u00e8me qui avait initialement men\u00e9 \u00e0 la cr\u00e9ation de <em>Bloc-Notes<\/em> (besoin d&rsquo;une rubrique pour les nouvelles courtes r\u00e9duites \u00e0 la seule information) se posait \u00e0 nouveau&#8230;<\/p>\n<\/p>\n<p><p>\t La rubrique <em>Ouverture libre<\/em> fut cr\u00e9\u00e9e au d\u00e9but 2010 (voir le premier article le <a href=\"http:\/\/www.dedefensa.org\/article-de_platon_a_notre_crise_14_12_2009.html\" class=\"gen\">10 janvier 2010<\/a>). Sa vocation premi\u00e8re \u00e9tait d&rsquo;ouvrir les colonnes de <em>dedefensa.org<\/em> aux lecteurs, dans une rubrique sp\u00e9cifique et signal\u00e9e comme telle pour bien s\u00e9parer ce contenu r\u00e9dactionnel de celui du site. Pourtant, nous nous accordions \u00e0 nous-m\u00eames une place, avec une sorte de fiction d&rsquo;intervention de l&rsquo;ext\u00e9rieur (avec la signature <em>dedefensa.org<\/em>), pour des textes ax\u00e9s sur des citations longues d&rsquo;articles publi\u00e9s sur d&rsquo;autres sites avec quelques mots d&rsquo;introduction,  croyant ainsi, pour notre compte, r\u00e9soudre le probl\u00e8me de l&rsquo;\u00e9volution de <em>Bloc-Notes<\/em> alors que notre formule \u00e9tait beaucoup trop hybride, incertaine et ambigu\u00eb pour y parvenir. Le constat pour <em>Ouverture libre<\/em>, par rapport \u00e0 la place qui lui \u00e9tait assign\u00e9e, est celui d&rsquo;une pi\u00e8tre r\u00e9ussite qui pourrait plut\u00f4t se nommer \u00e9chec. Les contributions de lecteurs, qui sont sans le moindre doute de qualit\u00e9, sont extr\u00eamement r\u00e9duites et limit\u00e9es \u00e0 quelques plumes que tout le monde conna\u00eet. Pour notre compte (interventions sign\u00e9es <em>dedefensa.org<\/em>), \u00e9chec \u00e9galement. La plupart du temps, nos commentaires sont tels que les textes obtenus deviennent automatiquement des textes <em>Bloc-Notes<\/em>. (L&rsquo;\u00e9chec d&rsquo;<em>Ouverture libre<\/em> se mesure quantitativement : alors que les onze textes <em>Bloc-Notes<\/em> figurant en page d&rsquo;accueil vont du 30 d\u00e9cembre 2013 au 15 janvier 2014, les onze textes d&rsquo;<em>Ouverture libre<\/em> figurant en page d&rsquo;accueil vont du 16 novembre 2013 au 13 janvier 2014.) Bref, la rubrique <em>Ouverture libre<\/em> reste pr\u00e9sente dans les limites et le rythme qu&rsquo;elle s&rsquo;est elle-m\u00eame choisis mais elle n&rsquo;a pas rempli la fonction \u00e9ditoriale esp\u00e9r\u00e9e. Dont acte pour cette \u00e9volution : ce n&rsquo;est en rien une mise en cause de la rubrique mais un constat.<\/p>\n<\/p>\n<p><p>\t Ainsi vint <em>Br\u00e8ves de crise<\/em>, pour remplir ce manque \u00e9vident depuis des ann\u00e9es. Nous esp\u00e9rons simplement, cette fois, que la rubrique voudra bien remplir la fonction que nous lui assignons, et nous nous donnons toutes les chances pour cela. (Si une <em>Br\u00e8ve de crise<\/em> prenait des allures de d\u00e9veloppement, simplement elle deviendrait un texte <em>Bloc-Notes<\/em> ; si elle n\u00e9cessitait une longue citation d&rsquo;un article ext\u00e9rieur sans commentaire utile, elle deviendrait un texte <em>Ouverture libre<\/em>.) On a compris que la rubrique <em>Br\u00e8ves de crise<\/em> sera constitu\u00e9e de textes courts (disons, 3 500 signes<D> \u00e0 l&rsquo;extr\u00eame maximum), concentr\u00e9s sur l&rsquo;information, comprenant des suites ou des compl\u00e9ments de th\u00e8mes trait\u00e9s dans d&rsquo;autres rubriques, ou des nouvelles non trait\u00e9es mais que nous voulons tout de m\u00eame signaler. Il ne s&rsquo;agit nullement d&rsquo;un domaine que nous nous imposons \u00e0 nous-m\u00eames, mais bien d&rsquo;un besoin que nous ressentons nous-m\u00eames devant telle ou telle information dont nous voudrions signaler l&rsquo;importance et l&rsquo;int\u00e9r\u00eat selon notre estime, mais qui ne trouve pas sa place dans les autres rubriques. La pr\u00e9sentation des <em>Br\u00e8ves de crise<\/em> signalera la sp\u00e9cificit\u00e9 de la rubrique et la bri\u00e8vet\u00e9 du traitement : titre sans sous-titre, <em>Br\u00e8ve de crise<\/em> revenant dans le titre&#8230;<\/p>\n<\/p>\n<p><p>\tL&rsquo;agencement de la page d&rsquo;accueil sera r\u00e9am\u00e9nag\u00e9, avec le nombre d&rsquo;articles signal\u00e9s modifi\u00e9. <em>Br\u00e8ves de crise<\/em> viendra imm\u00e9diatement en-dessous de notre <em>S\u00e9lection des derni\u00e8res parution<\/em> pour signaler son imm\u00e9diatet\u00e9 et son actualit\u00e9 serr\u00e9e ; en g\u00e9n\u00e9ral, ses articles figureront un temps tr\u00e8s court (un jour est une bonne mesure) dans la <em>S\u00e9lection des derni\u00e8res parution<\/em>, pour ensuite en \u00eatre retir\u00e9s. Le nombre de titres apparaissant sur la page d&rsquo;accueil sera sans doute de quatre-cinq, avec une circulation rapide : il est probable en effet (si nous tenons nos pr\u00e9visions) que nous publierons souvent plus d&rsquo;une <em>Br\u00e8ve de crise<\/em> par jour, parce qu&rsquo;il y a beaucoup de mat\u00e9riel d&rsquo;information pour cela et que ces textes sont rapides \u00e0 faire. Il y aura peut-\u00eatre un peu moins de textes <em>Bloc-Notes<\/em> signal\u00e9s sur la page d&rsquo;accueil et certainement beaucoup moins (de onze \u00e0 quatre) de textes <em>Ouverture libre<\/em> sur cette m\u00eame page d&rsquo;accueil. Bien entendu, pour tout cela, les archives existent et l&rsquo;on peut les explorer selon l&rsquo;int\u00e9r\u00eat qu&rsquo;on en a.<\/p>\n<\/p>\n<p><p>\tNormalement, c&rsquo;est d\u00e8s ce jour que <em>Br\u00e8ves de crise<\/em> appara\u00eetra sur <em>dedefensa.org<\/em><\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 17 janvier 2014 \u00e0 07H33<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une nouvelle rubrique pour dedefensa.org Notre sitededefensa.org a subi depuis son origine diverses modifications dans sa structure et dans son contenu, qui constituent \u00e9videmment le processus naturel de maturation d&rsquo;un ensemble recherchant \u00e0 la fois la diversit\u00e9 et la compl\u00e9mentarit\u00e9 de ses rubriques pour enrichir et d\u00e9velopper le th\u00e8me principiel fondamental qui est sa raison&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[16],"tags":[15538,3228,2631,2981,3517],"class_list":["post-73640","post","type-post","status-publish","format-standard","hentry","category-notre-situation","tag-breves","tag-crise","tag-de","tag-dedefensa-org","tag-rubrique"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73640"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73640\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}