{"id":73646,"date":"2014-01-20T05:43:29","date_gmt":"2014-01-20T05:43:29","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/01\/20\/le-japon-agressif-sa-strategie-du-choc-et-le-cover-up-de-fukushima\/"},"modified":"2014-01-20T05:43:29","modified_gmt":"2014-01-20T05:43:29","slug":"le-japon-agressif-sa-strategie-du-choc-et-le-cover-up-de-fukushima","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/01\/20\/le-japon-agressif-sa-strategie-du-choc-et-le-cover-up-de-fukushima\/","title":{"rendered":"Le Japon agressif, sa \u201c\u2018strat\u00e9gie du choc\u201d et le <em>cover-up<\/em> de Fukushima"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Le Japon agressif, sa strat\u00e9gie du choc et le <em>cover-up<\/em> de Fukushima<\/h3>\n<\/p>\n<p><p>\tDepuis l&rsquo;arriv\u00e9e de Shinzo Abe comme Premier ministre, en d\u00e9cembre 2012, le Japon suit une ligne nationaliste dure conduisant \u00e0 des tensions avec la Chine et la Cor\u00e9e du Sud. On dira aussit\u00f4t et avec une tr\u00e8s grande fermet\u00e9 que la particularit\u00e9 de ce nationalisme est d&rsquo;\u00eatre compl\u00e8tement faussaire et totalement inverti. Le nationalisme, qui est une notion douteuse dans le maniement et l&rsquo;entendement du mot, devrait avoir au moins comme certitudes de sa d\u00e9finition une r\u00e9f\u00e9rence irr\u00e9fragable aux notions d&rsquo;ind\u00e9pendance et de souverainet\u00e9 nationales. Dans le cas du Japon, il appara\u00eet que ce nationalisme faussaire garde le pire du concept et trahit ce qu&rsquo;on y trouve de vertueux. Le nationalisme de Shinzo Abe, fond\u00e9 en v\u00e9rit\u00e9 sur la corruption absolue d&rsquo;une classe politique japonaise d\u00e9vor\u00e9e par la subversion d&rsquo;elle-m\u00eame, s&rsquo;op\u00e9rationnalise selon une situation du pass\u00e9 compl\u00e8tement faussaire et selon une situation pr\u00e9sente de compl\u00e8te inversion du concept. Le Japon de Shinzo Abe est essentiellement agressif envers la Cor\u00e9e du Sud et la Chine qui ne menacent en rien son ind\u00e9pendance et sa souverainet\u00e9 nationales (quelles que soient leurs intentions et leurs politique), en s&rsquo;appuyant sur l&rsquo;alliance US, la force subversive et destructrice essentielle de son ind\u00e9pendance et de sa souverainet\u00e9 nationales. Il s&rsquo;agit donc d&rsquo;une parfaite int\u00e9gration-Syst\u00e8me par son caract\u00e8re complet d&rsquo;inversion, dont l&rsquo;un des effets antiSyst\u00e8me pour l&rsquo;instant accessoire mais potentiellement int\u00e9ressant est de rapprocher un autre satellite des USA, la Cor\u00e9e du Sud, de la Chine.<\/p>\n<\/p>\n<p><p>\tA part certains exercices de d\u00e9monstration d&rsquo;affirmation dans des querelles de territoires contest\u00e9s (des \u00eeles) et une rh\u00e9torique \u00e0 mesure, Shinzo Abe affirme notamment une politique de communication appuy\u00e9 sur un symbolisme agressif (c\u00e9l\u00e9bration, au travers de divers gestes symboliques, du Japon expansionniste vis-\u00e0-vis de la zone consid\u00e9r\u00e9e dans son cycle apparu au tout d\u00e9but des ann\u00e9es 1930, dont eurent \u00e0 souffrir horriblement la Chine et la Cor\u00e9e du Sud). (La Cor\u00e9e du Sud et la Chine d\u00e9veloppent eux aussi, \u00e0 c\u00f4t\u00e9 de d\u00e9monstrations d&rsquo;affirmation dans des querelles de territoires contest\u00e9s, des gestes symboliques bas\u00e9s sur la c\u00e9l\u00e9bration du pass\u00e9 marquant l&rsquo;expansionnisme japonais \u00e0 leur encontre, comme on peut le lire en d\u00e9but de l&rsquo;article du <a href=\"http:\/\/www.dedefensa.org\/article-de_2013_2014_en_passant_par_1914_02_01_2014.html\" class=\"gen\">2 janvier 2014<\/a>.)<\/p>\n<\/p>\n<p><p>\tMais il y a un autre aspect dans la politique dite-nationaliste de Shinzo Abe, qui appara\u00eet \u00e0 premi\u00e8re vue compl\u00e9mentaire du reste et qui est gros d&rsquo;une dimension sp\u00e9cifique fondamentale, potentiellement bien plus dramatique et d\u00e9structurante : la constitution d&rsquo;un v\u00e9ritable \u00c9tat de S\u00e9curit\u00e9 Nationale \u00e0 l&rsquo;aide de lois d&rsquo;urgence, dite de secret d&rsquo;\u00c9tat, effectives depuis novembre-d\u00e9cembre 2013. Cette d\u00e9marche recopie le mod\u00e8le du <em>National Security State<\/em> (NSS) \u00e9tabli en 1947 par les USA ; bien entendu, les USA, au nom d&rsquo;une <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_la_politique-syst_me__17_11_2012.html\" class=\"gen\">politique-Syst\u00e8me<\/a> aveugl\u00e9ment poursuivie, apporte un soutien enthousiaste \u00e0 Shinzo Abe apr\u00e8s avoir press\u00e9 le Japon d&rsquo;aller dans ce sens, depuis 2009 (tiens, depuis l&rsquo;arriv\u00e9e de saint-BHO, l&rsquo;homme qui devait changer la <a href=\"http:\/\/www.dedefensa.org\/article-bho_c_est_gw-turbo_16_02_2012.html\" class=\"gen\">politique<\/a> de l&rsquo;id\u00e9ologie et de l&rsquo;instinct de GW Bush). L&rsquo;aspect le plus notable et le plus terrible est le lien qui est \u00e9tabli entre cette construction s\u00e9curitaire contraignante et la catastrophe de Fukushima avec ses cons\u00e9quences plus que jamais en plein d\u00e9veloppement : il appara\u00eet manifeste \u00e0 nombre d&rsquo;activistes japonais, avec nombre d&rsquo;arguments compl\u00e8tement fond\u00e9s, que ces lois sont \u00e9galement faites pour dissimuler (<em>cover-up<\/em>) les cons\u00e9quences en cours et <strong>surtout \u00e0 venir<\/strong> de la catastrophe de Fukushima.<\/p>\n<\/p>\n<p><p>\t(On notera que le niveau des radiations \u00e0 Fukushima a atteint ces jours derniers un record, selon <em>Russia Today<\/em> le <a href=\"http:\/\/rt.com\/news\/japan-fukushima-radiation-high-831\/\" class=\"gen\">18 janvier 2014<\/a> : \u00ab<em>A record high level of beta rays released from radioactive strontium-90 has been detected at the crippled Fukushima nuclear power plant beneath the No. 2 reactor&rsquo;s well facing the ocean, according to the facility&rsquo;s operator. Tokyo Electric Power Company (TEPCO) measured the amount of beta ray-emitting radioactivity at more than 2.7 million becquerels per liter, Fukushima&rsquo;s operator said as reported in Japanese media. The measurements were taken on Thursday.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tUne interview par Amy Goodman, de <em>Democracy Now!<\/em> (le <a href=\"http:\/\/www.democracynow.org\/2014\/1\/15\/shock_doctrine_in_japan_shinzo_abesop\" class=\"gen\">15 janvier 2014<\/a>), du professeur Koichi Nakano, de l&rsquo;universit\u00e9 Sophia de Tokyo et directeur de l&rsquo;IGC (<em>Institute of Global Concern<\/em>), illustre de fa\u00e7on critique cette nouvelle situation japonaise dans tous ses caract\u00e8res. En voici un extrait.<\/p>\n<\/p>\n<p><p>\t<strong><em>Amy Goodman<\/em><\/strong> : \u00ab<em>And talk about state secrets. What are these state secrets?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<strong><em>Koichi Nakano<\/em><\/strong>: \u00ab<em>Well, it&rsquo;s very poorly defined. It, of course, concerns primarily security issues and anti-terrorist measures. But in the parliamentary exchange, it became increasingly clear that the interpretation of what actually constitutes state secret could be very arbitrary and rather freely defined by government leaders. And, for example, anti-nuclear citizen movements can come under surveillance without their knowledge, and arrests can be made if it turns out that they obtain some information that they didn&rsquo;t even know constituted state secrets.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<strong><em>Amy Goodman<\/em><\/strong> : \u00ab<em>You talk about a Japanese shock doctrine.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<strong><em>Koichi Nakano<\/em><\/strong>: \u00ab<em>Right. The state secrecy law that was passed in December last year, just a month ago, basically two years after the big earthquake and tsunami and the nuclear power accident, that still continues to literally kind of shake Japan, and in the climate of anxiety and insecurity, the government basically is pushing in the classic sort of Naomi Klein kind of way of shock doctrine. And for the Japanese, it is particularly worrisome because it reminds us of what happened before the Second World War, actually, when Tokyo was destroyed by a huge earthquake in 1923. And the peace preservation law that eventually led to the birth of state secret police and the brutality of the military regime was also enacted two years right after the big earthquake that destroyed Tokyo back in the 1920s. So, the parallel is quite spooky.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<strong><em>Amy Goodman<\/em><\/strong> : \u00ab<em>And the parallel now with Fukushima, what it would mean in a cover-up of what&rsquo;s been happening? And we&rsquo;re not talking about the past now<\/em>\u00bb&#8230; [&#8230;]<\/p>\n<\/p>\n<p><p>\t<strong><em>Koichi Nakano<\/em><\/strong>: \u00ab<em>Exactly. The continuous contamination of water, of ocean, of the soil, and the continuous danger with the spent fuels in the nuclear reactors in FukushimaI think there are lots of concerns, and citizens are trying to know the truth. But I think the state secrecy law is potentially going to make it easier for the government to cover up information&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tBien entendu, ce qui doit nous int\u00e9resser particuli\u00e8rement, c&rsquo;est ce qui nous appara\u00eet comme un processus-Syst\u00e8me caract\u00e9ristique. C&rsquo;est l&rsquo;ensemble du processus, entre les dimensions sp\u00e9cifiques concern\u00e9s et les circonstances en cours, \u00e9tablissant un lien entre un \u00e9v\u00e9nement de politique d&rsquo;urgence s\u00e9curitaire classique (cr\u00e9ation d&rsquo;un NSS japonais) et un \u00e9v\u00e9nement eschatologique int\u00e9grant une catastrophe naturelle peut-\u00eatre li\u00e9 au d\u00e9r\u00e8glement climatique acc\u00e9l\u00e9r\u00e9 sinon suscit\u00e9 par les activit\u00e9s de notre contre-civilisation (du Syst\u00e8me) et un aspect de surpuissance (le nucl\u00e9aire) directement li\u00e9  li\u00e9s \u00e0 une perception catastrophiste du d\u00e9veloppement de la contre-civilisation dans le domaine du syst\u00e8me du technologisme, tout cela dans le chef de l&rsquo;\u00e9v\u00e9nement catastrophique de Fukushima en 2011. Plus pr\u00e9cis\u00e9ment dit, il s&rsquo;agit donc de l&rsquo;existence incontestable d&rsquo;un rapport d\u00e9lib\u00e9r\u00e9, quasiment directement de cause \u00e0 effet, entre le processus NSS-japonais et la politique de <em>cover-up<\/em>, de dissimulation, des cons\u00e9quences catastrophiques de Fukushima, d\u00e9j\u00e0 d\u00e9velopp\u00e9e et qui devrait donc s&rsquo;amplifier encore. (Les r\u00e9f\u00e9rences du tremblement de terre de Tokyo de 1923 et de ce qui a suivi, donn\u00e9es par le professeur Koichi Nakano, sont particuli\u00e8rement impressionnantes pour ce qu&rsquo;ils nous disent du pr\u00e9c\u00e9dent manipulatoire \u00e0 cet \u00e9gard, mais alors sans la dimension eschatologique qui distingue dramatiquement la situation actuelle.)<\/p>\n<\/p>\n<p><p>\tCette interpr\u00e9tation probablement compl\u00e8tement justifi\u00e9e constituerait, constitue m\u00eame une premi\u00e8re extr\u00eamement impressionnante, \u00e0 cause de l&rsquo;importance de la puissance du Japon et de ses capacit\u00e9s d&rsquo;une \u00e9ventuelle nuisance catastrophique, \u00e0 la fois strat\u00e9giques et de communication. Elle nous donnerait \u00e0 voir le premier cas de l&rsquo;\u00e8re d&rsquo;urgence catastrophique symboliquement ouverte avec 9\/11, et finalement le premier cas de cette sorte pour l&rsquo;\u00e9poque commenc\u00e9e avec le <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_d_cha_nement_de_la_mati_re__05_11_2012.html\" class=\"gen\">d\u00e9cha\u00eenement de la Mati\u00e8re<\/a>, o\u00f9 le choix d&rsquo;une politique humaine contraignante, s\u00e9curitaire et \u00e9ventuellement militariste jusqu&rsquo;\u00e0 bouleverser la structure d&rsquo;un gouvernement, voire de l&rsquo;\u00c9tat, est dans une part tr\u00e8s importante li\u00e9 directement \u00e0 la lutte par dissimulation et \u00e0 la tentative de suppression de la v\u00e9rit\u00e9 d&rsquo;une situation en partie caus\u00e9e par une catastrophe naturelle et en partie par l&rsquo;effet du d\u00e9veloppement conduisant \u00e0 la destruction du monde par le Syst\u00e8me. Il s&rsquo;agit alors d&rsquo;un \u00e9v\u00e9nement eschatologique de premi\u00e8re grandeur, o\u00f9 l&rsquo;\u00e9l\u00e9ment humain, la <em>sapiens<\/em> soi-m\u00eame, joue par sa position de relais aveugle du Syst\u00e8me un r\u00f4le central d&rsquo;outil de dissimulation et de simulacre. Cette occurrence est bien eschatologique parce qu&rsquo;elle tend \u00e0 dissimuler les \u00e9l\u00e9ments fondamentaux de la destruction du monde, pour permettre objectivement, quelles que soient les intentions et la conscience des choses des <em>sapiens<\/em>-ex\u00e9cutants, la poursuite en mode acc\u00e9l\u00e9r\u00e9 de cette destruction du monde. (Et l&rsquo;on insister bien ici : pour poursuivre &#8230; [la] destruction du monde et non, par exemple, la poursuite de la domination du monde,  la nuance (!) est eschatologique et m\u00e9taphysique.)  Le <em>sapiens<\/em>, donc, ex\u00e9cutant de la surpuissance suscitant la destruction du monde, \u00e9galement ex\u00e9cutant des conditions d&rsquo;autodestruction du Syst\u00e8me puisque le caract\u00e8re eschatologique de la chose ne peut qu&rsquo;y conduire. Voil\u00e0 au fond qui est une poursuite logique de la catastrophe qui a abouti \u00e0 la situation du Japon, c&rsquo;est-\u00e0-dire successivement sa politique des ann\u00e9es 1930, sa destruction effective et symbolique par l&rsquo;arme atomique, par son adversaire assurant la vassalisation et la transmutation du pays, jusqu&rsquo;\u00e0 ces conditions actuelles achevant le dessein surpuissance-autodestruction du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tOn comprend que, dans des conditions qui pourraient s&rsquo;aggraver notablement, un Shinzo Abe s&rsquo;arrangerait bien d&rsquo;un conflit avec l&rsquo;un ou l&rsquo;autre dans la r\u00e9gion, pour encore mieux dissimuler les cons\u00e9quences de Fukushima. L\u00e0 aussi, il s&rsquo;agirait bien plus d&rsquo;eschatologie que de g\u00e9opolitique, alors que semble r\u00e9gner au Japon une psychologie g\u00e9n\u00e9rale de terreur sourde suscit\u00e9e par Fukushima (\u00ab<em>the climate of anxiety and insecurity<\/em>\u00bb mis en \u00e9vidence par le professeur Koichi Nakano). Nous mentionnons cette possibilit\u00e9 dans sa seule \u00e9laboration de projet et de pr\u00e9paration du projet, car il nous semblerait compl\u00e8tement improbable qu&rsquo;un tel plan puisse aboutir \u00e0 sa concr\u00e9tisation du type g\u00e9opolitique normal en fonction des multiples interf\u00e9rences, contestation et contradictions expos\u00e9es par le syst\u00e8me de la communication. L\u00e0 aussi, le d\u00e9veloppement ne serait nullement g\u00e9opolitique mais eschatologique et d&rsquo;autodestruction du Syst\u00e8me selon l&rsquo;orientation dans ce sens permise sinon favoris\u00e9e par l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_l_re_psychopolitique_12_10_2013.html\" class=\"gen\">\u00e8re psychopolitique<\/a>.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 20 janvier 2014 \u00e0 05H43<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Japon agressif, sa strat\u00e9gie du choc et le cover-up de Fukushima Depuis l&rsquo;arriv\u00e9e de Shinzo Abe comme Premier ministre, en d\u00e9cembre 2012, le Japon suit une ligne nationaliste dure conduisant \u00e0 des tensions avec la Chine et la Cor\u00e9e du Sud. On dira aussit\u00f4t et avec une tr\u00e8s grande fermet\u00e9 que la particularit\u00e9 de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[15543,4270,3977,3392,3299,3228,2651,7548,10993,9054,4662,3890,4271,6568,15542,3973,3300],"class_list":["post-73646","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-abe","tag-autodestruction","tag-chine","tag-climatique","tag-coree","tag-crise","tag-du","tag-eschatologie","tag-fukushima","tag-inversion","tag-japon","tag-national","tag-nationalisme","tag-security","tag-shnizo","tag-state","tag-sud"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73646"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73646\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}