{"id":73679,"date":"2014-02-04T07:04:42","date_gmt":"2014-02-04T07:04:42","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/02\/04\/la-mort-dun-comedien-et-notre-intense-fragilite-psychologique\/"},"modified":"2014-02-04T07:04:42","modified_gmt":"2014-02-04T07:04:42","slug":"la-mort-dun-comedien-et-notre-intense-fragilite-psychologique","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/02\/04\/la-mort-dun-comedien-et-notre-intense-fragilite-psychologique\/","title":{"rendered":"La mort d&rsquo;un com\u00e9dien et notre intense fragilit\u00e9 psychologique"},"content":{"rendered":"<p><h3 class=\"titrebloc\">La mort d&rsquo;un com\u00e9dien et notre intense fragilit\u00e9 psychologique<\/h3>\n<\/p>\n<p><p>\tLa mort du com\u00e9dien Philip Seymour Hoffman,  tr\u00e8s probablement \u00e0 cause d&rsquo;une overdose d&rsquo;h\u00e9ro\u00efne,  est un \u00e9v\u00e9nement public tragique par tous les composants de l&rsquo;\u00e9v\u00e9nement : l&rsquo;excellence du com\u00e9dien d\u00e9passant tr\u00e8s largement le standard hollywoodien, son \u00e9tat psychologique qui l&rsquo;avait amen\u00e9 \u00e0 la consommation de drogue, l&rsquo;habituelle tension antagoniste opposant le talent et son exercice d&rsquo;une part, les exigences et le climat de mat\u00e9rialisme marchand et comp\u00e9titif avec son abaissement qualitatif caract\u00e9risant Hollywood et sa <em>movie industry<\/em> d&rsquo;autre part.<\/p>\n<\/p>\n<p><p>\tL&rsquo;on dira qu&rsquo;il n&rsquo;y a rien de nouveau dans tout cela. Depuis qu&rsquo;Hollywood existe, cette sorte de conflit g\u00e9n\u00e9ral est r\u00e9currente, entre des valeurs artistiques et intellectuelles et l&rsquo;expression absolument capitalistique (religion du profit, sauvagerie des relations professionnelles, s\u00e9lection impitoyable de type darwiniste, manipulation sans vergogne des \u00eatres) et am\u00e9ricaniste (conformisme de l&rsquo;expression d&rsquo;une pens\u00e9e qu&rsquo;on est tenu d&rsquo;avoir). La structure hollywoodienne est construite compl\u00e8tement selon ce sch\u00e9ma qui \u00e9pouse enti\u00e8rement les <em>diktat<\/em> du Syst\u00e8me, \u00e0 un point tel de perfection qu&rsquo;on a fait de sa production un n\u00e9ologisme (hollywoodisme) dont la connotation-Syst\u00e8me de type id\u00e9ologique est bien connue.<\/p>\n<\/p>\n<p><p>\tCe qui est remarquable, dans la mort de Hoffman et ce qui l&rsquo;accompagne, c&rsquo;est la force et le radicalisme des arguments \u00e9chang\u00e9s, autant que leur pr\u00e9tention affich\u00e9e \u00e0 exprimer non pas seulement un cas personnel (Hoffman) ou un cas sp\u00e9cifique (le com\u00e9dien de talent face \u00e0 la machine hollywoodienne),  quels que soient la valeur et le bien-fond\u00e9 des arguments,  mais un cas symbolique de notre crise g\u00e9n\u00e9rale de civilisation, ce que nous nommons \u00e9galement la <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_l_effondrement_du_syst_me_12_01_2014.html\" class=\"gen\">crise d&rsquo;effondrement du Syst\u00e8me<\/a>. Ce qui est remarquable, en d&rsquo;autres mots, ce n&rsquo;est pas l&rsquo;intensit\u00e9 (la jacasserie) du bruit du syst\u00e8me de la communication saluant la mort de Seymour Hoffman, que son contenu dans certains des cas envisag\u00e9s. Il faut ajouter, bien entendu, que les moyens du syst\u00e8me de la communication, y compris les moyens s\u00e9lectifs permettant l&rsquo;\u00e9mission instantan\u00e9e d&rsquo;avis tr\u00e8s courts mais p\u00e9remptoires, jouent leur r\u00f4le dans le ph\u00e9nom\u00e8ne qu&rsquo;on d\u00e9crit. Mais l&rsquo;on ne fait l\u00e0 que signaler l&rsquo;un des moyens d&rsquo;expression de ce sentiment diffus que nous tentons de d\u00e9crire, qui sublime tout \u00e9v\u00e9nement propice mais d&rsquo;abord per\u00e7u comme limit\u00e9 \u00e0 une personne, un milieu et ses murs, en un \u00e9v\u00e9nement <strong>symbolique de la grande crise qui p\u00e8se sur nos psychologies<\/strong>.<\/p>\n<\/p>\n<p><p>\tNous allons prendre trois exemples de r\u00e9actions \u00e0 la mort du com\u00e9dien qui illustrent, \u00e0 notre sens, ce processus psychologique. Encore une fois, il faut les appr\u00e9cier d&rsquo;un point de vue qualitatif par rapport \u00e0 leurs r\u00e9f\u00e9rences et non quantitatif, par rapport \u00e0 ce qu&rsquo;ils repr\u00e9sentant en termes-Syst\u00e8me d&rsquo;audience, d&rsquo;importance du support, d&rsquo;honorabilit\u00e9-Syst\u00e8me et ainsi de suite. Il faut les appr\u00e9cier selon le constat que certaines d&rsquo;entre elles conduisent leurs auteurs \u00e0 des positions dites \u00e0 fronts renvers\u00e9s par rapport \u00e0 leurs habituelles prises de position politique. Il faut appr\u00e9cier combien ce qui est d&rsquo;abord un fait soci\u00e9tal, c&rsquo;est-\u00e0-dire concernant les d\u00e9bats de soci\u00e9t\u00e9 d\u00e9velopp\u00e9s actuellement pour tenter d&rsquo;ent\u00e9riner la postmodernit\u00e9 et \u00e9viter la grande question de notre crise d&rsquo;effondrement du Syst\u00e8me (le <em>big Now<\/em>, voir le <a href=\"http:\/\/www.dedefensa.org\/article-du_big_now_l_l_ternel_pr_sent__29_01_2014.html\" class=\"gen\">29 janvier 2014<\/a>), ram\u00e8ne irr\u00e9sistiblement \u00e0 cette derni\u00e8re. <\/p>\n<\/p>\n<p><p>\t Simon Jenkins, dans <em>The Guardian<\/em>, le <a href=\"http:\/\/www.theguardian.com\/commentisfree\/2014\/feb\/03\/philip-seymour-hoffman-drugs-double-standard\" class=\"gen\">3 f\u00e9vrier 2014<\/a>, fait un article qui est un plaidoyer pour la l\u00e9galisation des drogues qui, seule, selon lui, \u00e9viterait aux consommateurs de drogue des situations de clandestinit\u00e9, d&rsquo;urgence et d&rsquo;absence de r\u00e9gulation personnelle menant \u00e0 une trag\u00e9die comme celle de Seymour Hoffman. C&rsquo;est une th\u00e8se d\u00e9sormais classique, qui a ses arguments et ne doit pas \u00eatre condamn\u00e9e n\u00e9cessairement selon tel ou tel principe,  d&rsquo;autant que l&rsquo;on sait par ailleurs dans quel \u00e9tat se trouvent ces principes \u00e0 force de manipulation et de d\u00e9bilitation. On retiendra essentiellement l&rsquo;introduction du texte de Jenkins, qui, lui, d\u00e9veloppe un argument renvoyant, involontairement sans doute, inconsciemment sans aucun doute, \u00e0 la situation du d\u00e9veloppement de r\u00e9alit\u00e9s parall\u00e8les caract\u00e9risant la r\u00e9action du Syst\u00e8me pour \u00e9carter tous les probl\u00e8mes sociaux, \u00e9conomiques, psychologiques, etc., en tant que tels, de crainte qu&rsquo;ils nous ram\u00e8nent \u00e0 la question centrale (la crise de ce Syst\u00e8me).<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Anyone who saw Philip Seymour Hoffman in the film A Late Quartet could sense an accident on its way to happening. We now know that the actor and the tortured violinist he portrayed were close to the same person. Acting is a dangerous calling, pushing its practitioners back and forth over the border of unreality. Hoffman&rsquo;s death has been universally greeted as a tragedy. He struggled with addiction, seemed to recover, relapsed and died of what appears to have been an accidental overdose. The world of cinema mourns.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Does the law also mourn? It lumps Hoffman together with thousands found dead and friendless in urban backstreets, also with needles in their arms. It treats them all as outlaws. Such is the double standard that now governs the regulation of addictive substances that we have had to develop separate universes of condemnation&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Il y a une tr\u00e8s courte intervention de <a href=\"http:\/\/en.wikipedia.org\/wiki\/Ben_Shapiro#Perspective_on_Israel\" class=\"gen\">Ben Shapiro<\/a> sur son <em>blog<\/em> du <em>National Journal<\/em>, le <a href=\"http:\/\/www.nationalreview.com\/node\/370158\/print\" class=\"gen\">2 f\u00e9vrier 2014<\/a>. Shapiro est connu comme un <em>neocon<\/em>, partisan radical d&rsquo;Isra\u00ebl et de la politique extr\u00e9misme de son gouvernement. Par cons\u00e9quent, on serait conduit \u00e0 le classer dans la rubrique classique des bellicistes extr\u00e9mistes agissant dans le sens du d\u00e9veloppement de la surpuissance d\u00e9structurante du Syst\u00e8me. Pourtant, son commentaire, tr\u00e8s court (nous le reprenons en entier), qui d\u00e9nonce l&rsquo;absence de structuration morale et principielle r\u00e9gnant dans les milieux avanc\u00e9s de Hollywood, pourrait \u00eatre ais\u00e9ment pris, dans la forme r\u00e9f\u00e9rentielle \u00e0 laquelle il renvoie, comme une d\u00e9marche antiSyst\u00e8me.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Philip Seymour Hoffman was one of the most talented actors of his generation, a leading man without leading-man looks, an actor whose magnetism onscreen sprang from intelligence and fervor rather than appearance. But his self-inflicted death is yet another hallmark of the broken leftist culture that dominates Hollywood, enabling rather than preventing the loss of some of its greatest talents. Libertarianism becomes libertinism without a cultural force pushing back against the penchant for sin; Hollywood has no such cultural force. In fact, the Hollywood demand is for more self-abasement, less spirituality, less principle, less standards.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>No one knows what sort of demons plagued Seymour Hoffman. But without a sound moral structure around those in Hollywood who have every financial and talent advantage, the path to destruction is far too easy.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Le troisi\u00e8me intervenant qu&rsquo;on cite est Kurt Nimmo, avec un article du <a href=\"http:\/\/www.infowars.com\/cultural-war-inanities-and-the-death-of-philip-seymour-hoffman\/\" class=\"gen\">3 f\u00e9vrier 2014<\/a> sur <em>Infowars.com<\/em>. Nimmo est un sp\u00e9cialiste des grandes analyses g\u00e9opolitiques-complotistes des grands \u00e9v\u00e9nements \u00e9galement g\u00e9opolitiques, ou consid\u00e9r\u00e9s comme tels et faussement selon notre point de vue, tels l&rsquo;Iran, la Syrie, l&rsquo;Ukraine, etc. Il s&rsquo;affiche r\u00e9solument antiSyst\u00e8me et ne l&rsquo;est pas toujours, tant s&rsquo;en faut et tant les grandes analyses structur\u00e9es construites sur des rationalit\u00e9s suppos\u00e9es d&rsquo;acteurs puissants suppos\u00e9es manipuler les \u00e9v\u00e9nements de la plan\u00e8te produisent souvent l&rsquo;effet inverse \u00e0 celui qu&rsquo;on attend. Nous avons souvent d\u00e9velopp\u00e9 ce th\u00e8me o\u00f9 l&rsquo;on charge le Syst\u00e8me, qui serait dans son cas une cr\u00e9ation humaine contr\u00f4l\u00e9e par les <em>sapiens<\/em> idoines, de capacit\u00e9s manuvri\u00e8res qu&rsquo;il n&rsquo;a pas (il suffit de se rappeler ce que tous ces analystes annon\u00e7aient du triomphe du bloc BAO en Syrie d\u00e9but 2012 et ce qu&rsquo;il en reste), ce qui conduit \u00e0 des conclusions faussaires dont l&rsquo;effet,  m\u00eame si l&rsquo;on n&rsquo;en veut certainement pas,  est de reconna\u00eetre <em>in fine<\/em> l&rsquo;irr\u00e9sistibilit\u00e9 de la surpuissance du Syst\u00e8me, par cons\u00e9quent la vanit\u00e9 de s&rsquo;opposer \u00e0 lui, par cons\u00e9quent l&rsquo;affaiblissement de la psychologie de la r\u00e9sistance qui s&rsquo;ensuit (c&rsquo;est le plus important) : dans ce cas, le fantasme de la raison subvertie remplace l&rsquo;esprit de r\u00e9sistance avec des cons\u00e9quences d\u00e9vastatrices. Aussi l&rsquo;attaque de Nimmo contre Shapiro, au pr\u00e9texte que la guerre culturelle dont t\u00e9moigne Shapiro est une diversion manipul\u00e9e du Syst\u00e8me pour d\u00e9tourner notre attention, produit l&rsquo;effet exactement inverse de l&rsquo;antiSyst\u00e8me. La guerre culturelle, ou les \u00e9v\u00e9nements soci\u00e9taux, constitue un \u00e9v\u00e9nement objectif que le Syst\u00e8me voudrait manipuler \u00e0 son avantage pour dissimuler sa propre crise, mais qui finalement d\u00e9bouche sur une v\u00e9rit\u00e9 de situation, qui t\u00e9moigne de la dynamique d\u00e9structurante et dissolvante du Syst\u00e8me, qui met \u00e0 nu la crise que sa dynamique de surpuissance alimente et dont les effets contribuent puissamment \u00e0 transmuter cette dynamique de surpuissance en dynamique d&rsquo;autodestruction. Lorsque Nimmo d\u00e9nonce la critique de Shapiro comme une guerre culturelle qui serait un rideau de fum\u00e9e pendant que Rome br\u00fble, donc nous dissimulant que Rome br\u00fble, il manque l&rsquo;\u00e9vidence que cette fum\u00e9e-l\u00e0 provient \u00e9galement et directement de l&rsquo;incendie de Rome.<\/p>\n<\/p>\n<p><p>\t\u00ab<em> Shapiro offers no further explanation what precisely leftist culture is or how it led to Hoffman&rsquo;s death, if it did. True, Hollywood celebrities are predominately liberal, but we are not clued in on how this might lead to an actor using narcotics. Is Shaprio saying liberal culture promotes drug use, or merely tolerant of it? Does tolerance negate personal responsibility?<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>\t\u00bb<em>It is fair to say Philip Seymour Hoffman suffered from depression. His death had more to do with the perils of self-medication and dangerous drugs than any sort of cultural or societal permissiveness. Millions of people try to do the same thing with alcohol and prescription drugs. Are they Leftist, too? The Left cries about the supposed Right advocating war and making excuses for predatory capitalism, while the Right complains about cultural Marxism and a destructive permissiveness leading to a decadent tolerance for drugs and abortion. The two sides fight it out ad nauseam in circus sideshow fashion. Meanwhile, Rome burns in the background.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The left-vs-right sideshow is a near perfect system for the ruling elite who operate outside the firing range behind the scenes. Most people line up like football spectators and cheer their team on while bankster and corporatist criminals make off with the goods below the bleachers and out of sight of the goal line.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tComme on voit, il est difficile de d\u00e9terminer un parti dans ces \u00e9changes, par rapport aux coh\u00e9rences habituelles, et, surtout, <strong>il est totalement inutile<\/strong> de chercher \u00e0 d\u00e9terminer un parti ou l&rsquo;autre, et encore plus de quoi il s&rsquo;agit lorsqu&rsquo;on parle de coh\u00e9rences habituelles. Il y a de moins en moins de tout cela,  un parti, des coh\u00e9rences habituelles ; il y a des \u00e9v\u00e9nements divers, selon des r\u00e9f\u00e9rences multiples, qui s&rsquo;accumulent, qui s&#8217;empilent, sans que nous puissions vraiment les appr\u00e9cier et trancher. Dans une semaine, qui songera encore \u00e0 la mort de Seymour Hoffman, alors que nous nous trouvons dans ce fameux <em>big Now<\/em> o\u00f9 tout s&rsquo;accumule et s&#8217;empile dans un temps historique paralys\u00e9, par cons\u00e9quent sans que nous puissions aller jusqu&rsquo;au bout, trancher le cas, porter un jugement d\u00e9cisif, puisqu&rsquo;entretemps l&rsquo;\u00e9v\u00e9nement suivant, la crise suivante, sollicite toute notre attention&#8230;<\/p>\n<\/p>\n<p><p>\tAu reste, est-ce si mauvais ? Comment pr\u00e9tendre aller jusqu&rsquo;au bout, trancher le cas, porter un jugement d\u00e9cisif, alors que tous les courants d&rsquo;information, les pressions du syst\u00e8me de la communication, les interpr\u00e9tations et manipulations dans tous les sens interdisent d&rsquo;esp\u00e9rer aller \u00e0 de telles conclusions, et surtout rendent compl\u00e8tement vaines et accessoires, sinon faussaires pour l&rsquo;essentiel, de telles conclusions ? Alors, c&rsquo;est autre chose que nous r\u00e9v\u00e8le cet \u00e9v\u00e9nement qui est bien moins marquant et grave que tant d&rsquo;autres, qui l&rsquo;est pourtant suffisamment pour nous servir dans ce sens ; il nous r\u00e9v\u00e8le l&rsquo;extraordinaire fragilit\u00e9 de notre psychologie dans le climat g\u00e9n\u00e9ral, et par cons\u00e9quent la d\u00e9monstration par la sensibilit\u00e9 qui d\u00e9coule de cette fragilit\u00e9 de la puissance pr\u00e9gnante, omnipr\u00e9sente, de notre Grande Crise G\u00e9n\u00e9rale, de la crise d&rsquo;effondrement du Syst\u00e8me. Et l\u00e0, nous passons du <em>big Now<\/em> \u00e0 l&rsquo;\u00ab<em>\u00e9ternel pr\u00e9sent<\/em>\u00bb, qui serait plut\u00f4t le v\u00e9ritable champ de bataille o\u00f9 s&rsquo;affrontent Syst\u00e8me et antiSyst\u00e8me, o\u00f9 se d\u00e9veloppe de plus en plus vite la crise d&rsquo;effondrement du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tCette vuln\u00e9rabilit\u00e9 de nos psychologies, ces nerfs \u00e0 vif, font que plus aucun \u00e9v\u00e9nement aujourd&rsquo;hui, s&rsquo;il d\u00e9passe la norme banalisante de la manipulation du syst\u00e8me de la communication par le Syst\u00e8me, n&rsquo;\u00e9chappe \u00e0 sa transformation symbolique en expression de la Grande Crise G\u00e9n\u00e9rale et est d\u00e9battu comme tel, avec toutes les interf\u00e9rences et contradictions qu&rsquo;on a vues, s&rsquo;exprimant en permanence et dans tous les sens, faisant de l&rsquo;un et de l&rsquo;autre, alternativement selon le flux des circonstances, un antiSyst\u00e8me sans n\u00e9cessit\u00e9 de conscience de la chose, et par cons\u00e9quent un acteur temporaire de r\u00e9f\u00e9rence de la v\u00e9rit\u00e9 de notre crise civilisationnelle g\u00e9n\u00e9rale. Cette constante animation de la r\u00e9f\u00e9rence n\u00e9e de la vuln\u00e9rabilit\u00e9 et de la sensibilit\u00e9 des psychologies, contribue elle-m\u00eame \u00e0 renforcer vuln\u00e9rabilit\u00e9 et sensibilit\u00e9 de la psychologie, alimentant le sentiment et le climat g\u00e9n\u00e9ral dans le sens qu&rsquo;on comprend. Ce cercle vicieux d&rsquo;auto-alimentation serait plut\u00f4t vertueux que vicieux&#8230;<\/p>\n<\/p>\n<p><p>\tCela nous conduit \u00e0 observer, une fois de plus, que la crise d&rsquo;effondrement du Syst\u00e8me est aussi, et en un sens <strong>est d&rsquo;abord<\/strong> une immense crise collective des psychologies, en m\u00eame temps qu&rsquo;une crise de la psychologie collective, les deux choses s&rsquo;alimentant l&rsquo;une l&rsquo;autre. Nous sommes pris dans un tissu crisique absolument herm\u00e9tique, qui ne nous laisse aucun r\u00e9pit, qui met et maintient cadenass\u00e9e dans nos t\u00eates la Grande Crise G\u00e9n\u00e9rale, consciemment ou pas. Cela est certes inconfortable, et en g\u00e9n\u00e9ral extr\u00eamement angoissant, mais c&rsquo;est la voie oblig\u00e9e du d\u00e9roulement de cette crise et de son acc\u00e9l\u00e9ration vers l&rsquo;issue n\u00e9cessairement d\u00e9sirable de l&rsquo;autodestruction du Syst\u00e8me ; et certes, c&rsquo;est, d&rsquo;une fa\u00e7on paradoxale et ironique si l&rsquo;on veut, la contribution cette fois r\u00e9solument antiSyst\u00e8me de <em>sapiens<\/em> \u00e0 la chose.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 4 f\u00e9vrier 2014 \u00e0 07H00<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mort d&rsquo;un com\u00e9dien et notre intense fragilit\u00e9 psychologique La mort du com\u00e9dien Philip Seymour Hoffman, tr\u00e8s probablement \u00e0 cause d&rsquo;une overdose d&rsquo;h\u00e9ro\u00efne, est un \u00e9v\u00e9nement public tragique par tous les composants de l&rsquo;\u00e9v\u00e9nement : l&rsquo;excellence du com\u00e9dien d\u00e9passant tr\u00e8s largement le standard hollywoodien, son \u00e9tat psychologique qui l&rsquo;avait amen\u00e9 \u00e0 la consommation de drogue,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4646,4270,8874,3228,5651,4019,2651,11307,15596,15591,3371,8490,4954,15597,11844,5775,15592,2785,12738,3099,15594,4414,15595,3014,15593],"class_list":["post-73679","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-antisysteme","tag-autodestruction","tag-bog","tag-crise","tag-deffondrement","tag-drogue","tag-du","tag-eternel","tag-heroine","tag-hoffman","tag-hollywood","tag-hollywoodisme","tag-jenkins","tag-legalisation","tag-nimmo","tag-now","tag-overdose","tag-philip","tag-present","tag-psychologie","tag-sensibilite","tag-seymour","tag-shapiro","tag-systeme","tag-vulnerablite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73679"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73679\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}