{"id":73689,"date":"2014-02-08T10:27:58","date_gmt":"2014-02-08T10:27:58","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/02\/08\/notes-sur-le-theme-de-lapocalypse\/"},"modified":"2014-02-08T10:27:58","modified_gmt":"2014-02-08T10:27:58","slug":"notes-sur-le-theme-de-lapocalypse","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/02\/08\/notes-sur-le-theme-de-lapocalypse\/","title":{"rendered":"Notes sur le th\u00e8me de l&rsquo;apocalypse"},"content":{"rendered":"<p><h2 class=\"common-article\">Notes sur le th\u00e8me de l&rsquo;apocalypse<\/h2>\n<\/p>\n<p><p>\t8 f\u00e9vrier 2014  L&rsquo;excellent chroniqueur et auteur Tom Engelhardt, \u00e9diteur du site <em>TomDispatch.com<\/em> lui-m\u00eame d&rsquo;excellente r\u00e9putation, est particuli\u00e8rement pr\u00e9occup\u00e9 par la crise climatique et ses cons\u00e9quences. Nombre de collaborateurs de son site s&rsquo;int\u00e9ressent \u00e0 la question sous divers angles, mais c&rsquo;est bien dans ses propres chroniques, lorsqu&rsquo;il prend lui-m\u00eame la plume, qu&rsquo;on mesure sa propre pr\u00e9occupation personnelle \u00e0 cet \u00e9gard. <\/p>\n<\/p>\n<p><p>\tNous nous attachons \u00e0 l&rsquo;une des plus r\u00e9centes de ses chroniques, en date du <a href=\"http:\/\/www.tomdispatch.com\/blog\/175801\/\" class=\"gen\">2 f\u00e9vrier 2014<\/a>. Engelhardt y aborde un sujet plus sp\u00e9cifique de cette question, et sans doute un des aspects les plus importants, qui est le sujet de la pr\u00e9sence, ou plut\u00f4t de l&rsquo;absence dans les nouvelles de la crise climatique et de ses implications apocalyptiques : \u00ab<em>Ending the World the Human Way \u00a0Climate Change as the Anti-News.<\/em>\u00bb<\/p>\n<h3>Mises au point et d\u00e9finitions<\/h3>\n<\/p>\n<p><p>\tRenouvelons aussit\u00f4t l&rsquo;avertissement que nous donnons \u00e0 l&rsquo;une ou l&rsquo;autre occasion, lorsque nous abordons nous-m\u00eames le sujet, et nous disons notre conviction que c&rsquo;est dans le m\u00eame esprit qu&rsquo;Engelhardt lui-m\u00eame l&rsquo;aborde effectivement. Nous \u00e9cartons le facteur un peu trop spectaculaire de la pol\u00e9mique secondaire portant sur la question technique de mesurer l&rsquo;action humaine pr\u00e9cis\u00e9ment sur la question \u00e9troite des \u00e9missions de CO2 d&rsquo;origine humaine sur le changement climatique, ou <em>global warming<\/em>, avec les positions diverses allant de la n\u00e9gation d&rsquo;un <em>global warming<\/em>, voire d&rsquo;une crise climatique, \u00e0 la question de la part humaine dans ces aspects de la crise g\u00e9n\u00e9rale, lorsque celle-ci est admise.<\/p>\n<\/p>\n<p><p>\tCe qui nous int\u00e9resse c&rsquo;est la Grande Crise G\u00e9n\u00e9rale ou Grande Crise du monde, et crise sans aucun doute eschatologique de la destruction du monde dans le sens physique du terme, qui concerne les diverses et nombreuses activit\u00e9s, et cons\u00e9quences colossales, du syst\u00e8me de d\u00e9veloppement qui s&rsquo;est impos\u00e9 plus qu&rsquo;il n&rsquo;a \u00e9t\u00e9 choisi depuis la fin du XVIIIe si\u00e8cle, l\u00e0 o\u00f9 nous situons le ph\u00e9nom\u00e8ne du <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_d_cha_nement_de_la_mati_re__05_11_2012.html\" class=\"gen\">d\u00e9cha\u00eenement de la Mati\u00e8re<\/a>. Ce rangement que nous estimons de type m\u00e9tahistorique est largement confirm\u00e9 par les scientifiques eux-m\u00eames, dans leur domaine, avec la probable acceptation officielle d&rsquo;un nouveau rangement g\u00e9ologique, avec l&rsquo;institution d&rsquo;une nouvelle \u00e8re g\u00e9ologique, l&rsquo;anthropoc\u00e8ne, \u00e0 partir de la fin du XVIIIe si\u00e8cle,  1784 exactement, comme date-symbole, voyant l&rsquo;introduction des premi\u00e8res machines \u00e0 vapeur (en Angleterre) et donc de ce qu&rsquo;Alain Gras nomme <em>Le choix du feu<\/em> dans son livre \u00e9ponyme. On a rappel\u00e9 encore r\u00e9cemment notre analyse \u00e0 cet \u00e9gard, le <a href=\"http:\/\/www.dedefensa.org\/article-les_origines_du_mal_01_12_2013.html\" class=\"gen\">1er d\u00e9cembre 2013<\/a>.<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit donc de la Grande Crise eschatologique de la destruction du monde, essentiellement suscit\u00e9 par l&rsquo;activit\u00e9 humaine, et qui constitue par cons\u00e9quent <strong>autre chose<\/strong> que les cycles physiques et g\u00e9ologiques habituels conduisant \u00e0 des modifications des conditions physiques du monde. Il s&rsquo;agit d&rsquo;une sorte de gigantesque artefact g\u00e9ologique, une rupture artificielle fondamentale, aux cons\u00e9quences colossales et hors de la seule dynamique naturelle, qui se sont d\u00e9velopp\u00e9es \u00e0 une vitesse exponentielle. Cette rupture n&rsquo;a <strong>plus aucun rapport<\/strong> avec l&rsquo;\u00e9volution naturelle du monde. En effet, l&rsquo;\u00e9l\u00e9ment de la rapidit\u00e9 des changements de destruction est fondamental, unique, central, et donne toute sa substance \u00e0 la Grande Crise, qui s&rsquo;ins\u00e8re ou encadre c\u00a0\u00bbest selon ce que nous nommons la crise d&rsquo;effondrement du Syst\u00e8me que nous sommes <strong>en train de vivre<\/strong>. Nous ressentons aujourd&rsquo;hui tous les effets <strong>ultimes<\/strong> du processus d\u00e9marr\u00e9 avec le d\u00e9cha\u00eenement de la Mati\u00e8re, effets catastrophiques et eschatologiques,  quelque chose qui est <strong>en essence<\/strong> absolument \u00e9tranger \u00e0 l&rsquo;\u00e9volution normale du monde. Nous recommandons le livre <em>L&rsquo;\u00e9v\u00e9nement anthropoc\u00e8ne<\/em>, de Christophe Bonneuil et Jean-Baptise Fressoz (Seuil, octobre 2013), qui constitue une excellente documentation \u00e0 cet \u00e9gard, d\u00e9montrant l&rsquo;aspect catastrophique de l&rsquo;action humaine sur l&rsquo;\u00e9volution du monde, essentiellement par la disposition de la puissance totalement artificielle du technologisme, et des conditions de son emploi au profit de conceptions d\u00e9structurantes, dissolvantes et \u00e0 finalit\u00e9 d&rsquo;entropisation.<\/p>\n<\/p>\n<p><p>\tDans le m\u00eame ordre d&rsquo;id\u00e9es de notre d\u00e9finition des termes employ\u00e9s dans cette note, nous pr\u00e9cisons que les termes apocalypse et d\u00e9riv\u00e9s qui sont utilis\u00e9s, le sont d&rsquo;une mani\u00e8re symbolique et pour ainsi dire impressionniste, sans signifier quoi que ce soit de pr\u00e9cis contenu dans la d\u00e9finition du mot, y compris dans le sens religieux certes. Nous employons ce mot pour d\u00e9signer la dimension g\u00e9n\u00e9rale, eschatologique, hors du contr\u00f4le humain, des \u00e9v\u00e9nements que nous vivons. Utilis\u00e9 comme facilit\u00e9 de langage et outil de raisonnement, cela n&rsquo;interdit aucune possibilit\u00e9, mais cela n&rsquo;en indique aucune pr\u00e9cis\u00e9ment.<\/p>\n<h3>\u00ab<em>This is the road to hell<\/em>\u00bb<\/h3>\n<\/p>\n<p><p>\tNous donnons ci-dessous quelques paragraphes d&rsquo;introduction du texte d&rsquo;Engelhardt, et les deux de conclusion, simplement pour situer le probl\u00e8me : pourquoi cet \u00e9v\u00e9nement colossal, qui devrait surpasser tous les autres dans notre syst\u00e8me de la communication, est-il en fait compl\u00e8tement absent dans l&rsquo;expos\u00e9 de ses cons\u00e9quences catastrophiques de plus en plus probables et de plus rapproch\u00e9es, et des cons\u00e9quences sans le moindre doute situ\u00e9es dans la dimension eschatologique&#8230; Engelhardt termine par la description de \u00ab<em>The Road to Hell<\/em>\u00bb, comme le <a href=\"http:\/\/www.lyricsdepot.com\/chris-rea\/the-road-to-hell-part-ii.html\" class=\"gen\">chantait<\/a> de fa\u00e7on pr\u00e9monitoire Chris Rea, en 1989.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Here&rsquo;s the scoop: When it comes to climate change, there is no story, not in the normal news sense anyway.<\/em> [&#8230;] <em>Don&rsquo;t misunderstand me. Each of the above was reported somewhere and climate change itself is an enormous story, if what you mean is Story with a capital S. It could even be considered the story of all stories.  It&rsquo;s just that climate change and its component parts are unlike every other story from the Syrian slaughter and the problems of Obamacare to Bridgegate and Justin Bieber&rsquo;s arrest. The future of all other stories, of the news and storytelling itself, rests on just how climate change manifests itself over the coming decades or even century.  What happens in the 2014 midterms or the 2016 presidential elections, in our wars, politics, and culture, who is celebrated and who ignored  none of it will matter if climate change devastates the planet. Climate change isn&rsquo;t the news and it isn&rsquo;t a set of news stories.  It&rsquo;s the prospective end of all news.<\/em> <strong><em> Think of it as the anti-news.<\/em><\/strong><\/p>\n<\/p>\n<p><p>\t\u00bb<em>All the rest is part of the annals of human history: the rise and fall of empires, of movements, of dictatorships and democracies, of just about anything you want to mention.  The most crucial stories, like the most faddish ones, are  every one of them  passing phenomena, which is of course what makes them the news.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Climate change isn&rsquo;t.<\/em> [&#8230;] <\/p>\n<\/p>\n<p><p>\t\u00bb<em>We&rsquo;re so used to the phrase the news that we often forget its essence: what&rsquo;s new multiplied by that s.  It&rsquo;s true that the new can be repetitively so.  How many times have you seen essentially the same story about Republicans and Democrats fighting on Capitol Hill?  But the momentousness of climate change, which isn&rsquo;t hard to discern, is difficult to regularly turn into meaningful new headlines (Humanity Doomed If&#8230;), to repeatedly and successfully translate into a form oriented to the present and the passing moment, to what happened yesterday, today, and possibly tomorrow.<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>\t\u00bb<em>In fact, one of the grim wonders of climate change has been the ability of Big Energy and its lobbyists to politicize an issue that wouldn&rsquo;t normally have a left or right, and to make bad science into an ongoing news story.  In other words, an achievement that couldn&rsquo;t be more criminal in nature has also been their great coup de th\u00e9\u00e2tre. In a world heading toward the brink, here&rsquo;s the strange thing: most of the time that brink is nowhere in sight.  And how can you get people together to solve a human-caused problem when it&rsquo;s so seldom meaningfully in the news (and so regularly challenged by energy interests when it is)?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>This is the road to hell and it has not been paved with good intentions.  If we stay on it, we won&rsquo;t even be able to say that future historians considered us both a wonder (for our ability to create world-ending scenarios and put them into effect) and a disgrace (for our inability to face what we had done).  By then, humanity might have arrived at the end of history, and so of historians.<\/em>\u00bb<\/p>\n<h3>Information sur l&rsquo;apocalypse en cours<\/h3>\n<\/p>\n<p><p>\tNous nous saisissons de cette intervention d&rsquo;Engelhardt pour d\u00e9velopper notre propre intervention. Cela commencera par une r\u00e9f\u00e9rence substantielle de deux textes publi\u00e9s sur ce site. Ces textes nous rappellent que le probl\u00e8me que soul\u00e8ve Engelhardt se posait d\u00e8s 2006-2007, et qu&rsquo;il avait alors re\u00e7u un commencement de r\u00e9ponse, venu des milieux les plus officiels du Syst\u00e8me. En fait, la question du <em>global warming<\/em> \u00e9tendue \u00e0 sa dimension de Grande Crise de la destruction du monde (selon notre \u00e9nonc\u00e9) est pos\u00e9e <strong>officiellement<\/strong>, donc sur l&rsquo;initiative m\u00eame de repr\u00e9sentants du Syst\u00e8me, d\u00e8s l&rsquo;automne 2006 avec la publication du rapport Stern, r\u00e9alis\u00e9 \u00e0 la demande du gouvernement britannique (voir le <a href=\"http:\/\/www.dedefensa.org\/article-la_crise_climatique_entre_en_scene_27_10_2006.html\" class=\"gen\">27 octobre 2006<\/a>).<\/p>\n<\/p>\n<p><p>\tD&rsquo;abord, voici des extraits d&rsquo;un texte du <a href=\"http:\/\/www.dedefensa.org\/article-notre_devoir_d_apocalypse_12_03_2007.html\" class=\"gen\">12 mars 2007<\/a>, reprenant une partie de la rubrique <em>de defensa<\/em> de notre Lettre d&rsquo;Analyse<D> <em>de defensa &#038; eurostrat\u00e9gie<\/em> (<em>dd&#038;e<\/em>) volume 22 n\u00b08 du 10 janvier 2007. Le th\u00e8me \u00e9tait d&rsquo;ores et d\u00e9j\u00e0 du type comment penser l&rsquo;apocalypse ?, comment informer \u00e0 propos de l&rsquo;apocalypse ?, impliquant alors que la perspective \u00e9tait officiellement  admise et que l&rsquo;on pouvait se pencher sur les mani\u00e8res de l&rsquo;envisager. En d&rsquo;autres termes, la probl\u00e9matique dont Engelhardt se plaint de l&rsquo;absence dans le flux actuel (2014) de l&rsquo;information, se trouvait dans ce flux en 206-2008 et il \u00e9tait unanimement admis que l&rsquo;on pouvait s&rsquo;en pr\u00e9occuper \u00e0 visage d\u00e9couvert. Nous extrayons deux passages du texte cit\u00e9&#8230; Le premier envisage les conditions que le professionnel de l&rsquo;information et de la r\u00e9flexion \u00e0 partir de cette information devait affronter pour mener \u00e0 bien cette t\u00e2che.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Lorsque nous nous retournons sur les trente et quarante derni\u00e8res ann\u00e9es et mesurons le bouleversement formidable qui a transform\u00e9 le m\u00e9tier de l&rsquo;information, le m\u00e9tier de commentateur et d&rsquo;observateur de la marche du monde, alors nous sommes assur\u00e9s de dire une v\u00e9rit\u00e9 en parlant d&rsquo;ind\u00e9pendance et de responsabilit\u00e9. Notre m\u00e9tier a acquis des bottes de sept lieues. L&rsquo;ind\u00e9pendant, sans moyens, sans prestige, est devenu un g\u00e9ant de l&rsquo;information,  et, s&rsquo;il le m\u00e9rite, il est \u00e9cout\u00e9 et consult\u00e9 comme tel. Cela est bien, puisque le monde officiel, nos \u00e9lites, a abdiqu\u00e9 toute pr\u00e9tention \u00e0 la dignit\u00e9 et \u00e0 l&rsquo;ind\u00e9pendance du jugement. C&rsquo;est \u00e0 lui, \u00e0 cet ind\u00e9pendant charg\u00e9 d&rsquo;observer l&rsquo;\u00e9tat du monde et d&rsquo;en faire rapport, \u00e0 tenir ferme le r\u00f4le que nos \u00e9lites, du ministre \u00e0 l&rsquo;intellectuel officiel, de l&rsquo;expert \u00e0 l&rsquo;artiste consacr\u00e9, refusent d\u00e9sormais de tenir.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Ce r\u00f4le n&rsquo;est pas simple. Il s&rsquo;agit du m\u00e9lange d&rsquo;une fonction de sentinelle, d&rsquo;un double regard qui s\u00e9pare l&rsquo;apparence de la substance, d&rsquo;une psychologie qui doit tenir bon malgr\u00e9 l&rsquo;impossible esp\u00e9rance que nous refusent les perspectives du monde, malgr\u00e9 la menace qui existe contre l&rsquo;\u00e9quilibre de l&rsquo;esprit. Il s&rsquo;agit de mesurer la trag\u00e9die du monde. Nous ne pouvons tenir, nous autres ind\u00e9pendants, qu&rsquo;en acceptant l&rsquo;inspiration. Nous devons \u00eatre n\u00e9cessairement inspir\u00e9s, ou bien nous ne servons \u00e0 rien et tout ce gigantesque outil, et ce n\u00e9cessaire remplacement des \u00e9lites d\u00e9missionnaires, n&rsquo;auront pas de raison d&rsquo;\u00eatre. C&rsquo;est une t\u00e2che ardue.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Nous voulons parler, bien entendu, des crises gigantesques qui nous pressent, qui n&rsquo;ont plus rien \u00e0 voir, d\u00e9sormais, avec les classifications anciennes, les guerres, les r\u00e9volutions, les conqu\u00eates. Nous sommes entr\u00e9s dans le domaine de l&rsquo;inconnu paroxystique, que l&rsquo;on parle de la crise de l&rsquo;\u00e9nergie ou de la crise climatique, dans ce domaine o\u00f9 les \u00e9v\u00e9nements catastrophiques ont n\u00e9cessairement une r\u00e9sonance d&rsquo;apocalypse. Rien ne nous y pr\u00e9parait. Au contraire, la vanit\u00e9 et la l\u00e2chet\u00e9 de l&rsquo;esprit humain n&rsquo;ont cess\u00e9 de faire miroiter \u00e0 nos esprits et \u00e0 nos m\u00e9moires, par une voie ou par une autre, par de multiples voix charmeuses comme autant de sir\u00e8nes acharn\u00e9es \u00e0 tromper et \u00e0 encha\u00eener leur Ulysse, les lendemains qui chantent et le Progr\u00e8s globalisant du monde. Rien de cela ne s&rsquo;est produit. Si certains le savent, aucune voix ne s&rsquo;\u00e9l\u00e8ve, qui puisse marquer l&rsquo;\u00e9poque par sa lucidit\u00e9, pour d\u00e9noncer la tromperie \u00e0 laquelle il est demand\u00e9 une compl\u00e8te soumission, aucune voix qui puisse d\u00e9passer son destin individuel pour oser embrasser le destin collectif qui nous menace.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Le d\u00e9fi le plus grand dans cette situation se d\u00e9finit par l&rsquo;audace de la pens\u00e9e qu&rsquo;il nous faut, le saut du jugement dans l&rsquo;inconnu de situations gigantesques que seuls quelques rares esprits, des ind\u00e9pendants certes, sont capables d&#8217;embrasser. Il est difficile de faire preuve d&rsquo;audace, c&rsquo;est-\u00e0-dire d&rsquo;alacrit\u00e9 et d&rsquo;allant, pour juger d&rsquo;une situation qui ne semble laisser aucun espoir. Il est difficile de continuer \u00e0 esp\u00e9rer en \u00e9tant, d&rsquo;une certaine fa\u00e7on, sans espoir. Il faut, \u00e0 la fois, une rage qui vous remue le corps et une inspiration \u00e9vidente qui vous entra\u00eene et vous \u00e9l\u00e8ve l&rsquo;\u00e2me. A ce compte, et \u00e0 ce compte seulement, le gladiateur se trouve pr\u00eat au combat.<\/em>\u00bb<\/p>\n<h3>Comment penser l&rsquo;apocalypse ?<\/h3>\n<\/p>\n<p><p>\tPlus loin,  en conclusion de l&rsquo;extrait de <em>dd&#038;e<\/em> cit\u00e9, nous pr\u00e9cisions les conditions op\u00e9rationnelles auxquelles nous devions faire face. Nous jugions que certains \u00e9v\u00e9nements tr\u00e8s pressants et tr\u00e8s proches devaient effectivement nous placer dans un laps de temps tr\u00e8s rapproch\u00e9 dans des conditions o\u00f9 nous devrions nous atteler \u00e0 cette t\u00e2che que nous d\u00e9finirions un peu plus tard comme le devoir de penser l&rsquo;apocalypse.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Pourtant, les \u00e9v\u00e9nements nous pressent. Quelles crises (ou r\u00e9alisation, ou prise en compte de quelles crises d\u00e9j\u00e0 existantes) sont venues s&rsquo;ajouter \u00e0 notre architecture? Nous en distinguons deux, essentiellement.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em> Depuis octobre-d\u00e9cembre 2006, la crise climatique est brutalement accept\u00e9e, avec ses perspectives les plus extr\u00eames. C&rsquo;est la crise de la survie de l&rsquo;esp\u00e8ce, remarque, avec quelle sobri\u00e9t\u00e9, un tr\u00e8s haut fonctionnaire international dans une organisation europ\u00e9enne de s\u00e9curit\u00e9. Du rapport Stern \u00e0 la mobilisation sur le th\u00e8me \u00e0 la Commission europ\u00e9enne, tout le confirme.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em> D\u00e9sormais, la crise am\u00e9ricaniste est prise tr\u00e8s au s\u00e9rieux par des cercles dirigeants europ\u00e9ens au point o\u00f9, selon une autre source europ\u00e9enne de haut niveau, certaines bureaucraties travaillent d&rsquo;ores et d\u00e9j\u00e0 sur la question: qu&rsquo;allons-nous faire dans l&rsquo;hypoth\u00e8se d&rsquo;un effondrement progressif, peut-\u00eatre rapide, du syst\u00e8me am\u00e9ricain?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>On comprend ainsi, \u00e0 peine \u00e9voqu\u00e9es deux perspectives d&rsquo;apocalypse,  car que peut-on imaginer de pire que ces deux crises, aux niveaux de la nature du monde et de la politique du monde des hommes?  combien l&rsquo;\u00e9volution des choses s&rsquo;acc\u00e9l\u00e8re dans un crescendo tragique. La chose, pour ceux qui la connaissent et qui la mesurent, est d&rsquo;autant plus effrayante qu&rsquo;elle se d\u00e9roule dans une atmosph\u00e8re d\u00e9l\u00e9t\u00e8re. Il faut bien du courage pour \u00eatre courageux.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Le fond g\u00e9n\u00e9ral sur lequel se met en place cette terrible prise de conscience des crises de la fin des temps est celui d&rsquo;un syst\u00e8me dont la raison de vivre n&rsquo;est plus qu&rsquo;une repr\u00e9sentation virtualiste et faussaire du monde, une repr\u00e9sentation forcen\u00e9e et hors de toute raison, sans parler de courage et de dignit\u00e9. Il faut en effet du courage (bis) pour explorer les conditions de ces crises terribles alors que triomphe une entreprise syst\u00e9matique de dissimulation des conditions de ces crises terribles; alors que r\u00e8gne une volont\u00e9 absolument et \u00e9videmment syst\u00e9mique, mais aussi inconsciente, robotis\u00e9e, de pr\u00f4ner une fa\u00e7on de vivre et une perception du monde qui bafouent chaque jour le bon sens et la r\u00e9alit\u00e9; alors que se manifeste un penchant irr\u00e9sistible et sans cesse acc\u00e9l\u00e9r\u00e9 pour le nihilisme le plus complet, le plus insensible \u00e0 toute dignit\u00e9 et \u00e0 toute mesure. C&rsquo;est un temps o\u00f9 les \u00e2mes doivent se tremper si elles ne veulent pas mourir. C&rsquo;est un temps de fer et de feu.<\/em>\u00bb<\/p>\n<h3>2008, ann\u00e9e fatidique<\/h3>\n<\/p>\n<p><p>\tDans la logique de cette analyse, nous \u00e9voquions le <a href=\"http:\/\/www.dedefensa.org\/article-l_esprit_de_l_apocalypse_salue_l_ann_e_2008_02_01_2008.html\" class=\"gen\">2 janvier 2008<\/a>, ce que pouvait devenir cette ann\u00e9e 2008 \u00e0 l&rsquo;aune de cet esprit de l&rsquo;apocalypse qui s&rsquo;\u00e9tait install\u00e9 comme une des premi\u00e8res pr\u00e9occupations des r\u00e9flexions g\u00e9n\u00e9rales, y compris dans le Syst\u00e8me. Nous nous r\u00e9f\u00e9rions notamment au livre que venait de publier Ren\u00e9 Girard, <em>Achever Clausewitz<\/em>, dans lequel le philosophe d\u00e9crivait ce qu&rsquo;il jugeait \u00eatre les temps nouveaux qui s&rsquo;installaient, selon une sorte de d\u00e9finition qu&rsquo;on retrouvait dans diverses r\u00e9flexions, et qui rencontrait nos propres d\u00e9veloppements constatant l&rsquo;int\u00e9gration des \u00e9v\u00e9nements politiques courants de plus en plus marqu\u00e9s par la violence et la confusion d&rsquo;une part, des \u00e9v\u00e9nements naturels caus\u00e9s par les d\u00e9r\u00e8glements suscit\u00e9s par la crise de destruction du monde d&rsquo;autre part : \u00ab<em>La violence est aujourd&rsquo;hui d\u00e9cha\u00een\u00e9e au niveau de la plan\u00e8te enti\u00e8re, provoquant ce que les textes apocalyptiques annon\u00e7aient: une confusion entre les d\u00e9sastres caus\u00e9s par la nature et les d\u00e9sastres caus\u00e9s par les hommes, la confusion du naturel et de l&rsquo;artificiel&#8230;<\/em>\u00bb A partir de cette description, Girard r\u00e9clamait un autre type de rationalit\u00e9 pour penser la crise, ou, selon notre approche d\u00e9finie par cette expression, pour penser l&rsquo;apocalypse : \u00ab[&#8230;N]<em>ous sommes entr\u00e9s dans une p\u00e9riode o\u00f9 l&rsquo;anthropologie va devenir un outil plus pertinent que les sciences politiques. Nous allons devoir changer radicalement notre interpr\u00e9tation des \u00e9v\u00e9nements, cesser de penser en hommes des Lumi\u00e8res, envisager enfin la radicalit\u00e9 de la violence, et avec elle constituer un tout autre type de rationalit\u00e9. Les \u00e9v\u00e9nements l&rsquo;exigent.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tA partir de ces observations, nous d\u00e9veloppions une r\u00e9flexion qui, effectivement, prenait en compte comme un fait acquis de la situation internationale cette perspective de la Grande Crise de destruction du monde, consid\u00e9r\u00e9e d\u00e9sormais comme un fait patent, ind\u00e9niable. Nous envisagions effectivement que des \u00e9v\u00e9nements, dans cette ann\u00e9e 2008, allaient d\u00e9velopper des situations o\u00f9 ce facteur de la Grande Crise aurait sa pr\u00e9sence assur\u00e9e, et cette pr\u00e9sence reconnue comme telle, y compris par les autorit\u00e9s-Syst\u00e8me elles-m\u00eames. Nous donnions des pr\u00e9cisions, \u00e0 cet \u00e9gard, \u00e0 propos de tels \u00e9v\u00e9nements&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Ce que Girard sugg\u00e8re, c&rsquo;est un changement de notre psychologie pour aborder la puissance des \u00e9v\u00e9nements qui nous pressent, et les appr\u00e9cier avec un autre esprit que celui auquel nous sommes accoutum\u00e9s. Nous dirions que cela va de soi, a contrario finalement,  par le constat que la psychologie actuelle, telle qu&rsquo;elle est contrainte par les normes impos\u00e9es par la civilisation en cours, est totalement incapable de supporter le choc des \u00e9v\u00e9nements qui s&rsquo;amassent, sinon par aveuglement volontaire quoique inconscient ou menac\u00e9e par la folie,  le premier menant au second sur le terme.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Parlons de cet aveuglement volontaire quoique inconscient. Le constat que nous faisons est que la fatalit\u00e9 de la modernit\u00e9, notamment avec l&rsquo;aide des formidables moyens technologiques qu&rsquo;elle a d\u00e9gag\u00e9s, notamment dans le domaine de la communication, a entra\u00een\u00e9 et continue d&rsquo;entra\u00eener comme mesure d&rsquo;urgence de sauvegarde d&rsquo;elle-m\u00eame (de la modernit\u00e9) une d\u00e9formation de la rationalit\u00e9 courante. Nous sommes pass\u00e9s d&rsquo;une d\u00e9formation transformationnelle notamment fournie par les r\u00e9f\u00e9rences utopiques, \u00e0 une d\u00e9formation substantielle, avec ce que nous d\u00e9signons comme le virtualisme, que nous pourrions d\u00e9signer comme le stade ultime de l&rsquo;utopie. (Nous parlons bien d&rsquo;une psychologie d\u00e9form\u00e9e, et non d&rsquo;une propagande assum\u00e9e. Les virtualistes sont aussi les premiers \u00e0 \u00eatre virtualis\u00e9s ; ils croient \u00e0 l&rsquo;univers en faux-semblant qu&rsquo;ils cr\u00e9ent, au contraire des propagandistes qui ne font que travailler sur des moyens de transformer la perception des autres sans prendre position sur la chose ainsi cr\u00e9\u00e9e.) Une telle situation, qui implique le naufrage de la rationalit\u00e9 telle que nous la connaissons et la pratiquons, implique a contrario la n\u00e9cessit\u00e9 de cr\u00e9er une autre rationalit\u00e9,  disons, pour rejoindre notre citation sans pour autant partager l&rsquo;analyse que fait Girard des causes de cette n\u00e9cessit\u00e9, un tout autre type de rationalit\u00e9. Sans aucun doute, <\/em>[l]<em>es \u00e9v\u00e9nements l&rsquo;exigent.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>(Girard base son exigence sur la forme de la violence, c&rsquo;est-\u00e0-dire, selon lui, la guerre qui devient apocalyptique. Nous avons une autre approche, \u00e0 moins que l&rsquo;on mette en cause la substance m\u00eame de la guerre, et que le concept de guerre d\u00e9crive autre chose que ce qu&rsquo;il d\u00e9crit aujourd&rsquo;hui. La guerre est devenue, aujourd&rsquo;hui, quelque chose qui a essentiellement \u00e0 voir avec la communication et marginalement avec l&rsquo;op\u00e9ration guerri\u00e8re. Elle est de plus en plus infaisable par refus de coop\u00e9ration des adversaires de ceux qui la promeuvent.)<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Cette dynamique folle du d\u00e9veloppement machiniste du Progr\u00e8s, am\u00e8ne \u00e0 la perte de contr\u00f4le, \u00e0 la prise du pouvoir par un processus syst\u00e9mique contre lequel on se trouve d\u00e9sarm\u00e9 et qui nous emprisonne si l&rsquo;on ne modifie pas sa rationalit\u00e9 critique qui permet effectivement de porter un jugement lib\u00e9r\u00e9. On conclut effectivement que la crise actuelle, notre crise syst\u00e9mique fondamentale est moins cette question machiniste (\u00e9conomique et technologique) qui en est l&rsquo;origine et le moteur et qui existe depuis longtemps, qu&rsquo;une question psychologique dans un l&rsquo;aspect d\u00e9sormais essentiel de son fondement,  c&rsquo;est-\u00e0-dire notre crise psychologique, conduisant \u00e0 la recherche d&rsquo;\u00abun tout autre type de rationalit\u00e9\u00bb pour la r\u00e9soudre. C&rsquo;est notre psychologie qui a permis \u00e0 la b\u00eate de se d\u00e9cha\u00eener et qui nous a conduits \u00e0 nous encha\u00eener, par fascination et vanit\u00e9 tout autant, \u00e0 son d\u00e9veloppement incontr\u00f4l\u00e9. C&rsquo;est elle seule, notre psychologie, si nous acceptons l&rsquo;id\u00e9e qu&rsquo;il nous faut d\u00e9velopper une nouvelle rationalit\u00e9, qui nous permettrait de nous en lib\u00e9rer: non seulement pour observer d&rsquo;une fa\u00e7on radicalement critique un domaine jusqu&rsquo;ici consid\u00e9r\u00e9 comme tabou, mais pour \u00e9carter, gr\u00e2ce \u00e0 cette vision critique, notre tendance syst\u00e9mique \u00e0 confondre l&rsquo;id\u00e9e de la force avec l&rsquo;id\u00e9e du bien et \u00e0 faire d&rsquo;une fonction dynamique (la force) une fonction morale (le bien).<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Il nous appara\u00eet \u00e9vident que l&rsquo;id\u00e9e d&rsquo;une psychologie \u00e9voluant de fa\u00e7on \u00e0 pouvoir penser l&rsquo;apocalypse comme on pense un \u00e9v\u00e9nement historique possible est une voie acceptable pour tenter d&rsquo;atteindre \u00e0 ce \u00abtout autre type de rationalit\u00e9\u00bb que r\u00e9clame Girard. L&rsquo;ann\u00e9e 2008 pourrait \u00eatre un bon exercice pour cela, dans la mesure o\u00f9 elle pourrait \u00eatre une ann\u00e9e o\u00f9 certaines r\u00e9alit\u00e9s pourraient s&rsquo;imposer et faire voler en \u00e9clats notre virtualisme (nous pensons notamment aux \u00e9v\u00e9nements que pourrait susciter, aux USA d&rsquo;abord et ailleurs ensuite, l&rsquo;\u00e9lection pr\u00e9sidentielle US).<\/em>\u00bb<\/p>\n<h3>Pourquoi rien de tout cela ne s&rsquo;est r\u00e9alis\u00e9 ?<\/h3>\n<\/p>\n<p><p>\tDans son article, Engelhardt emploie l&rsquo;expression d&rsquo;<em>anti-news<\/em> pour marquer ce qu&rsquo;il juge \u00eatre l&rsquo;\u00e9tat actuel de l&rsquo;information sur ce que nous d\u00e9finissions, nous, comme la crise de la destruction du monde, et m\u00eame comme la crise eschatologique de la destruction du monde. Il remercie m\u00eame celui qui lui a sugg\u00e9r\u00e9 l&rsquo;expression, qui va bien au-del\u00e0 d&rsquo;une sorte d&rsquo;aspect de censure par refus de la nouvelle, qui constitue presque une sorte d&rsquo;impossibilit\u00e9 d&rsquo;\u00eatre trait\u00e9 comme une nouvelle, par le canal classique de l&rsquo;information, par le syst\u00e8me de la communication. (Engelhardt  \u00ab<em>Note: I would like to thank Jonathan Schell for loaning me the term anti-news in relation to climate change.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tCette id\u00e9e doit \u00eatre d\u00e9velopp\u00e9e, en fonction du <strong>fait \u00e9vident<\/strong> qu&rsquo;en 2006-2008, l&rsquo;information sur la crise de la destruction du monde \u00e9tait entr\u00e9e dans le circuit du syst\u00e8me de la communication, et qu&rsquo;elle en a quasiment disparu comme le d\u00e9plore Engelhardt. (On peut accepter ce terme d&rsquo;<em>anti-news<\/em>, ou anti-nouvelle, dans le sens op\u00e9rationnel propos\u00e9 par Engelhardt en r\u00e9f\u00e9rence \u00e0 la disproportion de cette faible couverture informationnelle par rapport au gigantisme eschatologique <strong>indescriptible<\/strong> de la chose, m\u00eame si sa pertinence peut \u00eatre mise en question. Ce terme d&rsquo;indescriptible, renforc\u00e9 d&rsquo;autres tel que indicible, etc., doit \u00eatre retenu, pour d\u00e9crire la r\u00e9alit\u00e9 ontologique du ph\u00e9nom\u00e8ne. Litt\u00e9ralement, on peut alors ais\u00e9ment envisager que la Grande Crise de la destruction du monde ne peut \u00eatre d\u00e9crite par le seul usage normal de l&rsquo;information.)<\/p>\n<\/p>\n<p><p>\tD&rsquo;abord les \u00e9v\u00e9nements &#8230; Dans notre deuxi\u00e8me texte r\u00e9f\u00e9renc\u00e9, nous annoncions que l&rsquo;ann\u00e9e 2008 pourrait \u00eatre celle o\u00f9 l&rsquo;on pourrait commencer \u00e0 penser l&rsquo;apocalypse : \u00ab<em> Il nous appara\u00eet \u00e9vident que l&rsquo;id\u00e9e d&rsquo;une psychologie \u00e9voluant de fa\u00e7on \u00e0 pouvoir penser l&rsquo;apocalypse comme on pense un \u00e9v\u00e9nement historique possible est une voie acceptable pour tenter d&rsquo;atteindre \u00e0 ce tout autre type de rationalit\u00e9 que r\u00e9clame Girard. L&rsquo;ann\u00e9e 2008 pourrait \u00eatre un bon exercice pour cela, dans la mesure o\u00f9 elle pourrait \u00eatre une ann\u00e9e o\u00f9 certaines r\u00e9alit\u00e9s pourraient s&rsquo;imposer et faire voler en \u00e9clats notre virtualisme (nous pensons notamment aux \u00e9v\u00e9nements que pourrait susciter, aux USA d&rsquo;abord et ailleurs ensuite, l&rsquo;\u00e9lection pr\u00e9sidentielle US).<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCurieusement, cette pr\u00e9vision se rapproche de certains \u00e9v\u00e9nements qui pourraient la justifier <em>a posteriori<\/em>, et elle est <strong>compl\u00e8tement fausse<\/strong> dans son esprit. Un \u00e9v\u00e9nement formidable a eu lieu aux USA, le 15 septembre 2008, avec l&rsquo;effondrement financier de Wall Street. Il avait lieu en marge de la campagne pr\u00e9sidentielle certes mais il exer\u00e7a sur cette campagne une influence consid\u00e9rable, qui n&rsquo;a jamais \u00e9t\u00e9 reconnue \u00e0 sa juste valeur. (Notre conviction est qu&rsquo;Obama l&rsquo;a emport\u00e9 notamment sinon principalement \u00e0 cause de la crise, ses qualit\u00e9s d&rsquo;orateur aussi bien que sa forte pr\u00e9sence \u00e0 la r\u00e9union de crise de la Maison-Blanche du 24 septembre 2008 rassemblant les principaux dirigeants US en activit\u00e9 ou sur le point de l&rsquo;\u00eatre, contrastant avec le stup\u00e9fiant mutisme de son adversaire John McCain dans cette occasion. La crise, et cette perception d&rsquo;Obama comme pr\u00e9sident de crise \u00e9carta l&rsquo;obstacle que pouvait constituer pour lui le fait d&rsquo;\u00eatre Africain-Am\u00e9ricain,  et notre conviction a toujours \u00e9t\u00e9 qu&rsquo;on a \u00e9lu le 5 novembre 2008 le meilleur pr\u00e9sident de crise disponible, avec la tromperie allant avec, et nullement le premier pr\u00e9sident Africain-Am\u00e9ricain.) On pouvait donc penser que la pr\u00e9vision avait une certaine v\u00e9rit\u00e9 et que cet \u00e9v\u00e9nement majeur de 2008 \u00e9tait promis \u00e0 permettre de commencer \u00e0 penser l&rsquo;apocalypse&#8230;<\/p>\n<\/p>\n<p><p>\tIl n&rsquo;en a rien \u00e9t\u00e9, directement consid\u00e9r\u00e9. L&rsquo;\u00e9v\u00e9nement 9\/15 a, au contraire, \u00e9touff\u00e9 toute perspective de penser l&rsquo;apocalypse, cela <strong>dans un premier temps<\/strong>.<\/p>\n<h3>Une crise de d\u00e9flection-<em>deception<\/em><\/h3>\n<\/p>\n<p><p>\tPar rapport \u00e0 notre imp\u00e9ratif de penser l&rsquo;apocalypse, la crise 9\/15 est une crise de d\u00e9flection-<em>deception<\/em>. Nous employons les deux mots d&rsquo;une fa\u00e7on r\u00e9aliste et symbolique \u00e0 la fois, avec le premier (d\u00e9flection) indiquant une modification de trajectoire, qui est l&rsquo;effet direct de 9\/15, et le second, le mot <em>deception<\/em> en anglais, faux-ami par excellence, qui signifie tromperie, qui est l&rsquo;effet indirect de 9\/15, et qui pourrait \u00eatre aussi bien v\u00e9cu comme une d\u00e9ception (en fran\u00e7ais).<\/p>\n<\/p>\n<p><p>\tCe qui s&rsquo;est pass\u00e9 avec 9\/15 est qu&rsquo;on a retrouv\u00e9 une crise classique, du d\u00e9j\u00e0-vu pour les esprits des dirigeants et du public, \u00e0 l&rsquo;occasion de laquelle les analogies historiques ne manqu\u00e8rent pas (le spectre de la Grande D\u00e9pression). L&rsquo;important dans cet \u00e9v\u00e9nement pour notre propos est qu&rsquo;on pouvait s&rsquo;\u00e9loigner de la recherche de penser l&rsquo;apocalypse et du \u00ab<em>tout autre type de rationalit\u00e9<\/em>\u00bb recommand\u00e9 par Girard. En quelque sorte, la crise \u00e9norme de 9\/15 \u00e9tait <strong>rassurante<\/strong>, au point qu&rsquo;un bouffon faisant-s\u00e9rieux comme Bernanke pouvait annoncer les jeunes pousses du printemps (la reprise) d\u00e8s mars 2009 et d\u00e9velopper sa campagne d&rsquo;intox d\u00e9flection-<em>deception<\/em> durant tout le printemps (voir le <a href=\"http:\/\/www.dedefensa.org\/article-l_etrange_optimisme_sans_espoir__23_05_2009.html\" class=\"gen\">23 mai 2009<\/a>). Bien entendu, tout cela \u00e9tait pure tromperie, mais la v\u00e9ritable tromperie (<em>deception<\/em>) \u00e9tait bien de remplacer une crise par l&rsquo;autre. <\/p>\n<\/p>\n<p><p>\tEffectivement, avec 9\/15 et imm\u00e9diatement apr\u00e8s, on ne pensa plus gu\u00e8re \u00e0 la crise climatique et il fut surtout question des <em>chicayas<\/em> autour de l&rsquo;\u00e9v\u00e9nement dit de <em>Climategate<\/em> pour savoir qui \u00e9tait exactement coupable de quoi dans la comptabilit\u00e9 des \u00e9missions de CO2 &#8230; On ne pensa plus gu\u00e8re \u00e0 la Grande Crise de la destruction du monde en tant que ph\u00e9nom\u00e8ne eschatologique fondamental, comme on l&rsquo;avait fait de l&rsquo;automne 2006 jusqu&rsquo;\u00e0 9\/15 (2008), mais en termes parcellaires et op\u00e9rationnels, \u00e0 l&rsquo;occasion d&rsquo;accidents ou de catastrophes climatiques, d&rsquo;anomalies g\u00e9ophysiques, etc. Mais il s&rsquo;agit ici d&rsquo;un point de vue relatif \u00e0 ce qui avait pr\u00e9c\u00e9d\u00e9, et une d\u00e9marche de liquidation de la d\u00e9marche impliquant de penser l&rsquo;apocalypse. Cette strat\u00e9gie naturelle de dissimulation du Syst\u00e8me (dissimulation, autre mot pour <em>deception<\/em>, proche de tromperie mais avec une nuance d&rsquo;\u00e9laboration en plus) portait une dimension bien plus grave pour le Syst\u00e8me ; parfait retour de flamme, tel est pris qui croyait prendre, inversion vertueuse prestement r\u00e9alis\u00e9e..<\/p>\n<h3>Un complot du Syst\u00e8me contre lui-m\u00eame<\/h3>\n<\/p>\n<p><p>\tDe nombreuses th\u00e8ses de manipulation et de complots ont \u00e9t\u00e9 \u00e9mises pour expliciter ou interpr\u00e9ter cette crise 9\/15, mais elles ressortent toutes des activit\u00e9s complotistes habituelles, comme elles ressortent \u00e9galement des effets d&rsquo;accaparement du pouvoir par l&rsquo;une ou l&rsquo;autre faction du Syst\u00e8me ; elles n&rsquo;ont aucun int\u00e9r\u00eat pour notre raisonnement. S&rsquo;il nous importe de retenir l&rsquo;id\u00e9e d&rsquo;un complot, c&rsquo;est \u00e0 une toute autre hauteur, dans un autre champ, dans un tout autre domaine qui est celui de la m\u00e9tahistoire.<\/p>\n<\/p>\n<p><p>\tDe notre point de vue, on pourrait tr\u00e8s logiquement interpr\u00e9ter la crise 9\/15 de 2008 comme une sorte de complot d\u00e9flection-<em>deception<\/em> du Syst\u00e8me contre lui-m\u00eame. Il est alors entendu que nous consid\u00e9rons le Syst\u00e8me comme une entit\u00e9, voire une \u00e9gr\u00e9gore, dont l&rsquo;activit\u00e9 r\u00e9pond \u00e0 une psychologie int\u00e9gr\u00e9e et \u00e0 une logique globale interne, et \u00e0 niveau d&rsquo;intelligence allant de la surpuissance extatique \u00e0 l&rsquo;autodestruction d&rsquo;une stupidit\u00e9 av\u00e9r\u00e9e. En effet, la dynamique que nous baptisions penser l&rsquo;apocalypse durant les ann\u00e9es fin 2006-d\u00e9but 2008 avait \u00e9t\u00e9 lanc\u00e9e par le Syst\u00e8me lui-m\u00eame (rapport Stern) ; c&rsquo;est donc contre lui-m\u00eame que la crise financi\u00e8re 9\/15 est activ\u00e9e et se d\u00e9veloppe si on consid\u00e8re cette crise effectivement comme de type d\u00e9flection-<em>deception<\/em>, destin\u00e9e \u00e0 d\u00e9tourner notre attention de la Grande Crise de destruction du monde <em>per se<\/em>. 9\/15 concentre toute l&rsquo;attention, toute la capacit\u00e9 d&rsquo;alarme et de d\u00e9bat, toute la potentialit\u00e9 de r\u00e9flexion autour de la probl\u00e9matique de la crise sectorielle de la finance encha\u00eenant sur l&rsquo;\u00e9conomico-sociale. C&rsquo;est un domaine f\u00e9cond, \u00e0 la fois pour l&rsquo;analyse critique, \u00e0 la fois pour l&rsquo;int\u00e9r\u00eat du public et des contestataires antiSyst\u00e8me, \u00e0 la fois pour l&rsquo;exercice du pouvoir, qui se trouve en plus confortablement install\u00e9e sur de nombreuses r\u00e9f\u00e9rences historiques, \u00e0 la fois rassurantes et rationalisantes pour l&rsquo;esprit. Ainsi disparut la dynamique du penser l&rsquo;apocalypse, ainsi la Grande Crise de destruction du monde devint-elle, selon le mot d&rsquo;Engelhardt, une anti-nouvelle, ou, mieux encore, une non-information<\/p>\n<h3>Encha\u00eenement politique : cha\u00eene crisique et infrastructure crisique<\/h3>\n<\/p>\n<p><p>\tLe complot r\u00e9ussit au-del\u00e0 de toute esp\u00e9rance, c&rsquo;est-\u00e0-dire qu&rsquo;il se d\u00e9passa lui-m\u00eame, produisant de plus en plus de crises de toutes les formes, de tous les domaines sectoriels, dont on pourrait croire \u00e0 premi\u00e8re vue qu&rsquo;elles poursuivirent et renforc\u00e8rent le travail de d\u00e9flection-<em>deception<\/em> en accentuant l&rsquo;impression de fragmentation et de cloisonnement emp\u00eachant la r\u00e9alisation de la Grande Crise dans son ensemble. Mais qu&rsquo;y a-t-il au-del\u00e0 de toute esp\u00e9rance dans la situation que nous d\u00e9crivons, sinon des domaines o\u00f9 l&rsquo;on trouve brusquement des situations conjoncturelles qui ridiculisent l&rsquo;esp\u00e9rance en question, qui trahissent le but recherch\u00e9 et d\u00e9couvrent ce qu&rsquo;on a voulu dissimuler ?<\/p>\n<\/p>\n<p><p>\tD&rsquo;abord, 9\/15 n&rsquo;aboutit pas au but op\u00e9rationnel recherch\u00e9. Ce ne fut pas une crise au sens initial du mot,  un paroxysme, suivi d&rsquo;un apaisement, dans un sens ou l&rsquo;autre, et d&rsquo;un retour \u00e0 l&rsquo;ordre, d&rsquo;une nature ou l&rsquo;autre. La crise \u00e9volua en embourbement crisique si l&rsquo;on veut, r\u00e9pondant ainsi d&rsquo;une fa\u00e7on convaincante \u00e0 une nouvelle d\u00e9finition du concept de crise d\u00e9j\u00e0 pr\u00e9par\u00e9e par des s\u00e9quences telle que celle de la crise iranienne d\u00e9montrant son caract\u00e8re chaotique d&#8217;embourbement depuis 2005. Nous nous retrouv\u00e2mes rapidement dans la situation d\u00e9crite par la rapide d\u00e9finition mentionn\u00e9e au d\u00e9but de notre <em>Glossaire.dde<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_l_effondrement_du_syst_me_12_01_2014.html\" class=\"gen\">12 janvier 2014<\/a> (la crise d&rsquo;effondrement du Syst\u00e8me constituant un \u00e9v\u00e9nement central de notre temps, qui renvoie bien entendu \u00e0 la Grande Crise de la destruction du monde, et vice-versa, les deux \u00e9tant irr\u00e9m\u00e9diablement li\u00e9es jusqu&rsquo;\u00e0 se confondre dans telle ou telle occasion) :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>On observera ici, et cela vaut aussi pour d&rsquo;autres articles du Glossaire.dde, que l&#8217;emploi g\u00e9n\u00e9ralis\u00e9 du terme crise n&rsquo;est pas n\u00e9cessairement appropri\u00e9 selon la stricte d\u00e9finition de la chose ; mais il l&rsquo;est, selon nous, si on situe cet emploi dans un contexte particulier, qui est effectivement celui que nous choisissons, que nous d\u00e9signons explicitement ou qui est simplement implicite chez nous ; il s&rsquo;agit du contexte de cette p\u00e9riode sp\u00e9cifique de fin de civilisation, ou de fin de notre&rsquo; contre-civilisation comme nous d\u00e9signons la civilisation o\u00f9 nous nous trouvons depuis le d\u00e9but du XIXe si\u00e8cle. La crise devient alors dans ce cas une circonstance d&rsquo;une s\u00e9quence temporelle et civilisationnelle plus large, plus ample et \u00e9videmment d\u00e9cisive, et une circonstance si fortement li\u00e9e \u00e0 cette s\u00e9quence temporelle et civilisationnelle qu&rsquo;elle en est d&rsquo;une m\u00eame substance. La crise devient une composante essentielle, et de plus en plus exclusive, du Temps G\u00e9n\u00e9ral que nous vivons, et elle se caract\u00e9rise par une sorte de structuration, voire m\u00eame jusqu&rsquo;\u00e0 repr\u00e9senter l&rsquo;id\u00e9e assez paradoxale, sinon oxymorique, d&rsquo;une paroxysme durable qui devient de plus en plus un paroxysme structurel, qui devient la seule<\/em> <strong><em>fa\u00e7on d&rsquo;\u00eatre<\/em><\/strong> <em>de notre temps m\u00e9tahistorique.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tOn sait comment les choses se sont d\u00e9roul\u00e9es depuis 9\/15, accentuant les remarques ci-dessus. D&rsquo;autres crises sont apparues et ont pris la m\u00eame forme, ou plut\u00f4t la m\u00eame absence de forme que 9\/15, en m\u00eame temps qu&rsquo;un reclassement g\u00e9n\u00e9ral des principaux centres du Syst\u00e8me se faisait sous la forme du <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_bloc_bao_10_12_2012.html\" class=\"gen\">bloc BAO<\/a>. Les crises se sont empil\u00e9es dans divers domaines, sous la forme d&rsquo;une <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_chaine_crisique_ddecrisis_02_04_2011.html\" class=\"gen\">cha\u00eene crisique<\/a> dans le chef du printemps arabe, pour former une <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_notre_kosmos_crisique__27_03_2013.html\" class=\"gen\">infrastructure<\/a> <a href=\"http:\/\/www.dedefensa.org\/article-glossairedde_le_facteur_crisique__30_04_2013.html\" class=\"gen\">crisique<\/a>, qui constitue une op\u00e9rationnalisation g\u00e9n\u00e9rale de l&#8217;embourbement crisique et de l&rsquo;utilisation du concept de crise comme mat\u00e9riel de base des relations internationales, et de la situation du monde en g\u00e9n\u00e9ral. C&rsquo;est notre situation actuelle&#8230;<\/p>\n<h3>Retour par le fen\u00eatre : la crise du monde revient et devient politique<\/h3>\n<\/p>\n<p><p>\tLe r\u00e9sultat est une situation g\u00e9n\u00e9rale sans pr\u00e9c\u00e9dent. La crise d&rsquo;effondrement du Syst\u00e8me, qui est d\u00e9crite et op\u00e9rationnalis\u00e9e par la multitude de ph\u00e9nom\u00e8nes crisiques constituant la substance de la situation g\u00e9n\u00e9rale du monde, et d\u00e9finissant l&rsquo;essence de cette situation, englobe d\u00e9sormais toute notre \u00e9poque. Rien ne lui \u00e9chappe. D&rsquo;une fa\u00e7on tr\u00e8s logique, la Grande Crise de la destruction du monde, dont les manifestations ou ce qui est per\u00e7u comme ses manifestations se multiplient, a naturellement trouv\u00e9 sa place dans cette situation g\u00e9n\u00e9rale sans pr\u00e9c\u00e9dent. La psychologie joue un r\u00f4le fondamental dans ce processus, elle qui est d\u00e9sormais d&rsquo;une sensibilit\u00e9 exacerb\u00e9e \u00e0 tout ce qui concerne de pr\u00e8s ou de loin le caract\u00e8re crisique de cette situation g\u00e9n\u00e9rale sans pr\u00e9c\u00e9dent ; cela fait que tout \u00e9v\u00e9nement naturel, climatique avec ses cons\u00e9quences, etc., semblant hors des normes,  et l&rsquo;interpr\u00e9tation dans ce sens est ais\u00e9e,  est aussit\u00f4t interpr\u00e9t\u00e9e comme une manifestation de la Grande Crise de destruction du monde et aussit\u00f4t int\u00e9gr\u00e9e dans cette situation g\u00e9n\u00e9rale sans pr\u00e9c\u00e9dent.<\/p>\n<\/p>\n<p><p>\tCe ph\u00e9nom\u00e8ne d&rsquo;int\u00e9gration de la Grande Crise de destruction du monde, dont le principe et l&rsquo;identification avaient \u00e9t\u00e9 \u00e9cart\u00e9s par 9\/15, fait que ce qui avait \u00e9t\u00e9 chass\u00e9 par la grande porte de 9\/15 est revenu par la fen\u00eatre, sans la moindre opposition de quiconque. Dans ce cas comme dans tant d&rsquo;autres, on voit ce confirmer ce qu&rsquo;on a d\u00e9fini depuis 2008 sous le terme bloc BAO, savoir que le Syst\u00e8me, malgr\u00e9 ses fureurs de surpuissance, est dans une position de formidable fragilit\u00e9 (autodestruction d\u00e9coulant de la surpuissance) qui lui interdit de contrecarrer de tels \u00e9v\u00e9nements comme celui du retour par la fen\u00eatre de la Grande Crise de destruction du monde.<\/p>\n<\/p>\n<p><p>\tNous observions ce ph\u00e9nom\u00e8ne, notamment d\u00e8s le <a href=\"http:\/\/www.dedefensa.org\/article-integration_de_la_crise_climatique_22_07_2010.html\" class=\"gen\">22 juillet 2010<\/a>, dans un texte sur l&rsquo;int\u00e9gration de la crise climatique (dans la crise d&rsquo;effondrement du Syst\u00e8me&#8230;). Nous proposions ainsi : <\/p>\n<\/p>\n<p><p>\t\u00ab<em>La crise climatique est entr\u00e9e dans la crise du syst\u00e8me, elle s&rsquo;est int\u00e9gr\u00e9e. Comme d&rsquo;habitude, le syst\u00e8me, d&rsquo;une puissance inou\u00efe, est d&rsquo;une sottise \u00e0 mesure. Il n&rsquo;a pas su appr\u00e9hender cette crise climatique selon ses propres param\u00e8tres (r\u00e9duction cons\u00e9quente de la consommation d&rsquo;\u00e9nergie, technologies propres, etc.) et il n&rsquo;y parviendra pas parce qu&rsquo;il est totalement<\/em> <strong><em>impuissant<\/em><\/strong> <em>\u00e0 mettre un frein \u00e0 sa boulimie de puissance. Il alimente donc l&rsquo;\u00e9largissement radical de la crise, la transformation de crises sectorielles d&rsquo;une part, de crises naturelles d&rsquo;autre part, en des crises politiques, c&rsquo;est-\u00e0-dire des crises m\u00e9tahistoriques selon la r\u00e9f\u00e9rence de la Grande D\u00e9pression (avec le Dust Bowl). Il acc\u00e9l\u00e8re consid\u00e9rablement les conditions objectives,  ou, disons, les conditions eschatologiques de la mise en cause de lui-m\u00eame par l&rsquo;int\u00e9gration des \u00e9v\u00e9nements qu&rsquo;il rencontre.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Aujourd&rsquo;hui, plus aucune catastrophe naturelle, m\u00eame si elle est r\u00e9ellement naturelle, ne peut plus \u00e9chapper \u00e0 cette fatalit\u00e9 d&rsquo;\u00eatre consid\u00e9r\u00e9e comme une cons\u00e9quence de la crise du syst\u00e8me, ou comme une cons\u00e9quence de la crise climatique dans la mesure o\u00f9 cette crise climatique est la cons\u00e9quence de la crise du syst\u00e8me. C&rsquo;est une machinerie infernale, qui s&rsquo;ajoute \u00e0 d&rsquo;autres machineries du m\u00eame genre, qui alimente \u00e9videmment la crise psychologique g\u00e9n\u00e9rale (notre \u00e9puisement psychologique) dont on ne cesse de relever les effets dans tous les domaines. De ce point de vue \u00e9galement, \u00e0 c\u00f4t\u00e9 des amuse-bouche sur le pourcentage de la responsabilit\u00e9 humaine dans le global warming, histoire d&rsquo;animer les talk-shows, la crise climatique s&rsquo;est install\u00e9e dans notre t\u00eate et dans notre psychologie comme un enfant difforme et inf\u00e2me de la crise du syst\u00e8me. Le DVD montrant le flot de p\u00e9trole s&rsquo;\u00e9chappant de la conduite BP au fond du Golfe du Mexique n&rsquo;a pas fini de faire des d\u00e9g\u00e2ts dans nos psychismes.<\/em>\u00bb<\/p>\n<h3>La crise du monde dans toute son ampleur, accusatrice du Syst\u00e8me<\/h3>\n<\/p>\n<p><p>\tCe processus s&rsquo;est poursuivi et il est d\u00e9sormais bien rod\u00e9. On comprend l&rsquo;amertume d&rsquo;Engelhardt devant la disparition dans les nouvelles de la crise climatique (la Grande Crise&#8230;), mais on le jugera infond\u00e9 par le fait m\u00eame que nous avons d\u00e9crit : l&rsquo;int\u00e9gration de la Grande Crise de destruction du monde. La psychologie, puis le jugement, ont ent\u00e9rin\u00e9 cela, comme nous l&rsquo;avons not\u00e9 dans plusieurs textes r\u00e9cents, si bien qu&rsquo;en n&rsquo;\u00e9tant gu\u00e8re identifi\u00e9e pour ce qu&rsquo;elle est, la Grande Crise&#8230; est partout pr\u00e9sente. Plus encore, elle est implicitement identifi\u00e9e pour ce qu&rsquo;elle est, \u00e0 savoir la cons\u00e9quence directe des syst\u00e8mes d\u00e9velopp\u00e9s par notre contre-civilisation, donc cons\u00e9quence \u00e0 la fois symbolique et eschatologique du Syst\u00e8me ; notamment et essentiellement par cons\u00e9quent, son caract\u00e8re eschatologique ne peut plus \u00eatre ni d\u00e9ni\u00e9, ni \u00e9cart\u00e9&#8230; Cette fois, alors qu&rsquo;elle est de retour, elle trouve le Syst\u00e8me totalement sur la d\u00e9fensive, totalement impuissant, alors m\u00eame qu&rsquo;il en est lui-m\u00eame \u00e0 subir sa propre crise d&rsquo;effondrement (bien plus que la g\u00e9rer, cela va sans dire). C&rsquo;\u00e9tait le constat que nous faisions le <a href=\"http:\/\/www.dedefensa.org\/article-_leur_monde_menace_le_monde_16_09_2013.html\" class=\"gen\">16 septembre 2013<\/a>, commentant une initiative-Syst\u00e8me face \u00e0 la Grande Crise de l&rsquo;effondrement du monde, qui \u00e9tait aussi une aveu du Syst\u00e8me de sa propre responsabilit\u00e9 dans cette Grande Crise&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Le rapport Stern \u00e9tait un document recommandant une strat\u00e9gie de lutte contre ce processus, avec comme philosophie implicite qu&rsquo;il existait effectivement une possibilit\u00e9 d&rsquo;infl\u00e9chir la courbe g\u00e9n\u00e9rale de d\u00e9structuration et de dissolution de l&rsquo;environnement. Il s&rsquo;agissait de la fili\u00e8re g\u00e9n\u00e9rale de n\u00e9gociations diverses concernant la r\u00e9gulation de production de gaz \u00e0 effets de serre, de transformation des processus de production d&rsquo;\u00e9nergie et de sources d&rsquo;\u00e9nergie, etc. Il s&rsquo;agissait donc d&rsquo;une sorte de plan g\u00e9n\u00e9ral de contre-offensive, pour infl\u00e9chir d&rsquo;une fa\u00e7on d\u00e9cisive le fonctionnement du Syst\u00e8me et \u00e9viter les principaux effets catastrophiques de la crise environnementale. En un sens, la menace eschatologique de la crise environnementale n&rsquo;\u00e9tait justement pas per\u00e7ue comme eschatologique, puisqu&rsquo;il \u00e9tait admis qu&rsquo;une action concert\u00e9e pouvait en \u00e9carter les principaux effets.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Sept ans plus tard, avec la cr\u00e9ation du CSER comme \u00e9v\u00e9nement symbolique, on peut mesurer le chemin parcouru dans le sens de la d\u00e9gradation extraordinairement rapide de la situation, et l&rsquo;impuissance totale des \u00e9lites-Syst\u00e8me \u00e0 incurver la course du Syst\u00e8me. C&rsquo;est \u00e0 ce point, dans le domaine le plus spectaculairement effrayant de la destruction du monde, qu&rsquo;on peut mesurer la validit\u00e9 mat\u00e9rielle,  dans le domaine de la Mati\u00e8re elle-m\u00eame, cens\u00e9e \u00eatre pourtant le moteur du Syst\u00e8me,  que l&rsquo;\u00e9quation surpuissance-autodestruction prend toute sa force. La cr\u00e9ation du CSER signale en effet, principalement, deux grands constats, qui prennent acte de la modification compl\u00e8te de la<\/em> <strong><em>perception de la situation<\/em><\/strong> <em> par rapport \u00e0 l&rsquo;\u00e9poque du rapport Stern.<\/em>\u00bb<\/p>\n<h3>Nous sommes d\u00e9sormais pens\u00e9s par l&rsquo;apocalypse<\/h3>\n<\/p>\n<p><p>\tNotre conclusion de cette description d&rsquo;une \u00e9volution ultra-rapide d&rsquo;int\u00e9gration de ph\u00e9nom\u00e8nes sans pr\u00e9c\u00e9dent,  la crise d&rsquo;effondrement du Syst\u00e8me, la Grande Crise de la destruction du monde, la responsabilit\u00e9 directe de la premi\u00e8re comme cause essentielle de la seconde,  se trouve dans la description d&rsquo;un renversement complet du processus de jugement de la situation g\u00e9n\u00e9rale de notre pens\u00e9e. Nous n&rsquo;en sommes plus \u00e0 tenter de penser l&rsquo;apocalypse, nous en sommes au stade o\u00f9 l&rsquo;apocalypse commence \u00e0 nous penser, plus encore, o\u00f9 l&rsquo;apocalypse nous pense d\u00e9j\u00e0 compl\u00e8tement,  o\u00f9, d\u00e9sormais, nous sommes pens\u00e9s par l&rsquo;apocalypse. Nous avions voulu ma\u00eetriser (le rapport Stern) ce que nous identifiions comme un danger majeur  mais le Syst\u00e8me a \u00e9videmment sabord\u00e9 cette tentative qui l&rsquo;aurait rapidement mis en accusation en introduisant des facteurs (eschatologiques) qu&rsquo;il ne contr\u00f4le pas. L&rsquo;inverse complet s&rsquo;est r\u00e9alis\u00e9, en accouchant d&rsquo;une situation pire pour le Syst\u00e8me, la pire qu&rsquo;on puisse imaginer : d\u00e9sormais, c&rsquo;est Notre Tout Crisique qui est devenu eschatologique, la crise climatique transmut\u00e9e en Grande Crise de destruction du monde, nos crises sectorielles r\u00e9alis\u00e9es et int\u00e9gr\u00e9es en une immense crise d&rsquo;effondrement du Syst\u00e8me, et les deux branches \u00e9tant elles-m\u00eames int\u00e9gr\u00e9es.<\/p>\n<\/p>\n<p><p>\tLes \u00e9v\u00e9nements terrestres ne constituent plus des cat\u00e9gories \u00e0 part, faites pour nous interdire une pens\u00e9e g\u00e9n\u00e9rale et int\u00e9gratrice, ils sont forc\u00e9s de s&rsquo;int\u00e9grer dans le courant apocalyptique. Ils ne pr\u00e9sentent plus aucune coh\u00e9rence interne, ils se d\u00e9veloppent dans un d\u00e9sordre g\u00e9n\u00e9ral qui porte chaque jour t\u00e9moignage de cette situation apocalyptique. Leur op\u00e9rationnalisation interne est elle-m\u00eame devenue compl\u00e8tement chaotique, dans un <a href=\"http:\/\/www.dedefensa.org\/article-apolaire_ou_antipolaire__16_11_2013.html\" class=\"gen\">monde antipolaire<\/a> qui refuse d\u00e9sormais tout contr\u00f4le humain. Chaque nouvel \u00e9pisode crisique nous montre cela, jusqu&rsquo;aux plus infimes et grotesques p\u00e9rip\u00e9ties (voir, pour le plus r\u00e9cent et pour le grotesque, l&rsquo;\u00e9pisode Victoria Nuland-Fuck li\u00e9 \u00e0 l&rsquo;Ukraine [le <a href=\"http:\/\/www.dedefensa.org\/article-victoria_nuland-fuck_et_la_politique_us_fuck_fuck_fuck_07_02_2014.html\" class=\"gen\">7 f\u00e9vrier 2014<\/a>]). <\/p>\n<\/p>\n<p><p>\tAvec 9\/15, le Syst\u00e8me croyait \u00e9chapper au pire de ce qu&rsquo;il pouvait craindre avec une classification des \u00e9v\u00e9nements le <strong>mettant directement en question<\/strong> en imposant, contre le champ apocalyptique ouvert par le rapport Stern, des \u00e9v\u00e9nements terrestres (9\/15, l&rsquo;\u00e9norme crise financi\u00e8re) qui, par leur ampleur, \u00e9cartaient la terrible menace du penser l&rsquo;apocalypse. Il y est aujourd&rsquo;hui compl\u00e8tement soumis, dans un renversement stup\u00e9fiant, qui est bien plus qu&rsquo;une inversion vertueuse, qui est une r\u00e9volution de l&rsquo;esprit dont nous allons d\u00e9couvrir les cons\u00e9quences absolument prodigieuses remettant en cause plus de 3-5 si\u00e8cles de civilisation transform\u00e9e en contre-civilisation. Nous sommes soumis aujourd&rsquo;hui, comme l&rsquo;on dit d&rsquo;un combattant vaincu, par ce renversement complet des exigences de la logique des \u00e9v\u00e9nements. Nous (y compris les autorit\u00e9s-Syst\u00e8me, et les autorit\u00e9s-Syst\u00e8me en premier, dans un bouleversement terrifiant pour elles et dont il faut se r\u00e9jouir au plus haut point),  nous n&rsquo;int\u00e9grons absolument pas le penser l&rsquo;apocalypse tout en le contr\u00f4lant, mais nous sommes int\u00e9gr\u00e9s <strong>de toute force<\/strong> par les \u00e9v\u00e9nements dans un penser l&rsquo;apocalypse qui nous a \u00e9chapp\u00e9, qui se manifeste dans des \u00e9v\u00e9nements sup\u00e9rieurs et incontr\u00f4lables, manifestement de nature supra-humaine, qui nous domine absolument et nous emporte comme f\u00e9tus de paille. Nous,  c&rsquo;est-\u00e0-dire lui, le Syst\u00e8me, ou toi, le venin,  le Syst\u00e8me a tout perdu au change : refusant le penser l&rsquo;apocalypse comme un des domaines de sa r\u00e9flexion, il est devenu lui-m\u00eame pens\u00e9 par l&rsquo;apocalypse, il a \u00e9t\u00e9 annex\u00e9 par l&rsquo;apocalypse&#8230;<\/p>\n<\/p>\n<p><p>\tAinsi, comme le constate Engelhardt, effectivement la crise climatique en tant qu&rsquo;elle op\u00e9rationnalise et symbolise absolument la Grande Crise de la destruction du monde n&rsquo;est pas dans les nouvelles. Mais elle n&rsquo;est pas <em>anti-news<\/em> pour autant. Elle est devenue la substance fondatrice, pr\u00e9gnante, omnipr\u00e9sente de l&rsquo;information et m\u00eame du syst\u00e8me de la communication, en int\u00e9grant absolument la crise d&rsquo;effondrement du Syst\u00e8me&#8230;. Ce sont les crises accumul\u00e9es par le Syst\u00e8me depuis 2008 qui forment ces cha\u00eenes crisiques, cette infrastructure crisique, qui s&rsquo;ins\u00e8rent dans un ensemble qui porte la marque de la crise dite de l&rsquo;apocalypse. Nous n&rsquo;avons plus \u00e0 chercher \u00e0 penser l&rsquo;apocalypse car voici la Grande Nouvelle  : d\u00e9sormais, l&rsquo;apocalypse pense pour nous, comme elle nous pense&#8230;<\/p>\n<\/p>\n<p><p>\t&#8230; Cela dit sans autre constat que ce soit, ni terreurs horrifi\u00e9es, ni joie exacerb\u00e9e et un peu hyst\u00e9rique, non. Il s&rsquo;agit d&rsquo;un constat. Il correspond \u00e0 ce que nous jugeons de la situation et nous affirmons l\u00e0-dessus tout ignorer, et tout <strong>vouloir ignorer<\/strong> pour \u00e9carter les pressions trompeuses de l&rsquo;affectivit\u00e9 humaine, de ce que ce constat signifie et nous r\u00e9serve. Mais nous ne voyons dans la perspective aucune fatalit\u00e9 que notre raison (suspecte, puisque sensible \u00e0 la subversion) pourrait nous sugg\u00e9rer. Nous sommes dans une situation qui n&rsquo;est plus ni dans notre pouvoir, ni dans notre perception, et dont les protagonistes nous d\u00e9passent.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur le th\u00e8me de l&rsquo;apocalypse 8 f\u00e9vrier 2014 L&rsquo;excellent chroniqueur et auteur Tom Engelhardt, \u00e9diteur du site TomDispatch.com lui-m\u00eame d&rsquo;excellente r\u00e9putation, est particuli\u00e8rement pr\u00e9occup\u00e9 par la crise climatique et ses cons\u00e9quences. Nombre de collaborateurs de son site s&rsquo;int\u00e9ressent \u00e0 la question sous divers angles, mais c&rsquo;est bien dans ses propres chroniques, lorsqu&rsquo;il prend lui-m\u00eame&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[3093,4906,370,4012,4270,10859,3392,3228,8294,2631,2686,2651,1381,2891,7572,4807,2622,2878,6051,11131],"class_list":["post-73689","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-3093","tag-4906","tag-370","tag-apocalypse","tag-autodestruction","tag-chaine","tag-climatique","tag-crise","tag-crisique","tag-de","tag-destruction","tag-du","tag-engelhardt","tag-grande","tag-infrastructure","tag-integration","tag-la","tag-monde","tag-stern","tag-surpuissance"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73689"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73689\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}