{"id":73707,"date":"2014-02-17T10:52:40","date_gmt":"2014-02-17T10:52:40","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/02\/17\/uk-sous-les-eaux-libre-echange-ou-libre-climate-change\/"},"modified":"2014-02-17T10:52:40","modified_gmt":"2014-02-17T10:52:40","slug":"uk-sous-les-eaux-libre-echange-ou-libre-climate-change","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/02\/17\/uk-sous-les-eaux-libre-echange-ou-libre-climate-change\/","title":{"rendered":"UK sous les eaux : libre-\u00e9change ou libre-<em>climate change<\/em> ?"},"content":{"rendered":"<p><h3 class=\"titrebloc\">UK sous les eaux : libre-\u00e9change ou libre-<em>climate change<\/em> ?<\/h3>\n<\/p>\n<p><p>\tOn sait que le Royaume-Uni est sous les eaux, encore bien plus que la Bretagne, et que cela dure depuis des semaines, au rythme des temp\u00eates venues de l&rsquo;Atlantique,  et, pour certains, de la crise climatique. Les hommes politiques ont chauss\u00e9 leurs bottes en caoutchouc d&rsquo;au moins sept lieues et s&rsquo;en vont, se baladant dans les dizaines de centim\u00e8tres d&rsquo;eau qui baignent les villages et les campagnes. La Tamise elle-m\u00eame est, selon les bruits qui courent dans les commentaires de la presse-Syst\u00e8me, \u00e0 son plus haut niveau historique. (Depuis 60 ans ? Depuis plus avant, ou plus en arri\u00e8re dans l&rsquo;histoire ? Laissons cela et gardons l&rsquo;effet d&rsquo;annonce du niveau historique car seul l&rsquo;effet importe dans le fonctionnement du Syst\u00e8me.)<\/p>\n<\/p>\n<p><p>\tL&rsquo;\u00e9v\u00e9nement climatique est assez durable, et assez accablant dans ses effets propag\u00e9s par le syst\u00e8me de la communication et la perception que ce mouvement dispense, \u00e0 cause m\u00eame de la surpuissance du Syst\u00e8me et des cons\u00e9quences multiples qu&rsquo;il engendre lui-m\u00eame par l&rsquo;influence de ses annonces, pour faire revenir \u00e0 la surface (comme c&rsquo;est le cas de le dire par analogie tentante) le grand th\u00e8me de la question climatique. Il s&rsquo;agit bien s\u00fbr de l&rsquo;argument fondamental de communication de la crise climatique, c&rsquo;est-\u00e0-dire, pour nous, la grande crise de la destruction du monde par le Syst\u00e8me. (On est, l\u00e0, tr\u00e8s loin des pol\u00e9miques sur le <em>global warming<\/em>, bien entendu. Ce cas sp\u00e9cifique n&rsquo;a pour nous qu&rsquo;un int\u00e9r\u00eat tr\u00e8s accessoire en soi, et sa vertu n&rsquo;existe que dans le fait qu&rsquo;il s&rsquo;ins\u00e8re dans la crise d&rsquo;effondrement du Syst\u00e8me et qu&rsquo;il l&rsquo;acc\u00e9l\u00e8re. Ce d\u00e9sint\u00e9r\u00eat pour notre part a \u00e9t\u00e9 fix\u00e9 depuis longtemps et n&rsquo;a fait que s&rsquo;accentuer,  voir le <a href=\"http:\/\/www.dedefensa.org\/article-inconnaissance_climat_derrida_deleuze_et_cie__18_07_2011.html\" class=\"gen\">18 juillet 2011<\/a>, \u00ab<em>Inconnaissance, climat, Derrida, Deleuze &#038; Cie<\/em>\u00bb, dans la partie \u00ab<em>Le sexe climatique des anges<\/em>\u00bb.) Ce d\u00e9bat a resurgi au Royaume-Uni \u00e0 l&rsquo;occasion d&rsquo;une offensive politicienne qui ne surprend pas, qui pr\u00e9tend d&rsquo;abord mettre en accusation le gouvernement <em>tory<\/em>-lib\u00e9ral dans le chef de l&rsquo;opposition travailliste. (Un sondage de <em>The Independent<\/em> montre que 6 Britanniques sur 10 accusent le gouvernement d&rsquo;incomp\u00e9tence, et 48% contre 30% des Britanniques attribuent les intemp\u00e9ries \u00e0 la crise climatique.) Cette soupe politicienne, et bassement par d\u00e9finition, n&#8217;emp\u00eache pas que le d\u00e9bat qu&rsquo;elle fait ressurgir est quelque chose de s\u00e9rieux, c&rsquo;est-\u00e0-dire la chose la plus s\u00e9rieuse qu&rsquo;on puisse imaginer, et qui ne cesse de se faire de plus en plus pressante (voir nos <em>Notes d&rsquo;analyse<\/em> sur le th\u00e8me de l&rsquo;apocalypse, le <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_le_th_me_de_l_apocalypse_08_02_2014.html\" class=\"gen\">8 f\u00e9vrier 2014<\/a>).<\/p>\n<\/p>\n<p><p>\tC&rsquo;est ainsi que Ed Miliband, le chef du parti travailliste, s&rsquo;est adress\u00e9 \u00e0 l&rsquo;<em>Observer<\/em> le <a href=\"http:\/\/www.theguardian.com\/politics\/2014\/feb\/15\/ed-miliband-stark-warning-climate-change\" class=\"gen\">16 f\u00e9vrier 2014<\/a>, pour avertir le monde politique britannique que,  surprise, surprise,  la question du <em>climate change<\/em>, ou crise climatique, est une question centrale de s\u00e9curit\u00e9 nationale&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Britain is sleepwalking towards disaster because of a failure to recognise that climate change is causing the extreme weather that has blighted the country for more than a month, Ed Miliband has warned. The Labour leader says in an interview with the Observer that climate change is now an issue of national security that has the potential not only to destabilise and cause conflict between regions of the world, but to destroy the homes, livelihoods and businesses of millions of British people&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCette affirmation qui semble \u00eatre faite comme un coup de tonnerre n&rsquo;est rien moins que nouvelle, particuli\u00e8rement pour les Britanniques, comme on le rappelle \u00e9galement dans le texte d\u00e9j\u00e0 r\u00e9f\u00e9renc\u00e9 (le <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_le_th_me_de_l_apocalypse_08_02_2014.html\" class=\"gen\">8 f\u00e9vrier 2014<\/a>). On sait en effet que la premi\u00e8re alerte officielle s\u00e9rieuse et institutionnalis\u00e9e sur la crise climatique comme crise centrale de la destruction du monde, et par cons\u00e9quent comme crise de s\u00e9curit\u00e9 nationale de premi\u00e8re dimension, est venue du Royaume-Uni \u00e0 l&rsquo;automne 2006 avec le rapport Stern. Au reste, trois jours avant Miliband, le m\u00eame Lord Stern qui r\u00e9digea ce rapport avait publi\u00e9 un texte dans le <em>Guardian<\/em> (le <a href=\"http:\/\/www.theguardian.com\/environment\/2014\/feb\/13\/flooding-storms-uk-climate-change-lord-stern\" class=\"gen\">13 f\u00e9vrier 2014<\/a>) pour rappeler les termes de l&rsquo;alarme, et de l&rsquo;urgence de cette alarme, qui figuraient d\u00e9j\u00e0 dans son rapport d&rsquo;octobre 2006&#8230;<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The devastating floods and storms sweeping Britain are clear indications of the dangers of climate change, according to Lord Stern, the author of a 2006 report on the economics of climate change. Writing in the Guardian, the crossbench peer said the flooding and storm damage demonstrate the need for Britain and the rest of the world to continue to implement low-carbon policies to reduce the probability of greater tragedies in the future&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tOn sait que des conditions climatiques exceptionnelles touchent \u00e9galement les USA (tr\u00e8s nombreux articles l\u00e0-dessus, comme celui d&rsquo;<em>Accuweather.com<\/em>, du <a href=\"http:\/\/www.accuweather.com\/en\/weather-news\/ice-storm-begins-to-unfold-in\/23186487\" class=\"gen\">13 f\u00e9vrier 2014<\/a>). Pourtant, aucun d\u00e9bat sur le <em>climate change<\/em> l\u00e0-bas, o\u00f9 la majorit\u00e9 du monde politique, des caciques du parti r\u00e9publicains aux complotistes \u00e9pisodiquement antiSyst\u00e8me d&rsquo;<em>Infowars.com<\/em>, est plut\u00f4t du c\u00f4t\u00e9 climatosceptique (il est impensable d&rsquo;esp\u00e9rer trouver une majorit\u00e9 pour la th\u00e8se du <em>climate change<\/em> au Congr\u00e8s, ce qui r\u00e9duit l&rsquo;argument de victimisation des climatosceptiques \u00e0 une manuvre de communication classique). M\u00eame chose en France, touch\u00e9e par les temp\u00eates bretonnes : le syst\u00e8me de la communication dans ce pays, et le monde politique dans la foul\u00e9e puisque le sujet n&rsquo;est de toutes les fa\u00e7ons pas sur son agenda boucl\u00e9 sur les th\u00e8mes essentiels de survie de la civilisation, des questions du racisme, du f\u00e9minisme, du mariage <em>gay<\/em>, etc., ne sont gu\u00e8re int\u00e9ress\u00e9s par la question climatique. A cet \u00e9gard, et si ce n&rsquo;est qu&rsquo;un hasard le hasard fait bien les choses, la France molle du pr\u00e9sident-poire confirme sa ligne sp\u00e9cifique d&rsquo;am\u00e9ricanisation. (La situation fran\u00e7aise est cocasse dans sa grandeur d\u00e9cadente : de toutes les fa\u00e7ons, la France ne dit rien contre le grand alli\u00e9 am\u00e9ricaniste, sauf lorsque Merkel engage rudement Hollande \u00e0 s&rsquo;orienter vers des mesures disant implicitement cela,  comme dans l&rsquo;entente, forc\u00e9e par les Allemands, sur le projet de faire un r\u00e9seau-data ind\u00e9pendant de celui des USA,  voir <em>Russia Today<\/em>, du <a href=\"http:\/\/rt.com\/news\/european-data-protection-network-283\/\" class=\"gen\">16 f\u00e9vrier 2014<\/a>. C&rsquo;est ce qu&rsquo;on nomme un conflit d&rsquo;all\u00e9geance.) Dans ces cas cit\u00e9s concernant la crise climatique, dans leurs interpr\u00e9tations des points de vue politiques et de communication (l&rsquo;aspect scientifique ne nous int\u00e9ressant pas), il n&rsquo;y a rien de nouveau, absolument rien. Il s&rsquo;agit de positions qui d\u00e9pendent de ce qui a \u00e9t\u00e9 d\u00e9fini comme le <em>big Now<\/em>, ou l&rsquo;\u00ab<em>\u00e9ternel pr\u00e9sent<\/em>\u00bb (voir le <a href=\"http:\/\/www.dedefensa.org\/article-du_big_now_l_l_ternel_pr_sent__29_01_2014.html\" class=\"gen\">29 janvier 2014<\/a>), c&rsquo;est-\u00e0-dire les positions fig\u00e9es par la crise d&rsquo;effondrement du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tQue les Britanniques aient une position en fl\u00e8che sur la crise climatique, qui ressort \u00e0 chaque \u00e9v\u00e9nement du genre au niveau de la communication, ne peut surprendre aujourd&rsquo;hui. Ils entretiennent cette position depuis Thatcher au printemps 1989, \u00e0 la conf\u00e9rence de Rio sur l&rsquo;environnement, et ils l&rsquo;ont montr\u00e9 en 2006 avec le rapport Stern, compl\u00e8tement soutenu par le gouvernement Blair. C&rsquo;est moins une position d\u00e9lib\u00e9r\u00e9e et fondamentale qu&rsquo;une sp\u00e9cificit\u00e9 de la psychologie britannique, qui entretient avec d\u00e9lice certaines contradictions internes, en m\u00eame temps que des positions inspir\u00e9es par les th\u00e8mes d&rsquo;humanisme universaliste que favorisent certains courants de pens\u00e9e britanniques. A c\u00f4t\u00e9 de l&rsquo;alignement complet  sur la ligne de l&rsquo;am\u00e9ricanisation, le Royaume-Uni ne cesse, lorsque les \u00e9v\u00e9nements le sollicitent, de r\u00e9affirmer sa position radicale au sein du bloc BAO sur ce sujet sp\u00e9cifique de la crise climatique. (Bien entendu, c&rsquo;est toujours le domaine de la communication, qui n&rsquo;engendre gu\u00e8re d&rsquo;actions sp\u00e9cifiques mais nourrit les troubles de la psychologie et des n\u00e9cessit\u00e9s de coh\u00e9sion du bloc BAO.) L&rsquo;int\u00e9r\u00eat de la s\u00e9quence actuelle est dans ce que, depuis 2006, les variations diverses du d\u00e9bat accessoire sur la crise climatique nous ont largement rapproch\u00e9s du d\u00e9bat sur ce que nous nommons la crise de destruction du monde qui, lui, met en cause le Syst\u00e8me et ses cons\u00e9quences. (Voir le <a href=\"http:\/\/www.dedefensa.org\/article-la_r_sistance_populaire_facteur_g_ophysique_de_la_crise_d_effondrement_31_10_2013.html\" class=\"gen\">31 octobre 2013<\/a> sur \u00ab<em>La r\u00e9sistance populaire, facteur g\u00e9ophysique de la crise d&rsquo;effondrement<\/em>\u00bb, o\u00f9 l&rsquo;on voit des scientifiques, partisans d&rsquo;une vision apocalyptique de la crise climatique, pr\u00f4ner comme seule issue la r\u00e9volte populaire contre le Syst\u00e8me. Voil\u00e0 un exemple parfait de la <strong>seule utilit\u00e9<\/strong> concevable du d\u00e9bat sur les causes et les cons\u00e9quences du d\u00e9r\u00e8glement climatique : lorsqu&rsquo;il conduit \u00e0 une mise en accusation du Syst\u00e8me dont la responsabilit\u00e9 est totale dans la crise de destruction du monde,  la vraie crise du domaine, et la seule qui ne peut \u00eatre d\u00e9ni\u00e9e parce qu&rsquo;elle a un caract\u00e8re absolu.) On attendra donc avec int\u00e9r\u00eat les effets de cette alerte sur le climat (politique) au Royaume-Uni, par rapport au Syst\u00e8me : puisque la ligne officielle dans ce pays est qu&rsquo;il y a une crise climatique pressante et que les inondations ont mobilis\u00e9 l&rsquo;\u00e9lectorat dans ce sens d&rsquo;une part, puisque d&rsquo;autre part ce pays est, avec les USA, le pilier absolument fondamental du Syst\u00e8me, notamment dans ses composantes financi\u00e8re, \u00e9conomique et commerciale.<\/p>\n<\/p>\n<p><p>\tCe dernier point nous sugg\u00e8re la conclusion, qui est toute enti\u00e8re d&rsquo;ordre symbolique, \u00e0 propos de ces intemp\u00e9ries. On observera que les deux grandes manifestations climatiques de la p\u00e9riode, susceptibles effectivement de ressusciter ou dans tous les cas d&rsquo;alimenter le d\u00e9bat sur le <em>climate change<\/em>, se produisent dans les deux pays fournisseurs, producteurs et principaux serviteurs du Syst\u00e8me. Cette fois, c&rsquo;est une facette incontestable de l&rsquo;humour britannique, le <em>nonsense<\/em> qui acquiert un sens lorsqu&rsquo;on le consid\u00e8re du point de vue symbolique qui ne s&#8217;embarrasse gu\u00e8re des grands d\u00e9bats terrestres en cours sur la solidit\u00e9 et la couleur des briques qui nous tombent sur la t\u00eate.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 17 f\u00e9vrier 2014 \u00e0 10H45<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>UK sous les eaux : libre-\u00e9change ou libre-climate change ? On sait que le Royaume-Uni est sous les eaux, encore bien plus que la Bretagne, et que cela dure depuis des semaines, au rythme des temp\u00eates venues de l&rsquo;Atlantique, et, pour certains, de la crise climatique. Les hommes politiques ont chauss\u00e9 leurs bottes en caoutchouc&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3101,2998,15622,3392,3228,2686,2651,4237,15621,2878,6051,4238],"class_list":["post-73707","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-angleterre","tag-change","tag-climate","tag-climatique","tag-crise","tag-destruction","tag-du","tag-global","tag-milliband","tag-monde","tag-stern","tag-warming"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73707"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73707\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}