{"id":73709,"date":"2014-02-18T06:26:16","date_gmt":"2014-02-18T06:26:16","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/02\/18\/snowden-unificateur-des-extremes-us-de-gauche-et-de-droite\/"},"modified":"2014-02-18T06:26:16","modified_gmt":"2014-02-18T06:26:16","slug":"snowden-unificateur-des-extremes-us-de-gauche-et-de-droite","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/02\/18\/snowden-unificateur-des-extremes-us-de-gauche-et-de-droite\/","title":{"rendered":"Snowden, unificateur des extr\u00eames US de gauche et de droite"},"content":{"rendered":"<p><h4 class=\"breve-de-crise\">Snowden, unificateur des extr\u00eames US de gauche et de droite<\/h4>\n<p>Nous travaillons depuis un certain temps sur l&rsquo;hypoth\u00e8se que la crise Snowden\/NSA est un \u00e9v\u00e9nement f\u00e9d\u00e9rateur de deux groupes politiques jusqu&rsquo;ici unis par une hostilit\u00e9 furieuse, r\u00e9ciproque, l&rsquo;un contre l&rsquo;autre. (Notre dernier texte en date sur ce sujet, le <a href=\"http:\/\/www.dedefensa.org\/article-un_parti_anti-nsa__14_02_2014.html\" class=\"gen\">14 f\u00e9vrier 2014<\/a>.) AP a r\u00e9alis\u00e9 un sondage sur cette question, avec GfK Poll, qui confirme que cette question est <strong>le seul th\u00e8me<\/strong> qui renverse radicalement cette hostilit\u00e9 et suscite un rapprochement spectaculaire. S&rsquo;il est exploit\u00e9 pour les \u00e9lections <em>mid-term<\/em> de novembre, ce qui semble devoir \u00eatre le cas au vu de l&rsquo;orientation de la campagne, ce ph\u00e9nom\u00e8ne peut aboutir \u00e0 la constitution d&rsquo;un bloc puissant regroupant les tendances extr\u00eames des deux partis (progressistes d\u00e9mocrates et libertariens r\u00e9publicains, qu&rsquo;on peut qualifier de populistes [de gauche et de droite] sans craindre la mauvaise r\u00e9putation,  le terme \u00e9tant admis en g\u00e9n\u00e9ral comme honorable sur la sc\u00e8ne politique US, et nullement antiparlementaire mais utilisant l&rsquo;institution parlementaire pour proposer leurs vues.)<\/p>\n<\/p>\n<p><p>\tQuelques extraits du reportage de AP (le <a href=\"http:\/\/m.apnews.com\/ap\/db_16048\/contentdetail.htm?contentguid=JiIOaL1J\" class=\"gen\">17 f\u00e9vrier 2014<\/a>) sur ce sondage. Un premier texte de AP pr\u00e9sentant plus en d\u00e9tails les r\u00e9sultats du sondage datant des 17-21 janvier, mais sans enqu\u00eate aupr\u00e8s de personnes impliqu\u00e9es dans ces deux courants, avait paru le <a href=\"http:\/\/ap-gfkpoll.com\/featured\/ap-gfk-poll-americans-value-privacy-over-security\" class=\"gen\">27 janvier 2014<\/a>. (Le terme <em>liberal<\/em> utilis\u00e9 par les d\u00e9mocrates regroup\u00e9s dans ce nouveau courant doit \u00eatre interpr\u00e9t\u00e9s comme progressiste en fran\u00e7ais, et populiste de gauche \u00e9ventuellement.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Whether they are Republicans, Democrats or independents, almost half of Americans say they support the tea party movement or call themselves liberal. Compared with their more moderate Republican or Democratic peers, tea partyers and liberals are significantly more likely to oppose the collection of millions of ordinary citizens&rsquo; telephone and Internet data, an Associated Press-GfK poll shows.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>By a 2-to-1 margin, these two groups say the government should put protecting citizens&rsquo; rights and freedoms ahead of protecting them from terrorists. Nearly 6 in 10 Republicans support the tea party movement. Nearly 4 in 10 Democrats call themselves liberals. Combined, they are buoying a coalition of conservative and liberal lawmakers pushing to rein in the NSA, while party leaders balk at anything that might weaken the agency&rsquo;s ability to foil terrorists.<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>\t\u00bb<em>When it comes to Snowden, tea-party supporters and liberals are back in step &#8211; about half of each group says the former NSA contractor did the right thing. Among non-tea party Republicans and nonliberal Democrats, a strong majority thinks he was wrong to reveal classified programs.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Christina Ott, who works on her family&rsquo;s farm near Woodbury, Tenn., found Snowden&rsquo;s action inspiring. I thought it was somebody taking a moral stand and a big risk, said Ott, a liberal Democrat. She isn&rsquo;t surprised to find herself siding with the tea party for once. Regardless of their political views, Ott said, the people who worry about mass surveillance are the ones \u00ab\u00a0who are paying close attention and believe it is possible for things to go badly wrong. But Lewis, an Obama fan, is shocked to agree with tea partyers about anything. I can&rsquo;t explain it. It&rsquo;s kind of scary, she said, joking: Now I might have to rethink my position.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl est remarquable que AP ait jug\u00e9 appropri\u00e9 de faire suivre, apr\u00e8s un certain temps o\u00f9 l&rsquo;argument de la nouveaut\u00e9 du jour n&rsquo;existe plus, le texte consacr\u00e9 directement aux r\u00e9sultats du sondage d&rsquo;un autre texte reprenant la nouvelle et l&rsquo;agr\u00e9mentant d&rsquo;une enqu\u00eate aupr\u00e8s de personnes impliqu\u00e9es. C&rsquo;est une reconnaissance implicite, et de l&rsquo;importance du sondage et de ses r\u00e9sultats, et de l&rsquo;importance de la perspective politique ainsi ouverte aux USA.<\/p>\n<\/p>\n<p><p>\tLes USA sont le seul pays influent du bloc BAO qui semble sur la voie de r\u00e9ussir la synth\u00e8se radicale antiSyst\u00e8me n\u00e9cessaire pour esp\u00e9rer peser d&rsquo;une fa\u00e7on <strong>significative sinon victorieuse dans certains cas importants<\/strong> sur les institutions politiques officielles, au contraire des pays europ\u00e9ens qui s&rsquo;opposent toujours, d&rsquo;une fa\u00e7on st\u00e9rile et objectivement favorable au Syst\u00e8me, entre extr\u00e9mistes radicaux de droite et de gauche. Ce serait certainement un des plus beaux succ\u00e8s de Snowden, libertarien de la droite radicale affich\u00e9 et extr\u00eamement populaire gr\u00e2ce \u00e0 ce qui est jug\u00e9 comme son courage et son civisme, chez les progressistes de la gauche radicale.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 18 f\u00e9vrier 2014 \u00e0 06H21<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Snowden, unificateur des extr\u00eames US de gauche et de droite Nous travaillons depuis un certain temps sur l&rsquo;hypoth\u00e8se que la crise Snowden\/NSA est un \u00e9v\u00e9nement f\u00e9d\u00e9rateur de deux groupes politiques jusqu&rsquo;ici unis par une hostilit\u00e9 furieuse, r\u00e9ciproque, l&rsquo;un contre l&rsquo;autre. (Notre dernier texte en date sur ce sujet, le 14 f\u00e9vrier 2014.) AP a r\u00e9alis\u00e9&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[4646,5149,6985,3871,7069,7348,12224,5190,8256],"class_list":["post-73709","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-antisysteme","tag-ap","tag-libertarien","tag-nsa","tag-party","tag-progressiste","tag-snowden","tag-sondage","tag-tea"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73709"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73709\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}