{"id":73762,"date":"2014-03-12T06:29:42","date_gmt":"2014-03-12T06:29:42","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/03\/12\/lintelligence-us-et-dianne-feinstein\/"},"modified":"2014-03-12T06:29:42","modified_gmt":"2014-03-12T06:29:42","slug":"lintelligence-us-et-dianne-feinstein","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/03\/12\/lintelligence-us-et-dianne-feinstein\/","title":{"rendered":"L&rsquo;<em>intelligence<\/em> US et Dianne Feinstein"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">L&rsquo;<em>intelligence<\/em> US et Dianne Feinstein<\/h2>\n<\/p>\n<p><p>&#8230; Effectivement, il suffit de changer quelques mots dans le titre et le sous-titre du <em>Bloc-Notes<\/em> pr\u00e9c\u00e9dent (le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-l_intelligence_us_et_l_ukraine_11_03_2014.html\">11 mars 2014<\/a>) pour passer de la sc\u00e8ne ukrainienne \u00e0 la sc\u00e8ne washingtonienne tout en restant avec le m\u00eame acteur (l&rsquo;<em>Intelligence Community<\/em>, ou IC) qui ne cesse d&rsquo;accumuler les erreurs, les abus de pouvoir, les fausses man&oelig;uvres. Plus pr\u00e9cis\u00e9ment au sein de l&rsquo;IC, il s&rsquo;agit de la CIA, &ndash; ce qui nous change de <em>prima dona<\/em> et permet \u00e0 la NSA de souffler un peu, &ndash; mais avec la surprise de retrouver comme accusatrice publique celle qui fut la d\u00e9fenderesse acharn\u00e9e de la susdite NSA, la s\u00e9natrice d\u00e9mocrate Dianne Feinstein, par ailleurs pr\u00e9sidente de la commission sur le renseignement du S\u00e9nat. Feinstein a donn\u00e9, hier, devant le S\u00e9nat en assembl\u00e9e pl\u00e9ni\u00e8re et non plus dans sa seule commission, un de ces grands discours dont les parlementaires US ont parfois le secret. Ils savent alors faire oublier, le temps du vertige des mots qui font encore croire que l&rsquo;architecture am\u00e9ricaniste est honorable, combien cette architecture est branlante, vici\u00e9e, corrompue&#8230; Ce discours, on s&rsquo;en doute alors, a \u00e9t\u00e9 accueilli par ses coll\u00e8gues, notamment des d\u00e9mocrates qui n&rsquo;\u00e9taient pas de son c\u00f4t\u00e9 lorsqu&rsquo;elle d\u00e9fendait la NSA, avec une grande satisfaction et une admiration bruyante pour l&rsquo;oratrice. Bref, le S\u00e9nat crut \u00e0 nouveau, pour quelques instants, repr\u00e9senter ce qu&rsquo;il y a de plus haut dans la Grande R\u00e9publique. (Cela n&rsquo;ira pas plus loin dans l&rsquo;ivresse factice et l&rsquo;on reviendra vite sur terre&#8230;)<\/p>\n<\/p>\n<p><p>&laquo;<em>On the Senate floor earlier, Patrick Leahy, chairman of the judiciary committee and the longest serving US senator, described Feinstein&rsquo;s speech at the most important he had witnessed in his time in Congress. \u00ab\u00a0I cannot think of any speech by any member of any party as important as the one the senator from California just gave,\u00a0\u00bb Leahy said. Senator Mark Udall of Colorado, an intelligence committee member, said in a statement he applauded Feinstein for \u00ab\u00a0setting the record straight today on the Senate floor about the CIA&rsquo;s actions to subvert congressional oversight\u00a0\u00bb.<\/em>&raquo; (Voir le <em>Guardian<\/em> du <a class=\"gen\" href=\"http:\/\/www.theguardian.com\/world\/2014\/mar\/11\/feinstein-accuses-cia-intimidation-torture-report?CMP=twt_gu\">11 mars 2014<\/a>.)<\/p>\n<\/p>\n<p><p>L&rsquo;affaire est \u00e9videmment particuli\u00e8rement grave, mais elle n&rsquo;\u00e9tonne pas par ailleurs si l&rsquo;on a une bonne mesure des m&oelig;urs washingtoniens. Elle concerne des intrusions secr\u00e8tes et ill\u00e9gales de la CIA dans les ordinateurs de divers membres et employ\u00e9s de la commission Feinstein, pour d\u00e9truire ou subtiliser des pi\u00e8ces concernant l&rsquo;enqu\u00eate g\u00e9n\u00e9rale, y compris des rapports tr\u00e8s sensibles, concernant les activit\u00e9s de torture de la CIA. (Feinstein, \u00e0 c\u00f4t\u00e9 de ses diverses accointances et engagements-Syst\u00e8me, notamment pour une protection sans concessions de la NSA, s&rsquo;est engag\u00e9e avec fougue dans le sens inverse, en faisant de la lutte contre les pratiques de torture de la CIA un axe central de son action parlementaire.) Il est \u00e9galement important de noter que la CIA a ripost\u00e9 \u00e0 certaines exigences et accusations de Feinstein, sans craindre de prendre l&rsquo;offensive et de d\u00e9fier la s\u00e9natrice et le Congr\u00e8s en g\u00e9n\u00e9ral. L&rsquo;affrontement prend des tournures fondamentales, Feinstein estimant qu&rsquo;il y a violation de la Constitution, intrusion et pression d&rsquo;une branche du pouvoir (l&rsquo;ex\u00e9cutif) contre la branche l\u00e9gislative. Certains estiment que ce conflit peut prendre un caract\u00e8re fondamental pour le Syst\u00e8me et conduire jusqu&rsquo;\u00e0 la Cour Supr\u00eame et \u00e0 un d\u00e9chirement consid\u00e9rable de ces deux branches du pouvoir washingtonien. Bref, l&rsquo;on ne parle pas moins que d&rsquo;une \u00ab\u00a0crise constitutionnelle\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Feinstein et sa commission, alli\u00e9s inconditionnels de l&rsquo;administration dans l&rsquo;affaire de la NSA, se retrouvent comme des adversaires d\u00e9termin\u00e9es, puisque l&rsquo;administration a d&rsquo;ores et d\u00e9j\u00e0 proclam\u00e9 son soutien et sa confiance \u00e0 la CIA et \u00e0 son directeur Brennan. Certains commentateurs ont imm\u00e9diatement trouv\u00e9 une formule pour caract\u00e9riser l&rsquo;attitude de la s\u00e9natrice Feinstein : l'\u00a0\u00bbeffet Merkel\u00a0\u00bb (concernant la fureur de la chanceli\u00e8re d\u00e9couvrant qu&rsquo;elle est \u00e9cout\u00e9e en permanence par la NSA), qui d\u00e9signe une attitude toute personnelle, conduisant une personnalit\u00e9 politique en g\u00e9n\u00e9ral bon petit soldat du Syst\u00e8me, s&rsquo;engageant brusquement dans une attaque contre ce Syst\u00e8me d\u00e8s lors qu&rsquo;elle en subit personnellement les pressions et les intrusions alors qu&rsquo;elle acceptait ou d\u00e9fendait ces pressions et ces intrusions par comportement conforme lorsque celles-ci ne la concernaient pas directement. La fureur anti-CIA (anti-IC) de Feinstein, d\u00e9fenderesse de l&rsquo;IC en g\u00e9n\u00e9ral, \u00e9quivaut \u00e0 la fureur antiam\u00e9ricaniste de Merkel, d\u00e9fenderesse des liens transatlantiques en g\u00e9n\u00e9ral, d\u00e8s lors que l&rsquo;une et l&rsquo;autre sont les victimes du Syst\u00e8me qu&rsquo;elles d\u00e9fendent en g\u00e9n\u00e9ral, &ndash; \u00ab\u00a0humain, trop humain\u00a0\u00bb, d\u00e9plore le Syst\u00e8me&#8230;<\/p>\n<\/p>\n<p><p>&bull; On trouve de tr\u00e8s nombreuses sources qui d\u00e9taillent cet affrontement. Outre le <em>Guardian<\/em>, on signalera l&rsquo;article de McClatchy.<em>News<\/em> du <a class=\"gen\" href=\"http:\/\/www.mcclatchydc.com\/2014\/03\/11\/220916\/cia-may-have-broken-law-undermined.html\">11 mars 2014<\/a> (&laquo;<em>CIA may have broken law, undermined Constitution, Sen. Feinstein charges<\/em>&raquo;), extr\u00eamement bien document\u00e9. On cite des extraits de <em>The Intercept<\/em>, la nouvelle publication de Glenn Greenwald, Laura Poitras &#038; compagnie, qui publie un long article sur cette affaire, le <a class=\"gen\" href=\"https:\/\/firstlook.org\/theintercept\/2014\/03\/11\/cia-search-congressional-computer-sparks-constitutional-crisis\/\">11 mars 2014<\/a>. (<em>The Intercept<\/em> est particuli\u00e8rement bien plac\u00e9 pour pr\u00e9senter et commenter cette affaire, vu la haute qualit\u00e9 et la sp\u00e9cialisation de son \u00e9quipe dans ce domaine. Le <a class=\"gen\" href=\"https:\/\/firstlook.org\/theintercept\/2014\/03\/05\/congress-intelligence-community-whos-overseeing\/\">5 mars 2014<\/a>, <em>The Intercept<\/em> avait publi\u00e9 un article sur des r\u00e9v\u00e9lations concernant l&rsquo;espionnage de la CIA de la commission Feinstein, renversant le r\u00f4le habituel de la surveillance de la CIA par cette commission. Nous sommes dans le m\u00eame domaine de l&rsquo;ill\u00e9galit\u00e9 et du viol de la Constitution.)<\/p>\n<\/p>\n<p><p>&laquo;<em>Two top Senate leaders declared Tuesday that the CIA&rsquo;s recent conduct has undermined the separation of powers as set out in the Constitution, setting the stage for a major battle to reassert the proper balance between the two branches. Intelligence Committee chair Dianne Feinstein (D-Calif.), in a floor speech that Judiciary Committee chair Patrick Leahy (D-Vt.) immediately called the most important he had heard in his career, said the CIA had searched through computers belonging to staff members investigating the agency&rsquo;s role in torturing detainees, and had then leveled false charges against her staff in an attempt to intimidate them.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>\u00ab\u00a0I have grave concerns that the CIA&rsquo;s search may well have violated the separation of powers principle embodied in the United States Constitution, including the speech and debate clause,\u00a0\u00bb she said. \u00ab\u00a0It may have undermined the constitutional framework essential to effective congressional oversight of intelligence activities or any other government function.\u00a0\u00bb She concluded: \u00ab\u00a0The recent actions that I have just laid out make this a defining moment for the oversight of our intelligence community. How Congress responds and how this is resolved will show whether the Intelligence Committee can be effective in monitoring and investigating our nation&rsquo;s intelligence activities, or whether our work can be thwarted by those we oversee. I believe it is critical that the committee and the Senate reaffirm our oversight role and our independence under the Constitution of the United States.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>She also accused the CIA of obstructing her committee&rsquo;s torture inquiry in general, and of disputing findings that its own internal inquiry had substantiated. The document at the heart of this confrontation is an internal review conducted by the CIA of the materials it had turned over to Feinstein&rsquo;s committee during the course of the four-year congressional investigation into the Bush-era torture practices. Feinstein said the document, which has become known as the Panetta Review after then-director of the CIA Leon Panetta, was first discovered by committee staff using CIA-provided search tools in 2010. It became particularly relevant later, after the committee completed a scathing 6,300-page report in December 2012, and the CIA sent its official response in June 2013.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Feinstein cite un historique des tentatives de la CIA d&rsquo;interf\u00e9rer sur le travail de la commission, par des actions ill\u00e9gales ou clandestines, selon des modalit\u00e9s qui apparentent ces actions \u00e0 un crime passible des condamnations les plus s\u00e9v\u00e8res, outre les aspects fondamentaux de leur inconstitutionnalit\u00e9, avec de sa part des tentatives pour avertir la CIA et demander des explications \u00e0 son directeur. &laquo;<em>John Brennan<\/em> [&#8230;] <em>informed her that CIA personnel had conducted a search of the committee&rsquo;s computers in the Virginia facility, including the standalone network that contained the committee staff&rsquo;s own internal work product and communication. The senator was outraged, she said, and fired off a letter expressing her concerns that the action was illegal and unconstitutional.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>\u00ab\u00a0I have asked for an apology and a recognition that this CIA search of computers used by its oversight committee was inappropriate. I have received neither,\u00a0\u00bb she said. \u00ab\u00a0Besides the constitutional implications, the CIA search may also have violated the Fourth Amendment, the Computer Fraud and Abuse Act, as well as Executive Order 12333, which prohibits the CIA from conducting domestic searches or surveillance.\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<p><p>On trouvera dans les diff\u00e9rents articles cit\u00e9s les nombreux d\u00e9tails et arcanes de cette affaire, qui a le potentiel de devenir tr\u00e8s grave puisqu&rsquo;elle a \u00e9t\u00e9 aussit\u00f4t plac\u00e9e sur le plan le plus haut qui est l&rsquo;affrontement entre deux branches du syst\u00e8me de l&rsquo;am\u00e9ricanisme, et l&rsquo;accusation d&rsquo;inconstitutionnalit\u00e9. Bien entendu, de nombreuses autres affaires auraient m\u00e9rit\u00e9 de telles agitations, qui ont \u00e9t\u00e9 prestement \u00e9touff\u00e9es, mais celle-l\u00e0 pr\u00e9sente la particularit\u00e9 de voir les deux adversaires (Feinstein\/Congr\u00e8s d&rsquo;une part, CIA\/administration d&rsquo;autre part) prendre aussit\u00f4t et publiquement des attitudes antagonistes tranch\u00e9es, dans le cadre le plus fondamental des r\u00e8gles du Syst\u00e8me, tout cela les engageant \u00e0 mesure. Il s&rsquo;agit aussi bien des circonstances m\u00eames que des engagements personnels solennels, fond\u00e9s sur des convictions de pr\u00e9rogatives, sur des inimiti\u00e9s personnelles, sur une rh\u00e9torique dramatis\u00e9e et des r\u00e9f\u00e9rences au cadre fondamental du syst\u00e8me (du c\u00f4t\u00e9 de Feinstein) et des obligations fondamentales de s\u00e9curit\u00e9 nationale (du c\u00f4t\u00e9 de la CIA).<\/p>\n<\/p>\n<p><p>Peu nous importe ici, pour l&rsquo;instant dans tous les cas, de conna&icirc;tre le fondement de ces positions respectives, non plus que les arguments des uns et des autres. L&rsquo;essentiel est ce conflit au sein du Syst\u00e8me et la dimension tr\u00e8s importante qu&rsquo;il a aussit\u00f4t prise. Il est d&rsquo;ailleurs remarquable qu&rsquo;il ait \u00e9t\u00e9 aussit\u00f4t propuls\u00e9 dans les domaines les plus fondamentaux des querelles internes, avec l&rsquo;accusation sacril\u00e8ge de la violation de la Constitution. Bien d&rsquo;autres affaires de cette sorte ont d\u00e9j\u00e0 eu lieu, certaines \u00e9touff\u00e9es, d&rsquo;autre trait\u00e9es avec le maximum de retenue pour les emp\u00eacher d&rsquo;aboutir justement \u00e0 ce point de rupture. La tournure extr\u00eame aussit\u00f4t proclam\u00e9e et affirm\u00e9e implique une immense nervosit\u00e9 \u00e0 Washington, des divisions tr\u00e8s graves au sein du syst\u00e8me de l&rsquo;am\u00e9ricanisme, des r\u00e9flexes des acteurs de se replier aussit\u00f4t sur leurs pr\u00e9rogatives formelles d&rsquo;une fa\u00e7on solennelle en accusant gravement la partie adverse pour mieux se d\u00e9fausser de comportements ant\u00e9rieurs o&ugrave; ils furent gravement mis en cause. On peut faire l&rsquo;hypoth\u00e8se que Feinstein, bien qu&rsquo;elle ait montr\u00e9 depuis longtemps une hostilit\u00e9 furieuse aux programmes de torture de la CIA, n&rsquo;aurait pas n\u00e9cessairement r\u00e9agi avec tant de vigueur et de fureur si elle n&rsquo;avait pas \u00e9t\u00e9 mise en cause pendant ces neuf derniers mois pour sa d\u00e9fense de la NSA, &ndash; laquelle est elle aussi, comme la CIA, dans des zones de violation de la Constitution sans que cela ait \u00e9mu Feinstein. Si l&rsquo;on ose dire pour une dame si honorable, la s\u00e9natrice se refait une virginit\u00e9 \u00e0 cette occasion, &ndash; cela sur un plan politique et constitutionnel, cela va sans dire et sans la moindre ironie d\u00e9plac\u00e9e, on peut en \u00eatre assur\u00e9.<\/p>\n<\/p>\n<p><p>Bien entendu, on fera la remarque que cette affaire qui devrait mobiliser toute l&rsquo;attention de l&rsquo;ex\u00e9cutif et du l\u00e9gislatif, \u00e9clate en pleine crise ukrainienne et interf\u00e8re d\u00e8s lors dans une action collective qui aurait d&ucirc; \u00eatre exclusive \u00e0 cette crise si importante. Cela affaiblit brusquement d&rsquo;autant la position des USA, qui n&rsquo;est d\u00e9j\u00e0 pas particuli\u00e8rement efficace. C&rsquo;est en effet une constante de l&rsquo;\u00e9norme machinerie washingtonienne qu&rsquo;elle est incapable paradoxalement de traiter plusieurs questions urgentes de front, qu&rsquo;elle d\u00e9place toute son attention mobilis\u00e9e vers la nouvelle crise d\u00e8s que celle-ci survient, d\u00e9laissant d&rsquo;autant la crise o&ugrave; elle se trouvait engag\u00e9e.<\/p>\n<\/p>\n<p><p>L&rsquo;affaire Feinstein-CIA va n\u00e9cessairement monopoliser le Congr\u00e8s derri\u00e8re Feinstein d&rsquo;une part, obliger l&rsquo;administration Obama qui doit d\u00e9fendre au moins pour l&rsquo;instant la CIA \u00e0 se lancer dans une de ces batailles internes qui accapare toute son attention d&rsquo;autre part. Les diff\u00e9rents partis, les diff\u00e9rentes factions, vont devoir \u00e0 nouveau se lancer dans cette bataille interne, se red\u00e9finir en fonction d&rsquo;une nouvelle crise, ce qui implique \u00e0 nouveau un d\u00e9sint\u00e9r\u00eat pour la crise ukrainienne. Par ailleurs, on devrait voir dans ce processus une confirmation indirecte de l&rsquo;attitude g\u00e9n\u00e9rale de Washington, qui ne s&rsquo;est jamais jug\u00e9 compl\u00e8tement senti concern\u00e9 par la crise ukrainienne, bien que l&rsquo;administration et le Congr\u00e8s s&rsquo;y soient engag\u00e9s \u00e0 fond durant ces deux derni\u00e8res semaines, souvent d&rsquo;ailleurs pour des raisons de communication avec une composante interne non n\u00e9gligeable (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-communication-blitzkrieg_10_03_2014.html\">10 mars 2014<\/a>). Cela introduit une nouvelle phase d&rsquo;incertitudes, de possibilit\u00e9 de fausses man&oelig;uvres ou d&rsquo;absence de r\u00e9action de la part de l&rsquo;administration Obama, et donc un d\u00e9sordre suppl\u00e9mentaire dans la crise ukrainienne ; et d&rsquo;ailleurs, et bien s&ucirc;r, cela introduit les m\u00eames composants \u00e0 Washington.<\/p>\n<\/p>\n<p><p>Mis en ligne le 12 mars 2014 \u00e0 06H28<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;intelligence US et Dianne Feinstein &#8230; Effectivement, il suffit de changer quelques mots dans le titre et le sous-titre du Bloc-Notes pr\u00e9c\u00e9dent (le 11 mars 2014) pour passer de la sc\u00e8ne ukrainienne \u00e0 la sc\u00e8ne washingtonienne tout en restant avec le m\u00eame acteur (l&rsquo;Intelligence Community, ou IC) qui ne cesse d&rsquo;accumuler les erreurs, les abus&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[12592,3104,1463,15685,3285,4518,6302,3228,7614,4008,3871,2807,1296,15687],"class_list":["post-73762","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-brennan","tag-cia","tag-commission","tag-communauty","tag-congres","tag-constitution","tag-constitutionnelle","tag-crise","tag-feinstein","tag-intelligence","tag-nsa","tag-renseignement","tag-ukraine","tag-violation"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73762"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73762\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}