{"id":73777,"date":"2014-03-19T14:45:12","date_gmt":"2014-03-19T14:45:12","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/03\/19\/melenchon-de-nouveau-parmi-nous\/"},"modified":"2014-03-19T14:45:12","modified_gmt":"2014-03-19T14:45:12","slug":"melenchon-de-nouveau-parmi-nous","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/03\/19\/melenchon-de-nouveau-parmi-nous\/","title":{"rendered":"M\u00e9lenchon de nouveau parmi nous"},"content":{"rendered":"<p><h4 class=\"breve-de-crise\">M\u00e9lenchon de nouveau parmi nous<\/h4>\n<p>Quand les grandes questions et crises internationales surgissent, M\u00e9lenchon, l&rsquo;homme du Font de gauche, excelle \u00e0 nous rappeler ce que devrait \u00eatre la politique de la France. O\u00f9 devrait \u00eatre actuellement Fran\u00e7ois Hollande ?, l&rsquo;interrogeait <em>France 24<\/em> dimanche <a href=\"http:\/\/www.dailymotion.com\/video\/x1hmu4g_hollande-ment-tout-le-temps-j-l-melenchon_news?start=138\" class=\"gen\">16 mars 2014<\/a> apr\u00e8s que lon eut vu le pr\u00e9sident-poire dans un de ces inoubliables performances sur le droit internationale, sur l&rsquo;Europe, nos amis am\u00e9ricains, etc. ; \u00e0 quoi M\u00e9lenchon r\u00e9pondait  : A Moscou, en train de n\u00e9gocier avec les Russes, pour savoir les conditions qui satisferaient leurs besoins de s\u00e9curit\u00e9. (M\u00e9lenchon pense que la suppression des sites antimissiles BDM le long de la fronti\u00e8re russe, l&rsquo;Ukraine orientale garantie en zone d\u00e9militaris\u00e9e, la base S\u00e9bastopol garantie aux Russes, \u00e9viteraient ais\u00e9ment la crise actuelle, dont les cons\u00e9quences sont incalculables et incontr\u00f4lables&#8230;)<\/p>\n<\/p>\n<p><p>\tLe <a href=\"http:\/\/www.jean-luc-melenchon.fr\/2014\/03\/15\/au-debut-des-magnolias\/#article2\" class=\"gen\">15 mars 2014<\/a>, sur son <em>blog<\/em>, M\u00e9lenchon \u00e9crivait notamment : \u00ab<em>Bien s\u00fbr la Crim\u00e9e est perdue pour l&rsquo;OTAN. Bonne nouvelle. Il faut esp\u00e9rer que, du coup, la bande de provocateurs et d&rsquo;agit\u00e9s qui dirigent la manuvre va se calmer quelque temps. Car il \u00e9tait \u00e9vident que si recommen\u00e7ait le cirque qui a conduit en son temps le g\u00e9orgien Saakachvili \u00e0 vouloir brutaliser les enclaves russophones de son pays, l&rsquo;affaire finirait comme alors. C&rsquo;est-\u00e0-dire par une s\u00e9cession sous protection militaire russe. Poutine a profit\u00e9 habilement d&rsquo;une politique aventuri\u00e8re et irresponsable provoqu\u00e9e par les autorit\u00e9s de fait ukrainiennes. Mais avait-il le choix ? Pouvait-il accepter une avanc\u00e9e de l&rsquo;OTAN en Crim\u00e9e, sa grande base navale sur la mer noire, trajet du gazoduc qui contourne l&rsquo;incontr\u00f4lable Ukraine ? Non, bien s\u00fbr, et aucune personne inform\u00e9e ne peut soutenir le contraire. Inconv\u00e9nient : l&rsquo;occasion a fait le larron: la prise d&rsquo;avantage est consid\u00e9rable pour la Russie. Avantage : la fronti\u00e8re de l&rsquo;est est \u00e0 peu pr\u00e8s stabilis\u00e9e si l&rsquo;OTAN n&rsquo;en rajoute pas. Les USA avancent et conqui\u00e8rent le chaos ukrainien, mais les russes reprennent la Crim\u00e9e. En cas de prolongation des tensions, les Russes prendront aussi le Donetz. Le moment venu, les Polonais mettront les doigts dans le secteur eux aussi. Mais c&rsquo;est une autre histoire&#8230;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tNous ne cesserons jamais de regretter que les forces qui, en France, ont des analyses et des positions politiques proches, sinon convergentes, sur les grandes questions et crises internationales conditionnant et pr\u00e9cipitant toutes les graves tensions int\u00e9rieures que nous connaissons, que ces forces se s\u00e9parent par des antagonismes int\u00e9rieurs qui ne rel\u00e8vent justement que d&rsquo;effets indirects. On pense \u00e9videmment \u00e0 la gauche antiSyst\u00e8me et \u00e0 la droite antiSyst\u00e8me, qui ont dans la crise actuelle cette convergence, qui est le fondement fran\u00e7ais de la position antiSyst\u00e8me, c&rsquo;est-\u00e0-dire de ce que devrait \u00eatre une position fran\u00e7aise logique, digne et souveraine, hors de la bouillie pour les chats qu&rsquo;ils d\u00e9gustent \u00e0 la louche dans leurs palais minist\u00e9riels. (Pour M\u00e9lenchon, voir le <a href=\"http:\/\/www.dedefensa.org\/article-in_extremis__12_04_2012.html\" class=\"gen\">12 avril 2012<\/a>, le <a href=\"http:\/\/www.dedefensa.org\/article-m_lenchon_tel_qu_en_lui-m_me_20_04_2012.html\" class=\"gen\">20 avril 2012<\/a>, pour Marine Le Pen, puisque c&rsquo;est la repr\u00e9sentante de l&rsquo;autre tendance qu&rsquo;on \u00e9voque ici, voir le <a href=\"http:\/\/www.dedefensa.org\/article-marine_d_un_extr_me_l_autre_02_07_2013.html\" class=\"gen\">2 juillet 2013<\/a>.)<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 19 mars 2014 \u00e0 14H46<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9lenchon de nouveau parmi nous Quand les grandes questions et crises internationales surgissent, M\u00e9lenchon, l&rsquo;homme du Font de gauche, excelle \u00e0 nous rappeler ce que devrait \u00eatre la politique de la France. O\u00f9 devrait \u00eatre actuellement Fran\u00e7ois Hollande ?, l&rsquo;interrogeait France 24 dimanche 16 mars 2014 apr\u00e8s que lon eut vu le pr\u00e9sident-poire dans un&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[4646,3228,3579,2711,3572,8315,3314,2730,5507,1296],"class_list":["post-73777","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-antisysteme","tag-crise","tag-gaullisme","tag-le","tag-marine","tag-melenchon","tag-pen","tag-russie","tag-sebastopol","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73777"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73777\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}