{"id":73836,"date":"2014-04-19T16:54:28","date_gmt":"2014-04-19T16:54:28","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/04\/19\/de-strangelove-a-breedlove\/"},"modified":"2014-04-19T16:54:28","modified_gmt":"2014-04-19T16:54:28","slug":"de-strangelove-a-breedlove","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/04\/19\/de-strangelove-a-breedlove\/","title":{"rendered":"De <em>Strangelove<\/em> \u00e0 Breedlove&#8230;"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">De <em>Strangelove<\/em> \u00e0 Breedlove&#8230;<\/h2>\n<\/p>\n<p><p>Non, admettez tout de m\u00eame que le destin a d&rsquo;\u00e9tranges fac\u00e9ties, &ndash; et nous-m\u00eames, sans les r\u00e9aliser aussit\u00f4t ! Le g\u00e9n\u00e9ral commandant en chef des forces de l&rsquo;OTAN qui se trouvent <strong>face \u00e0 la Russie<\/strong> dans la crise ukrainienne, un g\u00e9n\u00e9ral de l&rsquo;USAF plac\u00e9 au poste de SACEUR, se nomme Breedlove. Cela signifierait aussi bien \u00ab\u00a0produire l&rsquo;amour\u00a0\u00bb, ou bien encore \u00ab\u00a0engendrer l&rsquo;amour\u00a0\u00bb ; alors, sans penser \u00e0 plus salace que cela, il est vrai que doit vous venir \u00e0 l&rsquo;esprit le nom de <em>Strangelove<\/em> (\u00ab\u00a0Amour \u00e9trange\u00a0\u00bb, ou \u00ab\u00a0Folamour\u00a0\u00bb), qui est le titre du film de Kubrick de 1964, &ndash; <em>Dr. Strangelove, Or How I Learned to Love the Bomb<\/em>, &ndash; et ainsi a-t-on le g\u00e9n\u00e9ral Breedlove qui \u00ab\u00a0engendre l&rsquo;amour\u00a0\u00bb, et cet amour qui pourrait bien \u00eatre ce <em>Strangelove<\/em> de 1964. Dans tous les cas, John Pilger fait avec sagacit\u00e9 et \u00e0-propos le rapprochement entre les deux noms, dans son commentaire, notamment sur <em>Antiwar.com<\/em> le <a class=\"gen\" href=\"http:\/\/original.antiwar.com\/pilger\/2014\/04\/18\/the-strangelove-effect-or-how-we-are-hoodwinked-into-accepting-a-new-world-war\/\">19 avril 2014<\/a> (&laquo;<em>The Strangelove Effect &ndash; Or How We Are Hoodwinked Into Accepting a New World War<\/em>&raquo;).<\/p>\n<\/p>\n<p><p>&laquo;<em>Since Washington&rsquo;s putsch in Kiev &ndash; and Moscow&rsquo;s inevitable response in Russian Crimea, to protect its Black Sea Fleet &ndash; the provocation and isolation of Russia have been inverted in the news to the \u00ab\u00a0Russian threat\u00a0\u00bb. This is fossilized propaganda. The US Air Force general who runs NATO forces in Europe &ndash; General Breedlove, no less &ndash; claimed more than two weeks ago to have pictures showing 40,000 Russian troops \u00ab\u00a0massing\u00a0\u00bb on the border with Ukraine. So did Colin Powell claim to have pictures of weapons of mass destruction in Iraq. What is certain is that Obama&rsquo;s rapacious, reckless coup in Ukraine has ignited a civil war and Vladimir Putin is being lured into a trap.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Following a 13-year rampage that began in stricken Afghanistan well after Osama bin Laden had fled, then destroyed Iraq beneath a false flag, then invented a \u00ab\u00a0nuclear rogue\u00a0\u00bb in Iran, dispatched Libya to a Hobbesian anarchy and backed jihadists in Syria, the US finally has a new cold war to supplement its worldwide campaign of murder and terror by drone.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>A NATO Membership Action Plan or MAP &ndash; straight from the war room of Strangelove &ndash; is General Breedlove&rsquo;s gift to the new dictatorship in Ukraine. \u00ab\u00a0Rapid Trident\u00a0\u00bb will put US troops on Ukraine&rsquo;s Russian border and \u00ab\u00a0Sea Breeze\u00a0\u00bb will put US warships within sight of Russian ports. At the same time, NATO war games throughout eastern Europe are designed to intimidate Russia. Imagine the response if this madness was reversed and happened on America&rsquo;s borders&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Le rappel de <em>Strangelove<\/em> par Pilger est bienvenu. Bien entendu, la r\u00e9f\u00e9rence est, ou devrait \u00eatre dans tous les esprits avertis des risques r\u00e9els qui se trouvent \u00e0 peine dissimul\u00e9s, derri\u00e8re cette monstrueuse crise ukrainienne. Nous-m\u00eames l&rsquo;avons \u00e9voqu\u00e9, <em>Strangelove<\/em>, r\u00e9cemment encore, \u00e9galement \u00e0 propos de l&rsquo;attitude si \u00e9tonnamment d\u00e9sinvolte d&rsquo;Obama concernant l&rsquo;hypoth\u00e8se d&rsquo;un affrontement militaire direct avec la Russie (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-de_folamour_bho_et_l_attaque_inappropri_e_contre_la_russie_20_03_2014.html\">20 mars 2014<\/a>). Cette attitude d\u00e9sinvolte, et sans la moindre conscience de l&rsquo;ampleur des risques courus d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, avec l&rsquo;hypoth\u00e8que de la guerre nucl\u00e9aire, appara&icirc;t encore dans une intervention plus r\u00e9cente du m\u00eame Obama, qui se trouve \u00eatre pr\u00e9sident des Etats-Unis (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-bho_ou_l_int_gration_r_ussie_de_l_hybris_apocalyptique_18_04_2014.html\">18 avril 2014<\/a>).<\/p>\n<\/p>\n<p><p>&Eacute;voquant <em>Strangelove<\/em>, Pilger rappelle les personnages et l&rsquo;une ou l&rsquo;autre sc\u00e8ne fameuse du film. Il rappelle combien ce film est inspir\u00e9 de personnages r\u00e9els, et m\u00eame de situations r\u00e9elles, ce qui \u00e9tait d&rsquo;ailleurs bien dans la mani\u00e8re de Kubrick qui introduisait dans tous ses films de tr\u00e8s nombreux symboles, des r\u00e9f\u00e9rences cach\u00e9es, etc., qui constituent aujourd&rsquo;hui un domaine d&rsquo;\u00e9tude sp\u00e9cifique. Il est en g\u00e9n\u00e9ral admis que le g\u00e9n\u00e9ral Turgidson, chef d&rsquo;\u00e9tat-major de l&rsquo;USAF, repr\u00e9sente la psychologie un peu caricatur\u00e9e du g\u00e9n\u00e9ral LeMay, lui-m\u00eame chef d&rsquo;\u00e9tat-major de l&rsquo;USAF jusqu&rsquo;en 1964 et bien connu pour saliver \u00e0 propos des d\u00e9comptes de dizaines de millions de morts qu&rsquo;aurait caus\u00e9s l&rsquo;une ou l&rsquo;autre mission des B-52 de \u00ab\u00a0son\u00a0\u00bb Strategic Air Command (SAC). Quant \u00e0 la v\u00e9racit\u00e9 recr\u00e9\u00e9e de la situation et du propos, on se reportera \u00e0 la r\u00e9action de Daniel Ellsberg lorsqu&rsquo;il vit le film \u00e0 sa sortie en 1964, commentant simplement : \u00ab\u00a0C&rsquo;est un documentaire sur le SAC\u00a0\u00bb (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-folamour_n_tait_pas_loin_du_vrai_29_01_2010.html\">29 janvier 2010<\/a>). Pilgen : &laquo;<em>I watched Dr. Strangelove the other day. I have seen it perhaps a dozen times; it makes sense of senseless news. When Major T.J. \u00ab\u00a0King\u00a0\u00bb Kong goes \u00ab\u00a0toe to toe with the Rooskies\u00a0\u00bb and flies his rogue B52 nuclear bomber to a target in Russia, it&rsquo;s left to General \u00ab\u00a0Buck\u00a0\u00bb Turgidson to reassure the President. Strike first, says the general, and \u00ab\u00a0you got no more than 10 to 20 million killed, tops.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>President Merkin Muffley: \u00ab\u00a0I will not go down in history as the greatest mass-murderer since Adolf Hitler.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>General Turgidson: \u00ab\u00a0Perhaps it might be better, Mr. President, if you were more concerned with the American people than with your image in the history books.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>The genius of Stanley Kubrick&rsquo;s film is that it accurately represents the cold war&rsquo;s lunacy and dangers. Most of the characters are based on real people and real maniacs. There is no equivalent to Strangelove today, because popular culture is directed almost entirely at our interior lives, as if identity is the moral zeitgeist and true satire is redundant; yet the dangers are the same. The nuclear clock has remained at five minutes to midnight; the same false flags are hoisted above the same targets by the same \u00ab\u00a0invisible government\u00a0\u00bb, as Edward Bernays, the inventor of public relations, described modern propaganda.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Ces temps \u00e9taient peut-\u00eatre fous, comme le montre Kubrick, mais peut-\u00eatre moins, beaucoup moins que nos temps actuels o&ugrave; l&rsquo;hypoth\u00e8se et l&rsquo;hypoth\u00e8que de la guerre nucl\u00e9aire sont \u00e9trangement ignor\u00e9es, ou presque. Comme on le lit, Pilgen observe justement combien <em>Strangelove<\/em> pr\u00e9sente des situations et des personnages compl\u00e8tement absents de nos esprits (&laquo;<em>There is no equivalent to Strangelove today, because popular culture is directed almost entirely at our interior lives, as if identity is the moral zeitgeist and true satire is redundant&#8230;<\/em>&raquo;). Il attribue ce fait, cette absence extraordinaire du danger de la guerre nucl\u00e9aire sous la forme symbolique et populaire, \u00e0 \u00ab\u00a0notre culture\u00a0\u00bb, mais nous-m\u00eames irions plus loin et jugerions que nos psychologies ont \u00e9t\u00e9 compl\u00e8tement transform\u00e9es, et d&rsquo;ailleurs plus par la puissance du syst\u00e8me de la communication que par \u00ab\u00a0nos cultures\u00a0\u00bb. Cette formidable pouss\u00e9e transformant la psychologie s&rsquo;est faite au travers de l'\u00a0\u00bbindividualisation\u00a0\u00bb, vers l&rsquo;individu, l&rsquo;individualisme, l&rsquo;identit\u00e9 de soi et rien d&rsquo;autre, referm\u00e9 sur le reste du monde sinon l&rsquo;acquiescement aux slogans convenus du Syst\u00e8me, avec la perte du sens collectif des \u00e9v\u00e9nements, et la sensation de plus en plus r\u00e9pandu chez l&rsquo;individu de n&rsquo;\u00eatre pas concern\u00e9 par la plupart des \u00e9v\u00e9nements collectifs, et encore plus par des \u00e9v\u00e9nements collectifs dont il ignore finalement la possibilit\u00e9, ou dont il n&rsquo;accepte pas la possibilit\u00e9.<\/p>\n<\/p>\n<p><p>Il nous semble que cette situation psychologique joue un grand r\u00f4le dans l&rsquo;extraordinaire farce tragique qu&rsquo;est la crise ukrainienne, essentiellement du c\u00f4t\u00e9 du bloc BAO, o&ugrave; m\u00eame les dirigeants, &ndash; o&ugrave; surtout les dirigeants semblent avoir perdu la perception de la monstruosit\u00e9 de la possibilit\u00e9 de la guerre nucl\u00e9aire. On a clairement cette sensation avec Obama, comme avec nombre de dirigeants occidentaux en Europe ; on en est encore \u00e0 attendre, parmi les cris d&rsquo;indignation sur tel ou tel aspect de la crise, parmi les mesures militaires de d\u00e9monstration recommand\u00e9es, etc., une voix un peu plus mesur\u00e9e qui nous rappellerait ce qu&rsquo;est le risque d&rsquo;un affrontement militaire entre les USA et la Russie, les deux puissances nucl\u00e9aires strat\u00e9giques qui sont impliqu\u00e9es. (Il nous semble bien entendu que, du c\u00f4t\u00e9 russe, la situation est sans nul doute certainement tr\u00e8s diff\u00e9rente. Il est manifeste que les Russes ont une conscience beaucoup plus nette de la <strong>dangerosit\u00e9 objective<\/strong> de la situation, ce qui explique sans doute divers aspects de leur d\u00e9marche et de leur comportement dans la crise.)<\/p>\n<\/p>\n<p><p>Il nous para&icirc;t que cette dimension psychologique repr\u00e9sente une force consid\u00e9rable dans le d\u00e9veloppement de la crise, comme si la tension m\u00eame de la crise confirmait la vision r\u00e9ductrice du danger qu&rsquo;elle rec\u00e8le. Cette situation permet effectivement l&rsquo;aggravation de la crise, particuli\u00e8rement aux niveaux de la perception et de la communication qui ont toujours \u00e9t\u00e9 consid\u00e9r\u00e9es comme les domaines fondamentaux des relations entre les puissances nucl\u00e9aires pendant la guerre froide, justement parce que par leurs canaux, en cas de dysfonctionnement, on pouvait aboutir \u00e0 une situation d&rsquo;affrontement qu&rsquo;on voulait \u00e9viter \u00e0 tout prix. Aujourd&rsquo;hui, toujours \u00e0 cause de cette psychologie essentiellement du c\u00f4t\u00e9 du bloc BAO, rien ne freine l&rsquo;\u00e9volution vers des situations impr\u00e9vues o&ugrave; justement l&rsquo;on pourrait d\u00e9boucher sur le risque nucl\u00e9aire supr\u00eame. La conduite des USA, ponctuant des n\u00e9gociations dites de \u00ab\u00a0d\u00e9sescalade\u00a0\u00bb par des quasi-insultes officielles et des renforcements de forces US dans les pays limitrophes de la Russie, est un des moteurs essentiels de cette dynamique. La description plus large qu&rsquo;offre Pilger dans son article, observant le m\u00eame comportement US dans la zone asiatique, contre la Chine, conduit \u00e0 la conclusion que l&rsquo;une des deux puissances nucl\u00e9aires strat\u00e9giques du monde a effectivement perdu tout contact de perception avec la signification de ce statut qui est le sien. Nous ne sommes plus \u00e0 l&rsquo;\u00e9poque o&ugrave; les milieux officiels craignaient que l&rsquo;un ou l&rsquo;autre <em>Strangelove<\/em> impliqu\u00e9 dans la direction du pays suscit\u00e2t une \u00e9volution du type d\u00e9crit par le film (on sait que Kennedy avait encourag\u00e9, au d\u00e9but des ann\u00e9es soixante, des films de ce type) ; nous sommes \u00e0 l&rsquo;\u00e9poque o&ugrave; les USA sont devenu <em>Strangelove<\/em> lui-m\u00eame, en oubliant d\u00e9sormais de r\u00e9aliser ce que cela signifie en fait de risques strat\u00e9giques, sinon de risques ontologiques. Pour autant, et en observant le nombre de sp\u00e9culations des milieux ind\u00e9pendants concernant un tel risque, et peut-\u00eatre, sans doute si la crise se poursuit \u00e0 ce rythme, la probabilit\u00e9 que la Russie elle-m\u00eame \u00e9voque ce risque, nous consid\u00e9rons plus que jamais qu&rsquo;\u00e0 un moment la r\u00e9alit\u00e9 de cette hypoth\u00e8se catastrophique va finalement transpercer le barrage psychologique qui la repousse pour l&rsquo;instant. Il s&rsquo;agira sans aucun doute d&rsquo;un moment-clef de la crise (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-la_guerre_est_en_r_paration_d_urgence_03_03_2014.html\">23 mars 2014<\/a>).<\/p>\n<\/p>\n<p><p>Mis en ligne le 19 avril 2014 \u00e0 16H56<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De Strangelove \u00e0 Breedlove&#8230; Non, admettez tout de m\u00eame que le destin a d&rsquo;\u00e9tranges fac\u00e9ties, &ndash; et nous-m\u00eames, sans les r\u00e9aliser aussit\u00f4t ! Le g\u00e9n\u00e9ral commandant en chef des forces de l&rsquo;OTAN qui se trouvent face \u00e0 la Russie dans la crise ukrainienne, un g\u00e9n\u00e9ral de l&rsquo;USAF plac\u00e9 au poste de SACEUR, se nomme Breedlove.&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3380,13535,3004,4855,3099,1296],"class_list":["post-73836","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-folamour","tag-kubrick","tag-nucleaire","tag-pilger","tag-psychologie","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73836"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73836\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}