{"id":73837,"date":"2014-04-21T22:48:02","date_gmt":"2014-04-21T22:48:02","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/04\/21\/un-objectif-eurobrics\/"},"modified":"2014-04-21T22:48:02","modified_gmt":"2014-04-21T22:48:02","slug":"un-objectif-eurobrics","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/04\/21\/un-objectif-eurobrics\/","title":{"rendered":"Un objectif : EuroBRICS"},"content":{"rendered":"<p><h2 class=\"common-article2\">Un objectif : EuroBRICS<\/h2>\n<\/p>\n<p><p>\tLes pays du BRICS ont annonc\u00e9 r\u00e9cemment qu&rsquo;ils entendaient mettre en place dans les prochains mois l&rsquo;\u00e9quivalent du FMI et de la Banque mondiale dans le cadre de l&rsquo;association qu&rsquo;ils ont d\u00e9cid\u00e9 de cr\u00e9er entre eux il y a environ un an.<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit d&rsquo;abord de mobiliser des \u00e9pargnes venant directement des pays concern\u00e9s, afin de financer des op\u00e9rations int\u00e9ressant ces m\u00eames pays. Il s&rsquo;agit ensuite d&rsquo;\u00e9chapper \u00e0 l&rsquo;influence jug\u00e9e excessive des Etats-Unis au sein du FMI et de la Banque mondiale. Ces organismes imposent aux pays assist\u00e9s des conditions d&rsquo;acc\u00e8s aux cr\u00e9dits depuis longtemps jug\u00e9es non seulement inefficaces mais encore permettant aux pays riches et aux int\u00e9r\u00eats financiers qu&rsquo;ils repr\u00e9sentent une intrusion ill\u00e9gitime dans la gestion des pays \u00ab assist\u00e9s \u00bb. <\/p>\n<\/p>\n<p><p>\tMais les Etats-Unis refusent toute modification du statut des organismes \u00e0 vocation internationale mis en place \u00e0 la fin de la seconde guerre mondiale, qui leur assurent un r\u00f4le dominant. Ils bataillent en effet depuis quatre ans pour repousser une r\u00e9forme structurelle qui les priverait d&rsquo;une partie de leur pouvoir d&rsquo;influence, notamment le droit de veto constituant l&rsquo;essentiel de leur pouvoir de d\u00e9cision. <\/p>\n<\/p>\n<p><p>\tSelon les informations actuellement diffus\u00e9es, le fonds de r\u00e9serve de futur organisme serait disponible d\u00e8s 2015. La Banque internationale correspondante serait mise en place aussit\u00f4t apr\u00e8s. Le montant du Fonds serait initialement fix\u00e9 \u00e0 50 milliards de dollars. D&rsquo;ores et d\u00e9j\u00e0 la Chine a propos\u00e9 de fournir 41 milliards, le Br\u00e9sil, l&rsquo;Inde et la Russie 18 milliards chacun, l&rsquo;Afrique du Sud 5 milliards. Le montant du futur fonds ne serait pas aussi \u00e9lev\u00e9 que celui du FMI (370 milliards de dollars) mais initialement le nombre des pays pouvant y pr\u00e9tendre serait moins grand. Dans la perspective de l&rsquo;\u00e9tablissement d&rsquo;un monde multipolaire, \u00e9chappant \u00e0 la domination jusqu&rsquo;ici exerc\u00e9e unilat\u00e9ralement par les Etats-Unis, ce Fonds sera le bienvenu. <\/p>\n<h3>Une participation europ\u00e9enne<\/h3>\n<\/p>\n<p><p>\tNous pensons que l&rsquo;Europe ne devrait pas s&rsquo;en tenir \u00e0 l&rsquo;\u00e9cart. L&rsquo;Europe ou tout au moins l&rsquo;Eurogroupe, par l&rsquo;interm\u00e9diaire de la Banque centrale europ\u00e9enne et de ses fonds d&rsquo;investissement utilisant l&rsquo;euro, pourrait offrir une contribution importante au fonds d&rsquo;investissement des BRICS. Cela ne l&rsquo;obligerait pas d&rsquo;ailleurs \u00e0 se retirer du FMI. La participation europ\u00e9enne serait en euros. Une parit\u00e9 fixe ou flottante pourrait \u00eatre organis\u00e9e avec la future unit\u00e9 de change commune qu&rsquo;\u00e9tudient par ailleurs les BRICS. Au sein du fonds BRICS, les europ\u00e9ens pourraient participer directement au financement de projets int\u00e9ressant les membres du BRICS ou d&rsquo;autres pays consid\u00e9r\u00e9s comme partageant les m\u00eames pr\u00e9occupations politiques et \u00e9conomiques. Plus g\u00e9n\u00e9ralement, ils se mettraient en \u00e9tat de n\u00e9gocier avec eux sur des bases solides d&rsquo;\u00e9ventuels trait\u00e9s de libre-\u00e9change. Ceux-ci \u00e9quilibreraient utilement le futur Trait\u00e9 de libre-\u00e9change transatlantique en cours de n\u00e9gociation. <\/p>\n<\/p>\n<p><p>\tAu del\u00e0 de ceci, quels avantages les Europ\u00e9ens trouveraient-ils dans la participation de l&rsquo;Union europ\u00e9enne au futur Fonds, que nous nommerons d\u00e9sormais Fonds Mon\u00e9taire EuroBRICS (EuroBRICS monetary fund ou EBMF) ? D&rsquo;une part ils pourraient se rapprocher diplomatiquement de pays qui repr\u00e9sentent d\u00e9j\u00e0 les 2\/3 des effectifs mondiaux. D&rsquo;autre part et surtout, ils pourraient influencer les investissements des membres dans un sens correspondant aux grands objectifs que d\u00e9fend l&rsquo;Europe. Nous pensons en particulier aux programmes destin\u00e9s \u00e0 pr\u00e9venir les destructions qu&rsquo;imposera le r\u00e9chauffement climatique. Ils pourront aussi soutenir par ce biais les industriels europ\u00e9ennes travaillant dans le sens des activit\u00e9s dites vertes. <\/p>\n<\/p>\n<p><p>\tOn objectera qu&rsquo;il serait utopique d&rsquo;envisager la cr\u00e9ation d&rsquo;un EBMF tel qu&rsquo;esquiss\u00e9 ici. Le poids des int\u00e9r\u00eats atlantique est encore si grand en Europe que de tels projets seront d\u00e9courag\u00e9s avant m\u00eame d&rsquo;avoir \u00e9t\u00e9 pr\u00e9cis\u00e9s. On peut quand m\u00eame penser qu&rsquo;avec le d\u00e9clin relatif du poids mondial des Etats-Unis et un regard plus constructif jet\u00e9 sur la Russie et la Chine, les opinions publics verraient d&rsquo;un bon oeil la mise en place d&rsquo;un tel Fonds \u00e9quilibrant les pouvoirs aujourd&rsquo;hui excessifs du FMI et de la Banque Mondiale.<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Jean-Paul Baquiast<\/p>\n<\/p>\n<h4>Sources<\/h4>\n<p><a href=\"http:\/\/www.dedefensa.org\/article-le_fmi_les_brics_et_l_id_al_de_puissance__17_04_2014.html\" class=\"gen\"> http:\/\/www.dedefensa.org\/article-le_fmi_les_brics_et_l_id_al_de_puissance__17_04_2014.html<\/a>.<\/p>\n<\/p>\n<p><p>\t<a href=\"http:\/\/www.zerohedge.com\/print\/487410\" class=\"gen\">http:\/\/www.zerohedge.com\/print\/487410<\/a>  (BRICS Consider Creating IMF-Alternative As US Loses Credibility.)<\/p>\n<\/p>\n<p><p>\t<a href=\"http:\/\/rbth.co.uk\/business\/2014\/04\/14\/brics_countries_to_set_up_their_own_imf_35891.html\" class=\"gen\">http:\/\/rbth.co.uk\/business\/2014\/04\/14\/brics_countries_to_set_up_their_own_imf_35891.html<\/a>.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un objectif : EuroBRICS Les pays du BRICS ont annonc\u00e9 r\u00e9cemment qu&rsquo;ils entendaient mettre en place dans les prochains mois l&rsquo;\u00e9quivalent du FMI et de la Banque mondiale dans le cadre de l&rsquo;association qu&rsquo;ils ont d\u00e9cid\u00e9 de cr\u00e9er entre eux il y a environ un an. Il s&rsquo;agit d&rsquo;abord de mobiliser des \u00e9pargnes venant directement&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[7895,11035,12178],"class_list":["post-73837","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-baquiast","tag-brics","tag-zerohedge"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73837"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73837\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}