{"id":73850,"date":"2014-04-28T05:46:00","date_gmt":"2014-04-28T05:46:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/04\/28\/les-republicains-vont-ils-perdre-leur-godfather\/"},"modified":"2014-04-28T05:46:00","modified_gmt":"2014-04-28T05:46:00","slug":"les-republicains-vont-ils-perdre-leur-godfather","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/04\/28\/les-republicains-vont-ils-perdre-leur-godfather\/","title":{"rendered":"Les r\u00e9publicains vont-ils perdre leur <em>Godfather<\/em> ?"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Les r\u00e9publicains vont-ils perdre leur <em>Godfather<\/em> ?<\/h3>\n<\/p>\n<p><p>\tIl nous est d\u00e9j\u00e0 arriv\u00e9 (voir le <a href=\"http:\/\/www.dedefensa.org\/article-eurovegas_ou_la_civilisation_du_casino_au_bordel_12_04_2012.html\" class=\"gen\">12 avril 2012<\/a>) de parler de Sheldon Adelson, milliardaire de double nationalit\u00e9, isra\u00e9lienne et am\u00e9ricaine, fervent partisan de tout ce qu&rsquo;il y a d&rsquo;extr\u00e9misme sioniste en Isra\u00ebl et soutien sonnant et tr\u00e9buchant des r\u00e9publicains \u00e0 condition qu&rsquo;ils soutiennent inconditionnellement ce qu&rsquo;il y a de plus extr\u00e9miste sioniste en Isra\u00ebl. Adelson soutient de plus en plus ouvertement et impun\u00e9ment le parti r\u00e9publicain \u00e0 ses conditions, et il a \u00e9t\u00e9 jusqu&rsquo;\u00e0 transformer la <em>Republican Jewish Coalition<\/em> qui s&rsquo;est r\u00e9uni les 27-29 mars \u00e0 Las Vegas, en une sorte de primaires o\u00f9 il aurait d\u00e9sign\u00e9 son ou ses candidats r\u00e9publicains aux pr\u00e9sidentielles, apr\u00e8s avoir entendu leur serment d&rsquo;all\u00e9geance. (Pour l&rsquo;atmosph\u00e8re de la chose, voir le Washington <em>Post<\/em> du <a href=\"http:\/\/www.washingtonpost.com\/politics\/governors-christie-walker-and-kasich-woo-adelson-at-vegas-event\/2014\/03\/29\/aa385f34-b779-11e3-b84e-897d3d12b816_story.html\" class=\"gen\">31 mars 2014<\/a>.) Les caciques et apprentis-candidats r\u00e9publicains se sont pr\u00e9cipit\u00e9s \u00e0 Vegas, sauf quelques rares oiseaux rares, tel Rand Paul. <\/p>\n<\/p>\n<p><p>\t&#8230; Vegas, bien entendu, parce que c&rsquo;est le fief d&rsquo;Adelson. Le milliardaire bienfaiteur des bonnes causes ultra-sionistes et r\u00e9publicaines est aussi le propri\u00e9taire de divers casinos, \u00e0 Vegas et \u00e0 Macao, et r\u00e9put\u00e9 comme \u00e9tant un des <em>godfathers<\/em> du crime organis\u00e9 dans le domaine des jeux, aussi bien aux USA que dans ses extensions internationales (vers la Chine, notamment). C&rsquo;est l\u00e0 que l&rsquo;histoire devient, esp\u00e9rons-le, piquante. Dans <em>PressTV.ir<\/em>, Gordon Duff, un v\u00e9t\u00e9ran du Corps des Marines et l&rsquo;un des principaux collaborateurs du site <em>Veterans Today<\/em> repr\u00e9sentant une association des v\u00e9t\u00e9rans des forces arm\u00e9es, d\u00e9veloppe une longue analyse sur la situation juridique actuelle d&rsquo;Adelson, qui fait l&rsquo;objet d&rsquo;une enqu\u00eate particuli\u00e8rement attentive du FBI. (Adelson a eu plusieurs fois d\u00e9j\u00e0 affaire \u00e0 la justice, et dans son cas qui implique le parti r\u00e9publicain, l&rsquo;administration d\u00e9mocrate ne lui fait aucun cadeau parce qu&rsquo;il est du c\u00f4t\u00e9 r\u00e9publicain, m\u00eame si cet acharnement porte sur une affaire qui, au bout du compte, discr\u00e9dite tout le Syst\u00e8me,  habituel d\u00e9rive antiSyst\u00e8me d&rsquo;un membre du Syst\u00e8me, par int\u00e9r\u00eat propre.) Duff \u00e9crit dans un article du <a href=\"http:\/\/www.presstv.ir\/detail\/2014\/04\/26\/360110\/aipac-gambling-boss-may-flee-us\/\" class=\"gen\">26 avril 2014<\/a> sur <em>PressTV.ir<\/em>, qu&rsquo;Adelson serait sur le point d&rsquo;\u00eatre inculp\u00e9 par un grand jury, selon le t\u00e9moignage d&rsquo;un de des collaborateurs actuellement sous un r\u00e9gime de garde \u00e0 vue qui s&rsquo;apparenterait plut\u00f4t \u00e0 une protection jusqu&rsquo;au t\u00e9moignage sous serment. <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Yesterday, federal officials took into custody the reputed partner of gambling boss Sheldon Adelson, the chief financial backer for the American-Israel Public Affairs Committee (AIPAC) and primary financier for America&rsquo;s GOP or Republican Party. Sources at the Department of Justice say Adelson is accused of laundering $364 million dollars, much of which went into the pockets of politicians in Washington friendly to Israel.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>If Adelson is indicted, and sources in the Justice Department say this process is well underway, politicians around the US, all Republicans, will be required to return millions in what would then be not only illegal campaign contributions but clearly proof of ties between the GOP and organized crime.<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Sources direct to the investigation tell us that a special grand jury is preparing an indictment against Adelson for a long list of offenses, including but not limited to money laundering, mail and wire fraud and conspiracy.<\/em> [&#8230;] <em>Sources in the US Department of Justice are concerned that Adelson, who has vast holdings in Macao and around the world, will flee the United States rather than face arrest. Justice officials say that Adelson&rsquo;s arrest is only a matter of time.<\/em><\/p>\n<\/p>\n<p><p>\tCes probl\u00e8mes juridiques et judiciaires d&rsquo;Adelson sont en g\u00e9n\u00e9ral soigneusement pass\u00e9s sous silence par la presse-Syst\u00e8me, qui \u00e9vite comme la peste tout ce qui peut laisser penser que l&rsquo;<em>establishment<\/em> politique washingtonien puisse \u00eatre un tant soit peu soup\u00e7onn\u00e9 de corruption ; avec Adelson, la chose prend une telle allure gargantuesque que tout doit \u00eatre fait pour dissimuler ses probl\u00e8mes, alors que ses connections corruptrices avec Washington sont elles-m\u00eames bien connues. Le <a href=\"http:\/\/mediamatters.org\/print\/blog\/2014\/03\/31\/bribery-money-laundering-and-islamaphobia-the-s\/198684\" class=\"gen\">31 mars 2014<\/a>, dans <em>MediaMatters.org<\/em>, Hannah Groch-Begley observait \u00e0 ce propos,  alors que les probl\u00e8mes judiciaires d&rsquo;Adelson, pour la phase actuelle, \u00e9taient d\u00e9j\u00e0 en cours :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The Republican Jewish Coalition met March 27-29 in Las Vegas, and the event was dubbed the Adelson Primary as GOP presidential hopefuls used the meeting to fawn over magnate Sheldon Adelson. Adelson is the chairman and CEO of Las Vegas Sands Corp., a casino and resort operating firm, who reportedly spent nearly $150 million attempting to buy the 2012 election with donations to a super PAC aligned with Mitt Romney and other outside groups (including Karl Rove&rsquo;s American Crossroads). Before switching allegiance to Romney, Adelson had donated millions to Newt Gingrich. He has also given generously in the past to super PACs associated with a variety of Republican politicians, including Scott Walker, John McCain, Rudy Giuliani, George W. Bush, and Eric Cantor.<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>\t\u00bb<em>While Republicans&rsquo; efforts to court Adelson made big news in print media over the past week, none of the articles mentioning Adelson in The New York Times, Washington Post, Politico, or The Wall Street Journal mentioned that he has come under investigation for illegal business practices, including bribery, or his history of extreme remarks. A search of the Nexis and Factiva databases from March 24 to March 31 turned up several articles in the papers \u00admentioning the billionaire, none of which mentioned Adelson&rsquo;s checkered past. The New York Times called Adelson one of the Republican Party&rsquo;s most coveted and fearsome moneymen and detailed his current fight against online gambling, while The Washington Post&rsquo;s March 25 preview of the event simply reported that Adelson was driven by what he has said he sees as Obama&rsquo;s socialist agenda. He is a fierce opponent of organized labor and is currently embroiled in a fight to ban online gambling.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCette affaire avec ses diverses ramifications, cela sans pr\u00e9juger d&rsquo;une \u00e9ventuelle inculpation d&rsquo;Adelson, met en lumi\u00e8re les extraordinaires ramifications existantes entre le crime organis\u00e9 aussi bien que quelques milliardaires des milieux extr\u00e9mistes, et la direction politique washingtonienne. (Certes, la m\u00eame situation existe du c\u00f4t\u00e9 d\u00e9mocrate, selon d&rsquo;autres fili\u00e8res, notamment Wall Street, qui entretient dans certaines de ses filiales des organisations qu&rsquo;on peut effectivement qualifier de crime organis\u00e9.) Les habituels sceptiques diront tout le monde le sait, et ils auront tort, comme d&rsquo;habitude. Une telle possible exposition, avec de possibles inculpations ou la fuite de l&rsquo;un ou l&rsquo;autre (Adelson) des USA, de ce que tout le monde sait d\u00e9passe d&rsquo;une fa\u00e7on d\u00e9cisive en impact psychologique et intellectuel le savoir non substantiv\u00e9 de la chose. Le spectacle qui se forme peu \u00e0 peu est bien, dans ce cas mais sans oublier que le parti d\u00e9mocrate rec\u00e8le d&rsquo;autres cas du m\u00eame type, la situation d&rsquo;un parti politique, et de l&rsquo;une des deux branches du parti unique, compl\u00e8tement \u00e0 la solde d&rsquo;un homme, d&rsquo;une fortune, d&rsquo;une orientation politique,  mais surtout, finalement, compl\u00e8tement \u00e0 la solde du crime organis\u00e9 en tant que tel et sans r\u00e9el interm\u00e9diaire pour att\u00e9nuer l&rsquo;infamie. Il s&rsquo;agit du degr\u00e9 absolu, non seulement de la corruption, mais en plus de l&rsquo;inversion totale de toutes les valeurs dont ce monde politique est comptable. Gordon Duff fait cette hypoth\u00e8se, dans le cas o\u00f9 effectivement Adelson arriverait \u00e0 concr\u00e9tiser son achat du parti r\u00e9publicain et de ses candidats pour les pr\u00e9sidentielles ; il s&rsquo;agit d&rsquo;une hypoth\u00e8se d\u00e9structurante fondamentale des USA, qui fait l&rsquo;hypoth\u00e8se que certaines entit\u00e9s r\u00e9gionales US, au niveau des \u00c9tats ou groupes d&rsquo;\u00c9tats de l&rsquo;Union, ne pourraient accepter une telle corruption affich\u00e9e, revenant \u00e0 l&rsquo;acquisition pure et simple par le crime organis\u00e9 et l&rsquo;extr\u00e9misme de l&rsquo;appareil politique US, et s&rsquo;orienterait vers un \u00e9tat de s\u00e9cession :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Critical is Adelson&rsquo;s virtual control of America&rsquo;s pro-Israel Republican Party. The GOP had hopes of using Adelson cash to gain control of the United States Senate. Analysts predict that were this to happen, America would not only move toward domestic collapse but there is a real possibility that<\/em> <strong><em>regions of the US would seek to withdraw from the union, seeking an autonomous zone.<\/em><\/strong>\u00bb<\/p>\n<\/p>\n<p><p>\tD&rsquo;autre part, si les sources de Duff sont bonnes et si, effectivement, Adelson est inculp\u00e9 ou qu&rsquo;il doit fuir, par cons\u00e9quent si le parti r\u00e9publicain devait rembourser les sommes importantes qu&rsquo;il a re\u00e7ues (plusieurs centaines de $millions), ce parti se trouverait dans un \u00e9tat de banqueroute qui bouleverserait compl\u00e8tement la situation \u00e9lectorale. Dans ce cas, on se trouverait dans une situation politique compl\u00e8tement in\u00e9dite, avec la porte ouverte \u00e0 des mouvements et des candidats populistes. On peut m\u00eame avancer que la remarque de Duff sur la coh\u00e9sion interne US vaudrait \u00e9galement dans ce cas&#8230; <\/p>\n<\/p>\n<p><p>\tLes r\u00e9v\u00e9lations et les mises \u00e0 jour des aspects divers, coutumiers et structurels, de la situation de la politique aux USA,  particuli\u00e8rement aux USA o\u00f9 aucune r\u00e8gle r\u00e9galienne ne pr\u00e9vaut,  contribuent \u00e0 sans cesse fragiliser le Syst\u00e8me exactement comme les pouss\u00e9es successives d&rsquo;une mar\u00e9e en progression minent un ch\u00e2teau de sable. Avec des r\u00e9v\u00e9lations et des mises \u00e0 jour d&rsquo;une telle puissance, la pouss\u00e9e de la mar\u00e9e est proche d&rsquo;\u00eatre irr\u00e9sistible. Il est impossible de ne pas conclure qu&rsquo;\u00e0 un moment ou l&rsquo;autre, le ch\u00e2teau c\u00e9dera.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 28 avril 2014 \u00e0 05H39<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les r\u00e9publicains vont-ils perdre leur Godfather ? Il nous est d\u00e9j\u00e0 arriv\u00e9 (voir le 12 avril 2012) de parler de Sheldon Adelson, milliardaire de double nationalit\u00e9, isra\u00e9lienne et am\u00e9ricaine, fervent partisan de tout ce qu&rsquo;il y a d&rsquo;extr\u00e9misme sioniste en Isra\u00ebl et soutien sonnant et tr\u00e9buchant des r\u00e9publicains \u00e0 condition qu&rsquo;ils soutiennent inconditionnellement ce qu&rsquo;il&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[11800,15771,3858,8039,3578,2838,5147,15772,2774,7719,5238,15769,8040,15768,15770,5239],"class_list":["post-73850","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-adelson","tag-casinos","tag-corruption","tag-crime","tag-duff","tag-fbi","tag-gordon","tag-inculpation","tag-israel","tag-jeux","tag-las","tag-macao","tag-organise","tag-parrain","tag-ultra-sioniste","tag-vegas"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73850"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73850\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}