{"id":73869,"date":"2014-05-10T08:19:39","date_gmt":"2014-05-10T08:19:39","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2014\/05\/10\/le-desarroi-a-la-derive-du-bloc-bao\/"},"modified":"2014-05-10T08:19:39","modified_gmt":"2014-05-10T08:19:39","slug":"le-desarroi-a-la-derive-du-bloc-bao","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2014\/05\/10\/le-desarroi-a-la-derive-du-bloc-bao\/","title":{"rendered":"Le d\u00e9sarroi \u00e0 la d\u00e9rive du bloc BAO"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Le d\u00e9sarroi \u00e0 la d\u00e9rive du bloc BAO<\/h2>\n<\/p>\n<p><p>A quoi sert le gambit de Poutine (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-poutine_tactical_retreat_ou_gambit_08_05_2014.html\">8 mai 2014<\/a>) ? Sans doute Poutine l&rsquo;ignore-t-il lui-m\u00eame, sinon, &ndash; et c&rsquo;est l&rsquo;essentiel pour lui, &ndash;comme un mouvement tactique dont l&rsquo;effet est d&rsquo;accroitre l&rsquo;\u00e9tat de la politique du bloc BAO dans la crise ukrainienne ; c&rsquo;est-\u00e0-dire, comme on le sugg\u00e8re plus haut, d\u00e9sordre, \u00ab\u00a0d\u00e9sarroi \u00e0 la d\u00e9rive\u00a0\u00bb (ce qui est le comble du d\u00e9sarroi), absence compl\u00e8te de direction y compris et surtout \u00e0 Washington o&ugrave; l&rsquo;inspiration de la \u00ab\u00a0politique\u00a0\u00bb semble comme une sorte de yo-yo allant du bastion <em>neocon<\/em> qu&rsquo;est devenu le d\u00e9partement d&rsquo;&Eacute;tat \u00e0 divers autres centres de pouvoir improvisant au jour le jour. L\u00e0-dessus, la coh\u00e9sion entre comp\u00e8res du bloc BAO, et notamment entre certains Europ\u00e9ens et les plus durs du bloc, est plus que jamais en lambeaux, &ndash; et, sur ces points divers, effectivement, le \u00ab\u00a0gambit-Poutine\u00a0\u00bb a eu son effet avec une telle efficacit\u00e9 qu&rsquo;il devrait prendre sa place dans la grande nomenclature des \u00e9checs comme un coup sp\u00e9cifique&#8230; Et il ne vaut, certes, que gr\u00e2ce \u00e0 l&rsquo;aimable coop\u00e9ration du comportement catastrophique de ses \u00ab\u00a0partenaires\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Avant de d\u00e9tailler cette situation extraordinaire o&ugrave; le bloc BAO est devenu lui-m\u00eame un monde clos o&ugrave; le d\u00e9sordre tourbillonne sans piti\u00e9, un rapide coup d&rsquo;&oelig;il sur la situation en Ukraine. Le spectacle n&rsquo;y est pas plus rassurant, dans tous les cas pour ceux qui croient encore avec une ferveur d\u00e9clinante qu&rsquo;il y a dans tout cela un plan arr\u00eat\u00e9, une ligne de conduite, un projet structur\u00e9. Le <em>blog<\/em> d\u00e9sormais c\u00e9l\u00e8bre et dont on conna&icirc;t l&rsquo;engagement fervent dans cette crise et aussi la bonne base d&rsquo;information dont il dispose, <em>The Vineyard of the Saker<\/em>, d\u00e9crit, ce <a class=\"gen\" href=\"http:\/\/vineyardsaker.blogspot.be\/2014\/05\/the-ukrainian-banderastan-as-ugly-as-it.html\">9 mai 2014<\/a> l&rsquo;extraordinaire incomp\u00e9tence de la ni\u00e8me \u00ab\u00a0offensive\u00a0\u00bb lanc\u00e9e par le pseudo-pouvoir \u00e0 Kiev. Le d\u00e9sordre est grand dans l&rsquo;Ukraine russophone, mais l&rsquo;intervention de Kiev pour \u00ab\u00a0r\u00e9tablir l&rsquo;ordre\u00a0\u00bb semble devoir ajouter une dimension encore plus exceptionnelle \u00e0 cet \u00e9tat des choses, comme s&rsquo;il y avait une course \u00e0 la perfection du d\u00e9sordre. (M\u00eame le r\u00e9f\u00e9rendum attendu pour demain est trait\u00e9 presque accessoirement, comme un \u00e9l\u00e9ment du d\u00e9sordre parmi d&rsquo;autres, alors que la chose devrait \u00eatre un enjeu capital. Elle l&rsquo;est, en fait, mais entre dans un ensemble o&ugrave; tout est enjeu capital et o&ugrave; plus rien ne se distingue vraiment comme plus capital qu&rsquo;autre chose &#8230; C&rsquo;est l&rsquo;entropisation du d\u00e9sordre, si l&rsquo;on veut)<\/p>\n<\/p>\n<p><p>&laquo;<em>It would be wrong to compare these Ukie thugs to the SS, as some have done. For all their wrongs, the Waffen-SS fought well, and not only against defenseless civilians, but also in real combat. But these Ukie \u00ab\u00a0special units\u00a0\u00bb still have not managed in taking over Slaviansk or Kramatorsk! Yes, there even was a Victory Day parade in Slaviansk were Pavel Gubarev, the \u00ab\u00a0people-elected governor\u00a0\u00bb of the Donetsk region spoke at an official rally. Same thing in Kramatorsk where a Victory Day celebration also took place. Amazing, no? We are, by Kiev&rsquo;s official count, already in the second phase of the second anti-terrorist operation and the \u00ab\u00a0special\u00a0\u00bb forces have yet to capture a single town!<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo;<em>Several times I have referred to this regime as a \u00ab\u00a0freak show\u00a0\u00bb and I did not mean that as an insult, but as a statement of fact. The folks which have seized power in Kiev are quite literally freaks and so far, they have not succeeded in doing anything at all. Nothing.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>I am beginning to suspect that they might even fail in disrupting the upcoming referendum scheduled for Sunday. Frankly, I had &ndash; and still have &ndash; major doubts about the ability of the pro-Russian forces in the Donbass to organized such a referendum on such short notice and in the midst of a small but ugly mini-civil war, but then when I look at the freaks in Kiev and their \u00ab\u00a0scorecard\u00a0\u00bb so far I have even bigger doubts about their ability to disrupt the upcoming referendum, nevermind preventing it from taking place&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<p><p>&bull; C&rsquo;est donc dans ce climat que la \u00ab\u00a0diplomatie\u00a0\u00bb du bloc BAO continue \u00e0 d\u00e9ployer ses charmes divers, son incoh\u00e9rence, sa fragmentation extraordinaire, son d\u00e9sint\u00e9r\u00eat presque religieux pour la v\u00e9rit\u00e9 de la situation. Comme on l&rsquo;a dit, le d\u00e9partement d&rsquo;&Eacute;tat est, \u00e0 cet \u00e9gard, un bastion de la couleur de ces temps \u00e9tranges. Nous sommes marris mais malheureusement contraints de reconna&icirc;tre que le \u00ab\u00a0genre f\u00e9minin\u00a0\u00bb domine, sinon monopolise l&rsquo;action \u00e0 cet \u00e9gard, &ndash; en prenant, pour notre cas et notre attention vertueuse aux susceptibilit\u00e9s diverses, la pr\u00e9caution de n&rsquo;en tirer aucune conclusion. Une nouvelle vedette \u00e0 cet \u00e9gard, \u00e0 ajouter aux Nuland, Power, Rice, etc., c&rsquo;est Jen Psaki, la porte-parole, qui r\u00e9pond \u00e0 toutes les questions sur les violences en Ukraine russophone, &ndash; y compris le mauvais temps \u00e9ventuel : \u00ab\u00a0c&rsquo;est la faute aux Russes\u00a0\u00bb (voir <em>Russia Today<\/em>, le <a class=\"gen\" href=\"http:\/\/rt.com\/news\/157992-mariupol-violence-us-osce\/\">9 mai 2014<\/a>). Psaki semble justifier le jugement que donnait d&rsquo;elle Nikolai Boubkine, le <a class=\"gen\" href=\"http:\/\/www.strategic-culture.org\/news\/2014\/04\/18\/the-aggressive-feminine-face-of-us-diplomacy.html\">18 avril 2014<\/a> sur <em>Strategic-culture.org<\/em>, proposant l&rsquo;hypoth\u00e8se que m\u00eame la porte-parole a sa propre politique au d\u00e9partement d&rsquo;&Eacute;tat&#8230;<\/p>\n<\/p>\n<p><p>&laquo;<em>The fact that the tone in the anti-Russian campaign is being set by American women bureaucrats does not reduce the responsibility of the U.S. leadership. For example, U.S. State Department spokeswoman Jen Psaki cannot be considered a political figure; her job is merely to make public the official position of the foreign policy agency. However, she takes the liberty of drawing personal inferences and conclusions which, like Samantha Power&rsquo;s behavior in the UN, are simply shocking. The official State Department representative does not bother with proof. Psaki&rsquo;s answers to journalists&rsquo; questions sometimes cause indignation. Female logic is no excuse in this case. If spokeswoman Psaki shapes U.S. foreign policy, then what is Secretary of State John Kerry there for? After all, she often contradicts his statements, making her boss a laughing stock&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<p><p>&bull; Et c&rsquo;est donc vers le <em>Guardian<\/em> qu&rsquo;il faut orienter sa lecture pour pouvoir mieux et plus s\u00e9rieusement appr\u00e9cier l&rsquo;\u00e9tat des lieux et des esprits au c&oelig;ur du bloc BAO, face \u00e0 la situation ukrainienne. Le <em>Guardian<\/em> est f\u00e9rocement anti-Poutine mais, au moins, il admet qu&rsquo;il faut parfois tenir compte de la v\u00e9rit\u00e9 de la situation plut\u00f4t que le \u00ab\u00a0c&rsquo;est la faute des Russes\u00a0\u00bb de la Psaki. Tout tourne autour du \u00ab\u00a0gambit-Poutine\u00a0\u00bb, dont les commentateurs ne peuvent qu&rsquo;admettre qu&rsquo;il a pris compl\u00e8tement \u00e0 contrepied les pays du bloc BAO, ancr\u00e9s dans leur vision extr\u00e9miste et caricaturale du pr\u00e9sident russe, et que ces pays ne savent quoi en faire d&rsquo;une fa\u00e7on coordonn\u00e9e alors qu&rsquo;on constate dans leurs rangs des disparit\u00e9s et des d\u00e9sordres grandissants. Le commentaire de Ian Trainor, absolument antirusse et anti-Poutine selon la ligne du journal (notez le \u00ab\u00a0Poutine gagne toutes les batailles mais cela ne signifie pas qu&rsquo;il gagnera la guerre\u00a0\u00bb, &ndash; car il y a une justice divine, certes), ce commentaire du <a class=\"gen\" href=\"http:\/\/www.theguardian.com\/world\/2014\/may\/08\/ukraine-crisis-vladimir-putin-caught-west-napping\">9 mai 2014<\/a> est d&rsquo;autant plus significatif pour appr\u00e9cier l&rsquo;\u00e9tat d&rsquo;esprit dont nous parlons.<\/p>\n<\/p>\n<p><p>&laquo;<em>Vladimir Putin acts, and the west (sometimes) reacts. That has been the pattern of the Ukraine crisis since it erupted into an open contest between Russia and the west last November. At every stage, whether through poor intelligence, policy shambles or divisions in Europe and with America, the west has been caught napping, while the Kremlin called the shots. Putin has been winning all the battles, although it does not necessarily mean he will win the war&#8230;<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo;<em> He has made himself indispensable to any settlement&#8230; <\/em> [&#8230;] <em>For western would-be mediators, Putin is the one to go to. But who does Putin go to? Is it Angela Merkel or Barack Obama? Or perhaps Catherine Ashton? Or John Kerry or William Hague or Herman Van Rompuy? Putin&rsquo;s central control contrasts with western fragmentation, incoherence, and equivocation. \u00ab\u00a0Putin is continuing to pursue the strategy of indirect, proxy destabilisation in order to achieve his goals. This latest apparent feint appears at best a tactic to diminish the costs of pursuing this strategy,\u00a0\u00bb said the Eurasia Group on Thursday&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<p><p>&bull; Orlando Figes, toujours dans le <em>Guardian<\/em> (le <a class=\"gen\" href=\"http:\/\/www.theguardian.com\/commentisfree\/2014\/may\/09\/ukraine-putin-west-sanctions-russia\">9 mai 2014<\/a>) examine la position de la Russie face au bloc BAO et n&rsquo;y trouve que des situations o&ugrave; la Russie a la main, et o&ugrave; le bloc BAO ne peut que suivre p\u00e9niblement, certainement en n&rsquo;y comprenant pas grand&rsquo;chose (sauf le d\u00e9partement d&rsquo;&Eacute;tat bien s&ucirc;r, et, il est temps de le mentionner, l&rsquo;essentiel de la presse-Syst\u00e8me US qui suit aveugl\u00e9ment la <em>narrative<\/em> qu&rsquo;elle y entend, que ce soit la version-Kerry ou la version-Psaki). Aussi, le commentaire de Figes est-il parfaitement r\u00e9sum\u00e9 par son titre et son sous-titre, du type \u00ab\u00a0Poutine fait des cercles autour de l&rsquo;Ouest\u00a0\u00bb, <em>running the show<\/em> comme l&rsquo;on dit (&laquo;<em>In Ukraine, Putin is running rings around the west &ndash; Sanctions only boost the Russian leader&rsquo;s popularity at home. There is little the west can do &ndash; apart from talk<\/em>&raquo;). Cela rejoint le fond de l&rsquo;\u00e9ditorial du <em>Guardian<\/em> (le <a class=\"gen\" href=\"http:\/\/www.theguardian.com\/commentisfree\/2014\/may\/08\/ukraine-putin-new-line-editorial\">9 mai 2014<\/a>), qui entend tout de m\u00eame \u00eatre optimiste et redonner un peu de couleur \u00e0 la civilisation du bloc BAO, &ndash; et qui est conduit, pour cela, \u00e0 la conclusion paradoxale que, oui, le \u00ab\u00a0gambit-Poutine\u00a0\u00bb doit \u00eatre pris au s\u00e9rieux, que le pr\u00e9sident russe pourrait peut-\u00eatre nous r\u00e9server quelque surprise aimable, avec une solution-miracle qui permettrait au bloc BAO de <em>remake<\/em> du sauvetage <em>in extremis<\/em> d&rsquo;Obama par le m\u00eame Poutine en septembre 2014, dans l&rsquo;imbroglio syrien qui a tant de similitudes avec l&rsquo;ukrainien sur la mani\u00e8re d&rsquo;\u00eatre du bloc BAO&#8230;<\/p>\n<\/p>\n<p><p>&laquo;<em>Mr Putin&rsquo;s aims may well be the same as they were. What has shifted is the understanding, on both sides, of relative weakness and strength. It has become even clearer that Mr Putin does not want to invade or to annex eastern Ukraine. Nor does he want to be in a position where he has to reject calls for military help. Equally, we see Kiev has weak support in parts of the east, and its security forces are inadequate or estranged. People are confused and frightened, many trusting, it can be speculated, neither Kiev nor Moscow. Time, then, for a cautious but at the same time speedy exploration of the Kremlin&rsquo;s new line.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Poutine est-il un strat\u00e8ge de grande envergure doubl\u00e9 d&rsquo;un tacticien de g\u00e9nie? On verra plus tard pour le jugement d\u00e9finitif, car ce n&rsquo;est pas la question la plus urgente. L&rsquo;essentiel pour l&rsquo;imm\u00e9diat dans cette bouillie pour les chats n&rsquo;est pas la politique russe, ni la position de la Russie, ni les initiatives de la Russie, ni la pens\u00e9e profonde de la Russie, &ndash; bien qu&rsquo;il ne faille certainement pas n\u00e9gliger d&rsquo;en parler avec attention et profondeur, comme nous le faisons r\u00e9guli\u00e8rement (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-destin_e_russe_06_05_2014.html\">6 mai 2014<\/a>). L&rsquo;essentiel dans cet expos\u00e9 succinct d&rsquo;une situation pr\u00e9sente, c&rsquo;est l&rsquo;extraordinaire, l&rsquo;incroyable, l&rsquo;indescriptible <strong>inexistence politique du bloc BAO et de tout ce qui en \u00e9mane<\/strong>, y compris les clowns de Kiev inspir\u00e9s par le FMI et leurs diverses offensives finales contre les \u00ab\u00a0terroristes\u00a0\u00bb russophones. C&rsquo;est l\u00e0 le grand, le tr\u00e8s grand \u00e9v\u00e9nement que l&rsquo;on sentait et pressentait, que l&rsquo;on d\u00e9crivait partiellement de commentaire en commentaire, qui appara&icirc;t de plus en plus dans son exceptionnelle unicit\u00e9, presque dans une sorte de perfection transcendantale&#8230; Nous voulons dire par l\u00e0 que l&rsquo;inexistence, le nihilisme, la fragmentation jusqu&rsquo;\u00e0 une sorte de poussi\u00e8re informe et inf\u00e2me qu&rsquo;est cette \u00ab\u00a0politique\u00a0\u00bb-l\u00e0 si parfaitement robotis\u00e9e semblent indiquer que la chose est effectivement impos\u00e9e au bloc BAO du dehors de lui. Le bloc ne peut faire autre chose que ce qu&rsquo;il fait, c&rsquo;est-\u00e0-dire une sorte de \u00ab\u00a0rien\u00a0\u00bb tonitruant et hyst\u00e9rique qui arrive pourtant \u00e0 accoucher des effets sans nombre, lesquels sont \u00e9videmment d&rsquo;une n\u00e9gativit\u00e9 quasi-parfaite, on s&rsquo;en doute. Ne vous \u00e9tonnez pas et ne nous \u00e9tonnons pas si nous nous r\u00e9f\u00e9rons in\u00e9vitablement et aussit\u00f4t au Syst\u00e8me et \u00e0 sa politique-Syst\u00e8me. Le bloc Bao, chariots form\u00e9s en cercle autour duquel Poutine galope en lan\u00e7ant ses fl\u00e8ches l\u00e0 o&ugrave; il choisit de le faire, est emmen\u00e9 dans une ronde infernale par des forces qui le d\u00e9passent, le manipulent, et dont il est le prisonnier \u00e9bahi, parfois d\u00e9sagr\u00e9ablement pr\u00e9occup\u00e9 comme l&rsquo;est le <em>Guardian<\/em>, parfois allum\u00e9 et parfaitement satisfait de l&rsquo;aide du Ciel comme peut l&rsquo;\u00eatre un <em>neocon<\/em>-standard du d\u00e9partement d&rsquo;&Eacute;tat.<\/p>\n<\/p>\n<p><p>Car enfin, il se pourrait bien que nous nous dirigions vers la voie tant attendue, ce moment o&ugrave; il commencera \u00e0 s&rsquo;av\u00e9rer irr\u00e9sistiblement que la crise ukrainienne est en train de se transmuter en crise du bloc BAO, c&rsquo;est-\u00e0-dire s&rsquo;ins\u00e9rant avec toute sa dynamique de surpuissance dans la s\u00e9quence en cours de la crise g\u00e9n\u00e9rale en lui donnant l&rsquo;\u00e9lan qui importe pour qu&rsquo;elle s&rsquo;inscrive d\u00e9cisivement dans la crise d&rsquo;effondrement du Syst\u00e8me. C&rsquo;est ce moment-l\u00e0 qu&rsquo;il faut guetter pour \u00eatre pr\u00eat \u00e0 l&rsquo;identifier sans h\u00e9sitation, lorsqu&rsquo;il se manifestera. Vraiment la voie lui est ouverte, et l&rsquo;\u00e9quation surpuissance-autodestruction en pleine activit\u00e9.<\/p>\n<\/p>\n<p><p>Mis en ligne le 10 mai 2014 \u00e0 08H07<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le d\u00e9sarroi \u00e0 la d\u00e9rive du bloc BAO A quoi sert le gambit de Poutine (voir le 8 mai 2014) ? Sans doute Poutine l&rsquo;ignore-t-il lui-m\u00eame, sinon, &ndash; et c&rsquo;est l&rsquo;essentiel pour lui, &ndash;comme un mouvement tactique dont l&rsquo;effet est d&rsquo;accroitre l&rsquo;\u00e9tat de la politique du bloc BAO dans la crise ukrainienne ; c&rsquo;est-\u00e0-dire, comme&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4270,3889,3888,15793,3659,855,2797,5520,916,15794,1225,12664,11131,6418],"class_list":["post-73869","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-autodestruction","tag-detat","tag-departement","tag-figes","tag-guardian","tag-kerry","tag-kiev","tag-nuland","tag-poutine","tag-psaki","tag-referendum","tag-saker","tag-surpuissance","tag-traynor"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73869"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73869\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}