{"id":73910,"date":"2011-07-19T09:02:39","date_gmt":"2011-07-19T09:02:39","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/07\/19\/de-lincontrolabilite-des-choses-la-crise-murdoch\/"},"modified":"2011-07-19T09:02:39","modified_gmt":"2011-07-19T09:02:39","slug":"de-lincontrolabilite-des-choses-la-crise-murdoch","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/07\/19\/de-lincontrolabilite-des-choses-la-crise-murdoch\/","title":{"rendered":"De l&rsquo;incontr\u00f4labilit\u00e9 des choses (la crise Murdoch)"},"content":{"rendered":"<p><p>Dans la crise Murdoch, c&rsquo;est le <strong>rythme<\/strong> qui domine tout, rythme des \u00e9v\u00e9nements, rythme des r\u00e9v\u00e9lations, rythme des mesures n\u00e9cessairement prises (d\u00e9missions, arrestations, enqu\u00eates, etc.),  le rythme \u00e0 laquelle la pi\u00e8ce se d\u00e9tricote. La constat est celui d&rsquo;une absence compl\u00e8te de contr\u00f4le des \u00e9v\u00e9nements, le ph\u00e9nom\u00e8ne illustre une immense dynamique d&rsquo;incontr\u00f4labilit\u00e9, la perspective est la poursuite d&rsquo;une marche forc\u00e9e dans une sorte de <em>terra incognita<\/em> qui englobe l&rsquo;ensemble divers et puissant du pouvoir anglo-am\u00e9ricaniste, ou de l&rsquo;anglosph\u00e8re.<\/p>\n<\/p>\n<p><p>\t Au niveau du groupe Murdoch, les d\u00e9missions et arrestations se multiplient, touchant d\u00e9sormais les structures de direction du groupe lui-m\u00eame, avec la d\u00e9mission et l&rsquo;arrestation de Rebekah Brooks, l&rsquo;extr\u00eame menace qui p\u00e8se sur James Murdoch (pr\u00e9sident de News International UK, plac\u00e9 juste au-dessus de Brooks), <a href=\"http:\/\/www.guardian.co.uk\/media\/2011\/jul\/18\/phone-hacking-murdochs-brooks-mps\" class=\"gen\">les auditions<\/a> aux Communes (aujourd&rsquo;hui) de Brooks et de <a href=\"http:\/\/www.independent.co.uk\/news\/uk\/crime\/murdochs-in-the-dock-2315871.html\" class=\"gen\">Rupert Murdoch<\/a> (ce dernier, par t\u00e9l\u00e9conf\u00e9rence). On y ajoutera de nouveaux \u00e9l\u00e9ments autour de ce foyer central, qui rel\u00e8vent \u00e0 la fois du fait divers et du soup\u00e7on de la criminalit\u00e9 au plus haut niveau ; avec la d\u00e9couverte, signal\u00e9e en premier par le <em>Guardian<\/em> (le <a href=\"http:\/\/www.guardian.co.uk\/media\/2011\/jul\/18\/mystery-bag-bin-rebekah-brooks\" class=\"gen\">18 juillet 2011<\/a>), d&rsquo;un sac contenant un ordinateur, des documents et un t\u00e9l\u00e9phone qui appartiendraient \u00e0 Rebekah Brooks, dans la voiture du mari de Rebekah ; avec <a href=\"http:\/\/www.telegraph.co.uk\/news\/uknews\/phone-hacking\/8646415\/Phone-hacking-Sean-Hoare-the-News-of-the-World-whistleblower-found-dead.html\" class=\"gen\">la mort<\/a>, dans son appartement, de Sam Hoare, le journaliste de <em>News of the World<\/em> qui a contribu\u00e9 d\u00e9cisivement \u00e0 r\u00e9v\u00e9ler l&rsquo;\u00e9tendue du scandale des \u00e9coutes, et une mort que la police n&rsquo;explique pas mais ne juge pas suspecte.<\/p>\n<\/p>\n<p><p>\t Au niveau des institutions britanniques, alors qu&rsquo;on voit s&rsquo;accumuler les arrestations et que l&rsquo;enqu\u00eate de la police est contrainte de prendre un tour extr\u00eamement agressif, cette m\u00eame police (Scotland Yard), sous le coup d&rsquo;accusations massives de corruption, est d\u00e9capit\u00e9e avec la d\u00e9mission de son chef et de l&rsquo;adjoint de ce dernier (Sir Paul Stephenson et John Yates), et que d&rsquo;autres hauts dirigeants du m\u00eame Scotland Yard sont sur la corde raide (accusations de corruption, bruits de d\u00e9mission). C&rsquo;est donc, comme l&rsquo;observe <em>The Independent<\/em> de ce <a href=\"http:\/\/www.independent.co.uk\/news\/uk\/crime\/chaos-at-the-yard-as-yates-resigns-and-more-officers-face-allegations-2315874.html\" class=\"gen\">19 juillet 2011<\/a>, le chaos \u00e0 Scotland Yard alors que Scotland Yard est ce m\u00eame organisme qui est <strong>dans l&rsquo;obligation<\/strong>, sous la surveillance du syst\u00e8me de la communication (pression m\u00e9diatique, fureur d\u00e9fensive du monde politique, fureur tout court,  suppos\u00e9e et dans tous les cas affirm\u00e9e,  de l&rsquo;opinion publique), de mener cette enqu\u00eate agressive dont nous parlons plus haut. Quant \u00e0 l&rsquo;ex\u00e9cutif en charge th\u00e9orique de la conduite des affaires (David Cameron le Premier ministre), il suit comme il peut, le souffle court, avec un Cameron largement compromis par ses liens avec Rebekah Brooks rentrant d&rsquo;urgence d&rsquo;une tourn\u00e9e en Afrique et mobilisant le Parlement pour un jour de plus pris sur ses vacances, pour que lui, Cameron, puisse faire une d\u00e9claration. (Extr\u00eame caract\u00e8re incontr\u00f4lable de la situation : d&rsquo;habitude, les premiers ministres dans cette situation sont particuli\u00e8rement satisfaits de voir le Parlement partir en vacances ; Cameron, lui, le retient, comme s&rsquo;il voulait s&rsquo;accrocher \u00e0 une structure stable, lui f\u00fbt-elle hostile, dans cet emportement g\u00e9n\u00e9ral d&rsquo;incontr\u00f4labilit\u00e9.) <\/p>\n<\/p>\n<p><p>\t D&rsquo;o\u00f9 cette question assez simple et sympathique : qui dirige le pays ? Question pos\u00e9e par Dominic Lawson, de <em>The Independent<\/em> (le <a href=\"http:\/\/www.independent.co.uk\/opinion\/commentators\/dominic-lawson\/dominic-lawson-who-runs-the-country-not-murdoch-2315937.html\" class=\"gen\">19 juillet 2011<\/a>). Lawson r\u00e9pond que ce n&rsquo;est certainement pas (plus) Rupert Murdoch, mais que ce pourrait \u00eatre, par exemple, l&rsquo;acteur Hugh Grant ; lequel Grant a pris avec autorit\u00e9 et alacrit\u00e9 la t\u00eate de la croisade des victimes des \u00e9coutes, et qui, d\u00e9sormais, fait des d\u00e9clarations extr\u00eamement dures sur la situation politique du pays (\u00ab<em>She<\/em> [Brooks] <em>was best chums with the Prime Minister  this Prime Minister, the previous Prime Minister  and was virtually running the country<\/em>\u00bb).<\/p>\n<\/p>\n<p><p>\t Aux Etats-Unis, autre territoire o\u00f9 des parties non n\u00e9gligeables du syst\u00e8me de communication sont administr\u00e9es, d&rsquo;une fa\u00e7on un peu diff\u00e9rente qu&rsquo;au Royaume-Uni, par Murdoch, l\u00e0 aussi c&rsquo;est la situation de l&rsquo;incontr\u00f4labilit\u00e9 des choses. (Voir une bonne nomenclature de la pr\u00e9sence et de l&rsquo;influence de Murdoch aux USA, par John Nichols de <em>The Nation<\/em>, repris par <em>CommonDreams.org<\/em>, le <a href=\"http:\/\/www.commondreams.org\/view\/2011\/07\/17-2\" class=\"gen\">17 juillet 2011<\/a>.) Il y a eu des flottements dans l&rsquo;attitude officielle, avec des tensions diverses entre d\u00e9mocrates et r\u00e9publicains (d\u00e9mocrates plut\u00f4t inclin\u00e9s \u00e0 exploiter le scandale au niveau politique, \u00e0 cause des liens suppos\u00e9s exclusifs entre Murdoch et les r\u00e9publicains, ces m\u00eames r\u00e9publicains tirant plut\u00f4t dans l&rsquo;autre sens). Mais il n&rsquo;est pas certain pour autant que l&rsquo;administration,  du moins ceux qui, dans l&rsquo;administration, restent disponibles pour quelque int\u00e9r\u00eat pour cette affaire, n&rsquo;\u00e9tant pas absolument obnubil\u00e9s par le d\u00e9bat sur la dette,  tenait \u00e0 en faire un cas juridique officiel, avec les possibilit\u00e9s d&rsquo;accroissement suppl\u00e9mentaire de ce caract\u00e8re d&rsquo;incontr\u00f4labilit\u00e9. Quoi qu&rsquo;il en soit, le rythme des choses en a d\u00e9cid\u00e9 autrement, et le DoJ (minist\u00e8re de la justice) s&rsquo;est inclin\u00e9 et a ouvert une enqu\u00eate sur l&rsquo;affaire (le <em>Guardian<\/em> du <a href=\"http:\/\/www.guardian.co.uk\/media\/2011\/jul\/18\/news-corp-global-investigation-bribery\" class=\"gen\">18 juillet 2011<\/a>). Cette enqu\u00eate, qui r\u00e9pond \u00e0 la loi <em>Foreign Corrupt Practices Act<\/em> (FCPA), doit \u00eatre massive et globale, le FCPA faisant obligation au DoJ \u00e0 mener une enqu\u00eate sur toutes les ramifications nationales et internationales d&rsquo;une entit\u00e9 priv\u00e9e, d\u00e8s lors que cette entit\u00e9 poss\u00e8de une structure am\u00e9ricaniste officielle (cas du groupe Murdoch). L&rsquo;enqu\u00eate du DoJ n&rsquo;a donc th\u00e9oriquement aucune limitation g\u00e9ographique et factuelle, d\u00e8s lors qu&rsquo;elle passe par cette entit\u00e9 (la branche am\u00e9ricaniste de Murdoch) qui est sous sa juridiction, avec le moyen de pression du maintien ou de la suppression des licences permettant \u00e0 cette unit\u00e9 de fonctionner aux USA.<\/p>\n<\/p>\n<p><p>\t Aux USA m\u00eame, les publications du groupe Murdoch ne sont pas vraiment \u00e0 la f\u00eate. Les plus int\u00e9ressantes r\u00e9actions viennent du Wall Street <em>Journal<\/em> (WSJ), qui publie un \u00e9ditorial le <a href=\"http:\/\/online.wsj.com\/article\/SB10001424052702303661904576451812776293184.html?mod=djkeyword#articleTabs=article\" class=\"gen\">18 juillet 2011<\/a>. L&rsquo;article est pr\u00e9sent\u00e9 notamment par <em>MediaMatters.org<\/em> (tr\u00e8s actif dans la bataille anti-Murdoch) le <a href=\"http:\/\/mediamatters.org\/blog\/201107180015\" class=\"gen\">18 juillet 2011<\/a>, qui en fait un commentaire d&rsquo;une extr\u00eame s\u00e9v\u00e9rit\u00e9, faisant de l&rsquo;\u00e9dito une d\u00e9monstration de bassesse, repr\u00e9sentant \u00ab<em>just one example in recent days of Murdoch&rsquo;s American properties trying desperately to come to their owner&rsquo;s aid by offering up the unseemly combination of fabrications and self-pity<\/em>\u00bb. Notre avis serait plus nuanc\u00e9. L&rsquo;\u00e9ditorial pr\u00e9sente certainement des v\u00e9rit\u00e9s approximatives, voire des contre-v\u00e9rit\u00e9s, mais il repr\u00e9sente surtout une tentative tr\u00e8s offensive d&rsquo;affirmer la continuit\u00e9 de ce qui est pr\u00e9sent\u00e9, par le WSJ lui-m\u00eame, comme ses propres capacit\u00e9s et \u00e9thique professionnelles, dont il est affirm\u00e9 qu&rsquo;elles ont \u00e9t\u00e9 largement maintenues depuis le rachat du journal par Murdoch. En ce sens, il s&rsquo;agit plut\u00f4t d&rsquo;une tentative de d\u00e9marcation de celles des activit\u00e9s du groupe qui ont \u00e9t\u00e9 mises \u00e0 jour avec le <em>News of the World<\/em> et tout ce qui est apparu avec le scandale. On distingue l\u00e0 une tactique naissante, aux USA, qui pourrait annoncer, selon les r\u00e9sultats de l&rsquo;enqu\u00eate, un \u00e9clatement des positions, \u00e0 l&rsquo;int\u00e9rieur du groupe, vis-\u00e0-vis de la direction du groupe elle-m\u00eame. (A noter que <em>MediaMatters.org<\/em> <a href=\"http:\/\/mediamatters.org\/blog\/201107180028\" class=\"gen\">rappelle<\/a> un tr\u00e8s long article du WSJ sur Rupert Murdoch, du <a href=\"http:\/\/online.wsj.com\/article\/SB118100557923424501.html\" class=\"gen\">5 juin 2007<\/a>, alors que le m\u00eame Murdoch n\u00e9gociait f\u00e9rocement pour racheter le journal. A noter que les anciens propri\u00e9taires du WSJ, qui ont vendu le WSJ \u00e0 Murdoch, ont d\u00e9clar\u00e9 publiquement qu&rsquo;il ne l&rsquo;aurait pas fait s&rsquo;ils avaient connu la r\u00e9alit\u00e9 des activit\u00e9s du groupe.)<\/p>\n<h4>Notre commentaire<\/h4>\n<p>Il y a peu d&rsquo;exemples pour une crise de cette importance, d&rsquo;un cas o\u00f9 la dynamique de la chose est compl\u00e8tement hors du contr\u00f4le des protagonistes, avec un d\u00e9part situ\u00e9 \u00e0 un niveau certainement \u00e9mouvant (la r\u00e9v\u00e9lation des \u00e9coutes de la famille d&rsquo;une petite fille assassin\u00e9e) mais sans aucune esp\u00e8ce de correspondance avec la hauteur des enjeux qui sont impliqu\u00e9s actuellement. Il semble n&rsquo;y avoir pas de force structur\u00e9e qui soit capable, pour l&rsquo;instant, de reprendre ce contr\u00f4le (m\u00eame pour poursuivre une strat\u00e9gie de r\u00e9duction et de punition du groupe Murdoch). Ce constat nous semble conforme \u00e0 une situation que nous avons tent\u00e9e d&rsquo;analyser dans plusieurs textes (voir le <a href=\"http:\/\/www.dedefensa.org\/article-auto-destructuration_suite_au_tour_de_murdoch__07_07_2011.html\" class=\"gen\">7 juillet 2011<\/a>, le <a href=\"http:\/\/www.dedefensa.org\/article-fait_divers_ou_revolution__09_07_2011.html\" class=\"gen\">9 juillet 2011<\/a> et le <a href=\"http:\/\/www.dedefensa.org\/article-finalement_c_est_la_revolution__15_07_2011.html\" class=\"gen\">15 juillet 2011<\/a>). Le principal caract\u00e8re de cette situation, et d&rsquo;ailleurs aussi bien USA, malgr\u00e9 leur position pour l&rsquo;instant tr\u00e8s en retrait, qu&rsquo;au Royaume-Uni, est l&rsquo;absence de r\u00e9f\u00e9rences structur\u00e9es. Il s&rsquo;agit principalement de l&rsquo;absence compl\u00e8te des facteurs de la l\u00e9gitimit\u00e9, voire de la souverainet\u00e9, notamment par l&rsquo;absence de quelque acteur que ce soit capable de montrer des caract\u00e8res r\u00e9galiens.<\/p>\n<\/p>\n<p><p>\tPar d\u00e9finition, les activit\u00e9s du groupe Murdoch, d&rsquo;une fa\u00e7on fondamentale et quasi exclusive pour certains domaines (dont les directions politiques) pour le Royaume-Uni, d&rsquo;une fa\u00e7on importante pour les USA, avec l&rsquo;aide d&rsquo;autres forces autant que de la nature du pouvoir f\u00e9d\u00e9ral, ont contribu\u00e9 d\u00e9cisivement depuis 15 \u00e0 20 ans \u00e0 l&rsquo;\u00e9limination ce qu&rsquo;il restait de l\u00e9gitimit\u00e9 et de souverainet\u00e9 des pouvoirs politiques. Mais, bien entendu, le ph\u00e9nom\u00e8ne Murdoch n&rsquo;a remplac\u00e9 ces caract\u00e8res structurants par rien de structurant, ses activit\u00e9s \u00e9tant des activit\u00e9s de dissolution (influence diverses, jusqu&rsquo;\u00e0 une r\u00e9putation de terreur physique, du style crime organis\u00e9e, corruption, pressions indirectes). Ces activit\u00e9s, qui rel\u00e8vent de la contrainte et de la force en g\u00e9n\u00e9ral, peuvent \u00eatre efficaces tant que rien ne vient les contrecarrer et que les \u00e9v\u00e9nements g\u00e9n\u00e9raux vont dans leur sens, mais elles s&rsquo;av\u00e8rent impuissantes \u00e0 imposer des structures durables ; d&rsquo;o\u00f9 l&rsquo;absence d&rsquo;une possibilit\u00e9 de d\u00e9fense solide, voire de la subsistance d&rsquo;une partie des effets psychologiques de sa domination, d\u00e8s lors que cette domination est mise en cause, avec m\u00eame la transformation des forces de cette domination en faiblesses mortelles, parce qu&rsquo;elles rel\u00e8vent d&rsquo;un pouvoir (le groupe Murdoch) totalement d\u00e9nu\u00e9 lui-m\u00eame de l\u00e9gitimit\u00e9 et de souverainet\u00e9. C&rsquo;est-\u00e0-dire qu&rsquo;en exer\u00e7ant sa dictature, notamment par les activit\u00e9s qu&rsquo;on sait, le groupe Murdoch a renforc\u00e9 son pouvoir quantitatif mais a d\u00e9velopp\u00e9 une faiblesse qualitative qui montre aujourd&rsquo;hui tous ses effets. C&rsquo;est un reflet d\u00e9sormais habituel du fonctionnement du Syst\u00e8me, dont Murdoch est \u00e9videmment partie int\u00e9grante, avec le d\u00e9veloppement d&rsquo;une surpuissance s&rsquo;accompagnant d&rsquo;un processus d&rsquo;autodestruction.<\/p>\n<\/p>\n<p><p>\tDans cette situation, des courants qu&rsquo;on jugeait totalement soumis et jugul\u00e9s, et d\u00e9risoires, reprennent une puissance inattendue, notamment tout ce qui est charri\u00e9 par le syst\u00e8me de la communication qui retrouve alors son statut de <a href=\"http:\/\/www.dedefensa.org\/article-dialogues-13_de_la_sublimite_du_systeme_de_la_communication_08_11_2010.html\" class=\"gen\">Janus<\/a>. On veut parler notamment de l&rsquo;opinion publique, cette chose extr\u00eamement vague et quasi impossible \u00e0 substantiver, mais dont tout le monde parle dans cette affaire, et dont tout le monde ressent la pression psychologique qui pourrait d&rsquo;ailleurs \u00eatre pour une grande part une cr\u00e9ation de la psychologie et un \u00e9trange r\u00e9flexe \u00e9galement autodestructeur. Il n&rsquo;y a eu aucune manifestation de masse, aucun incident particulier contre Murdoch, etc., de la part du public, mais l&rsquo;affirmation r\u00e9p\u00e9t\u00e9e et r\u00e9p\u00e9t\u00e9e, que le public est outrag\u00e9, furieux, etc. (Tout juste peut-on parler \u00e0 cet \u00e9gard de la r\u00e9action de l&rsquo;acteur Hugh Grant et de quelques autres c\u00e9l\u00e9brit\u00e9s, dont on peut pourtant difficilement croire qu&rsquo;ils repr\u00e9sentent l&rsquo;opinion publique.) On peut donc admettre qu&rsquo;il s&rsquo;agit vraiment d&rsquo;une dynamique cr\u00e9\u00e9e par les \u00e9v\u00e9nements eux-m\u00eames, et \u00e0 laquelle se soumettent les diff\u00e9rents centres de pouvoir. Brad Simon, un avocat de la firme Simon and Partners de New York, sp\u00e9cialis\u00e9 dans la d\u00e9fense de consommateurs et groupes de plaignants individuels face \u00e0 des scandales impliquant des grands groupes, fait une remarque sur le comportement du minist\u00e8re US de la Justice (DoJ), d&rsquo;une ambigu\u00eft\u00e9 suffisante pour s&rsquo;inscrire dans cette sorte d&rsquo;explication qu&rsquo;on propose : Simon pr\u00e9sente l&rsquo;attitude du DoJ,  et d&rsquo;ailleurs comme on la voit aujourd&rsquo;hui o\u00f9 le DoJ engage des poursuites, soumise justement \u00e0 ce rythme des \u00e9v\u00e8nements,  comme si la position du DoJ avait finalement assez peu \u00e0 voir avec les r\u00e9els caract\u00e8res de l&rsquo;affaire, responsabilit\u00e9 ou pas, probable culpabilit\u00e9 ou pas, gravit\u00e9 des actes commis ou pas, etc., et tout avec le rythme des choses  : \u00ab<em>The US justice department traditionally responds to fast-breaking news developments and the fact that there have been resignations and arrests in the UK make it more likely than not that the US authorities will pursue this matter.<\/em>\u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 19 juillet 2011 \u00e0 08H58<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans la crise Murdoch, c&rsquo;est le rythme qui domine tout, rythme des \u00e9v\u00e9nements, rythme des r\u00e9v\u00e9lations, rythme des mesures n\u00e9cessairement prises (d\u00e9missions, arrestations, enqu\u00eates, etc.), le rythme \u00e0 laquelle la pi\u00e8ce se d\u00e9tricote. La constat est celui d&rsquo;une absence compl\u00e8te de contr\u00f4le des \u00e9v\u00e9nements, le ph\u00e9nom\u00e8ne illustre une immense dynamique d&rsquo;incontr\u00f4labilit\u00e9, la perspective est la&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3858,3907,6640,3823,3555,4749,2746,3372,3132],"class_list":["post-73910","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-corruption","tag-destructuration","tag-doj","tag-journal","tag-legitimite","tag-murdoch","tag-souverainete","tag-street","tag-wall"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73910"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73910\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}