{"id":73913,"date":"2011-07-20T17:10:31","date_gmt":"2011-07-20T17:10:31","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/07\/20\/le-tres-tres-etrange-cas-du-f-22\/"},"modified":"2011-07-20T17:10:31","modified_gmt":"2011-07-20T17:10:31","slug":"le-tres-tres-etrange-cas-du-f-22","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/07\/20\/le-tres-tres-etrange-cas-du-f-22\/","title":{"rendered":"Le tr\u00e8s tr\u00e8s \u201c\u00e9trange cas du F-22\u201d"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Le tr\u00e8s tr\u00e8s \u00ab\u00a0\u00e9trange cas du F-22\u00a0\u00bb<\/h2>\n<\/p>\n<p><p>Merci de prendre des nouvelles, puisqu&rsquo;en effet <strong>toute<\/strong> la flotte des F-22 de l&rsquo;USAF continue \u00e0 \u00eatre <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-l_etrange_cas_du_f-22_13_07_2011.html\">interdite de vol<\/a> (depuis le 3 mai). Le cas constitue d\u00e9sormais un record de dur\u00e9e dans l&rsquo;histoire militaire des Etats-Unis, pour l&rsquo;interdiction de vol d&rsquo;un type d&rsquo;appareil, et encore bien plus significatif, d&rsquo;un appareil reconnu d&rsquo;une importance strat\u00e9gique essentielle dans le dispositif de s\u00e9curit\u00e9 nationale des forces arm\u00e9es. La dur\u00e9e de l&rsquo;interdiction de <strong>toute<\/strong> la flotte de F-22 d\u00e9passe d\u00e9sormais le fameux incident des ann\u00e9es 1957-1958 affectant le bombardier B-47 <em>StratoJet<\/em> \u00e0 capacit\u00e9s nucl\u00e9aires, du SAC. (Une faiblesse structurelle tr\u00e8s grave \u00e0 l&#8217;emplanture de l&rsquo;aile fut d\u00e9couverte sur l&rsquo;avion, ce qui conduisit \u00e0 l&rsquo;interdiction de vol de toute la flotte de ce bombardier durant un peu plus de deux mois, &ndash; jusqu&rsquo;\u00e0 l&rsquo;identification et l&rsquo;\u00e9valuation du probl\u00e8me, puis la possibilit\u00e9 admise pour le reste de la flotte de voler en attendant les modification apport\u00e9es \u00e0 mesure sur un groupe apr\u00e8s l&rsquo;autre ; ces modifications faites, les B-47 r\u00e9nov\u00e9s retrouvaient le service op\u00e9rationnel tandis que d&rsquo;autres \u00e9taient immobilis\u00e9s \u00e0 leur tour.)<\/p>\n<\/p>\n<p><p>Le F-22 est toujours clou\u00e9 au sol et c&rsquo;est comme si une situation quasiment structurelle s&rsquo;installait. L&rsquo;USAF est extraordinairement discr\u00e8te sur la question, &ndash; son aspect technique et les dispositions chronologiques (possibilit\u00e9 de reprise des vols). Deux nouvelles valent d&rsquo;\u00eatre cit\u00e9es concernant ce cas extraordinaire, qui a autant une valeur circonstancielle qu&rsquo;une valeur conjoncturelle, concernant les capacit\u00e9s r\u00e9elles et possibles des avions aux technologies tr\u00e8s avanc\u00e9es, et enti\u00e8rement structur\u00e9s par le contr\u00f4le \u00e9lectronique et informatique ; et m\u00eame, qui a une valeur exemplaire pour quelques questions fondamentales concernant l&rsquo;usage des technologies.<\/p>\n<\/p>\n<p><p>&bull; La premi\u00e8re nouvelle vient de Bill Sweetman, sur le site <em>AviationWeek.com<\/em>, le <a class=\"gen\" href=\"http:\/\/www.aviationweek.com\/aw\/generic\/story.jsp?topicName=Check6&#038;id=news\/awst\/2011\/07\/18\/AW_07_18_2011_p35-347638.xml&#038;headline=F-22s%20Grounded%20Pending%20Oxygen%20System%20Probe&#038;channel=&#038;from=topicalreports\">18 juillet 2011<\/a>. Sweetman examine la question de la \u00ab\u00a0panne\u00a0\u00bb (syst\u00e8me \u00e0 oxyg\u00e8ne pour le pilote, ou Obogs pour <em>onboard oxygen-generation system<\/em>) qui aurait \u00e9t\u00e9 identifi\u00e9e ; pour aussit\u00f4t observer que la \u00ab\u00a0panne\u00a0\u00bb n&rsquo;a en fait pas \u00e9t\u00e9 \u00ab\u00a0clairement identifi\u00e9e\u00a0\u00bb (&laquo;<em>The U.S. Air Force&rsquo;s F-22 fighter remains subject to the longest full-force grounding of any combat aircraft in recent history, with no cause firmly identified<\/em>&raquo;). C&rsquo;est cette \u00ab\u00a0panne\u00a0\u00bb qui aurait \u00e9t\u00e9 la cause de la perte d&rsquo;un F-22 et de son pilote le 16 novembre 2010 en Alaska, &ndash; quoique l&rsquo;USAF reste particuli\u00e8rement discr\u00e8te sur ce cas (&laquo;<em>The response to the question, \u00ab\u00a0Has a cause been positively identified?\u00a0\u00bb is, \u00ab\u00a0The investigation is still ongoing\u00a0\u00bb<\/em>&raquo;). Sweetman a trouv\u00e9 quelques indications assez impr\u00e9cises et incertaines sur ce que <strong>pourrait<\/strong> \u00eatre la \u00ab\u00a0panne\u00a0\u00bb (&laquo;<em>According to a source familiar with some aspects of the investigation, Honeywell participants in the investigation believe the problem does not lie with the Obogs alone&hellip;<\/em>&raquo;). Sweetman note que, comme on le sait, cette panne se retrouve sur d&rsquo;autres avions en service, mais il semble ajouter qu&rsquo;elle est plus grave pour le F-22 (et pour le F-35, <em>by the way<\/em>, &ndash; lorsqu&rsquo;elle interviendra ?), &ndash; et cela, pour une cause assez \u00e9trange&hellip; : &laquo;<em>A complicating factor, one observer suggests, could be the fact that the F-22 (and F-35) Obogs are \u00ab\u00a0relatively simple\u00a0\u00bb systems&hellip;<\/em>&raquo; Suivent de longues explications concernant le F\/A-18C\/D <em>Super Hornet<\/em>, qui utilise le syst\u00e8me Obogs, qui conna&icirc;t \u00e9galement des probl\u00e8mes, mais qui n&rsquo;a, lui, jamais \u00e9t\u00e9 interdit de vol.<\/p>\n<\/p>\n<p><p>&bull; Un article de Hugh Lessig, du <em>Daily Press<\/em>, en Virginie, dat\u00e9 du <a class=\"gen\" href=\"http:\/\/www.military.com\/news\/article\/grounded-raptor-pilots-work-to-keep-their-edge.html\">19 juillet 2011<\/a> ; il s&rsquo;agit d&rsquo;un reportage sur la base de Langley (Virginie), qui abrite le 1st Tactical Fighter Group, qui devient un centre d&rsquo;accueil pour pilotes de F-22 d\u00e9s&oelig;uvr\u00e9s, venus de diverses unit\u00e9s et diverses bases. Il s&rsquo;est organis\u00e9 \u00e0 Langley une sorte de centre d&rsquo;entretien th\u00e9orique de vol, par le biais de simulateurs de vol, avec divers programmes d&rsquo;entretien technique, psychologique et physique pour les pilotes (beaucoup de gym, pour la forme). Les m\u00e9caniciens sont \u00e9galement l\u00e0, qui perfectionnent leur capacit\u00e9s d&rsquo;entretien et de logistique. Il arrive qu&rsquo;on fasse rouler des F-22, moteurs allum\u00e9s, sur la piste (le pilote peut fermer les yeux et s&rsquo;imaginer qu&rsquo;il effectue une mission de combat). Nous avons subrepticement soulign\u00e9 de gras deux pr\u00e9cisions dites accessoirement dans l&rsquo;article, qui peuvent s&rsquo;av\u00e9rer pr\u00e9cieuses.<\/p>\n<\/p>\n<p><p>&laquo;<em>Raptor pilots at Langley are not exactly twiddling their thumbs waiting for the all-clear. They&rsquo;ve ramped up training in a high-tech simulator and are spending more time in the classroom. Maintenance crews are handling more ambitious projects work they could never do during the normal flight cycle.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>And time in the gym? It&rsquo;s on the rise. Fighter pilots are not exactly low-energy individuals. \u00ab\u00a0The guys are getting antsy,\u00a0\u00bb said Lt. Col. Jason Hinds, director of operations for the 27th Fighter Squadron.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>The F-22 simulator at Langley has become a popular place &ndash; not just with Langley pilots, but throughout the Air Force. It is only one of two F-22 simulators in the service; the other is at Tyndall Air Force Base in Florida. Since the stand down, pilots from Hawaii, New Mexico and elsewhere have come to Langley to train, said Capt. Travis Passey, training flight commander in the Operational Support Squadron. This past week, pilots from Alaska were at the base. \u00ab\u00a0For the<\/em> <strong><em>next three months<\/em><\/strong><em>, we&rsquo;ve got people booked to come here to operate in our simulators,\u00a0\u00bb Passey said.<\/em> [&hellip;]<\/p>\n<\/p>\n<p><p>&laquo;<em>\u00ab\u00a0The risk isn&rsquo;t there,\u00a0\u00bb said Lt. Col. Pete Fesler, commander of the 27th Fighter Squadron. \u00ab\u00a0That risk equates to stress. You can&rsquo;t really hit the ground in a simulator. Obviously, you can in a real airplane, so you tend to take risks that are a little bit higher when you fly the simulator because there&rsquo;s no threat to you or the airplane.\u00a0\u00bb But it does help, the pilots say, as does increased classroom time. Pilots are going through weapons and tactics briefings and receiving intelligence updates on relevant situations from around the world, said Hinds.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>\u00ab\u00a0We&rsquo;re keeping our brains engaged with the &#8230; numbers they have memorized,\u00a0\u00bb Hinds said. \u00ab\u00a0I guarantee you, these guys can tell you everything about the Raptor and everything about the primary-threat airplanes we fly against.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Langley also plans to ramp up activity on its flight line in the near future. They will prepare the Raptor as if to fly. Pilots will don their equipment. Traffic controllers and weather forecasters will do their jobs. Then the Raptor will taxi to the end of the runway and return. That doesn&rsquo;t sound like much, but that short trip will enable the pilots and maintenance crews to get a lot more data about the condition of the airplane, and fix potential problems. Fesler said Langley should emerge from the stand down &ndash; whenever that is &ndash; with a stronger maintenance capability.<\/em> [&hellip;]<\/p>\n<\/p>\n<p><p>&raquo;<em>&hellip;And while they&rsquo;re anxious to return to the sky, the pilots will do it step by step, gradually increasing activity and the complexity of their missions. Residents of Hampton<\/em> <strong><em>shouldn&rsquo;t expect crowded skies right away.<\/em><\/strong>&raquo;<\/p>\n<\/p>\n<p><p>La pr\u00e9cision que le programme de simulateurs de vol est d\u00e9j\u00e0 \u00ab\u00a0<em>surbook\u00e9<\/em>\u00a0\u00bb pour les trois prochains mois, avec des pilotes de F-22 venus d&rsquo;un peu partout, signifie-t-elle qu&rsquo;on ne pr\u00e9voit pas la reprise des vols avant trois mois au mieux ? L&rsquo;id\u00e9e n&rsquo;est certainement pas d\u00e9mentie par la derni\u00e8re phrase cit\u00e9e (\u00ab\u00a0Les r\u00e9sidents de Hampton ne devraient pas attendre des cieux encombr\u00e9s [de F-22] pour tout de suite\u00a0\u00bb) ; alors que la phrase pr\u00e9c\u00e9dente, dans le paragraphe, laisse l&rsquo;impression \u00e9trange de pilotes de F-22 qui devraient se pr\u00e9parer longuement avant de reprendre les vols, peu \u00e0 peu, \u00e0 partir du moment o&ugrave; l&rsquo;interdiction de vol serait lev\u00e9e, &ndash; et cela, comme s&rsquo;il s&rsquo;agissait d&rsquo;un tout nouvel avion alors qu&rsquo;il est en service depuis 4 \u00e0 5 ans. Ce reportage \u00e9paissit le myst\u00e8re plut\u00f4t qu&rsquo;il ne l&rsquo;\u00e9claire, et donne l&rsquo;impression qu&rsquo;on s&rsquo;installe pour longtemps dans une situation o&ugrave; les F-22 ne voleront pas.<\/p>\n<\/p>\n<p><p>Les pr\u00e9cisions donn\u00e9es par Sweetman ne sont pas plus rassurantes, avec toujours la m\u00eame question de savoir pourquoi le F-22 est interdit de vol pour des probl\u00e8mes qui existent pour d&rsquo;autres mod\u00e8les d&rsquo;avion, qui, eux, n&rsquo;ont jamais \u00e9t\u00e9 interdits de vol. On ne peut s&#8217;emp\u00eacher d&rsquo;\u00e9voquer l&rsquo;hypoth\u00e8se selon laquelle une panne donn\u00e9e dans un type d&rsquo;avion moins avanc\u00e9, devient une panne insupportable pour le F-22, qui conduit \u00e0 son interdiction de vol&hellip; Or, comme le syst\u00e8me Obogs du type employ\u00e9 conna&icirc;t des probl\u00e8mes depuis l&rsquo;origine, c&rsquo;est-\u00e0-dire depuis au moins 2000 pour le <em>Super Hornet<\/em>, on voit sur quelle <em>terra incognita<\/em> l&rsquo;on s&rsquo;engage.<\/p>\n<\/p>\n<p><p>Le sort actuel du F-22, sans pr\u00e9c\u00e9dent dans l&rsquo;histoire de l&rsquo;aviation militaire, conduit \u00e0 s&rsquo;interroger sur l'\u00a0\u00bbop\u00e9rationnalit\u00e9\u00a0\u00bb fondamentale de cette classe d&rsquo;appareils d\u00e9velopp\u00e9s par les USA, o&ugrave; l&rsquo;habillage \u00e9lectronique et informatique semble avoir franchi le pas d&rsquo;un contr\u00f4le complet, qui commande \u00e0 tous les caract\u00e8res de l&rsquo;avion, \u00e0 l&rsquo;avion lui-m\u00eame. Il est ainsi possible qu&rsquo;on se trouve au seuil d&rsquo;une situation g\u00e9n\u00e9rale o&ugrave; l&rsquo;utilisation des technologies, avec leur importance, leur place, leur situation dans la cha&icirc;ne de contr\u00f4le, constitue potentiellement un obstacle insupportable dans la mesure o&ugrave; elle prive les utilisateurs (<em>sapiens<\/em>) de la ma&icirc;trise du syst\u00e8me. (L&rsquo;on sait, bien entendu, que ce ne sont pas les premiers probl\u00e8mes \u00ab\u00a0myst\u00e9rieux\u00a0\u00bb que rencontre le F-22 ; l&rsquo;on sait que le F-35, log\u00e9 \u00e0 la m\u00eame enseigne en pire, en a connu d&rsquo;\u00e9quivalents et il devrait en conna&icirc;tre de plus en plus.) Si l&rsquo;on ajoute \u00e0 cette possible perspective relevant du probl\u00e8me fondamental du blocage du progr\u00e8s technologique par transformation substantielle de ce progr\u00e8s, la crainte absolument panique de l&rsquo;USAF de prendre le moindre risque, aboutissant \u00e0 la possible perte de l&rsquo;un ou l&rsquo;autre appareil, on a une id\u00e9e assez \u00e9tonnante de la situation o&ugrave; se trouve aujourd&rsquo;hui la flotte de l&rsquo;avion de combat le plus avanc\u00e9 du monde. <em>In illo tempore<\/em>, les probl\u00e8mes d&rsquo;un syst\u00e8me d&rsquo;arme, type avion de combat avanc\u00e9, se manifestaient lors des tests de mise au point, et l&rsquo;entr\u00e9e en service marquait le moment o&ugrave; ces probl\u00e8mes avaient disparu, ou bien \u00e9taient ma&icirc;tris\u00e9s et s&rsquo;att\u00e9nuaient rapidement jusqu&rsquo;\u00e0 dispara&icirc;tre (sauf accident exceptionnel et d&rsquo;ailleurs pr\u00e9cis\u00e9ment identifi\u00e9 et compr\u00e9hensible, comme celui du B-47). Avec cette nouvelle g\u00e9n\u00e9ration de \u00ab\u00a0monstres technologiques\u00a0\u00bb fort proches de l&rsquo;incontr\u00f4labilit\u00e9, il y a toujours les probl\u00e8mes de mise au point, plus nombreux qu&rsquo;\u00e0 l&rsquo;ordinaire, tandis que l&rsquo;entr\u00e9e en service signale l&rsquo;apparition de nouveaux probl\u00e8mes qui, eux, semblent proches d&rsquo;\u00eatre insolubles, &ndash; et m\u00eame, peut-\u00eatre, le sont. La \u00ab\u00a0b\u00eate\u00a0\u00bb a pris son sort en mains&hellip;<\/p>\n<\/p>\n<p><p>Mis en ligne le 20 juillet 2011 \u00e0 17H09<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le tr\u00e8s tr\u00e8s \u00ab\u00a0\u00e9trange cas du F-22\u00a0\u00bb Merci de prendre des nouvelles, puisqu&rsquo;en effet toute la flotte des F-22 de l&rsquo;USAF continue \u00e0 \u00eatre interdite de vol (depuis le 3 mai). Le cas constitue d\u00e9sormais un record de dur\u00e9e dans l&rsquo;histoire militaire des Etats-Unis, pour l&rsquo;interdiction de vol d&rsquo;un type d&rsquo;appareil, et encore bien plus&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[11311,4616,2631,249,2969,11310,11292,250,11313,11309,11312,3519,5712,4584],"class_list":["post-73913","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-b-47","tag-blocage","tag-de","tag-f-22","tag-f-35","tag-incontrolabilite","tag-interdit","tag-jsf","tag-langley","tag-maitrise","tag-simulateur","tag-technologie","tag-technologique","tag-vol"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73913"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73913\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}