{"id":73946,"date":"2011-08-02T07:40:59","date_gmt":"2011-08-02T07:40:59","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/08\/02\/puisque-les-talibans-sont-au-congres-parlons-en\/"},"modified":"2011-08-02T07:40:59","modified_gmt":"2011-08-02T07:40:59","slug":"puisque-les-talibans-sont-au-congres-parlons-en","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/08\/02\/puisque-les-talibans-sont-au-congres-parlons-en\/","title":{"rendered":"Puisque les talibans sont au Congr\u00e8s, parlons-en\u2026"},"content":{"rendered":"<p><p>S&rsquo;il y a un article qui a fait quelque bruit dans le sens du sensationnalisme qu&rsquo;affectionne le syst\u00e8me de la communication, c&rsquo;est celui de l&rsquo;ancien parlementaire d\u00e9mocrate du Texas Mart\u00edn Frost, sur <em>Politico.com<\/em> le <a href=\"http:\/\/dyn.politico.com\/printstory.cfm?uuid=007E6612-168A-469F-AFC7-0068ABB55747\" class=\"gen\">29 juillet 2011<\/a>. Passons aussit\u00f4t au contenu, qui est d&rsquo;assimiler <em>Tea Party<\/em> aux talibans.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Ten years ago, the Taliban in Afghanistan destroyed two gigantic figures of Buddha, carved into a hillside 18 centuries before. The world was aghast at this barbarian act taken in the name of religious purity. But was powerless to stop it.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>We now have a group of U.S. politicians seeking political purity, who seem to have much in common with the Taliban. They are tea party members; and because of blind adherence to smaller government, they seem intent on risking destroying what American political leaders have constructed in more than two centuries of hard, often painful work. Like the Taliban, they see compromise as an unacceptable alternative<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;image est jolie mais d&rsquo;\u00e9vocation inqui\u00e9tante du point de vue de l&rsquo;op\u00e9rationnalit\u00e9. Martin Frost s&rsquo;est-il avis\u00e9 que nous ne sommes plus tr\u00e8s loin, aujourd&rsquo;hui, 1) de trouver les talibans assez acceptables pour avoir nombre de contacts avec eux en Afghanistan, et 2) d&rsquo;observer que la situation leur est tellement favorable qu&rsquo;on est \u00e0 peu pr\u00e8s assur\u00e9 de les retrouver rapidement au pouvoir dans les deux ou trois ann\u00e9es qui viennent, amalgam\u00e9s \u00e0 d&rsquo;autres groupes, ou bien gouvernant par des voies plus autoritaires. Frost signifie-t-il que c&rsquo;est ce qui nous attend, aux USA, avec <em>Tea Party<\/em> ?<\/p>\n<\/p>\n<p><p>\tLe paradoxe de la situation actuelle est que le monde entier, y compris Washington D.C., d\u00e9couvre avec horreur <em>Tea Party<\/em> et lui attribue une puissance extraordinaire au moment o\u00f9, depuis novembre 2010, <em>Tea Party<\/em> est nettement en d\u00e9clin. (<em>Tea Party<\/em> a notamment perdu beaucoup de sa popularit\u00e9, \u00e0 cause de sa branche la plus id\u00e9ologique, en se tenant au c\u00f4t\u00e9 du gouverneur du Wisconsin durant les troubles de Madison, en <a href=\"http:\/\/www.dedefensa.org\/article-les_usa_et_le_grand_trouble_28_02_2011.html\" class=\"gen\">f\u00e9vrier 2011<\/a>.) La publicit\u00e9 qui lui a \u00e9t\u00e9 ainsi faite lors de la crise de la dette sera peut-\u00eatre un bon moyen de relancer la chose, le citoyen US courant pouvant s&rsquo;aviser qu&rsquo;apr\u00e8s tout, <em>Tea Party<\/em> est un excellent moyen de mettre un peu de d\u00e9sordre d\u00e9structurant dans ce chaos pompeux et arrogant qu&rsquo;est l&rsquo;<em>establishment<\/em> washingtonien actuel. En effet, ceux des commentateurs-Syst\u00e8me qui tablent sur la frayeur des citoyens devant l&rsquo;activisme d\u00e9structurant de <em>Tea Party<\/em> durant la crise de la dette ne tiennent pas vraiment compte que l&rsquo;humeur du citoyen, et encore plus apr\u00e8s les effets catastrophiques pour lui (emploi, etc.) de l&rsquo;accord sur la dette, serait plus celle de la revendication furieuse et de la col\u00e8re anti-washingtonienne que celle de la prudence.<\/p>\n<\/p>\n<p><p>\tEt pourtant <em>Tea Party<\/em> n&rsquo;a qu&rsquo;une responsabilit\u00e9 r\u00e9duite dans ce tourbillon washingtonien, ce qui montre que les manuvres de d\u00e9fense du Syst\u00e8me sont parfois doublement pervers (en remettant \u00e9ventuellement <em>Tea Party<\/em> en selle \u00e0 cause de son activisme dont il n&rsquo;est pas la v\u00e9ritable cause). Comme d&rsquo;habitude, on se pr\u00e9cipite aux apparences des remous des n\u00e9gociations, avec le suppl\u00e9ment de l&rsquo;anath\u00e8me id\u00e9ologique, et on cantonne la m\u00e9moire historique aux derni\u00e8res 48 heures. La cause fondamentale de la crise, c&rsquo;est simplement la dette elle-m\u00eame, qui est de la responsabilit\u00e9, ou plut\u00f4t de l&rsquo;irresponsabilit\u00e9 du pouvoir de l&rsquo;<em>establishment<\/em>, des Maison-Blanche successives, des Congr\u00e8s successifs (sans <em>Tea Party<\/em>), de Wall Street avec ses banques d\u00e9voreuses de $trillions de l&rsquo;argent public et ainsi de suite.<\/p>\n<\/p>\n<p><p>\tPlus pr\u00e8s de nous, le responsable est bien l&rsquo;appareil de l&rsquo;<em>establishment<\/em> qui a d\u00e9montr\u00e9 son impuissance-Syst\u00e8me. Cet appareil n&rsquo;est plus capable de contr\u00f4ler ses exc\u00e8s et ses parlementaires, comme l&rsquo;\u00e9crit avec un cynisme incroyable, Megan Carpentier, du <em>Guardian<\/em>, le <a href=\"http:\/\/www.guardian.co.uk\/commentisfree\/cifamerica\/2011\/jul\/29\/john-boehner-republicans\" class=\"gen\">29 juillet 2011<\/a>. Il en faut, en effet, du cynisme, pour rappeler avec regret (avec cette \u00e9quipe-l\u00e0, <em>Tea Party<\/em> aurait \u00e9t\u00e9 mis au pas) l&rsquo;\u00e9poque de l&rsquo;\u00e9quipe Hastert-DeLay, qui menait la Chambre \u00e0 majorit\u00e9 r\u00e9publicaine jusqu&rsquo;en 2006. Cynisme incroyable dans un journal (le <em>Guardian<\/em>) qui se veut un parangon de la d\u00e9mocratie et de toutes ses vertus, parce que l&rsquo;\u00e9quipe Hastert-DeLay (le second en prison pour corruption) repr\u00e9sente l&rsquo;organisation parlementaire la plus mafieuse, la plus basse, la plus m\u00e9diocre, la plus corrompue, la plus ill\u00e9gitime qui n&rsquo;ait jamais exist\u00e9 dans l&rsquo;histoire parlementaire pourtant fort fleurie \u00e0 cet \u00e9gard du Congr\u00e8s des Etats-Unis. Mais fort bien, si madame Carpentier veut cela pour mettre de l&rsquo;ordre dans les rangs, elle a le sens de la logique-Syst\u00e8me et des habitudes qui vont avec ; c&rsquo;est bien le crime organis\u00e9 qui, dans les banlieues et quartiers populaires US, avec les municipalit\u00e9s corrompues comme il fallait, sut toujours maintenir l&rsquo;ordre et d\u00e9fendit effectivement l&rsquo;ordre du Syst\u00e8me, avec ses moyens du bord (racket, corruption, pressions physiques, votes organis\u00e9s, etc.). Puisque <em>Tea Party<\/em> semble \u00eatre un mouvement populiste, il est assez logique et conforme au Syst\u00e8me de lui souhaiter un traitement d\u00e9mocratique du genre.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>But it wasn&rsquo;t always this way. Less than a decade ago, in the wake of the compounding infidelity scandals that rocked the then House leadership during the time of then President Clinton&rsquo;s impeachment, former high school wrestling coach Denny Hastert held the speaker&rsquo;s gavel and his consigliere, majority whip-cum-leader Tom The Hammer DeLay, ruled votes with an iron fist. Didn&rsquo;t like a bill? Delay didn&rsquo;t care  it was your job to vote for the leadership&rsquo;s legislation. Have a Dick Armey-led group threatening you with a primary opponent? DeLay was scarier: he&rsquo;d set up your primary opponents, kill your earmarks, yank your chairmanship and even, in a case for which he was eventually censured, go after your family. He had no need to kowtow to some upstart ultra-conservative group, because he made sure they knew who was boss from the outset (and, frankly, you could hardly get more conservative than DeLay).<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCertes, tout le monde s&rsquo;\u00e9tonne. Les coutumes sont renvers\u00e9es, non seulement les coutumes mafieuses (voir ci-dessus) mais \u00e9galement les harmonies de compromis, d&rsquo;arrangements, de march\u00e9s conclu qui ont toujours marqu\u00e9 les pratiques du Congr\u00e8s des Etats-Unis. <strong>Toujours<\/strong>, certes, puisque, d\u00e8s le mois de mai 1791, le premier Secr\u00e9taire d&rsquo;Etat du gouvernement f\u00e9d\u00e9ral, Thomas Jefferson,  \u00e9crivait une lettre fameuse \u00e0 son pr\u00e9sident, le premier des Etats-Unis d&rsquo;Am\u00e9rique, George Washington, pour d\u00e9noncer la corruption du Congr\u00e8s, les arrangements, les compromissions, et annoncer un avenir bien sombre pour la Grande R\u00e9publique si aucun bon ordre n&rsquo;y \u00e9tait mis. Rien ne changea. De ce point de vue, la crise a marqu\u00e9 une nouveaut\u00e9 historique : les murs d\u00e9nonc\u00e9s par Jefferson, sans dispara\u00eetre \u00e9videmment puisque les pratiques en question restent actives, ont soudainement \u00e9t\u00e9 boulevers\u00e9s par un nouveau spectacle d&rsquo;intransigeance id\u00e9ologique qui a pris pour cette p\u00e9riode le devant de la sc\u00e8ne. Ce n&rsquo;est certainement pas dire que <em>Tea Party<\/em> est vertueux \u00e0 cet \u00e9gard, certes non et mille fois non ; c&rsquo;est dire plus droitement, pour aller \u00e0 l&rsquo;essentiel, que les circonstances ont soudainement boulevers\u00e9 les attitudes prioritaires et ont plac\u00e9 les d\u00e9bats sous le signe de la politique, intransigeante, furieuse, voire hyst\u00e9rique,  exerc\u00e9e contre <em>Tea Party<\/em>,  et que cette pression a montr\u00e9 des r\u00e9sultats mitig\u00e9s en m\u00eame temps que la grande peur de l&rsquo;<em>establishment<\/em>, version US de <em>La grande peur des bien-pensants<\/em><\/p>\n<\/p>\n<p><p>\t<em>The Observer<\/em>, du <a href=\"http:\/\/www.guardian.co.uk\/world\/2011\/jul\/31\/us-debt-congress-tea-party\" class=\"gen\">31 juillet 2011<\/a> : \u00ab<em>Larry Sabato, a professor of politics at the University of Virginia, said: This is a very unusual place in American history. No one in my field can remember circumstances like this. You have people in Congress who will not sit down and compromise. Compromise is a dirty word. But representative government is impossible without compromise. The Republicans and Democrats are voting as separate units, which they have rarely done in the US.<\/em> [] <em>The crisis is being driven by a hardcore of about 20 House members affiliated to the Tea Party. They are prepared to put at risk the US&rsquo;s faltering economic recovery  and economies around the world  to push the Tea Party ideal of small government, in particular cutting federal spending.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tAussi avons-nous droit d\u00e9sormais \u00e0 diverses crises de nerfs, ici et l\u00e0, exc\u00e8s des esprits et des curs les plus vertueux de l&rsquo;<em>establishment<\/em>. Aussit\u00f4t,  mais c&rsquo;est l\u00e0 une contagion qui touche tous les commentateurs,  le spectre de l&rsquo;intol\u00e9rance et de la dictature est d\u00e9nonc\u00e9. On a pu entendre et voir l&rsquo;honorable Fareed Zacharias, digne repr\u00e9sentant du non moins digne Council on Foreign Relations (CFR), d\u00e9noncer la dictature que, semble-t-il, du moins \u00e0 son estime, <em>Tea Party<\/em> voudrait imposer aux USA (Une chose n&rsquo;est pas fausse dans les g\u00e9missements de Zacharias, et elle est m\u00eame tr\u00e8s encourageante, presque d&rsquo;essence vertueuse \u00e0 l&rsquo;avantage de <em>Tea Party<\/em>, et c&rsquo;est l&rsquo;\u00e9vocation de la possibilit\u00e9, de la menace dans ce cas que <em>Tea Party<\/em> fasse exploser le pays.) (S\u00e9quence TV reprise par <em>RAW Story<\/em> le <a href=\"http:\/\/www.rawstory.com\/rawreplay\/2011\/07\/cnn-host-tea-party-debt-dealings-counter-constitutional-anti-democratic\/\" class=\"gen\">31 juillet 2011<\/a>.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>CNN host Fareed Zakaria was a guest on Anderson Cooper&rsquo;s AC360 Friday night, where he said that the ultra-conservative tea party faction of the Republican Party was sending a message that we&rsquo;ll blow up the country if you don&rsquo;t listen to us. We will hold hostage the credit of the United States, the good standing of the United States and we&rsquo;ll blow it up. They were not elected dictators of the United States, he said of their slowing of the debt ceiling negotiation process.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCertes, <em>Tea Party<\/em> n&rsquo;a pas \u00e9t\u00e9 \u00e9lu dictateur des Etats-Unis et il y a fort peu de chances qu&rsquo;il ne le soit jamais, ni, surtout, qu&rsquo;il ne cherche jamais \u00e0 l&rsquo;\u00eatre. Il faut prendre garde \u00e0 ne pas projeter l&rsquo;hyst\u00e9rie postmoderniste n\u00e9e et sans cesse aggrav\u00e9e sous la pression matricielle du Syst\u00e8me, concernant tous les artefacts qui surgissent \u00e0 l&rsquo;occasion de la crise centrale du Syst\u00e8me et de sa chute,  de la Chute tout court. C&rsquo;est une mauvaise tendance et une mauvaise querelle. Dans le cas de <em>Tea Party<\/em>, comme dans bien d&rsquo;autres, l&rsquo;impr\u00e9cation semble suffire au jugement qu&rsquo;on en a, qu&rsquo;on accorde \u00e0 une sorte de jugement-Syst\u00e8me avec l&rsquo;aide du cat\u00e9chisme du parti des salonnards. Le jugement en est fort brouill\u00e9 par cons\u00e9quent.<\/p>\n<\/p>\n<p><p>\t<em>Tea Party<\/em> n&rsquo;est certes pas idyllique, ni vertueux, et certains de ses projets sont monstrueux. (Mais la monstruosit\u00e9 est une pratique courante et de tous bords dans ces temps agit\u00e9s.) Comme nous avons <a href=\"http:\/\/www.dedefensa.org\/article-metaphysique_de_tea_party_16_09_2010.html\" class=\"gen\">souvent<\/a> tent\u00e9 de <a href=\"http:\/\/www.dedefensa.org\/article-tea_party_est-il_un_systeme_anthropopuliste__21_09_2010.html\" class=\"gen\">le montrer<\/a>, <em>Tea Party<\/em> est une sorte d&rsquo;organisation sans organisation, un rassemblement politique fort peu rassembl\u00e9, h\u00e9t\u00e9roclite, insaisissable, une sorte de ph\u00e9nom\u00e8ne renvoyant bien aux conceptions h\u00e9rit\u00e9es de l&rsquo;<a href=\" http:\/\/www.dedefensa.org\/article-apocalypse_molle_type_deleuzien-demasque-par-mattei__22_07_2011.html\" class=\"gen\">inspiration deleuzienne<\/a>. Mais, dans un mouvement d\u00e9sormais habituel d&rsquo;autodestruction, la chose ainsi qualifi\u00e9e de deleuzienne se retourne contre le Syst\u00e8me, lui-m\u00eame dispensateur de destruction de l&rsquo;essence des choses par la dissolution qu&rsquo;il implique, \u00e9galement d&rsquo;inspiration deleuzienne. Objectivement jug\u00e9e, l&rsquo;action de <em>Tea Party<\/em> va dans le sens d\u00e9structurant du Syst\u00e8me qu&rsquo;il faut.<\/p>\n<\/p>\n<p><p>\tToutes les fariboles id\u00e9ologiques du Syst\u00e8me \u00e0 son encontre (fascisme, m\u00eame bolch\u00e9visme, etc.) sont bien des fariboles de circonstance. La seule dynamique qui soit commune \u00e0 ce mouvement insaisissable et souvent contradictoire \u00e0 l&rsquo;int\u00e9rieur de lui-m\u00eame, c&rsquo;est son opposition au centre, au gouvernement f\u00e9d\u00e9ral, \u00e0 un centralisme public relayant l&rsquo;action du Syst\u00e8me ; cette dynamique qui est un facteur fondamental contre toute formule totalitaire renvoyant au XX\u00e8me si\u00e8cle. La formule totalitaire suppose comme condition <em>sine qua non<\/em> un centre puissant, autoritaire, potentiellement totalitaire, etc., le contraire absolu de ce que cherche absolument <em>Tea Party<\/em>. Un signe de son action dissolutive de la structure-Syst\u00e8me en place, elle-m\u00eame d\u00e9j\u00e0 d&rsquo;essence totalitaire implicite et engendrant une action dissolutive du reste, c&rsquo;est le refus de <em>Tea Party<\/em> de se constituer en parti (<em>Party<\/em> n&rsquo;est pas parti), de refuser de sortir des structures du parti r\u00e9publicain, donc de poursuivre sa tactique de l&rsquo;entrisme, donc en se mettant en position, volontaire ou non qu&rsquo;importe, de tenter d&rsquo;\u00e9largir la contagion de la pouss\u00e9e centrifuge qui le caract\u00e9rise. <em>Tea Party<\/em> ne doit pas \u00eatre jug\u00e9 sur son simili programme, sur ses intentions de circonstance, sur ses professions de foi d&rsquo;un \u00e9conomisme extr\u00e9miste exacerb\u00e9, sur les liens de certains de ses nombreuses fractions avec le <em>business<\/em> qui de toutes les fa\u00e7ons p\u00e8se sur tous les groupes washingtoniens,  mais sur l&rsquo;effet objectif, c&rsquo;est-\u00e0-dire sur l&rsquo;effet <strong>r\u00e9el<\/strong> de son action. Durant la crise de la dette, <em>Tea Party<\/em> a \u00e9volu\u00e9, qu&rsquo;il le veuille ou non, qu&rsquo;il en ait conscience ou non, comme un <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_les_systemes_antisysteme_ddecrisis_17_01_2011.html\" class=\"gen\">syst\u00e8me antiSyst\u00e8me<\/a> attaquant le monstre d\u00e9structurant du syst\u00e8me washingtonien. Tout le reste est accessoire, secondaire, etc., et constitue plut\u00f4t l&rsquo;occasion d&rsquo;une vaine th\u00e9rapie par anath\u00e8me et tentatives d&rsquo;exorcisme des id\u00e9ologues du Syst\u00e8me. Car ceux-l\u00e0, les id\u00e9ologues-Syst\u00e8me, sont bien mal en point.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 2 ao\u00fbt 2011 \u00e0 07H41<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S&rsquo;il y a un article qui a fait quelque bruit dans le sens du sensationnalisme qu&rsquo;affectionne le syst\u00e8me de la communication, c&rsquo;est celui de l&rsquo;ancien parlementaire d\u00e9mocrate du Texas Mart\u00edn Frost, sur Politico.com le 29 juillet 2011. Passons aussit\u00f4t au contenu, qui est d&rsquo;assimiler Tea Party aux talibans. \u00abTen years ago, the Taliban in Afghanistan&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4646,3567,4099,3228,2631,5252,10119,9862,4118,2622,7069,3014,8256],"class_list":["post-73946","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-antisysteme","tag-business","tag-centrifuge","tag-crise","tag-de","tag-dette","tag-dissolution","tag-entrisme","tag-establishment","tag-la","tag-party","tag-systeme","tag-tea"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73946"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73946\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}