{"id":73947,"date":"2011-08-02T11:08:13","date_gmt":"2011-08-02T11:08:13","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/08\/02\/israeliens-indignes-eux-aussi\/"},"modified":"2011-08-02T11:08:13","modified_gmt":"2011-08-02T11:08:13","slug":"israeliens-indignes-eux-aussi","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/08\/02\/israeliens-indignes-eux-aussi\/","title":{"rendered":"Isra\u00e9liens indign\u00e9s, \u2013 eux aussi\u2026"},"content":{"rendered":"<p><p><em>Aljazeera.net<\/em>, d\u00e9pendant de la fameuse station TV \u00e0 la r\u00e9putation un peu ternie ces derniers mois par une politique \u00e9ditoriale qui \u00e9pouse un peu trop les int\u00e9r\u00eats politiques des dirigeants qataris, se rattrape lors qu&rsquo;il s&rsquo;agit d&rsquo;Isra\u00ebl. Ce qui a fait avec une couverture tr\u00e8s d\u00e9taill\u00e9e des \u00e9v\u00e9nements int\u00e9rieurs d&rsquo;Isra\u00ebl, dont on a commence \u00e0 avoir un \u00e9cho depuis les deux derni\u00e8res semaines, et qui, depuis samedi, commencent \u00e0 figurer d&rsquo;une fa\u00e7on int\u00e9ressante sur le sc\u00e8ne de la communication,  \u00e0 la rubrique, assez inattendue pour Isra\u00ebl, des indign\u00e9s, nom d\u00e9sormais g\u00e9n\u00e9rique de la col\u00e8re confuse mais clairement antiSyst\u00e8me des populations civiles.<\/p>\n<\/p>\n<p><p>\tD&rsquo;abord, <em>Aljazeera<\/em> a consacr\u00e9, le <a href=\"http:\/\/english.aljazeera.net\/programmes\/insidestory\/2011\/08\/201181101836750831.html\" class=\"gen\">1er ao\u00fbt 2011<\/a>, un programme TV au th\u00e8me inattendu de \u00ab<em>Has the Arab Spring arrived in Israel?<\/em>\u00bb. La pr\u00e9sentation du programme r\u00e9sume le propos imm\u00e9diat de l&rsquo;agitation nouvelle dans les rues isra\u00e9liennes, suivi des bonnes questions<\/p>\n<\/p>\n<p><p>\t\u00ab<em>More than 100,000 people took to the streets of 11 cities in Israel on Saturday to protest against the spiralling cost of living in the country. Protesters at the largest gatherings, in Tel Aviv, Jerusalem, Be&rsquo;er Sheva and Haifa, chanted the people demand social justice and we want justice, not charity.<\/em> [] <em>On this episode of Inside Story, we ask: Has the Arab Spring reached Israel? What are its root causes? Is it likely to affect Binyamin Netanyahu&rsquo;s grip on power? What impact will it have on Arab-Israelis?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tUne tr\u00e8s longue analyse d&rsquo;<em>Aljazeera.net<\/em> a \u00e9t\u00e9 \u00e9galement consacr\u00e9 \u00e0 ces \u00e9v\u00e8nements d&rsquo;Isra\u00ebl, le <a href=\"http:\/\/english.aljazeera.net\/indepth\/features\/2011\/07\/201173110175240835.html\" class=\"gen\">31 juillet 2011<\/a>. Elle met en \u00e9vidence les caract\u00e8res essentiellement int\u00e9rieurs, sociaux, du mouvement, mais aussi des caract\u00e8res qui ont une logique g\u00e9n\u00e9rale d\u00e9passant les fronti\u00e8res et s&rsquo;inscrivent <em>de facto<\/em>,  surprise, surprise,  dans une dynamique transnationale qui implique une opposition au Syst\u00e8me en g\u00e9n\u00e9ral ; qui pourrait effectivement s&rsquo;inspirer du soi disant printemps arabe, et s&rsquo;inscrire \u00e9ventuellement dans la structure de <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_chaine_crisique_ddecrisis_02_04_2011.html\" class=\"gen\">cha\u00eene crisique<\/a> de cet \u00e9v\u00e9nement (en m\u00eame temps certes que le mouvement dit des indign\u00e9s, en <a href=\"http:\/\/www.dedefensa.org\/article-des_indignes_pas_serieux_28_06_2011.html?admin=1\" class=\"gen\">Gr\u00e8ce<\/a>, en Espagne et ailleurs). <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Before summer, the prime minister of Israel was riding high, with an approval rating higher than 50 per cent. Though this threatened to be a long hot summer, there has been no war, third intifada or attack on Iran. Admired at home for standing up to the US president in Washington, Binyamin Netanyahu is now being stood down by the common man on the streets of Tel Aviv. The latest survey of public opinion in Israel shows Bibi&rsquo;s popularity, at 32 per cent, has taken a dive due to rapidly escalating housing protests.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>In the aftermath of feared Nakba, Naksa, Flotilla II and Flytilla protests on which the media and the defence-oriented, right-wing government had been fixated, tent cities have sprung up in dozens of locations around the country.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Tent cities have sprung up just 60 days before Palestinian envoys take their case to the world body at its annual gathering in New York. But top figures in the somewhat leaderless popular protest movement, as well as Israeli and Palestinian officials, are loath to conflate an internal Israeli problem with the Palestinian question.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>At Saturday&rsquo;s massive rallies  billed by the Ma&rsquo;ariv daily 150,000 in largest social protest in the history of the country  an unprecented number of Israelis marched across the country. Ordinary citizens expressed a sense of communal euphoria, and a glowing pride in the size of the new movement. They also chanted anti-Netanyahu refrains louder than the week prior on July 23.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>For several weeks, grassroots protesters from Tel Aviv and Jerusalem to Ashdod and Kiryat Shmona have been camping out in city centres and blocking streets. Marching on the prime minister&rsquo;s residence and chanting Bibi Habayta <\/em>[<em>Bibi, go home<\/em>] <em>and Netanyahu d\u00e9gage was unthinkable just last month, so the ruling coalition is looking increasingly vulnerable.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The problem uniting protesters hinges on real estate  a lack of urban housing at decent prices. That and the issue of the basic standard of living, tied to soaring costs for all sorts of goods, has energised previously apolitical citizens to clamour for change, united by a common sense of feeling ripped off. The rhythmic Hebrew slogans used at many of the protests are strikingly similar to punchy Arabic lines that have reverberated throughout the Middle East since January: Ha&rsquo;am doresh \/ tzedek chevrati <\/em>[<em>The people demand social justice<\/em>].\u00bb<\/p>\n<\/p>\n<p><p>\tOn trouve \u00e9galement dans ce texte un aspect int\u00e9ressant qui est une sp\u00e9culation sur les rapports, au niveau du syst\u00e8me de la communication, donc de la dynamique du mouvement et de son poids politique par cons\u00e9quent, entre ces \u00e9v\u00e9nements int\u00e9rieurs et les \u00e9v\u00e9nements de s\u00e9curit\u00e9 nationale. La vigueur des premiers d\u00e9pend de l&rsquo;effacement des seconds et, sans aucun doute, jugent certains, vice-versa. C&rsquo;est un aspect tr\u00e8s sp\u00e9cifique d&rsquo;Isra\u00ebl, o\u00f9 les questions de s\u00e9curit\u00e9 nationale ont une importance qui n&rsquo;a d&rsquo;\u00e9quivalent dans aucun autre pays. D&rsquo;autre part, existe un cas rarissime o\u00f9, au contraire, les \u00e9v\u00e9nements int\u00e9rieurs et un \u00e9v\u00e8nement de s\u00e9curit\u00e9 nationale pourraient additionner les effets, comme le note encore le texte de <em>Aljazeera.net<\/em> : les \u00e9v\u00e9nements int\u00e9rieurs en cours et la possible proclamation unilat\u00e9rale d&rsquo;un Etat palestinien.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>With calm borders, many commentators suggest the press needed a new focus, and protesters have the political space they need so as not to be accused of harming national security. Bibi&rsquo;s twin nightmares  a growing domestic housing crisis and the imminent push for Palestinian statehood at the UN in September  threaten to merge internal and external forces into a political colossus.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>If another intifada or a serious security flare up happens, then the<\/em> [<em>housing protests<\/em>] <em>could all end very quickly, the Jerusalem Post&rsquo;s Hartman says. The duration of the protests just depends on whether a serious enough &lsquo;foreign policy&rsquo; crisis distracts the media.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tNous avons n\u00e9cessairement pris l&rsquo;habitude de consid\u00e9rer Isra\u00ebl comme un avant-poste strat\u00e9gique, pour le meilleur et pour le pire selon le sentiment qu&rsquo;on en a, et pas comme un pays comme un autre. Cette habitude fait penser que le seul d\u00e9bat possible est de type s\u00e9curit\u00e9 nationale. De m\u00eame, elle fait consid\u00e9rer comme seule opposition s\u00e9rieuse \u00e0 l&rsquo;actuelle \u00e9quipe en place, et au parti de la guerre isra\u00e9lien, une pouss\u00e9e pacifiste comme il y eut au d\u00e9but des ann\u00e9es 1990, directement li\u00e9e, l\u00e0 encore, \u00e0 la situation de s\u00e9curit\u00e9 nationale. Les nouvelles de ces derniers jours mettent brusquement en question cette conviction. Elles nous font envisager que les Isra\u00e9liens sont aussi sensibles aux questions civiques en g\u00e9n\u00e9ral, y compris \u00e9conomiques, c&rsquo;est-\u00e0-dire, dans le climat actuel et les circonstances pr\u00e9sentes, les questions li\u00e9es \u00e0 l&rsquo;application d\u00e9vastatrice du Syst\u00e8me dans les conditions int\u00e9rieures. Soudain appara\u00eet la possibilit\u00e9 qu&rsquo;Isra\u00ebl soit un pays comme un autre, avec le d\u00e9veloppement d&rsquo;une puissante opposition, au niveau de l&rsquo;opinion publique, contre les conditions de vue impos\u00e9es par le Syst\u00e8me. (On ajoutera \u00e0 cela qu&rsquo;Isra\u00ebl est d&rsquo;autant plus un pays comme un autre qu&rsquo;il fut consid\u00e9r\u00e9 jusqu&rsquo;ici comme ne l&rsquo;\u00e9tant pas, y compris par les forces \u00e9conomiques pr\u00e9datrices, qui s&rsquo;y sont <a href=\"http:\/\/www.dedefensa.org\/article-israel_futur_failed_state__12_01_2009.html\" class=\"gen\">d\u00e9velopp\u00e9es<\/a> dans ce qu&rsquo;elles croyaient \u00eatre une totale impunit\u00e9,  pressions de s\u00e9curit\u00e9 nationale oblige,  jusqu&rsquo;\u00e0 faire de ce pays un compromis entre une structure mafieuse et Etat failli.)<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit d&rsquo;un d\u00e9veloppement potentiellement tr\u00e8s important, confirmant le renversement de tendance qui s&rsquo;op\u00e8re depuis 2007-2008 au niveau des structures internationales. De 2001 \u00e0 2007, il y eut donc la politique ext\u00e9rieure impos\u00e9e par la direction US, avec Isra\u00ebl comme suppl\u00e9tif, \u00e0 la suite de l&rsquo;attaque 9\/11 (politique notamment exprim\u00e9e sous forme de la fameuse <a href=\"http:\/\/www.dedefensa.org\/article-le_c_ur_du_sujet_29_05_2009.html\" class=\"gen\">politique<\/a> de l&rsquo;id\u00e9ologie et de l&rsquo;instinct, qui vient d&rsquo;ailleurs de plus loin que de 2001 et de 9\/11). Ce courant a \u00e9t\u00e9 frapp\u00e9 \u00e0 mort, d&rsquo;abord par la crise de l&rsquo;automne 2008, puis en 2010 par le basculement vers les <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_crise_eschatologique_ddecrisis_13_10_2010.html\" class=\"gen\">crises eschatologiques<\/a> (notamment celles qui sont li\u00e9es \u00e0 la crise environnementale). Le ph\u00e9nom\u00e8ne de la cha\u00eene crisique d\u00e9marr\u00e9 en d\u00e9cembre 2010 a renforc\u00e9 cette \u00e9volution. Depuis cette p\u00e9riode, la politique ext\u00e9rieure belliciste des ann\u00e9es 2001-2007 est devenue erratique, incoh\u00e9rente, plong\u00e9e dans un d\u00e9sordre profond que toutes les th\u00e8ses complotistes du monde ne parviennent plus \u00e0 organiser et \u00e0 pr\u00e9senter comme des effets des forces dissimul\u00e9es. L&rsquo;\u00e9l\u00e9ment isra\u00e9lien apparu ces derniers jours constitue alors un facteur consid\u00e9rable qui, s&rsquo;il est poursuivi et devient structurel, ach\u00e8vera de boucler compl\u00e8tement l&rsquo;\u00e9pisode 2001-2007. Il aura d&rsquo;autant plus d&rsquo;importance que des r\u00e9percussions consid\u00e9rables se feraient sentir, en r\u00e9action indirecte, notamment des effets sur les pressions internes du lobby isra\u00e9lien \u00e0 Washington, par cons\u00e9quent affaiblissant les derniers pans de la politique de 2001-2007 aux USA.<\/p>\n<\/p>\n<p><p>\tOn comprend,  le texte le dit d&rsquo;ailleurs clairement,  qu&rsquo;il s&rsquo;agit d&rsquo;un danger terrible pour Netanyahou et toute sa clique. Un tel mouvement est une possibilit\u00e9 s\u00e9rieuse qui peut mettre en question le carcan terroriste o\u00f9 la direction isra\u00e9lienne tient la population, lui imposant une coh\u00e9sion interne \u00e0 toutes forces sous le pr\u00e9texte des menaces pesant sur la s\u00e9curit\u00e9 nationale,  les pays arabes, le terrorisme, la bombe iranienne, la dialectique de l&rsquo;Holocauste et le reste. Il existe m\u00eame cette occurrence o\u00f9 le mouvement interne isra\u00e9lien peut ressurgir sur la politique ext\u00e9rieure, mais d&rsquo;une fa\u00e7on constructive, si une relation de renforcement mutuel est trouv\u00e9 avec la pouss\u00e9e palestinienne pour un Etats ind\u00e9pendant de septembre prochain. C&rsquo;est ce que le texte d&rsquo;<em>Aljazeera.net<\/em> d\u00e9signe comme le sc\u00e9nario de cauchemar de Netanyahou.  A l&rsquo;inverse, on peut \u00e9videmment envisager que cette situation int\u00e9rieure sera n\u00e9cessairement un argument de plus pour que Netanyahou cherche une diversion en politique ext\u00e9rieure, par un acte brutal ou l&rsquo;autre (mais on pense surtout \u00e0 une attaque contre l&rsquo;Iran). Simplement, la manuvre pr\u00e9sente des faiblesses \u00e9videntes, puisqu&rsquo;une d\u00e9nonciation du danger de l&rsquo;Iran sera de plus en plus per\u00e7ue, justement, comme une manuvre de diversion (cela, d&rsquo;autant plus qu&rsquo;il y a eu <a href=\"http:\/\/www.dedefensa.org\/article-9_11_en_septembre_2011_04_06_2011.html\" class=\"gen\">l&rsquo;intervention<\/a> de l&rsquo;ancien chef du <em>Mossad<\/em> Dagan contre cette attaque).<\/p>\n<\/p>\n<p><p>\tMais ceci, sous forme d&rsquo;hypoth\u00e8se que sugg\u00e8rent les \u00e9v\u00e8nements isra\u00e9liens, est certainement le plus important Si, dans les meilleures conditions envisageables, on pouvait assister \u00e0 un rapprochement entre Isra\u00ebl et les pays arabes de la r\u00e9gion par le biais d&rsquo;oppositions populaires de m\u00eame nature, on arriverait \u00e0 la potentialit\u00e9 d&rsquo;une situation extraordinaire. Le probl\u00e8me du Moyen Orient et le probl\u00e8me isra\u00e9lien \u00e9volueraient non pas \u00e0 cause de l&rsquo;\u00e9volution des probl\u00e8mes sp\u00e9cifiques vieux de plus d&rsquo;un demi-si\u00e8cle, mais \u00e0 cause des probl\u00e8mes caus\u00e9s par le Syst\u00e8me, par le biais de la globalisation et du reste, et qui seraient ainsi nouvellement r\u00e9alis\u00e9s. Il s&rsquo;agirait d&rsquo;une v\u00e9ritable int\u00e9gration de cette r\u00e9gion dans la probl\u00e9matique de la crise centrale du Syst\u00e8me qui, derri\u00e8re l&rsquo;\u00e9cran des vieilles probl\u00e9matiques g\u00e9opolitiques qu&rsquo;on voudrait prolonger \u00e0 toute force, d\u00e9chire en v\u00e9rit\u00e9 ce d\u00e9but du XXI\u00e8me si\u00e8cle.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 2 ao\u00fbt 2011 \u00e0 11H08<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aljazeera.net, d\u00e9pendant de la fameuse station TV \u00e0 la r\u00e9putation un peu ternie ces derniers mois par une politique \u00e9ditoriale qui \u00e9pouse un peu trop les int\u00e9r\u00eats politiques des dirigeants qataris, se rattrape lors qu&rsquo;il s&rsquo;agit d&rsquo;Isra\u00ebl. Ce qui a fait avec une couverture tr\u00e8s d\u00e9taill\u00e9e des \u00e9v\u00e9nements int\u00e9rieurs d&rsquo;Isra\u00ebl, dont on a commence \u00e0&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[6911,10859,5592,8294,4345,2774,2790,6136,3178,3014],"class_list":["post-73947","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-arabe","tag-chaine","tag-contestation","tag-crisique","tag-independance","tag-israel","tag-netanyahou","tag-palestine","tag-printemps","tag-systeme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73947"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73947\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}