{"id":73989,"date":"2011-08-17T16:18:13","date_gmt":"2011-08-17T16:18:13","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/08\/17\/et-si-je-vous-dis-moi-que-ron-paul-nexiste-pas\/"},"modified":"2011-08-17T16:18:13","modified_gmt":"2011-08-17T16:18:13","slug":"et-si-je-vous-dis-moi-que-ron-paul-nexiste-pas","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/08\/17\/et-si-je-vous-dis-moi-que-ron-paul-nexiste-pas\/","title":{"rendered":"Et si je vous dis, moi, que Ron Paul n&rsquo;existe pas\u2026"},"content":{"rendered":"<p><p>L&rsquo;affaire prend une tournure sympathique, comme si l&rsquo;on visionnait une version modernis\u00e9e de l&rsquo;immortel <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Vol_au-dessus_d'un_nid_de_coucou\" class=\"gen\">film<\/a> de Milos Forman, <em>Vol au-dessus d&rsquo;un nid de coucous<\/em>. Nous voulons dire par l\u00e0, nous, que la schizophr\u00e9nie les guette, eux, tous ces malheureux, qui retournent et retournent leurs stylos, et sauvegardent l&rsquo;article du temps pass\u00e9, du temps b\u00e9ni o\u00f9 Ron Paul n&rsquo;existait pas, pour constater qu&rsquo;il n&rsquo;est plus possible de s&rsquo;y tenir puisqu&rsquo;il semblerait que Ron Paul existe<\/p>\n<\/p>\n<p><p>\tIl est vrai, m\u00eame, que cette affaire commence \u00e0 avoir un nom g\u00e9n\u00e9rique (<em>Ron Paul Blackout<\/em>), ce qui est un bien mauvais signe. (Lorsqu&rsquo;un nom g\u00e9n\u00e9rique s&rsquo;impose, on n&rsquo;est plus tr\u00e8s loin d&rsquo;une crise, les m\u00e9dias ayant \u00e0 leur disposition le mot de passe dialectique qui leur permet de discourir de la chose,  m\u00eame si cette chose est faite pour acter leur propre schizophr\u00e9nie.) C&rsquo;est dans tous les cas le titre des 4 minutes 23 secondes d&rsquo;intervention de l&rsquo;irr\u00e9sistible Jon Stewart, ce <a href=\"http:\/\/vimeo.com\/27757870\" class=\"gen\">15 ao\u00fbt 2011<\/a>, sous le titre effectivement de <em>Ron Paul Blackout<\/em>. \u00ab<em>Jon Stewart&rsquo;s takedown of the Ron Paul media blackout is devastating, and, for the most part, funny<\/em>\u00bb, \u00e9crit Justin Raimondo, dans sa chronique du <a href=\"http:\/\/original.antiwar.com\/justin\/2011\/08\/16\/the-media-is-the-enemy\/\" class=\"gen\">17 ao\u00fbt 2011<\/a> sur <em>Antiwar.com<\/em>.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est qu&rsquo;effectivement, l&rsquo;affaire devient si grossi\u00e8re qu&rsquo;elle commence \u00e0 int\u00e9resser la presse elle-m\u00eame, y compris la presse-Syst\u00e8me, qui se trouve donc en position de se piquer de son aiguillon empoisonn\u00e9, comme dit la l\u00e9gende (largement suspecte et contredite) \u00e0 propos du scorpion Le titre pourrait \u00eatre : Quel scandale ! Pourquoi ne parlons-nous pas de Ron Paul ? Si ce n&rsquo;est de la schizophr\u00e9nie, c&rsquo;est dans tous les cas dans la bonne voie. (Cela nous dirait alors que, d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, plus que jamais et d&rsquo;une fa\u00e7on de plus en plus assur\u00e9e, la dynamique de surpuissance du Syst\u00e8me s&rsquo;est mise au service de sa dynamique d&rsquo;autodestruction.)<\/p>\n<\/p>\n<p><p>\t Paul Harris, par exemple, dans le <em>Guardian<\/em> du <a href=\"http:\/\/www.guardian.co.uk\/commentisfree\/cifamerica\/2011\/aug\/16\/ron-paul-media-bias\" class=\"gen\">16 ao\u00fbt 2011<\/a>, consacre un article scandalis\u00e9 \u00e0 l&rsquo;affaire. \u00ab<em>For the last few days, the American media and political classes have been debating the fallout from the Ames straw poll <\/em>[bla bla bla] <em>But what of Ron Paul, who came second?<\/em>\u00bb Harris ajoute m\u00eame, ce qui est tout \u00e0 fait juste \u00e0 notre estime : \u00ab<em>If Paul had got an extra 153 votes and actually won, I bet the analysis would have stayed the same. Paul would have been dismissed as a no hoper and Bachmann&rsquo;s second place would still have been hailed as the real breakthrough.<\/em>\u00bb  <\/p>\n<\/p>\n<p><p>\tEnsuite, Paul Harris, respect\u00e9 correspondant principal du <em>Guardian<\/em> aux USA, expose le cas du <em>Ron Paul Blackout<\/em>, dans des termes qu&rsquo;on jugerait presque audacieux, renvoyant \u00e0 d&rsquo;autres chroniques moins centr\u00e9es sur Paul du m\u00eame journal. Cette fois, Ron Paul, libertarien US souvent class\u00e9 \u00e0 l&rsquo;extr\u00eame droite, est bien la vedette de cet article de ce journal britannique de centre gauche<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Unlike other candidates from both parties  who tack left and right as the polls tell them  Paul has held his beliefs for years and does not change them to suit a focus group. He has principles and stands by them. This makes Paul admirable even when you disagree with him (as I mostly do). It also makes Paul the one thing that American media and political elites of all stripes can&rsquo;t stand: a genuine outsider.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>This is especially true for foreign policy. Paul&rsquo;s outspokenness on America&rsquo;s wars abroad and troubles with Iran are a prime example. During the last GOP debate, Paul spoke angrily in favour of leaving Iran alone and played down the threat of Tehran&rsquo;s nuclear ambitions. He also made reference to the US-backed coup in Iran that overthrew democratically-elected Prime Minister Mohammad Mosaddeq in 1953. We started it in 1953 when we sent in a coup, installed the Shah  it&rsquo;s been going on and on because we just plain don&rsquo;t mind our own business. That&rsquo;s our problem! Paul said, showing he knew his Middle East history.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>But, of course, no politicians or journalists are interested in that history<\/em> [] <em>Meanwhile, Paul is portrayed as the crazy uncle at the family party. Which is a tragedy. Paul likely won&rsquo;t win the 2012 nomination. His support is solid, enthusiastic, but hard to see growing very broad. But to cast him as a fringe weirdo says far more about the biases and idiocy of the media and his political rivals than it does about Paul.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Revenons un instant \u00e0 Justin Raimondo, dans sa chronique d\u00e9j\u00e0 mentionn\u00e9e du <a href=\"http:\/\/original.antiwar.com\/justin\/2011\/08\/16\/the-media-is-the-enemy\/\" class=\"gen\">17 ao\u00fbt 2011<\/a>. Raimondo tire \u00e0 boulets rouges sur la presse-Syst\u00e8me, cite les uns et les autres en grand nombre (article de Raimondo \u00e9galement pr\u00e9cieux \u00e0 consulter pour le nombre de liens r\u00e9f\u00e9renc\u00e9s). Il met en \u00e9vidence les grossi\u00e8res contradictions des commentateurs-Syst\u00e8me occup\u00e9s \u00e0 descendre Paul en flammes, avec des arguments totalement contradictoires ; ce Aaron Blake, par exemple, du Washington <em>Post<\/em>, le <a href=\"http:\/\/www.washingtonpost.com\/blogs\/the-fix\/post\/ron-paul-campaign-virtually-zero-chance-of-third-party-bid\/2011\/08\/15\/gIQAZvC2IJ_blog.html#pagebreak\" class=\"gen\">16 ao\u00fbt 2011<\/a>, qui ne donne aucune chance \u00e0 Ron Paul d&rsquo;\u00eatre d\u00e9sign\u00e9 par le parti r\u00e9publicain, parce que, explique-t-il, il (Paul) est anti-guerre et que cette position va contre le courant populaire des r\u00e9publicains,  cela avant d&rsquo;ajouter quelques lignes plus loin, que le soutien populaire notable qu&rsquo;il (Paul) a r\u00e9ussi \u00e0 constituer vient d&rsquo;une augmentation du sentiment anti-guerre chez les r\u00e9publicains. Cela permet \u00e0 Raimondo de poursuivre sur ce th\u00e8me que Ron Paul est l\u00e0 pour s&rsquo;affirmer avec une force grandissante, que cela est un signe que des changements fondamentaux ont lieu souterrainement, qui prennent m\u00eame Ron Paul par surprise.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Either Paul&rsquo;s anti-interventionist views virtually rule him out as a potential GOP presidential nominee, or else his views benefit him  Blake can&rsquo;t have it both ways. That he&rsquo;s desperately trying to is evidence of some confusion, as well as an ingrained bias. Confusion because journalists are not omniscient: they&rsquo;re just ordinary people, who often don&rsquo;t have the foresight to see new trends developing even as they are occurring  although you&rsquo;d think that would be the core of a reporter&rsquo;s job, especially one who specializes in politics. The breakdown of the right-left, red-blue, Fox-MSNBC paradigm is an ongoing process, one bound to take unexpected turns  and take many by surprise, up to and including those, like Paul, in the forefront of this trend.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>I don&rsquo;t think anyone has been more astonished by his success than Ron Paul. He is clearly thrilled at the sight of thousands of young people cheering him on and chanting End the Fed! at campus rallies across the nation. I don&rsquo;t think he expected the outpouring of support that greeted his announcement: in fundraising capabilities alone, he&rsquo;s a top tier candidate no matter what the Beltway pundits say<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tTout cela nous donne un paysage assez vari\u00e9, qui commence \u00e0 montrer combien Ron Paul est un formidable agitateur, un formidable <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_les_systemes_antisysteme_ddecrisis_17_01_2011.html\" class=\"gen\">syst\u00e8me antiSyst\u00e8me<\/a>. Plus encore : en consultant Raimondo et la multitude de liens que r\u00e9f\u00e9rence son article, en lisant l&rsquo;article de Harris, on est conduit \u00e0 se demander si la schizophr\u00e9nie qu&rsquo;impose le Syst\u00e8me \u00e0 ses serviteurs n&rsquo;est pas en train de d\u00e9boucher sur une sorte de joyeuse explosion de contradictions, conduisant au r\u00e9sultat inverse de celui qui est, suppose-t-on, recherch\u00e9 Aaron Blake, vilipend\u00e9 par Raimondo, \u00e9crit tout de m\u00eame en t\u00eate de son article : \u00ab<em>Paul&rsquo;s showing at the Ames Straw Poll on Saturday  he came within 200 votes or so of winning  has<\/em> <strong><em>forced<\/em><\/strong> <em>people to take notice of his campaign.<\/em>\u00bb Cette phrase signifie apr\u00e8s tout que Harris, Jon Steward et Justin Raimondo, et d&rsquo;autres, s&rsquo;il ont \u00e9videmment raison, n&rsquo;ont d\u00e9j\u00e0 plus tout \u00e0 fait raison, parce qu&rsquo;il y a peut-\u00eatre une sorte de courant de communication qui est en train de pousser vers des situations inattendues, o\u00f9 tout le monde en viendrait \u00e0 d\u00e9battre de ce qui fait que personne, y compris soi-m\u00eame, ne parle de Ron Paul comme il est \u00e9vident qu&rsquo;il faudrait en parler (Et nous-m\u00eames, jusqu&rsquo;\u00e0 un certain point, nous serions d\u00e9mentis lorsque nous constations ce <em>blackout<\/em> Quoique nous ayons <a href=\"http:\/\/www.dedefensa.org\/article-la_presse-systeme_et_ron_paul_apres_sa_confirmation_de_l_iowa_14_08_2011.html\" class=\"gen\">montr\u00e9<\/a> que nous doutions d\u00e9sormais de l&rsquo;intangibilit\u00e9 de ce verdict de <em>blackout<\/em> et envisagions effectivement que la vraie situation politique pourrait imposer sa loi : \u00ab<em>Par cons\u00e9quent, <\/em>[avec son r\u00e9sultat dans l&rsquo;Iowa] <em>celui qui \u00e9tait en maintes occurrences un non-\u00eatre et un non-candidat a forc\u00e9 le syst\u00e8me de la communication \u00e0 admettre qu&rsquo;il existe bel et bien, en chair et en os, et en nombre de votes. Par cons\u00e9quent, la presse-Syst\u00e8me est oblig\u00e9e de r\u00e9agir.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tSi, demain, l&rsquo;affaire <em>Ron Paul Blackout<\/em> devient une sorte de crise dans le petit monde du syst\u00e8me de la communication, peut-\u00eatre va-t-on se mettre \u00e0 \u00e9crire en abondance consid\u00e9rable, \u00e0 propos de Ron Paul, sur le fait de savoir pourquoi et comment personne ne parle de Ron Paul. Ainsi serait-on conduit \u00e0 d\u00e9battre des probl\u00e8mes dont on ne veut pas d\u00e9battre et dont Ron Paul d\u00e9bat, par exemple de la justification des guerres que conduisent les USA et le bloc BAO, puisqu&rsquo;il faudra bien explorer les raisons pour lesquelles on ne parle pas de Ron Paul. Ainsi la presse-Syst\u00e8me, qui se trouve elle-m\u00eame plong\u00e9e dans les contradictions de son autocensure-Syst\u00e8me et de ses mots d&rsquo;ordre humanistes \u00e9galement exig\u00e9s par le Syst\u00e8me, sur la libert\u00e9 d&rsquo;expression, sur la d\u00e9mocratie et toutes cette sorte de choses, se trouverait-elle conduite dans un d\u00e9bat o\u00f9, en d\u00e9battant sur l&rsquo;absence de d\u00e9bat \u00e0 propos de Ron Paul, elle d\u00e9battrait \u00e0 propos de sa propre schizophr\u00e9nie. Ainsi avons-nous la confirmation que le plus grand int\u00e9r\u00eat de Ron Paul n&rsquo;est certes pas dans son programme, dans son \u00e9ventuelle conqu\u00eate du pouvoir, dans son \u00e9ventuelle d\u00e9signation comme candidat r\u00e9publicain, mais dans tous les brandons incandescents qu&rsquo;il s\u00e8me autour de lui et qui d\u00e9clenchent des d\u00e9bats dont personne ne voulait entendre parler.<\/p>\n<\/p>\n<p><p>\tNous ne doutons pas une seule seconde, si Ron Paul continue son parcours, que le commentaire de la presse-Syst\u00e8me, en plus des diverses crises de nerf washingtoniennes, ressemblera de plus en plus \u00e0 une conversation extraite d&rsquo;une version mise au go\u00fbt du jour de <em>Vol au-dessus d&rsquo;un nid de coucous<\/em>. Cet immortel <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Vol_au-dessus_d'un_nid_de_coucou\" class=\"gen\">film<\/a> de Milos Forman le m\u00e9riterait bien, et nous aussi.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 17 ao\u00fbt 2011 \u00e0 16H19<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;affaire prend une tournure sympathique, comme si l&rsquo;on visionnait une version modernis\u00e9e de l&rsquo;immortel film de Milos Forman, Vol au-dessus d&rsquo;un nid de coucous. Nous voulons dire par l\u00e0, nous, que la schizophr\u00e9nie les guette, eux, tous ces malheureux, qui retournent et retournent leurs stylos, et sauvegardent l&rsquo;article du temps pass\u00e9, du temps b\u00e9ni o\u00f9&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[11404,8672,4270,11406,11405,2631,4385,7340,7856,3570,6325,3140,3340,11299,3310,4584],"class_list":["post-73989","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-au-dessus","tag-autocensure","tag-autodestruction","tag-coucous","tag-dun","tag-de","tag-harris","tag-iowa","tag-justin","tag-medias","tag-nid","tag-paul","tag-presidentielles","tag-raimondi","tag-ron","tag-vol"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73989"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73989\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}