{"id":74023,"date":"2011-08-30T18:54:47","date_gmt":"2011-08-30T18:54:47","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/08\/30\/letrange-triangle-paris-tripoli-alger-a-lombre-du-printemps-arabe\/"},"modified":"2011-08-30T18:54:47","modified_gmt":"2011-08-30T18:54:47","slug":"letrange-triangle-paris-tripoli-alger-a-lombre-du-printemps-arabe","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/08\/30\/letrange-triangle-paris-tripoli-alger-a-lombre-du-printemps-arabe\/","title":{"rendered":"L&rsquo;\u00e9trange triangle Paris-Tripoli-Alger, \u00e0 l&rsquo;ombre du \u201cprintemps arabe\u201d"},"content":{"rendered":"<p><p>Le nouveau gouvernement libyen, qui n&rsquo;est ni vraiment gouvernement, ni encore en place, bien qu&rsquo;il soit largement reconnue par le bloc BAO et la masse des suiveurs, a d\u00e9j\u00e0 une m\u00e9chante affaire sur les bras. La nouveaut\u00e9 du cas est qu&rsquo;il s&rsquo;agit d&rsquo;une querelle internationale, qui pourrait, en r\u00eavant un peu, nous conduire \u00e0 une tension internationale quasiment belliciste avant que le gouvernement n&rsquo;exist\u00e2t.<\/p>\n<\/p>\n<p><p>\tLe fait principal est que la famille Kadhafi (sa femme, sa fille, deux de ses fils et leurs enfants) sont pass\u00e9s en Alg\u00e9rie avec l&rsquo;accord complet et m\u00eame, nous semble-t-il, ostensiblement affich\u00e9 des autorit\u00e9s alg\u00e9riennes. (Voir le <em>Guardian<\/em> du <a href=\"http:\/\/www.guardian.co.uk\/world\/2011\/aug\/29\/gaddafi-family-escape-libya-algeria\" class=\"gen\">29 ao\u00fbt 2011<\/a>.) La r\u00e9action des rebelles a \u00e9t\u00e9 violente, avec l&rsquo;exigence d&rsquo;un retour imm\u00e9diat de la famille Kadhafi en Libye, et l&rsquo;accusation que l&rsquo;attitude de l&rsquo;Alg\u00e9rie constituait un acte d&rsquo;agression contre la Libye lib\u00e9r\u00e9e. Reuters a interrog\u00e9 le porte-parole du CNT sur cette question, le <a href=\"http:\/\/www.reuters.com\/article\/2011\/08\/30\/us-libya-idUSTRE77A2Y920110830\" class=\"gen\">30 ao\u00fbt 2011<\/a>.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Algeria&rsquo;s acceptance of Gaddafi&rsquo;s wife and offspring angered the rebel leadership, who want him and his entourage to face justice for years of repressive rule and who fear that he could orchestrate a new insurgency unless he is captured.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>We have promised to provide a just trial to all those criminals and therefore we consider this an act of aggression, spokesman Mahmoud Shamman told Reuters. We are warning anybody not to shelter Gaddafi and his sons. We are going after them &#8230; to find them and arrest them. We have heard that Algeria will harbor them till they go to another country. They are trying to go to another country, possibly an east European country, he said.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>NTC chairman Mustafa Abdel Jalil called on the Algerian government  which has not recognized the council as Libya&rsquo;s legitimate authority  to cooperate with it and hand over any of Gaddafi&rsquo;s sons on its wanted list.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDu c\u00f4t\u00e9 alg\u00e9rien, l&rsquo;attitude semble \u00e0 la fois ferme et r\u00e9solue, et en quelque sorte d\u00e9fiante par rapport aux rebelles libyens et \u00e0 leurs exigences. En plus de la stricte affaire du passage de la famille Kadhafi en Alg\u00e9rie, il y a l&rsquo;annonce de la fermeture de la fronti\u00e8re alg\u00e9rienne avec la Libye, et de l&rsquo;\u00e9tat d&rsquo;alerte qui y est instaur\u00e9e, dans une posture qu&rsquo;il est difficile de ne pas distinguer comme cette m\u00eame d\u00e9fiance qui confinerait \u00e0 l&rsquo;hostilit\u00e9. Le site <em>Elwatan.com<\/em> donne quelques pr\u00e9cisions \u00e0 ce propos, ce <a href=\"http:\/\/www.elwatan.com\/une\/l-algerie-va-fermer-partiellement-sa-frontiere-avec-la-libye-30-08-2011-138124_108.php\" class=\"gen\">30 ao\u00fbt 2011<\/a>. On notera le ton de l&rsquo;\u00e9change \u00e0 distance entre le porte-parole du CNT et le minist\u00e8re alg\u00e9rien des affaires \u00e9trang\u00e8res.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>C&rsquo;est l&rsquo;alerte g\u00e9n\u00e9rale \u00e0 la fronti\u00e8re terrestre alg\u00e9ro-libyenne. L&rsquo;Etat alg\u00e9rien a d\u00e9cid\u00e9 unilat\u00e9ralement de fermer la partie extr\u00eame sud de la fronti\u00e8re terrestre avec la Libye, mettant en branle tous ses services de s\u00e9curit\u00e9, apprend-on de sources diplomatiques alg\u00e9riennes.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb[Cette d\u00e9cision intervient] <em>apr\u00e8s l&rsquo;annonce de l&rsquo;\u00e9limination de cinq individus arm\u00e9s non identifi\u00e9s qui auraient travers\u00e9 la fronti\u00e8re alg\u00e9rienne. Aussi, quarante-huit heures plus t\u00f4t, le chef d&rsquo;\u00e9tat- major de l&rsquo;Arm\u00e9e nationale populaire, Ahmed Ga\u00efd Salah, \u00e9tait \u00e0 la fronti\u00e8re libyenne o\u00f9 il a inspect\u00e9 le d\u00e9ploiement des services militaires \u00e0 la limite du territoire sud-est alg\u00e9rien. La fermeture de cette fronti\u00e8re terrestre, dans sa partie extr\u00eame sud avec la Libye, est la deuxi\u00e8me du genre apr\u00e8s la d\u00e9cision, en 1994, de la fermeture de la fronti\u00e8re avec la monarchie marocaine. Avant-hier, Ahmed Omar Bani, porte-parole militaire des insurg\u00e9s libyens, a d\u00e9clar\u00e9, lors d&rsquo;une conf\u00e9rence de presse organis\u00e9e \u00e0 Benghazi, que l&rsquo;Alg\u00e9rie devra r\u00e9pondre de son attitude \u00e0 l&rsquo;\u00e9gard de la r\u00e9bellion. Le lendemain, le minist\u00e8re des Affaires \u00e9trang\u00e8res a d\u00e9clar\u00e9 que les propos irresponsables et irr\u00e9v\u00e9rencieux tenus par ce personnage ne m\u00e9ritent ni consid\u00e9ration ni commentaire.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tPour l&rsquo;instant, il s&rsquo;agit de d\u00e9sordre et de la mont\u00e9e d&rsquo;une certaine tension, sans qu&rsquo;on puisse d\u00e9brouiller les possibilit\u00e9s d&rsquo;aggravation et d&rsquo;extension de la querelle. Il n&#8217;emp\u00eache que l&rsquo;hostilit\u00e9 entre les deux partis est palpable, visc\u00e9rale, d&rsquo;ailleurs avec des disparit\u00e9s troublantes. (Les propos du porte-parole militaire Ahmed Omar Bani, \u00e0 la limite de la menace, tr\u00e8s diff\u00e9rents de ceux du pr\u00e9sident du CNT, tandis que la r\u00e9ponse du minist\u00e8re des affaires \u00e9trang\u00e8res alg\u00e9rien \u00e0 Bani est extr\u00eamement abrupte et m\u00e9prisante ; comme Bani est porte-parole <strong>militaire<\/strong>, certains, du c\u00f4t\u00e9 alg\u00e9rien, pourraient juger qu&rsquo;il a quelque chose d&rsquo;islamiste dans ses propos&#8230;)<\/p>\n<\/p>\n<p><p>\tIl n&#8217;emp\u00eache, il y a une vraie circonstance qui a une apparence symbolique de <em>casus belli<\/em>, qui est la pr\u00e9sence de la famille Kadhafi en Alg\u00e9rie. Des deux c\u00f4t\u00e9s, la position est radicale, et il sera difficile \u00e0 l&rsquo;un ou l&rsquo;autre des deux partis de reculer sans essuyer une humiliation politique dont l&rsquo;un et l&rsquo;autre partis ne veulent pas entendre parler. D&rsquo;autre part, si les Alg\u00e9riens ont agi de cette fa\u00e7on, on pourrait croire qu&rsquo;ils sont d\u00e9termin\u00e9s \u00e0 \u00e9tablir entre les rebelles libyens et eux des tensions officielles qui ne rel\u00e8vent pas de la seule mise en sc\u00e8ne folklorique, mais bien du rapport de force. Et ainsi de suite, dans le registre de l&rsquo;aggravation, volontaire ou pas.<\/p>\n<\/p>\n<p><p>\tL\u00e0-dessus, on peut disserter plus pr\u00e9cis\u00e9ment sur la position d&rsquo;une des nations intervenantes, membres de l&rsquo;OTAN, meneuse de l&rsquo;affaire et triomphatrice \u00e0 l&rsquo;image de son pr\u00e9sident, nation avec des liens si particuliers avec l&rsquo;Alg\u00e9rie, avec une tr\u00e8s forte communaut\u00e9 alg\u00e9rienne sur son territoire, et ainsi de suite l\u00e0 aussi. La France, porte-drapeau de la lib\u00e9ration de la Libye par rebelles interpos\u00e9s, ce qui constitue une excellente trouvaille de son pr\u00e9sident pour tenter de parvenir \u00e0 se hausser au niveau de certains attributs de sa fonction, la France est tout de m\u00eame dans une position bien particuli\u00e8re dans ce cas. Les relations de la France avec l&rsquo;Alg\u00e9rie sont historiques, d\u00e9licates et tr\u00e8s importantes, les relations de la France avec la Libye <em>new age<\/em> sont venues de nulle part dans l&rsquo;histoire et sont proclam\u00e9es dans l&rsquo;instant comme formidables. Si ce n&rsquo;est l&rsquo;amorce d&rsquo;un imbroglio diplomatique plein de chausse-trappes, cela y ressemble fort.<\/p>\n<\/p>\n<p><p>\tLa principale le\u00e7on \u00e9tant que l&rsquo;affaire libyenne et le printemps arabe ne cessent de nous r\u00e9server bien des surprises, dans le cours desquelles il est difficile de se retrouver. Un analyste politique bien inform\u00e9 se demanderait qui est le plus infr\u00e9quentable, en termes de morale politique, d&rsquo;intelligence diplomatique, de psychologie politique, entre le r\u00e9gime d\u00e9chu du colonel Kadfhafi, les rebelles libyens, le r\u00e9gime alg\u00e9rien, le pr\u00e9sident fran\u00e7ais si agit\u00e9. Il aurait du mal \u00e0 trancher. L&rsquo;Alg\u00e9rie pourrait se dire qu&rsquo;une bonne crise avec la Libye <em>new age<\/em> qu&rsquo;elle d\u00e9teste avant m\u00eame qu&rsquo;elle n&rsquo;existe, serait une bonne fa\u00e7on de ressouder une unit\u00e9 nationale si perturb\u00e9e par le printemps arabe suivant des d\u00e9cennies de dictature corrompue et g\u00e9rontocratique du parti \u00e9videmment unique et r\u00e9volutionnaire. Il n&rsquo;est pas assur\u00e9 que l&rsquo;OTAN ait des plans pr\u00e9par\u00e9s pour l&rsquo;invasion de l&rsquo;Alg\u00e9rie. Il n&rsquo;est pas assur\u00e9 non plus que l&rsquo;Alg\u00e9rie ne songe pas \u00e0 pr\u00eater main forte \u00e0 ce qu&rsquo;il reste du colonel Kadhafi et de ses troupes. Les lib\u00e9raux interventionnistes qui croient encore \u00e0 leur chansonnette d\u00e9mocratique, croient que l&rsquo;Alg\u00e9rie, en se d\u00e9couvrant si hostile \u00e0 la Libye <em>new age<\/em>, a choisi le mauvais c\u00f4t\u00e9 de l&rsquo;Histoire (\u00ab<em>By giving the Gaddafi family refuge, Algeria&rsquo;s gerontocracy is putting itself on the wrong side of history<\/em>\u00bb, selon Brian Whitacker, du <em>Guardian<\/em>, le <a href=\"http:\/\/www.guardian.co.uk\/commentisfree\/2011\/aug\/30\/arab-uprising-algeria-next\" class=\"gen\">30 ao\u00fbt 2011<\/a>) ; pauvre Histoire, que ne lui fait-on pas dire&#8230; Il s&rsquo;en d\u00e9duit que rien n&rsquo;est assur\u00e9 en Libye et alentour, \u00e0 l&rsquo;heure du printemps arabe.<\/p>\n<\/p>\n<p><p>\tPour l&rsquo;instant, il s&rsquo;agit de d\u00e9sordre, \u00e9crivions-nous plus haut ; mais quand c&rsquo;est fini, n-i ni ni, \u00e7a recommence, et plus \u00e7a change, plus c&rsquo;est la m\u00eame chose Ainsi en est-il de la r\u00e8gle d&rsquo;or du printemps arabe et de cette \u00e9trange \u00e9poque, o\u00f9 \u00e0 chaque \u00e9v\u00e9nement, le d\u00e9sordre semble acqu\u00e9rir encore plus d&rsquo;esprit pour trouver encore mieux en mati\u00e8re de d\u00e9sordre.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 30 ao\u00fbt 2011 \u00e0 18H52<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le nouveau gouvernement libyen, qui n&rsquo;est ni vraiment gouvernement, ni encore en place, bien qu&rsquo;il soit largement reconnue par le bloc BAO et la masse des suiveurs, a d\u00e9j\u00e0 une m\u00e9chante affaire sur les bras. La nouveaut\u00e9 du cas est qu&rsquo;il s&rsquo;agit d&rsquo;une querelle internationale, qui pourrait, en r\u00eavant un peu, nous conduire \u00e0 une&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[5917,2735,6911,2825,3356,10891,6902,3256,3178],"class_list":["post-74023","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-age","tag-algerie","tag-arabe","tag-democratie","tag-desordre","tag-kadhafi","tag-libye","tag-new","tag-printemps"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74023"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74023\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}