{"id":74056,"date":"2011-09-13T14:26:49","date_gmt":"2011-09-13T14:26:49","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/09\/13\/notes-sur-la-dissolution-du-monde-ddecrisis\/"},"modified":"2011-09-13T14:26:49","modified_gmt":"2011-09-13T14:26:49","slug":"notes-sur-la-dissolution-du-monde-ddecrisis","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/09\/13\/notes-sur-la-dissolution-du-monde-ddecrisis\/","title":{"rendered":"Notes sur la dissolution du monde (<em>dde.crisis<\/em>)"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Notes sur la dissolution du monde (<em>dde.crisis<\/em>)<\/h2>\n<\/p>\n<p><p>Le num\u00e9ro du <a class=\"gen\" href=\"http:\/\/www.edde.eu\/publication-ddecrisis_du_10_septembre_2011.html\">10 septembre 2011<\/a> de <em>dde.crisis<\/em> a comme sujet \u00ab\u00a0la dissolution du monde\u00a0\u00bb. Le traitement de ce sujet concerne un mouvement puissant et syst\u00e9matique de fragmentation qui affecte la constitution formelle du monde.<\/p>\n<\/p>\n<p><p>Nous consid\u00e9rons que, sous la pouss\u00e9e \u00e0 la fois de politiques tr\u00e8s violentes (notamment ce que nous d\u00e9signons comme la \u00ab\u00a0<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-le_c_ur_du_sujet_29_05_2009.html\">politique<\/a> de l&rsquo;id\u00e9ologie et de l&rsquo;instinct\u00a0\u00bb du syst\u00e8me de l&rsquo;am\u00e9ricanisme) et des crises end\u00e9miques qui en furent l&rsquo;effet partiel, a exist\u00e9 d&rsquo;abord un tr\u00e8s rapide mouvement de d\u00e9structuration, s\u00e9parant et affaiblissant les diverses structures politiques, sociales et \u00e9conomiques existantes, et affaiblissant d&rsquo;autant la structuration des psychologies elles-m\u00eames. Cette phase en tant que telle s&rsquo;est termin\u00e9e en 2008-2009, c\u00e9dant la place \u00e0 une nouvelle phase o&ugrave; la dynamique de d\u00e9structuration est renforc\u00e9e, \u00ab\u00a0doubl\u00e9e\u00a0\u00bb en quelque sorte, par un mouvement de fragmentation et d&rsquo;atomisation de ces structures d\u00e9j\u00e0 elles-m\u00eames en crise. C&rsquo;est ce que nous nommons le mouvement de dissolution.<\/p>\n<\/p>\n<p><p>Nous citons <em>dde.crisis<\/em> (autres citations, \u00e9galement extraites du num\u00e9ro, sauf lorsqu&rsquo;il en en est pr\u00e9cis\u00e9 autrement) :<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>L&rsquo;\u00e9t\u00e9 2011 nous a confirm\u00e9 dans l&rsquo;assurance que nous nous trouvions dans ce que nous pourrions nommer un \u00ab\u00a0cycle crisique\u00a0\u00bb, avec l&rsquo;int\u00e9gration d&rsquo;une structure crisique, &ndash; l&rsquo;existence structurelle de crises permanentes, &ndash; et d&rsquo;une dynamique de cha&icirc;ne crisique, &ndash; l&rsquo;existence de forces conduisant \u00e0 la prolif\u00e9ration des crises selon des processus de communication et autres ph\u00e9nom\u00e8nes soft ne n\u00e9cessitant pas de violence ou de d\u00e9sordres selon l&rsquo;entendement coutumier de ces termes ; ou bien, parlerions-nous de \u00ab\u00a0violences\u00a0\u00bb ou de \u00ab\u00a0d\u00e9sordres\u00a0\u00bb de ces types nouveaux qui nous correspondent bien, que ce soit la flamb\u00e9e nihiliste de violence barbare au Royaume-Uni, que ce soit l&rsquo;extraordinaire mouvement des \u00ab\u00a0indign\u00e9s\u00a0\u00bb isra\u00e9liens, inspir\u00e9 du \u00ab\u00a0printemps arabe\u00a0\u00bb et des divers cas europ\u00e9ens du domaine (Espagne, Gr\u00e8ce).<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Ce qui nous a paru \u00e9vident comme constat intuitif, et qui soutient \u00e9videmment notre r\u00e9flexion, c&rsquo;est le lien qu&rsquo;il faut \u00e9tablir entre tous ces mouvements, flamb\u00e9es, crises classiques ou pas, etc. Aujourd&rsquo;hui, plus rien ne peut plus \u00eatre s\u00e9par\u00e9 de rien ; il y a l\u00e0 une logique mondiale en marche, sorte de globalisation retourn\u00e9e contre les instigateurs-Syst\u00e8me de la chose ; et une logique mondiale qui ressort d&rsquo;une crise g\u00e9n\u00e9rale de civilisation, ou de notre contre-civilisation pour mieux dire, donc qui constitue une attaque frontale contre le Syst\u00e8me&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Plut\u00f4t GC3 que GDFC2<\/h3>\n<\/p>\n<p><p>Dans un <em>Faits &#038; Commentaires<\/em> du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article\/la-crise-ferale-phase-gfc2-pour-les-amis\">4 ao&ucirc;t 2011<\/a>, nous pr\u00e9sentions des acronyme nouveaux pour d\u00e9finir l&rsquo;\u00e9tat des crises que nous enregistrions \u00e0 cette p\u00e9riode de juillet-ao&ucirc;t 2011. Ces acronymes, avec leur signification, permettent \u00e9videmment de r\u00e9sumer l&rsquo;essentiel de notre appr\u00e9ciation du ph\u00e9nom\u00e8ne que nous tentons de d\u00e9crire.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;[A]<em>ffutons nos acronymes&hellip;GFC2 n&rsquo;est pas GFC2, mais bien GCC tout court, sans num\u00e9rotation, &ndash; pour \u00ab\u00a0Great Civilisationnal Crisis\u00a0\u00bb (ou in French, les deux acronymes correspondant pour une fois, \u00ab\u00a0Grande Crise Civilisationnelle\u00a0\u00bb) ; ou encore, si l&rsquo;on pr\u00e9f\u00e8re la sophistication, GCCC (\u00ab\u00a0Grande Crise de la Contre-Civilisation\u00a0\u00bb, ou \u00ab\u00a0Great Counter-Civilization Crisis\u00a0\u00bb).<\/em>&raquo; (Entretemps, nous avons pr\u00e9cis\u00e9 que GCCC pouvait \u00eatre \u00e9galement \u00e9nonc\u00e9, d&rsquo;une fa\u00e7on acronymique marquante, comme GC3.)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ce que nous constations dans le <em>Faits &#038; Commentaires<\/em> <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-la_crise_ferale_phase_gfc2_pour_les_amis_04_08_2011.html\">cit\u00e9<\/a>, c&rsquo;\u00e9tait une int\u00e9gration de toutes les crises, souvent diff\u00e9rentes et portant sur des domaines diff\u00e9rents, en une grande crise g\u00e9n\u00e9rale (la Grande Crise de notre Contre-Civilisation). Le r\u00e9sultat de cette int\u00e9gration est une acc\u00e9l\u00e9ration irr\u00e9sistible de la dissolution des structures ou des restes des structures du monde puisque toutes les structures, elles-m\u00eames d\u00e9j\u00e0 affaiblies par des chocs d\u00e9structurants, subissent d\u00e9sormais les effets de <strong>toutes<\/strong> les crises qui parcourent la crise g\u00e9n\u00e9rale int\u00e9grant toutes les crises, et non plus les seuls effets sectoriels des crises de leurs domaines respectifs. Cette \u00ab\u00a0int\u00e9gration\u00a0\u00bb de toutes les crises dans la GC3 est d&rsquo;abord un puissant processus de perception psychologique poussant \u00e0 la conscience que la crise affecte la civilisation (la Contre-Civilisation) et\/ou le Syst\u00e8me <em>as a whole<\/em>. Toutes les pouss\u00e9es dissolvantes des crises se trouvent int\u00e9gr\u00e9es et agissent sur toutes les structures du Syst\u00e8me d\u00e9j\u00e0 fortement affaiblis par la d\u00e9structuration g\u00e9n\u00e9rale. En un sens c&rsquo;est cette \u00e9volution d&rsquo;int\u00e9gration qui a suscit\u00e9 la transformation du courant d\u00e9structurant en un y ajoutant un effet dissolvant majeur.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>Mieux (ou pire), GC3 a la vertu insigne de nous donner la clef fondamentale de la description des \u00e9v\u00e9nements. Ce que cet acronyme d\u00e9crit, c&rsquo;est non seulement l&rsquo;installation quasiment \u00ab\u00a0structurelle\u00a0\u00bb de la crise par l&rsquo;int\u00e9gration de toutes les crises sectorielles, mais plus encore, le passage \u00e9galement au niveau de la crise, et de toutes les crises finalement, du ph\u00e9nom\u00e8ne de dissolution que nous avons signal\u00e9 plus haut. Cette dissolution n&rsquo;est possible, elle, qu&rsquo;\u00e0 cause de l'\u00a0\u00bbinsoutenable l\u00e9g\u00e8ret\u00e9 du Syst\u00e8me\u00a0\u00bb par rapport \u00e0 ses propres vices.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Le ph\u00e9nom\u00e8ne de \u00ab\u00a0La crise est en crise\u00a0\u00bb<\/h3>\n<\/p>\n<p><p>Nous poursuivons par l&rsquo;analyse et l&rsquo;\u00e9largissement de l&rsquo;id\u00e9e du ph\u00e9nom\u00e8ne de \u00ab\u00a0La crise est en crise\u00a0\u00bb (<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-meme_les_crises_sont_en_crise__19_08_2011.html\">19 ao&ucirc;t 2011<\/a>). La crise devient elle-m\u00eame d\u00e9structur\u00e9e et perd sa paradoxale \u00ab\u00a0coh\u00e9sion\u00a0\u00bb de crise du sch\u00e9ma habituel d&rsquo;une crise (d\u00e9clenchement, aggravation, paroxysme, r\u00e9solution en bien ou en mal). La crise perd sa sp\u00e9cificit\u00e9 paradoxale de \u00ab\u00a0stabilit\u00e9\u00a0\u00bb (le fait de savoir ce qu&rsquo;est une \u00ab\u00a0crise\u00a0\u00bb, avec son d\u00e9but, son paroxysme et sa chute, conduit effectivement \u00e0 une paradoxale stabilit\u00e9). Le ph\u00e9nom\u00e8ne de \u00ab\u00a0La crise est en crise\u00a0\u00bb conduit, par les effets inattendus qu&rsquo;elle suscite, par l&rsquo;incertitude paradoxale qu&rsquo;elle installe dans l&rsquo;instabilit\u00e9 elle-m\u00eame inh\u00e9rente \u00e0 la crise, \u00e0 acc\u00e9l\u00e9rer et \u00e0 approfondir les effets sur la psychologie. La cons\u00e9quence est un paroxysme d&rsquo;instabilit\u00e9 pour la psychologie, qui ne se manifeste pas par une psychologie exprimant un \u00e9tat de folie mais par un comportement erratique, sinon fou, de la psychologie.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>La crise se fragmente, se d\u00e9structure, perd son identit\u00e9 r\u00e9elle, etc. Elle entre effectivement dans un processus de dissolution qui consiste en une agression g\u00e9n\u00e9rale contre tout ce qui peut appara&icirc;tre comme coh\u00e9rent et comme \u00e9quilibr\u00e9&#8230; On observe que les crises qui sont engendr\u00e9es par la puissance du Syst\u00e8me, et qui s&rsquo;exercent naturellement contre le Syst\u00e8me, subissent elles-m\u00eames le traitement qu&rsquo;elles pr\u00e9tendraient faire subir aux objets qu&rsquo;elles affectent. Le processus de dissolution appliqu\u00e9 \u00e0 la crise reproduit donc parfaitement le mouvement du Syst\u00e8me, avec la dynamique de surpuissance se mettant finalement au service de la dynamique d&rsquo;autodestruction.<\/em> [&hellip;]<\/p>\n<\/p>\n<p><p>&raquo;<em>La volatilit\u00e9 des crises est due \u00e9videmment \u00e0 leur d\u00e9structuration, puis \u00e0 leur dissolution, qui les rend inconsistantes, incontr\u00f4lables, et d&rsquo;autant plus violentes dans leur surgissement et les effets psychologiques induits. L&rsquo;absence de \u00ab\u00a0stabilit\u00e9\u00a0\u00bb des crises (\u00ab\u00a0stabilit\u00e9\u00a0\u00bb, &ndash; mot paradoxal dans ce cas, &ndash; du sch\u00e9ma classique d&rsquo;une crise), ce qui fait que \u00ab\u00a0la crise elle-m\u00eame est en crise\u00a0\u00bb \u00e0 cause de sa dissolution, soumet la psychologie \u00e0 une instabilit\u00e9 de tension qui, elle-m\u00eame, conduit la psychologie de plus en plus d\u00e9structur\u00e9e \u00e0 une situation de dissolution. Elle aussi, la psychologie, devient incontr\u00f4lable, insaisissable ; elle devient folle sous le coup de sa dissolution, sans \u00eatre pourtant une psychologie d&rsquo;un \u00e9tat de folie ; la psychologie reste relativement saine mais son comportement devient fou, erratique, sous la pression de l&rsquo;angoisse, de la peur, de l&rsquo;incertitude, &ndash; un nouvel \u00e9tat de fatigue port\u00e9 \u00e0 une sorte de paroxysme&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">La dissolution du monde et l&rsquo;hypoth\u00e8se deleuzienne<\/h3>\n<\/p>\n<p><p>Nous avons plusieurs fois \u00e9voqu\u00e9 l&rsquo;hypoth\u00e8se deleuzienne ces derni\u00e8res semaines, notamment \u00e0 travers de la superbe description critique qu&rsquo;en fit Jean-Fran\u00e7ois Mattei (voir notamment le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-apocalypse_molle_type_deleuzien-demasque-par-mattei__22_07_2011.html\">22 juillet 2011<\/a>). Notre propre hypoth\u00e8se est que l&rsquo;\u00e9tat du monde \u00e0 partir de 2008-2009, et notamment avec une \u00e9volution d\u00e9cisive vers la dynamique de sa dissolution \u00e0 cette \u00e9poque, correspond \u00e0 cette conception deleuzienne.<\/p>\n<\/p>\n<p><p>Il est alors int\u00e9ressant d&rsquo;observer combien cette \u00e9volution vers cette correspondance de l&rsquo;hypoth\u00e8se deleuzienne et de l&rsquo;\u00e9tat du monde a \u00e9t\u00e9 pr\u00e9c\u00e9d\u00e9e et pr\u00e9par\u00e9e par une p\u00e9n\u00e9tration subreptice et sans doute inconsciente de la psychologie am\u00e9ricaniste par la m\u00eame th\u00e9orie (ou la th\u00e9orie deleuzienne \u00e9largie aux postmodernistes, et connue aux USA sous l&rsquo;expression de <em>French Theory<\/em>). En quelque sorte, comme on le voit par les correspondances de date, la th\u00e9orie deleuzienne (la <em>French Theory<\/em>) a \u00e9t\u00e9 le support symbolique de la folie am\u00e9ricaniste, baptis\u00e9e dans ce cas &laquo;<em>la folie propre de l&rsquo;Am\u00e9rique<\/em>&raquo; et qui allait nous emporter sur les chemins qu&rsquo;on sait, &ndash; de 9\/11 \u00e0 la \u00ab\u00a0dissolution du monde\u00a0\u00bb.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>Il est int\u00e9ressant d&rsquo;explorer l&rsquo;hypoth\u00e8se que nous proposons, qui est que cette th\u00e9orie trouva son application, ou \u00e9pousa une \u00e9volution en lui donnant toute sa signification, en transformant une potentialit\u00e9 en une dynamique historique r\u00e9elle, dans l&rsquo;histoire des Etats-Unis depuis les ann\u00e9es 1990. Tout s&rsquo;encha&icirc;ne et se correspond parfaitement, les USA \u00e9tant la matrice de la modernit\u00e9 et du Syst\u00e8me, et conduisant la chevauch\u00e9e vers la dissolution.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Voici donc la <em>French Theory<\/em>, avec son grand succ\u00e8s d&rsquo;estime dans les ann\u00e9es 1970 aux USA, avec son influence souterraine majeure sur la psychologie am\u00e9ricaniste, dans les ann\u00e9es 1990, pour ouvrir le barrage de &laquo;<em>la folie propre de l&rsquo;Am\u00e9rique<\/em>&raquo; &hellip; On pourrait penser que la <em>French Theory<\/em> entra en correspondance presque intime avec l&rsquo;\u00e9volution finale des USA, apr\u00e8s la chute de l&rsquo;URSS, &ndash; comme si la France retrouvait, pour pr\u00e9parer (certes, sans y penser et encore moins le vouloir) la chute de l&rsquo;Am\u00e9rique, le r\u00f4le d&rsquo;influence qu&rsquo;elle occupa \u00e0 l&rsquo;av\u00e9nement de la m\u00eame Grande R\u00e9publique, dans les ann\u00e9es 1770.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>Nous ne parlons pas ici d&rsquo;une influence r\u00e9elle, ou d&rsquo;une \u00ab\u00a0philosophie\u00a0\u00bb changeant les m&oelig;urs et la pens\u00e9e, ou th\u00e9orisant un changement de m&oelig;urs et de pens\u00e9e, mais d&rsquo;une correspondance quasiment mystique ou spirituelle, ceci ou cela non r\u00e9alis\u00e9s, et surtout ceci ou cela pr\u00e9sentant une mystique ou une spiritualit\u00e9 invers\u00e9e. La French Theory semble s&rsquo;\u00eatre plaqu\u00e9e, simplement comme une indication fondamentale pour qui veut retrouver les traces profondes de notre \u00e9volution m\u00e9tahistorique profonde, sur ce que Cusset nomme \u00ab\u00a0la folie propre de l&rsquo;Am\u00e9rique\u00a0\u00bb : \u00ab\u00a0Car ses lecteurs am\u00e9ricains soulignent constamment son alt\u00e9rit\u00e9 radicale \u00e0 leur mode de pens\u00e9e en m\u00eame temps qu&rsquo;une forme de radicalit\u00e9 seule \u00e0 m\u00eame de saisir dans ses rets la folie propre de l&rsquo;Am\u00e9rique.\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Un Grand Tout fait de petits riens<\/h3>\n<\/p>\n<p><p>La th\u00e9orie deleuzienne appliqu\u00e9e aux USA, et par cons\u00e9quent au monde puisque les USA c&rsquo;est le monde, c&rsquo;est la course vers une sorte d&rsquo;an\u00e9antissement par dissolution. En cela, la logique d&rsquo;autodestruction du Syst\u00e8me s&rsquo;en trouve parfaitement confort\u00e9e.<\/p>\n<\/p>\n<p><p>Ce que Deleuze propose comme \u00ab\u00a0meilleur des mondes\u00a0\u00bb par dissolution, c&rsquo;est une v\u00e9ritable \u00ab\u00a0op\u00e9rationnalit\u00e9\u00a0\u00bb conceptuelle, une m\u00e9taphysique-simulacre de la fameuse th\u00e8se de la recherche du chaos, ou du \u00ab\u00a0chaos cr\u00e9ateur\u00a0\u00bb &hellip; Ainsi peut-on avancer que &laquo;<em>la folie propre de l&rsquo;Am\u00e9rique<\/em>&raquo; tenait en r\u00e9serve une cat\u00e9gorie tr\u00e8s sp\u00e9cifique de ce \u00ab\u00a0chaos cr\u00e9ateur\u00a0\u00bb cher au capitalisme ; c&rsquo;est ainsi que le \u00ab\u00a0chaos cr\u00e9ateur\u00a0\u00bb abouti \u00e0 la \u00ab\u00a0cr\u00e9ation\u00a0\u00bb d&rsquo;un \u00e9trange Grand Tout devenu \u00ab\u00a0les petits riens\u00a0\u00bb, constitu\u00e9 d&rsquo;une infinit\u00e9 de \u00ab\u00a0petits riens\u00a0\u00bb &ndash; c&rsquo;est-\u00e0-dire que l&rsquo;an\u00e9antissement par dissolution figure l&rsquo;accomplissement d\u00e9cisif, il le pr\u00e9pare avec attention, nous dirions m\u00eame : avec minutie, presque comme un ma&icirc;tre-horloger.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>Ils avaient peut-\u00eatre plus raison qu&rsquo;ils ne croient, ceux qui affirmaient qu&rsquo;en Irak, le but de l&rsquo;Am\u00e9rique \u00e9tait le chaos ; le but du capitalisme de ces temps nouveaux est \u00e9galement le chaos, et aussi le but de l&rsquo;instructure m\u00eame qu&rsquo;est la globalisation. Il ne s&rsquo;agit certainement pas de faire tabula rasa pour que la re-cr\u00e9ation puisse se faire (narrative hollywoodienne du \u00ab\u00a0chaos cr\u00e9ateur\u00a0\u00bb) mais, au contraire en un sens, pour que l&rsquo;effet ainsi obtenu d&rsquo;une destruction compl\u00e8te des structures se transforme en une v\u00e9ritable \u00ab\u00a0structure\u00a0\u00bb qu&rsquo;on qualifierait presque de \u00ab\u00a0p\u00e9renne\u00a0\u00bb, &ndash; les petits riens devenus le Grand Tout en un sens&hellip;<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Qu&rsquo;y a-t-il de plus \u00ab\u00a0petits riens\u00a0\u00bb que la compl\u00e8te dissolution en une infinit\u00e9 de \u00ab\u00a0petits riens\u00a0\u00bb figurant autant de situations de dissolution d&rsquo;autant de grains de sable ? Ainsi atteint-on un \u00e9tat o&ugrave; la dissolution compl\u00e8te figure effectivement l&rsquo;accomplissement du paradoxal Grand Tout, et l&rsquo;accomplissement aussi de &laquo;<em>la folie propre de l&rsquo;Am\u00e9rique<\/em>&raquo;&hellip; (Mais l&rsquo;on sait, depuis lors, que l&rsquo;Am\u00e9rique, en la circonstance, n&rsquo;est que le syst\u00e8me de l&rsquo;am\u00e9ricanisme, qui n&rsquo;est qu&rsquo;une part du Syst\u00e8me, ce qui conduit le Grand Tout et le Syst\u00e8me \u00e0 s&rsquo;identifier totalement. Et nous sommes confort\u00e9s par cons\u00e9quent dans l&rsquo;id\u00e9e que cette \u00ab\u00a0folie propre&hellip;\u00a0\u00bb et le Mal, dans ces temps extr\u00eames o&ugrave; la force et les actes donnent tous leurs effets jusqu&rsquo;\u00e0 l&rsquo;inversion, ne font qu&rsquo;une seule et m\u00eame chose.)<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Le tournant de la dissolution<\/h3>\n<\/p>\n<p><p>Dans cette \u00e9volution de l&rsquo;effondrement du Syst\u00e8me, et ce passage \u00e0 un courant de dissolution, nous citons le \u00ab\u00a0tournant\u00a0\u00bb des ann\u00e9es 2008-2009. A partir de l\u00e0 commence, apr\u00e8s la p\u00e9riode de d\u00e9structuration qui a pr\u00e9c\u00e9d\u00e9, ce que nous d\u00e9signons comme \u00ab\u00a0la dissolution du monde\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>On conna&icirc;t les divers \u00e9v\u00e9nements de 2008, et notamment celui de la crise financi\u00e8re du 15 septembre de cette ann\u00e9e-l\u00e0, qui domine les autres de toute la puissance de sa manifestation. Cet \u00e9v\u00e9nement est effectivement marquant pour notre propos, mais nullement du point de vue financier, ou dans ses cons\u00e9quences \u00e9conomiques et politiques. C&rsquo;est la psychologie qui nous importe d&rsquo;abord, car c&rsquo;est elle qui fut principalement marqu\u00e9e, frapp\u00e9e et transform\u00e9e.<\/p>\n<\/p>\n<p><p>L&rsquo;immense \u00e9v\u00e9nement du 15 septembre 2008 n&rsquo;est immense que par sa dimension psychologique, qui ne lui est pas sp\u00e9cifique mais qui \u00e9claire comme un symbole toute la crise g\u00e9n\u00e9rale, en montrant que, face \u00e0 une crise d\u00e9clench\u00e9e par le Syst\u00e8me, comme \u00e0 toute crise de ce genre, la riposte des directions politiques n&rsquo;est que de reconduire le Syst\u00e8me dans sa totalit\u00e9 furieuse et pr\u00e9datrice, avec un <em>satisfecit<\/em> sans nuance ; l&rsquo;incendiaire applaudi, encens\u00e9, f\u00eat\u00e9, &ndash; institu\u00e9 comme seul pompier possible de l&rsquo;incendie gigantesque qu&rsquo;il a allum\u00e9. Cette immense et affreuse r\u00e9action suicidaire eut l&rsquo;effet fondamental de frapper directement les psychologies et d&rsquo;ainsi ouvrir l&rsquo;esprit, sans que cet esprit en prenne conscience imm\u00e9diatement, \u00e0 la perspective de la n\u00e9cessit\u00e9 de la destruction du Syst\u00e8me, et donc \u00e0 ce courant inarr\u00eatable de la \u00ab\u00a0dissolution du monde\u00a0\u00bb qui est l&rsquo;encha&icirc;nement technique \u00e9vident, apr\u00e8s la d\u00e9structuration, de cette destruction. (Certes, en parlant de \u00ab\u00a0dissolution du monde\u00a0\u00bb c&rsquo;est bien de la dissolution du Syst\u00e8me que l&rsquo;on parle ; puisque le monde, apr\u00e8s la p\u00e9riode de d\u00e9structuration qui avait pr\u00e9c\u00e9d\u00e9, r\u00e9alis\u00e9e au profit du Syst\u00e8me, \u00e9tait devenu le Syst\u00e8me en soi.)<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>Ce qu&rsquo;il y a \u00e9videmment de plus remarquable durant cette p\u00e9riode, c&rsquo;est que les \u00e9v\u00e9nements firent la d\u00e9monstration de la faillite compl\u00e8te d&rsquo;un syst\u00e8me, et que la cons\u00e9quence en fut, dans les psychologies des directions politiques, de consid\u00e9rer que le Syst\u00e8me \u00e9tait vraiment indispensable ; on conclut qu&rsquo;il \u00e9tait le mod\u00e8le absolument d\u00e9terminant, sinon \u00ab\u00a0magique\u00a0\u00bb, qui allait fournir la clef de la crise. Il ne s&rsquo;agit pas l\u00e0 d&rsquo;un jugement intellectuel, ni m\u00eame d&rsquo;une n\u00e9cessit\u00e9 politique, \u00e9conomique ou autre, mais bien d&rsquo;un effet de dissolution des psychologies confront\u00e9es \u00e0 ces \u00e9v\u00e9nements. Cette orientation extraordinaire, tordant le jugement \u00e9vident qu&rsquo;on pouvait, qu&rsquo;on devait avoir sur les \u00e9v\u00e9nements par rapport au syst\u00e8me qui les avait g\u00e9n\u00e9r\u00e9s, ne pouvait qu&rsquo;appliquer une formidable pression sur la psychologie ; non seulement pour la p\u00e9n\u00e9trer, dans un travail automatique d&rsquo;influence de type assez classique ; mais, plus encore, pour la fatiguer, pour l&rsquo;\u00e9puiser, pour en faire un instrument absolument pr\u00eat \u00e0 participer \u00e0 un mouvement g\u00e9n\u00e9ral de dissolution, qui serait effectivement, dans ce cas, le produit direct d&rsquo;un \u00e9puisement de la psychologie et la dissolution \u00e9tant le produit fragment\u00e9 de cet \u00e9puisement.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">\u00ab\u00a0Sarkozy-devenu-Sarko\u00a0\u00bb, personnage deleuzien et maistrien<\/h3>\n<\/p>\n<p><p>Un exemplaire et typique <em>sapiens<\/em> de ce parcours vers la dissolution, c&rsquo;est le pr\u00e9sident fran\u00e7ais Sarkozy, et son parcours, le parcours de ce que nous d\u00e9signons \u00ab\u00a0Sarkozy-devenu-Sarko\u00a0\u00bb. L&rsquo;ann\u00e9e 2008 est sans aucun doute celle o&ugrave; ce pr\u00e9sident aurait pu se transformer en homme d&rsquo;Etat, gr\u00e2ce aux circonstances alors qu&rsquo;il assurait la pr\u00e9sidence de l&rsquo;Union Europ\u00e9enne. C&rsquo;est \u00e0 ce moment qu&rsquo;un destin s&rsquo;offrit \u00e0 lui ; tr\u00e8s rapidement sa religion fut faite, et il pr\u00e9f\u00e9ra \u00e0 ce destin offert celui de suivre le destin de la dissolution du monde&hellip;<\/p>\n<\/p>\n<p><p>Nous d\u00e9crivons ainsi &laquo;[l]<em>a facilit\u00e9 et la subrepticit\u00e9 avec laquelle Sarkozy devint Sarko, et le parfait dirigeant-Syst\u00e8me qu&rsquo;il est ainsi devenu&hellip;<\/em>&raquo; On conviendra que cela revient \u00e0 constater un \u00ab\u00a0juste\u00a0\u00bb retour des choses&hellip;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>La French Theory triomphait enfin en France et Sarko, personnage sans identit\u00e9 \u00e0 qui un choix avait \u00e9t\u00e9 offert, \u00e9tait devenu un personnage deleuzien, &ndash; fait effectivement de r\u00e9seaux, d&rsquo;inconsistances, de pens\u00e9es \u00ab\u00a0d\u00e9structur\u00e9es, \u00e9clat\u00e9es, dispers\u00e9es\u00a0\u00bb et en voie de dissolution, etc&hellip;<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Mais plus encore, tant le personnage semble nous r\u00e9server des tr\u00e9sors de bassesse et une exceptionnelle adaptabilit\u00e9 \u00e0 la servilit\u00e9 par rapport aux grands \u00e9v\u00e9nements qui ordonnent la crise. Il se trouve que nous trouvons finalement \u00e0 \u00ab\u00a0Sarkozy-devenu-Sarko\u00a0\u00bb, personnage devenu parfaitement deleuzien en m\u00eame temps qu&rsquo;exemplaire dirigeant-Syst\u00e8me, un air <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-a_propos_de_maistre_de_sarko_de_l_histoire_et_du_reste_21_05_2007.html\">maistrien<\/a> incontestable lorsque l&rsquo;on consid\u00e8re o&ugrave; tout cela nous m\u00e8ne sur la voie de la \u00ab\u00a0dissolution du monde\u00a0\u00bb, et la fa\u00e7on dont il (Sarko) prend bien garde \u00e0 ne pas entraver la marche d&rsquo;\u00e9v\u00e9nements en acceptant compl\u00e8tement d&rsquo;\u00eatre manipul\u00e9 par eux. Cela nous conduit \u00e0 \u00e9tablir une correspondance paradoxale mais bien de circonstance entre la th\u00e9orie maistrienne et la th\u00e9orie deleuzienne, &ndash; ou la th\u00e9orie deleuzienne, retourn\u00e9e contre ses propres fantasmes, comme excellent outil d&rsquo;accomplissement de la th\u00e9orie maistrienne.<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>Nous serions tent\u00e9s de voir dans la French Theory et les conceptions deleuziennes une sorte d&rsquo;adaptation \u00e0 la modernit\u00e9, du mod\u00e8le du monde en crise et du sort manipul\u00e9 des acteurs humains, tels que Joseph de Maistre les a vus et d\u00e9crits du temps de la R\u00e9volution Fran\u00e7aise. La diff\u00e9rence fondamentale r\u00e9side dans la formidable charpente spirituelle que propose Maistre, par contraste avec le vide spirituel de la th\u00e9orie deleuzienne. Ainsi la th\u00e9orie deleuzienne d\u00e9crirait la dissolution d&rsquo;un monde dont la th\u00e9orie maistrienne nous annon\u00e7ait la condamnation.<\/em>&raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Situation de l'\u00a0\u00bbhonn\u00eate homme\u00a0\u00bb<\/h3>\n<\/p>\n<\/blockquote>\n<p><p>Nous observons enfin comment cette \u00ab\u00a0dissolution du monde\u00a0\u00bb est en voie de compl\u00e8tement \u00ab\u00a0d\u00e9c\u00e9r\u00e9brer\u00a0\u00bb les relations internationales, de leur \u00f4ter leur identit\u00e9 et d&rsquo;en faire un corps mou et flasque, &ndash; th\u00e9orie deleuzienne oblige, &ndash; comme serait un corps priv\u00e9 de colonne vert\u00e9brale. (&laquo;<em>Il a autant de colonne vert\u00e9brale qu&rsquo;un \u00e9clair au chocolat<\/em>&raquo; disait le vice-pr\u00e9sident Th\u00e9odore Roosevelt de son pr\u00e9sident McKinley, et c&rsquo;est l&rsquo;image qui convient.) Les crises incessantes, le processus de d\u00e9structuration encha&icirc;nant sur la dissolution ont affaibli jusqu&rsquo;\u00e0 la compl\u00e8te insubstance les notions de coop\u00e9ration, d&rsquo;alliances, de relations politiques, etc. Il est de moins en moins concevable de parler d'\u00a0\u00bbengagement\u00a0\u00bb, de \u00ab\u00a0choix politique\u00a0\u00bb, voire d'\u00a0\u00bbalignement\u00a0\u00bb, etc. &hellip; Nous suivons toujours, \u00e0 cet \u00e9gard, le cas fran\u00e7ais sous l&#8217;empire incertain de \u00ab\u00a0Sarkozy devenu Sarko\u00a0\u00bb&hellip;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>Cela \u00e9crit, il serait absurde de suivre l&rsquo;id\u00e9e, par exemple, que la France s&rsquo;est abaiss\u00e9e devant l&rsquo;Am\u00e9rique, a r\u00e9int\u00e9gr\u00e9 l&rsquo;OTAN par servilit\u00e9 inutile et ainsi de suite. Tout cela est vrai dans la conception, mais inexistant dans la r\u00e9alisation. En s&rsquo;abaissant devant l&rsquo;Am\u00e9rique et en faisant acte de servilit\u00e9 en r\u00e9int\u00e9grant l&rsquo;OTAN, la France a r\u00e9ussi \u00e0 d\u00e9montrer qu&rsquo;il devenait impossible de s&rsquo;abaisser devant l&rsquo;Am\u00e9rique parce que cette puissance est elle-m\u00eame trop basse, et que l&rsquo;enjeu n&rsquo;est plus de mesurer sa position par rapport aux USA ; qu&rsquo;entrer dans l&rsquo;OTAN par servilit\u00e9 n&rsquo;est pas vraiment faire preuve de servilit\u00e9 parce qu&rsquo;il n&rsquo;y a plus personne devant lequel on peut se montrer servile, tant chacun se pr\u00e9occupe, dans son coin, de sa propre servilit\u00e9 au Syst\u00e8me&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cela implique la disparition compl\u00e8te des concepts structurants tels que l\u00e9gitimit\u00e9, souverainet\u00e9, tout cela remplac\u00e9 par un vide en formation acc\u00e9l\u00e9r\u00e9e, sous la pression de la dissolution d\u00e9velopp\u00e9e par le Syst\u00e8me&hellip;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;[C]<em>ela n&rsquo;est effectivement pas une capitulation (fran\u00e7aise) mais bien une course fran\u00e7aise (une sp\u00e9cialit\u00e9 du f\u00e9brile Sarko) pour s&rsquo;aligner sur la \u00ab\u00a0substance insubstantielle\u00a0\u00bb des relations internationales. La France r\u00e9ussit cet exploit, effectivement, de se ranger compl\u00e8tement dans \u00ab\u00a0le camp am\u00e9ricaniste\u00a0\u00bb, alors que ce camp est \u00e0 l&rsquo;abandon, ouvert \u00e0 tous les vents, englu\u00e9 dans de multiples crises dont la plus s\u00e9v\u00e8re est certainement l&rsquo;effondrement total de sa structure de pouvoir. Ainsi, la dissolution fran\u00e7aise se fait-elle au seul profit du d\u00e9sordre.<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>A cela, nous ajoutons le courant majeur de dissolution sp\u00e9cifique au dispositif du bloc BAO, donc du Syst\u00e8me, &ndash; le \u00ab\u00a0bloc\u00a0\u00bb figurant, comme on le comprend, nullement un rassemblement politique actif, mais une \u00e9manation flasque et par automatisme du Syst\u00e8me ; ce \u00ab\u00a0courant majeur de dissolution\u00a0\u00bb \u00e9tabli dans les pays arabes, par le biais du \u00ab\u00a0printemps arabe\u00a0\u00bb. Bien entendu, ce printemps-l\u00e0 n&rsquo;est pas celui de l&rsquo;\u00e9tablissement d&rsquo;un nouvel ordre d\u00e9mocratique, qui serait prestement r\u00e9cup\u00e9r\u00e9 par le Syst\u00e8me, mais bien celui d&rsquo;une acc\u00e9l\u00e9ration du d\u00e9sordre introduit dans ce dispositif par le courant de dissolution.<\/p>\n<\/p>\n<p><p>La cons\u00e9quence pour l'\u00a0\u00bbhonn\u00eate homme\u00a0\u00bb, ce concept du XVII\u00e8me si\u00e8cle qu&rsquo;il importerait de ressusciter pour situer la d\u00e9finition de la n\u00e9cessit\u00e9 de r\u00e9sistance, est un \u00ab\u00a0devoir de situation\u00a0\u00bb par rapport au Syst\u00e8me qui d\u00e9finira l&rsquo;essentiel de sa r\u00e9sistance. Cela commence par une d\u00e9finition de la position de l'\u00a0\u00bbhonn\u00eate homme\u00a0\u00bb par rapport aux effets de la crise, par rapport aux artifices encore offerts comme simulacres par le Syst\u00e8me pour y attirer ceux qui sont pr\u00eats \u00e0 y succomber, pour qu&rsquo;ils y succombent&hellip;<\/p>\n<\/p>\n<blockquote class=\"normal\" style=\"font-size:1.05em;\">\n<p><p>&laquo;<em>Il importe de se situer hors de ces remous et de ces formidables bouleversements, m\u00eame si l&rsquo;on est n\u00e9cessairement partie d&rsquo;un pays, d&rsquo;un ensemble ou d&rsquo;un \u00ab\u00a0bloc\u00a0\u00bb. Mais nous ne sommes plus partie de rien de cette sorte, en v\u00e9rit\u00e9, tant ces concepts divers, &ndash; pays, ensemble, \u00ab\u00a0bloc\u00a0\u00bb, &ndash; sont d\u00e9sormais totalement d\u00e9pourvus de formes et d&rsquo;essence, de l\u00e9gitimit\u00e9, de fondements, etc. Ce ne sont plus que des artefacts informes d&rsquo;un courant qui les emporte tous&hellip;<\/em>&raquo;<\/p>\n<\/p>\n<\/blockquote><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur la dissolution du monde (dde.crisis) Le num\u00e9ro du 10 septembre 2011 de dde.crisis a comme sujet \u00ab\u00a0la dissolution du monde\u00a0\u00bb. Le traitement de ce sujet concerne un mouvement puissant et syst\u00e9matique de fragmentation qui affecte la constitution formelle du monde. Nous consid\u00e9rons que, sous la pouss\u00e9e \u00e0 la fois de politiques tr\u00e8s violentes&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[2631,11301,3907,10119,11488,11470,11376,11490,4595,4596,3099,4590,11489],"class_list":["post-74056","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-de","tag-deleuze","tag-destructuration","tag-dissolution","tag-french","tag-gc3","tag-gccc","tag-insubstance","tag-joseph","tag-maistre","tag-psychologie","tag-sarkozy","tag-theory"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74056"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74056\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}