{"id":74057,"date":"2011-09-14T09:04:58","date_gmt":"2011-09-14T09:04:58","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/09\/14\/turquie-versus-israel-ou-le-poids-des-armes-us\/"},"modified":"2011-09-14T09:04:58","modified_gmt":"2011-09-14T09:04:58","slug":"turquie-versus-israel-ou-le-poids-des-armes-us","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/09\/14\/turquie-versus-israel-ou-le-poids-des-armes-us\/","title":{"rendered":"Turquie <em>versus<\/em> Isra\u00ebl, ou le poids des armes (US)"},"content":{"rendered":"<p><p>En compl\u00e9ment de l&rsquo;activit\u00e9 diplomatique de la phase politique tr\u00e8s active qu&rsquo;ont inaugur\u00e9 la Turquie et son Premier ministre Erdogan, il existe sans aucun doute un aspect factuel qui concerne la situation fondamentalement antagoniste entre la Turquie et Isra\u00ebl. Cette situation s&rsquo;est tr\u00e8s fortement marqu\u00e9e, effectivement, par des faits concrets qui confirment cet antagonisme. Le fait politico-militaire principal est l&rsquo;annonce par la Turquie que la marine turque interviendrai si la marine isra\u00e9lienne op\u00e9rait hors de ses eaux territoriales, pour assurer le blocus de Gaza que la Turquie consid\u00e8re comme ill\u00e9gal. La marine turque a donn\u00e9 des d\u00e9tails techniques tr\u00e8s pr\u00e9cis (\u00ab<em>If Turkish warships encounter an Israeli military ship outside Israel&rsquo;s 12-mile territorial waters, they will advance up to 100 meters from the ship and disable its weapon system<\/em>\u00bb).<\/p>\n<\/p>\n<p><p>\tDe ce point de vue des mesures annonc\u00e9es par les Turcs concernant cette situation navale, des commentateurs arabes jugent qu&rsquo;elle sont \u00e0 la fois audacieuses et risqu\u00e9es, qu&rsquo;elles substantivent effectivement la nouvelle politique turque mais posent la question de savoir si et comment elles peuvent \u00eatre suivies d&rsquo;effets. Le risque est \u00e9videmment qu&rsquo;une mesure aussi importante, annonc\u00e9e et \u00e9ventuellement non suivie d&rsquo;effets dans certaines circonstances, constituerait un \u00e9norme revers diplomatique pour la Turquie. Cet extrait d&rsquo;<em>Arab.News<\/em>, une publication proche des pays du Golfe, r\u00e9sume cet aspect de la question (le <a href=\"http:\/\/arabnews.com\/opinion\/editorial\/article501278.ece\" class=\"gen\">143 septembre 2011<\/a>).<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Arab opinion applauds the fact that at last an important outside country, a member of NATO, with close ties to both the EU and the United States, is finally getting tough with the Israelis. It is good to hear such language, and one wishes that the US or the EU would resort to a small proportion of this tough talk. Nonetheless the exhilaration at this spectacle cannot blind anyone, not least Erdogan himself, to the considerable challenges involved in his increasingly powerful line toward the Netanyahu government.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The bottom line is that a threat is only meaningful if there is a readiness to carry it through. Is Erdogan ready to see his navy fighting it out with the Israelis in the eastern Mediterranean? Has he thought through the consequences, not least where such a firefight could lead politically and militarily and of no less importance, the impact to Turkey&rsquo;s standing in NATO and with Europe?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tSur ce point particulier des aspects militaires des relations d\u00e9sormais antagonistes entre Isra\u00ebl et la Turquie, des nouvelles concernant les armements respectifs montrent qu&rsquo;une activit\u00e9 sp\u00e9cifique marque le domaine, qui refl\u00e8tent effectivement cet antagonisme. Elles caract\u00e9risent des actions des deux c\u00f4t\u00e9s, avec des interf\u00e9rences US majeures marquant l&rsquo;implication consid\u00e9rable des USA dans ce domaine de l&rsquo;\u00e9quipement militaire, pour les <strong>deux<\/strong> pays.<\/p>\n<\/p>\n<p><p>\t Il y a l&rsquo;annonce, du c\u00f4t\u00e9 turc, venue d&rsquo;un journal d&rsquo;Ankara (le <em>Star Gazete<\/em>), que les avions de combat turcs, notamment les F-16, re\u00e7oivent un nouveau radar de fabrication turque qui leur permet l&rsquo;acquisition d&rsquo;objectifs isra\u00e9liens lors d&rsquo;\u00e9ventuelles missions de combat. Originellement, les F-16 sont livr\u00e9s par les USA avec une programmation \u00e9lectronique d&rsquo;origine USA, et verrouill\u00e9e par les USA, impliquant une r\u00e9partition des cibles entre amis et ennemis (<em>Identification Friend and Foes<\/em> [IFF]), avec une classification d&rsquo;Isra\u00ebl dans les amis qui interdit l&rsquo;intervention arm\u00e9e turque contre Isra\u00ebl. Le site isra\u00e9lien <em>Ynet.News<\/em> d\u00e9veloppe la nouvelle le <a href=\"http:\/\/www.ynetnews.com\/articles\/0,7340,L-4121642,00.html\" class=\"gen\">13 septembre 2011<\/a>, en insistant sur le fait que ce nouvel \u00e9quipement turc a \u00e9t\u00e9 d\u00e9velopp\u00e9 sur instruction directe d&rsquo;Erdogan. (Il faut aussi insister sur le fait que cet \u00e9quipement IFF implique des missions d\u00e9fensives, les missions offensives pouvant difficilement \u00eatre verrouill\u00e9es dans ce sens par le constructeur initial,  les USA). (Une question compl\u00e9mentaire int\u00e9ressante serait de savoir si les avions isra\u00e9liens d&rsquo;origine US sont tributaires des m\u00eames limitations, avec un IFF interdisant l&rsquo;acquisition \u00e9lectronique de cibles turques class\u00e9es amies. Ce serait bien \u00e9tonnant et le contraire,  Turquie hors de la classification amies, \u00e9ventuellement sur intervention technique des Isra\u00e9liens sur leurs propres avions, est bien plus probable.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The new radar system  Identification Friend or Foe (IFF)  is a defensive command and control system developed by Turkey&rsquo;s Military Electronics Industry (ASELSAN) for the nation&rsquo;s air force and navy. It is slated to replace a similar US version which is in use today<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Le <a href=\"http:\/\/www.debka.com\/article\/21297\/\" class=\"gen\">13 septembre 2011<\/a>, <em>DEBKAFiles<\/em> \u00e9crit que les USA ont refus\u00e9 une demande de la Turquie pour l&rsquo;acquisition ou la disposition de syst\u00e8mes a\u00e9riens sans pilotes (UCAV) <em>Predator<\/em>, tant que la Turquie menacera militairement Isra\u00ebl (l&rsquo;affaire de la pr\u00e9sence navale turque contre l&#8217;embargo isra\u00e9lien). Selon <em>DEBKAFiles<\/em>, ce refus US paralyse en partie l&rsquo;action turque contre les rebelles de l&rsquo;organisation kurde PKK, notamment \u00e0 cause de probl\u00e8mes pour utiliser des UCACV isra\u00e9liens <em>Heron<\/em>,  vendus par Isra\u00ebl \u00e0 la Turquie,  qui ont des probl\u00e8mes techniques d&#8217;emploi. Conform\u00e9ment \u00e0 son habitude, <em>DEBKAFiles<\/em> est tr\u00e8s pessimiste et belliciste et consid\u00e8re que l&rsquo;affrontement arm\u00e9 entre la Turquie et Isra\u00ebl a d&rsquo;ores et d\u00e9j\u00e0 discr\u00e8tement commenc\u00e9.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The Obama administration has turned down a Turkish request for drones or for the deployment of US Predators at Turkish bases until Ankara stops threatening Israel with armed attack, DEBKAfile&rsquo;s military and Washington sources report.  Turkey has no functioning unmanned aerial vehicles at present. The technical problems grounding the Herons Israel sold Ankara have crippled the Turkish army&rsquo;s campaign against the Kurdish PKK rebels  both in northern Iraq and in southeast Turkey.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>In recent days, therefore, the rebels have stepped up their raids on Turkish territory, killing nine people including army and police personnel.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Israeli officialdom and military chiefs are doing their utmost to keep the lid on the spiraling Turkish-Israel confrontation, claiming that a military clash is not imminent because the US, NATO and Europe won&rsquo;t let it happen. Turkey is after all a member of the North Atlantic Treaty Organization. However, DEBKAfile&rsquo;s military sources report, the confrontation has already broken surface. Despite Western efforts to contain the rising tension, the armed conflict has quietly begun<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCes diverses informations, quoi qu&rsquo;il en soit de leur exactitude, montrent dans tous les cas que l&rsquo;antagonisme isra\u00e9lo-turc est d\u00e9sormais pris tr\u00e8s au s\u00e9rieux, y compris par le troisi\u00e8me sommet du triangle, les USA, principal fournisseur des deux pays qui s&rsquo;affrontent. Mais il faut aussit\u00f4t aller bien plus loin que le seul aspect de la quincaillerie, voire que l&rsquo;aspect op\u00e9rationnel.<\/p>\n<\/p>\n<p><p>\tSi l&rsquo;information de <em>DEBKAFiles<\/em> est confirm\u00e9e, elle est extr\u00eamement grave. Elle p\u00e8se, de la part des USA, doublement sur la souverainet\u00e9 et la souverainet\u00e9 nationales de la Turquie. D&rsquo;une part, selon la pr\u00e9sentation qui en est faite, l&rsquo;\u00e9ventuel embargo sur le <em>Predator<\/em> est li\u00e9 \u00e0 une d\u00e9cision non pas technique, mais politique et de s\u00e9curit\u00e9 nationale, notamment la d\u00e9cision d&rsquo;Erdogan de faire respecter la libre circulation dans les eaux internationales face aux incursions isra\u00e9liennes,  consid\u00e9r\u00e9e dans ce cas par les USA comme une menace contre Isra\u00ebl. D&rsquo;autre part, elle affecte un potentiel turc non pas contre Isra\u00ebl, mais dans le cadre d&rsquo;une lutte engag\u00e9e contre une gu\u00e9rilla, qui est consid\u00e9r\u00e9e par l&rsquo;Etat turc,  \u00e0 juste raison ou pas, c&rsquo;est un autre probl\u00e8me,  comme cruciale pour la s\u00e9curit\u00e9 nationale du pays. Il s&rsquo;agit d&rsquo;un v\u00e9ritable chantage portant sur l&rsquo;int\u00e9grit\u00e9 souveraine de la Turquie, sans doute l&rsquo;initiative la plus grave dans ses implications qu&rsquo;on puisse imaginer dans la situation pr\u00e9sente. (La gravit\u00e9 du cas est aliment\u00e9e par la nouvelle que les Turcs envisagent une <a href=\"http:\/\/original.antiwar.com\/updates\/2011\/09\/13\/turkey-threatens-to-send-troops-into-northern-iraq\/\" class=\"gen\">invasion<\/a> du nord de ce pays pour lutter le PKK. Ils recherchent l&rsquo;accord du gouvernement irakien, ce qui pourrait d&rsquo;ailleurs conduire \u00e0 d&rsquo;int\u00e9ressantes interf\u00e9rences avec les USA, toujours pr\u00e9sents en Irak, et dont certains ont \u00e9t\u00e9 jusqu&rsquo;\u00e0 soup\u00e7onner qu&rsquo;ils auraient pu ne pas rechigner \u00e0 la livraison de certains armements au PKK,  pour alimenter le multilat\u00e9ralisme exub\u00e9rant de leurs politiques fractionn\u00e9es entre agences et d\u00e9partements concurrents.)<\/p>\n<\/p>\n<p><p>\tDans tous les cas, il s&rsquo;agit d&rsquo;un durcissement notable des USA, c&rsquo;est-\u00e0-dire du Pentagone dans ce cas (les modalit\u00e9s de la s\u00e9curit\u00e9 d&rsquo;Isra\u00ebl <a href=\"http:\/\/www.dedefensa.org\/article-bibi-2011_comme_l_idf_face_au_hezbollah_en_2006_12_09_2011.html\" class=\"gen\">constituent<\/a> son domaine r\u00e9serv\u00e9), et cela ne passera pas inaper\u00e7u ni ne sera sans cons\u00e9quence. Si l&rsquo;orientation est bien celle de la d\u00e9cision rapport\u00e9e par <em>DEBKAFiles<\/em>, il ne fait aucun doute que l&rsquo;on se dirige vers une d\u00e9t\u00e9rioration consid\u00e9rable des relations de la Turquie,  avec Isra\u00ebl, certes, quoique cela soit d\u00e9j\u00e0 fait pour une bonne part,  mais <strong>surtout<\/strong> avec les USA, avec des cons\u00e9quences importantes, impossibles \u00e0 pr\u00e9voir, au sein de l&rsquo;organisation et du climat des alliances du bloc am\u00e9ricaniste-occidentaliste (BAO), au sein de l&rsquo;OTAN et m\u00eame de l&rsquo;UE.<\/p>\n<\/p>\n<p><p>\tD&rsquo;une fa\u00e7on plus g\u00e9n\u00e9ral et au niveau des principes, la d\u00e9monstration est faite une fois de plus des questions essentielles soulev\u00e9es par les fournitures d&rsquo;armements avanc\u00e9s. (La d\u00e9monstration vaut aussi bien pour les deux cas \u00e9voqu\u00e9, l&rsquo;IFF des F-16 et le <em>Predator<\/em>.) Il s&rsquo;agit de rien moins que du respect de la souverainet\u00e9 et de l&rsquo;ind\u00e9pendance des partenaires, qui sont en g\u00e9n\u00e9ral (la souverainet\u00e9 et l&rsquo;ind\u00e9pendance) syst\u00e9matiquement pi\u00e9tin\u00e9es par les USA, qui font au contraire de leurs fournitures d&rsquo;armements le moyen d&rsquo;un chantage le plus grossier et le plus brutal. La tradition fran\u00e7aise, dans ce cas, \u00e9tait d&rsquo;assurer le contraire, le complet respect de la souverainet\u00e9 de l&rsquo;acheteur,  mais la question se pose aujourd&rsquo;hui, avec l&rsquo;effondrement de la politique ext\u00e9rieure fran\u00e7aise dans la conformit\u00e9 hyst\u00e9rique au Syst\u00e8me, de savoir exactement ce qu&rsquo;il reste de cette tradition. Les Russes sont, parmi les gros fournisseurs d&rsquo;armement, les seuls \u00e0 conserver \u00e0 peu pr\u00e8s ce respect de la souverainet\u00e9 des autres, cela correspondant d&rsquo;ailleurs \u00e0 leur politique \u00e9trang\u00e8re. On a d\u00e9j\u00e0 vu que les Turcs avaient effectu\u00e9 quelques achats d&rsquo;armements russes et s&rsquo;int\u00e9ressaient \u00e0 d&rsquo;autres, plus importants (voir notre <em>Faits &#038; Commentaires<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-la_turquie_entre_otan_europe_et_russie_29_04_2009.html\" class=\"gen\">29 avril 2011<\/a>, qui parlait d&rsquo;armements russes importants pour la Turquie, en m\u00eame temps que des relations d\u00e9j\u00e0 quelque peu refroidies de la Turquie avec l&rsquo;OTAN). Tout cela sugg\u00e8re bien entendu des \u00e9volutions possibles d&rsquo;importance, selon l&rsquo;\u00e9volution des \u00e9v\u00e8nements au Moyen-Orient.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 14 septembre 2011 \u00e0 09H04<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En compl\u00e9ment de l&rsquo;activit\u00e9 diplomatique de la phase politique tr\u00e8s active qu&rsquo;ont inaugur\u00e9 la Turquie et son Premier ministre Erdogan, il existe sans aucun doute un aspect factuel qui concerne la situation fondamentalement antagoniste entre la Turquie et Isra\u00ebl. Cette situation s&rsquo;est tr\u00e8s fortement marqu\u00e9e, effectivement, par des faits concrets qui confirment cet antagonisme. Le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3481,3737,1015,11491,4345,857,2774,4447,3890,2937,11492,4986,4205,2746,2613,4211],"class_list":["post-74057","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-armements","tag-erdogan","tag-f-16","tag-iff","tag-independance","tag-irak","tag-israel","tag-kurdes","tag-national","tag-nationale","tag-pkk","tag-predator","tag-securite","tag-souverainete","tag-turquie","tag-ucav"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74057"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74057\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}