{"id":74095,"date":"2011-09-28T09:39:11","date_gmt":"2011-09-28T09:39:11","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/09\/28\/leur-discorde-generale-et-leffondrement-du-systeme\/"},"modified":"2011-09-28T09:39:11","modified_gmt":"2011-09-28T09:39:11","slug":"leur-discorde-generale-et-leffondrement-du-systeme","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/09\/28\/leur-discorde-generale-et-leffondrement-du-systeme\/","title":{"rendered":"Leur discorde g\u00e9n\u00e9rale et l&rsquo;effondrement du Syst\u00e8me"},"content":{"rendered":"<p><p>Une situation tend \u00e0 devenir d\u00e9sormais structurelle au sein du bloc BAO (bloc am\u00e9ricaniste-occidentaliste), qui est une situation de division et d&rsquo;antagonisme. Il nous para\u00eet vain de tenter d&rsquo;identifier, selon les normes h\u00e9rit\u00e9es de cet autre temps du <em>leadership<\/em> US o\u00f9 comptaient des notions de type servile comme l&rsquo;alignement ou l&rsquo;isolement, des positions sp\u00e9cifiques en fonction de cette soi-disant coh\u00e9sion de puissance (derri\u00e8re les USA) impliquant justement alignement et isolement. Cette \u00e9poque de rangement des relations internationales \u00e0 l&rsquo;int\u00e9rieur du bloc BAO est d\u00e9pass\u00e9e.<\/p>\n<\/p>\n<p><p>\tLa question essentielle actuelle tourne autour de la position de l&rsquo;Allemagne par rapport \u00e0 l&rsquo;action \u00e0 entreprendre dans la crise de la Gr\u00e8ce et tout le reste qui lui est li\u00e9. Merkel est prise dans la tenaille habituelle des exigences de certains de ses partenaires ext\u00e9rieurs, et des exigences de son opinion int\u00e9rieure relay\u00e9e largement par une partie de la direction politique allemande. C&rsquo;est bien entendu la situation centrale de puissance financi\u00e8re de l&rsquo;Allemagne, qui en fait le principal acteur ext\u00e9rieur de la crise grecque, qui la met dans cette position o\u00f9 se manifestent des querelles et des pressions puissantes par rapport \u00e0 elle. Mais il ne s&rsquo;agit que d&rsquo;une situation conjoncturelle, qui n&rsquo;implique nullement une situation sp\u00e9cifique de rangement des relations.<\/p>\n<\/p>\n<p><p>\t Il y a deux fronts principaux, le premier \u00e9tant bien entendu europ\u00e9en. Le <em>Guardian <\/em> du <a href=\"http:\/\/www.guardian.co.uk\/business\/2011\/sep\/27\/merkel-efsf-greek-bailout-fund\" class=\"gen\">28 septembre 2011<\/a> consacre un article \u00e0 cet aspect de la situation. On ne peut sans aucun doute parler de front stable, avec les acteurs bien identifi\u00e9s d&rsquo;un c\u00f4t\u00e9 et de l&rsquo;autre, ou l&rsquo;Allemagne isol\u00e9e, etc. C&rsquo;est essentiellement une situation mouvante, instable, avec des variables en d\u00e9placement constant. La France, que le <em>Guardian<\/em> pr\u00e9sente ici comme en opposition avec l&rsquo;Allemagne pour des raisons conjoncturelles, cherche par ailleurs une unit\u00e9 d&rsquo;action avec l&rsquo;Allemagne (ce n&rsquo;est ni la premi\u00e8re ni la derni\u00e8re fois).<\/p>\n<\/p>\n<p><p>\t\u00ab<em>German negotiators at loggerheads with their French counterparts over pledges to quadruple the eurozone&rsquo;s 440bn (\u00a3382bn) bailout fund ahead of a crucial vote in the Bundestag on Thursday that could decide the fate of the currency zone. Attempts by Berlin to write off up to 50% of Greek debts as part of a wider rescue package faced stiff opposition from France, which is concerned many of its banks would need to find extra funds to cope with the resulting losses.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Wrangling over the need to expand the bailout came to the fore at a meeting of the International Monetary Fund in Washington last weekend. EU officials told the IMF plans were under way to increase the bailout fund to about 2tn and write of half of Greece&rsquo;s sovereign debts. But that pledge was reported to be at risk with France said to be in conflict with Germany, Finland and Slovenia.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Fears that the major EU countries will fail to agree an expanded package of measures to cope with a default by Greece, and possibly Italy and Spain, has undermined confidence in the eurozone and led to a collapse in bank shares. French banks have suffered huge falls since the summer when concerns first emerged that they would collapse under the weight of unpaid debts if Greece defaulted.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>In the last two days shares have rallied on hopes the IMF talks would lead to concrete agreement.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t\u00bb<em>However, conscious of animosity among the majority of German voters about helping the less prudent nation, Merkel attached strings to her support, calling on Greece to \u00ab\u00a0do its homework\u00a0\u00bb in implementing painful cuts and reforms.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Tomorrow the Bundestag will vote on whether to increase the powers of the EFSF  the forerunner of the permanent rescue facility, the European Stability Mechanism, due to come into force in 2013. Three out of four Germans are against the move, which would raise the country&rsquo;s contributions to the pot from 123bn to 211bn. Some parliaments do not vote until the middle of next month and also face opposition from a sceptical public<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t L&rsquo;autre front est transatlantique. Il oppose principalement l&rsquo;Allemagne et les USA, avec certains pays europ\u00e9ens variant dans leurs positions selon leur propre position conjoncturelle vis-\u00e0-vis de l&rsquo;Allemagne. De toutes les fa\u00e7ons, on a pu voir, depuis la r\u00e9cente r\u00e9union des ministres des finances de l&rsquo;UE de Varsovie \u00e0 laquelle s&rsquo;\u00e9tait invit\u00e9 le secr\u00e9taire US au tr\u00e9sor Geithner, qu&rsquo;il r\u00e8gne une r\u00e9elle tension, soit entre l&rsquo;Europe et les USA \u00e0 certains moments, soit entre l&rsquo;Allemagne et les USA d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale. Les arguments sont connus, sinon \u00e9vidents, avec deux zones (UE et USA) dans un \u00e9tat d&rsquo;effondrement effrayant, et chacune exigeant de l&rsquo;autre des efforts sp\u00e9cifique, mais \u00e0 la convenance et pour les int\u00e9r\u00eats de soi-m\u00eame,  cela, c&rsquo;est surtout la m\u00e9thode US, bien entendu. Ambrose Evans-Pritchard, du <em>Dalily Telegraph<\/em>, ce <a href=\"http:\/\/www.telegraph.co.uk\/finance\/financialcrisis\/8793010\/Germany-slams-stupid-US-plans-to-boost-EU-rescue-fund.html\" class=\"gen\">27 septembre 2011<\/a>, s&rsquo;attache \u00e0 cet aspect du d\u00e9sordre.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>German finance minister Wolfgang Schauble said it would be a folly to boost the EU&rsquo;s bail-out machinery (EFSF) beyond its 440bn lending limit by deploying leverage to up to 2 trillion, perhaps by raising funds from the European Central Bank. I don&rsquo;t understand how anyone in the European Commission can have such a stupid idea. The result would be to endanger the AAA sovereign debt ratings of other member states. It makes no sense, he said.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Mr Schauble told Washington to mind its own businesss after President Barack Obama rebuked EU leaders for failing to recapitalise banks and allowing the debt crisis to escalate to the point where it is scaring the world. It&rsquo;s always much easier to give advice to others than to decide for yourself. I am well prepared to give advice to the US government, he said.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The comments risk irritating the White House. US Treasury Secretary Tim Geithner has been a key driver of plans to give the EFSF enough firepower to shore up Italy and Spain, fearing a drift into cascading default, bank runs and catastrophic risk without dramatic action. The danger for Germany is that America will lose patience, with unpredictable consequences. The US Federal Reserve is currently propping up the European banking system in a variety of ways, including dollar swaps.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEn v\u00e9rit\u00e9, il nous semblerait extr\u00eamement audacieux et finalement compl\u00e8tement infond\u00e9, sinon faussaire, de tirer des enseignements d&rsquo;ordre politique et g\u00e9opolitique de tous ces \u00e9v\u00e8nements. (Par enseignements d&rsquo;ordre politique et g\u00e9opolitique, nous entendons des raisonnements ou des perspectives de r\u00e9alignement, de type europ\u00e9en ou transatlantique, \u00e0 l&rsquo;int\u00e9rieur du bloc BAO, selon les r\u00e9f\u00e9rences signal\u00e9es plus haut d&rsquo;alignement ou d&rsquo;isolation, voire m\u00eame d&rsquo;alliances de circonstance hors des influences d&rsquo;un <em>leadership<\/em> qui n&rsquo;est plus exerc\u00e9 par personne,  particuli\u00e8rement par les USA, qui ont d\u00e9finitivement abdiqu\u00e9 leur position de pr\u00e9dominance.) Ces divers reclassements, \u00e9volutions des uns par rapport aux autres, sont absolument circonstanciels, devant des \u00e9v\u00e8nements que personne ne contr\u00f4le, que les centaines de milliards d&rsquo;euros ou de dollars valsant dans tous les azimuts ne contr\u00f4lent pas davantage. Il y a dans cette situation, pour notre compte, deux faits majeurs \u00e0 signaler.<\/p>\n<\/p>\n<p><p>\t D&rsquo;une part, le d\u00e9sordre impos\u00e9s par les \u00e9v\u00e9nements (et non le d\u00e9sordre des \u00e9v\u00e9nements). Les \u00e9v\u00e8nements vont dans un seul sens, qui est de montrer et de d\u00e9montrer inlassablement que le Syst\u00e8me est en crise terminale, que tous les actes et toutes les mesures prises en son nom et selon ses r\u00e8gles d&rsquo;action sont faussaires et inefficaces. Le d\u00e9sordre qui en r\u00e9sulte, qui est effectivement le produit des \u00e9v\u00e8nements mais seulement d&rsquo;un point de vue conjoncturel, d\u00e9gage au contraire une le\u00e7on fondamentale qui est en elle-m\u00eame le contraire du d\u00e9sordre des \u00e9v\u00e9nements. Cette le\u00e7on est que le Syst\u00e8me en place et tous les actes et mesures qu&rsquo;il est conduit \u00e0 prendre sont les seuls g\u00e9n\u00e9rateurs du d\u00e9sordre, m\u00eame s&rsquo;ils le sont par des canaux indirects. Les \u00e9v\u00e8nements imposent cette conclusion, et mettent ainsi en \u00e9vidence le caract\u00e8re catastrophique de la situation du Syst\u00e8me. Le d\u00e9sordre est, dans ce cas, la d\u00e9monstration <em>ad absurdo<\/em> que l&rsquo;ordre arbitraire et faussaire impos\u00e9 jusqu&rsquo;ici par le Syst\u00e8me est en v\u00e9rit\u00e9 la source, non seulement de tous les maux, mais \u00e9galement de tous les d\u00e9sordres.<\/p>\n<\/p>\n<p><p>\t Le second fait majeur est l&rsquo;\u00e9puisement grandissant des directions politiques. Plac\u00e9es devant l&rsquo;impasse fondamentale qu&rsquo;impliquent le Syst\u00e8me et ses divers blocages, et le d\u00e9sordre qui en r\u00e9sulte, les directions politiques sont soumises \u00e0 des contraintes sans nombre et qui vont dans tous les sens. Elles se trouvent comme d&rsquo;habitude prises dans la tenaille du d\u00e9r\u00e8glement fondamental du Syst\u00e8me avec ses exigences diverses dont l&rsquo;effet g\u00e9n\u00e9ral est le d\u00e9sordre qu&rsquo;on a vu plus haut ; et, d&rsquo;autre part, les exigences pressantes de leurs situations int\u00e9rieures, cette fois aussi bien les opinions publiques que leurs bases politiques, voire une partie non n\u00e9gligeable de leurs directions politiques elles-m\u00eames. Ces deux forces sont directement antagonistes, puisque le Syst\u00e8me est construit selon une logique absolument d\u00e9structurante et dissolvante de tout ce qui fait les identit\u00e9s et les l\u00e9gitimit\u00e9s existantes (qu&rsquo;elles soient nationales, communautaires, r\u00e9gionales, etc., quand elles existent \u00e0 ce niveau). Il r\u00e9sulte de cette situation un formidable \u00e9puisement psychologique des directions politiques actives, qui rend leurs actions de plus en plus erratiques, \u00e9ventuellement conflictuelles sans qu&rsquo;il y ait le moindre plan ou vues construites au del\u00e0 du plus imm\u00e9diat court terme. Les psychologies de ces directions politiques sont marqu\u00e9es par le d\u00e9sarroi, la perte des r\u00e9f\u00e9rences stables, l&rsquo;incompr\u00e9hension et le repli sur une action retardataire du processus d&rsquo;effondrement sans aucune autre perspective que la tentative de r\u00e9action au coup par coup. On doit envisager la probabilit\u00e9 que cet \u00e9puisement psychologique provoquera, \u00e0 un moment ou l&rsquo;autre, des r\u00e9actions incontr\u00f4l\u00e9es g\u00e9n\u00e9ratrices d&rsquo;\u00e9v\u00e9nements qui feraient soudainement acc\u00e9l\u00e9rer le processus actuel d&rsquo;effondrement. <\/p>\n<\/p>\n<p><p>\tL&rsquo;ensemble de cette situation acte la poursuite tr\u00e8s rapide de l&rsquo;effondrement du Syst\u00e8me. La concentration du d\u00e9sordre et de l&rsquo;\u00e9puisement des directions politiques dans les pays et les zones du bloc BAO confirme effectivement, \u00e0 c\u00f4t\u00e9 des consid\u00e9rations financi\u00e8res et autres, la chute du Syst\u00e8me en tant que tel puisque le bloc BAO en est \u00e0 la fois le moteur et le promoteur essentiels. Nous ne voyons en aucune fa\u00e7on que les autres puissances et zones diverses ext\u00e9rieures au bloc BAO puissent se substituer \u00e0 ce bloc pour reprendre le Syst\u00e8me \u00e0 leur compte, selon un sch\u00e9ma classique de transfert, notamment g\u00e9opolitique, de puissance. Simplement, ces puissances et ces zones ext\u00e9rieures sont logiquement en marge de la catastrophe mais elles ne pourront en aucun cas l&#8217;emp\u00eacher, notamment par une r\u00e9forme d&rsquo;un Syst\u00e8me dont la caract\u00e9ristique fondamentale est d&rsquo;\u00eatre absolument irr\u00e9formable,  vu son herm\u00e9tisme d&rsquo;une part, son emprisonnement dans ses dynamiques de surpuissance et d&rsquo;autodestruction d&rsquo;autre part.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 28 septembre 2011 \u00e0 09H38<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une situation tend \u00e0 devenir d\u00e9sormais structurelle au sein du bloc BAO (bloc am\u00e9ricaniste-occidentaliste), qui est une situation de division et d&rsquo;antagonisme. Il nous para\u00eet vain de tenter d&rsquo;identifier, selon les normes h\u00e9rit\u00e9es de cet autre temps du leadership US o\u00f9 comptaient des notions de type servile comme l&rsquo;alignement ou l&rsquo;isolement, des positions sp\u00e9cifiques en&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[10900,6039,2803,9580,398,3841,11530,4633,8355,3741,1205],"class_list":["post-74095","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-bao","tag-bloc","tag-effondrement","tag-epuisement","tag-europe","tag-grece","tag-greithner","tag-merkel","tag-psychologies","tag-psychologique","tag-transatlantique"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74095"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74095\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}