{"id":74105,"date":"2011-10-01T09:20:09","date_gmt":"2011-10-01T09:20:09","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/10\/01\/psychologie-du-trader-au-psychopathe\/"},"modified":"2011-10-01T09:20:09","modified_gmt":"2011-10-01T09:20:09","slug":"psychologie-du-trader-au-psychopathe","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/10\/01\/psychologie-du-trader-au-psychopathe\/","title":{"rendered":"Psychologie, du <em>trader<\/em> au psychopathe"},"content":{"rendered":"<p><p>Au d\u00e9but de la semaine, la confession t\u00e9l\u00e9visuelle d&rsquo;un <em>trader<\/em> (ou assimil\u00e9) de la <em>City<\/em> de Londres, sur la BBC, a fait sensation. Alessio Rastani n&rsquo;a pourtant dit que tout ce que tout le monde sait Par exemple : \u00ab<em>I&rsquo;m dreaming of this moment for three years  I go to bed every night dreaming of another recession. It&rsquo;s an opportunity.<\/em>\u00bb Ou encore : \u00ab<em>Governments don&rsquo;t rule the world, Goldman Sachs rules the world<\/em> [<em>and<\/em>] <em>Goldman Sachs does not care about the rescue package.<\/em>\u00bb Certains avaient d&rsquo;abord cru \u00e0 un montage, qu&rsquo;Alessio Rastani \u00e9tait un artiste jouant un <em>trader<\/em> qui aurait flou\u00e9 la BBC ; cela s&rsquo;est av\u00e9r\u00e9 inexact, Rastani existe et nous l&rsquo;avons tous reconnu (voir le <em>Guardian<\/em>, le <a href=\"http:\/\/www.guardian.co.uk\/media\/2011\/sep\/27\/trader-goldman-sachs-bbc-hoax?INTCMP=SRCH\" class=\"gen\">27 septembre 2011<\/a>, puis le <a href=\"http:\/\/www.guardian.co.uk\/commentisfree\/2011\/sep\/29\/alessio-rastani-no-prank\" class=\"gen\">29 septembre 2011<\/a>). Le <em>Daily Telegraph<\/em> du <a href=\"http:\/\/www.telegraph.co.uk\/finance\/economics\/8792829\/BBC-financial-expert-Alessio-Rastani-Im-an-attention-seeker-not-a-trader.html\" class=\"gen\">27 septembre 2011<\/a> avait effectivement, entretemps, retrouv\u00e9 Rastani et l&rsquo;avait interview\u00e9 \u00e0 nouveau, pour bien confirmer qu&rsquo;il s&rsquo;agit d&rsquo;un <em>trader<\/em> ou assimil\u00e9, comme vous et moi.<\/p>\n<\/p>\n<p><p>\tEntretemps \u00e0 nouveau, <em>Le Figaro<\/em> avait publi\u00e9 un article d&rsquo;Isabelle Foucaud le <a href=\"http:\/\/recherche.lefigaro.fr\/recherche\/access\/lefigaro_fr.php?archive=BszTm8dCk78atGCYonbyzq1O0vYua8FOGTrH3lmcLkXQZhzw6llv0xRfGJx2iVrYu2IGtjAq08M%3D\" class=\"gen\">28 septembre 2011<\/a>, sur une \u00e9tude pour la pr\u00e9paration d&rsquo;une th\u00e8se \u00e0 l&rsquo;universit\u00e9 de Saint-Gall, en Suisse, de Pascal Scherrer, un expert l\u00e9giste, et Thomas Noll, un administrateur de la prison de P\u00f6schwies (Zurich). Les Suisses sont int\u00e9ress\u00e9s par les <em>traders<\/em> depuis que l&rsquo;affaire du <em>trader<\/em> fraudeur de la banque UBS. L&rsquo;\u00e9tude de Scherrer-Noll s&rsquo;int\u00e9resse \u00e0 la psychologie des <em>traders<\/em>, qui s&rsquo;av\u00e8re d&rsquo;un type assez proche de celle des psychopathes, mais en plus accentu\u00e9e (que celle des psychopathes, s\u00e9rions tout de m\u00eame les dangers).<\/p>\n<\/p>\n<p><p>\t\u00ab[I]<em>ls ont soumis un groupe de 28 investisseurs professionnels issus de plateformes de trading sur produits d\u00e9riv\u00e9s, le forex et de capital investissement  \u00e0 des tests d&rsquo;intelligence et des simulations informatiques afin d&rsquo;\u00e9valuer leur aptitude \u00e0 coop\u00e9rer et leur degr\u00e9 d&rsquo;individualisme. Ont \u00e9t\u00e9 \u00e9galement pass\u00e9s au crible leur capacit\u00e9 \u00e0 se rebeller, leur d\u00e9sir de pouvoir, leur immunit\u00e9 au stress et \u00e0 la peur. Les r\u00e9sultats ont \u00e9t\u00e9 compar\u00e9s \u00e0 ceux d&rsquo;une \u00e9tude conduite aupr\u00e8s de 24 psychopathes hospitalis\u00e9s dans des \u00e9tablissements hautement s\u00e9curis\u00e9s en Allemagne.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLes r\u00e9sultats sont concluants : les <em>traders<\/em> sont plus psychopathes que les psychopathes, du point de vie des caract\u00e8res de tension et d&rsquo;agressivit\u00e9 de la psychologie. Noll a d\u00e9clar\u00e9 au <em>Spiegel<\/em> : \u00ab<em>Evidemment, on ne peut pas dire que tous les traders sont d\u00e9rang\u00e9s. Mais il s&rsquo;est av\u00e9r\u00e9 qu&rsquo;ils ont eu un comportement plus \u00e9gocentrique et ont \u00e9t\u00e9 plus enclins \u00e0 prendre des risques que le groupe de psychopathes qui ont \u00e9t\u00e9 soumis aux m\u00eames tests.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDans le m\u00eame article du <em>Figaro<\/em>, on rappelle, sans surprise esp\u00e8re-t-on, qu&rsquo;une \u00e9tude du <em>New Scientist<\/em> de 2004 donnait des r\u00e9sultats assez proches pour une autre cat\u00e9gorie professionnelle, dans le m\u00eame environnement psychologique fait d&rsquo;exigences de comp\u00e9titivit\u00e9, de total individualisme, de cloisonnement complet vis-\u00e0-vis des conditions r\u00e9elles du monde, bref une psychologie-Syst\u00e8me par d\u00e9finition.  (\u00ab<em>New Scientist comparait les employ\u00e9s d\u00e9sireux de grimper l&rsquo;\u00e9chelle hi\u00e9rarchique de leur entreprise avec des psychopathes, \u00e0 cause de leur manque d&#8217;empathie et de compassion dans un environnement de stress.<\/em>\u00bb). D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, tous ces divers chercheurs confirment que l&rsquo;essentiel de cette psychologie n&rsquo;est pas l&rsquo;app\u00e2t du gain, qui ne peut \u00eatre un caract\u00e8re psychologique puisqu&rsquo;il s&rsquo;agit du r\u00e9sultat \u00e9labor\u00e9 d&rsquo;une intelligence influenc\u00e9e par sa psychologie ; le caract\u00e8re essentiel est le besoin pressant de comp\u00e9titivit\u00e9 d\u00e9velopp\u00e9 par une psychologie tr\u00e8s individualiste, et renfor\u00e7ant cette individualisme ; cela, avec la question essentielle de savoir qui est cr\u00e9ateur de qui au d\u00e9part,  la psychologie individualiste entra\u00eenant le besoin de comp\u00e9titivit\u00e9, ou la n\u00e9cessit\u00e9-Syst\u00e8me de la comp\u00e9titivit\u00e9 cr\u00e9ant et d\u00e9veloppant une psychologie de plus en plus individualiste. (\u00ab<em>Selon les chercheurs, le moteur principal des traders n&rsquo;est pas de d\u00e9gager les gains les plus importants, mais de prendre l&rsquo;avantage sur leurs concurrents. Dans un contexte de comp\u00e9tition, ils abandonnent toute approche r\u00e9fl\u00e9chie et strat\u00e9gique de l&rsquo;investissement dans le seul but d&rsquo;\u00e9craser leurs adversaires.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tComme c&rsquo;est le cas en g\u00e9n\u00e9ral pour nombre de d\u00e9monstrations scientifiques, notamment en mati\u00e8re de psychologie, les recherches se concluent par l&rsquo;enfon\u00e7age de portes ouvertes, c&rsquo;est-\u00e0-dire la confirmation d&rsquo;\u00e9vidences intuitives. La psychologie des <em>traders<\/em> \u00e9quivalente \u00e0 la psychologie des psychopathes, en plus accentu\u00e9e, n&rsquo;est qu&rsquo;un exemple d&rsquo;une psychologie g\u00e9n\u00e9rale qui est formidablement influenc\u00e9e par le Syst\u00e8me, \u00e0 mesure de l&rsquo;affaiblissement continuel de cette psychologie tel que nous l&rsquo;observons dans un cadre g\u00e9n\u00e9ral o\u00f9 la psychologie joue un r\u00f4le fondamental. Cet affaiblissement se fait toujours dans le sens de l&rsquo;individualisme, du cloisonnement de la psychologie qui correspond \u00e0 son emprisonnement, de l&rsquo;isolement  et de l&rsquo;appauvrissement spirituels qui en r\u00e9sultent, de la perte totale de la capacit\u00e9 d&rsquo;int\u00e9gration des psychologies dans une situation g\u00e9n\u00e9rale du monde marqu\u00e9e de plus en plus, \u00e0 cause de ce fait psychologique additionn\u00e9 \u00e0 la puissance du <a href=\"http:\/\/www.dedefensa.org\/article-presentation_de_la_cinquieme_partie_de_la_grace_de_l_histoire_02_12_2010.html\" class=\"gen\">technologisme<\/a>, par une crise profonde. (Cette crise profonde, bien s\u00fbr, qui peut \u00eatre, plus simplement, per\u00e7ue comme la crise g\u00e9n\u00e9rale que nous connaissons aujourd&rsquo;hui, ou <a href=\"http:\/\/www.dedefensa.org\/article-la_chute_ou_la_saison_de_notre_heroisme_29_09_2011.html\" class=\"gen\">la crise de la Chute<\/a>.)<\/p>\n<\/p>\n<p><p>\tNotre appr\u00e9ciation sur ces questions est bien connue,  sur le r\u00f4le fondamental de la psychologie, sa vuln\u00e9rabilit\u00e9 aux pressions du Syst\u00e8me ou, d&rsquo;une fa\u00e7on plus g\u00e9n\u00e9rale, aux forces qui ont enfant\u00e9 le <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_source_de_tous_les_maux_ddecrisis_10_09_2010.html\" class=\"gen\">d\u00e9cha\u00eenement de la Mati\u00e8re<\/a>,  pour ces forces, \u00e0 commencer par notre th\u00e8se sur le <a href=\"http:\/\/www.dedefensa.org\/article-sommes-nous_en_1789__14_07_2010.html\" class=\"gen\">persiflage<\/a> au XVIII\u00e8me si\u00e8cle. Que cela se retrouve chez un <em>trader<\/em> ou assimil\u00e9 interview\u00e9 \u00e0 la BBC, et chez les <em>traders<\/em> en g\u00e9n\u00e9ral, ceux-ci un peu plus psychologiquement d\u00e9s\u00e9quilibr\u00e9s que les psychopathes, cela n&rsquo;a rien pour \u00e9tonner. Au reste, entre <em>traders<\/em> et psychopathes, il y a un comportement et des actes similaires, simplement l&rsquo;objet change ; il n&rsquo;est pas assur\u00e9 que l&rsquo;assassinat du monde (par le <em>trader<\/em>) soit moins catastrophique, ou condamnable pour les esprits qui s&rsquo;en tiennent aux dimensions juridique et morale des chose, que les actes des psychopathes.<\/p>\n<\/p>\n<p><p>\tLe plus remarquable, finalement, est que l&rsquo;on continue \u00e0 accumuler la d\u00e9monstration et la confirmation scientifique des \u00e9vidences que l&rsquo;intuition impose depuis longtemps, et qu&rsquo;aucune conclusion structur\u00e9e et m\u00e9dit\u00e9e quant \u00e0 la validit\u00e9 du Syst\u00e8me qui nous tient n&rsquo;est tir\u00e9e, dans tous les cas dans ces divers milieux-Syst\u00e8me qui sont cit\u00e9s ici. (L&rsquo;article du <em>Figaro<\/em> est <strong>extraordinaire<\/strong> de ce point de vue,  ou bien simplement exemplaire, apr\u00e8s tout : aucune mise en question du Syst\u00e8me, ou simplement du syst\u00e8me financier, ou simplement de la doctrine \u00e9conomique qui anime tout cela en imposant les <em>traders<\/em> qui attendent avec passion la prochaine r\u00e9cession,  rien, absolument rien qui se rapproche de cela) Il est vrai, puisque le Syst\u00e8me les tient tous, des <em>traders<\/em> aux journalistes-Syst\u00e8me en passant par les scientifiques, qu&rsquo;il n&rsquo;y a aucune raison pour qu&rsquo;ils le d\u00e9noncent. Nous savons depuis longtemps que l&rsquo;\u00e9volution fondamentale ne vient pas du <em>sapiens<\/em> courant, compl\u00e8tement subjugu\u00e9 par le Syst\u00e8me, qu&rsquo;il soit <em>trader<\/em>-psychopathe, ou commentateur-Syst\u00e8me et scientifique qui s&rsquo;effraient de d\u00e9couvrir que <em>trader<\/em> et psychopathe ne font \u00e0 peu pr\u00e8s qu&rsquo;un. Autres d\u00e9monstration et confirmation, certes, du travers humain concentr\u00e9 dans une consid\u00e9rable faiblesse bien plus qu&rsquo;un caract\u00e8re mauvais qui lui soit propre, puisque ce caract\u00e8re m\u00eame du Mal est bien et fermement substantiv\u00e9 par le Syst\u00e8me lui-m\u00eame (<em>dito<\/em>,  <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_source_de_tous_les_maux_ddecrisis_10_09_2010.html\" class=\"gen\">la Mati\u00e8re<\/a>). Comme le disait <a href=\"http:\/\/www.dedefensa.org\/article-la_chute_ou_la_saison_de_notre_heroisme_29_09_2011.html\" class=\"gen\">Plotin<\/a>, \u00e9videmment fort rarement cit\u00e9 dans <em>Le Figaro<\/em> et lui-m\u00eame sans gu\u00e8re d&rsquo;exp\u00e9rience de <em>trader<\/em> : \u00ab<em>Mais les autres, ceux qui participeraient de lui et s&rsquo;y assimileraient, deviennent mauvais, n&rsquo;\u00e9tant pas mauvais en soi.<\/em>\u00bb Tout cela vient donc d&rsquo;un peu de faiblesse humaine qu&rsquo;un peu de sable ne manquera pas d&rsquo;effacer,  apr\u00e8s les prochaines temp\u00eates<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 1er octobre 2011 \u00e0 09H18<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au d\u00e9but de la semaine, la confession t\u00e9l\u00e9visuelle d&rsquo;un trader (ou assimil\u00e9) de la City de Londres, sur la BBC, a fait sensation. Alessio Rastani n&rsquo;a pourtant dit que tout ce que tout le monde sait Par exemple : \u00abI&rsquo;m dreaming of this moment for three years I go to bed every night dreaming of&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[8992,2631,8854,3879,2622,8855,11541,9839,3099,11539,11540,11538],"class_list":["post-74105","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-competitivite","tag-de","tag-dechainement","tag-individualisme","tag-la","tag-matiere","tag-noll","tag-persiflage","tag-psychologie","tag-rastani","tag-scherrer","tag-trader"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74105"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74105\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}