{"id":74123,"date":"2011-10-07T16:28:23","date_gmt":"2011-10-07T16:28:23","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/10\/07\/le-tribunal-pour-les-dirigeants-de-dexia\/"},"modified":"2011-10-07T16:28:23","modified_gmt":"2011-10-07T16:28:23","slug":"le-tribunal-pour-les-dirigeants-de-dexia","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/10\/07\/le-tribunal-pour-les-dirigeants-de-dexia\/","title":{"rendered":"Le tribunal pour les dirigeants de Dexia"},"content":{"rendered":"<p><h2 class=\"common-article2\">Le tribunal pour les dirigeants de Dexia<\/h2>\n<\/p>\n<p><p>\tCe n&rsquo;est pas tr\u00e8s sympathique d&rsquo;en appeler aux tribunaux, voire aux tribunaux p\u00e9naux, pour des gens qui dira-t-on n&rsquo;ont \u00e9t\u00e9 coupables que de mauvaise gestion. De plus, \u00e0 quoi bon puisque le droit ne sanctionne pas de tels faits? Pourtant, \u00e0 une \u00e9poque o\u00f9, \u00e0 juste titre, on souligne les responsabilit\u00e9s du secteur bancaire dans la crise politique et \u00e9conomique actuelle, comment ne pas r\u00e9agir devant des comportements qui sont proches du vol qualifi\u00e9. <\/p>\n<\/p>\n<p><p>\tVoici des gens, au conseil d&rsquo;administration et dans les \u00e9quipes dirigeantes, qui ont h\u00e9rit\u00e9 d&rsquo;une \u00e9pargne historique, celle destin\u00e9es aux collectivit\u00e9s locales dans la branche fran\u00e7aise de Dexia. Des milliers de collectivit\u00e9s comptaient sur ce patrimoine pour financer des investissements \u00e0 la fois utiles et sans risques particuliers. Mais saisis parce qu&rsquo;il faut bien appeler une folie des grandeurs  et un  go\u00fbt du lucre forcen\u00e9, ces gens ont utilis\u00e9 ces fonds pour sp\u00e9culer \u00e0 haut risque, afin de se rendre plus puissants et riches qu&rsquo;ils n&rsquo;\u00e9taient. Issus du service public, ils en ont foul\u00e9 aux pieds les principes. Comme de plus ils \u00e9taient sensibles aux pressions politiques (celles de qui vous savez en France) et comme par ailleurs ils \u00e9taient cons (excusez le mot), ils ont fait les plus mauvais choix possibles pour plaire aux princes.<\/p>\n<\/p>\n<p><p>\tAujourd&rsquo;hui, dira-t-on, tous les patrons, tous les conseils d&rsquo;administrations font de m\u00eame, gaspillant pour de vaines sp\u00e9culations et souvent des superprofits personnels les r\u00e9serves des entreprises.  Ils mettent ce faisant au ch\u00f4mage des dizaines de milliers de salari\u00e9s qui, eux, faisaient bien leur travail. Pourquoi s&rsquo;en prendre \u00e0 Dexia? <\/p>\n<\/p>\n<p><p>\tParce que, puisqu&rsquo;on les a sous la main, il faudrait les faire payer \u00e0 titre d&rsquo;exemple pour les autres. Cela ferait r\u00e9fl\u00e9chir leurs homologues de la Caisse des D\u00e9p\u00f4ts et de la Banque Postale qui s&rsquo;appr\u00eatent \u00e0 prendre les m\u00eames risques avec une \u00e9pargne qui ne leur appartient pas. Au lieu de d\u00e9missionner, les responsables de ces organismes s&rsquo;appr\u00eatent \u00e0 ob\u00e9ir  aux  nouvelles injonctions d&rsquo;un prince en fin de course mais capable encore de faire de gros d\u00e9g\u00e2ts avant de c\u00e9der la place.<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Jean-Paul Baquiast<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le tribunal pour les dirigeants de Dexia Ce n&rsquo;est pas tr\u00e8s sympathique d&rsquo;en appeler aux tribunaux, voire aux tribunaux p\u00e9naux, pour des gens qui dira-t-on n&rsquo;ont \u00e9t\u00e9 coupables que de mauvaise gestion. De plus, \u00e0 quoi bon puisque le droit ne sanctionne pas de tels faits? Pourtant, \u00e0 une \u00e9poque o\u00f9, \u00e0 juste titre, on&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[831,11554,11361,11556,11555,7112],"class_list":["post-74123","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-a","tag-dexia","tag-gestion","tag-hauts","tag-placements","tag-risques"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74123"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74123\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}