{"id":74144,"date":"2011-10-14T16:39:08","date_gmt":"2011-10-14T16:39:08","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/10\/14\/drones-infectes-de-lusaf-le-virus-est-aussi-dans-la-communication\/"},"modified":"2011-10-14T16:39:08","modified_gmt":"2011-10-14T16:39:08","slug":"drones-infectes-de-lusaf-le-virus-est-aussi-dans-la-communication","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/10\/14\/drones-infectes-de-lusaf-le-virus-est-aussi-dans-la-communication\/","title":{"rendered":"<em>Drones<\/em> infect\u00e9s de l&rsquo;USAF : le virus est aussi dans la communication"},"content":{"rendered":"<p><p>C&rsquo;est le site <em>Danger Room<\/em> qui avait rendu publique la nouvelle qu&rsquo;un virus avait infect\u00e9 les ordinateurs de bord de conduite de <em>drone<\/em> type UCAV <em>Raptor<\/em> et <em>Rapeer<\/em> (le <a href=\"http:\/\/www.wired.com\/dangerroom\/2011\/10\/virus-hits-drone-fleet\/\" class=\"gen\">7 octobre 2011<\/a>). C&rsquo;est encore et toujours <em>Danger Room<\/em> qui annonce, ce <a href=\"http:\/\/www.wired.com\/dangerroom\/2011\/10\/drone-virus-kept-quiet\/\" class=\"gen\">11 octobre 2011<\/a>, un aspect encore plus sensationnel de cette affaire. Il s&rsquo;agit de la mise en \u00e9vidence que le probl\u00e8me, d\u00e9tect\u00e9 par le personnel servant ces engins \u00e0 partir de  la base de Creech, aux USA, n&rsquo;a pas diffus\u00e9 la nouvelle dans sa hi\u00e9rarchie, notamment aupr\u00e8s des unit\u00e9s de cyberguerre du commandement dont d\u00e9pend la base (la 24th Air Force). <\/p>\n<\/p>\n<p><p>\tLes gens de la cyberguerre de la 24th Air Force ont appris la nouvelle dans Danger Room, explique <em>Danger Room<\/em> dans son article ; \u00ab<em>the four-star general who oversees the Air Force&rsquo;s networks was briefed on the infection this morning<\/em>\u00bb (le 11 octobre 2011). L&rsquo;article est encombr\u00e9 de longues explications, venues de diverses sources, expliquant le cloisonnement qui existe entre les r\u00e9seaux des diverses unit\u00e9s, services, groupes de l&rsquo;Air Force, ce qui fait de la r\u00e9tention d&rsquo;informations \u00e0 l&rsquo;int\u00e9rieur de l&rsquo;USAF un sport assez courant et commun.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Officials at Creech Air Force Base in Nevada knew for two weeks about a virus infecting the drone cockpits there. But they kept the information about the infection to themselves  leaving the unit that&rsquo;s supposed to serve as the Air Force&rsquo;s cybersecurity specialists in the dark. The network defenders at the 24th Air Force learned of the virus by reading about it in Danger Room.<\/em> [] <em>It was not highlighted to us, says a source involved with Air Force network operations. When your article came out, it was like, What is this?&rsquo;<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em> The four branches of the U.S. armed forces each has a dedicated unit that, in theory, is supposed to handle cyber defense for the entire service. The 24th Air Force, for example, is the operational warfighting organization that establishes, operates, maintains and defends Air Force networks, according to a military fact sheet. These units are then supposed to provide personnel and information to U.S. Cyber Command, which is supposed to oversee the military&rsquo;s overall network defense.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>In practice, it&rsquo;s not that simple. Unlike most big private enterprises, the 24th doesn&rsquo;t have a centralized system for managing and monitoring its networks. There&rsquo;s no place at the 24th&rsquo;s San Antonio headquarters where someone could see all the digital traffic hurtling through the service&rsquo;s pipes. In fact, most of the major commands within the Air Force don&rsquo;t have formal agreements to carry the other&rsquo;s network traffic. (The 24th Air Force did not immediately respond to requests to comment for this article.)<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>We&rsquo;d never managed the entire Air Force network as a single enterprise, Vince Ross, the program manager of the Air Force Electronic Systems Center&rsquo;s Cyber Integration Division, said in March. That meant there was no centralized management of the network, that systems and hardware weren&rsquo;t standardized, and that top-level commanders didn&rsquo;t have complete situational awareness.<\/p>\n<\/p>\n<p><p>\tThe plan is to one day integrate all that infrastructure into a single Air Force network. But for now, it&rsquo;s largely cybersecurity by the honor system. Each base and each unit in the Air Force has its own geek squad. They only call for help if there&rsquo;s a broader network problem, or if they&rsquo;re truly stumped.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEt l&rsquo;on pourrait supposer avec toutes les raisons du monde que ce qui est vrai pour l&rsquo;USAF, l&rsquo;est aussi pour la Navy et pour l&rsquo;U.S. Army, et pour d&rsquo;autres services encore, et ainsi de suite. Ce qui est sugg\u00e9r\u00e9 avec insistance comme un embarras technique propre \u00e0 l&rsquo;USAF, du fait d&rsquo;un manque de moyens et de temps pour effectivement int\u00e9grer les r\u00e9seaux disparates fonctionnant au sein de l&rsquo;USAF, est en r\u00e9alit\u00e9 une d\u00e9rive subversive de la situation conjugu\u00e9e des bureaucraties et des r\u00e9seaux \u00e0 mesure que sont introduites, de plus en plus rapidement, de nouvelles technologiques et de nouvelles expansions des r\u00e9seaux. La robotisation grandissante des actions ext\u00e9rieures transporte le cadre de l&rsquo;intervention, du th\u00e9\u00e2tre d&rsquo;op\u00e9rations aux services ad\u00e9quats install\u00e9s dans l&rsquo;ensemble bureaucratique national, aux USA. Les r\u00e9flexes de coop\u00e9ration inh\u00e9rents \u00e0 des arm\u00e9es en campagne, \u00e0 cause des conditions <strong>r\u00e9elles<\/strong> de combat, existent (ou existaient) m\u00eame dans les forces US malgr\u00e9 la compartimentation et les antagonismes inter-services qui ont toujours \u00e9t\u00e9 des caract\u00e9ristiques sp\u00e9cifiques du cadre am\u00e9ricaniste ; ces r\u00e9flexes sont en train de dispara\u00eetre avec le transfert de l&rsquo;acte op\u00e9rationnel du th\u00e9\u00e2tre des op\u00e9rations aux labyrinthes bureaucratiques existant au cur de la soci\u00e9t\u00e9-Syst\u00e8me postmoderniste. (Cette tendance est encore accentu\u00e9e par le caract\u00e8re des guerres actuelles, o\u00f9 existent \u00e0 la fois une parano\u00efa du secret et une parano\u00efa de l&rsquo;action ind\u00e9pendante, notamment au travers de l&#8217;emploi des diverses forces sp\u00e9ciales ou des forces et milices priv\u00e9es.) <\/p>\n<\/p>\n<p><p>\tAinsi, ce qui est d\u00e9crit comme un fait technique qui devrait \u00eatre corrig\u00e9 \u00e0 mesure que la situation est identifi\u00e9e et analys\u00e9e, nous appara\u00eet, \u00e0 nous, comme un fait bureaucratique, technologique et psychologique en pleine expansion, \u00e0 l&rsquo;image des r\u00e9seaux, et en constante aggravation. A cet \u00e9gard, l&rsquo;\u00e9l\u00e9ment humain est de plus en plus int\u00e9gr\u00e9 dans les r\u00e9seaux et se comporte de plus en plus \u00e0 l&rsquo;image de ces faits objectivement non-humains qui caract\u00e9risent de plus en plus le Syst\u00e8me, notamment pour ce qui concerne dans ce cas le fait-bureaucratique et le fait-technologique, chacun en tant que tel. Il s&rsquo;agit d&rsquo;un processus d&rsquo;accroissement acc\u00e9l\u00e9r\u00e9 de l&rsquo;incontr\u00f4labilit\u00e9 du Syst\u00e8me. Les seuls \u00e9l\u00e9ments \u00e9chappant \u00e0 ces processus sont des r\u00e9voltes humaines individuelles, poussant l&rsquo;un ou l&rsquo;autre \u00e0 divulguer une information accessible sur un r\u00e9seau et pas sur les autres, et de plus en plus vers la presse non-Syst\u00e8me, ou appr\u00e9ci\u00e9e comme telle,   qui est la presse de l&rsquo;Internet, appr\u00e9ci\u00e9e comme non inf\u00e9od\u00e9e au Syst\u00e8me (dans ce cas, le r\u00e9seau qu&rsquo;est l&rsquo;Internet pour l&rsquo;information joue le r\u00f4le inverse de d\u00e9nonciateur de la situation des r\u00e9seaux-Syst\u00e8me, conform\u00e9ment \u00e0 l&rsquo;attitude de <a href=\"http:\/\/www.dedefensa.org\/article-dialogues-13_de_la_sublimite_du_systeme_de_la_communication_08_11_2010.html\" class=\"gen\">Janus<\/a> du syst\u00e8me de la communication). Un enseignement de plus de cette affaire est que l&rsquo;information de l&rsquo;Internet gagne encore plus en cr\u00e9dit, d\u00e9passant irr\u00e9m\u00e9diablement l&rsquo;information des pouvoirs officiels (y compris \u00e0 l&rsquo;int\u00e9rieur de leurs propres syst\u00e8mes) et l&rsquo;information de la presse-Syst\u00e8me. L&rsquo;ensemble donne l&rsquo;image d&rsquo;une soci\u00e9t\u00e9-Syst\u00e8me compl\u00e8tement bloqu\u00e9e, compl\u00e8tement en cours d&rsquo;absorption et de dissolution par le fait de l&rsquo;app\u00e9tit carnivore et aveugle de ses propres d\u00e9mons.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 14 octobre 2011 \u00e0 16H42<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est le site Danger Room qui avait rendu publique la nouvelle qu&rsquo;un virus avait infect\u00e9 les ordinateurs de bord de conduite de drone type UCAV Raptor et Rapeer (le 7 octobre 2011). C&rsquo;est encore et toujours Danger Room qui annonce, ce 11 octobre 2011, un aspect encore plus sensationnel de cette affaire. Il s&rsquo;agit de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2623,3015,4718,2631,10274,2622,3859,8590,8049,3014,3519],"class_list":["post-74144","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-bureaucratie","tag-communication","tag-danger","tag-de","tag-janus","tag-la","tag-raptor","tag-room","tag-subversion","tag-systeme","tag-technologie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74144"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74144\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}