{"id":74190,"date":"2011-10-29T05:57:47","date_gmt":"2011-10-29T05:57:47","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/10\/29\/les-veterans-des-guerres-postmodernistes-et-ows\/"},"modified":"2011-10-29T05:57:47","modified_gmt":"2011-10-29T05:57:47","slug":"les-veterans-des-guerres-postmodernistes-et-ows","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/10\/29\/les-veterans-des-guerres-postmodernistes-et-ows\/","title":{"rendered":"Les v\u00e9t\u00e9rans des guerres postmodernistes et OWS"},"content":{"rendered":"<p><p>Une question sp\u00e9cifique commence \u00e0 \u00eatre d\u00e9battue \u00e0 propos des \u00e9v\u00e9nements int\u00e9rieurs aux USA, concernant la participation de v\u00e9t\u00e9rans des diverses guerres entreprises par les USA depuis 2001 au mouvement OWS, ou <em>Occupy<\/em>. Elle est apparue lors d&rsquo;une sc\u00e8ne d\u00e9sormais fameuse, avec une vid\u00e9o devenue fameuse sur l&rsquo;Internet, de l&rsquo;ancien sergent des Marines Shamar Thomas, habill\u00e9 d&rsquo;un \u00e9quipement op\u00e9rationnel, s&rsquo;interposant entre les protestataires d&rsquo;OWS et la police, et apostrophant les policiers en d\u00e9non\u00e7ant leur brutalit\u00e9 (le <a href=\"http:\/\/www.rawstory.com\/rs\/2011\/10\/17\/decorated-marine-lectures-new-york-police-there-is-no-honor-in-this\/\" class=\"gen\">17 octobre 2011<\/a>). D&rsquo;autre part, il y a le cas de Scott Olsen, ancien Marine, <a href=\"http:\/\/www.rawstory.com\/rs\/2011\/10\/28\/doctors-scott-olsen-suffered-brain-damage-and-is-unable-to-speak\/\" class=\"gen\">gri\u00e8vement bless\u00e9<\/a> par un policier lors de la manifestation d&rsquo;Oakland du 24 octobre. <\/p>\n<\/p>\n<p><p>\t<em>Russia Today<\/em>, toujours extr\u00eamement attentif \u00e0 l&rsquo;\u00e9volution des \u00e9v\u00e9nements int\u00e9rieurs aux USA, aborde et d\u00e9veloppe cette question de la participation des v\u00e9t\u00e9rans (nous pr\u00e9f\u00e9rons ce terme \u00e0 celui de militaires employ\u00e9 dans le texte, on verra plus loin pourquoi). Observons que, dans ce texte, il est \u00e9galement question des policiers, notamment des grades subalternes, qui pourraient suivre \u00e9galement le mouvement, si on les consid\u00e8re comme partie int\u00e9grante des 99%<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The fact that more and more military personnel are joining us shows that they recognize that this is American movement. It&rsquo;s not about hippies and the negative stereotypes, said Occupy Wall Street security volunteer Paul Isaac.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>30 year old Gary Briggs has served in the National Guard for the last two years. He has come to spend his short vacation at Occupy Wall Street in New York. You got some marines here, National Guard, Navy Seals  the more the better, said Briggs. The guardsman expressed outrage at the fact that marines are getting attacked at home. The cop that did it should be fired and hung up by his balls, he said.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Others at Occupy Wall Street believe it won&rsquo;t be long, however, until the police join the crowds instead of restricting them. We are going to see a lot of the police officers protesting because they&rsquo;re going to work 20 years and they&rsquo;re going to see that their pension is zero, said Occupy Wall Street security colunteer Paul Isaac.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>But even if this doesn&rsquo;t happen  the movement won&rsquo;t be scared away any time soon with marines and other military vets pledging to have the protesters&rsquo; back. Everybody has banded together, and the rope that&rsquo;s being created here  no sword will cut, said protester Will Birnie.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tSans \u00e9carter l&rsquo;importance de la position des policiers des \u00e9chelons subalternes, bien au contraire, nous restons tout de m\u00eame concentr\u00e9s sur le sujet des v\u00e9t\u00e9rans, qui constitue en soi une probl\u00e9matique du plus grand int\u00e9r\u00eat aux USA. Il y a en effet plus d&rsquo;un million de v\u00e9t\u00e9rans de ce qu&rsquo;on pourrait d\u00e9signer comme les guerres postmodernistes, c&rsquo;est-\u00e0-dire les guerres d\u00e9clench\u00e9es apr\u00e8s le 11 septembre 2001 par les USA. Il s&rsquo;agit de conflits extr\u00eamement sp\u00e9cifiques, qu&rsquo;on a d\u00e9sign\u00e9s \u00e9galement comme des guerres de la 4\u00e8me g\u00e9n\u00e9ration (G4G), dont les motifs sont tr\u00e8s confus, notamment et particuli\u00e8rement pour ceux qui les font, qui impliquent des affrontement extr\u00eamement dissym\u00e9triques entre des arm\u00e9es am\u00e9ricanistes-occidentalistes tr\u00e8s sophistiqu\u00e9es et des adversaires \u00e9voluant entre la gu\u00e9rilla, le terrorisme de type religieux ou nationaliste, la r\u00e9sistance populaire contre l&rsquo;occupation, avec des m\u00e9thodes m\u00e9langeant des aspects primitifs et des aspects individuels sophistiqu\u00e9s. Ce sont des conflits cruels, souvent d&rsquo;une ill\u00e9galit\u00e9 av\u00e9r\u00e9e, avec des pertes civiles importantes et des destructions importantes et de tous ordres. Les arm\u00e9es du bloc BAO ont peu de pertes directes, et les bless\u00e9s sont tr\u00e8s souvent sauv\u00e9s gr\u00e2ce aux soins m\u00e9dicaux avanc\u00e9s, ce qui renforce encore le groupe des v\u00e9t\u00e9rans et son aspect psychologique tr\u00e8s d\u00e9s\u00e9quilibr\u00e9 et revendicatif. La d\u00e9bauche de mat\u00e9riels avanc\u00e9s de ces arm\u00e9es ajoute au sens d&rsquo;une guerre d\u00e9s\u00e9quilibr\u00e9e et incompr\u00e9hensible, et marque profond\u00e9ment les psychologies : les affections psychologiques des militaires du bloc BAO, essentiellement US, sont extr\u00eamement nombreuses, les suicides sont nombreux ; les v\u00e9ritables blessures les plus durables sont d&rsquo;ordre psychologique, ce qui fait de cette masse de v\u00e9t\u00e9rans ayant regagn\u00e9 la vie civile un groupe humain tr\u00e8s sp\u00e9cifique et exp\u00e9rimentant une souffrance durable, tr\u00e8s r\u00e9fractaire \u00e0 une r\u00e9int\u00e9gration dans une soci\u00e9t\u00e9 individualiste et en crise profonde, qui reste relativement regroup\u00e9 au sein d&rsquo;associations, qui fournit des contingents importants de nouveaux pauvres (notamment des sans logis, des ch\u00f4meurs chroniques, etc.), qui entretient enfin une r\u00e9action psychologique d&rsquo;hostilit\u00e9 au Syst\u00e8me extr\u00eamement sp\u00e9cifique. D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, on doit consid\u00e9rer les v\u00e9t\u00e9rans de ces guerres postmodernistes comme un groupe social en soi qui sort des normes, souffrant des maux de la modernit\u00e9 en crise d&rsquo;une fa\u00e7on particuli\u00e8rement dramatique, repr\u00e9sentant en fait une avanc\u00e9e effrayante dans l&rsquo;enfer social et psychologique que m\u00e9nage la crise d&rsquo;effondrement de cette modernit\u00e9.<\/p>\n<\/p>\n<p><p>\tOn comprend que ce groupe soit consid\u00e9r\u00e9 par certains experts et analystes comme un facteur social important pour un risque de contestation, voire d&rsquo;insurrection aux USA. Cette id\u00e9e est assez nouvelle, elle est dans nombre d&rsquo;esprit \u00e0 cet \u00e9gard \u00e0 cause des conditions sociales et \u00e9conomiques actuelles aux USA, depuis 2008-2009. L&rsquo;analogie a \u00e9t\u00e9 faite avec la situation des v\u00e9t\u00e9rans US de la Premi\u00e8re Guerre mondiale durant la Grande D\u00e9pression, qui r\u00e9clamaient des allocations qui ne leur avaient pas \u00e9t\u00e9 vers\u00e9es et qui se trouvaient dans des conditions sociales difficiles. Ils entreprirent une action organis\u00e9e au printemps 1932, sous <a href=\"http:\/\/en.wikipedia.org\/wiki\/Bonus_Army\" class=\"gen\">le nom<\/a> de <em>Bonus Army<\/em> et march\u00e8rent sur Washington. Ils s&rsquo;y install\u00e8rent dans des campements de tentes, \u00e0 l&rsquo;image des actions <em>Occupy<\/em> d&rsquo;aujourd&rsquo;hui. Leur manifestation fut sauvagement r\u00e9prim\u00e9e par l&rsquo;U.S. Army, dans une action dirig\u00e9e personnellement par son chef d&rsquo;\u00e9tat-major, le g\u00e9n\u00e9ral MacArthur, dont on entendit parler ensuite pour des motifs plus glorieux. Les v\u00e9t\u00e9rans rest\u00e8rent, jusqu&rsquo;aux premiers fruits de l&rsquo;action de l&rsquo;administration de Roosevelt en 1933-1934, l&rsquo;un des groupes antigouvernementaux les plus mena\u00e7ants. Dans son <em>show<\/em> du <a href=\"http:\/\/www.rawstory.com\/rs\/2011\/10\/27\/maddow-compares-occupy-oakland-to-1930s-bonus-army-protest\/\" class=\"gen\">27 octobre 2011<\/a> de MSNBC, Rachel Maddow a rappel\u00e9 cet \u00e9pisode de la Grande D\u00e9pression et a compar\u00e9 cette situation avec celle du mouvement <em>Occupy<\/em>, du point de vue de l&rsquo;\u00e9ventuel ralliement au mouvement de v\u00e9t\u00e9rans des guerres postmodernistes.<\/p>\n<\/p>\n<p><p>\tLes conditions sont effectivement favorables \u00e0 une telle extension de la contestation vers les v\u00e9t\u00e9rans. L&rsquo;analogie avec la <em>Bonus Army<\/em> de la Grande D\u00e9pression est acceptable, des points de vue \u00e9conomique et social, et aussi structurellement (v\u00e9t\u00e9rans ayant servi comme volontaires). Du point de vue psychologiques, par contre, l&rsquo;analogie avec les \u00e9v\u00e9nements des ann\u00e9es 1960 est plus pertinente (alors que les conditions \u00e9conomiques \u00e9taient diff\u00e9rentes, et que l&rsquo;arm\u00e9e engag\u00e9e au Vietnam \u00e9tait une arm\u00e9e de conscription et non de volontariat). On y retrouve certains des d\u00e9s\u00e9quilibres avec cons\u00e9quences psychologiques constat\u00e9s pour la guerres postmodernistes, et notamment le sentiment d&rsquo;une culpabilit\u00e9 d&rsquo;avoir men\u00e9 d&rsquo;une position de force des guerres ill\u00e9gales et disproportionn\u00e9es contre des populations agress\u00e9es, et la responsabilit\u00e9 de cette culpabilit\u00e9 \u00e9ch\u00e9ant au Syst\u00e8me d&rsquo;une fa\u00e7on particuli\u00e8rement \u00e9clatante et indiscutable. Cette psychologie n&rsquo;existait pas en 1932 avec la <em>Bonus Army<\/em>, la Premi\u00e8re Guerre mondiale \u00e9tant per\u00e7ue en g\u00e9n\u00e9ral comme justifi\u00e9e et \u00e9quilibr\u00e9e. Le groupe des v\u00e9t\u00e9rans US actuel combine ainsi les motifs de r\u00e9volte des deux r\u00e9f\u00e9rences mentionn\u00e9es, \u00e9conomique et sociale pour la Grande D\u00e9pression, psychologique pour les ann\u00e9es 1960, en y ajoutant l&rsquo;\u00e9l\u00e9ment dramatique de la perception d&rsquo;une crise de la modernit\u00e9 elle-m\u00eame. L&rsquo;hypoth\u00e8se de la participation des v\u00e9t\u00e9rans au mouvement <em>Occupy<\/em> comme un aspect sp\u00e9cifique de ce mouvement est donc acceptable ; une telle participation, si elle devenait effectivement importante et organis\u00e9e, donnerait au mouvement une potentialit\u00e9 explosive importante, en confortant son aspect anti-Syst\u00e8me dans ses c\u00f4t\u00e9s les plus brutaux et en exposant en pleine lumi\u00e8re les contradictions du patriotisme utilis\u00e9 et manipul\u00e9 par le Syst\u00e8me, comme moyen de faire ses guerres postmodernistes.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 29 octobre 2011 \u00e0 05H53<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une question sp\u00e9cifique commence \u00e0 \u00eatre d\u00e9battue \u00e0 propos des \u00e9v\u00e9nements int\u00e9rieurs aux USA, concernant la participation de v\u00e9t\u00e9rans des diverses guerres entreprises par les USA depuis 2001 au mouvement OWS, ou Occupy. Elle est apparue lors d&rsquo;une sc\u00e8ne d\u00e9sormais fameuse, avec une vid\u00e9o devenue fameuse sur l&rsquo;Internet, de l&rsquo;ancien sergent des Marines Shamar Thomas,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3236,3289,7857,11634,11635,5701,5181,857,3099,8339,1010],"class_list":["post-74190","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-afghanistan","tag-army","tag-bonus","tag-disorder","tag-dissymetriques","tag-g4g","tag-guerres","tag-irak","tag-psychologie","tag-stress","tag-vietnam"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74190"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74190\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}