{"id":74263,"date":"2011-11-21T06:36:43","date_gmt":"2011-11-21T06:36:43","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/11\/21\/les-quatre-verites-de-barak\/"},"modified":"2011-11-21T06:36:43","modified_gmt":"2011-11-21T06:36:43","slug":"les-quatre-verites-de-barak","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/11\/21\/les-quatre-verites-de-barak\/","title":{"rendered":"Les quatre v\u00e9rit\u00e9s de Barak"},"content":{"rendered":"<p><p>Le ministre isra\u00e9lien de la d\u00e9fense Ehud Barak a eu quelques remarques int\u00e9ressantes lors d&rsquo;une interview, lors du <em>Charlie Rose show<\/em> de la station US de t\u00e9l\u00e9vision PBS le 17 novembre, aux USA. Ces remarques ont amen\u00e9 des r\u00e9actions plut\u00f4t courrouc\u00e9es dans les relais des milieux gouvernementaux isra\u00e9liens, pour leur candeur, pour leur r\u00e9alisme, pour la fa\u00e7on dont elles interf\u00e8rent gravement sur la <em>narrative<\/em> selon laquelle l&rsquo;Iran poursuit une qu\u00eate irrationnelle et monstrueuse de d\u00e9velopper l&rsquo;arme nucl\u00e9aire pour d\u00e9truire Isra\u00ebl (rayer Isra\u00ebl de la carte, selon une traduction faussaire d&rsquo;un discours du pr\u00e9sident iranien de 2007), renouvelant ainsi, toujours selon la <em>narrative<\/em>, le cauchemar de l&rsquo;Holocauste.<\/p>\n<\/p>\n<p><p>\tLe <a href=\"http:\/\/news.antiwar.com\/2011\/11\/17\/israels-barak-steps-back-from-iran-gaffe\/\" class=\"gen\">18 novembre 2011<\/a>, <em>Antiwar.com<\/em> rapportait la gaffe de Barak (lire : la d\u00e9claration pleine de franchise) et la fa\u00e7on dont il a \u00e9t\u00e9 oblig\u00e9 pr\u00e9cipitamment de r\u00e9trop\u00e9daler.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Israeli Defense Minister Ehud Barak has had to back down from statements he made on U.S. television on Tuesday that made him seem to empathize with Iran&rsquo;s alleged quest for nuclear weapons.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>On PBS&rsquo;s Charlie Rose show, when asked if he would want a nuclear weapon were he a member of Iran&rsquo;s government, Barak said Probably, probably. I don&rsquo;t delude myself that they are doing it just because of Israel. They look around, they see the Indians are nuclear, the Chinese are nuclear, Pakistan is nuclear  not to mention the Russians. When asked by Charlie Rose whether Israel&rsquo;s possession of nuclear weapons also might compel Iran towards seeking nuclear weapons capability, Barak said Yeah. IsraelAllegedly.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Barak has caught flak in Israel for assigning a rationale to Iran&rsquo;s as yet unproven weapons program. It seemed an accidental slip from typical U.S.-Israeli propaganda, that the Iranian government wants a nuclear weapon because they are irrational religious fanatics who want to destroy Israel and everyone living in it.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tParall\u00e8lement, <em>DEBKAFiles<\/em> donnait, le <a href=\"http:\/\/www.debka.com\/article\/21488\/\" class=\"gen\">17 novembre 2011<\/a> des pr\u00e9cisions plus substantielles sur l&rsquo;interview, qui \u00e9clairaient largement le propos de Barak, sans r\u00e9f\u00e9rence \u00e0 cette notion de gaffe. Au contraire, les d\u00e9clarations \u00e9taient consid\u00e9r\u00e9es fort s\u00e9rieusement et, d&rsquo;une certaines fa\u00e7on, accept\u00e9es comme justifi\u00e9es dans leur logique.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Barak offered the opinion that if the late Libyan leader Muammar Qaddafi had not relinquished his nuclear program in 2003 but attained a nuclear bomb instead, the March 2011 NATO operation against him would not have been ordered either by French President Nicolas Sarkozy, former Italian Prime Minister Silvio Berlusconi or British Prime Minister David Cameron.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>As to Iraq&rsquo;s Saddam Hussain: Had he possessed a few crude nuclear devices when he invaded Kuwait in 1990, said Barak,  the US-led coalition could not have pushed him out of the emirate in the first Gulf War.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>In the interview, Barak warned that a nuclear-armed Iran would touch off a Middle East nuclear arms race drawing in Egypt and less responsible regimes headed by the Muslim Brotherhood. You could wake up one morning, he said, to find Iran had occupied Bahrain or Qatar. Who then would come and liberate them?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tMalgr\u00e9 le r\u00e9trop\u00e9dalage de Barak, ses d\u00e9clarations restent du plus grand int\u00e9r\u00eat, notamment par leur nettet\u00e9. L&rsquo;argument g\u00e9n\u00e9ral qu&rsquo;il donne est sans surprise et manque, lui, d&rsquo;un complet int\u00e9r\u00eat parce qu&rsquo;il est marqu\u00e9 par l&rsquo;aspect obsessionnel de la direction de s\u00e9curit\u00e9 nationale d&rsquo;Isra\u00ebl concernant les intentions expansionnistes de l&rsquo;Iran. (\u00ab<em>You could wake up one morning to find Iran had occupied Bahrain or Qatar. Who then would come and liberate them?<\/em>\u00bb, interroge Barack. Il pourrait poser la m\u00eame question, en un peu plus nuanc\u00e9e, sans besoin du nucl\u00e9aire, \u00e0 propos de l&rsquo;Arabie qui a occup\u00e9 Bahrain avec ses forces, cette fois avec le consentement d&rsquo;une direction du Bahrain dont l&rsquo;ill\u00e9gitimit\u00e9 est notoire. Il pourrait poser la m\u00eame question \u00e0 propos de Gaza, qu&rsquo;Isra\u00ebl envahit r\u00e9guli\u00e8rement, avec la douceur qu&rsquo;on sait, et ainsi de suite)<\/p>\n<\/p>\n<p><p>\tBarak accr\u00e9dite compl\u00e8tement la th\u00e8se en faveur de la prolif\u00e9ration des armes nucl\u00e9aires, notamment en ce qui concerne l&rsquo;Iran et en g\u00e9n\u00e9ral comme tous les pays susceptibles d&rsquo;\u00eatre menac\u00e9s d&rsquo;agression du bloc BAO, mais plus pr\u00e9cis\u00e9ment avec le cas r\u00e9cent de la Libye dont il parle explicitement. (Les Isra\u00e9liens savent quelque chose de cette th\u00e8se, eux qui ont fait leur propre arsenal nucl\u00e9aire de pr\u00e8s de 300 bombes, dont on ne parle que si rarement, dans le m\u00eame but de dissuasion.) Personne n&rsquo;aurait envahi la Libye si Kadhafi avait dispos\u00e9 de quelque chose approchant une arme nucl\u00e9aire, dont il avait abandonn\u00e9 la fabrication \u00e0 la suite de son rapprochement avec l&rsquo;Ouest,  ce qui permet d&rsquo;appr\u00e9cier une fois de plus, pure routine du constat, l&rsquo;ironie sinistre et la valeur morale des politiques du bloc BAO. Par contre, bien entendu, qui songe \u00e0 envahir la Cor\u00e9e du Nord, dont on sait les innombrables vices selon les jugements humanistes, et qui poss\u00e8de l&rsquo;une et l&rsquo;autre armes nucl\u00e9aires bricol\u00e9es, et qui reste ainsi intouchable ? Premi\u00e8re chose incontestablement et quasi officiellement authentifi\u00e9e par le ministre isra\u00e9lien : pour \u00e9viter les spasmes pseudo n\u00e9ocolonialistes du Syst\u00e8me en phase d&rsquo;effondrement, bricolez quelque chose qui ressemble \u00e0 du nucl\u00e9aire On peut m\u00eame dire que ces consid\u00e9rations renforcent magistralement d&rsquo;\u00e9ventuelles intentions iraniennes de produire du nucl\u00e9aire, et la m\u00eame chose, sans aucun doute, pour l&rsquo;Egypte o\u00f9 cette id\u00e9e ne cesse de <a href=\"http:\/\/www.dedefensa.org\/article-l_enigme_nucleaire_du_sphinx_15_02_2011.html\" class=\"gen\">se renforcer<\/a> en marge des troubles que conna\u00eet ce pays, et peut-\u00eatre, m\u00eame, \u00e0 cause de ces troubles.<\/p>\n<\/p>\n<p><p>\tMais plus encore, bien plus encore En admettant que les dirigeants iraniens peuvent avoir de ces consid\u00e9rations rationnelles (faire du nucl\u00e9aire pour \u00e9viter une invasion ou une attaque unilat\u00e9rale du bloc BAO, attaque \u00e9voqu\u00e9e tous les trois jours), Barak admet que ces dirigeants ont un comportement rationnel, qui est bas\u00e9 sur des calculs de rapports de puissance et sur une analyse raisonnable de la situation strat\u00e9gique et de la politique du bloc BAO. Dans ce cas, que devient l&rsquo;argument principal, compl\u00e8tement fantasmagorique et bas\u00e9 sur l&rsquo;irrationalit\u00e9 hyst\u00e9rique des dirigeants iraniens dont l&rsquo;obsession est un second Holocauste avec une attaque nucl\u00e9aire d&rsquo;Isra\u00ebl ? L&rsquo;on comprend que beaucoup en Isra\u00ebl soient m\u00e9contents de ces d\u00e9clarations car Barak s&rsquo;est dangereusement d\u00e9couvert, et a d\u00e9couvert l&rsquo;aspect mensonger de la polititique-<em>narrative<\/em> officielle d&rsquo;Isra\u00ebl, et surtout son aspect pathologique et obsessionnel. Le m\u00eame Barak, qui fait cette analyse pond\u00e9r\u00e9e des attitudes des dirigeants iraniens, est celui qui d\u00e9nonce l&rsquo;hyst\u00e9rie anti-isra\u00e9lienne et antis\u00e9mite de ces m\u00eames dirigeants. Le plus remarquable, selon notre conviction, est que ces deux aspects cohabitent dans la m\u00eame conviction (la leur) chez cette sorte de dirigeants isra\u00e9liens. L&rsquo;hyst\u00e9rie et l&rsquo;obsession, dans cette partie, sont absolument du c\u00f4t\u00e9 isra\u00e9lien, et c&rsquo;est bien pourquoi l&rsquo;accusation de ces m\u00eames tares chez les Iraniens leur vient si naturellement \u00e0 l&rsquo;esprit,  sauf, dans ce cas, au d\u00e9tour d&rsquo;une interview mal contr\u00f4l\u00e9e.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 21 novembre 2011 \u00e0 06H38<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le ministre isra\u00e9lien de la d\u00e9fense Ehud Barak a eu quelques remarques int\u00e9ressantes lors d&rsquo;une interview, lors du Charlie Rose show de la station US de t\u00e9l\u00e9vision PBS le 17 novembre, aux USA. Ces remarques ont amen\u00e9 des r\u00e9actions plut\u00f4t courrouc\u00e9es dans les relais des milieux gouvernementaux isra\u00e9liens, pour leur candeur, pour leur r\u00e9alisme, pour&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[10900,6039,2929,4880,5135,2773,6902,11706,3004],"class_list":["post-74263","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-bao","tag-bloc","tag-dissuasion","tag-holocauste","tag-hysterie","tag-iran","tag-libye","tag-neocolonialisme","tag-nucleaire"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74263"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74263\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}