{"id":74278,"date":"2011-11-26T12:58:54","date_gmt":"2011-11-26T12:58:54","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/11\/26\/occupy-fait-irruption-sur-les-campus\/"},"modified":"2011-11-26T12:58:54","modified_gmt":"2011-11-26T12:58:54","slug":"occupy-fait-irruption-sur-les-campus","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/11\/26\/occupy-fait-irruption-sur-les-campus\/","title":{"rendered":"<em>Occupy<\/em> fait irruption sur les campus"},"content":{"rendered":"<p><p>Le mouvement <em>Occupy<\/em>, qui ne fait plus la une de nos pr\u00e9occupations en raison de la diversit\u00e9 du spectacle crisique du monde, continue \u00e0 un excellent rythme. Un nouveau d\u00e9veloppement, d&rsquo;un particulier int\u00e9r\u00eat, est son d\u00e9marrage dans le monde universitaire, sur les campus des grandes universit\u00e9s am\u00e9ricaines, particuli\u00e8rement en Californie, berceau de toutes les contestations estudiantines (\u00ab<em> At UC Davis, an encampment of some 100 tents has sprung up since Monday&rsquo;s rally. Encampments are also in place at UC Berkeley and other California campuses<\/em>\u00bb). D&rsquo;autres mouvements importants du m\u00eame type sont signal\u00e9s \u00e0 New York.<\/p>\n<\/p>\n<p><p>\tBien entendu, l&rsquo;incident de Berkelery (voir notre <em>Bloc-Notes<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-a_berkeley_utilite_et_force_symbolique_de_la_non-violence_legitimee_21_11_2011.html\" class=\"gen\">21 novembre 2011<\/a>) est pour beaucoup dans cette extension du mouvement. Le DVD montrant cet incident a \u00e9t\u00e9 vu par plusieurs millions de personnes sur l&rsquo;Internet. Le fait confirme une fois de plus l&rsquo;extraordinaire puissance du syst\u00e8me de la communication dans l&rsquo;acc\u00e9l\u00e9ration des \u00e9v\u00e9nements, ou dit en termes plus g\u00e9n\u00e9raux l&rsquo;acc\u00e9l\u00e9ration de l&rsquo;Histoire, dans la contraction du temps \u00e9v\u00e9nementiel, dans la dramatisation extraordinairement rapide des \u00e9v\u00e8nements.<\/p>\n<\/p>\n<p><p>\tPar ailleurs, dans ce cas \u00e9galement, nous consid\u00e9rons que cette extension rencontre un ph\u00e9nom\u00e8ne psychologique collectif, lui-m\u00eame li\u00e9 \u00e0 l&rsquo;impulsion de courants m\u00e9tahistoriques dans la logique m\u00eame de l&rsquo;extension du mouvement <em>Occupy<\/em>. (Voir notre <em>F&#038;C<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-de_l_imprescriptibilite_d_occupy_21_11_2011.html\" class=\"gen\">21 novembre 2011<\/a>.)<\/p>\n<\/p>\n<p><p>\tC&rsquo;est le site <em>Alternet.org<\/em> (d\u00e9j\u00e0 cit\u00e9 plus haut), reprenant des informations de Reuters, qui dresse le <a href=\"http:\/\/www.trust.org\/alertnet\/news\/occupy-movement-inspires-rise-in-us-campus-activism\" class=\"gen\">25 novembre 2011<\/a> un tableau de la <strong>soudaine<\/strong> irruption d&rsquo;<em>Occupy<\/em> sur les campus.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Violent confrontations between police and protesters at two University of California campuses have drawn a new cadre of students into the Occupy Wall Street movement and unleashed what some historians call the biggest surge in campus activism since the 1960s.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>While Occupy Wall Street protesters have a broad set of grievances that include income inequality and perceived corporate greed, many students have more specific concerns: soaring tuition, campus budget cuts, and fear of heavy student loan debt and lack of job opportunities upon graduation. Student protests related to these issues have broken out sporadically on U.S. college campuses over the past few years, but the Occupy protests  and the police response to them  have swelled the ranks of campus activists in recent weeks.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>A crowd of about 2,000 students, professors and parents held a rally at UC Davis on Monday and called for university Chancellor Linda Katehi to resign after police last week pepper-sprayed students sitting passively on the campus quad.<\/em> []  <\/p>\n<\/p>\n<p><p>\t\u00bb<em>We didn&rsquo;t really know what it was until we actually were here on the quad (quadrangle) seeing fellow students getting maced, said John Caccamo, an 18-year-old biology student at UC Davis. The campus, near Sacramento, is not known as a hotbed of activism. This is the first time in the 11 years I&rsquo;ve been here that students have said  Wait a minute, I need to wake up to where I am and what&rsquo;s going on,&rsquo; UC Davis art professor Robin Hill told Reuters at the Davis rally.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tBien entendu, comme l&rsquo;a vu \u00e9voqu\u00e9 plus haut, l&rsquo;analogie avec le mouvement \u00e9tudiant des ann\u00e9es 1960 est dans tous les esprits. Comme on peut le lire, \u00e9galement dans le texte d&rsquo;<em>Alternet.org<\/em>, les historiens en sont d\u00e9j\u00e0 \u00e0 \u00e9voquer les similitudes et les diff\u00e9rentes La principale diff\u00e9rence, incontestablement, se trouve dans la rapidit\u00e9 du d\u00e9marrage du mouvement<\/p>\n<\/p>\n<p><p>\t\u00ab<em>New York University historian Robert Cohen said the Occupy movement on California campuses is accelerating quickly compared with the student movement of the 1960s. If you date things from the Port Huron Statement and the summer of &rsquo;62, it wasn&rsquo;t really until the fall of &rsquo;64 that there was a mass student movement on campus, he said. The Port Huron Statement was the manifesto of the Students for a Democratic Society, one of the key groups of the 1960s New Left movement in the United States.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The 1960s and early 1970s were a time of great social unrest as college students rallied against the Vietnam war and in support of minority and women&rsquo;s rights. Angus Johnston, a historian at City University of New York, said, What we have had up until now is something very similar to the early 1960s, where you had not a huge number of activists but a committed core who were working really hard but weren&rsquo;t getting huge amount of traction from media or fellow students.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tBien entendu, il y a d&rsquo;autres diff\u00e9rences avec les ann\u00e9es 1960, et des diff\u00e9rence consid\u00e9rables qui tiennent essentiellement au contexte. La situation US est aujourd&rsquo;hui infinit\u00e9simalement plus grave qu&rsquo;au d\u00e9but des ann\u00e9es 1960, o\u00f9 le mouvement \u00e9tudiant n&rsquo;avait comme r\u00e9plique initiatrice que le mouvement des droits civiques des Noirs, et aucune crise int\u00e9rieure massive pour lui assurer une certaine coh\u00e9sion et une certaine bienveillance de la part du public (le Vietnam en deviendrait une \u00e0 partir de 1965-1966, 3 \u00e0 4 ans apr\u00e8s le d\u00e9marrage du mouvement estudiantin). Aujourd&rsquo;hui, bien entendu, on conna\u00eet tous les ph\u00e9nom\u00e8nes crisiques en cours (<a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_dissolution_du_pouvoir_politique_ddecrisis_14_06_2010.html\" class=\"gen\">structure crisique<\/a>, <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_chaine_crisique_ddecrisis_02_04_2011.html\" class=\"gen\">cha\u00eene crisique<\/a>, <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_dissolution_crisique__22_11_2011.html\" class=\"gen\">dissolution crisique<\/a>) dans lesquels le mouvement estudiantin naissant devrait trouver \u00e0 la fois son aliment et sa place naturelle.<\/p>\n<\/p>\n<p><p>\tDans ce cas, la rapidit\u00e9 du ph\u00e9nom\u00e8ne, par comparaison \u00e0 celui des ann\u00e9es 1960, r\u00e9pond \u00e9galement aux conditions historiques et m\u00e9tahistoriques en cours. L&rsquo;int\u00e9r\u00eat de ce mouvement, s&rsquo;il se confirme, est de fournir une nouvelle masse de manuvre importante \u00e0 la crise g\u00e9n\u00e9rale qui frappe les USA, et \u00e0 <em>Occupy<\/em> particuli\u00e8rement.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 26 novembre 2011 \u00e0 12H58<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le mouvement Occupy, qui ne fait plus la une de nos pr\u00e9occupations en raison de la diversit\u00e9 du spectacle crisique du monde, continue \u00e0 un excellent rythme. Un nouveau d\u00e9veloppement, d&rsquo;un particulier int\u00e9r\u00eat, est son d\u00e9marrage dans le monde universitaire, sur les campus des grandes universit\u00e9s am\u00e9ricaines, particuli\u00e8rement en Californie, berceau de toutes les contestations&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[11719,3484,11718,2942,10859,5592,8294,10119,10300,11493,7114],"class_list":["post-74278","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-11719","tag-annees","tag-berkeley","tag-californie","tag-chaine","tag-contestation","tag-crisique","tag-dissolution","tag-etudiants","tag-occupy","tag-structure"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74278"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74278\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}