{"id":74280,"date":"2011-11-28T05:34:48","date_gmt":"2011-11-28T05:34:48","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/11\/28\/notes-sur-les-transversales-de-lautodestruction\/"},"modified":"2011-11-28T05:34:48","modified_gmt":"2011-11-28T05:34:48","slug":"notes-sur-les-transversales-de-lautodestruction","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/11\/28\/notes-sur-les-transversales-de-lautodestruction\/","title":{"rendered":"Notes sur les transversales de l&rsquo;autodestruction"},"content":{"rendered":"<p><h2 class=\"common-article\">Notes sur les transversales de l&rsquo;autodestruction<\/h2>\n<\/p>\n<p><p>\tPourquoi attendre 2012, apr\u00e8s tout ? Le d\u00e9sordre de 2011 est effectivement en train de passer \u00e0 une vitesse sup\u00e9rieure, pour faire de 2012, avec ses divers rendez-vous d\u00e9mocratiques de changements de pouvoir, une ann\u00e9e singuli\u00e8rement agit\u00e9e ; mais ce d\u00e9sordre est tel qu&rsquo;on se croirait d\u00e9j\u00e0 en 2012<\/p>\n<\/p>\n<p><p>\tDans notre num\u00e9ro de <em>dde.crisis<\/em> du 10 d\u00e9cembre 2011, que nous consacrons \u00e0 cette ann\u00e9e 2012, nous identifions deux grands courants de d\u00e9sordre qui s&rsquo;ajoutent aux incertitudes fix\u00e9es des changements de pouvoir (pr\u00e9sidentielles en Russie, en France, au Mexique, aux USA, peut-\u00eatre en Egypte, nouvelle direction en Chine). Le premier concerne l&rsquo;agitation int\u00e9rieure qui touche les pays du bloc BAO, essentiellement les USA d\u00e9sormais, pour l&rsquo;importance de la chose. (Ce que William Pfaff d\u00e9signe, parlant \u00e9videmment des USA, comme \u00ab<em>our own revolutionary unrest<\/em>\u00bb.) Le second concerne les \u00e9v\u00e9nements au Moyen-Orient, ce qu&rsquo;on nomme le printemps arabe, devenu un d\u00e9sordre pour toutes les saisons et hors de sa r\u00e9gion propre. A propos de ce second \u00e9l\u00e9ment, nous \u00e9crivons dans ce <em>dde.crisis<\/em> :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Le second de ces \u00e9v\u00e8nements est l&rsquo;\u00e9volution en un chaos d&rsquo;\u00e9v\u00e8nements furieux et incontr\u00f4lables du printemps arabe, ou disons de la folle saison du Moyen-Orient, de la Libye \u00e0 l&rsquo;Egypte, de l&rsquo;Egypte \u00e0 Isra\u00ebl, \u00e0 la Syrie, \u00e0 l&rsquo;Iran, \u00e0 Bahrain et \u00e0 l&rsquo;Arabie, au Yemen, \u00e0 la Turquie, etc., avec en plus les acteurs ext\u00e9rieurs (USA et bloc BAO, Russie, Chine, etc.). Il n&rsquo;est plus possible de donner une orientation pr\u00e9cise ni de faire un compte binaire de ce d\u00e9sordre (les r\u00e9volutions et les contre-r\u00e9volutions) ; partout se glissent des facteurs inattendus, des int\u00e9r\u00eats contradictoires dans divers sens, des changements de position ou de politique, etc. Il n&rsquo;existe plus aucun point de stabilit\u00e9 nulle part dans cette zone et il existe en m\u00eame temps une extr\u00eame rapidit\u00e9 des \u00e9v\u00e8nements qui prend continuellement les acteurs ext\u00e9rieurs \u00e0 contrepied. Bien entendu, l&rsquo;importance strat\u00e9gique \u00e9norme que les autres acteurs, notamment le bloc BAO, accordent \u00e0 cette r\u00e9gion \u00e9tend son instabilit\u00e9 et sa rapidit\u00e9 de d\u00e9stabilisation \u00e0 ces m\u00eames acteurs ext\u00e9rieurs.<\/em>\u00bb<\/p>\n<h3>Int\u00e9gration de crise et <em>Amiral Kouznetzov<\/em><\/h3>\n<\/p>\n<p><p>\tOn a vu, ce <a href=\"http:\/\/www.dedefensa.org\/article-la_syrie_entre_dans_la_crise_generale_26_11_2011.html\" class=\"gen\">26 novembre 2011<\/a> comment la crise syrienne est en train de s&rsquo;inscrire, en plus d&rsquo;\u00eatre en partie n\u00e9e de la cha\u00eene crisique du printemps arabe, comme une crise internationale <em>per se<\/em>. Cela implique, dans notre univers plong\u00e9 dans la grande crise d&rsquo;effondrement de la civilisation, une int\u00e9gration de la crise syrienne <em>per se<\/em> dans la grande crise g\u00e9n\u00e9rale. (Sur ce concept d&rsquo;int\u00e9gration, voir le <a href=\"http:\/\/www.dedefensa.org\/article-la_crise_ferale_phase_gfc2_pour_les_amis_04_08_2011.html\" class=\"gen\">4 ao\u00fbt 2011<\/a>, le <a href=\"http:\/\/www.dedefensa.org\/article-l_integration_de_la_crise_ou_la_vision_de_la_dystopie_15_08_2011.html\" class=\"gen\">15 ao\u00fbt 2011<\/a>, le <a href=\"http:\/\/www.dedefensa.org\/article-meme_les_crises_sont_en_crise__19_08_2011.html?admin=1\" class=\"gen\">19 ao\u00fbt 2011<\/a>.)<\/p>\n<\/p>\n<p><p>\tPour ce cas, la pr\u00e9sence conjointe d&rsquo;unit\u00e9s militaires navales US et russes, dans des positions implicitement antagonistes, en dit long sur le processus. Signalant le d\u00e9placement du seul porte-avions russe <em>Amiral Kouznetzov<\/em> (avec son groupe de combat) vers les c\u00f4tes syriennes pour soutenir les navires qui s&rsquo;y trouvent d\u00e9j\u00e0, <em>DEBKAFiles<\/em> observe (le <a href=\"http:\/\/www.debka.com\/article\/21521\/\" class=\"gen\">26 novembre 2011<\/a>) :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The Russian Kuznetzov carrier and its accompanying strike vessels will join the three Russian warships parked opposite Tartus for more than a week. It will enter the same Syrian offshore waters as the USS Bush and the US Sixth Fleet, which is permanently posted in the Mediterranean.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The Syrian crisis is therefore building up to a superpower face-off unparalleled since the Cold War between America and the Soviet Union ended in the nineties, DEBKAfile&rsquo;s military sources note. While Washington clearly stands ready to back operations against the Assad regime, Moscow is drawing a red line around his presidential palace in Damascus. The Kremlin is warning the US, NATO and the Arab League that they will not be allowed to repeat their feat in Libya of overthrowing Muammar Qaddafi against Assad.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tUn relent de guerre froide, ou une nouvelle guerre froide ? Comme l&rsquo;on peut le voir aussit\u00f4t, ce ne serait pas la seule. Nous sommes dans ce temps m\u00e9tahistorique \u00e9pique o\u00f9 l&rsquo;on peut pr\u00e9tendre installer plusieurs guerres froides alors que toutes les bases \u00e9conomiques et sociales des puissances qui s&rsquo;engagent dans cette voie s&rsquo;effondrent. Mais, dirait-on aussit\u00f4t, ceci expliquerait bien cela<\/p>\n<h3>L&rsquo;<em>hubris<\/em> qui p\u00e9dalait dans le vide<\/h3>\n<\/p>\n<p><p>\tEffectivement, nous nous tournons aussit\u00f4t, et pour un instant, vers l&rsquo;Asie et le Pacifique. La tourn\u00e9e du pr\u00e9sident Obama dans la zone a accouch\u00e9 effectivement d&rsquo;un \u00e9trange rejeton. <em>PressTV.com<\/em> signale (le <a href=\"http:\/\/www.presstv.com\/detail\/212282.html \" class=\"gen\">26 novembre 2011<\/a>) que la chose est officielle : \u00ab<em>The formal organ of China&rsquo;s ruling party has reported that a cold war era has started between China and the US as Washington has stepped up a campaign to counter Beijing&rsquo;s growing clout across the globe.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe <a href=\"http:\/\/www.williampfaff.com\/modules\/news\/article.php?storyid=548\" class=\"gen\">22 novembre 2011<\/a>, William Pfaff avait comment\u00e9 avec une perplexit\u00e9 inqui\u00e8te ou d\u00e9courag\u00e9e c&rsquo;est selon, la progression de cette d\u00e9claration de guerre froide du pr\u00e9sident Obama. Il note d&rsquo;abord l&rsquo;extraordinaire pr\u00e9tention de la dialectique USA, comme si le <em>Titanic<\/em> clamait son air de triomphe de la technologie moderniste et navale apr\u00e8s avoir heurt\u00e9 l&rsquo;iceberg : \u00ab<em>This message said that the United States now considers itself a permanent Pacific and Asian power. Just as it long ago settled in as an unofficial permanent European power (the ally who wouldn&rsquo;t go home), it now is permanently Asian, and anything that happens in the Pacific and the Far East automatically will concern Americans.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tQue se passe-t-il ? s&rsquo;interroge Pfaff. Il songe \u00e0 l&rsquo;<em>hubris<\/em>, jamais plus fort dans une psychologie d\u00e9rang\u00e9e que lorsqu&rsquo;on en perd toutes les raisons d&rsquo;y pr\u00e9tendre (\u00ab<em>What does that actually mean, and what is it worth? Bragging rights about who is top nation? That&rsquo;s what Washington seems to care about<\/em>\u00bb). Puis il conclut finalement, avec l&rsquo;absurdit\u00e9 de la d\u00e9marche, par l&rsquo;explication (soulign\u00e9 par nous en gras) qui vient naturellement sous la plume de tout commentateur du Syst\u00e8me-qui-s&rsquo;effondre, comme compl\u00e9ment \u00e9vident de cet <em>hubris<\/em> \u00e0 la fois exacerb\u00e9 et vid\u00e9 de toute substance :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Are we Americans really sure that we want to be all-in? All-in what? A war over China&rsquo;s claims on Taiwan and the South China Sea? Or over access to rare earths? Or over  as just might happen  a China reduced to ruins by revolutionary upheaval? Or is Mr. Obama and the Washington \u00e9lite<\/em> <strong><em>looking for distraction from our own revolutionary unrest?<\/em><\/strong>\u00bb<\/p>\n<h3>En passant par le Pakistan<\/h3>\n<\/p>\n<p><p>\tRevenons vers l&rsquo;Ouest, vers ce printemps arabe pour toutes les saisons, d&rsquo;ailleurs en passant par le Pakistan, qui est sur notre route, pour noter \u00e0 ce propos que les relations entre ce pays et les USA (avec le bloc BAO) sont bien ex\u00e9crables apr\u00e8s la tuerie de 24  soldats pakistanais par des h\u00e9licopt\u00e8res US, en territoire pakistanais, par erreur coutumi\u00e8re et hautement civilis\u00e9e,   car qu&rsquo;est-ce qui distingue un basan\u00e9 pakistanais d&rsquo;un bas\u00e9 taliban, on vous le demande ? Outre de <a href=\"http:\/\/www.guardian.co.uk\/world\/2011\/nov\/26\/pakistan-halts-nato-supplies-attack\" class=\"gen\">bloquer<\/a> l&rsquo;approvisionnement par route des forces du bloc BAO en Afghanistan, le Pakistan, note <em>PressTV.com<\/em> le <a href=\"http:\/\/www.presstv.com\/detail\/212301.html\" class=\"gen\">26 novembre 2011<\/a>, a donn\u00e9 15 jours \u00e0 la CIA pour \u00e9vacuer la base de Shamsi qu&rsquo;elle occupe dans le sud-ouest du pays. On verra si l&rsquo;ultimatum tient la route, car cette fois le Pakistan semble <a href=\"http:\/\/www.guardian.co.uk\/commentisfree\/2011\/nov\/27\/pakistan-strategic-error\" class=\"gen\">\u00e0 bout de patience<\/a>.<\/p>\n<\/p>\n<p><p>\t(En attendant, on notera que <em>PressTV.com<\/em>, station iranienne, a sorti la nouvelle 24 heures avant le <em>Guardian<\/em>, en g\u00e9n\u00e9ral bien inform\u00e9, qui parle de cette affaire d&rsquo;expulsion de la base de la CIA le <a href=\"http:\/\/www.guardian.co.uk\/world\/2011\/nov\/27\/pakistan-orders-us-leave-shamsi-airbase\" class=\"gen\">27 novembre 2011<\/a>. Entre Karachi et T\u00e9h\u00e9ran, les nouvelles vont vite, comme si l&rsquo;on s&rsquo;entendait bien, tous comptes faits&#8230;)<\/p>\n<\/p>\n<p><p>\tParall\u00e8lement, et pour agr\u00e9menter notre p\u00e9riple, on peut noter qu&rsquo;en m\u00eame temps <a href=\"http:\/\/www.presstv.com\/detail\/211983.html\" class=\"gen\">se termine<\/a> un grand exercice militaire conjoint sino-pakistanais au Pakistan (<em>Friendship-2011<\/em>), qui appara\u00eet comme une concr\u00e9tisation \u00e0 propos du resserrement spectaculaire des liens strat\u00e9giques entre le Pakistan et la Chine. Tout se fait dans le sens de la transversale<\/p>\n<h3>L&rsquo;Arabie qui virevolte<\/h3>\n<\/p>\n<p><p>\tRevenus au Moyen-Orient, vers qui se tourner ? L&rsquo;Arabie Saoudite, par exemple. Un site \u00e9gyptien lib\u00e9ral, <em>Arabisnet.com<\/em>, pr\u00e9sente, le <a href=\"http:\/\/www.arabist.net\/blog\/2011\/11\/25\/saudi-arabias-changing-foreign-policy.html\" class=\"gen\">25 novembre 2011<\/a>, un texte de David Ignatius, du Washington <em>Post<\/em> (du <a href=\"http:\/\/www.washingtonpost.com\/opinions\/saudi-arabia-expands-its-power-as-us-influence-diminishes\/2011\/11\/18\/gIQAX8wwZN_story.html\" class=\"gen\">19 novembre 2011<\/a>). En se r\u00e9f\u00e9rant implicitement au sentiment r\u00e9gnant dans la r\u00e9gion, le site \u00e9gyptien semble tenir pour particuli\u00e8rement importante l&rsquo;analyse d&rsquo;Ignatius selon laquelle l&rsquo;Arabie, sous la direction nouvelle qui s&rsquo;est mise en place, nuance notablement sa politique r\u00e9gionale, certes en r\u00e9affirmant son r\u00f4le qui correspond \u00e0 l&rsquo;effacement US, mais en le nuan\u00e7ant par rapport \u00e0 certaines obsessions.<\/p>\n<\/p>\n<p><p>\tLes deux extraits cit\u00e9s de l&rsquo;article d&rsquo;Ignatius sont les suivants :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Saudis describe the kingdom&rsquo;s growing role as a reaction, in part, to the diminished clout of the United States. They still regard the U.S.- Saudi relationship as valuable, but it&rsquo;s no longer seen as a guarantor of their security. For that, the Saudis have decided they must rely more on themselves  and, down the road, on a wider set of friends that includes their military partner, Pakistan, and their largest oil customer, China.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>They may be spearheading the counter-revolution, but the Saudis are not just a status-quo force anymore. Like other states, they are restructuring to the new reality<\/em> [] <em>Two weeks ago, at a meeting of the International Institute for Strategic Studies in Geneva that I attended, Prince Turki outlined his proposal to deal with the region&rsquo;s most urgent issues through two broad arcs: reviving the Arab Peace Initiative (ie a comprehensive Israeli-Arab peace rather than a separate Israeli-Palestinian one) and the decades-old idea of a Middle East free of weapons of mass destruction (ie tackling the Israeli and Iranian nuclear issues together, rather than ignoring the former and focusing on the latter.) The proposal was interesting not so much on its details as what it implied: a much more multilaterally-driven agenda for Middle East diplomacy. No more waiting for Washington to act first.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCes deux extraits nous conduisent observer, (1) que, parmi les nouveaux alli\u00e9s sur lesquels l&rsquo;Arabie s&rsquo;appuierait pour remplacer les USA, se trouvent le Pakistan et la Chine, dont on a vu la chaleur caract\u00e9risant leurs liens avec ces m\u00eames USA ; et (2) que, plut\u00f4t qu&rsquo;appuyer l&rsquo;id\u00e9e d&rsquo;une attaque de l&rsquo;Iran qui plaisait tant \u00e0 Isra\u00ebl, l&rsquo;Arabie commencerait \u00e0 pr\u00e9f\u00e9rer \u00e0 nouveau l&rsquo;id\u00e9e d&rsquo;une zone d\u00e9nucl\u00e9aris\u00e9e qui d\u00e9pla\u00eet tant \u00e0 Isra\u00ebl.<\/p>\n<h3>L&rsquo;Egypte, comme du sable entre les mains<\/h3>\n<\/p>\n<p><p>\tCertes, il y a \u00e9galement l&rsquo;Egypte. Il y a ceux qui disent que le d\u00e9sordre est sciemment entretenu par le bloc BAO depuis l&rsquo;origine, sans doute pour \u00e9liminer l&rsquo;une apr\u00e8s l&rsquo;autre les directions qui lui sont favorables (au bloc BAO). C&rsquo;est une tactique dialectique habile pour dissimuler les impuissances et une vieille rengaine, tout cela qui n&#8217;emp\u00eache pas la v\u00e9rit\u00e9 de la situation de se manifester : l&rsquo;incapacit\u00e9 des militaires \u00e9gyptiens de rendre efficace l&rsquo;usage d&rsquo;une force qui s&rsquo;appuie en fait sur l&rsquo;irr\u00e9solution et l&rsquo;incompr\u00e9hension,  car, pour eux principalement, la situation \u00e9gyptienne est comme du sable qui coule entre les mains.<\/p>\n<\/p>\n<p><p>\tAujourd&rsquo;hui, les Fr\u00e8res Musulmans qui font traditionnellement si peur \u00e0 tout le monde semblent la seule force politique consistante d&rsquo;opposition a encore soutenir les militaires, parce qu&rsquo;il existe <a href=\"http:\/\/www.dedefensa.org\/article-hypothese_egyptienne_une_alliance_militaires-freres_musulmans__23_11_2011.html \" class=\"gen\">un march\u00e9<\/a> entre eux et les militaires pour le futur pouvoir. Dans l&rsquo;autre camp, Mohamed El Baradei, ancien secr\u00e9taire g\u00e9n\u00e9ral de l&rsquo;IAEA, r\u00e9cemment et r\u00e9trospectivement baptis\u00e9 agent de l&rsquo;Iran \u00e0 ce poste par Isra\u00ebl pour n&rsquo;avoir pas acquiesc\u00e9 aux intuitions fulgurantes de Netanyahou sur les projets d&rsquo;Holocauste-II de ce m\u00eame Iran, se pose comme candidat de la foule de la place Tahrir, d&rsquo;ailleurs acclam\u00e9 par elle dans la nuit du <a href=\"http:\/\/www.presstv.com\/detail\/212376.html\" class=\"gen\">26 novembre<\/a>, comme candidat Premier ministre d&rsquo;un gouvernement civil de transition ; cela, \u00e0 la place du nouveau Premier ministre nomm\u00e9 par les militaires, un v\u00e9n\u00e9rable (78 ans) d&rsquo;un service de 20 ans aux ordres de Moubarak.<\/p>\n<\/p>\n<p><p>\tM\u00eame si les militaires arrivent \u00e0 faire passer leur programme de d\u00e9mocratisation \u00e0 leur sauce, au moins pour l&rsquo;image, avec la probabilit\u00e9 d&rsquo;une majorit\u00e9 parlementaire gagn\u00e9e par les Fr\u00e8res Musulmans devenus alli\u00e9s de ces militaires, la perspective n&rsquo;est pas n\u00e9cessairement radieuse (du point de vue de notre cher bloc BAO). Un expert des questions \u00e9gyptiennes observe, pour <em>Russia Today<\/em>, le <a href=\"http:\/\/rt.com\/news\/egypt-protests-military-warning-319\/\" class=\"gen\">27 novembre 2011<\/a> : \u00ab<em>Political analyst Dr. Marcus Papadopoulos says if the Muslim Brotherhood comes to power, it may lead to a new Libya-like conflict with the West. If the people vote them in you could see in a few years time NATO or the British and Western press talking about how awful the regime is there, how dangerous it is, and then you are back to a situation where there is discussion about NATO air strikes against Egypt.<\/em>\u00bb <\/p>\n<\/p>\n<p><p>\tCertes, il y a la Syrie qui occupe toutes les pens\u00e9es humanitaires des strat\u00e8ges du bloc BAO, mais n&rsquo;est-ce pas \u00e0 nouveau l&rsquo;Egypte <em>where the action is<\/em>, aujourd&rsquo;hui au Moyen-Orient ? Le bloc BAO a oubli\u00e9 de menacer les militaires \u00e9gyptiens d&rsquo;une intervention humanitaire contre la r\u00e9pression des foules de la place Tahrir.<\/p>\n<h3>Les Turcs, ou comment se passer des USA<\/h3>\n<\/p>\n<p><p>\tCe caract\u00e8re essentiel des \u00e9v\u00e9nements \u00e9gyptiens, c&rsquo;est aussi l&rsquo;avis des Turcs,  dans tous les cas, en partie. Le <a href=\"http:\/\/www.hurriyetdailynews.com\/n.php?n=dawn-of-a-new-middle-eastern-order-2011-11-25\" class=\"gen\">25 novembre 2011<\/a>, le commentateur Ilan Tanhir, du quotidien <em>Hurriyet<\/em>, c\u00e9l\u00e9brait le printemps arabe comme nullement endeuill\u00e9 par les frimas de l&rsquo;hiver  : \u00ab<em>The Arab Spring had a whirlwind week. While skepticism about where the uprisings are headed continues, the historic transformation gained three significant victories.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tParmi les trois victoires de la semaine, Tanhir c\u00e9l\u00e8bre la deuxi\u00e8me r\u00e9volution \u00e9gyptienne, <em>Tahrir 2.0<\/em>. Il s&rsquo;\u00e9tend longuement sur la l\u00e9gitimit\u00e9 et la puissance du mouvement et sur l&rsquo;inconsistance, les contradictions et la lenteur de Washington \u00e0 r\u00e9agir aux \u00e9v\u00e9nements. Tanhir \u00e9carte l&rsquo;id\u00e9e d&rsquo;un complot occidental en la mati\u00e8re, id\u00e9e par ailleurs fort r\u00e9pandue et permettant de faire survivre le mythe de l&rsquo;invincibilit\u00e9 intellectuelle et machiav\u00e9lique des restes de la puissance am\u00e9ricaniste.<\/p>\n<\/p>\n<p><p>\tLes deux autres \u00e9v\u00e9nements c\u00e9l\u00e9br\u00e9s par Tanhir sont d&rsquo;abord l&rsquo;acceptation du gouvernement de Bahrain des conclusions d&rsquo;une commission d&rsquo;enqu\u00eate ind\u00e9pendante sur les abus de la r\u00e9pression lors des manifestations dans ce royaume ; ensuite, la condamnation de la Syrie par la Ligue Arabe, avec l&rsquo;accent tr\u00e8s fortement mis par le m\u00eame Tanhir sur l&rsquo;effacement des USA derri\u00e8re la Ligue C&rsquo;est ce point qui est essentiel dans cette analyse : <\/p>\n<\/p>\n<p><p>\t\u00ab<em>On Syria too, it appears Washington is also not taking the lead. U.S. Secretary of State Clinton, during a series of interviews last week, kept emphasizing Turkey and the Arab League&rsquo;s importance in ending the bloodshed there; a line that suits perfectly both of these actors&rsquo; wishes which, for months, have stated the solution for Syria can only be found regionally.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tSur la Syrie, la Turquie a pris une position en fl\u00e8che, qui est un m\u00e9lange de calculs politiques de communication (soutien, <strong>partout<\/strong>, au printemps arabe), visant \u00e0 \u00e9tablir un <em>leadership<\/em> dans la r\u00e9gion, et une furieuse \u00e9quation personnelle d&rsquo;Erdogan et de son ministre des affaires \u00e9trang\u00e8res contre Assad. Le probl\u00e8me pour les Turcs, d\u00e9sormais, est de contrecarrer toute tentative occidentale du bloc BAO de confisquer \u00e0 son avantage une \u00e9ventuelle intervention humanitaire en Syrie. Difficile, l&rsquo;exercice.<\/p>\n<h3>La Libye ne fera qu&rsquo;une bouch\u00e9e de la Syrie<\/h3>\n<\/p>\n<p><p>\tD&rsquo;une certaine fa\u00e7on, pas moins difficile exercice pour Isra\u00ebl. L&rsquo;id\u00e9e, qui vient d&rsquo;\u00eatre \u00e9mise par le nouveau r\u00e9gime libyen (voir <em>Antiwar.com<\/em>, du <a href=\"http:\/\/news.antiwar.com\/2011\/11\/25\/libyas-new-regime-may-attack-syria\/\" class=\"gen\">25 novembre 2011<\/a>), d&rsquo;envoyer en Syrie des combattants de la libert\u00e9 (on dit aussi moudjahiddines) contre Assad n&rsquo;enchante gu\u00e8re Isra\u00ebl. Ces moudjahiddines seraient des islamistes, sorte de transfuge de l&rsquo;al Qa\u00efda r\u00e9gional, et ils p\u00e8seraient d&rsquo;autant pour une alternative tr\u00e8s islamiste au r\u00e9gime d&rsquo;Assad. Les Isra\u00e9liens sont furieux de cette id\u00e9e, favoris\u00e9e par certains pays de l&rsquo;OTAN, dont certains habiles diplomates fran\u00e7ais. Ils ont d\u00e9j\u00e0 remarqu\u00e9, les Isra\u00e9liens, que des islamistes libyens, tous frais sortis de leur guerre de lib\u00e9ration sous les ordres du mar\u00e9chal BHL et de l&rsquo;OTAN, se sont install\u00e9s \u00e0 Gaza avec des missiles <em>Grad<\/em>.<\/p>\n<\/p>\n<p><p>\tLes Libanais, les Jordaniens et les Irakiens sont \u00e9galement terroris\u00e9s \u00e0 l&rsquo;id\u00e9e d&rsquo;une Syrie basculant dans l&rsquo;extr\u00e9misme et tentent de freiner d&rsquo;autant (sans beaucoup de succ\u00e8s) l&rsquo;action de la Ligue Arabe. Toutes ces finasseries qui pourraient \u00e9galement signifier le d\u00e9sir de conserver le traitement de l&rsquo;affaire syrienne dans le champ r\u00e9gional, ne font au contraire qu&rsquo;exacerber un peu plus la volont\u00e9 humaniste et vertueuse des plus activistes du bloc BAO, dont les Fran\u00e7ais, d&rsquo;intervenir en Syrie. Peut-\u00eatre n&rsquo;ont-ils pas remarqu\u00e9 que cela pourrait les placer en confrontation directe avec les Russes ?<\/p>\n<h3>Le d\u00e9sordre BMDE hors les murs (europ\u00e9ens)<\/h3>\n<\/p>\n<p><p>\tCette derni\u00e8re id\u00e9e nous ram\u00e8ne au th\u00e8me de guerre froide, \u00e9voqu\u00e9 au d\u00e9but de cette analyse. Une autre retomb\u00e9e de la guerre froide <em>new age<\/em>, prolif\u00e9rant en diverses versions, concerne le r\u00e9seau anti-missiles BMDE. Un radar de ce r\u00e9seau devrait \u00eatre plac\u00e9 en Turquie, mais les conditions sont encore bien n\u00e9buleuses,  et quant \u00e0 l&rsquo;acceptation de la Turquie, et quant \u00e0 la r\u00e9ticence agressive des Turcs d&rsquo;\u00e9ventuellement transf\u00e9rer des donn\u00e9es de ce radar vers les Isra\u00e9liens qui feraient partie du r\u00e9seau.<\/p>\n<\/p>\n<p><p>\tPour ajouter \u00e0 cette simplicit\u00e9 du propos, les Iraniens viennent donc d&rsquo;annoncer qu&rsquo;en cas d&rsquo;attaque du bloc BAO contre l&rsquo;Iran, le radar qui serait install\u00e9 en Turquie serait la premi\u00e8re cible iranienne. Et cette attaque aurait lieu, en un sens, pour d\u00e9ciller les yeux du peuple turc sur la fa\u00e7on dont il est manipul\u00e9 par les USA et les int\u00e9r\u00eats sionistes (Voir <em>PressTV.com<\/em> du <a href=\"http:\/\/www.presstv.com\/detail\/212321.html\" class=\"gen\">26 novembre 2011<\/a>.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Brigadier General Amir-Ali Hajizadeh, Commander of the Aerospace Division of the Islamic Revolution Guards Corps says in case of a military movement against Iran, NATO&rsquo;s missile shield in Turkey will be Iran&rsquo;s first target. The West&rsquo;s missile shield which is being deployed in Turkey by NATO (North Atlantic Treaty Organization), is managed by America and the Zionists, but to deceive Turkish people, they call it NATO defense shield, Brigadier General Amir-Ali Hajizadeh said.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t(&#8230;P.S. \u00e0 ce point, pour donner un peu plus de coh\u00e9sion \u00e0 l&rsquo;analyse et ajouter au charme de la confusion cosmique de nos temps en cours, cette d\u00e9claration du ministre iranien des affaires \u00e9trang\u00e8res, ce <a href=\"http:\/\/www.presstv.com\/detail\/212551.html\" class=\"gen\">28 novembre 2011<\/a>, apr\u00e8s une rencontre avec un vice-ministre turc des affaires \u00e9trang\u00e8res. Pour lui, et en complet accord avec son interlocuteur, les liens entre l&rsquo;Iran et la Turquie ont devant eux un avenir confiant et brillant, et plein d&rsquo;une entente mutuelle.)<\/p>\n<h3>Faire la guerre, mais avec quoi ? <\/h3>\n<\/p>\n<p><p>\tCette abracadabrantesque affaire de missiles anti-missiles r\u00e9unissant, dans ce cas, l&rsquo;Iran, la Turquie et Isra\u00ebl dans des relations incestueuses, hostiles ou pas du tout, \u00e0 contrepieds divers, r\u00e9sume parfaitement le tableau g\u00e9n\u00e9ral. Elle le colore mieux encore lorsqu&rsquo;on sait de connaissance assur\u00e9e que ce vaste programme n&rsquo;a aucun sens strat\u00e9gique \u00e0 son origine, puisque n\u00e9 d&rsquo;une impulsion-Syst\u00e8me du complexe militaro-industriel qui raisonne en $milliards, et d\u00e9bouche sur le chaos strat\u00e9gique. (Pour un historique de cette crise du syst\u00e8me BMDE, voir par exemple le <a href=\" http:\/\/www.dedefensa.org\/article-une_sacrement_drole_de_crise_12_06_2007.html?admin=1\" class=\"gen\">12 juin 2007<\/a>.) C&rsquo;est effectivement le couronnement de cette uvre g\u00e9n\u00e9rale d&rsquo;un J\u00e9r\u00f4me Bosch abstrait et postmoderne d\u00e9crivant d&rsquo;un pinceau convulsif la situation g\u00e9n\u00e9rale qui ne l&rsquo;est pas moins, et cela justifie parfaitement d&rsquo;y inclure la d\u00e9claration de guerre froide en Asie du robot-Obama lisant avec z\u00e8le les fiches pour lui pr\u00e9par\u00e9es par les services du Pentagone.<\/p>\n<\/p>\n<p><p>\tCes diverses initiatives partent dans tous les sens, et l&rsquo;on a la juste impression d&rsquo;initiatives prises sans qu&rsquo;il soit tenu aucun les unes des autres, ni surtout de la situation g\u00e9n\u00e9rale, particuli\u00e8rement avec les USA qui sont les ma\u00eetres du cloisonnement. Les strat\u00e8ges am\u00e9ricanistes, chacun dans son domaine, continuent \u00e0 fonctionner comme au temps de la splendeur de leur puissance commune et sans pareille, et le pouvoir civil, qui ne pense qu&rsquo;\u00e0 la r\u00e9\u00e9lection du pr\u00e9sident, suit les instructions sans souci d&rsquo;y comprendre davantage. Si les Russes ont d\u00e9cid\u00e9 d&rsquo;\u00e9tablir devant la Syrie un dispositif naval, cons\u00e9quent avec l&rsquo;arriv\u00e9e de leur <em>Amiral Kouznetzov<\/em> et sans crainte d&rsquo;affaiblir leur dispositif ailleurs, c&rsquo;est qu&rsquo;ils savent bien qu&rsquo;au-del\u00e0 de ses porte-avions en affectation (un en M\u00e9diterran\u00e9e, un au large du Golfe Persique \u00e9galement sollicit\u00e9 par l&rsquo;Afghanistan), l&rsquo;U.S. Navy n&rsquo;a rien de disponible pour une escalade dans cette zone \u00e0 moins de mobiliser toutes ses forces pour une attaque g\u00e9n\u00e9rale ; laquelle deviendrait une option catastrophique alors qu&rsquo;existent tant de points de tension, dont par exemple les projets permanents d&rsquo;attaque de l&rsquo;Iran qui devient dans le paysage actuel une perspective assur\u00e9e d&rsquo;explosion de toute la r\u00e9gion ; dont, autre exemple, l&rsquo;entretien actif de la nouvelle guerre froide contre la Chine&#8230;. Les Russes savent bien que le Pentagone, au rythme des lamentations de Panetta, est en cours de transformation acc\u00e9l\u00e9r\u00e9e en <a href=\"http:\/\/www.dedefensa.org\/article-moby_dick_en_tigre_de_papier_le_gout_de_la_catastrophe_26_11_2011.html\" class=\"gen\">tigre de papier<\/a>.<\/p>\n<\/p>\n<p><p>\tQuestion subsidiaire et compl\u00e9mentaire quoique classique : risque-t-on une guerre g\u00e9n\u00e9rale et g\u00e9n\u00e9ralis\u00e9e ? Vu les effectifs disponibles, ce ne peut \u00eatre qu&rsquo;une gesticulation en forme de chaos ou bien la vraie der des ders, la nucl\u00e9aire. Le deuxi\u00e8me cas, le plus net, est difficile \u00e0 envisager pour une bureaucratie (l&rsquo;am\u00e9ricaniste) qui cultive paradoxalement, \u00e0 c\u00f4t\u00e9 de son <em>hubris<\/em>, le go\u00fbt d&rsquo;une prudentissime planification, qui d\u00e9teste les aventures, qui n&rsquo;envisage quelque sorte de conflit que ce soit dans les conditions actuelles qu&rsquo;avec une marge de sup\u00e9riorit\u00e9 g\u00e9n\u00e9rale entre 5 contre 1 et 10 contre 1 avant de se d\u00e9cider. Pour le reste, il s&rsquo;agit d&rsquo;une non-guerre mena\u00e7ante faite de tensions et contrepieds divers, et nous verrions les Russes en meilleure posture que les autres Apr\u00e8s tout, lorsque ces m\u00eames Russes (voir Rogozine le <a href=\"http:\/\/fr.rian.ru\/world\/20111126\/192138498.html\" class=\"gen\">26 novembre 2011<\/a>) annoncent que les missiles <em>Iskander<\/em> qu&rsquo;ils d\u00e9ploient \u00e0 Kaliningrad contre le BMDE ne menacent pas la Pologne, membre de l&rsquo;OTAN, c&rsquo;est pour signaler qu&rsquo;ils peuvent tr\u00e8s bien, s&rsquo;il le faut, menacer la Pologne, membre de l&rsquo;OTAN ; ce qui d\u00e9tournerait l&rsquo;attention du principal (au Moyen-Orient et en Asie) en fournissant une ni\u00e8me guerre froid et l&rsquo;occasion \u00e0 la dynamique d&rsquo;autodestruction du bloc BAO de se manifester avec encore plus de vigueur. (Selon des sources cachotti\u00e8res mais non d\u00e9pourvues de connaissance, les services de l&rsquo;OTAN ont calcul\u00e9 qu&rsquo;actuellement, en cas de besoin en Europe, les pays europ\u00e9ens de l&rsquo;OTAN ne parviendraient m\u00eame pas \u00e0 r\u00e9unir 30.000 combattants, et cela en un nombre respectable de semaines. Il est bon de noter qu&rsquo;<strong>aujourd&rsquo;hui encore<\/strong>, ni l&rsquo;OTAN, ni les USA, ni les Isra\u00e9liens ne sont encore revenus de la rapidit\u00e9 et de l&rsquo;efficacit\u00e9 avec lesquelles les Russes, avec leurs chars fumants et p\u00e9taradants, et les vieilles tenues de combat de leurs tankistes, ont investi pr\u00e8s de la moiti\u00e9 de la G\u00e9orgie en trois jours, en ao\u00fbt 2008.)<\/p>\n<\/p>\n<p><p>\tL&rsquo;ensemble restitue cette dynamique de fuite en avant aveugle et obstin\u00e9e au nom d&rsquo;un <em>hubris<\/em> automatis\u00e9 devenu une sorte d&rsquo;affect de vieille midinette encombr\u00e9e du souvenir de ses fortunes d&rsquo;antan. Il en r\u00e9sulte une manifestation dialectique de surpuissance insupportable d&rsquo;arrogance sans fondement, une surpuissance dont la substance se dissout \u00e0 une vitesse acc\u00e9l\u00e9r\u00e9e et se transforme le plus naturellement du monde, et tout aussi rapidement, en une dynamique d&rsquo;autodestruction. Effectivement, pour conserver l&rsquo;effet de cette surpuissance qui n&rsquo;existe plus, la dynamique de l&rsquo;affirmation continue \u00e0 \u00eatre activ\u00e9e et elle devient, d\u00e9sormais plus naturellement que paradoxalement, celle de l&rsquo;affirmation de l&rsquo;autodestruction Fascination pour l&rsquo;autodestruction ? C&rsquo;est en effet peut-\u00eatre ce \u00e0 quoi sert aujourd&rsquo;hui leur caricature d&rsquo;<em>hubris<\/em>,  comment s&rsquo;autod\u00e9truire le plus efficacement possible. Le Syst\u00e8me a d&rsquo;excellents serviteurs jusqu&rsquo;au bout, jusqu&rsquo;\u00e0 l&rsquo;inversion finale.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur les transversales de l&rsquo;autodestruction Pourquoi attendre 2012, apr\u00e8s tout ? Le d\u00e9sordre de 2011 est effectivement en train de passer \u00e0 une vitesse sup\u00e9rieure, pour faire de 2012, avec ses divers rendez-vous d\u00e9mocratiques de changements de pouvoir, une ann\u00e9e singuli\u00e8rement agit\u00e9e ; mais ce d\u00e9sordre est tel qu&rsquo;on se croirait d\u00e9j\u00e0 en 2012&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[6911,3259,4270,4314,3977,9550,3106,2645,3319,3379,3178,2730,11131,3867,2613,2671],"class_list":["post-74280","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-arabe","tag-arabie","tag-autodestruction","tag-bmde","tag-chine","tag-egypte","tag-froide","tag-guerre","tag-navy","tag-pakistan","tag-printemps","tag-russie","tag-surpuissance","tag-syrie","tag-turquie","tag-us"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74280"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74280\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}