{"id":74293,"date":"2011-12-02T06:29:25","date_gmt":"2011-12-02T06:29:25","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/12\/02\/la-lecon-de-chose-du-jsf\/"},"modified":"2011-12-02T06:29:25","modified_gmt":"2011-12-02T06:29:25","slug":"la-lecon-de-chose-du-jsf","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/12\/02\/la-lecon-de-chose-du-jsf\/","title":{"rendered":"La le\u00e7on de chose du JSF"},"content":{"rendered":"<p><p>Dans l&rsquo;environnement apocalyptique de la situation washingtonienne, le programme JSF est plus que jamais une r\u00e9f\u00e9rence fondamentale, un indicateur, une illustration et un exemple. De quoi, tout cela ? R\u00e9f\u00e9rence, indicateur, illustration de la crise g\u00e9n\u00e9rale, certes. Le programme JSF est l&rsquo;\u00e9v\u00e9nement le plus pr\u00e9cis, le plus technologiquement et ontologiquemet identifi\u00e9, \u00e0 s&rsquo;\u00eatre d\u00e9gag\u00e9 de son propre courant de crise sp\u00e9cialis\u00e9e pour <strong>s&rsquo;int\u00e9grer<\/strong> dans la crise g\u00e9n\u00e9rale et en \u00eatre l&rsquo;illustration pour les domaines auxquels ils continuent \u00e0 appartenir. (Essentiellement, le syst\u00e8me du technologisme.)<\/p>\n<\/p>\n<p><p>\tAinsi s&rsquo;explique-t-il que, de plus en plus souvent, alors que, comme on l&rsquo;a d\u00e9j\u00e0 soulign\u00e9, le programme traverse une phase technique acceptable, \u00e9merge l&rsquo;examen de l&rsquo;hypoth\u00e8se nucl\u00e9aire, le <em>thinking the unthinkable<\/em>,  l&rsquo;abandon du programme JSF. C&rsquo;est le cas de deux grosses pointures d&rsquo;<em>Aviation Week &#038; Space Technology<\/em> (AW&#038;ST), David A. Fulghum et Bill Sweetman, le <a href=\"http:\/\/www.aviationweek.com\/aw\/generic\/story.jsp?topicName=Check6&#038;id=news\/asd\/2011\/11\/29\/01.xml&#038;headline=Are%20There%20Alternatives%20To%20The%20F-35%20Program?&#038;channel=&#038;from=topicalreports\" class=\"gen\">29 novembre 2011<\/a>. On y \u00e9tudie la question sacril\u00e8ge : Y a-t-il des alternatives au programme F-35 ?<\/p>\n<\/p>\n<p><p>\tInutile de s&rsquo;attarder aux r\u00e9ponses,  car oui, bien s\u00fbr, bien entendu, il existe des alternatives au F-35, m\u00eame si elles manquent de la gloire consid\u00e9rable du F-35, dans tous les cas en termes de communication, puisqu&rsquo;il ne serait plus alors question de parler d&rsquo;un avion de combat de la cinqui\u00e8me g\u00e9n\u00e9ration. (En effet, les alternatives concernent la modernisation de mod\u00e8les actuels,  c&rsquo;est-\u00e0-dire les F-15, F-16 e F-18 dont les premi\u00e8res productions remontent aux ann\u00e9es 1970 ; y compris, \u00e9trange paradoxe qui laisse perplexe jusqu&rsquo;\u00e0 nous conduire \u00e0 nous demander si nous ne sommes pas au bout du tunnel de l&rsquo;effondrement, modernisation avec l&rsquo;int\u00e9gration de sous-syst\u00e8mes avanc\u00e9s du JSF, \u00e0 propos desquels il existe une forte suspicion qu&rsquo;ils sont une des causes des avatars du m\u00eame JSF)<\/p>\n<\/p>\n<p><p>\tLe texte de Fulghum-Sweetman a fait suffisamment de bruit, \u00e0 cause du prestige de ces deux auteurs et de la publication o\u00f9 ils op\u00e8rent (AW&#038;ST). Philip Ewing, de <em>DoDBuzz.com<\/em>, y r\u00e9pond le <a href=\"http:\/\/www.dodbuzz.com\/2011\/11\/30\/thinking-the-unthinkable-about-the-f-35\/#ixzz1fJ90t5m9\" class=\"gen\">30 novembre 2011<\/a>, avec son titre (\u00ab<em>Thinking the unthinkable about the F-35<\/em>\u00bb)<MI>; puis avec son premier et court paragraphe, qui reprend explicitement le titre de Fulghum-Sweetman (Y a-t-il des alternatives au programme F-35 ?),  \u00ab<em>An AvWeek headline this week posed a question that once had an easy, one-word answer: No.<\/em>\u00bb Eh bien, ce n&rsquo;est plus le cas, constate Ewing, ce <em>No<\/em> p\u00e9remptoire et d\u00e9finitif, comme il l&rsquo;expose aussit\u00f4t :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The question was, per David A. Fulghum and Bill Sweetman: Are there alternatives to the F-35 program? But in post-super committee America, where the Air Force daydreams about growing its fleet with a service-life extension program for the Wright Flyer, things aren&rsquo;t as clear cut as they used to be<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEwing fait une rapide digression sur le bon vieux temps o\u00f9 les probl\u00e8mes existaient mais o\u00f9, finalement, le Syst\u00e8me marchait assez bien, de fa\u00e7on \u00e0 ce qu&rsquo;ils fussent r\u00e9solus, avec plus ou moins de bonheur. (Ewing et <em>DoDBuzz.com<\/em> sont d&rsquo;autant plus int\u00e9ressants \u00e0 suivre ici qu&rsquo;ils ne furent jamais, comme le fut Sweetman par exemple, parmi les premiers critiques du JSF, bien au contraire.) Plus loin dans son texte, Ewing aborde le cur de son sujet technique qui est de discuter de ces alternatives et de constater que, oui, finalement, on en discute dans les sph\u00e8res officielles, ce qui signifie qu&rsquo;on est bien en train de penser l&rsquo;impensable (l&rsquo;abandon du programme JSF), dans tous les cas comme une possibilit\u00e9, si minime soit-elle Entre les deux, Ewing glisse trois paragraphes d\u00e9crivant la situation <strong>g\u00e9n\u00e9rale<\/strong> \u00e0 Washington qui fait qu&rsquo;on en est arriv\u00e9 \u00e0 cette situation impensable de penser l&rsquo;impensable \u00e0 propos du JSF.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Problem is, Washington does strange things. Difficult as it was to believe the capital would trap itself in a Guns of August crisis of process, that is what has happened: Congressional deadlock lit a slow fuse set to burn until early 2013, when a budgetary detonation could obliterate nearly $1 trillion in planned DoD spending growth over the next 10 years. The Pentagon, having shut its eyes and plugged its ears in hopes that would banish this monster, made no plans for what to do in exactly the scenario that has materialized.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The White House doesn&rsquo;t want this bomb to go off, but under the bizarre logic of the moment, it has vowed to stop Congress from blowing out the fuse, in hopes that its continued burn will motivate lawmakers to get the kind of deal they couldn&rsquo;t to begin with  which set the whole thing in motion in the first place. Plus there&rsquo;s a nice little sideshow this week in which the Democratic president is in a showdown with the Democratically controlled Senate over detainee provisions in the defense bill.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>So in other words, things that may have once made sense now don&rsquo;t. All the reasons the F-35 was guaranteed to survive may no longer apply. Secretary Panetta himself dangled the program over the hotel balcony in his warning to Senate lawmakers about what might go away under sequestration. There are no brakes on this thing. At one point, we were supposed to get a thoughtful, soup-to-nuts strategic review that would show the way toward a new defense posture for Austerity America, but nope, nothin&rsquo; yet. Maybe this lack of any clear way forward is why people keep using the word decline.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;int\u00e9r\u00eat de ce passage est qu&rsquo;il vient d&rsquo;un sp\u00e9cialiste, qu&rsquo;il porte <em>in fine<\/em> sur une chose sp\u00e9cialis\u00e9e (le JSF\/F-35), dans un domaine non moins sp\u00e9cialis\u00e9e, et qu&rsquo;il d\u00e9crit pourtant toutes les conditions de la crise g\u00e9n\u00e9rale de la direction politique du syst\u00e8me de l&rsquo;am\u00e9ricanisme, qui constitue le moteur rugissant de l&#8217;empilement des crises qui ne cessent de faire s&rsquo;enfoncer l&rsquo;Am\u00e9rique. Le passage marque bien la conscience compl\u00e8te de tous les acteurs de ce qu&rsquo;il est n\u00e9cessaire de faire pour redresser cette pente catastrophique, et l&rsquo;\u00e9trange cheminement psychologique qui les conduit \u00e0 faire exactement le contraire, c&rsquo;est-\u00e0-dire \u00e0 s&rsquo;incliner devant la m\u00e9canique de la crise, \u00e0 accepter son in\u00e9luctabilit\u00e9. Eux aussi ne sont pas loin de sentir qu&rsquo;il y a l\u00e0, en marche, des forces sup\u00e9rieures \u00e0 eux, o\u00f9 la m\u00e9tahistoire peut bien prendre la forme d&rsquo;une op\u00e9rationnalit\u00e9 m\u00e9canique, qui les <strong>forcent<\/strong> \u00e0 agir dans le sens de l&rsquo;autodestruction. <\/p>\n<\/p>\n<p><p>\tLe JSF est ainsi d&rsquo;un int\u00e9r\u00eat d\u00e9monstratif tout \u00e0 fait essentiel. D&rsquo;une part, c&rsquo;est un artefact sp\u00e9cialis\u00e9, qui ne fut pas et qui n&rsquo;est pas trop soumis, certainement \u00e0 son origine, aux pressions n\u00e9gatives du syst\u00e8me de la communication ; un artefact qui vient de tr\u00e8s, tr\u00e8s loin (1993) et \u00e0 propos duquel l&rsquo;unanimit\u00e9 du syst\u00e8me de l&rsquo;am\u00e9ricanisme a agr\u00e9\u00e9 \u00e0 sa n\u00e9cessit\u00e9 incontestable jusqu&rsquo;\u00e0 l&rsquo;absolu ; un artefact qui, justement, \u00e0 cause de ces conditions, a utilis\u00e9 pendant bien plus d&rsquo;une d\u00e9cennie toute la puissance du syst\u00e8me de la communication \u00e0 son avantage, en d\u00e9bauchant par les moyens habituels (pression, corruption, mensonges, etc.) un certain nombre d&rsquo;allli\u00e9s sans que personne ne l\u00e8ve r\u00e9ellement le petit doigt ; un artefact qui a \u00e9t\u00e9 aliment\u00e9, choy\u00e9, couvert d&rsquo;ors et de $trillions, de consensus satisfaits par le tout-Washington, et dont l&rsquo;importance colossale en a fait une cause nationale D&rsquo;autre part, le fait est que, tout en continuant \u00e0 se d\u00e9velopper comme on le voit faire, il est en train de non seulement s&rsquo;effondrer, mais de <strong>se dissoudre<\/strong> litt\u00e9ralement sous nos yeux. Toutes ses vertus deviennent alors des vices irr\u00e9m\u00e9diables. Lui qui fut l&rsquo;\u00e9tendard de la surpuissance du Syst\u00e8me (sous la forme du syst\u00e8me de l&rsquo;am\u00e9ricanisme) devient le pavillon invers\u00e9 de l&rsquo;autodestruction du Syst\u00e8me (pavillon invers\u00e9, comme lorsque le drapeau am\u00e9ricain est hiss\u00e9 \u00e0 l&rsquo;envers avec le rectangle des \u00e9toiles vers le bas, pour indiquer venez \u00e0 notre aide, nous ne savons plus quoi faire)<\/p>\n<\/p>\n<p><p>\tC&rsquo;est effectivement le cas. Personne ne sait exactement <strong>pourquoi<\/strong> le JSF est en train de se dissoudre sous nos yeux,  et cette ignorance, peut-\u00eatre parce que les raisons de la dissolution jusqu&rsquo;alors ignor\u00e9es sont si puissantes et <strong>sup\u00e9rieures<\/strong>,  mais tout le monde <strong>sent<\/strong> que le JSF est en train de se dissoudre sous nos yeux. Cette grande cause de la surpuissance du syst\u00e8me du technologisme et du triomphe du XXI\u00e8me si\u00e8cle am\u00e9ricaniste (le second \u00e0 la suite de l&rsquo;<em>American Century<\/em>), est en train de devenir un grand sympt\u00f4me de l&rsquo;autodestruction du m\u00eame syst\u00e8me. L&rsquo;utilit\u00e9 de l&rsquo;int\u00e9r\u00eat du syst\u00e8me de la communication pour le JSF permet de nous faire suivre <em>in vivo<\/em>, sur un cas tr\u00e8s sp\u00e9cifique, la marche de l&rsquo;effondrement catastrophique devenant dissolution ; elle permet d&rsquo;observer que cette marche est aujourd&rsquo;hui un fait av\u00e9r\u00e9, act\u00e9 par les commentateurs sp\u00e9cialistes du domaine qui en arrivent, \u00e0 partir de lui, \u00e0 n&rsquo;\u00eatre plus sp\u00e9cialistes, \u00e0 se lib\u00e9rer du carcan de la sp\u00e9cialisation, pour offrir une interpr\u00e9tation et une description acceptables de la dissolution du Syst\u00e8me dans son enti\u00e8ret\u00e9 et sa sp\u00e9cificit\u00e9 universelle.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 2 d\u00e9cembre 2011 \u00e0 06H23<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans l&rsquo;environnement apocalyptique de la situation washingtonienne, le programme JSF est plus que jamais une r\u00e9f\u00e9rence fondamentale, un indicateur, une illustration et un exemple. De quoi, tout cela ? R\u00e9f\u00e9rence, indicateur, illustration de la crise g\u00e9n\u00e9rale, certes. Le programme JSF est l&rsquo;\u00e9v\u00e9nement le plus pr\u00e9cis, le plus technologiquement et ontologiquemet identifi\u00e9, \u00e0 s&rsquo;\u00eatre d\u00e9gag\u00e9 de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[7849,4270,10828,5252,10119,11740,2969,8217,250,10626,3194,11367,11131,6769],"class_list":["post-74293","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-alternative","tag-autodestruction","tag-courants","tag-dette","tag-dissolution","tag-ewig","tag-f-35","tag-fulghum","tag-jsf","tag-metahistoriques","tag-pentagone","tag-sequestration","tag-surpuissance","tag-sweetman"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74293"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74293\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}