{"id":74297,"date":"2011-12-05T06:34:05","date_gmt":"2011-12-05T06:34:05","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/12\/05\/israel-sinquiete-de-liran-non-plutot-de-legypte\/"},"modified":"2011-12-05T06:34:05","modified_gmt":"2011-12-05T06:34:05","slug":"israel-sinquiete-de-liran-non-plutot-de-legypte","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/12\/05\/israel-sinquiete-de-liran-non-plutot-de-legypte\/","title":{"rendered":"Isra\u00ebl s&rsquo;inqui\u00e8te de l&rsquo;Iran ? Non, plut\u00f4t de l&rsquo;Egypte\u2026"},"content":{"rendered":"<p><p>Qui a compris ce qui se passe en Egypte, qui est capable de comprendre ce qui se passera en Egypte ? Il y a deux semaines, la place Tahrir \u00e9tait en effervescence, la police tirait, on comptait morts et bless\u00e9s, le <em>Revolution 2.0<\/em> \u00e9tait en marche. Les insurg\u00e9s de Tahrir 2.0 proclamait que les \u00e9lections \u00e9taient un pi\u00e8ge (Elections, pi\u00e8ge \u00e0 cons, comme disaient nos glorieux a\u00een\u00e9s de 68). Les militaires ont frapp\u00e9 d&rsquo;une poigne pas trop dure sur une table r\u00e9serv\u00e9e \u00e0 cet effet, qui ne fait pas trop d&rsquo;\u00e9clats, et ont d\u00e9cid\u00e9 que les \u00e9lections, pi\u00e8ge \u00e0 cons auraient tout de m\u00eame lieu Lesquelles \u00e9lections, etc., ont donn\u00e9 comme premier r\u00e9sultat une majorit\u00e9 aux Fr\u00e8res Musulmans et une majorit\u00e9 absolue aux islamistes (Fr\u00e8res Musulmans et salafistes extr\u00e9mistes), ce qui constitue une issue assez \u00e9trange pour une op\u00e9ration d&rsquo;abord consid\u00e9r\u00e9e comme une r\u00e9cup\u00e9ration de la r\u00e9volution anti-Moubarak par le pouvoir des militaires dans le sens de l&rsquo;ancien r\u00e9gime. Pour l&rsquo;instant, les grands perdants sont donc les d\u00e9mocrates plus ou moins \u00e0 l&rsquo;occidentale, lib\u00e9raux et le reste.<\/p>\n<\/p>\n<p><p>\tCe qui, on le comprend, a l&rsquo;heur d&rsquo;alarmer consid\u00e9rablement Isra\u00ebl, qui va, avec le printemps arabe, plus ou moins activ\u00e9 ou soutenu par ses alli\u00e9s du bloc BAO selon la th\u00e9orie du complot du jour, de Charybde en Scylla. Apr\u00e8s la Tunisie et le Maroc aux islamistes, la Libye dans diverses mains dont les plus puissantes sont proches d&rsquo;al Qa\u00efda, l&rsquo;Egypte maintenant,  et dans quelles mains, telles qu&rsquo;elles se profilent. <em>PressTV.com<\/em>, qui n&rsquo;en rate pas une lorsqu&rsquo;il s&rsquo;agit d&rsquo;observer les d\u00e9boires isra\u00e9liens, mentionne, ce <a href=\"http:\/\/www.presstv.com\/detail\/213645.html\" class=\"gen\">3 d\u00e9cembre 2011<\/a>, la pr\u00e9occupation consid\u00e9rable du ministre isra\u00e9lien de la d\u00e9fense, Ehud Barak.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Israeli Defense Minister Ehud Barak says the initial result of the Egyptian elections are very disturbing, amid fears that the Muslim Brotherhood will end the long-standing peace treaty between the two. \u00ab\u00a0The process of Islamisation in Arab countries is very worrying,\u00a0\u00bb Israel&rsquo;s Channel Two television quoted Barak as saying.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>In addition, Israel also worries that the MB will seek closer ties with the Palestinian Resistance Movement of Hamas, which controls the besieged Gaza Strip<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Hamas had on Saturday hailed the partial results of the election with Hamas spokesperson Fawzi Barhum saying, It is a very good result it will mean more and more support for Palestinians issues. The relationship of the next regime in Egypt with the Palestinians will be very good, Barhum said.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLes d\u00e9tails de la course des \u00e9v\u00e8nements sont complexes et alternent les hauts et les bas, avec de soudaines retenues et d&rsquo;aussi soudaines avanc\u00e9es,  ceci et cela sur la voie de la dissolution de l&rsquo;ordre ancien amorc\u00e9e il y a un an en Tunisie. Mais l&rsquo;objectif fondamental de cette formidable pouss\u00e9e dont la dynamique \u00e9chappe compl\u00e8tement \u00e0 une action humaine concert\u00e9e reste similaire, tel qu&rsquo;on a pu l&rsquo;identifier d\u00e8s les premi\u00e8res semaines du soi-disant printemps arabe,  lequel devrait \u00eatre finalement qualifi\u00e9 d&rsquo;insurrection arabe, de la m\u00eame mani\u00e8re qu&rsquo;il y a une insurrection am\u00e9ricaine (contre l&rsquo;am\u00e9ricanisme) avec <em>Occupy<\/em> aux USA. (M\u00eame combat, comme l&rsquo;on disait \u00e9galement en 68, pr\u00e9monitoire pour les slogans, mais dans un sens qui tient \u00e9galement de l&rsquo;inversion.)<\/p>\n<\/p>\n<p><p>\tLes Isra\u00e9liens voient leurs pires pr\u00e9visions renforc\u00e9es par les \u00e9lections \u00e9gyptiennes. Pour eux, ces \u00e9lections ont toutes les malchances de r\u00e9activer s\u00e9rieusement le front palestinien, mais aussi \u00e9tablir un nouveau front aux fronti\u00e8res du Sina\u00ef, et r\u00e9activer le projet conceptuel d&rsquo;alliance entre l&rsquo;Egypte et la Turquie \u00e9voqu\u00e9 cet \u00e9t\u00e9 par Erdogan, en ramenant une partie de l&rsquo;int\u00e9r\u00eat de la Turquie de la Syrie vers la question isra\u00e9lienne. Pour \u00e9largir le champ des bouleversements catastrophiques pour l&rsquo;ordre ancien, on ajoutera <a href=\"http:\/\/www.presstv.com\/detail\/213631.html\" class=\"gen\">cet avis<\/a> assez significatif, sinon \u00e9nigmatique dans les liens qu&rsquo;il suppose entre l&rsquo;auteur de cet avis et la situation en Arabie, du dirigeant du parti islamiste tunisien al-Nahda vainqueur des \u00e9lections tunisienne, Rashid Ghannouchi, selon lequel l&rsquo;Arabie Saoudite est au bord de l&rsquo;explosion si elle ne d\u00e9cide pas des r\u00e9formes absolument radicales. Ces initiatives r\u00e9formistes qu&rsquo;on r\u00e9clame sont assez peu dans les capacit\u00e9s de l&rsquo;actuel pouvoir plus ou moins int\u00e9rimaire et extr\u00eamement flou du prince Nayef en Arabie. (On ajoutera \u00e9galement, pour compl\u00e9ter le tableau, la recrudescence des tensions et des troubles au Bahrain et au Yemen.).<\/p>\n<\/p>\n<p><p>\tQuant au bloc BAO, dont l&rsquo;attitude vis-\u00e0-vis de l&rsquo;\u00e9v\u00e9nement printemps\/insurrection arabe est du type schizophr\u00e9nie multiple, \u00e0 la fois soutenant les pouvoirs en place, les groupes extr\u00e9mistes des r\u00e9seaux sociaux oppos\u00e9s aux pouvoirs en place, les groupes lib\u00e9raux pr\u00e9tendument pro-occidentaux oppos\u00e9s aux deux pr\u00e9c\u00e9dents, les islamistes \u00e9ventuellement lorsqu&rsquo;ils sont suppos\u00e9s mod\u00e9r\u00e9s, la politique isra\u00e9lienne et ainsi de suite, l&rsquo;\u00e9pisode Tarhir 2.0\/\u00e9lections\/victoire islamiste n&rsquo;a rien provoqu\u00e9 en fait d&rsquo;analyse globale. Personne n&rsquo;a vraiment rien vu venir parce qu&rsquo;il semble bien que tout le monde ait renonc\u00e9 \u00e0 l&rsquo;id\u00e9e d&rsquo;esp\u00e9rer voir quelque chose venir. Les analystes du bloc BAO sont aujourd&rsquo;hui totalement perdus et \u00e9cartel\u00e9s, entre les constats de la v\u00e9rit\u00e9 de l&rsquo;\u00e9volution politique et les consignes des politiques \u00e9labor\u00e9es dans les salons et dans les officines humanitaristes et droitdel&rsquo;hommistes, qui sont immuablement enthousiastes en faveur de l&rsquo;influence et de la politique du susdit bloc.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 5 d\u00e9cembre 2011 \u00e0 06H34<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qui a compris ce qui se passe en Egypte, qui est capable de comprendre ce qui se passera en Egypte ? Il y a deux semaines, la place Tahrir \u00e9tait en effervescence, la police tirait, on comptait morts et bless\u00e9s, le Revolution 2.0 \u00e9tait en marche. Les insurg\u00e9s de Tahrir 2.0 proclamait que les \u00e9lections&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[7359,9550,11025,2774,3758,11243,11414],"class_list":["post-74297","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-barak","tag-egypte","tag-freres","tag-israel","tag-musulmans","tag-salafistes","tag-sinai"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74297"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74297\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}