{"id":74390,"date":"2012-01-06T04:48:45","date_gmt":"2012-01-06T04:48:45","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/01\/06\/le-guardian-chevauche-le-tigre\/"},"modified":"2012-01-06T04:48:45","modified_gmt":"2012-01-06T04:48:45","slug":"le-guardian-chevauche-le-tigre","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/01\/06\/le-guardian-chevauche-le-tigre\/","title":{"rendered":"Le <em>Guardian<\/em> \u201cchevauche le tigre\u201d"},"content":{"rendered":"<p><p>Ne g\u00e2chons pas notre (tr\u00e8s rare) plaisir, ou dans tous les cas demi-plaisir, au milieu de nos vitup\u00e9rations habituelles contre la presse-Syst\u00e8me. Le <em>Guardian<\/em>, qui s&rsquo;\u00e9tait montr\u00e9 tr\u00e8s, tr\u00e8s discret \u00e0 propos des premi\u00e8res manifestations pr\u00e9-\u00e9lectorales de Ron Paul dans le cadre du parti r\u00e9publicain, d\u00e9taille dans son \u00e9ditorial du <a href=\"http:\/\/www.guardian.co.uk\/world\/2012\/jan\/04\/republicans-iowa-gop-caucuses\" class=\"gen\">5 janvier 2012<\/a> la situation des primaires du m\u00eame parti apr\u00e8s le <em>Caucus<\/em> de l&rsquo;Iowa d&rsquo;une fa\u00e7on extr\u00eamement int\u00e9ressante. Le paradoxe est qu&rsquo;on saisit mal ce que les expressions employ\u00e9es d\u00e9signent en fait de candidats, et, par cons\u00e9quent, qu&rsquo;on se demande si le <em>Guardian<\/em> a bien compris la situation qu&rsquo;il d\u00e9crit pourtant avec une certaine justesse.<\/p>\n<\/p>\n<p><p>\tLa premi\u00e8re partie de l&rsquo;\u00e9dito d\u00e9crit une confrontation \u00e0 l&rsquo;int\u00e9rieur du parti r\u00e9publicain entre l&rsquo;<em>establishment<\/em> et une v\u00e9ritable force insurrectionnelle qu&rsquo;il qualifie de l&rsquo;image saisissante d&rsquo;un tigre furieux (\u00ab<em>A tiger this angry, dispossessed, and volatile<\/em>\u00bb). Par une pudeur remarquable,  ou bien est-ce une  ignorance effective, ou bien une inculture d\u00e9lib\u00e9r\u00e9e,  le nom de Ron Paul n&rsquo;est pas cit\u00e9 dans cette partie, alors qu&rsquo;il est notoirement \u00e9vident qu&rsquo;il s&rsquo;agit bien \u00e9videmment du repr\u00e9sentant, voire m\u00eame de l&rsquo;inspirateur de cette force insurrectionnelle. Curieusement, le <em>Guardian<\/em> semble le nier en observant qu&rsquo;aucun des candidats de l&rsquo;<em>establishment<\/em> ne parvient \u00e0 s&rsquo;imposer comme le porteur de torche de cette insurrection, et concluant implicitement, et m\u00eame explicitement, que, par cons\u00e9quent, <strong>personne<\/strong> parmi les candidats ne peut donc chevaucher le tigre (\u00ab<em>The inability of any one candidate in the race for the Republican nomination to survive as the torch bearer for this insurgency<\/em>\u00bb)  Et Ron Paul ? Sont-ils s\u00e9rieux, ces <em>gentlemen<\/em> de Fleet Street ?<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The Republican caucuses in Iowa did produce a clear result, although not one that will appeal to the nominal winner. The picture that emerges is that the GOP is not a party in the common sense of the word: a broad church with aisles stretching to left and right, and one altar. It has at least two of them. The first is used by establishment conservatives, who genuflect to the view that theirs is a natural right to govern. The second belongs to a revolutionary, some call it apocalyptic, insurgency, which believes that America has been usurped by forces alien to it, and it is their moral duty, not as politicians, but as yeomanry to take it back. They do not believe Washington can be reformed. It must be broken first on the back of a popular revolt. The destructive forces unleashed by one part of the GOP are highly toxic to the other.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The inability of any one candidate in the race for the Republican nomination to survive as the torch bearer for this insurgency may not be accidental. A tiger this angry, dispossessed, and volatile could be impossible to ride<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tA partir de l\u00e0, l&rsquo;\u00e9dito d\u00e9taille les batailles internes entre les candidats repr\u00e9sentatifs de l&rsquo;<em>establishment<\/em>, avec comme tactique de chercher, les uns apr\u00e8s les autres, \u00e0 ne pas \u00eatre Romney, cela \u00e9tant semble-t-il, leur tactique pour tenter, justement, de chevaucher le tigre et de le dompter. Encore une fois : sont-ils s\u00e9rieux ?<\/p>\n<\/p>\n<p><p>\tIl n&rsquo;y a dans cette bataille \u00e0 l&rsquo;int\u00e9rieur de l&rsquo;<em>establishment<\/em> aucune tactique concevable de r\u00e9cup\u00e9ration de l&rsquo;\u00e9lectorat insurg\u00e9, simplement parce que cette insurrection c&rsquo;est Ron Paul lui-m\u00eame, et qu&rsquo;il est toujours diablement en course, et que, lui, il chevauche le tigre parce qu&rsquo;il est lui-m\u00eame le tigre S&rsquo;en sont-ils aper\u00e7us, les <em>gentlemen<\/em> ? Tout juste est-il mentionn\u00e9 plus loin une indication approximative de la v\u00e9ritable situation tactique que le <em>Guardian<\/em> ne semble pas vraiment pouvoir ou vouloir embrasser, lorsqu&rsquo;il est \u00e9crit que le possible d\u00e9clin de Santorum apr\u00e8s son \u00e9clat de l&rsquo;Iowa permettrait \u00e0 un Ron Paul de r\u00e9cup\u00e9rer une partie de ceux qui auraient vot\u00e9 pour le m\u00eame Santorum (\u00ab<em>If Mr Santorum&rsquo;s sparkler fizzles out as one feels it must, Ron Paul is there to trudge on<\/em>\u00bb). Puis le m\u00eame texte encha\u00eene sur ces deux phrases \u00e9nigmatiques, ou dans tous les cas qui semblent \u00e9gar\u00e9s de la description d&rsquo;une autre situation : \u00ab<em>Republicans are racing the wrong course. They should not be trying to establish how far to the right it is safe to venture, but how many others they will take with them.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDe quelle droite extr\u00eame (\u00ab<em> how far to the right<\/em>\u00bb) est-il question ? Celle du tigre furieux, des insurg\u00e9s, caract\u00e9risation implicite dans le langage de cet \u00e9ditorial ? Mais un Gingrich ou un Santorum, et m\u00eame un Romney par certains aspects, tous personnages typiques de l&rsquo;<em>establishment<\/em> avec leur politique ext\u00e9rieure <a href=\"http:\/\/www.dedefensa.org\/article-l_iran_et_la_maniaco-depression_de_la_modernite_30_12_2011.html\" class=\"gen\">m\u00e9galomaniaque<\/a> de menace de guerre dans le sens qu&rsquo;on sait, leur soutien inconditionnel \u00e0 Isra\u00ebl, etc., sont naturellement \u00e0 la droite extr\u00eame, ou dans tous les cas dans l&rsquo;extr\u00eame selon les consignes du Syst\u00e8me ; Ron Paul, lui, avec sa politique de d\u00e9sengagement, est en g\u00e9n\u00e9ral situ\u00e9, \u00e0 peine ironiquement, comme \u00e9tant \u00e0 la gauche d&rsquo;Obama. Est-ce que la proposition de Gingrich, reprise avec brio par Santorum, selon laquelle, par d\u00e9cret divin, la Palestine n&rsquo;existe pas, va s\u00e9duire le tigre ? C&rsquo;est pourtant de l&rsquo;extr\u00eame,  ou bien non, peut-\u00eatre cela n&rsquo;est-il pas caract\u00e9ris\u00e9 comme extr\u00eame ?<\/p>\n<\/p>\n<p><p>\tLe tout se termine selon l&rsquo;id\u00e9e, tr\u00e8s londonienne, que tout cela profitera \u00e0 Obama, parce que les \u00e9lecteurs ind\u00e9pendants ne veulent pas voter pour la droite extr\u00eame (celle-l\u00e0, type-Gingrich ou Santorum ? Ou Romney ?). Mais ont-ils conscience, les <em>gentlemen<\/em>, que les ind\u00e9pendants n&rsquo;ont pas besoin d&rsquo;aller vers Obama parce qu&rsquo;ils vont d\u00e9j\u00e0 vers les insurg\u00e9s r\u00e9publicains, c&rsquo;est-\u00e0-dire Ron Paul ? Ah, mais nous avions oubli\u00e9 ; bien qu&rsquo;il ait \u00e9t\u00e9 nomm\u00e9 une fois, Ron Paul n&rsquo;existe pas.<\/p>\n<\/p>\n<p><p>\t Car, en effet, tout le raisonnement du <em>Guardian<\/em> est implicitement bas\u00e9 sur l&rsquo;acte de foi absolu que Paul <strong>ne peut pas<\/strong> arriver au stade final et \u00eatre l&rsquo;adversaire d&rsquo;Obama, comme candidat r\u00e9publicain ou comme candidat ind\u00e9pendant, non pas parce qu&rsquo;il n&rsquo;a aucune chance mais simplement <strong>parce qu&rsquo;il n&rsquo;existe pas<\/strong>. Par cons\u00e9quent, le <em>Guardian<\/em> reconna\u00eet qu&rsquo;il y a une formidable insurrection dans le parti r\u00e9publicain (et ailleurs, pourrait-il ajouter, chez les ind\u00e9pendants et chez une partie des \u00e9lecteurs d\u00e9mocrates) ; il reconna\u00eet que tous les candidats de l&rsquo;<em>establishment<\/em> se d\u00e9chirent <strong>entre eux<\/strong>, ne sachant comment r\u00e9cup\u00e9rer cette insurrection ; mais il semble ignorer que la raison en est simplement et \u00e9videmment que l&rsquo;insurrection se fait \u00e9videmment <strong>contre eux<\/strong>, conduite en cela par Ron Paul. Il termine, dans une explosion de logique-Syst\u00e8me, en laissant implicitement entendre que le candidat qui repr\u00e9sente cette insurrection, et qui a un tr\u00e8s fort soutien d&rsquo;ind\u00e9pendants et m\u00eame de d\u00e9mocrates, n&rsquo;a aucune chance. Mais bon, certes, il est vrai que ce candidat-l\u00e0, lui, il n&rsquo;existe pas. Point final.<\/p>\n<\/p>\n<p><p>\tUne telle dialectique va finir pour nous convaincre. Ils croient <strong>vraiment<\/strong> que Paul n&rsquo;existe pas. D&rsquo;ailleurs, regardez-le, il n&rsquo;a pas une t\u00eate de tigre D&rsquo;ailleurs, de qui parlez-vous ? Il n&#8217;emp\u00eache, le <em>Guardian<\/em> nous a tout de m\u00eame confirm\u00e9 qu&rsquo;il existe une insurrection, et que le tigre furieux, lui, n&rsquo;est pas une illusion sans consistance ni cons\u00e9quence. Alors, ce serait donc que Ron Paul existe ? Il est temps d&rsquo;aller faire visite \u00e0 notre psychanalyste.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 6 janvier 2012 \u00e0 04H37<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ne g\u00e2chons pas notre (tr\u00e8s rare) plaisir, ou dans tous les cas demi-plaisir, au milieu de nos vitup\u00e9rations habituelles contre la presse-Syst\u00e8me. Le Guardian, qui s&rsquo;\u00e9tait montr\u00e9 tr\u00e8s, tr\u00e8s discret \u00e0 propos des premi\u00e8res manifestations pr\u00e9-\u00e9lectorales de Ron Paul dans le cadre du parti r\u00e9publicain, d\u00e9taille dans son \u00e9ditorial du 5 janvier 2012 la situation&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[7928,2689,4118,5214,8698,7340,3140,11857,3310],"class_list":["post-74390","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-7928","tag-droite","tag-establishment","tag-extreme","tag-insurrection","tag-iowa","tag-paul","tag-presudentielles","tag-ron"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74390"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74390\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}