{"id":74402,"date":"2012-01-09T07:09:43","date_gmt":"2012-01-09T07:09:43","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/01\/09\/falloujah-et-son-ode-a-hatham-al-mannaa\/"},"modified":"2012-01-09T07:09:43","modified_gmt":"2012-01-09T07:09:43","slug":"falloujah-et-son-ode-a-hatham-al-mannaa","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/01\/09\/falloujah-et-son-ode-a-hatham-al-mannaa\/","title":{"rendered":"Falloujah et son ode \u00e0 Hatham al Mannaa"},"content":{"rendered":"<p><h2 class=\"common-article\">Falloujah et son ode \u00e0 Hatham al Mannaa<\/h2>\n<\/p>\n<p><p>\tAvril 2004.<\/p>\n<\/p>\n<p><p>\tLe deuxi\u00e8me mill\u00e9naire commen\u00e7ait de s&rsquo;\u00e9battre dans sa prime enfance, il entamait ses cinq ans.<\/p>\n<\/p>\n<p><p>\tLa ville de Falloujah rompait ses poches d&rsquo;eau, se vidait. Des colonnes en suintaient de toutes parts.<\/p>\n<\/p>\n<p><p>\tL&rsquo;envahisseur ne se montrait gu\u00e8re avare de ses froides foudres d&rsquo;uranium.<\/p>\n<\/p>\n<p><p>\tS&rsquo;expulsaient \u00e0 coups de missiles les futurs mal form\u00e9s.<\/p>\n<\/p>\n<p><p>\tEt tous ceux qui fuyaient par milliers, remontant le cours du fleuve, rejoignaient la Syrie voisine.<\/p>\n<\/p>\n<p><p>\tLe 7 juillet 2004, plus d&rsquo;un an apr\u00e8s l&rsquo;invasion de l&rsquo;Irak alors que l&rsquo;\u00e9vidence d&rsquo;absence d&rsquo;armes de destruction massives s&rsquo;imposait \u00e0 tous, paraissait une lettre ouverte sign\u00e9e par 105 intellectuels arabes \u00e0 majorit\u00e9 irakienne sur le journal Azzaman Newspapers.<\/p>\n<\/p>\n<p><p>\tElle \u00e9tait adress\u00e9e \u00e0 G. W. Bush et Tony Blair, alors respectivement Pr\u00e9sident des US(a) et Premier Ministre britannique.<\/p>\n<\/p>\n<p><p>\tCette lettre a \u00e9t\u00e9 pieusement conserv\u00e9e par des Irakiens de gauche pour qu&rsquo;aucune des personnes qui a appos\u00e9 son nom au bas du document ne soit omise le jour o\u00f9 il deviendra n\u00e9cessaire de l&rsquo;exhiber. Elle figure toujours ici : <a href=\"http:\/\/www.saotaliassar.org\/Frei%20Kitabat\/FreiKitabat\/Intelgent.htm.\" class=\"gen\">http:\/\/www.saotaliassar.org\/Frei%20Kitabat\/FreiKitabat\/Intelgent.htm.<\/a><\/p>\n<\/p>\n<p><p>\tPour les non arabophones, un <em>google translate<\/em> suffit \u00e0 en appr\u00e9hender la substance car elle ne pr\u00e9sente aucune difficult\u00e9 de traduction.<\/p>\n<\/p>\n<p><p>\tLes 105 intellectuels remercient et expriment toute leur gratitude aux deux chefs d&rsquo;\u00c9tat, \u00e0 leurs peuples et leurs arm\u00e9es pour avoir eu le courage d&rsquo;avoir envahi l&rsquo;Irak et d\u00e9barrass\u00e9 les Irakiens de Saddam Houssein.<\/p>\n<\/p>\n<p><p>\tLe cent et uni\u00e8me signataire, le Dr Haytham Al Mannaa est en r\u00e9alit\u00e9 un Syrien, exil\u00e9 \u00e0 Paris vivant de subsides allou\u00e9s par des instances de l&rsquo;ONU (?) pour s&rsquo;\u00eatre d\u00e9clar\u00e9 pr\u00e9sident d&rsquo;une association, organisme arabe des droits de l&rsquo;homme, \u00e9lev\u00e9e au titre de Commission arabe des droits humains. <\/p>\n<\/p>\n<p><p>\tD\u00e9but octobre 2011, Haytham al Mannaa caract\u00e9risait son rival, l&rsquo;autre opposant syrien, Bouhrane Ghalioune, pr\u00e9sident du Conseil National Syrien (CNS), pour ce que les instances franco-am\u00e9ricaines en ont fait, comme <a href=\"http:\/\/france-irak-actualite.over-blog.org\/article-un-dirigeant-de-l-opposition-syrienne-taxe-le-cns-de-club-de-washington-86262618.html\" class=\"gen\">un agent de l&rsquo;\u00e9tranger<\/a>.<\/p>\n<\/p>\n<p><p>\tIl constatait que B. Ghalioune s&rsquo;\u00e9tait autoproclam\u00e9 chef de l&rsquo;opposition sans avoir \u00e9t\u00e9 d\u00e9sign\u00e9  pour les repr\u00e9senter par les opposants de l&rsquo;int\u00e9rieur.<\/p>\n<\/p>\n<p><p>\tFin d\u00e9cembre 2011, Haytham Al Mannaa passe outre ses pr\u00e9ventions \u00e0 l&rsquo;\u00e9gard de son concurrent et signe au Caire <a href=\"http:\/\/www.al-akhbar.com\/system\/files\/Mannaa_English.pdf\" class=\"gen\">un pacte avec le CNS<\/a> qui jette quelques principes d&rsquo;accord pour l&rsquo;apr\u00e8s Bachar Al Assad. Le point 2 de protection des civils par tous les moyens dans le contexte du droit international peut rentrer en peu subtile contradiction avec son principe premier qui exclue toute intervention militaire \u00e9trang\u00e8re affectant la souverainet\u00e9 syrienne.<\/p>\n<\/p>\n<p><p>\tLes enfants syriens doivent-ils se pr\u00e9parer \u00e0 chanter une ode \u00e0 Haytham Al Mannaa pour le remercier de sa future gratitude \u00e0 l&rsquo;\u00e9gard de M. Jupp\u00e9 et de M. Obama qui tiennent pour acquise leur intervention militaire lib\u00e9ratrice en Syrie ?<\/p>\n<\/p>\n<p><p>\tLes enfants de Felloujah se permettent de se rappeler au souvenir de Haytham Al Mannaa :<\/p>\n<\/p>\n<p><\/p>\n<h4>Felloujah sur l&rsquo;Euphrate<D><\/h4>\n<p><\/p>\n<p><p>\tLaissons le temps ce vieillard morose<\/p>\n<\/p>\n<p><p>\tAux doigts de chapelets<\/p>\n<\/p>\n<p><p>\tSemer ses grains entre deux hivers<\/p>\n<\/p>\n<p><p>\tEt rencontrons nous de l&rsquo;autre c\u00f4t\u00e9 de l&rsquo;ann\u00e9e<\/p>\n<\/p>\n<p><p>\tCeinte de ses colliers de larmes<\/p>\n<\/p>\n<p><p>\tCouronn\u00e9e de feuilles de peupliers<\/p>\n<\/p>\n<p><p>\tet parfum\u00e9e des rires jasp\u00e9s des enfants de Falloujah<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tLaissons-le aux portes de notre printemps<\/p>\n<\/p>\n<p><p>\tLui qui ne compte plus<\/p>\n<\/p>\n<p><p>\tUs\u00e9 et prisonnier de son sablier<\/p>\n<\/p>\n<p><p>\tLes rues de nos villes sont pav\u00e9es des m\u00e9moires de notre oubli<\/p>\n<\/p>\n<p><p>\tEt chaque venelle s&rsquo;y d\u00e9verse charriant<\/p>\n<\/p>\n<p><p>\tLes blessures de nos enfants de Falloujah<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tIl se revigore de ses yeux blanchis au phosphore<\/p>\n<\/p>\n<p><p>\tA voir danser toutes plaies rentr\u00e9es<\/p>\n<\/p>\n<p><p>\tDans leurs robes de clairi\u00e8re et de mousse palm\u00e9e<\/p>\n<\/p>\n<p><p>\tT\u00eates bl\u00eamies dans leurs  fichus d&rsquo;attente<\/p>\n<\/p>\n<p><p>\tLes m\u00e8res des enfants de Falloujah<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tLaissons-le s&rsquo;attendrir, lui l&rsquo;impassible, le mesureur,<\/p>\n<\/p>\n<p><p>\tEnvas\u00e9 de ses deux  pieds dans la tourbe <\/p>\n<\/p>\n<p><p>\tQuand \u00e9clot la nu\u00e9e des enfants de Falloujah<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tSes l\u00e8vres se scellent et son cur d\u00e9borde<\/p>\n<\/p>\n<p><p>\tQuand se coude le fleuve rougi<\/p>\n<\/p>\n<p><p>\tDe ce qui reste des enfants de Falloujah<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tToutes ces clameurs, toutes ces couleurs et ce jasmin au bout de notre jardin<\/p>\n<\/p>\n<p><p>\tAu soir de notre patrie, car voici qu&rsquo;il veille de toutes ses nuits allum\u00e9es<\/p>\n<\/p>\n<p><p>\taux  r\u00eaves d&rsquo;\u00e9clair des enfants de Falloujah<\/p>\n<\/p>\n<p><\/p>\n<p>\n<p class=\"signature\">Badia Benjelloun<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Falloujah et son ode \u00e0 Hatham al Mannaa Avril 2004. Le deuxi\u00e8me mill\u00e9naire commen\u00e7ait de s&rsquo;\u00e9battre dans sa prime enfance, il entamait ses cinq ans. La ville de Falloujah rompait ses poches d&rsquo;eau, se vidait. Des colonnes en suintaient de toutes parts. L&rsquo;envahisseur ne se montrait gu\u00e8re avare de ses froides foudres d&rsquo;uranium. S&rsquo;expulsaient \u00e0&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3953,11868,4336,3867],"class_list":["post-74402","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-benjelloun","tag-cns","tag-falloujah","tag-syrie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74402"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74402\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}