{"id":74404,"date":"2012-01-09T15:49:52","date_gmt":"2012-01-09T15:49:52","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/01\/09\/liran-et-lincertitude-du-general-dempsey\/"},"modified":"2012-01-09T15:49:52","modified_gmt":"2012-01-09T15:49:52","slug":"liran-et-lincertitude-du-general-dempsey","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/01\/09\/liran-et-lincertitude-du-general-dempsey\/","title":{"rendered":"L&rsquo;Iran et l&rsquo;incertitude du g\u00e9n\u00e9ral Dempsey"},"content":{"rendered":"<p><p>Premi\u00e8re question : Pouvons-nous, si nous le devons, et sans utiliser nous-m\u00eames de syst\u00e8mes nucl\u00e9aires, \u00e9liminer leurs capacit\u00e9s nucl\u00e9aires (de l&rsquo;Iran) ? R\u00e9ponse du g\u00e9n\u00e9ral Dempsey, pr\u00e9sident du comit\u00e9 des chefs d&rsquo;\u00e9tat-major US : Eh bien, je veux sans le moindre doute qu&rsquo;ils croient que c&rsquo;est le cas  Nouvelle question : Et alors, est-ce bien le cas ? R\u00e9ponse du g\u00e9n\u00e9ral Dempsey : Je veux absolument qu&rsquo;ils croient que c&rsquo;est le cas.<\/p>\n<\/p>\n<p><p>\tPour confirmation, sur <em>Politico.com<\/em>, ce <a href=\"http:\/\/www.politico.com\/blogs\/politico-live\/2012\/01\/pentagon-brass-hedges-on-iran-capabilities-110068.html\" class=\"gen\">8 janvier 2012<\/a>, d&rsquo;apr\u00e8s un \u00e9change du jour sur CBS.<em>News<\/em>.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Joint Chiefs of Staff Chairman Gen. Martin Dempsey says he wants Iran to \u00ab\u00a0believe\u00a0\u00bb the U.S. had the capability to destroy their fledgling nuclear program  but declined to answer specifically whether the U.S. military possessed that capability.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Could we, if we had to, without using nuclear weapons ourselves, take out their nuclear capability? CBS host Bob Schieffer asked in an interview aired Sunday on Face the Nation.&rsquo;<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Well, I certainly want them to believe that that&rsquo;s the case, said Dempsey.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Well, is it? asked Schieffer.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>I absolutely want them to believe that that&rsquo;s the case, said Dempsey.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe g\u00e9n\u00e9ral Dempsey a beaucoup moins d&rsquo;entregent et de brio que son pr\u00e9d\u00e9cesseur, l&rsquo;amiral Mullen. Il n&rsquo;a pas, \u00e9galement, avec son secr\u00e9taire \u00e0 la d\u00e9fense Panetta, la complicit\u00e9 qui exista entre Mullen et le secr\u00e9taire \u00e0 la d\u00e9fense Gates, entre 2006 et 2011. Il ne b\u00e9n\u00e9ficie pas, dans certaines situations op\u00e9rationnelles, notamment face \u00e0 l&rsquo;Iran, d&rsquo;une paradoxale complicit\u00e9 avec les Iraniens, comme il y eut <a href=\"http:\/\/www.dedefensa.org\/article-de_l_amiral_fallon_au_uss_john_c_stennis_04_01_2012.html\" class=\"gen\">entre 2006 et 2008<\/a>, pour bloquer toute attaque contre l&rsquo;Iran que les militaires, et surtout la Navy, jugeaient insens\u00e9e. Dempsey est un peu terne, un peu taiseux et renfrogn\u00e9, il repr\u00e9sente bien les forces arm\u00e9es US confront\u00e9es \u00e0 des d\u00e9mons impossibles \u00e0 dompter, \u00e0 des forces impossibles \u00e0 contr\u00f4ler, tout cela engendr\u00e9 par le Syst\u00e8me lui-m\u00eame Sa pr\u00e9occupation est bien l\u00e0, sur le plan int\u00e9rieur, et c&rsquo;est pour cela que sa r\u00e9ponse ressemble \u00e0 une pri\u00e8re faite aux Iraniens : Par piti\u00e9, faites un effort et essayez de croire que nous pouvons vous mettre KO, pour ne pas risquer l&rsquo;aventure contre nous, pour ne pas nous entra\u00eener nous-m\u00eames dans une aventure que nous craignons&#8230;<\/p>\n<\/p>\n<p><p>\tLes r\u00e9ponses de Dempsey ont une allure presque choquante, dans leur ing\u00e9nuit\u00e9, et notamment la r\u00e9ponse principale qui est de ne pas r\u00e9pondre <strong>du tout<\/strong>. En 2006 ou en 2007, un Mullen aurait r\u00e9pondu 1) que les forces arm\u00e9es US ont les capacit\u00e9s n\u00e9cessaires pour remplir les missions qu&rsquo;on leur assigne, et 2) que l&rsquo;hypoth\u00e8se d&rsquo;une attaque contre l&rsquo;Iran n&rsquo;est pas une hypoth\u00e8se raisonnable et souhaitable, et qu&rsquo;il faut l&rsquo;\u00e9carter le plus possible comme une instance d&rsquo;ultime recours. S&rsquo;il y avait eu insistance dans les questions sur les capacit\u00e9s militaires elles-m\u00eames, Mullen aurait pr\u00e9cis\u00e9 que cela concerne un domaine couvert par le secret militaire, mais que, effectivement, les forces arm\u00e9es US ont les capacit\u00e9s n\u00e9cessaires, etc. Sa r\u00e9ponse se serait en fait adress\u00e9e aux faucons de l&rsquo;administration Bush (Cheney &#038; Cie), dans une bataille d&rsquo;influence qui n&rsquo;avait rien de militaire,  \u00e9tant entendu qu&rsquo;en tout \u00e9tat de cause, les capacit\u00e9s militaires ad\u00e9quates existaient puisqu&rsquo;il s&rsquo;agit des USA. La r\u00e9ponse de Dempsey, ou plut\u00f4t sa non-r\u00e9ponse, refl\u00e8te par contre une pr\u00e9occupation fondamentale concernant ces capacit\u00e9s, du fait de la d\u00e9gradation prodigieusement rapide des capacit\u00e9s US, essentiellement due, en plus des effets des contraintes op\u00e9rationnelles, aux blocages de processus et de production des programmes dans une structure bureaucratique (le Pentagone) absolument hors de tout contr\u00f4le, et d\u00e9sormais, en plus, aux contraintes budg\u00e9taires. Nul ne peut ne pas avoir \u00e0 l&rsquo;esprit, par exemple, l&rsquo;\u00e9tat de <a href=\"http:\/\/www.dedefensa.org\/article-comptabilite_du_trou_noir_06_09_2010.html\" class=\"gen\">d\u00e9cr\u00e9pitude<\/a> tr\u00e8s <a href=\"http:\/\/www.dedefensa.org\/article-l_effondrement_furtif_de_l_usaf_16_02_2011.html\" class=\"gen\">effrayante<\/a> de <a href=\"http:\/\/www.dedefensa.org\/article-comptabilite_du_trou_noir_06_09_2010.html\" class=\"gen\">l&rsquo;USAF<\/a>,  un participant essentiel \u00e0 toute engagement militaire contre l&rsquo;Iran,  bloqu\u00e9e entre des engagements multiples et multiformes sur plusieurs th\u00e9\u00e2tres ; un mat\u00e9riel vieillissant et de plus en plus limit\u00e9 et handicap\u00e9 par des contraintes d&#8217;emploi \u00e0 cause de vieillissement, avec une r\u00e9duction continu des effectifs ; et l&rsquo;attente d&rsquo;<strong>un seul<\/strong> programme qui doit assurer sa compl\u00e8te modernisation, et qui ne cesse de confirmer, dans son avancement au pas de l&rsquo;\u00e9crevisse, qu&rsquo;il est sur la voie d&rsquo;une catastrophe <em>in the making<\/em> (il s&rsquo;agit, qui ne l&rsquo;a devin\u00e9, du programme JSF).<\/p>\n<\/p>\n<p><p>\tOn peut raisonnablement voir, sinon confirm\u00e9es dans tous les cas notablement renforc\u00e9es, plusieurs hypoth\u00e8ses concernant la posture actuelle des USA face \u00e0 l&rsquo;Iran, du point de vue de l&rsquo;aspect militaire de la situation.<\/p>\n<\/p>\n<p><p>\t Le pouvoir civil, et encore plus les militaires, esp\u00e8rent que les mesures draconiennes (sanctions, embargo, etc.) prises contre l&rsquo;Iran feront c\u00e9der ce pays, et qu&rsquo;il ne sera assur\u00e9ment pas n\u00e9cessaire d&rsquo;aller jusqu&rsquo;\u00e0 l&rsquo;affrontement militaire. Au-del\u00e0, on peut \u00eatre moins assur\u00e9 que jamais que les USA sont pr\u00eats \u00e0 risquer effectivement un affrontement ; une th\u00e8se officielle courante \u00e0 Washington, pour la <em>narrative<\/em> (largement contest\u00e9e par des sources s\u00e9rieuses) de la crise dans le Golfe, est que les Iraniens bluffent lorsqu&rsquo;ils se disent pr\u00eats \u00e0 l&rsquo;affrontement ; la question pourrait \u00eatre renvers\u00e9e : les USA ne bluffent-ils lorsqu&rsquo;ils affichent leur r\u00e9solution de faire face \u00e0 tout incident dans le Golfe, dans toutes les conditions ?<\/p>\n<\/p>\n<p><p>\t L&rsquo;essentiel de ce qu&rsquo;il ressort de ces quelques mots h\u00e9sitants de Dempsey, qui viennent symboliquement confirmer une situation qui a commenc\u00e9 \u00e0 s&rsquo;\u00e9tablir \u00e0 partir d&rsquo;ao\u00fbt 2008 (lorsque les USA ne r\u00e9agirent absolument pas au niveau militaire face \u00e0 l&rsquo;invasion de la G\u00e9orgie par la Russie), c&rsquo;est que les USA ne sont d\u00e9sormais plus assur\u00e9s <strong>eux-m\u00eames<\/strong> de leur sup\u00e9riorit\u00e9 militaire. La question ici n&rsquo;est <strong>pas celle de la puissance<\/strong>,  la puissance militaire US existe toujours,  mais <strong>celle de la sup\u00e9riorit\u00e9<\/strong>, qui est, pour les USA, l&rsquo;indispensable dynamique derri\u00e8re tout acte militaire. Si les USA ne sont pas assur\u00e9s de leur sup\u00e9riorit\u00e9, leur puissance devient une impuissance paralysante.<\/p>\n<\/p>\n<p><p>\t C&rsquo;est cet \u00e9tat psychologique qui nous para\u00eet le plus important dans les d\u00e9clarations de Dempsey. La diff\u00e9rence est consid\u00e9rable avec 2006-2008, o\u00f9 Mullen-Gates luttaient contre un projet qu&rsquo;il jugeait fou et nullement contre une mission qu&rsquo;ils doutaient de pouvoir remplir. Aujourd&rsquo;hui, Dempsey ne se demande m\u00eame plus si une attaque ou une guerre contre l&rsquo;Iran est un projet fou, il prie simplement pour que l&rsquo;une ou l&rsquo;autre n&rsquo;ait pas lieu parce qu&rsquo;il n&rsquo;est plus s\u00fbr de rien. Ainsi prie-t-il pour que les Iraniens croient que les USA sont d&rsquo;une puissance supr\u00eamement sup\u00e9rieure \u00e0 la leur, suffisamment pour les dissuader de tout risque d&rsquo;affrontement.<\/p>\n<\/p>\n<p><p>\t Car, enfin, il faut savoir, ou bien entendu avoir \u00e0 l&rsquo;esprit, qu&rsquo;une guerre \u00e9ventuelle contre l&rsquo;Iran n&rsquo;est pas un coup gagnant final, l&rsquo;effort qui fait basculer vers une hypoth\u00e9tique victoire ; que ce n&rsquo;est qu&rsquo;un \u00e9l\u00e9ment, d&rsquo;une consid\u00e9rable lourdeur, qui va \u00eatre <strong>en plus<\/strong> dans une situation aux multiples engagements o\u00f9 les forces arm\u00e9es US sont d\u00e9j\u00e0 \u00e0 bout de souffle ; cela dans une situation strat\u00e9gique de grande tension, o\u00f9 les USA ont partout des points d&rsquo;appui strat\u00e9gique \u00e0 faire tenir comme autant de verrous de leur soi-disant h\u00e9g\u00e9monie militaire. Un conflit contre l&rsquo;Iran peut tout d\u00e9s\u00e9quilibrer, tout faire basculer, tout d&rsquo;un coup renverser l&rsquo;\u00e9difice complet. Au contraire du coup gagnant final, ce peut \u00eatre un coup de trop, un coup perdant o\u00f9 la puissance militaire US, cette fois hors de toute question de sup\u00e9riorit\u00e9, peut v\u00e9ritablement entrer dans un processus d&rsquo;effondrement. Ainsi la question est-elle moins de savoir si les USA peuvent emporter un conflit contre l&rsquo;Iran que de savoir si la structure de la puissance strat\u00e9gique US r\u00e9sisterait \u00e0 un tel choc C&rsquo;est un risque, certes, mais un risque mortel, une sorte de baiser de la mort \u00bb<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 9 janvier 2012 \u00e0 15H49<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Premi\u00e8re question : Pouvons-nous, si nous le devons, et sans utiliser nous-m\u00eames de syst\u00e8mes nucl\u00e9aires, \u00e9liminer leurs capacit\u00e9s nucl\u00e9aires (de l&rsquo;Iran) ? R\u00e9ponse du g\u00e9n\u00e9ral Dempsey, pr\u00e9sident du comit\u00e9 des chefs d&rsquo;\u00e9tat-major US : Eh bien, je veux sans le moindre doute qu&rsquo;ils croient que c&rsquo;est le cas Nouvelle question : Et alors, est-ce bien&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[8923,11165,3460,3723,7408,7098,3319,2779,5230,2671,41],"class_list":["post-74404","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-armees","tag-dempsey","tag-forces","tag-golfe","tag-incertitude","tag-mullen","tag-navy","tag-puissance","tag-superiorite","tag-us","tag-usaf"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=74404"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/74404\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=74404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=74404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=74404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}